{"id":9015,"date":"2026-03-15T00:00:00","date_gmt":"2026-03-15T04:00:00","guid":{"rendered":"https:\/\/onevoicefellowship.org\/?post_type=sermonss&#038;p=9015"},"modified":"2026-03-17T17:02:51","modified_gmt":"2026-03-17T21:02:51","slug":"where-are-you-running","status":"publish","type":"sermonss","link":"https:\/\/onevoicefellowship.org\/am\/sermons\/where-are-you-running","title":{"rendered":"Where are you running?"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"Sermon | 2 Timothy 2:22\u201326 | Where are you running? (3-15-26)\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/YUsG5GvAKWk?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>","protected":false},"featured_media":9016,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","ovf_transcripts_format":{"english":{"heading":[1],"centered":[2,3,4,24,25],"paragraph":[21,267,270,271,274,275,278,279],"bold":[203,211,222,233,244],"italic":[24,25],"hanging":[17,18,19,20,22,28,166,167,168,179,180,181,182,183,192,266,269,273,277],"section_heading":[265]}},"ovf_reading_format":null},"series":[118],"topics":[520],"books":[312,552,140],"speakers":[126],"class_list":["post-9015","sermonss","type-sermonss","status-publish","has-post-thumbnail","hentry","series-sunday-worship-service","topics-faith","books-2-timothy","books-2-timothy-2","books-new-testament","speakers-chris-sicks"],"acf":{"scripture_reference":"<a href=\"https:\/\/www.biblegateway.com\/passage\/?search=2%20Timothy%202:22%E2%80%9326%20&amp;version=ESV\" target=\"_blank\" rel=\"noopener nofollow noreferrer\">2 Timothy 2:22\u201326 <\/a>","sermon_manuscript":{"":null,"amharic_content":"\u12e8\u1275 \u1290\u12cd \u12e8\u121d\u1275\u122e\u1320\u12cd?\n2\u129b \u1322\u121e\u1274\u12ce\u1235 2\u136122-26\n\u1353\u1235\u1270\u122d \u12ad\u122a\u1235 \u1232\u12ad\u1235\n\u1218\u130b\u1262\u1275 15\u1363 2026\n\n\u1260\u1356\u122d\u1275\u120b\u1295\u12f5 \u12a6\u122a\u1308\u1295 \u1260\u1270\u12ab\u1204\u12f0\u12cd \u12e82019 \u121b\u122b\u1276\u1295 \u12cd\u12f5\u12f5\u122d \u120b\u12ed\u1363 \u12a0\u1295\u12f3\u1295\u12f5 \u121d\u122d\u1325 \u122f\u132e\u127d \u12cd\u12f5\u12f5\u1229\u1295 \u1270\u1238\u1295\u1348\u12cb\u120d\u1362\n\u1240\u122d\u134b\u134b \u1235\u1208\u1290\u1260\u1229 \u1233\u12ed\u1206\u1295 \u1260\u1270\u1233\u1233\u1270 \u1218\u1295\u1308\u12f5 \u1235\u1208\u1204\u12f1 \u1290\u12cd\u1362\n\u1260\u130d\u120d\u133d \u12eb\u120d\u1270\u1308\u1208\u1338\u1260\u1275 \u1218\u1295\u1308\u12f5 \u120b\u12ed \u1270\u122b \u1270\u1208\u12cb\u12c8\u1320\u1362\n\u1235\u1208\u12da\u1205 \u12a8\u1348\u1323\u1295 \u122f\u132e\u127d \u1218\u12ab\u12a8\u120d 20 \u12e8\u121a\u12eb\u1205\u1209\u1275 \u12a8\u12a0\u1295\u12f5 \u121b\u12ed\u120d \u1260\u120b\u12ed \u1260\u1270\u1233\u1233\u1270 \u12a0\u1245\u1323\u132b \u122e\u1320\u12cb\u120d!\n\u1235\u1205\u1270\u1271 \u1208\u12c8\u122b\u1275 \u1208\u1218\u122e\u1325 \u1232\u12d8\u130b\u1301 \u1208\u1246\u12e9\u1275 \u12cd\u12f5\u12f5\u122d \u12cd\u12f5 \u12f0\u1242\u1243\u12ce\u127d\u1295 \u1328\u121d\u122f\u120d\u1362\n\u12a5\u1290\u12da\u12eb \u12c8\u1295\u12f6\u127d\u1293 \u1234\u1276\u127d \u1320\u1295\u12ad\u1228\u12cd \u122e\u1321\u1363 \u12a5\u1293 \u1260\u134d\u1325\u1290\u1275 \u122e\u1321\u1362\n\u130d\u1295 \u1260\u1270\u1233\u1233\u1270 \u1218\u1295\u1308\u12f5 \u120b\u12ed \u1235\u1208\u1290\u1260\u1229 \u12cd\u12f5\u12f5\u1229\u1295 \u12a0\u1238\u1295\u1348\u12cb\u120d\u1362\n\u12db\u122c \u121b\u1273 \u12602\u129b \u1322\u121e\u1274\u12ce\u1235 \u1218\u133d\u1210\u134d \u12cd\u1235\u1325 \u12e8\u1235\u1265\u12a8\u1275 \u1270\u12a8\u1273\u1273\u12ed \u1275\u121d\u1205\u122d\u1276\u127d\u1295 \u12a5\u1295\u1240\u1325\u120b\u1208\u1295\u1362\n\u1210\u12cb\u122d\u12eb\u12cd \u1333\u12cd\u120e\u1235 \u1260\u12a4\u134c\u1236\u1295 \u1208\u121a\u1308\u1298\u12cd \u12e8\u12ad\u122d\u1235\u1272\u12eb\u1295 \u1264\u1270\u12ad\u122d\u1235\u1272\u12eb\u1295 \u1244\u1235 \u1208\u1206\u1290\u12cd \u1208\u1322\u121e\u1274\u12ce\u1235 \u12f0\u1265\u12f3\u1264 \u12ed\u133d\u134b\u120d \u1361\u1361\n\u1333\u12cd\u120e\u1235 \u1208\u1322\u121e\u1274\u12ce\u1235\u121d \u1206\u1290 \u12db\u122c \u1260\u1275\u12ad\u12ad\u1208\u129b\u12cd \u1218\u1295\u1308\u12f5 \u120b\u12ed \u12a5\u1295\u12f4\u1275 \u1218\u1246\u12e8\u1275 \u12a5\u1295\u12f0\u121d\u1295\u127d\u120d \u121d\u12ad\u122d \u12a5\u12e8\u1230\u1320\u1295 \u1290\u12cd\u1362\n2\u129b \u1322\u121e\u1274\u12ce\u1235 2\u136122\u201326\n22 \u201c\u1235\u1208\u12da\u1205 \u12e8\u12c8\u1323\u1276\u127d \u121d\u129e\u1275 \u123d\u123d\u1364 \u1260\u1295\u1339\u1215 \u120d\u1265 \u130c\u1273\u1295 \u12a8\u121a\u1320\u1229\u1275 \u130b\u122d \u133d\u12f5\u1245\u1295\u1363 \u12a5\u121d\u1290\u1275\u1295\u1363 \u134d\u1245\u122d\u1295\u1293 \u1230\u120b\u121d\u1295 \u1270\u12a8\u1270\u120d\u1362\n23 \u1290\u1308\u122d \u130d\u1295 \u1320\u1265\u1295 \u12a5\u1295\u12f2\u12eb\u1218\u1323 \u12a0\u12cd\u1240\u1205 \u12a8\u1230\u1290\u134e\u127d\u1293 \u12ab\u120d\u1270\u121b\u1229 \u121d\u122d\u1218\u122b \u122b\u1245\u1364\n24 \u12e8\u130c\u1273\u121d \u1263\u122a\u12eb \u120a\u1323\u120b \u12a5\u1295\u1302 \u1208\u1230\u12cd \u1201\u1209 \u1278\u122d\u1363 \u1208\u121b\u1235\u1270\u121b\u122d\u121d \u12e8\u121a\u1260\u1243\u1363 \u12ad\u1349\u12cd\u1295\u121d \u1260\u1275\u12d5\u130d\u1225\u1275 \u12e8\u121a\u1273\u1308\u1225 \u120a\u1206\u1295 \u12a0\u12ed\u1308\u1263\u12cd\u121d\u1362\n25 \u1270\u1243\u12cb\u121a\u12ce\u1279\u1295 \u1260\u1308\u122d\u1290\u1275 \u121b\u1228\u121d\u1362\n\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12a5\u12cd\u1290\u1275\u1295 \u12a5\u1295\u12f2\u12eb\u12cd\u1241 \u12e8\u121a\u12eb\u12f0\u122d\u130b\u1278\u12cd\u1295 \u1295\u1235\u1210 \u120a\u1230\u1323\u1278\u12cd \u12ed\u127d\u120b\u120d\u1364\n26 \u1348\u1243\u12f1\u1295 \u1208\u121b\u12f5\u1228\u130d \u1260\u12f2\u12eb\u1265\u120e\u1235 \u12a8\u1270\u12eb\u12d9 \u1260\u128b\u120b \u12c8\u12f0 \u12a0\u12a5\u121d\u122e\u12a0\u1278\u12cd \u12a5\u1295\u12f2\u1218\u1208\u1231\u1365 \u1348\u1243\u12f1\u1295\u121d \u12a5\u1295\u12f2\u12eb\u12f0\u122d\u1309 \u1260\u12a5\u122d\u1231 \u1270\u12ed\u12d8\u12cd \u12a8\u12f2\u12eb\u1265\u120e\u1235 \u12c8\u1325\u1218\u12f5\u121d \u12a5\u1295\u12f2\u12eb\u1218\u120d\u1321\u1362\n\n\u12a2\u1233\u12eb\u1235 40:8\u1295 \u12a0\u1265\u1228\u1295 \u12a5\u1293\u1290\u1263\u1208\u1295\n\u201d\u1223\u1229 \u12ed\u1320\u12c8\u120d\u130b\u120d\u1364 \u12a0\u1260\u1263\u12cd\u121d \u12ed\u1228\u130d\u134b\u120d\u1364 \u12e8\u12a0\u121d\u120b\u12ab\u127d\u1295 \u1243\u120d \u130d\u1295 \u1208\u12d8\u120b\u1208\u121d \u1338\u1295\u1276 \u12ed\u1296\u122b\u120d\u1362\u201d\n\n\u1241\u1325\u122d 22 \u12a5\u1295\u12f2\u1205 \u12ed\u120b\u120d\u1361-\n22 \u201d\u1235\u1208\u12da\u1205 \u12e8\u12c8\u1323\u1276\u127d \u121d\u129e\u1275 \u123d\u123d\u1364 \u1260\u1295\u1339\u1215 \u120d\u1265 \u130c\u1273\u1295 \u12a8\u121a\u1320\u1229\u1275 \u130b\u122d \u133d\u12f5\u1245\u1295\u1363 \u12a5\u121d\u1290\u1275\u1295\u1363 \u134d\u1245\u122d\u1295\u1293 \u1230\u120b\u121d\u1295 \u1270\u12a8\u1270\u120d\u1362\u201d\n\n\u12ed\u1205 \u1325\u1245\u1235 \u12e8\u12db\u122c\u12cd\u1295 \u1235\u1265\u12a8\u1275 \u121b\u1320\u1243\u1208\u12eb \u1290\u12cd\u1362\n\u12ed\u1205\u1295\u1295 \u1260\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u1243\u120d \u12cd\u1235\u1325 \u1265\u12d9 \u130a\u12dc \u12a5\u1293\u12e8\u12cb\u1208\u1295\u1362\n\u12a0\u1295\u12f3\u1295\u12f5 \u130a\u12dc \u1260\u1218\u12dd\u1219\u122d \u12c8\u12ed\u121d \u1260\u12a0\u1295\u1240\u1345 \u12cd\u1235\u1325 \u12e8\u1218\u1300\u1218\u122a\u12eb\u12cd \u12d3\u1228\u134d\u1270 \u1290\u1308\u122d \u121b\u1320\u1243\u1208\u12eb \u12ed\u1206\u1293\u120d\u1362\n\u12a8\u12da\u12eb\u121d \u12e8\u121a\u12a8\u1270\u1209\u1275 \u1243\u120b\u1275 \u12e8\u1320\u1245\u120b\u120b\u12cd \u1218\u12dd\u1219\u122d \u12c8\u12ed\u121d \u12a0\u1295\u1240\u133d \u12c8\u12ed\u121d \u121d\u12d5\u122b\u134d \u121b\u1265\u122b\u122a\u12eb \u1293\u1278\u12cd\u1362\n\u12e8\u130e\u1208\u1218\u1230 \u12ad\u122d\u1235\u1272\u12eb\u1295 \u12c8\u1295\u12f5 \u12c8\u12ed\u121d \u1234\u1275 \u121b\u1208\u1275 \u12c8\u1323\u1275 \u12a5\u12eb\u1208\u1295 \u1348\u1270\u1293 \u12ab\u12f0\u1228\u1231\u1265\u1295 \u1290\u1308\u122e\u127d \u12e8\u121a\u122d\u1245 \u1230\u12cd \u1290\u12cd\u1362\n\u12e8\u130e\u1208\u1218\u1230 \u1230\u12cd \u201c\u12e8\u12c8\u1323\u1275\u1290\u1275 \u1235\u121c\u1275\u201d \u12a8\u1218\u1206\u1295 \u12ed\u120d\u1245 \u12e8\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d\u1295 \u12a5\u1234\u1276\u127d \u121b\u1208\u1275\u121d \u133d\u12f5\u1245\u1295\u1363 \u12a5\u121d\u1290\u1275\u1295\u1363 \u134d\u1245\u122d\u1295\u1363 \u1230\u120b\u121d\u1295 \u1218\u12a8\u1270\u120d\u1295 \u12ed\u121b\u122b\u120d\u1362\n\u1333\u12cd\u120e\u1235 \u12c8\u1323\u1275 \u1260\u1290\u1260\u1228\u1260\u1275 \u130a\u12dc \u1233\u12cd\u120d \u12ed\u1263\u120d \u1290\u1260\u122d\u1362\n\u1233\u12a6\u120d \u1260\u12a9\u122b\u1275\u1293 \u1260\u122b\u1235 \u1218\u1270\u121b\u1218\u1295 \u12e8\u1270\u121e\u120b \u1290\u1260\u122d\u1363 \u12ad\u122d\u1235\u1272\u12eb\u1296\u127d\u1295 \u1208\u121b\u1233\u12f0\u12f5\u1293 \u12c8\u12f0 \u12a5\u1235\u122d \u1264\u1275 \u1208\u121b\u130b\u12dd \u1283\u12ed\u120d\u1295 \u1270\u1320\u1245\u121f\u120d\u1362\n\u1233\u12a6\u120d \u1270\u12c8\u12f3\u1305\u1293 \u1235\u12ac\u1273\u121b \u1218\u1206\u1295 \u12ed\u1348\u120d\u130d \u1290\u1260\u122d\u1364 \u1260\u122b\u1231 \u12a9\u122b\u1275 \u121d\u12ad\u1295\u12eb\u1275 \u120c\u120e\u127d\u1295 \u1208\u1218\u1309\u12f3\u1275 \u1348\u1243\u12f0\u129b \u1290\u1260\u122d\u1362\n\u1290\u1308\u122d \u130d\u1295 \u12e82\u129b \u1322\u121e\u1274\u12ce\u1235 \u1218\u120d\u12a5\u12ad\u1275 \u12e8\u1270\u133b\u1348\u12cd \u1260\u1333\u12cd\u120e\u1235 \u130e\u1260\u12dd \u12a0\u121b\u129d \u1290\u12cd\u1362\n\u12e8\u12c8\u1323\u1275\u1290\u1275 \u134d\u120b\u130e\u1276\u1279 \u121d\u1295 \u12eb\u1205\u120d \u1309\u12f3\u1275 \u12a5\u1295\u12f3\u1235\u12a8\u1270\u1209\u1260\u1275 \u1270\u1228\u12f5\u1276 \u1322\u121e\u1274\u12ce\u1235\u1295 \u1235\u1208\u12a5\u1290\u1231 \u12a5\u12eb\u1235\u1320\u1290\u1240\u1240\u12cd \u1290\u12cd\u1362\n\u1333\u12cd\u120e\u1235 \u12ed\u1205\u1295\u1295 \u1218\u120d\u12a5\u12ad\u1275 \u1260\u133b\u1348\u1260\u1275 \u12c8\u1245\u1275\u1363 \u1322\u121e\u1274\u12ce\u1235 \u121d\u1293\u120d\u1263\u1275 40 \u12d3\u1218\u1275 \u1308\u12f0\u121b \u120a\u1206\u1295 \u12ed\u127d\u120b\u120d\u1362\n\u1290\u1308\u122d \u130d\u1295 \u12c8\u12f0 \u201d\u12c8\u1323\u1275\u1290\u1275 \u1235\u121c\u1276\u127d\u201d \u1208\u1218\u122e\u1325 \u12c8\u1323\u1275 \u1218\u1206\u1295 \u12a0\u12eb\u1235\u1348\u120d\u130d\u121d\u1362\n\u12e857 \u12d3\u1218\u1274 \u1290\u12cd\u1363 \u130d\u1295 \u12a0\u1201\u1295\u121d \u12a8\u12c8\u1323\u1275\u1290\u1275 \u1235\u121c\u1276\u127d \u1218\u122b\u1245\u1295 \u12a5\u12e8\u1270\u121b\u122d\u12a9 \u1290\u12cd\u1362\n\u12a8\u12ae\u120c\u1305 \u12e8\u1218\u1323 \u12a8\u12a5\u1294 \u130b\u122d \u1270\u1218\u1233\u1233\u12ed \u12d5\u12f5\u121c \u12eb\u1208\u12cd \u1313\u12f0\u129b \u12a0\u1208\u129d\u1362\n\u130d\u1295 \u12a0\u1201\u1295\u121d \u12a835 \u12d3\u1218\u1273\u1275 \u1260\u134a\u1275 \u12a5\u1295\u12f0\u1290\u1260\u1228\u12cd \u12ed\u1296\u122b\u120d\u1362\n\u1205\u12ed\u12c8\u1271 \u1260\u12ae\u120c\u1305 \u12d8\u1218\u1293\u127d\u1295 \u1260\u12c8\u1323\u1275\u1290\u1275 \u1235\u121c\u1275 \u12e8\u1270\u121e\u120b \u1290\u12cd\u1362\n\u1265\u12d9\u12ce\u127b\u127d\u1295 \u12e8\u121a\u12eb\u130b\u1325\u1219\u1295 \u12e8\u12c8\u1323\u1275\u1290\u1275 \u1235\u121c\u1276\u127d \u12a5\u1290\u1206\u1361-\n\n*   \u12f0\u1235\u1273\u1361- \u12e8\u12c8\u1232\u1265 \u1283\u1322\u12a0\u1275 \u12e8\u12f0\u1235\u1273 \u1283\u1322\u12a0\u1275 \u12e8\u1270\u1208\u1218\u12f0 \u121d\u1233\u120c \u1290\u12cd\u1363 \u1290\u1308\u122d \u130d\u1295 \u12ed\u1205 \u1265\u127b \u12a0\u12ed\u12f0\u1208\u121d\u1362\n\u120c\u120e\u127d \u12e8\u1283\u1322\u12a0\u1275 \u12f0\u1235\u1273\u12ce\u127d \u12a0\u120d\u12ae\u120d\u1363 \u121d\u130d\u1265 \u12a5\u1293 \u1265\u12d9 \u12a0\u12ed\u1290\u1275 \u1218\u12dd\u1293\u129b\u12ce\u127d\u1295 \u120a\u12eb\u12ab\u1275\u1271 \u12ed\u127d\u120b\u1209\u1362\n\u12a5\u1290\u12da\u1205 \u1290\u1308\u122e\u127d \u1260\u1275\u12ad\u12ad\u120d \u12a8\u1270\u1270\u1308\u1260\u1229 \u1218\u1325\u134e \u12a0\u12ed\u12f0\u1209\u121d\u1362\n\u1208\u121d\u1233\u120c\u1363 \u12c8\u1232\u1265 \u1260\u12ad\u122d\u1235\u1272\u12eb\u1295 \u130b\u1265\u127b \u12a0\u12cd\u12f5 \u12cd\u1235\u1325 \u12cd\u1265 \u1235\u1326\u1273 \u1290\u12cd\u1362\n\u1290\u1308\u122d \u130d\u1295 \u121b\u1295\u129b\u12cd\u1295\u121d \u1290\u1308\u122d \u1260\u1270\u1233\u1233\u1270 \u1218\u1295\u1308\u12f5 \u1235\u1295\u1320\u1240\u121d\u1260\u1275\u1363 \u1260\u1215\u12ed\u12c8\u1273\u127d\u1295 \u120b\u12ed \u1283\u12ed\u120d \u12a5\u1295\u1230\u1320\u12cb\u1208\u1295\u1362\n\u1260\u120d\u1263\u127d\u1295 \u12cd\u1235\u1325 \u12eb\u1208\u12cd\u1295 \u1263\u12f6\u1290\u1275 \u1208\u1218\u1219\u120b\u1275 \u12e8\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d\u1295 \u1235\u1326\u1273\u12ce\u127d \u1235\u1295\u1320\u1240\u121d\u1363 \u12eb \u1290\u1308\u122d \u12e8\u1210\u1230\u1275 \u12a0\u121d\u120b\u12ad \u12ed\u1206\u1293\u120d- \u1323\u12d6\u1275\u1362\n\n*   \u1283\u12ed\u120d\u1361- \u12c8\u1323\u1275 \u1235\u1295\u1206\u1295 \u12a0\u1295\u12f3\u1295\u12f5 \u130a\u12dc \u12a0\u1245\u121d \u121b\u1323\u1275\u1363 \u12f5\u12ab\u121d \u12c8\u12ed\u121d \u1265\u1243\u1275 \u121b\u1323\u1275 \u12ed\u1230\u121b\u1293\u120d\u1362\n\u1260\u12a0\u1225\u122b\u12ce\u1279 \u12d5\u12f5\u121c \u12cd\u1235\u1325 \u12a5\u12eb\u1208\u1201 \u12a8\u12a5\u1290\u12da\u1205 \u1235\u121c\u1276\u127d \u130b\u122d \u12a5\u1273\u1308\u120d \u1290\u1260\u122d\u1362\n\u12a0\u1295\u12f3\u1295\u12f5 \u1230\u12ce\u127d \u12e8\u12f5\u12ad\u1218\u1275 \u1235\u121c\u1273\u1278\u12cd\u1295 \u1208\u1218\u1238\u1348\u1295 \u1235\u120d\u1323\u1295\u1295 \u12ed\u12a8\u1270\u120b\u1209\u1362\n\u1320\u1295\u12ab\u122b \u1218\u1206\u1295 \u12f0\u1205\u1295\u1290\u1275 \u12a5\u1295\u12f2\u1230\u121b\u1278\u12cd \u12a5\u1295\u12f0\u121a\u1228\u12f3\u1278\u12cd \u12eb\u1235\u1263\u1209\u1362\n\u1309\u120d\u1260\u1270\u129b \u12a5\u1231 \u12a5\u1295\u12f0\u121a\u1218\u1235\u1208\u12cd \u12a8\u1263\u12f5 \u12a5\u1295\u12f3\u120d\u1206\u1290 \u1273\u12cd\u1243\u1208\u1205?\n\u1309\u120d\u1260\u1270\u129b \u121b\u1208\u1275 \u1265\u12d9\u12cd\u1295 \u130a\u12dc \u1260\u1215\u12ed\u12c8\u1271 \u12cd\u1235\u1325 \u1235\u120b\u1208\u12cd \u1290\u1308\u122d \u12a0\u1245\u121d \u12a5\u1295\u12f0\u120c\u1208\u12cd \u12e8\u121a\u1230\u121b\u12cd \u1230\u12cd \u1290\u12cd\u1363 \u1235\u1208\u12da\u1205 \u122b\u1231\u1295 \u1283\u12ed\u1208\u129b \u12a5\u1295\u12f2\u1230\u121b\u12cd \u120c\u120e\u127d \u1230\u12ce\u127d\u1295 \u12ed\u130e\u12f3\u120d\u1362\n\n*   \u1270\u12c8\u12f3\u1305\u1290\u1275\u1361 \u12ed\u1205 \u1260\u1215\u12ed\u12c8\u1274 \u12cd\u1235\u1325 \u120c\u120b \u1320\u1295\u12ab\u122b \u1348\u1270\u1293 \u1206\u1296\u1265\u129b\u120d\u1362\n\u1230\u12ce\u127d \u12a5\u1294\u1295 \u1262\u12c8\u12f1\u129d \u1265\u12ec \u12d9 \u130a\u12dc \u12a5\u1328\u1290\u1243\u1208\u1201\u1362\n\u12e8\u120c\u120e\u127d \u1230\u12ce\u127d \u12a0\u1235\u1270\u12eb\u12e8\u1275 \u1260\u1323\u121d \u12eb\u1233\u1235\u1260\u129b\u120d\u1362\n\u12a5\u1293\u1295\u1270\u1235?\n\u1230\u12ce\u127d \u12a5\u1295\u12f2\u12c8\u12f7\u1279 \u1263\u1205\u122a\u1205\u12eb\u1279\u1295 \u12c8\u12ed\u121d \u1218\u120d\u12ab\u1279\u1295 \u1275\u1208\u12cd\u1323\u120b\u127d\u1201?\n\u1260\u1230\u12ce\u127d \u120b\u1208\u1218\u1308\u134b\u1275 \u1265\u120b\u1279 \u120a\u1296\u1228\u129d \u12ed\u1308\u1263\u120d \u1265\u120b\u1279 \u121d\u1273\u1235\u1261\u1275 \u1263\u1205\u122a \u12c8\u12ed\u1295\u121d \u1218\u120d\u12ad \u12a0\u120b\u127d\u1201?\n\n*   \u1200\u1265\u1275\u1361- \u12e8\u1308\u1295\u12d8\u1265\u1293 \u12e8\u1241\u1233\u12ca \u1200\u1265\u1275 \u134d\u1245\u122d \u1208\u12a0\u1265\u12db\u129e\u127b\u127d\u1295 \u127d\u130d\u122d \u1290\u12cd\u1362\n\u1270\u1328\u121b\u122a \u1290\u1308\u122e\u127d\u1295 \u12e8\u121b\u130d\u1298\u1275 \u12f0\u1205\u1295\u1290\u1275 \u12a5\u1293 \u121d\u127e\u1275 \u12a5\u1295\u1348\u120d\u130b\u1208\u1295\u1362\n\u12ed\u1205 \u12e8\u12a5\u121d\u1290\u1275 \u12a5\u1326\u1275\u1295 \u12eb\u1233\u12eb\u120d\u1362\n\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12a5\u122d\u1231 \u1218\u1320\u130a\u12eb\u127d\u1295\u1293 \u121d\u123d\u130b\u127d\u1295\u1363 \u12a0\u1245\u122b\u1262\u12eb\u127d\u1295\u121d \u12a5\u122d\u1231 \u1218\u1206\u1291\u1295 \u12a5\u1295\u12f5\u1295\u1228\u12f3 \u12ed\u1348\u120d\u130b\u120d\u1362\n\u1241\u1233\u12ca \u1290\u1308\u122e\u127d \u12f0\u1235\u1273\u1295 \u12a5\u1295\u12f0\u121a\u1230\u1321 \u1243\u120d \u1262\u1308\u1261\u121d\u1363 \u1243\u120b\u1278\u12cd\u1295 \u1218\u1348\u1338\u121d \u130d\u1295 \u12a0\u12ed\u127d\u1209\u121d\u1362\n\u121d\u12ad\u1295\u12eb\u1271\u121d \u120d\u1263\u127d\u1295 \u1201\u120d\u130a\u12dc \u12e8\u1260\u1208\u1320 \u12ed\u1293\u134d\u1243\u120d\u1362\n\n*   \u12a9\u122b\u1275\u1361\u1361 \u12ed\u1205 \u1260\u12a5\u122d\u130d\u1325 \u12a8\u12e8\u12a0\u1295\u12f5\u12a0\u1295\u12f1 \u1283\u1322\u12a0\u1275 \u1201\u1209 \u1300\u122d\u1263 \u12eb\u1208\u12cd \u1283\u1322\u12a0\u1275 \u1290\u12cd\u1362\n\u12a9\u122b\u1275 \u121b\u1208\u1275 \u12a5\u1294 \u1260\u12a5\u122d\u130d\u1325 \u1295\u1265\u1228\u1275\u1363 \u1283\u12ed\u120d\u1363 \u12f0\u1235\u1273 \u12a5\u1293 \u1270\u12c8\u12f3\u1305\u1290\u1275 \u12ed\u1308\u1263\u129b\u120d \u12e8\u121a\u120d \u12a5\u121d\u1290\u1275 \u1290\u12cd\u1362\n\u1208\u121d\u1295? \u121d\u12ad\u1295\u12eb\u1271\u121d \u12a5\u1294 \u120d\u12e9 \u1235\u1208\u1206\u1295\u12a9\u1362\n\u12e8\u12a9\u122b\u1275 \u1239\u12ad\u1239\u12ad\u1273 \u12a5\u1295\u12f2\u1205 \u1232\u120d \u12ed\u12cb\u1238\u1293\u120d\u1366\n\u201d\u127d\u130d\u122d \u12e8\u1208\u12cd\u121d\u1363 \u12eb\u1295\u1295 \u121b\u12f5\u1228\u130d \u1275\u127d\u120b\u1208\u1205-- \u12ed\u1308\u1263\u1203\u120d\u1362\u201d\n\u12a0\u1235\u1270\u12cb\u12cb\u1242\u12ce\u127d \u1208\u12a5\u129b\u121d \u1270\u1218\u1233\u1233\u12ed \u1290\u1308\u122d \u12ed\u1293\u1308\u122b\u1209\u1362\n\u201d\u12ed\u1308\u1263\u1203\u120d\u2026 \u1202\u12f5\u1293 \u130d\u12db\u12cd\u1362\u201d\n\u121d\u1293\u120d\u1263\u1275 \u1270\u1328\u121b\u122a \u130d\u12db\u1364 \u127d\u130d\u122d \u12e8\u1208\u12cd\u121d\u1362\n\u1208\u12da\u1205\u121d \u1290\u12cd \u12a5\u1295\u12f0\u12da\u1205 \u12a0\u12ed\u1290\u1275 \u1265\u12d9 \u121b\u1235\u1273\u12c8\u1242\u12eb\u12ce\u127d\u1295 \u12e8\u121d\u1293\u12e8\u12cd\u1363 \u121d\u12ad\u1295\u12eb\u1271\u121d \u12a9\u122b\u1273\u127d\u1295 \u12a5\u1290\u12da\u1205\u1295 \u1290\u1308\u122e\u127d \u121b\u1218\u1295 \u1235\u1208\u121a\u1348\u120d\u130d\u1362\n\n\u1313\u12f0\u129e\u127c \u12a0\u1295\u12f5 \u1325\u12eb\u1244 \u120d\u1320\u12ed\u1243\u127d\u1201 \u12a5\u127d\u120b\u1208\u1201?\n\u12a8\u12a5\u1290\u12da\u1205 \u12a0\u121d\u1235\u1275 \u1290\u1308\u122e\u127d \u12cd\u1235\u1325 \u12e8\u1275\u129b\u12cd\u1295 \u1273\u12cd\u1243\u120b\u127d\u1201?\n\u12a9\u122b\u1275\u1295\u1363 \u1295\u1265\u1228\u1275\u1295\u1363 \u1225\u120d\u1323\u1295\u1295\u1363 \u12f0\u1235\u1273\u1295 \u12c8\u12ed\u1235 \u1270\u12c8\u12f3\u1305\u1290\u1275\u1295 \u12a5\u12eb\u1233\u12f0\u12f5\u12ad \u1290\u12cd?\n\u12c8\u12ed\u1235 \u121d\u1293\u120d\u1263\u1275 \u12a8\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12e8\u121a\u12eb\u122d\u1245\u1205 \u120c\u120b \u1290\u1308\u122d \u120a\u1206\u1295 \u12ed\u127d\u120b\u120d?\n\u12db\u122c \u120d\u1265\u1205 \u12e8\u1275 \u1290\u12cd\u1363 \u12a5\u1293 \u12c8\u12f4\u1275 \u12a5\u12e8\u1204\u12f5\u12ad \u1290\u12cd?\n\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12a0\u12f3\u121d\u1295 \u200b\u200b\u1260\u12a0\u1275\u12ad\u120d\u1271 \u1235\u134d\u122b \u134d\u122c\u12cd\u1295 \u12a8\u1260\u120b \u1260\u128b\u120b \u12e8\u1320\u12e8\u1240\u12cd\u1295 \u1273\u1235\u1273\u12cd\u1233\u1208\u1205?\n\u12a0\u12f3\u121d\u1293 \u1214\u12cb\u1295 \u1270\u12f0\u1265\u1240\u12cd \u1290\u1260\u122d\u1364 \u12a5\u130d\u12da\u12a0\u1265\u1214\u122d\u121d \u201d\u12a0\u12f3\u121d \u1206\u12ed \u12e8\u1275 \u1290\u1205?\u201d \u12a0\u1208\u12cd\u1362\n\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12db\u122c \u1260\u121d\u12f5\u122d \u120b\u12ed \u120b\u1208 \u1208\u121b\u1295\u129b\u12cd\u121d \u1230\u12cd \u1270\u1218\u1233\u1233\u12ed \u1290\u1308\u122d \u12a5\u12e8\u1320\u12e8\u1240 \u1290\u12cd\u1362\n\u12e8\u1275 \u1293\u127d\u1201?\n\u1260\u12a0\u12ab\u120d \u12e8\u1275 \u12a5\u1295\u12f3\u120b\u1279 \u12a0\u12ed\u1320\u12ed\u1245\u121d\u1362\n\u00ab\u120d\u1263\u1279 \u12e8\u1275 \u1290\u12cd\u1367\u00bb \u1265\u120e \u12ed\u1320\u12ed\u1243\u120d\u1362\n\u121d\u12ad\u1295\u12eb\u1271\u121d \u120d\u1263\u127d\u1295 \u1260\u1323\u121d \u12c8\u12f0\u121d\u1295\u12c8\u12f0\u12cd \u1290\u1308\u122d \u12e8\u121a\u12c8\u1235\u12f0\u1295 \u12ae\u121d\u1353\u1235 \u1235\u1208\u1206\u1290 \u1290\u12cd\u1362\n\u1283\u1322\u12a0\u1275 \u1270\u1295\u12ae\u1208\u129b \u1235\u1208\u1206\u1290 \u12a5\u1295\u1320\u134b\u1208\u1295\u1364 \u12a5\u1295\u12b3\u1295 \u12a0\u1293\u12cd\u1240\u12cd\u121d\u1362\n\u1260\u12cd\u1235\u1323\u127d\u1295 \u121d\u1295 \u12a5\u12e8\u1270\u12a8\u1293\u12c8\u1290 \u12a5\u1295\u12f3\u1208 \u1208\u121b\u12e8\u1275 \u12e8\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12a5\u122d\u12f3\u1273 \u12eb\u1235\u1348\u120d\u1308\u1293\u120d\u1362\n\u1218\u12dd\u1219\u122d 139:23-24\u1295 \u12a5\u1295\u12f0 \u1338\u120e\u1275 \u12a0\u1265\u1228\u1295 \u12a5\u1293\u1295\u1265\u1265\u1361-\n\u1201\u1209\u121d\u1366 23 \u201c\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u1206\u12ed\u1363 \u1348\u120d\u1308\u129d\u1364 \u120d\u1264\u1295\u121d \u12a5\u12c8\u1245!\n\u121e\u12ad\u1228\u129d \u12a5\u1293 \u1200\u1233\u1264\u1295 \u12a5\u12c8\u1245!\n24\u1364 \u1260\u12cd\u1235\u1324\u121d \u12e8\u121a\u12eb\u1235\u1328\u1295\u1245 \u1218\u1295\u1308\u12f5 \u1262\u1296\u122d \u1270\u1218\u120d\u12a8\u1275\u1364\n\u1260\u12d8\u120b\u1208\u121d\u121d \u1218\u1295\u1308\u12f5 \u121d\u122b\u129d!\n\n\u12eb\u1208 \u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12a5\u122d\u12f3\u1273\u1363 \u201c\u1260\u12d8\u120b\u1208\u121d \u1218\u1295\u1308\u12f5\u201d \u12a0\u1295\u1204\u12f5\u121d\u1362\n\u12a8\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u120d\u1265 \u12e8\u121a\u12eb\u122d\u1241\u1295\u1295 \u1290\u1308\u122e\u127d \u12a5\u12e8\u1270\u12a8\u1270\u120d\u1295 \u1260\u1270\u1233\u1233\u1270 \u12a0\u1245\u1323\u132b \u12a5\u1295\u122e\u1323\u1208\u1295\u1362\n\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u130d\u1295 \u1260\u1323\u121d \u1278\u122d \u1235\u1208\u1206\u1290 \u1235\u1295\u1295\u12a8\u122b\u1270\u1275\u1293 \u1235\u1295\u1320\u134b \u1265\u127b \u12a0\u12eb\u12ed\u121d\u1362\n\u1260\u121d\u1275\u12a9\u1363 \u12e8\u1320\u134b\u12cd\u1295 \u1260\u130d \u12ed\u1348\u120d\u130b\u120d\u1362\n\u12c8\u12f0 \u12a5\u129b \u1218\u1325\u1276 \u12e8\u121b\u121d\u1208\u132b\u1293 \u12e8\u121b\u12f3\u1295 \u1218\u1295\u1308\u12f5 \u12eb\u1240\u122d\u1263\u120d\u1362\n2\u129b \u1322\u121e\u1274\u12ce\u1235 2:25\u1208-26\u1295 \u12a5\u1295\u12f0\u1308\u1293 \u1270\u1218\u120d\u12a8\u1271\u1361\n25\u1208 \u201c\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12a5\u12cd\u1290\u1275\u1295 \u12a5\u1295\u12f2\u12eb\u12cd\u1241 \u1295\u1235\u1210\u1295 \u120a\u1230\u1323\u1278\u12cd \u12ed\u127d\u120b\u120d\u1364\n26 \u1348\u1243\u12f1\u1295 \u1208\u121b\u12f5\u1228\u130d \u1260\u12f2\u12eb\u1265\u120e\u1235 \u12a8\u1270\u12eb\u12d9 \u1260\u128b\u120b \u12c8\u12f0 \u12a0\u12a5\u121d\u122e\u12a0\u1278\u12cd \u12a5\u1295\u12f2\u1218\u1208\u1231\u1365 \u1348\u1243\u12f1\u1295\u121d \u12a5\u1295\u12f2\u12eb\u12f0\u122d\u1309 \u1260\u12a5\u122d\u1231 \u1270\u12ed\u12d8\u12cd \u12a8\u12f2\u12eb\u1265\u120e\u1235 \u12c8\u1325\u1218\u12f5\u121d \u12a5\u1295\u12f2\u12eb\u1218\u120d\u1321\u1362\n\n\u1260\u1283\u1322\u12a0\u1275\u1293 \u1260\u12f2\u12eb\u1265\u120e\u1235 \u12a5\u12e8\u1270\u1320\u1218\u12f5\u12ad \u1219\u1209 \u1260\u1219\u1209 \u1290\u1343 \u1218\u12cd\u1323\u1275 \u12a5\u1295\u12f0\u121a\u127b\u120d \u1273\u12cd\u1243\u1208\u1205?\n\u1283\u1322\u12a0\u1275 \u12a5\u1295\u12f0 \u1290\u1343\u1290\u1275 \u12ed\u1230\u121b\u12cb\u120d\u1363 \u130d\u1295 \u1270\u1243\u122b\u1292\u12cd \u1290\u12cd\u1362\n\u12c8\u1325\u1218\u12f5 \u12a5\u1295\u12f0\u12da\u1205 \u12ed\u1218\u1235\u120b\u120d\u1362\n\u12a0\u1295\u12f5 \u12a5\u1295\u1235\u1233 \u1260\u1290\u1343\u1290\u1275 \u1218\u1295\u1308\u12f5 \u120b\u12ed \u12a5\u12e8\u122e\u1320 \u12a5\u12eb\u1208 \u1260\u12f5\u1295\u1308\u1275 \u12a0\u12f0\u130b \u120b\u12ed \u12e8\u12c8\u12f0\u1240\u1260\u1275\u1295 \u12e8\u121a\u12ed\u12dd \u12c8\u1325\u1218\u12f5 \u1290\u12cd\u1362\n\u1230\u12ed\u1323\u1295 \u1260\u121b\u122b\u1276\u1295 \u1229\u132b \u120b\u12ed \u12a5\u1295\u12f0 \u121d\u120d\u12ad\u1276\u127d \u12cd\u1238\u1275\u1295 \u12eb\u1235\u1240\u121d\u1323\u120d\u1363 \u12a5\u129b\u1295 \u1208\u121b\u1273\u1208\u120d\u1293 \u1208\u121b\u1325\u1218\u12f5\u1362\n\u1230\u12ed\u1323\u1295 \u12f0\u1235\u1273\u1295\u1363 \u1235\u120d\u1323\u1295\u1295\u1363 \u1270\u12c8\u12f3\u1305\u1290\u1275\u1295\u1363 \u1200\u1265\u1275\u1295\u1293 \u12a9\u122b\u1275\u1295 \u12a5\u12e8\u1270\u12a8\u1270\u120d\u1295 \u12a5\u1295\u12f5\u1295\u122e\u1325 \u12ed\u1348\u120d\u130b\u120d\u1362\n\u12a5\u1290\u12da\u1205 \u1323\u12d6\u1273\u1275 \u1290\u1343\u1290\u1275\u1295 \u12ed\u1230\u1321\u1293\u120d\u1363 \u12a5\u1293\u121d \u1290\u1343\u1290\u1275 \u1260\u1323\u121d \u12e8\u121d\u1295\u1348\u120d\u1308\u12cd \u1290\u1308\u122d \u1290\u12cd\u1362\n\u1260\u121a\u12eb\u1233\u12dd\u1295 \u1201\u1294\u1273\u1363 \u12a5\u1295\u12f0\u12da\u1205 \u12a0\u12ed\u1290\u1275 \u1290\u1308\u122e\u127d \u12a5\u122d\u12ab\u1273\u1363 \u12f0\u1205\u1295\u1290\u1275 \u12a5\u1293 \u12f0\u1235\u1270\u129b \u12a5\u1295\u12f5\u1295\u1206\u1295 \u120a\u1228\u12f1\u1295 \u12a5\u1295\u12f0\u121a\u127d\u1209 \u12a5\u1293\u121d\u1293\u1208\u1295\u1362\n\u1290\u1308\u122d \u130d\u1295 \u12a5\u1290\u12da\u1205 \u1323\u12d6\u1273\u1275 \u12a8\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d\u1293 \u12a8\u12a5\u12cd\u1290\u1270\u129b\u12cd \u12e8\u1215\u12ed\u12c8\u1275 \u130e\u12f3\u1293 \u12e8\u121a\u1320\u1265\u1241\u1295 \u12c8\u1325\u1218\u12f6\u127d \u1293\u1278\u12cd\u1362\n\u1230\u12ed\u1323\u1295 \u12e8\u1215\u12ed\u12c8\u1275\u1295 \u1218\u1295\u1308\u12f5 \u12a8\u12a5\u129b \u120a\u12f0\u1265\u1245 \u12ed\u1348\u120d\u130b\u120d\u1364 \u12a5\u1295\u12f2\u1205\u121d \u12ed\u120b\u120d\u1361-\n\u201d\u12c8\u12f0 \u12f5\u120d\u1293 \u12f0\u1235\u1273 \u1260\u12da\u1205 \u1218\u1295\u1308\u12f5 \u1202\u12f1!\u201d\n\u12a0\u12ce\u1363 \u1218\u1295\u1308\u12f1 \u12ed\u1204 \u1290\u12cd! \u1270\u12a8\u1270\u1208\u129d!\u201d\n\n\u1273\u12f2\u12eb \u12a0\u1295\u12f5 \u12a5\u1295\u1235\u1233 \u12a5\u1295\u12f0\u12da\u1205 \u12a0\u12ed\u1290\u1275 \u12c8\u1325\u1218\u12f5 \u12a5\u1295\u12f4\u1275 \u120a\u12eb\u1218\u120d\u1325 \u12ed\u127d\u120b\u120d?\n\u12a5\u1231 \u122b\u1231 \u121b\u12f5\u1228\u130d \u12e8\u121a\u127d\u1208\u12cd \u1290\u1308\u122d \u1290\u12cd?\n\u12a0\u12ed\u1363 \u1325\u1295\u1278\u1209 \u12a0\u1245\u1218 \u1262\u1235 \u1290\u12cd\u1362\n\u12a8\u12c8\u1325\u1218\u12f1 \u12cd\u1235\u1325 \u1208\u121b\u12cd\u1323\u1275 \u1265\u120d\u1205\u1293 \u1320\u1295\u12ab\u122b \u1230\u12cd \u12eb\u1235\u1348\u120d\u1308\u12cb\u120d\u1362\n\u12a5\u129b\u1295\u121d \u12e8\u121a\u12eb\u12f5\u1290\u1295 \u1265\u120d\u1205\u1293 \u1320\u1295\u12ab\u122b \u1230\u12cd \u12eb\u1235\u1348\u120d\u1308\u1293\u120d\u1362\n\u1235\u1208\u12da\u1205 \u1325\u1245\u1235 \u12a5\u1295\u12f5\u1273\u12e9\u1275 \u12e8\u121d\u1348\u120d\u1308\u12cd \u1260\u1323\u121d \u12a0\u1235\u1348\u120b\u130a\u12cd \u1290\u1325\u1265 \u12ed\u1205 \u1290\u12cd\u1362\n\u12a0\u12f3\u129d \u12eb\u1235\u1348\u120d\u1308\u1293\u120d \u121d\u12ad\u1295\u12eb\u1271\u121d \u122b\u1233\u127d\u1295\u1295 \u121b\u12f3\u1295 \u12c8\u12ed\u121d \u12c8\u12f0 \u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u1218\u1218\u1208\u1235 \u12a0\u1295\u127d\u120d\u121d\u1362\n\u1260\u1218\u1295\u1348\u1233\u12ca \u12e8\u121e\u1271 \u120d\u1266\u127d \u1215\u12ed\u12c8\u1275\u1295 \u1218\u121d\u1228\u1325 \u12a0\u12ed\u127d\u1209\u121d\u1362\n\u12a0\u1295\u1240\u133d 25 \u121d\u1295 \u12a5\u1295\u12f0\u121a\u120d \u1270\u1218\u120d\u12a8\u1275\u1361-\n\u201d\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u1295\u1235\u1210 \u120a\u1230\u1323\u1278\u12cd \u12ed\u127d\u120b\u120d\u201d\n\n\u12f5\u130e\u121b \u1290\u1343 \u1235\u1326\u1273 \u1290\u12cd\u1362\n\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12e8\u1295\u1235\u1210 \u1235\u1326\u1273 \u12a830 \u12d3\u1218\u1273\u1275 \u1260\u134a\u1275 \u1230\u1325\u1276\u129b\u120d\u1362\n\u1208\u12a0\u1235\u122d \u12a0\u1218\u1273\u1275 \u1260\u12a0\u133d\u1293\u1348 \u12d3\u1208\u121d \u12cd\u1235\u1325 \u12a0\u121d\u120b\u12ad \u12e8\u1208\u121d \u1265\u12ec \u1270\u1293\u130d\u122c \u1290\u1260\u122d\u1362\n\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12f0\u130d \u1235\u1208\u1206\u1290\u1363 \u1262\u122b\u1363 \u1234\u1276\u127d\u1293 \u121d\u12f5\u122b\u12ca \u1235\u12ac\u1275 \u12e8\u120d\u1264\u1295 \u134d\u120b\u130e\u1275 \u1348\u133d\u121e \u120a\u12eb\u1228\u12a9 \u12a5\u1295\u12f0\u121b\u12ed\u127d\u1209 \u12a0\u1233\u12e8\u129d\u1362\n\u1260\u1241\u1325\u122d 26 \u120b\u12ed \u201d\u12c8\u12f0 \u120d\u1266\u1293\u1278\u12cd \u1218\u1218\u1208\u1235\u201d \u12e8\u121a\u1208\u12cd \u1275\u122d\u1309\u121d \u12ed\u1205 \u1290\u12cd\u1362\n\u12e8\u12a0\u1245\u1323\u132b \u1235\u121c\u1275\u1205 \u130d\u122b \u1232\u130b\u1263\u1205 \u1260\u1270\u1233\u1233\u1270 \u12a0\u1245\u1323\u132b \u1275\u1204\u12f3\u1208\u1205\u1362\n\u12c8\u12f0 \u1264\u1275\u12ce \u12e8\u121a\u12c8\u1235\u12f0\u12cd\u1295 \u1218\u1295\u1308\u12f5 \u1208\u121b\u130d\u1298\u1275 \u12e8\u1218\u1300\u1218\u122a\u12eb\u12cd \u12a5\u122d\u121d\u1303 \u12e8\u1320\u1349 \u1218\u1206\u1293\u1278\u12cd\u1295 \u121b\u12c8\u1245 \u1290\u12cd\u1362\n\u12f3\u1295 \u121b\u12ad\u12f6\u12cd\u120d \u1260\u1356\u122d\u1275\u120b\u1295\u12f5 \u1260\u1270\u12ab\u1204\u12f0\u12cd \u1260\u12da\u12eb \u12e8\u121b\u122b\u1276\u1295 \u12cd\u12f5\u12f5\u122d \u12a8\u1320\u1349\u1275 \u122f\u132e\u127d \u12a0\u1295\u12f1 \u1290\u1260\u122d\u1362\n\u12a5\u1295\u12f2\u1205 \u1265\u120f\u120d\u1366 \u201d\u12c8\u12f0 \u1325\u130d \u12f0\u1228\u1235\u12a9\u1293 \u12a0\u1235\u122d \u1230\u12ce\u127d \u12dd\u121d \u1265\u1208\u12cd \u1246\u1218\u12cd \u12a0\u12e8\u1201\u2026\u201d\n\u12a5\u122d\u1235 \u1260\u12a5\u122d\u1233\u1278\u12cd \u12a5\u12e8\u1270\u12eb\u12e9 \u2018\u12a7\u1228 \u12ed\u1205 \u1275\u12ad\u12ad\u120d \u12a0\u12ed\u1218\u1235\u120d\u121d\u2019 \u1265\u1208\u12cd \u12a5\u12eb\u1230\u1261 \u1290\u1260\u122d\u1362\n\n\u120c\u120b\u129b\u12cd \u122f\u132d \u12db\u12ad \u12a9\u1235\u1270\u122d \u12a5\u1295\u12f3\u1209\u1275 \u1218\u12aa\u1296\u127d \u1260\u1230\u12d3\u1275 55 \u121b\u12ed\u120d \u134d\u1325\u1290\u1275 \u12a5\u12eb\u1233\u12f0\u1309 \u12c8\u12f0 \u12cb\u123b\u12cd \u1218\u130d\u1263\u1273\u1278\u12cd\u1295 \u1270\u1293\u130d\u1228\u12cb\u120d\u1362\n\u12eb\u1294 \u1290\u12cd \u12a8\u1275\u12ad\u12ad\u1208\u129b\u12cd \u1218\u1295\u1308\u12f5 \u12c8\u1325\u1276 \u12a5\u1295\u12f0\u1206\u1290 \u12e8\u1270\u1308\u1290\u12d8\u1260\u12cd\u1362\n\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12c8\u12f0 \u120d\u1266\u1293\u12ec \u12a8\u1218\u121d\u1323\u1271 \u1260\u134a\u1275 \u201d\u12e8\u12a5\u12cd\u1290\u1275 \u12a5\u12cd\u1240\u1275\u201d \u12a5\u1295\u12f3\u1208\u129d \u12a0\u1235\u1265 \u1290\u1260\u122d\u1362\n\u12a9\u122b\u1274 \u1275\u12ad\u12ad\u1208\u129b\u12cd\u1295 \u1218\u1295\u1308\u12f5 \u12a5\u1295\u12f0\u121d\u12a8\u1270\u120d \u1290\u1308\u1228\u129d\u1363 \u12a5\u1293\u121d \u1260\u1323\u121d \u1265\u120d\u1205 \u1235\u1208\u1206\u1295\u12a9 \u12e8\u121a\u1218\u122b\u129d \u12a0\u121d\u120b\u12ad \u12a0\u12eb\u1235\u1348\u120d\u1308\u129d\u121d \u1290\u1260\u122d\u1362\n\u12e8\u121a\u1308\u122d\u1218\u12cd \u1290\u1308\u122d\u1363 \u12e8\u1230\u12ed\u1323\u1295\u1295 \u121b\u1273\u1208\u120d \u1208\u121b\u12e8\u1275 \u1260\u1323\u121d \u121e\u129d \u1290\u1260\u122d\u12a9\u1362\n\u1260\u12cd\u1238\u1275 \u12c8\u1325\u1218\u12f5 \u1270\u12eb\u12dd\u12a9\u1362\n\u12a8\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u1238\u123d\u127c \u12f0\u1235\u1273\u1295 \u12a5\u1295\u12f0\u121b\u1308\u129d \u12e8\u12f2\u12eb\u1265\u120e\u1235\u1295 \u1243\u120d \u12a0\u121d\u1295 \u1290\u1260\u122d\u1362\n\u130d\u1295 \u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12e8\u1295\u1235\u1210 \u1235\u1326\u1273 \u1230\u1320\u129d\u1362\n\u12a5\u12da\u1205 \u120b\u12ed \u1208\u1295\u1235\u1210 \u12e8\u1308\u1263\u12cd \u12e8\u130d\u122a\u12ad \u1243\u120d \u121c\u1273\u1296\u12eb \u1290\u12cd\u1362\n\u1275\u122d\u1309\u1219\u121d \u201d\u12e8\u12a0\u1235\u1270\u1233\u1230\u1265 \u1208\u12cd\u1325\u1363 \u12e8\u1205\u12ed\u12c8\u1275 \u1208\u12cd\u1325 \u12a5\u1293 \u12e8\u12d3\u120b\u121b \u1208\u12cd\u1325\u201d \u121b\u1208\u1275 \u1290\u12cd\u1362\n\u12a2\u12e8\u1231\u1235 \u201d\u130c\u1273\u1295 \u12a8\u1295\u1339\u1205 \u120d\u1265 \u1218\u1325\u122b\u1275\u201d \u12a5\u1295\u12f5\u127d\u120d \u12a0\u12f2\u1235 \u120d\u1265 \u1230\u1325\u1276\u129b\u120d\u1364 \u12ed\u1205\u121d \u1241\u1325\u122d 22 \u12a5\u1295\u12f0\u121a\u1208\u12cd\u1362\n\u1295\u1341\u1205 \u120d\u1265 \u1245\u1295 \u120d\u1265 \u1290\u12cd\u1362\n\u201d\u1283\u1322\u12a0\u1274\u1295 \u12ed\u1245\u122d \u1260\u1208\u129d\u1363 \u12a5\u1263\u12ad\u1205 \u12ed\u1245\u122d \u1260\u1208\u129d\u201d \u1265\u120e \u12c8\u12f0 \u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12e8\u121a\u132e\u1205 \u120d\u1265\u1362\n\u12a8\u12a0\u1295\u1270 \u122d\u1244 \u1233\u12ed\u1206\u1295 \u12c8\u12f0 \u12a0\u1295\u1270 \u12a5\u1295\u12f5\u122e\u1325 \u12a5\u122d\u12f3\u129d\u1362\n\u1333\u12cd\u120e\u1235 \u1260\u122e\u121c 10:9-11 \u120b\u12ed \u12c8\u12f0 \u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12a5\u1295\u12f4\u1275 \u1218\u1218\u1208\u1235 \u12a5\u1295\u12f0\u121d\u1275\u127d\u120d\u1293 \u1218\u12f3\u1295 \u12a5\u1295\u12f0\u121d\u1275\u127d\u120d \u1260\u1323\u121d \u130d\u120d\u133d \u12e8\u1206\u1290 \u121b\u1265\u122b\u122a\u12eb \u133d\u134f\u120d\u1362\n9 \u201c\u12a2\u12e8\u1231\u1235 \u130c\u1273 \u1290\u12cd \u1265\u1208\u1205 \u1260\u12a0\u134d\u1205 \u1265\u1275\u1218\u1230\u12ad\u122d\u1363 \u12a5\u130d\u12da\u12a0\u1265\u1214\u122d\u121d \u12a8\u1219\u1273\u1295 \u12a5\u1295\u12f3\u1235\u1290\u1223\u12cd \u1260\u120d\u1265\u1205 \u1265\u1273\u121d\u1295 \u1275\u12f5\u1293\u1208\u1205\u1362\u201d\n10 \u1260\u120d\u1265\u1205 \u12a0\u121d\u1290\u1205 \u1275\u1338\u12f5\u1243\u1208\u1205\u1293\u1365 \u1260\u12a0\u134d\u1205\u121d \u12a5\u121d\u1290\u1275\u1205\u1295 \u1275\u1218\u1230\u12ad\u122b\u1208\u1205\u1293 \u1275\u12f5\u1293\u1208\u1205\u1293\u1362\n11 \u1218\u133d\u1210\u134d \u12a5\u1295\u12f0\u121a\u120d\u1363 \u201c\u1260\u12a5\u122d\u1231 \u12e8\u121a\u12eb\u121d\u1295 \u1201\u1209 \u12a0\u12eb\u134d\u122d\u121d\u1362\u201d\n\n\u12a5\u121d\u1290\u1275\u1205\u1295 \u1260\u12a0\u134d\u1205 \u1270\u1293\u130d\u1228\u1203\u120d\u1363 \u1235\u1208\u12da\u1205 \u1218\u12f3\u1295 \u1275\u127d\u120b\u1208\u1205?\n\u12ab\u120b\u12f0\u1228\u1309\u1275\u1363 \u12db\u122c \u12eb\u1295\u1295 \u1208\u121b\u12f5\u1228\u130d \u1325\u1229 \u1240\u1295 \u12a5\u1295\u12f0\u121a\u1206\u1295 \u12a0\u12ed\u1218\u1235\u120d\u12ce\u1275\u121d?\n\u1218\u1295\u1348\u1235 \u1245\u12f1\u1235 \u12a5\u12da\u1205 \u1260\u1218\u12ab\u12a8\u120b\u127d\u1295 \u12a0\u1208\u1364 \u121d\u1293\u120d\u1263\u1275\u121d \u1260\u120d\u1265\u1205 \u12cd\u1235\u1325 \u1260\u1239\u12ad\u1239\u12ad\u1273 \u12a5\u12e8\u1270\u1293\u1308\u1228 \u120a\u1206\u1295 \u12ed\u127d\u120b\u120d\u1364\n\u201d\u12a8\u1283\u1322\u12a0\u1275\u1293 \u12a8\u121e\u1275 \u1218\u1295\u1308\u12f5 \u1270\u1218\u1208\u1231!\u201d\n\u201c\u12a2\u12e8\u1231\u1235 \u130c\u1273 \u1290\u12cd!\u201d \u1260\u121b\u1208\u1275 \u12a0\u12f2\u1235 \u1215\u12ed\u12c8\u1275\u1295\u1293 \u12a0\u12f2\u1235 \u12a0\u1245\u1323\u132b\u1295 \u121d\u1228\u1325\u1362\n\n\u1333\u12cd\u120e\u1235 \u1235\u1208 \u12a0\u12f2\u1231 \u12a0\u1245\u1323\u132b \u12a0\u1295\u12f5 \u130a\u12dc \u12a8\u12da\u1205 \u1260\u134a\u1275 \u133d\u134f\u120d\u1362\n\u1322\u121e\u1274\u12ce\u1235 \u12a0\u1201\u1295 \u12a5\u1295\u12f0 \u1353\u1235\u1270\u122d \u1206\u1296 \u12a5\u12eb\u1308\u1208\u1308\u1208 \u1263\u1208\u1260\u1275 \u1260\u12a4\u134c\u1236\u1295 \u1208\u121a\u1308\u1298\u12cd \u1208\u12da\u1205\u127d \u1264\u1270 \u12ad\u122d\u1235\u1272\u12eb\u1295 \u1260\u133b\u1348\u12cd \u12f0\u1265\u12f3\u1264 \u120b\u12ed \u1290\u1260\u122d\u1362\n\u1333\u12cd\u120e\u1235 \u1260\u12a4\u134c\u1236\u1295 2\u13611-5 \u120b\u12ed \u1208\u12ad\u122d\u1235\u1272\u12eb\u1295 \u12a0\u121b\u129e\u127d \u12e8\u133b\u1348\u12cd\u1295 \u12a0\u12f5\u121d\u1321\u1363 \u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12a0\u12f2\u1235 \u1215\u12ed\u12c8\u1275\u1293 \u12a0\u12f2\u1235 \u12a0\u1245\u1323\u132b \u1235\u1208\u1230\u1323\u1278\u12cd \u1290\u1308\u122d\u1362\n1 \u201d\u12a5\u1293\u1295\u1270\u121d \u1260\u1260\u12f0\u120b\u127d\u1201\u1293 \u1260\u1283\u1322\u12a0\u1273\u127d\u1201 \u1219\u1273\u1295 \u1290\u1260\u122b\u127d\u1201\u201d\n2\u1364 \u1260\u12a5\u1293\u1295\u1270\u121d \u12cd\u1235\u1325\u1365 \u12e8\u12da\u1205\u1295 \u12d3\u1208\u121d \u1218\u1295\u1308\u12f5 \u12a5\u12e8\u1270\u12a8\u1270\u120b\u127d\u1201\u1365 \u12e8\u12a0\u12e8\u1229\u1295\u121d \u1283\u12ed\u120d \u12a0\u1208\u1243 \u12a5\u12e8\u1270\u12a8\u1270\u120b\u127d\u1201\u1365 \u1260\u121b\u12ed\u1273\u12d8\u12d9\u1275\u121d \u120d\u1306\u127d \u120b\u12ed \u12a0\u1201\u1295 \u12e8\u121a\u1230\u122b\u12cd\u1295 \u1218\u1295\u1348\u1235\u1365\n3\u1364 \u1260\u12a5\u1290\u12da\u1205\u121d \u1218\u12ab\u12a8\u120d \u12a5\u129b \u1201\u120b\u127d\u1295 \u1260\u134a\u1275 \u12e8\u1225\u130b\u127d\u1295\u1295\u1293 \u12e8\u12a0\u12a5\u121d\u122e\u1295 \u121d\u129e\u1275 \u12a5\u12eb\u12f0\u1228\u130d\u1295\u1365 \u1260\u1225\u130b\u127d\u1295 \u121d\u129e\u1275 \u12a5\u1295\u1296\u122d \u1290\u1260\u122d\u1295\u1365 \u12a5\u1295\u12f0 \u120c\u120e\u127d\u121d \u1230\u12ce\u127d \u1260\u1270\u1348\u1325\u122b\u127d\u1295 \u12e8\u1241\u1323 \u120d\u1306\u127d \u1290\u1260\u122d\u1295\u1362\n4 \u1290\u1308\u122d \u130d\u1295 \u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u1260\u121d\u1215\u1228\u1271 \u1263\u1208\u1320\u130b \u1235\u1208 \u1206\u1290\u1365 \u1235\u1208\u12c8\u12f0\u12f0\u1295 \u12a8\u1273\u120b\u1245 \u134d\u1245\u1229 \u12e8\u1270\u1290\u1223\u1365\n5 \u1260\u1260\u12f0\u120b\u127d\u1295 \u1219\u1273\u1295 \u1260\u1206\u1295\u1295 \u130a\u12dc\u121d \u12a5\u1295\u12b3 \u12a8\u12ad\u122d\u1235\u1276\u1235 \u130b\u122d \u1215\u12ed\u12c8\u1275 \u1230\u1320\u1295\u1364 \u1260\u1338\u130b \u12f5\u1293\u127d\u128b\u120d\u1293!\u201d\n\n\u201d\u130d\u1295 \u12a5\u130d\u12da\u12a0\u1265\u1214\u122d\u201d \u12e8\u121a\u1208\u12cd \u1243\u120d \u1260\u12a5\u12eb\u1295\u12f3\u1295\u12f1 \u1230\u12cd \u12e8\u121a\u1290\u1308\u1229\u1275 \u12a5\u1305\u130d \u12cd\u1265 \u1243\u120b\u1275 \u1201\u1208\u1271 \u1293\u1278\u12cd\u1362\n\u1333\u12cd\u120e\u1235 \u1260\u12a4\u134c\u1236\u1295 \u12e8\u1290\u1260\u1229\u1275\u1295 \u12a0\u121b\u129e\u127d \u12a5\u1295\u12f0 \u1325\u1295\u1278\u120d \u12c8\u1325\u1218\u12f5 \u12cd\u1235\u1325 \u12a5\u1295\u12f0\u1290\u1260\u1229\u1293 \u12a0\u1245\u1218 \u1262\u1235 \u12a5\u1295\u12f0\u1290\u1260\u1229 \u12a0\u1235\u1273\u12cd\u1237\u1278\u12cb\u120d\u1362\n\u1290\u1308\u122d \u130d\u1295 \u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u1260\u1338\u130b \u1265\u127b\u1363 \u1260\u12a5\u121d\u1290\u1275 \u1265\u127b\u1363 \u1260\u12ad\u122d\u1235\u1276\u1235 \u1265\u127b \u120a\u12eb\u12f5\u1293\u1278\u12cd \u1323\u120d\u1243 \u1308\u1263\u1362\n\u12e8\u12ad\u122d\u1235\u1276\u1235 \u1260\u1218\u1235\u1240\u120d \u120b\u12ed \u12e8\u12a8\u1348\u1208\u12cd \u1218\u1235\u12cb\u12d5\u1275\u1290\u1275 \u12a8\u1283\u1322\u12a0\u1275\u1293 \u12a8\u1280\u134d\u1228\u1275 \u120a\u12eb\u1325\u1265\u1205 \u12a5\u1295\u12f0\u1206\u1290 \u12ab\u1218\u1295\u12ad \u121b\u1295\u129b\u12cd\u121d \u1230\u12cd \u120a\u12f5\u1295 \u12ed\u127d\u120b\u120d\u1362\n\u12ed\u1205\u1295 \u1235\u1273\u121d\u1295 \u12a0\u12f2\u1235 \u1215\u12ed\u12c8\u1275 \u1275\u1240\u1260\u120b\u1208\u1205\u1364 \u12a2\u12e8\u1231\u1235\u121d \u1260\u12a0\u12f2\u1235 \u1218\u1295\u1308\u12f5 \u120b\u12ed \u12eb\u1235\u1240\u121d\u1323\u1203\u120d\u1362\n\u1260\u12a4\u134c\u1236\u1295 2:8 \u120b\u12ed \u1325\u1242\u1275 \u1241\u1325\u122e\u127d\u1295 \u1235\u1295\u1218\u1208\u12a8\u1275\u1363 \u1333\u12cd\u120e\u1235 \u1235\u1208\u12da\u12eb \u12a0\u12f2\u1235 \u12a0\u1245\u1323\u132b \u12ed\u1293\u1308\u122b\u120d\u1362\n\u12ed\u1205\u1295\u1295 \u12a8\u12a5\u1294 \u130b\u122d \u12a0\u1295\u1265\u1261\u1361-\n\u1201\u1209\u121d\u1366 10 \u201d\u12a5\u129b \u12e8\u12a5\u122d\u1231 \u1225\u122b \u1290\u1295\u1293\u1364 \u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12a0\u1235\u1240\u12f5\u121e \u12eb\u12d8\u130b\u1300\u12cd\u1295 \u1218\u120d\u12ab\u1219\u1295 \u1225\u122b \u1208\u121b\u12f5\u1228\u130d \u1260\u12ad\u122d\u1235\u1276\u1235 \u12a2\u12e8\u1231\u1235 \u1270\u1348\u1320\u122d\u1295\u1362\u201d\n\n\u12ed\u1205\u1295\u1295 \u1218\u120d\u12a5\u12ad\u1275 \u1208\u1218\u1328\u1228\u1235\u1363 \u1260\u1218\u120d\u12ab\u121d \u1225\u122b\u12ce\u127d \u1218\u1218\u120b\u1208\u1235 \u121d\u1295 \u12a5\u1295\u12f0\u121a\u1218\u1235\u120d \u12a5\u1295\u1218\u120d\u12a8\u1275\u1362\n\u1333\u12cd\u120e\u1235 \u1208\u1322\u121e\u1274\u12ce\u1235 \u12e8\u1218\u133d\u1210\u134d \u1245\u12f1\u1235 \u12a0\u1235\u1270\u121b\u122a\u12ce\u127d\u1295 \u121b\u1295 \u1218\u121d\u1228\u1325\u1293 \u121b\u1230\u120d\u1320\u1295 \u12a5\u1295\u12f3\u1208\u1260\u1275 \u1218\u1218\u122a\u12eb \u12a5\u12e8\u1230\u1320\u12cd \u1218\u1206\u1291\u1295 \u12a0\u1235\u1273\u12cd\u1235\u1362\n\u12a5\u1295\u12f0 \u12a0\u121b\u129e\u127d \u1270\u120d\u12a5\u12b3\u127d\u1295 \u12e8\u12c8\u1295\u130c\u120d\u1295 \u1218\u120d\u12ab\u121d \u12dc\u1293 \u12a8\u1245\u122d\u1265\u121d \u12a8\u1229\u1245\u121d \u120b\u1209 \u1230\u12ce\u127d \u121b\u12ab\u1348\u120d \u1290\u12cd\u1362\n\u1290\u1308\u122d \u130d\u1295 \u12ed\u1205\u1295\u1295 \u1260\u1273\u121b\u129d\u1290\u1275 \u1208\u121b\u12f5\u1228\u130d\u1363 \u1333\u12cd\u120e\u1235 \u1260\u12a5\u1290\u12da\u1205 \u1325\u1245\u1236\u127d \u12cd\u1235\u1325 \u12e8\u1308\u1208\u1338\u12cd\u1295 \u1263\u1205\u122a \u120a\u1296\u1228\u1295 \u12ed\u1308\u1263\u120d\u1362\n\u12e8\u121b\u1295\u1295\u121d \u120d\u1265 \u1218\u1208\u12c8\u1325 \u12a0\u1295\u127d\u120d\u121d\u1362\n\u1290\u1308\u122d \u130d\u1295 \u12a5\u12cd\u1290\u1271\u1295 \u1260\u12a5\u122d\u130b\u1273\u1363 \u1260\u12f0\u130d\u1290\u1275 \u12a5\u1293 \u1260\u1275\u12d5\u130d\u1235\u1275 \u120d\u1295\u1290\u130d\u122b\u1278\u12cd \u12a5\u1295\u127d\u120b\u1208\u1295\u1362\n\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d\u121d \u1208\u1270\u1218\u1228\u1321\u1275 \u120d\u1306\u1279 \u1260\u1275\u12ad\u12ad\u1208\u129b\u12cd \u130a\u12dc \u1295\u1235\u1210 \u12a5\u1295\u12f0\u121a\u1230\u1323\u1278\u12cd \u1218\u1270\u121b\u1218\u1295 \u12a5\u1295\u127d\u120b\u1208\u1295\u1362\n\u1260\u12db\u122c\u12cd \u12ad\u134d\u120d \u1260\u1241\u1325\u122d 24 \u12a5\u1293 25 \u120b\u12ed \u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u1260\u12a0\u1308\u120d\u130b\u12ee\u1279 \u12cd\u1235\u1325 \u120a\u12eb\u12f3\u1265\u122d \u12e8\u121a\u1348\u120d\u130b\u1278\u12cd\u1295 \u12a0\u121d\u1235\u1275 \u1263\u1215\u122d\u12eb\u1275 \u12a0\u12eb\u1208\u1201\u1361\n\n\u1325\u122b\u1275 1\u1361 \u1320\u1265 \u12a0\u132b\u122a \u12a0\u12ed\u12f0\u1208\u121d\u1362\n\u12a0\u1295\u12f3\u1295\u12f5 \u1230\u12ce\u127d \u1218\u12a8\u122b\u12a8\u122d \u12ed\u12c8\u12f3\u1209\u1362\n\u1324\u1293\u121b \u12ad\u122d\u12ad\u122d \u121d\u1295\u121d \u127d\u130d\u122d \u12e8\u1208\u12cd\u121d\u1362\n\u130d\u1295 \u1260\u1283\u1322\u12a0\u1275 \u201d\u1320\u1265\u201d \u12cd\u1235\u1325 \u1218\u1206\u1295\u1205\u1295 \u12a5\u1295\u12f4\u1275 \u1273\u12cd\u1243\u1208\u1205?\n\u121d\u1293\u120d\u1263\u1275 \u12ed\u1205\u1295\u1295 \u1325\u12eb\u1244 \u12a5\u122b\u1235\u12ce\u1295 \u1218\u1320\u12e8\u1245 \u12ed\u127d\u120b\u1209-\n\u201d\u12a8\u12a0\u1295\u12f5 \u1230\u12cd \u130b\u122d \u1218\u127c \u1290\u12cd \u12e8\u121d\u1328\u1243\u1328\u1240\u12cd\u1363 \u1235\u1208\u12da\u12eb \u1230\u12cd \u12e8\u1260\u1208\u1320 \u12e8\u121d\u1328\u1290\u1240\u12cd \u12c8\u12ed\u1235 \u1235\u1208 \u12ad\u122d\u12ad\u1229 \u121b\u1238\u1290\u134d?\n\u12a9\u122b\u1274 \u12f0\u130d \u12a8\u1218\u1206\u1295 \u12ed\u120d\u1245 \u1275\u12ad\u12ad\u120d \u1208\u1218\u1206\u1295 \u12a5\u1295\u12f3\u1270\u12a9\u122d \u12a5\u12eb\u12f0\u1228\u1308\u129d \u1290\u12cd?\n\n\u1325\u122b\u1275 2\u1361 \u1208\u1201\u1209\u121d \u12f0\u130d\u1362\n\u12e8\u130c\u1273 \u12a0\u1308\u120d\u130b\u12ed \u1208\u1201\u1209\u121d \u1230\u12cd \u12f0\u130d \u1218\u1206\u1295 \u12a0\u1208\u1260\u1275\u1362\n\u1208\u121a\u1320\u1209\u1205\u1293 \u120a\u130e\u12f1\u1205 \u1208\u121a\u1348\u120d\u1309 \u1230\u12ce\u127d \u12a5\u1295\u12b3\u1295\u1362\n\u12eb \u12a8\u1263\u12f5 \u1290\u12cd\u1363 \u12a0\u12cd\u1243\u1208\u1201\u1362\n\u122b\u1233\u127d\u1295\u1295 \u12a8\u120c\u120e\u127d \u1230\u12ce\u127d \u12e8\u121d\u1295\u1320\u1265\u1245\u1260\u1275 \u1218\u1295\u1308\u12f5 \u1320\u1295\u12ab\u122b \u1218\u1206\u1295\u1363 \u1283\u12ed\u120d\u1295 \u1218\u1320\u1240\u121d \u12a5\u1295\u12f0\u1206\u1290 \u12a5\u1293\u121d\u1293\u1208\u1295\u1362\n\u1290\u1308\u122d \u130d\u1295 \u1333\u12cd\u120e\u1235 \u1260\u122e\u121c 2:4 \u120b\u12ed \u121d\u1295 \u12a5\u1295\u12f3\u1235\u1273\u12c8\u1230\u1295 \u1270\u1218\u120d\u12a8\u1271\u1364\n\u201d\u12e8\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u1278\u122d\u1290\u1275 \u12c8\u12f0 \u1295\u1235\u1210 \u120a\u1218\u122b\u1205 \u12e8\u1273\u1230\u1260 \u1290\u12cd\u1362\u201d\n\u1260\u1283\u1322\u12a0\u1275 \u12cd\u1235\u1325 \u1206\u1290\u1205 \u12a8\u12a5\u122d\u1231 \u122d\u1240\u1205 \u1235\u1275\u1204\u12f5 \u12a2\u12e8\u1231\u1235 \u121d\u1295 \u12eb\u1205\u120d \u12f0\u130d \u1290\u1260\u122d?\n\u1278\u122d\u1290\u1271 \u1295\u1235\u1210 \u12a5\u1295\u12f5\u1275\u1308\u1261 \u12a0\u12f5\u122d\u1313\u127d\u128b\u120d\u1363\n\u1235\u1208\u12da\u1205 \u12a0\u1201\u1295 \u12ad\u122d\u1235\u1276\u1235\u1295 \u12e8\u1218\u121d\u1230\u120d \u12a5\u1293 \u1208\u1201\u1209\u121d \u12f0\u130d \u12e8\u1218\u1206\u1295 \u12a5\u12f5\u120d \u12a0\u120b\u127d\u1201\u1362\n\n\u1325\u122b\u1275 3\u1361 \u12ad\u134b\u1275\u1295 \u1260\u1275\u12d5\u130d\u1235\u1275 \u1218\u1273\u1308\u1235\u1362\n\u12e8\u12c8\u1295\u130c\u120d\u1295 \u12a5\u12cd\u1290\u1275 \u1235\u1293\u12ab\u134d\u120d\u1363 \u12e8\u121d\u1295\u1293\u1308\u1228\u12cd\u1295 \u12e8\u121b\u12ed\u12c8\u12f1 \u1230\u12ce\u127d \u1270\u1243\u12cd\u121e \u12eb\u130b\u1325\u1218\u1293\u120d\u1362\n\u12a5\u1235\u1322\u134b\u1296\u1235 \u1208\u1308\u12f0\u1209\u1275 \u1230\u12ce\u127d \u121d\u1295 \u121d\u120b\u123d \u12a5\u1295\u12f0\u1230\u1320 \u1273\u1235\u1273\u12cd\u1233\u1208\u1205?\n\u12e8\u1210\u12cb\u122d\u12eb\u1275 \u1225\u122b 7:59-60 \u12a5\u1295\u12f2\u1205 \u12ed\u120b\u120d\u1361-\n59 \u12a5\u1235\u1322\u134b\u1296\u1235\u121d \u12a5\u12e8\u12c8\u1309\u1275 \u1233\u1208 \u201d\u130c\u1273 \u12a2\u12e8\u1231\u1235 \u1206\u12ed\u1363 \u1218\u1295\u1348\u1234\u1295 \u1270\u1240\u1260\u120d\u201d \u1265\u120e \u1338\u1208\u12e8\u1362\n60 \u12a8\u12da\u12eb\u121d \u1260\u1309\u120d\u1260\u1271 \u1270\u1295\u1260\u122d\u12ad\u12ae\u1362 \u130c\u1273 \u1206\u12ed\u1365 \u12ed\u1205\u1295 \u1283\u1322\u12a0\u1275 \u12a0\u1275\u12eb\u12dd\u1263\u1278\u12cd \u1265\u120e \u132e\u12b8\u1362\n\n\u120d\u12ad \u12a5\u1295\u12f0 \u12a5\u1235\u1322\u134b\u1296\u1235 \u12ad\u134b\u1275\u1295 \u1260\u1275\u12d5\u130d\u1235\u1275 \u12a5\u1295\u12f5\u1295\u124b\u124b\u121d \u12e8\u121a\u1228\u12f3\u1295 \u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u1265\u127b \u1290\u12cd\u1362\n\u1290\u1308\u122d \u130d\u1295 \u1260\u127d\u130d\u122d \u130a\u12dc \u12c8\u12f0 \u12a5\u122d\u1231 \u1235\u1295\u132e\u1205 \u12ed\u1228\u12f3\u1293\u120d\u1362\n\u1260\u1230\u12cd\u1290\u1273\u127d\u1295 \u120b\u12ed \u121d\u1295\u121d \u1262\u12f0\u122d\u1235 \u1290\u134d\u1233\u127d\u1295 \u1260\u12a5\u1301 \u12cd\u1235\u1325 \u12a5\u1295\u12f3\u1208\u127d \u12a5\u12eb\u12c8\u1240\u1363 \u1260\u12a5\u122d\u1231 \u12a5\u1295\u12f5\u1295\u1273\u1218\u1295 \u12ed\u1228\u12f3\u1293\u120d\u1362\n\n\u1325\u122b\u1275 4\u1361 \u1260\u1308\u122d\u1290\u1275 \u121b\u1228\u121d\u1362\n\u1230\u12ce\u127d\u1295 \u121b\u1228\u121d \u12a8\u1263\u12f5 \u1290\u12cd\u1362\n\u120d\u1304 \u130d\u1295 \u12e8\u1206\u1290 \u1235\u1205\u1270\u1275 \u12a8\u1230\u122b\u1363 \u1235\u1208\u121d\u12c8\u12f0\u12cd \u12a5\u1290\u130d\u1228\u12cb\u1208\u1201\u1362\n\u12a0\u1295\u12f5\u1295 \u1230\u12cd \u121b\u1228\u121d \u1232\u1296\u122d\u1265\u12ce\u1275 \u120a\u12eb\u1235\u1261\u1260\u1275 \u12e8\u121a\u1308\u1263 \u12a0\u1235\u1348\u120b\u130a \u1325\u12eb\u1244 \u12a5\u1290\u1206\u1361\n\u201d\u120d\u1304\u1363 \u1313\u12f0\u129b\u12ec \u12c8\u12ed\u121d \u1263\u1208\u1264\u1274 \u134d\u1245\u122c\u1295 \u12ed\u1230\u121b\u12cb\u120d?\u201d\n\u12c8\u12ed\u1235 \u1241\u1323\u12ec\u1295 \u1265\u127b \u1290\u12cd \u12e8\u121a\u1230\u121b\u1278\u12cd?\n\n\u1260\u1241\u1323 \u12c8\u12ed\u121d \u1260\u1265\u1235\u132d\u1275 \u1235\u1293\u1235\u1270\u12ab\u12ad\u120d\u1363 \u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u120c\u120b\u129b\u12cd\u1295 \u1230\u12cd \u120a\u1208\u12cd\u1325 \u12a5\u1295\u12f0\u121b\u12ed\u127d\u120d \u12a5\u12eb\u12f0\u1228\u130d\u1295 \u1290\u12cd\u1362\n\u12a5\u1295\u12f2\u1240\u12ed\u1229 \u132b\u1293 \u120d\u1293\u12f0\u122d\u130d\u1263\u1278\u12cd \u12c8\u12ed\u121d \u1260\u1275\u12ad\u12ad\u1208\u129b\u12cd \u1218\u1295\u1308\u12f5 \u120b\u12ed \u12a5\u1235\u12aa\u12f0\u122d\u1231 \u12f5\u1228\u1235 \u132e\u12ad \u1265\u1208\u1295 \u120d\u1295\u132e\u1205\u1263\u1278\u12cd \u12a5\u1295\u12f0\u121d\u1295\u127d\u120d \u12a5\u1293\u1235\u1263\u1208\u1295\u1362\n\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u12a5\u12cd\u1290\u1270\u129b \u1283\u12ed\u120d \u12a5\u1295\u12f3\u1208\u12cd \u12e8\u121a\u12eb\u12cd\u1245 \u12a0\u1235\u1270\u121b\u122a \u130d\u1295 \u1308\u122d\u1363 \u1273\u130b\u123d \u12a5\u1293 \u12f0\u130d \u12ed\u1206\u1293\u120d\u1362\n\n\u1325\u122b\u1275 5\u1361 \u121b\u1235\u1270\u121b\u122d \u12e8\u121a\u127d\u120d\u1362\n\u12e8\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d\u1295 \u1243\u120d \u1208\u120c\u120e\u127d \u1208\u121b\u1235\u1228\u12f3\u1275 \u1260\u1242 \u1260\u1206\u1290 \u1218\u1295\u1308\u12f5 \u1270\u1228\u12f5\u1270\u12b8\u12cb\u120d?\n\u1218\u133d\u1210\u134d \u1245\u12f1\u1235\u1295 \u12a5\u12eb\u1235\u1273\u12c8\u1235\u12ad \u1290\u12cd\u1363 \u1235\u1208\u12da\u1205 \u1260\u1215\u12ed\u12c8\u1275\u1205 \u12cd\u1235\u1325 \u1208\u1218\u121d\u122b\u1275 \u12a5\u1293 \u1208\u120c\u120e\u127d \u1208\u121b\u12ab\u1348\u120d \u12dd\u130d\u1301 \u1290\u1205?\n\u1260\u12da\u1205 \u12c8\u122d \u12a0\u12f2\u1235 \u1290\u1308\u122d \u12a5\u1295\u1300\u121d\u122b\u1208\u1295\u1362\n\u12a5\u1235\u12a8 \u1218\u130b\u1262\u1275 \u1218\u1328\u1228\u123b \u12f5\u1228\u1235 \u12a0\u1295\u12f5 \u12e8\u1218\u133d\u1210\u134d \u1245\u12f1\u1235 \u1325\u1245\u1235 \u12a5\u1295\u12f5\u1273\u1235\u1273\u12cd\u1231 \u12a5\u1295\u1320\u12ed\u1243\u127d\u128b\u1208\u1295\u1362\n\u12a5\u1293 \u1260\u121b\u1295\u129b\u12cd\u121d \u124b\u1295\u124b \u12a8\u1218\u122a\u12ce\u127b\u127d\u1295 \u12a0\u1295\u12f1\u1295 \u121b\u1295\u1260\u1265 \u12a8\u127b\u120d\u12ad \u1270\u1208\u1323\u134a \u1273\u1308\u129b\u1208\u1205\u1362\n\u1260\u12cd\u1203 \u1320\u122d\u1219\u1235\u12ce \u12c8\u12ed\u121d \u1260\u121b\u1235\u1273\u12c8\u123b \u12f0\u1265\u1270\u122d\u12ce \u120b\u12ed \u121b\u1235\u1240\u1218\u1325 \u12ed\u127d\u120b\u1209\u1362\n\u1260\u12e8\u1275\u129b\u12cd\u121d \u1266\u1273 \u12eb\u12e9\u1273\u120d \u12a5\u1293 \u12d3\u1218\u1271\u1295 \u1219\u1209 \u1218\u1208\u121b\u1218\u12f1\u1295 \u12ed\u1240\u1325\u120b\u1209\u1362\n\u12e8\u1218\u130b\u1262\u1275 \u12c8\u122d \u1325\u1245\u1235\u1295 \u12a0\u1265\u1228\u1295 \u12a5\u1293\u1295\u1265\u1265\u1363 2\u129b \u1322\u121e\u1274\u12ce\u1235 3\u136116\u1362\n\u1201\u1209\u121d\u1366 \u201d\u1245\u12f1\u1233\u1275 \u1218\u133b\u1215\u134d\u1275 \u1201\u1209 \u12e8\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u1218\u1295\u1348\u1235 \u12eb\u1208\u1263\u1278\u12cd \u1293\u1278\u12cd\u1364 \u1208\u121b\u1235\u1270\u121b\u122d\u1363 \u1208\u1218\u1308\u1220\u133d\u1363 \u1208\u121b\u1228\u121d\u1293 \u1260\u133d\u12f5\u1245 \u1208\u1218\u121d\u12a8\u122d \u12ed\u1320\u1245\u121b\u1209\u201d\n\n\u1260\u1275\u12ad\u12ad\u1208\u129b\u12cd \u12a0\u1245\u1323\u132b \u1218\u122e\u1323\u127d\u1295\u1295 \u1208\u1218\u1240\u1320\u120d \u1201\u120b\u127d\u1295\u121d \u12a5\u122d\u12f3\u1273 \u12eb\u1235\u1348\u120d\u1308\u1293\u120d\u1362\n\u12e8\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u1243\u120d \u1260\u133d\u12f5\u1245 \u12a5\u1295\u12f5\u1295\u1218\u120b\u1208\u1235 \u1208\u121b\u1235\u1270\u121b\u122d\u1363 \u1208\u121b\u1228\u121d \u12a5\u1293 \u1208\u121b\u1230\u120d\u1320\u1295 \u12eb\u1235\u1348\u120d\u1308\u1293\u120d\u1362\n\u12a5\u1293\u121d \u1243\u1209\u1295 \u12a5\u1295\u12f5\u1295\u1228\u12f3\u1293 \u1270\u130d\u1263\u122b\u12ca \u12a5\u1295\u12f5\u1293\u12f0\u122d\u130d \u1218\u1295\u1348\u1235 \u1245\u12f1\u1235 \u12ed\u1228\u12f3\u1293\u120d\u1363 \u1235\u1208\u12da\u1205 \u12a0\u1201\u1295 \u1260\u1338\u120e\u1275 \u120d\u1263\u127d\u1295\u1295 \u12c8\u12f0 \u1230\u121b\u12ed \u12a5\u1293\u12d9\u122d\u1362\n\u12a2\u12e8\u1231\u1235 \u1206\u12ed\u1363 \u12a8\u12a0\u1265 \u130b\u122d \u1218\u1290\u130b\u1308\u122d \u12e8\u121d\u1295\u127d\u1208\u12cd \u1260\u121d\u12f5\u122d\u1293 \u1260\u1230\u121b\u12ed \u1218\u12ab\u12a8\u120d \u12f5\u120d\u12f5\u12ed \u1235\u1208\u1220\u122b\u1205 \u1265\u127b \u1290\u12cd\u1362\n\u12e8\u12f2\u12eb\u1265\u120e\u1235\u1295 \u12c8\u1325\u1218\u12f6\u127d \u12a0\u1325\u134d\u1270\u1203\u120d\u1364 \u12d3\u12ed\u1296\u127b\u127d\u1295\u1295\u121d \u12c8\u12f0 \u12a5\u12cd\u1290\u1275 \u12a8\u134d\u1270\u1203\u120d\u1362\n\u12a0\u1263\u1275 \u1206\u12ed\u1363 \u12e8\u1295\u1235\u1210 \u1235\u1326\u1273 \u1235\u1208\u1230\u1320\u12b8\u1295 \u12a5\u1293\u1218\u1230\u130d\u1293\u1208\u1295\u1363 \u1235\u1208\u12da\u1205 \u1235\u1208 \u1283\u1322\u12a0\u1273\u127d\u1295 \u1208\u122b\u1233\u127d\u1295\u121d \u1206\u1290 \u12a8\u12a0\u1295\u1270 \u130b\u122d \u1210\u1240\u129b \u200b\u200b\u1218\u1206\u1295 \u12a5\u1295\u127d\u120b\u1208\u1295\u1362\n\u1218\u1295\u1348\u1235 \u1245\u12f1\u1235 \u1206\u12ed\u1363 \u1208\u12f5\u1290\u1273\u127d\u1295 \u12c8\u12f0 \u12a2\u12e8\u1231\u1235 \u12a5\u1295\u12f5\u1295\u12de\u122d \u12a5\u121d\u1290\u1275 \u1235\u1208\u1230\u1320\u12b8\u1295 \u12a0\u1218\u1230\u130d\u1293\u1208\u1201\u1362\n\u1243\u1209\u1295 \u1208\u1218\u1228\u12f3\u1275\u1293 \u1260\u1215\u12ed\u12c8\u1273\u127d\u1295 \u1270\u130d\u1263\u122b\u12ca \u1208\u121b\u12f5\u1228\u130d \u12a0\u12a5\u121d\u122f\u127d\u1295\u1295\u1293 \u120d\u1263\u127d\u1295\u1295 \u12ad\u1348\u1275\u1362\n\u12a8\u134a\u1273\u127d\u1295 \u12e8\u1270\u12d8\u1228\u130b\u12cd\u1295 \u1229\u132b \u1260\u1265\u122d\u1271 \u12a5\u1295\u12f5\u1295\u122e\u1325\u1363 \u120c\u120e\u127d\u1295\u121d \u12c8\u12f0 \u1219\u1209\u1290\u1275\u1363 \u12c8\u12f0 \u1270\u1235\u134b \u12a5\u1293 \u12c8\u12f0 \u1230\u121b\u12ed \u1260\u121a\u12f0\u1228\u1308\u12cd \u1309\u12de \u120b\u12ed \u12a8\u12a5\u129b \u130b\u122d \u12a5\u1295\u12f2\u1240\u120b\u1240\u1209\u1295 \u1260\u1218\u130b\u1260\u12dd\u1363 \u12a0\u121c\u1295\u1362\n\n\u12e8\u121b\u1230\u120b\u1230\u12eb \u12a5\u1293 \u12e8\u1218\u12c8\u12eb\u12eb \u1325\u12eb\u1244\u12ce\u127d\n1.  2\u129b \u1322\u121e\u1274\u12ce\u1235 2:22 \u12a5\u1293 \u1218\u12dd\u1219\u122d 119:35-37\u1295 \u12a0\u1295\u1265\u1265\u1362\n\u1200) \u12cd\u1325\u1228\u1275 \u1232\u12eb\u130b\u1325\u121d\u1205 \u12c8\u12ed\u121d \u1218\u133d\u1293\u129b \u1232\u1348\u120d\u130d \u120d\u1265\u1205 \u1260\u1270\u1348\u1325\u122e\u12cd \u12c8\u12f0 \u12e8\u1275\u129b\u12cd \u201d\u12e8\u12c8\u1323\u1275\u1290\u1275 \u134d\u120b\u130e\u1276\u127d\u201d (\u12f0\u1235\u1273\u1363 \u1225\u120d\u1323\u1295\u1363 \u1270\u12c8\u12f3\u1305\u1290\u1275\u1363 \u1295\u1265\u1228\u1275\u1363 \u12a9\u122b\u1275) \u12ed\u122e\u1323\u120d?\n\n2.  \u12a4\u134c\u1236\u1295 2:1-5 \u12a5\u1293 \u1215\u12dd\u1245\u12a4\u120d 36:26\u1295 \u12a0\u1295\u1265\u1265\u1362\n\u1200) \u12a8\u201d\u121e\u1270\u201d \u12c8\u12f0 \u201d\u1215\u12eb\u12cd\u201d \u1208\u1218\u1238\u130b\u1308\u122d \u121d\u1295 \u12eb\u1235\u1348\u120d\u130b\u120d?\n\u1208) \u1295\u1235\u1210 \u12e8\u1338\u130b \u1235\u1326\u1273 \u1290\u12cd \u1265\u120e \u121b\u1218\u1295 \u1235\u1208 \u1283\u1322\u12a0\u1275\u1205 \u12a8\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d \u130b\u122d \u12e8\u1260\u1208\u1320 \u1210\u1240\u129b \u12a5\u1295\u12f5\u1275\u1206\u1295 \u12ed\u1228\u12f3\u1203\u120d?\n\n3.  2\u129b \u1322\u121e\u1274\u12ce\u1235 2:23-25\u1200 \u12a5\u1293 \u1246\u120b\u1235\u12ed\u1235 3:12-14\u1295 \u12a0\u1295\u1265\u1265\u1362\n\u1200) \u201d\u12e8\u130c\u1273 \u1263\u122a\u12eb\u201d \u120c\u120e\u127d\u1295 \u1232\u12a8\u122b\u12a8\u122d \u12c8\u12ed\u121d \u1232\u12eb\u122d\u121d \u12e8\u121a\u1320\u1240\u121d\u1263\u1278\u12cd \u1263\u1205\u122a\u12eb\u1275 \u121d\u1295\u12f5\u1293\u1278\u12cd?\n\u1208) \u12a2\u12e8\u1231\u1235 \u1260\u1273\u120b\u1245 \u1275\u12d5\u130d\u1235\u1275\u1293 \u1308\u122d\u1290\u1275 \u1235\u1208\u12c8\u12f0\u12f0\u1295\u1363 \u1260\u1215\u12ed\u12c8\u1275\u1205 \u12cd\u1235\u1325 \u1260\u12da\u12eb\u12cd \u1338\u130b \u121b\u1295\u1295 \u1275\u12c8\u12f3\u1208\u1205-- \u12a8\u12a0\u1295\u1270 \u130b\u122d \u1263\u12ed\u1235\u121b\u1219\u121d \u12c8\u12ed\u121d \u1263\u12ed\u12c8\u12f1\u1205\u121d?\n\n4.  \u122e\u121c 10:9-11 \u12a5\u1293 \u12d5\u1265\u122b\u12cd\u12eb\u1295 12:1-2\u1295 \u12eb\u1295\u1265\u1261\u1362\n\u1200) \u12d3\u12ed\u1296\u127b\u127d\u1295\u1295 \u1260\u12a2\u12e8\u1231\u1235 \u120b\u12ed \u121b\u1270\u12ae\u122d \u12a8\u1283\u1322\u12a0\u1275 \u12a5\u1295\u12f5\u1295\u1218\u1208\u1235\u1293 \u12c8\u12f0 \u12a0\u12f2\u1235 \u12a0\u1245\u1323\u132b \u12a5\u1295\u12f5\u1295\u122e\u1325 \u12e8\u121a\u1228\u12f3\u1295 \u12a5\u1295\u12f4\u1275 \u1290\u12cd?\n\u1208) 2\u129b \u1322\u121e\u1274\u12ce\u1235 3:16\u1295 \u121b\u1235\u1273\u12c8\u1235\u1205\u1295 \u12a0\u1235\u1273\u12cd\u1235\u1362 \u12e8\u12a5\u130d\u12da\u12a0\u1265\u1214\u122d\u1295 \u1243\u120d \u121b\u12c8\u1245 \u12e8\u12a5\u121d\u1290\u1275\u1295 \u121b\u122b\u1276\u1295 \u12a5\u1295\u12f5\u1295\u122e\u1325 \u12e8\u121a\u1228\u12f3\u1295 \u12a5\u1295\u12f4\u1275 \u1290\u12cd?","arabic_content":"\u0625\u0644\u0649 \u0623\u064a\u0646 \u0623\u0646\u062a \u0630\u0627\u0647\u0628\u061f\n\u0662 \u062a\u064a\u0645\u0648\u062b\u0627\u0648\u0633 \u0662: \u0662\u0662-\u0662\u0666\n\u0627\u0644\u0642\u0633 \u0643\u0631\u064a\u0633 \u0633\u064a\u0643\u0633\n15 \u0645\u0627\u0631\u0633 2026\n\n\u0641\u064a \u0645\u0627\u0631\u0627\u062b\u0648\u0646 2019 \u0641\u064a \u0628\u0648\u0631\u062a\u0644\u0627\u0646\u062f \u0628\u0648\u0644\u0627\u064a\u0629 \u0623\u0648\u0631\u064a\u063a\u0648\u0646\u060c \u062e\u0633\u0631 \u0628\u0639\u0636 \u0623\u0641\u0636\u0644 \u0627\u0644\u0639\u062f\u0627\u0626\u064a\u0646 \u0627\u0644\u0633\u0628\u0627\u0642 \u0628\u0627\u0644\u0641\u0639\u0644.\n\u0644\u064a\u0633 \u0644\u0623\u0646\u0647\u0645 \u0643\u0627\u0646\u0648\u0627 \u0628\u0637\u064a\u0626\u064a\u0646\u060c \u0628\u0644 \u0644\u0623\u0646\u0647\u0645 \u0633\u0644\u0643\u0648\u0627 \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u062e\u0637\u0623.\n\u0643\u0627\u0646 \u0647\u0646\u0627\u0643 \u0645\u0646\u0639\u0637\u0641 \u0641\u064a \u0627\u0644\u0645\u0633\u0627\u0631 \u0644\u0645 \u064a\u0643\u0646 \u0648\u0627\u0636\u062d\u0627\u064b.\n\u0644\u0630\u0627\u060c \u0631\u0643\u0636 \u062d\u0648\u0627\u0644\u064a 20 \u0645\u0646 \u0623\u0633\u0631\u0639 \u0627\u0644\u0639\u062f\u0627\u0626\u064a\u0646 \u0623\u0643\u062b\u0631 \u0645\u0646 \u0645\u064a\u0644 \u0641\u064a \u0627\u0644\u0627\u062a\u062c\u0627\u0647 \u0627\u0644\u062e\u0627\u0637\u0626!\n\u0623\u0636\u0627\u0641 \u0647\u0630\u0627 \u0627\u0644\u062e\u0637\u0623 \u062f\u0642\u0627\u0626\u0642 \u062b\u0645\u064a\u0646\u0629 \u0625\u0644\u0649 \u0633\u0628\u0627\u0642 \u0623\u0645\u0636\u0648\u0627 \u0634\u0647\u0648\u0631\u0627\u064b \u0641\u064a \u0627\u0644\u0627\u0633\u062a\u0639\u062f\u0627\u062f \u0644\u0647.\n\u0631\u0643\u0636 \u0647\u0624\u0644\u0627\u0621 \u0627\u0644\u0631\u062c\u0627\u0644 \u0648\u0627\u0644\u0646\u0633\u0627\u0621 \u0628\u0642\u0648\u0629\u060c \u0648\u0631\u0643\u0636\u0648\u0627 \u0628\u0633\u0631\u0639\u0629.\n\u0644\u0643\u0646\u0647\u0645 \u062e\u0633\u0631\u0648\u0627 \u0627\u0644\u0633\u0628\u0627\u0642\u060c \u0644\u0623\u0646\u0647\u0645 \u0643\u0627\u0646\u0648\u0627 \u064a\u0633\u064a\u0631\u0648\u0646 \u0641\u064a \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u062e\u0637\u0623.\n\u0646\u0648\u0627\u0635\u0644 \u0627\u0644\u0644\u064a\u0644\u0629 \u0633\u0644\u0633\u0644\u0629 \u0639\u0638\u0627\u062a \u0645\u0646 \u0643\u062a\u0627\u0628 \u062a\u064a\u0645\u0648\u062b\u0627\u0648\u0633 \u0627\u0644\u062b\u0627\u0646\u064a.\n\u064a\u0643\u062a\u0628 \u0627\u0644\u0631\u0633\u0648\u0644 \u0628\u0648\u0644\u0633 \u0625\u0644\u0649 \u062a\u064a\u0645\u0648\u062b\u0627\u0648\u0633\u060c \u0631\u0627\u0639\u064a \u0627\u0644\u0643\u0646\u064a\u0633\u0629 \u0627\u0644\u0645\u0633\u064a\u062d\u064a\u0629 \u0627\u0644\u0634\u0627\u0628 \u0641\u064a \u0623\u0641\u0633\u0633.\n\u064a\u0642\u062f\u0645 \u0628\u0648\u0644\u0633 \u0644\u062a\u064a\u0645\u0648\u062b\u0627\u0648\u0633\u060c \u0648\u0644\u0646\u0627 \u0627\u0644\u064a\u0648\u0645\u060c \u0646\u0635\u0627\u0626\u062d \u062d\u0648\u0644 \u0643\u064a\u0641\u064a\u0629 \u0627\u0644\u0628\u0642\u0627\u0621 \u0639\u0644\u0649 \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u0635\u062d\u064a\u062d.\n\u0662 \u062a\u064a\u0645\u0648\u062b\u0627\u0648\u0633 \u0662: \u0662\u0662-\u0662\u0666\n22 \u201d \u0623\u064e\u0645\u064e\u0651\u0627 \u0627\u0644\u0634\u064e\u0651\u0647\u064e\u0648\u064e\u0627\u062a\u064f \u0627\u0644\u0634\u064e\u0651\u0628\u064e\u0627\u0628\u0650\u064a\u064e\u0651\u0629\u064f \u0641\u064e\u0627\u0647\u0652\u0631\u064f\u0628\u0652 \u0645\u0650\u0646\u0652\u0647\u064e\u0627\u060c \u0648\u064e\u0627\u062a\u0652\u0628\u064e\u0639\u0650 \u0627\u0644\u0652\u0628\u0650\u0631\u064e\u0651 \u0648\u064e\u0627\u0644\u0625\u0650\u064a\u0645\u064e\u0627\u0646\u064e \u0648\u064e\u0627\u0644\u0652\u0645\u064e\u062d\u064e\u0628\u064e\u0651\u0629\u064e \u0648\u064e\u0627\u0644\u0633\u064e\u0651\u0644\u0627\u064e\u0645\u064e \u0645\u064e\u0639\u064e \u0627\u0644\u064e\u0651\u0630\u0650\u064a\u0646\u064e \u064a\u064e\u062f\u0652\u0639\u064f\u0648\u0646\u064e \u0627\u0644\u0631\u064e\u0651\u0628\u064e\u0651 \u0645\u0650\u0646\u0652 \u0642\u064e\u0644\u0652\u0628\u064d \u0646\u064e\u0642\u0650\u064a\u064d\u0651.\n23  \u0648\u064e\u0627\u0644\u0652\u0645\u064f\u0628\u064e\u0627\u062d\u064e\u062b\u064e\u0627\u062a\u064f \u0627\u0644\u0652\u063a\u064e\u0628\u0650\u064a\u064e\u0651\u0629\u064f \u0648\u064e\u0627\u0644\u0633\u064e\u0651\u062e\u0650\u064a\u0641\u064e\u0629\u064f \u0627\u062c\u0652\u062a\u064e\u0646\u0650\u0628\u0652\u0647\u064e\u0627\u060c \u0639\u064e\u0627\u0644\u0650\u0645\u0627\u064b \u0623\u064e\u0646\u064e\u0651\u0647\u064e\u0627 \u062a\u064f\u0648\u064e\u0644\u0650\u0651\u062f\u064f \u062e\u064f\u0635\u064f\u0648\u0645\u064e\u0627\u062a\u064d\u060c\n24  \u0648\u064e\u0639\u064e\u0628\u0652\u062f\u064f \u0627\u0644\u0631\u064e\u0651\u0628\u0650\u0651 \u0644\u0627\u064e \u064a\u064e\u062c\u0650\u0628\u064f \u0623\u064e\u0646\u0652 \u064a\u064f\u062e\u064e\u0627\u0635\u0650\u0645\u064e\u060c \u0628\u064e\u0644\u0652 \u064a\u064e\u0643\u064f\u0648\u0646\u064f \u0645\u064f\u062a\u064e\u0631\u064e\u0641\u0650\u0651\u0642\u0627\u064b \u0628\u0650\u0627\u0644\u0652\u062c\u064e\u0645\u0650\u064a\u0639\u0650\u060c \u0635\u064e\u0627\u0644\u0650\u062d\u0627\u064b \u0644\u0650\u0644\u062a\u064e\u0651\u0639\u0652\u0644\u0650\u064a\u0645\u0650\u060c \u0635\u064e\u0628\u064f\u0648\u0631\u0627\u064b \u0639\u064e\u0644\u064e\u0649 \u0627\u0644\u0652\u0645\u064e\u0634\u064e\u0642\u064e\u0651\u0627\u062a\u0650\u060c\n25  \u0645\u064f\u0624\u064e\u062f\u0650\u0651\u0628\u0627\u064b \u0628\u0650\u0627\u0644\u0652\u0648\u064e\u062f\u064e\u0627\u0639\u064e\u0629\u0650 \u0627\u0644\u0652\u0645\u064f\u0642\u064e\u0627\u0648\u0650\u0645\u0650\u064a\u0646\u064e\u060c\n\u0639\u064e\u0633\u064e\u0649 \u0623\u064e\u0646\u0652 \u064a\u064f\u0639\u0652\u0637\u0650\u064a\u064e\u0647\u064f\u0645\u064f \u0627\u0644\u0644\u0647\u064f \u062a\u064e\u0648\u0652\u0628\u064e\u0629\u064b \u0644\u0650\u0645\u064e\u0639\u0652\u0631\u0650\u0641\u064e\u0629\u0650 \u0627\u0644\u0652\u062d\u064e\u0642\u0650\u0651\u060c\n26  \u0641\u064e\u064a\u064e\u0633\u0652\u062a\u064e\u0641\u0650\u064a\u0642\u064f\u0648\u0627 \u0645\u0650\u0646\u0652 \u0641\u064e\u062e\u0650\u0651 \u0625\u0650\u0628\u0652\u0644\u0650\u064a\u0633\u064e \u0625\u0650\u0630\u0652 \u0642\u064e\u062f\u0650 \u0627\u0642\u0652\u062a\u064e\u0646\u064e\u0635\u064e\u0647\u064f\u0645\u0652 \u0644\u0625\u0650\u0631\u064e\u0627\u062f\u064e\u062a\u0650\u0647\u0650.\n\n\u0646\u0642\u0631\u0623 \u0645\u0639\u064b\u0627 \u0625\u0634\u0639\u064a\u0627\u0621 40:8:\n\u201d\u0627\u0644\u0639\u0634\u0628 \u064a\u0630\u0628\u0644\u060c \u0648\u0627\u0644\u0632\u0647\u0631\u0629 \u062a\u0630\u0628\u0644\u060c \u0623\u0645\u0627 \u0643\u0644\u0645\u0629 \u0625\u0644\u0647\u0646\u0627 \u0641\u0633\u062a\u0628\u0642\u0649 \u0625\u0644\u0649 \u0627\u0644\u0623\u0628\u062f.\u201d\n\n\u062a\u0642\u0648\u0644 \u0627\u0644\u0622\u064a\u0629 22:\n22 \u201d\u0623\u064e\u0645\u064e\u0651\u0627 \u0627\u0644\u0634\u064e\u0651\u0647\u064e\u0648\u064e\u0627\u062a\u064f \u0627\u0644\u0634\u064e\u0651\u0628\u064e\u0627\u0628\u0650\u064a\u064e\u0651\u0629\u064f \u0641\u064e\u0627\u0647\u0652\u0631\u064f\u0628\u0652 \u0645\u0650\u0646\u0652\u0647\u064e\u0627\u060c \u0648\u064e\u0627\u062a\u0652\u0628\u064e\u0639\u0650 \u0627\u0644\u0652\u0628\u0650\u0631\u064e\u0651 \u0648\u064e\u0627\u0644\u0625\u0650\u064a\u0645\u064e\u0627\u0646\u064e \u0648\u064e\u0627\u0644\u0652\u0645\u064e\u062d\u064e\u0628\u064e\u0651\u0629\u064e \u0648\u064e\u0627\u0644\u0633\u064e\u0651\u0644\u0627\u064e\u0645\u064e \u0645\u064e\u0639\u064e \u0627\u0644\u064e\u0651\u0630\u0650\u064a\u0646\u064e \u064a\u064e\u062f\u0652\u0639\u064f\u0648\u0646\u064e \u0627\u0644\u0631\u064e\u0651\u0628\u064e\u0651 \u0645\u0650\u0646\u0652 \u0642\u064e\u0644\u0652\u0628\u064d \u0646\u064e\u0642\u0650\u064a\u064d\u0651.\u201d\n\n\u0647\u0630\u0647 \u0627\u0644\u0622\u064a\u0629 \u0647\u064a \u0641\u064a \u0627\u0644\u062d\u0642\u064a\u0642\u0629 \u0645\u0644\u062e\u0635 \u0644\u062e\u0637\u0628\u0629 \u0627\u0644\u064a\u0648\u0645.\n\u0646\u0631\u0649 \u0647\u0630\u0627 \u0643\u062b\u064a\u0631\u0627\u064b \u0641\u064a \u0643\u0644\u0645\u0629 \u0627\u0644\u0631\u0628.\n\u0623\u062d\u064a\u0627\u0646\u064b\u0627 \u062a\u0643\u0648\u0646 \u0627\u0644\u0639\u0628\u0627\u0631\u0629 \u0627\u0644\u0623\u0648\u0644\u0649 \u0641\u064a \u0627\u0644\u0645\u0632\u0645\u0648\u0631 \u0623\u0648 \u0627\u0644\u0641\u0642\u0631\u0629 \u0628\u0645\u062b\u0627\u0628\u0629 \u0645\u0644\u062e\u0635.\n\u062b\u0645 \u062a\u0623\u062a\u064a \u0627\u0644\u0643\u0644\u0645\u0627\u062a \u0627\u0644\u062a\u0627\u0644\u064a\u0629 \u0643\u0634\u0631\u062d \u0644\u0644\u0645\u0632\u0645\u0648\u0631 \u0628\u0623\u0643\u0645\u0644\u0647 \u0623\u0648 \u0627\u0644\u0641\u0642\u0631\u0629 \u0623\u0648 \u0627\u0644\u0641\u0635\u0644.\n\u0625\u0646 \u0627\u0644\u0631\u062c\u0644 \u0623\u0648 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0645\u0633\u064a\u062d\u064a\u0629 \u0627\u0644\u0646\u0627\u0636\u062c\u0627\u0646 \u0647\u0645\u0627 \u0627\u0644\u0630\u0627\u0646 \u064a\u0628\u062a\u0639\u062f\u0627\u0646 \u0639\u0646 \u0627\u0644\u0623\u0634\u064a\u0627\u0621 \u0627\u0644\u062a\u064a \u062a\u063a\u0631\u064a\u0647\u0645\u0627 \u0639\u0646\u062f\u0645\u0627 \u0643\u0627\u0646\u0627 \u0635\u063a\u064a\u0631\u0627\u0646 \u0641\u064a \u0627\u0644\u0633\u0646.\n\u0628\u062f\u0644\u0627\u064b \u0645\u0646 \u201d\u0627\u0644\u0623\u0647\u0648\u0627\u0621 \u0627\u0644\u0634\u0628\u0627\u0628\u064a\u0629\u201d\u060c \u064a\u062a\u0639\u0644\u0645 \u0627\u0644\u0634\u062e\u0635 \u0627\u0644\u0646\u0627\u0636\u062c \u0627\u0644\u0633\u0639\u064a \u0648\u0631\u0627\u0621 \u0642\u064a\u0645 \u0627\u0644\u0647 \u0627\u0644\u0633\u0645\u0627\u0648\u0627\u062a\u060c \u0628\u0645\u0627 \u0641\u064a \u0630\u0644\u0643 \u0627\u0644\u0628\u0631 \u0648\u0627\u0644\u0625\u064a\u0645\u0627\u0646 \u0648\u0627\u0644\u0645\u062d\u0628\u0629 \u0648\u0627\u0644\u0633\u0644\u0627\u0645.\n\u0639\u0646\u062f\u0645\u0627 \u0643\u0627\u0646 \u0628\u0648\u0644\u0633 \u0634\u0627\u0628\u0627\u064b\u060c \u0643\u0627\u0646 \u0627\u0633\u0645\u0647 \u0634\u0627\u0648\u0644.\n\u0643\u0627\u0646 \u0634\u0627\u0648\u0644 \u0645\u0644\u064a\u0626\u0627\u064b \u0628\u0627\u0644\u0643\u0628\u0631\u064a\u0627\u0621 \u0648\u0627\u0644\u062b\u0642\u0629 \u0628\u0627\u0644\u0646\u0641\u0633\u060c \u0645\u0633\u062a\u062e\u062f\u0645\u0627\u064b \u0633\u0644\u0637\u062a\u0647 \u0644\u0627\u0636\u0637\u0647\u0627\u062f \u0627\u0644\u0645\u0633\u064a\u062d\u064a\u064a\u0646 \u0648\u0633\u062c\u0646\u0647\u0645.\n\u0643\u0627\u0646 \u0634\u0627\u0648\u0644 \u064a\u0631\u064a\u062f \u0623\u0646 \u064a\u0643\u0648\u0646 \u0645\u062d\u0628\u0648\u0628\u0627\u064b \u0648\u0646\u0627\u062c\u062d\u0627\u064b\u060c \u0648\u0643\u0627\u0646 \u0639\u0644\u0649 \u0627\u0633\u062a\u0639\u062f\u0627\u062f \u0644\u0625\u064a\u0630\u0627\u0621 \u0627\u0644\u0622\u062e\u0631\u064a\u0646 \u0628\u0633\u0628\u0628 \u0643\u0628\u0631\u064a\u0627\u0626\u0647.\n\u0644\u0643\u0646 \u0631\u0633\u0627\u0644\u0629 \u062a\u064a\u0645\u0648\u062b\u0627\u0648\u0633 \u0627\u0644\u062b\u0627\u0646\u064a\u0629 \u0643\u062a\u0628\u0647\u0627 \u0628\u0648\u0644\u0633 \u0627\u0644\u0645\u0624\u0645\u0646 \u0627\u0644\u0646\u0627\u0636\u062c.\n\u0625\u0646\u0647 \u064a\u062f\u0631\u0643 \u062d\u062c\u0645 \u0627\u0644\u0636\u0631\u0631 \u0627\u0644\u0630\u064a \u0623\u0644\u062d\u0642\u062a\u0647 \u0628\u0647 \u0639\u0648\u0627\u0637\u0641\u0647 \u0627\u0644\u0634\u0628\u0627\u0628\u064a\u0629\u060c \u0648\u0647\u0648 \u064a\u062d\u0630\u0631 \u062a\u064a\u0645\u0648\u062b\u064a \u0645\u0646\u0647\u0627.\n\u0641\u064a \u0627\u0644\u0648\u0642\u062a \u0627\u0644\u0630\u064a \u0643\u062a\u0628 \u0641\u064a\u0647 \u0628\u0648\u0644\u0633 \u0647\u0630\u0647 \u0627\u0644\u0631\u0633\u0627\u0644\u0629\u060c \u0643\u0627\u0646 \u062a\u064a\u0645\u0648\u062b\u0627\u0648\u0633 \u0639\u0644\u0649 \u0627\u0644\u0623\u0631\u062c\u062d \u064a\u0628\u0644\u063a \u0645\u0646 \u0627\u0644\u0639\u0645\u0631 \u062d\u0648\u0627\u0644\u064a 40 \u0639\u0627\u0645\u064b\u0627.\n\u0644\u0643\u0646 \u0644\u064a\u0633 \u0639\u0644\u064a\u0643 \u0623\u0646 \u062a\u0643\u0648\u0646 \u0634\u0627\u0628\u0627\u064b \u0644\u062a\u0646\u062f\u0641\u0639 \u0646\u062d\u0648 \u201d\u0634\u063a\u0641 \u0627\u0644\u0634\u0628\u0627\u0628\u201d.\n\u0623\u0646\u0627 \u0641\u064a \u0627\u0644\u0633\u0627\u0628\u0639\u0629 \u0648\u0627\u0644\u062e\u0645\u0633\u064a\u0646 \u0645\u0646 \u0639\u0645\u0631\u064a\u060c \u0644\u0643\u0646\u0646\u064a \u0645\u0627 \u0632\u0644\u062a \u0623\u062a\u0639\u0644\u0645 \u0643\u064a\u0641 \u0623\u0647\u0631\u0628 \u0628\u0627\u0633\u062a\u0645\u0631\u0627\u0631 \u0645\u0646 \u0639\u0648\u0627\u0637\u0641 \u0627\u0644\u0634\u0628\u0627\u0628.\n\u0644\u062f\u064a \u0635\u062f\u064a\u0642 \u0645\u0646 \u0627\u0644\u062c\u0627\u0645\u0639\u0629 \u0641\u064a \u0646\u0641\u0633 \u0639\u0645\u0631\u064a.\n\u0644\u0643\u0646\u0647 \u0644\u0627 \u064a\u0632\u0627\u0644 \u064a\u0639\u064a\u0634 \u0643\u0645\u0627 \u0643\u0627\u0646 \u064a\u0639\u064a\u0634 \u0642\u0628\u0644 35 \u0639\u0627\u0645\u0627\u064b.\n\u062d\u064a\u0627\u062a\u0647 \u0645\u062a\u0623\u062b\u0631\u0629 \u0628\u0634\u062f\u0629 \u0628\u0639\u0648\u0627\u0637\u0641 \u0627\u0644\u0634\u0628\u0627\u0628 \u0627\u0644\u062a\u064a \u0631\u0627\u0641\u0642\u062a \u0623\u064a\u0627\u0645 \u062f\u0631\u0627\u0633\u062a\u0646\u0627 \u0627\u0644\u062c\u0627\u0645\u0639\u064a\u0629.\n\u0625\u0644\u064a\u0643\u0645 \u0628\u0639\u0636 \u0627\u0644\u0634\u063a\u0641 \u0627\u0644\u0634\u0628\u0627\u0628\u064a \u0627\u0644\u0630\u064a \u064a\u0645\u0631 \u0628\u0647 \u0627\u0644\u0643\u062b\u064a\u0631 \u0645\u0646\u0627:\n\n*   \u0627\u0644\u0645\u062a\u0639\u0629: \u0627\u0644\u062e\u0637\u064a\u0626\u0629 \u0627\u0644\u062c\u0646\u0633\u064a\u0629 \u0645\u062b\u0627\u0644 \u0634\u0627\u0626\u0639 \u0639\u0644\u0649 \u062e\u0637\u064a\u0626\u0629 \u0627\u0644\u0645\u062a\u0639\u0629\u060c \u0644\u0643\u0646\u0647\u0627 \u0644\u064a\u0633\u062a \u0627\u0644\u0648\u062d\u064a\u062f\u0629.\n\u062a\u0634\u0645\u0644 \u0627\u0644\u0645\u0644\u0630\u0627\u062a \u0627\u0644\u0645\u062d\u0631\u0645\u0629 \u0627\u0644\u0623\u062e\u0631\u0649 \u0627\u0644\u0643\u062d\u0648\u0644 \u0648\u0627\u0644\u0637\u0639\u0627\u0645 \u0648\u0623\u0646\u0648\u0627\u0639\u064b\u0627 \u0639\u062f\u064a\u062f\u0629 \u0645\u0646 \u0627\u0644\u062a\u0631\u0641\u064a\u0647.\n\u0647\u0630\u0647 \u0627\u0644\u0623\u0634\u064a\u0627\u0621 \u0644\u064a\u0633\u062a \u0633\u064a\u0626\u0629 \u0625\u0630\u0627 \u062a\u0645 \u0627\u0633\u062a\u062e\u062f\u0627\u0645\u0647\u0627 \u0628\u0634\u0643\u0644 \u0635\u062d\u064a\u062d.\n\u0627\u0644\u062c\u0646\u0633\u060c \u0639\u0644\u0649 \u0633\u0628\u064a\u0644 \u0627\u0644\u0645\u062b\u0627\u0644\u060c \u0647\u0648 \u0647\u0628\u0629 \u062c\u0645\u064a\u0644\u0629 \u0641\u064a \u0633\u064a\u0627\u0642 \u0627\u0644\u0632\u0648\u0627\u062c \u0627\u0644\u0645\u0633\u064a\u062d\u064a.\n\u0644\u0643\u0646 \u0639\u0646\u062f\u0645\u0627 \u0646\u0633\u062a\u062e\u062f\u0645 \u0623\u064a \u0634\u064a\u0621 \u0628\u0637\u0631\u064a\u0642\u0629 \u062e\u0627\u0637\u0626\u0629\u060c \u0641\u0625\u0646\u0646\u0627 \u0646\u0645\u0646\u062d\u0647 \u0627\u0644\u0642\u0648\u0629 \u0639\u0644\u0649 \u062d\u064a\u0627\u062a\u0646\u0627.\n\u0639\u0646\u062f\u0645\u0627 \u0646\u0633\u062a\u062e\u062f\u0645 \u0623\u064a\u064b\u0627 \u0645\u0646 \u0647\u0628\u0627\u062a \u0627\u0644\u0631\u0628 \u0644\u0645\u0644\u0621 \u0627\u0644\u0641\u0631\u0627\u063a \u0641\u064a \u0642\u0644\u0648\u0628\u0646\u0627\u060c \u064a\u0635\u0628\u062d \u0630\u0644\u0643 \u0627\u0644\u0634\u064a\u0621 \u0625\u0644\u0647\u064b\u0627 \u0632\u0627\u0626\u0641\u064b\u0627- \u0635\u0646\u0645\u064b\u0627.\n\n*   \u0627\u0644\u0642\u0648\u0629: \u0639\u0646\u062f\u0645\u0627 \u0646\u0643\u0648\u0646 \u0635\u063a\u0627\u0631\u0627\u064b\u060c \u0646\u0634\u0639\u0631 \u0623\u062d\u064a\u0627\u0646\u0627\u064b \u0628\u0627\u0644\u0639\u062c\u0632 \u0623\u0648 \u0627\u0644\u0636\u0639\u0641 \u0623\u0648 \u0639\u062f\u0645 \u0627\u0644\u0643\u0641\u0627\u0621\u0629.\n\u0644\u0642\u062f \u0639\u0627\u0646\u064a\u062a \u0645\u0646 \u062a\u0644\u0643 \u0627\u0644\u0645\u0634\u0627\u0639\u0631 \u0641\u064a \u0641\u062a\u0631\u0629 \u0627\u0644\u0645\u0631\u0627\u0647\u0642\u0629.\n\u064a\u0633\u0639\u0649 \u0628\u0639\u0636 \u0627\u0644\u0646\u0627\u0633 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0637\u0629 \u0644\u0644\u062a\u063a\u0637\u064a\u0629 \u0639\u0644\u0649 \u0645\u0634\u0627\u0639\u0631 \u0627\u0644\u0636\u0639\u0641 \u0627\u0644\u062a\u064a \u062a\u0646\u062a\u0627\u0628\u0647\u0645.\n\u064a\u0639\u062a\u0642\u062f\u0648\u0646 \u0623\u0646 \u0627\u0644\u062a\u0635\u0631\u0641 \u0628\u0642\u0648\u0629 \u0633\u064a\u0633\u0627\u0639\u062f\u0647\u0645 \u0639\u0644\u0649 \u0627\u0644\u0634\u0639\u0648\u0631 \u0628\u0627\u0644\u0623\u0645\u0627\u0646.\n\u0647\u0644 \u062a\u0639\u0644\u0645 \u0623\u0646 \u0627\u0644\u0645\u062a\u0646\u0645\u0631 \u0644\u064a\u0633 \u0641\u064a \u0627\u0644\u0648\u0627\u0642\u0639 \u0628\u0627\u0644\u0642\u0648\u0629 \u0627\u0644\u062a\u064a \u064a\u0628\u062f\u0648 \u0639\u0644\u064a\u0647\u061f\n\u0627\u0644\u0645\u062a\u0646\u0645\u0631 \u0639\u0627\u062f\u0629\u064b \u0645\u0627 \u064a\u0643\u0648\u0646 \u0634\u062e\u0635\u064b\u0627 \u064a\u0634\u0639\u0631 \u0628\u0627\u0644\u0639\u062c\u0632 \u062a\u062c\u0627\u0647 \u0623\u0645\u0631 \u0645\u0627 \u0641\u064a \u062d\u064a\u0627\u062a\u0647\u060c \u0644\u0630\u0644\u0643 \u064a\u0624\u0630\u064a \u0627\u0644\u0622\u062e\u0631\u064a\u0646 \u0644\u064a\u0634\u0639\u0631 \u0628\u0627\u0644\u0642\u0648\u0629.\n\n*   \u0627\u0644\u0634\u0639\u0628\u064a\u0629: \u0644\u0642\u062f \u0643\u0627\u0646\u062a \u0647\u0630\u0647 \u0625\u062d\u062f\u0649 \u0627\u0644\u0625\u063a\u0631\u0627\u0621\u0627\u062a \u0627\u0644\u0642\u0648\u064a\u0629 \u0627\u0644\u0623\u062e\u0631\u0649 \u0641\u064a \u062d\u064a\u0627\u062a\u064a.\n\u0643\u062b\u064a\u0631\u0627\u064b \u0645\u0627 \u064a\u0646\u062a\u0627\u0628\u0646\u064a \u0627\u0644\u0642\u0644\u0642 \u0628\u0634\u0623\u0646 \u0645\u0627 \u0625\u0630\u0627 \u0643\u0627\u0646 \u0627\u0644\u0646\u0627\u0633 \u064a\u062d\u0628\u0648\u0646\u0646\u064a.\n\u0623\u0646\u0627 \u0623\u0647\u062a\u0645 \u0643\u062b\u064a\u0631\u0627\u064b \u0628\u0622\u0631\u0627\u0621 \u0627\u0644\u0622\u062e\u0631\u064a\u0646.\n\u0645\u0627\u0630\u0627 \u0639\u0646\u0643\u061f\n\u0647\u0644 \u0633\u0628\u0642 \u0644\u0643 \u0623\u0646 \u063a\u064a\u0631\u062a \u0633\u0644\u0648\u0643\u0643 \u0623\u0648 \u0645\u0638\u0647\u0631\u0643 \u0644\u062a\u062c\u0639\u0644 \u0627\u0644\u0646\u0627\u0633 \u064a\u062d\u0628\u0648\u0646\u0643\u061f\n\u0647\u0644 \u062a\u0639\u062a\u0642\u062f \u0623\u0646\u0647 \u0639\u0644\u064a\u0643 \u0627\u0644\u062a\u0635\u0631\u0641 \u0623\u0648 \u0627\u0644\u0638\u0647\u0648\u0631 \u0628\u0637\u0631\u064a\u0642\u0629 \u0645\u0639\u064a\u0646\u0629 \u0644\u062a\u062c\u0646\u0628 \u0627\u0644\u0631\u0641\u0636\u061f\n\n*   \u0627\u0644\u0645\u0645\u062a\u0644\u0643\u0627\u062a: \u0625\u0646 \u062d\u0628 \u0627\u0644\u0645\u0627\u0644 \u0648\u0627\u0644\u0645\u0645\u062a\u0644\u0643\u0627\u062a \u0627\u0644\u0645\u0627\u062f\u064a\u0629 \u064a\u0645\u062b\u0644 \u0645\u0634\u0643\u0644\u0629 \u0644\u0645\u0639\u0638\u0645\u0646\u0627.\n\u0646\u0631\u064a\u062f \u0627\u0644\u0623\u0645\u0627\u0646 \u0648\u0627\u0644\u0631\u0627\u062d\u0629 \u0627\u0644\u062a\u064a \u064a\u0648\u0641\u0631\u0647\u0627 \u0627\u0645\u062a\u0644\u0627\u0643 \u0627\u0644\u0645\u0632\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u064a\u0627\u0621.\n\u0647\u0630\u0627 \u064a\u0643\u0634\u0641 \u0639\u0646 \u0627\u0646\u0639\u062f\u0627\u0645 \u0627\u0644\u0625\u064a\u0645\u0627\u0646.\n\u064a\u0631\u064a\u062f \u0627\u0644\u0644\u0647 \u0623\u0646 \u0646\u0641\u0647\u0645 \u0623\u0646\u0647 \u0645\u0644\u062c\u0623\u0646\u0627 \u0648\u062d\u0635\u0646\u0646\u0627\u060c \u0648\u0647\u0648 \u0631\u0627\u0632\u0642\u0646\u0627.\n\u062a\u0639\u062f \u0627\u0644\u0623\u0634\u064a\u0627\u0621 \u0627\u0644\u0645\u0627\u062f\u064a\u0629 \u0628\u0627\u0644\u0633\u0639\u0627\u062f\u0629\u060c \u0644\u0643\u0646\u0647\u0627 \u0644\u0627 \u062a\u0633\u062a\u0637\u064a\u0639 \u0627\u0644\u0648\u0641\u0627\u0621 \u0628\u0648\u0639\u062f\u0647\u0627 \u0623\u0628\u062f\u0627\u064b.\n\u0644\u0623\u0646 \u0642\u0644\u0648\u0628\u0646\u0627 \u0633\u062a\u062a\u0648\u0642 \u062f\u0627\u0626\u0645\u0627\u064b \u0625\u0644\u0649 \u0627\u0644\u0645\u0632\u064a\u062f.\n\n*   \u0627\u0644\u0643\u0628\u0631\u064a\u0627\u0621: \u0647\u0630\u0647 \u0647\u064a \u0627\u0644\u062e\u0637\u064a\u0626\u0629 \u0627\u0644\u0643\u0627\u0645\u0646\u0629 \u0648\u0631\u0627\u0621 \u0643\u0644 \u062e\u0637\u064a\u0626\u0629 \u0623\u062e\u0631\u0649.\n\u0627\u0644\u0643\u0628\u0631\u064a\u0627\u0621 \u0647\u0648 \u0627\u0644\u0627\u0639\u062a\u0642\u0627\u062f \u0628\u0623\u0646\u0646\u064a \u0623\u0633\u062a\u062d\u0642 \u0628\u0627\u0644\u0641\u0639\u0644 \u0627\u0644\u0645\u0645\u062a\u0644\u0643\u0627\u062a \u0648\u0627\u0644\u0633\u0644\u0637\u0629 \u0648\u0627\u0644\u0645\u062a\u0639\u0629 \u0648\u0627\u0644\u0634\u0639\u0628\u064a\u0629.\n\u0644\u0645\u0627\u0630\u0627\u061f \u0644\u0623\u0646\u0646\u064a \u0645\u0645\u064a\u0632.\n\u064a\u0648\u0633\u0648\u0633 \u0644\u0646\u0627 \u0627\u0644\u0643\u0628\u0631\u064a\u0627\u0621 \u0628\u0627\u0644\u0623\u0643\u0627\u0630\u064a\u0628 \u0642\u0627\u0626\u0644\u0627\u064b:\n\u201d\u0644\u0627 \u0628\u0623\u0633\u060c \u064a\u0645\u0643\u0646\u0643 \u0641\u0639\u0644 \u0630\u0644\u0643- \u0623\u0646\u062a \u062a\u0633\u062a\u062d\u0642 \u0630\u0644\u0643.\u201d\n\u064a\u0642\u0648\u0644 \u0627\u0644\u0645\u0639\u0644\u0646\u0648\u0646 \u0627\u0644\u0634\u064a\u0621 \u0646\u0641\u0633\u0647 \u0644\u0646\u0627.\n\u0623\u0646\u062a \u062a\u0633\u062a\u062d\u0642 \u0630\u0644\u0643... \u062a\u0641\u0636\u0644\u060c \u0627\u0634\u062a\u0631\u0647.\n\u0631\u0628\u0645\u0627 \u0627\u0634\u062a\u0631\u064a \u0627\u0644\u0645\u0632\u064a\u062f\u060c \u0644\u0627 \u0628\u0623\u0633.\n\u0644\u0647\u0630\u0627 \u0627\u0644\u0633\u0628\u0628 \u0646\u0631\u0649 \u0627\u0644\u0643\u062b\u064a\u0631 \u0645\u0646 \u0627\u0644\u0625\u0639\u0644\u0627\u0646\u0627\u062a \u0643\u0647\u0630\u0647\u060c \u0644\u0623\u0646 \u0643\u0628\u0631\u064a\u0627\u0621\u0646\u0627 \u064a\u0631\u064a\u062f \u0641\u064a \u0627\u0644\u0648\u0627\u0642\u0639 \u0623\u0646 \u064a\u0635\u062f\u0642 \u0647\u0630\u0647 \u0627\u0644\u0623\u0634\u064a\u0627\u0621.\n\n\u0647\u0644 \u0644\u064a \u0623\u0646 \u0623\u0633\u0623\u0644\u0643\u0645 \u0633\u0624\u0627\u0644\u0627\u064b \u064a\u0627 \u0623\u0635\u062f\u0642\u0627\u0626\u064a\u061f\n\u0623\u064a \u0645\u0646 \u0647\u0630\u0647 \u0627\u0644\u0623\u0634\u064a\u0627\u0621 \u0627\u0644\u062e\u0645\u0633\u0629 \u064a\u0628\u062f\u0648 \u0645\u0623\u0644\u0648\u0641\u0627\u064b \u0644\u0643\u061f\n\u0647\u0644 \u062a\u0633\u0639\u0649 \u0648\u0631\u0627\u0621 \u0627\u0644\u0643\u0628\u0631\u064a\u0627\u0621\u060c \u0623\u0648 \u0627\u0644\u0645\u0645\u062a\u0644\u0643\u0627\u062a\u060c \u0623\u0648 \u0627\u0644\u0633\u0644\u0637\u0629\u060c \u0623\u0648 \u0627\u0644\u0645\u062a\u0639\u0629\u060c \u0623\u0648 \u0627\u0644\u0634\u0647\u0631\u0629\u061f\n\u0623\u0648 \u0631\u0628\u0645\u0627 \u0647\u0646\u0627\u0643 \u0634\u064a\u0621 \u0622\u062e\u0631 \u064a\u0628\u0639\u062f\u0643 \u0639\u0646 \u0627\u0644\u0627\u0644\u0647\u061f\n\u0623\u064a\u0646 \u0642\u0644\u0628\u0643 \u0627\u0644\u064a\u0648\u0645\u060c \u0648\u0625\u0644\u0649 \u0623\u064a\u0646 \u0623\u0646\u062a \u0630\u0627\u0647\u0628\u061f\n\u0647\u0644 \u062a\u062a\u0630\u0643\u0631 \u0645\u0627 \u0633\u0623\u0644\u0647 \u0627\u0644\u0644\u0647 \u0644\u0622\u062f\u0645 \u0641\u064a \u0627\u0644\u062c\u0646\u0629 \u0628\u0639\u062f \u0623\u0646 \u0623\u0643\u0644 \u0645\u0646 \u0627\u0644\u062b\u0645\u0631\u0629\u061f\n\u0643\u0627\u0646 \u0622\u062f\u0645 \u0648\u062d\u0648\u0627\u0621 \u064a\u062e\u062a\u0628\u0626\u0627\u0646\u060c \u0641\u0642\u0627\u0644 \u0627\u0644\u0644\u0647: \u201d\u0623\u064a\u0646 \u0623\u0646\u062a \u064a\u0627 \u0622\u062f\u0645\u061f\u201d\n\u064a\u0637\u0644\u0628 \u0627\u0644\u0631\u0628 \u0627\u0644\u0627\u0644\u0647 \u0627\u0644\u0634\u064a\u0621 \u0646\u0641\u0633\u0647 \u0645\u0646 \u0643\u0644 \u0634\u062e\u0635 \u0639\u0644\u0649 \u0648\u062c\u0647 \u0627\u0644\u0623\u0631\u0636 \u0627\u0644\u064a\u0648\u0645.\n\u0623\u064a\u0646 \u0623\u0646\u062a\u061f\n\u0647\u0648 \u0644\u0627 \u064a\u0633\u0623\u0644 \u0639\u0646 \u0645\u0643\u0627\u0646 \u0648\u062c\u0648\u062f\u0643 \u0641\u0639\u0644\u064a\u0627\u064b.\n\u0625\u0646\u0647 \u064a\u0633\u0623\u0644: \u201d\u0623\u064a\u0646 \u0642\u0644\u0628\u0643\u061f\u201d\n\u0644\u0623\u0646 \u0642\u0644\u0648\u0628\u0646\u0627 \u0645\u062b\u0644 \u0627\u0644\u0628\u0648\u0635\u0644\u0629 \u0627\u0644\u062a\u064a \u062a\u0642\u0648\u062f\u0646\u0627 \u0641\u064a \u0627\u0644\u0637\u0631\u064a\u0642 \u0646\u062d\u0648 \u0627\u0644\u0634\u064a\u0621 \u0627\u0644\u0630\u064a \u0646\u064f\u0642\u062f\u0651\u0631\u0647 \u0623\u0643\u062b\u0631 \u0645\u0646 \u063a\u064a\u0631\u0647.\n\u0646\u0636\u0644 \u0627\u0644\u0637\u0631\u064a\u0642 \u062f\u0648\u0646 \u0623\u0646 \u0646\u062f\u0631\u064a\u060c \u0644\u0623\u0646 \u0627\u0644\u062e\u0637\u064a\u0626\u0629 \u062e\u0628\u064a\u062b\u0629.\n\u0646\u062d\u0646 \u0628\u062d\u0627\u062c\u0629 \u0625\u0644\u0649 \u0639\u0648\u0646 \u0627\u0644\u0644\u0647 \u0644\u0646\u0631\u0649 \u0645\u0627 \u064a\u062c\u0631\u064a \u0641\u064a \u062f\u0627\u062e\u0644\u0646\u0627.\n\u0644\u0646\u0642\u0631\u0623 \u0645\u0639\u064b\u0627 \u0627\u0644\u0645\u0632\u0645\u0648\u0631 139: 23-24\u060c \u0643\u0635\u0644\u0627\u0629:\n\u0627\u0644\u062c\u0645\u064a\u0639: 23  \u0627\u062e\u0652\u062a\u064e\u0628\u0650\u0631\u0652\u0646\u0650\u064a \u064a\u064e\u0627 \u0627\u0644\u0644\u0647\u064f \u0648\u064e\u0627\u0639\u0652\u0631\u0650\u0641\u0652 \u0642\u064e\u0644\u0652\u0628\u0650\u064a.\n\u0627\u0645\u0652\u062a\u064e\u062d\u0650\u0646\u0650\u0651\u064a \u0648\u064e\u0627\u0639\u0652\u0631\u0650\u0641\u0652 \u0623\u064e\u0641\u0652\u0643\u064e\u0627\u0631\u0650\u064a.\n24  \u0648\u064e\u0627\u0646\u0652\u0638\u064f\u0631\u0652 \u0625\u0650\u0646\u0652 \u0643\u064e\u0627\u0646\u064e \u0641\u0650\u064a\u064e\u0651 \u0637\u064e\u0631\u0650\u064a\u0642\u064c \u0628\u064e\u0627\u0637\u0650\u0644\u064c\n\u0648\u064e\u0627\u0647\u0652\u062f\u0650\u0646\u0650\u064a \u0637\u064e\u0631\u0650\u064a\u0642\u0627\u064b \u0623\u064e\u0628\u064e\u062f\u0650\u064a\u0651\u0627\u064b.\n\n\u0628\u062f\u0648\u0646 \u0639\u0648\u0646 \u0627\u0644\u0631\u0628\u060c \u0644\u0646 \u0646\u0633\u064a\u0631 \u201d\u0641\u064a \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u0623\u0628\u062f\u064a\u201d.\n\u0633\u0646\u062c\u0631\u064a \u0641\u064a \u0627\u0644\u0627\u062a\u062c\u0627\u0647 \u0627\u0644\u062e\u0627\u0637\u0626\u060c \u0648\u0646\u0633\u0639\u0649 \u0648\u0631\u0627\u0621 \u0623\u0634\u064a\u0627\u0621 \u062a\u0628\u0639\u062f\u0646\u0627 \u0639\u0646 \u0642\u0644\u0628 \u0627\u0644\u0627\u0644\u0647.\n\u0644\u0643\u0646 \u0627\u0644\u0631\u0628 \u0643\u0631\u064a\u0645\u064c \u0644\u062f\u0631\u062c\u0629 \u0623\u0646\u0647 \u0644\u0627 \u064a\u0643\u062a\u0641\u064a \u0628\u0645\u0634\u0627\u0647\u062f\u062a\u0646\u0627 \u0648\u0646\u062d\u0646 \u0646\u0628\u062a\u0639\u062f \u0648\u0646\u0636\u0644\u0651 \u0627\u0644\u0637\u0631\u064a\u0642.\n\u0628\u062f\u0644\u0627\u064b \u0645\u0646 \u0630\u0644\u0643\u060c \u064a\u0628\u062d\u062b \u0639\u0646 \u062e\u0631\u0648\u0641\u0647 \u0627\u0644\u0636\u0627\u0644.\n\u064a\u0623\u062a\u064a \u0625\u0644\u064a\u0646\u0627 \u0648\u064a\u0642\u062f\u0645 \u0644\u0646\u0627 \u0637\u0631\u064a\u0642\u0627\u064b \u0644\u0644\u0647\u0631\u0648\u0628 \u0648\u0627\u0644\u0625\u0646\u0642\u0627\u0630.\n\u0627\u0646\u0638\u0631 \u0625\u0644\u0649 \u0631\u0633\u0627\u0644\u0629 \u062a\u064a\u0645\u0648\u062b\u0627\u0648\u0633 \u0627\u0644\u062b\u0627\u0646\u064a\u0629 2: 25\u0628-26 \u0645\u0631\u0629 \u0623\u062e\u0631\u0649:\n25\u0628 \u0645\u064f\u0624\u064e\u062f\u0650\u0651\u0628\u0627\u064b \u0628\u0650\u0627\u0644\u0652\u0648\u064e\u062f\u064e\u0627\u0639\u064e\u0629\u0650 \u0627\u0644\u0652\u0645\u064f\u0642\u064e\u0627\u0648\u0650\u0645\u0650\u064a\u0646\u064e\u060c \u0639\u064e\u0633\u064e\u0649 \u0623\u064e\u0646\u0652 \u064a\u064f\u0639\u0652\u0637\u0650\u064a\u064e\u0647\u064f\u0645\u064f \u0627\u0644\u0644\u0647\u064f \u062a\u064e\u0648\u0652\u0628\u064e\u0629\u064b \u0644\u0650\u0645\u064e\u0639\u0652\u0631\u0650\u0641\u064e\u0629\u0650 \u0627\u0644\u0652\u062d\u064e\u0642\u0650\u0651\u060c\n26  \u0641\u064e\u064a\u064e\u0633\u0652\u062a\u064e\u0641\u0650\u064a\u0642\u064f\u0648\u0627 \u0645\u0650\u0646\u0652 \u0641\u064e\u062e\u0650\u0651 \u0625\u0650\u0628\u0652\u0644\u0650\u064a\u0633\u064e \u0625\u0650\u0630\u0652 \u0642\u064e\u062f\u0650 \u0627\u0642\u0652\u062a\u064e\u0646\u064e\u0635\u064e\u0647\u064f\u0645\u0652 \u0644\u0625\u0650\u0631\u064e\u0627\u062f\u064e\u062a\u0650\u0647\u0650.\n\n\u0647\u0644 \u062a\u0639\u0644\u0645 \u0623\u0646\u0647 \u0645\u0646 \u0627\u0644\u0645\u0645\u0643\u0646 \u0623\u0646 \u062a\u0634\u0639\u0631 \u0628\u0627\u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u062a\u0627\u0645\u0629\u060c \u0628\u064a\u0646\u0645\u0627 \u0623\u0646\u062a \u0641\u064a \u0627\u0644\u0648\u0627\u0642\u0639 \u0645\u062d\u0627\u0635\u0631 \u0628\u0627\u0644\u062e\u0637\u064a\u0626\u0629 \u0648\u0627\u0644\u0634\u064a\u0637\u0627\u0646\u061f\n\u0627\u0644\u062e\u0637\u064a\u0626\u0629 \u062a\u0628\u062f\u0648 \u0648\u0643\u0623\u0646\u0647\u0627 \u062d\u0631\u064a\u0629\u060c \u0644\u0643\u0646\u0647\u0627 \u0641\u064a \u0627\u0644\u062d\u0642\u064a\u0642\u0629 \u0639\u0643\u0633 \u0630\u0644\u0643 \u062a\u0645\u0627\u0645\u0627\u064b.\n\u064a\u0628\u062f\u0648 \u0634\u0643\u0644 \u0627\u0644\u0635\u0646\u0627\u0631\u0629 \u0647\u0643\u0630\u0627.\n\u0625\u0646\u0647 \u0641\u062e \u064a\u0645\u0633\u0643 \u0628\u062d\u064a\u0648\u0627\u0646 \u0643\u0627\u0646 \u064a\u062c\u0631\u064a \u0628\u062d\u0631\u064a\u0629 \u0639\u0644\u0649 \u0637\u0648\u0644 \u0627\u0644\u0637\u0631\u064a\u0642\u060c \u062b\u0645 \u0623\u0635\u0628\u062d \u0641\u062c\u0623\u0629 \u0641\u064a \u062e\u0637\u0631.\n\u064a\u0636\u0639 \u0627\u0644\u0634\u064a\u0637\u0627\u0646 \u0627\u0644\u0623\u0643\u0627\u0630\u064a\u0628 \u0643\u0639\u0644\u0627\u0645\u0627\u062a \u0639\u0644\u0649 \u0645\u0633\u0627\u0631 \u0627\u0644\u0645\u0627\u0631\u0627\u062b\u0648\u0646\u060c \u0644\u064a\u062e\u062f\u0639\u0646\u0627 \u0648\u064a\u0648\u0642\u0639\u0646\u0627 \u0641\u064a \u0627\u0644\u0641\u062e.\n\u064a\u0631\u064a\u062f \u0627\u0644\u0634\u064a\u0637\u0627\u0646 \u0623\u0646 \u0646\u0633\u0639\u0649 \u0648\u0631\u0627\u0621 \u0627\u0644\u0645\u062a\u0639\u0629 \u0648\u0627\u0644\u0633\u0644\u0637\u0629 \u0648\u0627\u0644\u0634\u0647\u0631\u0629 \u0648\u0627\u0644\u0645\u0645\u062a\u0644\u0643\u0627\u062a \u0648\u0627\u0644\u0643\u0628\u0631\u064a\u0627\u0621.\n\u062a\u0639\u062f\u0646\u0627 \u0647\u0630\u0647 \u0627\u0644\u0623\u0635\u0646\u0627\u0645 \u0628\u0627\u0644\u062d\u0631\u064a\u0629\u060c \u0648\u0627\u0644\u062d\u0631\u064a\u0629 \u0647\u064a \u0645\u0627 \u0646\u0631\u064a\u062f\u0647 \u0628\u0634\u062f\u0629.\n\u0644\u0644\u0623\u0633\u0641\u060c \u0646\u0639\u062a\u0642\u062f \u0623\u0646 \u0645\u062b\u0644 \u0647\u0630\u0647 \u0627\u0644\u0623\u0634\u064a\u0627\u0621 \u064a\u0645\u0643\u0646 \u0623\u0646 \u062a\u0633\u0627\u0639\u062f\u0646\u0627 \u0639\u0644\u0649 \u0627\u0644\u0634\u0639\u0648\u0631 \u0628\u0627\u0644\u0631\u0636\u0627 \u0648\u0627\u0644\u0623\u0645\u0627\u0646 \u0648\u0627\u0644\u0633\u0639\u0627\u062f\u0629.\n\u0644\u0643\u0646 \u0647\u0630\u0647 \u0627\u0644\u0623\u0635\u0646\u0627\u0645 \u0647\u064a \u0641\u062e\u0627\u062e \u062a\u0628\u0639\u062f\u0646\u0627 \u0639\u0646 \u0627\u0644\u0627\u0644\u0647 \u0648\u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u062d\u064a\u0627\u0629 \u0627\u0644\u062d\u0642\u064a\u0642\u064a\u0629.\n\u064a\u0631\u064a\u062f \u0627\u0644\u0634\u064a\u0637\u0627\u0646 \u0623\u0646 \u064a\u062e\u0641\u064a \u0639\u0646\u0627 \u0637\u0631\u064a\u0642 \u0627\u0644\u062d\u064a\u0627\u0629\u060c \u0642\u0627\u0626\u0644\u0627\u064b:\n\u201d\u0627\u0633\u0644\u0643 \u0647\u0630\u0627 \u0627\u0644\u0637\u0631\u064a\u0642 \u0646\u062d\u0648 \u0627\u0644\u0646\u0635\u0631 \u0648\u0627\u0644\u0633\u0639\u0627\u062f\u0629!\u201d\n\u0646\u0639\u0645\u060c \u0647\u0630\u0627 \u0647\u0648 \u0627\u0644\u0637\u0631\u064a\u0642! \u0627\u062a\u0628\u0639\u0646\u064a!\n\n\u0625\u0630\u0646\u060c \u0643\u064a\u0641 \u064a\u0645\u0643\u0646 \u0644\u062d\u064a\u0648\u0627\u0646 \u0623\u0646 \u064a\u0646\u062c\u0648 \u0645\u0646 \u0641\u062e \u0643\u0647\u0630\u0627\u061f\n\u0647\u0644 \u064a\u0633\u062a\u0637\u064a\u0639 \u0641\u0639\u0644 \u0630\u0644\u0643 \u0628\u0645\u0641\u0631\u062f\u0647\u061f\n\u0644\u0627\u060c \u0627\u0644\u0623\u0631\u0646\u0628 \u0639\u0627\u062c\u0632.\n\u0625\u0646\u0647 \u0628\u062d\u0627\u062c\u0629 \u0625\u0644\u0649 \u0634\u062e\u0635 \u0623\u0643\u062b\u0631 \u0630\u0643\u0627\u0621\u064b \u0648\u0642\u0648\u0629 \u0644\u064a\u0623\u062a\u064a \u0648\u064a\u062e\u0631\u062c\u0647 \u0645\u0646 \u0627\u0644\u0641\u062e.\n\u0646\u062d\u0646 \u0628\u062d\u0627\u062c\u0629 \u0625\u0644\u0649 \u0634\u062e\u0635 \u0623\u0643\u062b\u0631 \u0630\u0643\u0627\u0621\u064b \u0648\u0642\u0648\u0629 \u0644\u0625\u0646\u0642\u0627\u0630\u0646\u0627 \u0623\u064a\u0636\u0627\u064b.\n\u0647\u0630\u0647 \u0647\u064a \u0627\u0644\u0646\u0642\u0637\u0629 \u0627\u0644\u0623\u0647\u0645 \u0627\u0644\u062a\u064a \u0623\u0631\u064a\u062f\u0643 \u0623\u0646 \u062a\u0644\u0627\u062d\u0638\u0647\u0627 \u0628\u062e\u0635\u0648\u0635 \u0647\u0630\u0647 \u0627\u0644\u0622\u064a\u0629.\n\u0646\u062d\u0646 \u0628\u062d\u0627\u062c\u0629 \u0625\u0644\u0649 \u0645\u0646\u0642\u0630 \u0644\u0623\u0646\u0646\u0627 \u0644\u0627 \u0646\u0633\u062a\u0637\u064a\u0639 \u0625\u0646\u0642\u0627\u0630 \u0623\u0646\u0641\u0633\u0646\u0627 \u0623\u0648 \u062d\u062a\u0649 \u0627\u0644\u0644\u062c\u0648\u0621 \u0625\u0644\u0649 \u0627\u0644\u0631\u0628 \u0627\u0644\u0627\u0644\u0647.\n\u0627\u0644\u0642\u0644\u0648\u0628 \u0627\u0644\u0645\u064a\u062a\u0629 \u0631\u0648\u062d\u064a\u0627\u064b \u0644\u0627 \u062a\u0633\u062a\u0637\u064a\u0639 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062d\u064a\u0627\u0629.\n\u0627\u0646\u0638\u0631 \u0625\u0644\u0649 \u0645\u0627 \u062a\u0642\u0648\u0644\u0647 \u0627\u0644\u0622\u064a\u0629 25:\n\u201d\u0644\u0639\u0644 \u0627\u0644\u0644\u0647 \u064a\u0631\u0632\u0642\u0647\u0645 \u0627\u0644\u062a\u0648\u0628\u0629\u201d.\n\n\u0627\u0644\u0645\u0646\u062d\u0629 \u0647\u064a \u0647\u0628\u0629 \u0645\u062c\u0627\u0646\u064a\u0629.\n\u0644\u0642\u062f \u0645\u0646\u062d\u0646\u064a \u0627\u0644\u0644\u0647 \u0646\u0639\u0645\u0629 \u0627\u0644\u062a\u0648\u0628\u0629 \u0642\u0628\u0644 30 \u0639\u0627\u0645\u0627\u064b.\n\u0642\u0644\u062a \u0644\u0645\u062f\u0629 \u0639\u0634\u0631 \u0633\u0646\u0648\u0627\u062a \u0625\u0646\u0647 \u0644\u0627 \u064a\u0648\u062c\u062f \u0625\u0644\u0647 \u0641\u064a \u0627\u0644\u0643\u0648\u0646.\n\u0644\u0643\u0646 \u0644\u0623\u0646 \u0627\u0644\u0644\u0647 \u0643\u0631\u064a\u0645\u060c \u0641\u0642\u062f \u0623\u0631\u0627\u0646\u064a \u0623\u0646 \u0627\u0644\u0628\u064a\u0631\u0629 \u0648\u0627\u0644\u0646\u0633\u0627\u0621 \u0648\u0627\u0644\u0646\u062c\u0627\u062d \u0627\u0644\u062f\u0646\u064a\u0648\u064a \u0644\u0627 \u064a\u0645\u0643\u0646 \u0623\u0646 \u062a\u0634\u0628\u0639 \u0631\u063a\u0628\u0627\u062a \u0642\u0644\u0628\u064a.\n\u0647\u0630\u0627 \u0647\u0648 \u0645\u0639\u0646\u0649 \u0639\u0628\u0627\u0631\u0629 \u201d\u064a\u0639\u0648\u062f\u0648\u0646 \u0625\u0644\u0649 \u0631\u0634\u062f\u0647\u0645\u201d \u0641\u064a \u0627\u0644\u0622\u064a\u0629 26.\n\u0639\u0646\u062f\u0645\u0627 \u064a\u062e\u062a\u0644\u0637 \u0639\u0644\u064a\u0643 \u0625\u062d\u0633\u0627\u0633\u0643 \u0628\u0627\u0644\u0627\u062a\u062c\u0627\u0647\u060c \u0641\u0625\u0646\u0643 \u062a\u0631\u0643\u0636 \u0641\u064a \u0627\u0644\u0627\u062a\u062c\u0627\u0647 \u0627\u0644\u062e\u0627\u0637\u0626.\n\u0627\u0644\u062e\u0637\u0648\u0629 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0625\u064a\u062c\u0627\u062f \u0637\u0631\u064a\u0642\u0643 \u0625\u0644\u0649 \u0627\u0644\u0645\u0646\u0632\u0644 \u0647\u064a \u0623\u0646 \u062a\u062f\u0631\u0643 \u0623\u0646\u0643 \u062a\u0627\u0626\u0647.\n\u0643\u0627\u0646 \u062f\u0627\u0646 \u0645\u0627\u0643\u062f\u0648\u064a\u0644 \u0623\u062d\u062f \u0627\u0644\u0639\u062f\u0627\u0626\u064a\u0646 \u0627\u0644\u0645\u0641\u0642\u0648\u062f\u064a\u0646 \u0641\u064a \u0645\u0627\u0631\u0627\u062b\u0648\u0646 \u0628\u0648\u0631\u062a\u0644\u0627\u0646\u062f.\n\u0642\u0627\u0644: \u201d\u0627\u0633\u062a\u062f\u0631\u062a \u0645\u0646 \u0627\u0644\u0632\u0627\u0648\u064a\u0629 \u0648\u0631\u0623\u064a\u062a \u0639\u0634\u0631\u0629 \u0623\u0634\u062e\u0627\u0635 \u0648\u0627\u0642\u0641\u064a\u0646 \u0628\u0644\u0627 \u062d\u0631\u0627\u0643...\n\u0643\u0627\u0646\u0648\u0627 \u064a\u0646\u0638\u0631\u0648\u0646 \u0625\u0644\u0649 \u0628\u0639\u0636\u0647\u0645 \u0627\u0644\u0628\u0639\u0636 \u0648\u064a\u0641\u0643\u0631\u0648\u0646: \u201d\u0623\u0648\u0647\u060c \u0647\u0630\u0627 \u0644\u0627 \u064a\u0628\u062f\u0648 \u0635\u062d\u064a\u062d\u0627\u064b\u201d.\n\n\u0648\u0642\u0627\u0644 \u0639\u062f\u0627\u0621 \u0622\u062e\u0631\u060c \u0632\u0627\u0643 \u0643\u0627\u0633\u062a\u0631\u060c \u0625\u0646\u0647 \u062f\u062e\u0644 \u0646\u0641\u0642\u0627\u064b \u062d\u064a\u062b \u0645\u0631\u062a \u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a \u0628\u062c\u0627\u0646\u0628\u0647 \u0628\u0633\u0631\u0639\u0629 55 \u0645\u064a\u0644\u0627\u064b \u0641\u064a \u0627\u0644\u0633\u0627\u0639\u0629.\n\u0639\u0646\u062f\u0647\u0627 \u0623\u062f\u0631\u0643 \u0623\u0646\u0647 \u0642\u062f \u0627\u0646\u062d\u0631\u0641 \u0639\u0646 \u0627\u0644\u0645\u0633\u0627\u0631.\n\u0642\u0628\u0644 \u0623\u0646 \u064a\u0639\u064a\u062f\u0646\u064a \u0627\u0644\u0631\u0628 \u0625\u0644\u0649 \u0635\u0648\u0627\u0628\u064a\u060c \u0643\u0646\u062a \u0623\u0638\u0646 \u0623\u0646\u0646\u064a \u0623\u0645\u0644\u0643 \u201d\u0645\u0639\u0631\u0641\u0629 \u0627\u0644\u062d\u0642\u064a\u0642\u0629\u201d.\n\u0623\u062e\u0628\u0631\u0646\u064a \u0643\u0628\u0631\u064a\u0627\u0626\u064a \u0623\u0646\u0646\u064a \u0639\u0644\u0649 \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u0635\u062d\u064a\u062d\u060c \u0648\u0623\u0646\u0646\u064a \u0644\u0633\u062a \u0628\u062d\u0627\u062c\u0629 \u0625\u0644\u0649 \u0623\u064a \u0625\u0644\u0647 \u0644\u064a\u0631\u0634\u062f\u0646\u064a \u0644\u0623\u0646\u0646\u064a \u0643\u0646\u062a \u0630\u0643\u064a\u0627\u064b \u062c\u062f\u0627\u064b.\n\u0648\u0627\u0644\u0645\u0641\u0627\u0631\u0642\u0629 \u0623\u0646\u0646\u064a \u0643\u0646\u062a \u063a\u0628\u064a\u0627\u064b \u062c\u062f\u0627\u064b \u0644\u062f\u0631\u062c\u0629 \u0623\u0646\u0646\u064a \u0644\u0645 \u0623\u0644\u0627\u062d\u0638 \u062e\u062f\u0627\u0639 \u0627\u0644\u0634\u064a\u0637\u0627\u0646.\n\u0644\u0642\u062f \u0648\u0642\u0639\u062a \u0641\u064a \u0641\u062e \u0623\u0643\u0627\u0630\u064a\u0628\u0647.\n\u0635\u062f\u0642\u062a \u0648\u0639\u062f \u0627\u0644\u0634\u064a\u0637\u0627\u0646 \u0628\u0623\u0646\u0646\u064a \u0633\u0623\u062c\u062f \u0627\u0644\u0633\u0639\u0627\u062f\u0629 \u0628\u0627\u0644\u0647\u0631\u0648\u0628 \u0645\u0646 \u0627\u0644\u0627\u0644\u0647.\n\u0644\u0643\u0646 \u0628\u0639\u062f \u0630\u0644\u0643\u060c \u0645\u0646\u062d\u0646\u064a \u0627\u0644\u0631 \u0646\u0639\u0645\u0629 \u0627\u0644\u062a\u0648\u0628\u0629.\n\u0627\u0644\u0643\u0644\u0645\u0629 \u0627\u0644\u064a\u0648\u0646\u0627\u0646\u064a\u0629 \u0647\u0646\u0627 \u0644\u0644\u062a\u0648\u0628\u0629 \u0647\u064a metanoia.\n\u0648\u064a\u0639\u0646\u064a \u0630\u0644\u0643 \u201d\u062a\u063a\u064a\u064a\u0631 \u0641\u064a \u0627\u0644\u0631\u0623\u064a\u060c \u0648\u062a\u063a\u064a\u064a\u0631 \u0641\u064a \u0627\u0644\u062d\u064a\u0627\u0629\u060c \u0648\u062a\u063a\u064a\u064a\u0631 \u0641\u064a \u0627\u0644\u0647\u062f\u0641\u201d.\n\u0644\u0642\u062f \u0645\u0646\u062d\u0646\u064a \u064a\u0633\u0648\u0639 \u0642\u0644\u0628\u0627\u064b \u062c\u062f\u064a\u062f\u0627\u064b \u062d\u062a\u0649 \u0623\u062a\u0645\u0643\u0646 \u0645\u0646 \u201d\u062f\u0639\u0648\u0629 \u0627\u0644\u0631\u0628 \u0645\u0646 \u0642\u0644\u0628 \u0637\u0627\u0647\u0631\u201d \u0643\u0645\u0627 \u062a\u0642\u0648\u0644 \u0627\u0644\u0622\u064a\u0629 22.\n\u0627\u0644\u0642\u0644\u0628 \u0627\u0644\u0646\u0642\u064a \u0647\u0648 \u0627\u0644\u0642\u0644\u0628 \u0627\u0644\u0635\u0627\u062f\u0642.\n\u0642\u0644\u0628 \u064a\u0646\u0627\u062f\u064a \u0627\u0644\u0631\u0628 \u0642\u0627\u0626\u0644\u0627\u064b: \u201d\u0623\u0646\u0627 \u0622\u0633\u0641 \u0639\u0644\u0649 \u0630\u0646\u0628\u064a\u060c \u0623\u0631\u062c\u0648\u0643 \u0627\u063a\u0641\u0631 \u0644\u064a\u201d.\n\u0633\u0627\u0639\u062f\u0646\u064a \u0639\u0644\u0649 \u0627\u0644\u0631\u0643\u0636 \u0646\u062d\u0648\u0643\u060c \u0644\u0627 \u0644\u0644\u0627\u0628\u062a\u0639\u0627\u062f \u0639\u0646\u0643.\n\u0643\u062a\u0628 \u0628\u0648\u0644\u0633 \u0641\u064a \u0631\u0633\u0627\u0644\u0629 \u0631\u0648\u0645\u064a\u0629 \u0661\u0660: \u0669-\u0661\u0661 \u0634\u0631\u062d\u0627\u064b \u0648\u0627\u0636\u062d\u0627\u064b \u062c\u062f\u0627\u064b \u0644\u0643\u064a\u0641\u064a\u0629 \u0627\u0644\u062a\u0648\u062c\u0647 \u0625\u0644\u0649 \u0627\u0644\u0644\u0647 \u0648\u0627\u0644\u062e\u0644\u0627\u0635\n9 \u00ab\u0625\u0630\u0627 \u0627\u0639\u062a\u0631\u0641\u062a \u0628\u0641\u0645\u0643 \u0623\u0646 \u064a\u0633\u0648\u0639 \u0647\u0648 \u0627\u0644\u0631\u0628\u060c \u0648\u0622\u0645\u0646\u062a \u0641\u064a \u0642\u0644\u0628\u0643 \u0623\u0646 \u0627\u0644\u0644\u0647 \u0623\u0642\u0627\u0645\u0647 \u0645\u0646 \u0627\u0644\u0623\u0645\u0648\u0627\u062a\u060c \u0641\u0633\u062a\u062e\u0644\u0635\u00bb.\n10 \u0644\u0623\u0646 \u0627\u0644\u0642\u0644\u0628 \u0647\u0648 \u0627\u0644\u0630\u064a \u064a\u0624\u0645\u0646 \u0628\u0647 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 \u0641\u064a\u0628\u0631\u0631\u060c \u0648\u0627\u0644\u0641\u0645 \u0647\u0648 \u0627\u0644\u0630\u064a \u064a\u0639\u062a\u0631\u0641 \u0628\u0647 \u0641\u064a\u062e\u0644\u0635.\n11 \u0643\u0645\u0627 \u064a\u0642\u0648\u0644 \u0627\u0644\u0643\u062a\u0627\u0628 \u0627\u0644\u0645\u0642\u062f\u0633: \u201d\u0643\u0644 \u0645\u0646 \u064a\u0624\u0645\u0646 \u0628\u0647 \u0644\u0646 \u064a\u062e\u0632\u0649 \u0623\u0628\u062f\u0627\u064b\u201d.\n\n\u0647\u0644 \u0627\u0639\u062a\u0631\u0641\u062a \u0628\u0627\u0644\u0625\u064a\u0645\u0627\u0646 \u0628\u0641\u0645\u0643 \u062d\u062a\u0649 \u062a\u0646\u0627\u0644 \u0627\u0644\u062e\u0644\u0627\u0635\u061f\n\u0625\u0630\u0627 \u0644\u0645 \u062a\u0641\u0639\u0644 \u0630\u0644\u0643 \u0628\u0639\u062f\u060c \u0623\u0644\u0627 \u062a\u0639\u062a\u0642\u062f \u0623\u0646 \u0627\u0644\u064a\u0648\u0645 \u0633\u064a\u0643\u0648\u0646 \u064a\u0648\u0645\u0627\u064b \u0631\u0627\u0626\u0639\u0627\u064b \u0644\u0644\u0642\u064a\u0627\u0645 \u0628\u0630\u0644\u0643\u061f\n\u0625\u0646 \u0627\u0644\u0631\u0648\u062d \u0627\u0644\u0642\u062f\u0633 \u0645\u0648\u062c\u0648\u062f \u0628\u064a\u0646\u0646\u0627\u060c \u0648\u0631\u0628\u0645\u0627 \u064a\u0647\u0645\u0633 \u0641\u064a \u0642\u0644\u0628\u0643:\n\u201d\u0627\u0628\u062a\u0639\u062f\u0648\u0627 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u062e\u0637\u064a\u0626\u0629 \u0648\u0627\u0644\u0645\u0648\u062a!\u201d\n\u0627\u062e\u062a\u0631 \u062d\u064a\u0627\u0629 \u062c\u062f\u064a\u062f\u0629 \u0648\u0627\u062a\u062c\u0627\u0647\u0627\u064b \u062c\u062f\u064a\u062f\u0627\u064b\u060c \u0628\u0625\u0639\u0644\u0627\u0646\u0643 \u0623\u0646 \u201d\u064a\u0633\u0648\u0639 \u0647\u0648 \u0627\u0644\u0631\u0628!\u201d\n\n\u0643\u062a\u0628 \u0627\u0644\u0631\u0633\u0648\u0644 \u0628\u0648\u0644\u0633 \u0645\u0646 \u0642\u0628\u0644 \u0639\u0646 \u0647\u0630\u0627 \u0627\u0644\u062a\u0648\u062c\u0647 \u0627\u0644\u062c\u062f\u064a\u062f.\n\u0643\u0627\u0646 \u0630\u0644\u0643 \u0641\u064a \u0631\u0633\u0627\u0644\u0629 \u0625\u0644\u0649 \u0646\u0641\u0633 \u0627\u0644\u0643\u0646\u064a\u0633\u0629 \u0641\u064a \u0623\u0641\u0633\u0633\u060c \u062d\u064a\u062b \u064a\u0639\u0645\u0644 \u062a\u064a\u0645\u0648\u062b\u0627\u0648\u0633 \u0627\u0644\u0622\u0646 \u0643\u0642\u0633.\n\u0627\u0633\u062a\u0645\u0639\u0648\u0627 \u0625\u0644\u0649 \u0645\u0627 \u0643\u062a\u0628\u0647 \u0628\u0648\u0644\u0633 \u0644\u0644\u0645\u0624\u0645\u0646\u064a\u0646 \u0627\u0644\u0645\u0633\u064a\u062d\u064a\u064a\u0646 \u0641\u064a \u0623\u0641\u0633\u0633 2: 1-5\u060c \u062d\u0648\u0644 \u0645\u0627 \u0641\u0639\u0644\u0647 \u0627\u0644\u0631\u0628 \u0644\u064a\u0645\u0646\u062d\u0647\u0645 \u062d\u064a\u0627\u0629 \u062c\u062f\u064a\u062f\u0629 \u0648\u062a\u0648\u062c\u0647\u0627\u064b \u062c\u062f\u064a\u062f\u0627\u064b: \n1 \u0648\u064e\u0623\u064e\u0646\u0652\u062a\u064f\u0645\u0652 \u0625\u0650\u0630\u0652 \u0643\u064f\u0646\u0652\u062a\u064f\u0645\u0652 \u0623\u064e\u0645\u0652\u0648\u064e\u0627\u062a\u0627\u064b \u0628\u0650\u0627\u0644\u0630\u064f\u0651\u0646\u064f\u0648\u0628\u0650 \u0648\u064e\u0627\u0644\u0652\u062e\u064e\u0637\u064e\u0627\u064a\u064e\u0627\u060c\n2  \u0627\u0644\u064e\u0651\u062a\u0650\u064a \u0633\u064e\u0644\u064e\u0643\u0652\u062a\u064f\u0645\u0652 \u0641\u0650\u064a\u0647\u064e\u0627 \u0642\u064e\u0628\u0652\u0644\u0627\u064b \u062d\u064e\u0633\u064e\u0628\u064e \u062f\u064e\u0647\u0652\u0631\u0650 \u0647\u064e\u0630\u064e\u0627 \u0627\u0644\u0652\u0639\u064e\u0627\u0644\u064e\u0645\u0650\u060c \u062d\u064e\u0633\u064e\u0628\u064e \u0631\u064e\u0626\u0650\u064a\u0633\u0650 \u0633\u064f\u0644\u0652\u0637\u064e\u0627\u0646\u0650 \u0627\u0644\u0652\u0647\u064e\u0648\u064e\u0627\u0621\u0650\u060c \u0627\u0644\u0631\u064f\u0651\u0648\u062d\u0650 \u0627\u0644\u064e\u0651\u0630\u0650\u064a \u064a\u064e\u0639\u0652\u0645\u064e\u0644\u064f \u0627\u0644\u0622\u0646\u064e \u0641\u0650\u064a \u0623\u064e\u0628\u0652\u0646\u064e\u0627\u0621\u0650 \u0627\u0644\u0652\u0645\u064e\u0639\u0652\u0635\u0650\u064a\u064e\u0629\u0650\u060c\n3  \u0627\u0644\u064e\u0651\u0630\u0650\u064a\u0646\u064e \u0646\u064e\u062d\u0652\u0646\u064f \u0623\u064e\u064a\u0652\u0636\u0627\u064b \u062c\u064e\u0645\u0650\u064a\u0639\u0627\u064b \u062a\u064e\u0635\u064e\u0631\u064e\u0651\u0641\u0652\u0646\u064e\u0627 \u0642\u064e\u0628\u0652\u0644\u0627\u064b \u0628\u064e\u064a\u0652\u0646\u064e\u0647\u064f\u0645\u0652 \u0641\u0650\u064a \u0634\u064e\u0647\u064e\u0648\u064e\u0627\u062a\u0650 \u062c\u064e\u0633\u064e\u062f\u0650\u0646\u064e\u0627\u060c \u0639\u064e\u0627\u0645\u0650\u0644\u0650\u064a\u0646\u064e \u0645\u064e\u0634\u0650\u064a\u0626\u064e\u0627\u062a\u0650 \u0627\u0644\u0652\u062c\u064e\u0633\u064e\u062f\u0650 \u0648\u064e\u0627\u0644\u0623\u064e\u0641\u0652\u0643\u064e\u0627\u0631\u0650\u060c \u0648\u064e\u0643\u064f\u0646\u064e\u0651\u0627 \u0628\u0650\u0627\u0644\u0637\u064e\u0651\u0628\u0650\u064a\u0639\u064e\u0629\u0650 \u0623\u064e\u0628\u0652\u0646\u064e\u0627\u0621\u064e \u0627\u0644\u0652\u063a\u064e\u0636\u064e\u0628\u0650 \u0643\u064e\u0627\u0644\u0652\u0628\u064e\u0627\u0642\u0650\u064a\u0646\u064e \u0623\u064e\u064a\u0652\u0636\u0627\u064b\u060c\n4  \u0627\u064e\u0644\u0644\u0647\u064f \u0627\u0644\u064e\u0651\u0630\u0650\u064a \u0647\u064f\u0648\u064e \u063a\u064e\u0646\u0650\u064a\u064c\u0651 \u0641\u0650\u064a \u0627\u0644\u0631\u064e\u0651\u062d\u0652\u0645\u064e\u0629\u0650\u060c \u0645\u0650\u0646\u0652 \u0623\u064e\u062c\u0652\u0644\u0650 \u0645\u064e\u062d\u064e\u0628\u064e\u0651\u062a\u0650\u0647\u0650 \u0627\u0644\u0652\u0643\u064e\u062b\u0650\u064a\u0631\u064e\u0629\u0650 \u0627\u0644\u064e\u0651\u062a\u0650\u064a \u0623\u064e\u062d\u064e\u0628\u064e\u0651\u0646\u064e\u0627 \u0628\u0650\u0647\u064e\u0627\u060c\n5  \u0648\u064e\u0646\u064e\u062d\u0652\u0646\u064f \u0623\u064e\u0645\u0652\u0648\u064e\u0627\u062a\u064c \u0628\u0650\u0627\u0644\u0652\u062e\u064e\u0637\u064e\u0627\u064a\u064e\u0627 \u0623\u064e\u062d\u0652\u064a\u064e\u0627\u0646\u064e\u0627 \u0645\u064e\u0639\u064e \u0627\u0644\u0652\u0645\u064e\u0633\u0650\u064a\u062d\u0650 - \u0628\u0650\u0627\u0644\u0646\u0650\u0651\u0639\u0652\u0645\u064e\u0629\u0650 \u0623\u064e\u0646\u0652\u062a\u064f\u0645\u0652 \u0645\u064f\u062e\u064e\u0644\u064e\u0651\u0635\u064f\u0648\u0646\u064e -\n\n\u201d\u0644\u0643\u0646 \u0627\u0644\u0631\u0628\" \u0647\u0645\u0627 \u0643\u0644\u0645\u062a\u0627\u0646 \u0645\u0646 \u0623\u062c\u0645\u0644 \u0627\u0644\u0643\u0644\u0645\u0627\u062a \u0627\u0644\u062a\u064a \u0642\u064a\u0644\u062a \u0639\u0644\u0649 \u0627\u0644\u0625\u0637\u0644\u0627\u0642.\n\u064a\u0630\u0643\u0651\u0631 \u0628\u0648\u0644\u0633 \u0627\u0644\u0645\u0624\u0645\u0646\u064a\u0646 \u0641\u064a \u0623\u0641\u0633\u0633 \u0628\u0623\u0646\u0647\u0645 \u0643\u0627\u0646\u0648\u0627 \u0641\u064a \u064a\u0648\u0645 \u0645\u0646 \u0627\u0644\u0623\u064a\u0627\u0645 \u0645\u062d\u0627\u0635\u0631\u064a\u0646 \u0648\u0639\u0627\u062c\u0632\u064a\u0646 \u0645\u062b\u0644 \u0630\u0644\u0643 \u0627\u0644\u0623\u0631\u0646\u0628 \u0641\u064a \u0627\u0644\u0641\u062e.\n\u0644\u0643\u0646 \u0627\u0644\u0631\u0628 \u062a\u062f\u062e\u0644 \u0644\u064a\u0646\u0642\u0630\u0647\u0645 \u0628\u0646\u0639\u0645\u062a\u0647 \u0648\u062d\u062f\u0647\u0627\u060c \u0648\u0645\u0646 \u062e\u0644\u0627\u0644 \u0627\u0644\u0625\u064a\u0645\u0627\u0646 \u0648\u062d\u062f\u0647\u060c \u0648\u0628\u0627\u0644\u0645\u0633\u064a\u062d \u0648\u062d\u062f\u0647.\n\u064a\u0645\u0643\u0646 \u0644\u0623\u064a \u0634\u062e\u0635 \u0623\u0646 \u064a\u062e\u0644\u0635\u060c \u0625\u0630\u0627 \u0622\u0645\u0646 \u0628\u0623\u0646 \u062a\u0636\u062d\u064a\u0629 \u0627\u0644\u0645\u0633\u064a\u062d \u0639\u0644\u0649 \u0627\u0644\u0635\u0644\u064a\u0628 \u0643\u0627\u0646\u062a \u0645\u0646 \u0623\u062c\u0644\u0643\u060c \u0644\u062a\u0637\u0647\u0631\u0643 \u0645\u0646 \u0627\u0644\u062e\u0637\u064a\u0626\u0629 \u0648\u0627\u0644\u0639\u0627\u0631.\n\u0639\u0646\u062f\u0645\u0627 \u062a\u0624\u0645\u0646 \u0628\u0630\u0644\u0643\u060c \u062a\u0646\u0627\u0644 \u062d\u064a\u0627\u0629 \u062c\u062f\u064a\u062f\u0629 \u0648\u064a\u0636\u0639\u0643 \u064a\u0633\u0648\u0639 \u0639\u0644\u0649 \u0637\u0631\u064a\u0642 \u062c\u062f\u064a\u062f.\n\u0648\u0628\u0639\u062f \u0628\u0636\u0639\u0629 \u0622\u064a\u0627\u062a \u0641\u064a \u0623\u0641\u0633\u0633 2:10 \u064a\u062a\u062d\u062f\u062b \u0628\u0648\u0644\u0633 \u0639\u0646 \u0647\u0630\u0627 \u0627\u0644\u062a\u0648\u062c\u0647 \u0627\u0644\u062c\u062f\u064a\u062f.\n\u0627\u0642\u0631\u0623 \u0647\u0630\u0647 \u0627\u0644\u0627\u064a\u0629 \u0645\u0639\u064a:\n\u0627\u0644\u062c\u0645\u064a\u0639: 10 \u201d\u0644\u0623\u064e\u0646\u064e\u0651\u0643\u064f\u0645\u0652 \u0628\u0650\u0627\u0644\u0646\u0650\u0651\u0639\u0652\u0645\u064e\u0629\u0650 \u0645\u064f\u062e\u064e\u0644\u064e\u0651\u0635\u064f\u0648\u0646\u064e\u060c \u0628\u0650\u0627\u0644\u0625\u0650\u064a\u0645\u064e\u0627\u0646\u0650\u060c \u0648\u064e\u0630\u064e\u0644\u0650\u0643\u064e \u0644\u064e\u064a\u0652\u0633\u064e \u0645\u0650\u0646\u0652\u0643\u064f\u0645\u0652. \u0647\u064f\u0648\u064e \u0639\u064e\u0637\u0650\u064a\u064e\u0651\u0629\u064f \u0627\u0644\u0631\u0628\u201d.\n\n\u0648\u0644\u0625\u0646\u0647\u0627\u0621 \u0647\u0630\u0647 \u0627\u0644\u0631\u0633\u0627\u0644\u0629\u060c \u062f\u0639\u0648\u0646\u0627 \u0646\u0646\u0638\u0631 \u0625\u0644\u0649 \u0645\u0627 \u064a\u0639\u0646\u064a\u0647 \u0627\u0644\u0633\u064a\u0631 \u0641\u064a \u0627\u0644\u0623\u0639\u0645\u0627\u0644 \u0627\u0644\u0635\u0627\u0644\u062d\u0629.\n\u062a\u0630\u0643\u0631 \u0623\u0646 \u0628\u0648\u0644\u0633 \u064a\u0643\u062a\u0628 \u0625\u0644\u0649 \u062a\u064a\u0645\u0648\u062b\u0627\u0648\u0633 \u0644\u064a\u0642\u062f\u0645 \u0644\u0647 \u0625\u0631\u0634\u0627\u062f\u0627\u062a \u062d\u0648\u0644 \u0645\u0646 \u064a\u062e\u062a\u0627\u0631\u0647 \u0648\u064a\u062f\u0631\u0628\u0647 \u0643\u0645\u0639\u0644\u0645\u064a\u0646 \u0644\u0644\u0643\u062a\u0627\u0628 \u0627\u0644\u0645\u0642\u062f\u0633.\n\u0648\u0645\u0647\u0645\u062a\u0646\u0627 \u0643\u0645\u0624\u0645\u0646\u064a\u0646 \u0647\u064a \u0645\u0634\u0627\u0631\u0643\u0629 \u0628\u0634\u0627\u0631\u0629 \u0627\u0644\u0625\u0646\u062c\u064a\u0644 \u0645\u0639 \u0627\u0644\u0646\u0627\u0633 \u0627\u0644\u0642\u0631\u064a\u0628\u064a\u0646 \u0648\u0627\u0644\u0628\u0639\u064a\u062f\u064a\u0646.\n\u0644\u0643\u0646 \u0644\u0643\u064a \u0646\u0641\u0639\u0644 \u0630\u0644\u0643 \u0628\u0623\u0645\u0627\u0646\u0629\u060c \u064a\u062c\u0628 \u0623\u0646 \u0646\u062a\u062d\u0644\u0649 \u0628\u0627\u0644\u0635\u0641\u0627\u062a \u0627\u0644\u062a\u064a \u064a\u0635\u0641\u0647\u0627 \u0628\u0648\u0644\u0633 \u0641\u064a \u0647\u0630\u0647 \u0627\u0644\u0622\u064a\u0627\u062a.\n\u0644\u0627 \u0646\u0633\u062a\u0637\u064a\u0639 \u062a\u063a\u064a\u064a\u0631 \u0642\u0644\u0628 \u0623\u064a \u0634\u062e\u0635.\n\u0644\u0643\u0646 \u0628\u0625\u0645\u0643\u0627\u0646\u0646\u0627 \u0623\u0646 \u0646\u062e\u0628\u0631\u0647\u0645 \u0628\u0627\u0644\u062d\u0642\u064a\u0642\u0629 \u0628\u0644\u0637\u0641 \u0648\u0644\u0637\u0641 \u0648\u0635\u0628\u0631.\n\u0648\u064a\u0645\u0643\u0646\u0646\u0627 \u0623\u0646 \u0646\u062b\u0642 \u0628\u0623\u0646 \u0627\u0644\u0631\u0628 \u0633\u064a\u0645\u0646\u062d \u0627\u0644\u062a\u0648\u0628\u0629 \u0644\u0623\u0628\u0646\u0627\u0626\u0647 \u0627\u0644\u0645\u062e\u062a\u0627\u0631\u064a\u0646 \u0641\u064a \u0627\u0644\u0648\u0642\u062a \u0627\u0644\u0645\u0646\u0627\u0633\u0628.\n\u0641\u064a \u0627\u0644\u0622\u064a\u062a\u064a\u0646 24 \u0648 25 \u0645\u0646 \u0646\u0635 \u0627\u0644\u064a\u0648\u0645\u060c \u0623\u0631\u0649 \u062e\u0645\u0633 \u0635\u0641\u0627\u062a \u064a\u0631\u064a\u062f \u0627\u0644\u0631\u0628 \u0623\u0646 \u064a\u0646\u0645\u064a\u0647\u0627 \u0641\u064a \u0639\u0628\u0627\u062f\u0647:\n\n\u0627\u0644\u0635\u0641\u0629 \u0627\u0644\u0623\u0648\u0644\u0649: \u063a\u064a\u0631 \u0645\u0634\u0627\u0643\u0644.\n\u0628\u0639\u0636 \u0627\u0644\u0646\u0627\u0633 \u064a\u062d\u0628\u0648\u0646 \u0627\u0644\u062c\u062f\u0627\u0644.\n\u0644\u0627 \u062d\u0631\u062c \u0641\u064a \u0627\u0644\u0646\u0642\u0627\u0634 \u0627\u0644\u0628\u0646\u0651\u0627\u0621.\n\u0644\u0643\u0646 \u0643\u064a\u0641 \u062a\u0639\u0631\u0641 \u0645\u062a\u0649 \u062a\u0643\u0648\u0646 \u201d\u0645\u0634\u0627\u0643\u0633\u064b\u0627\u201d \u0628\u0634\u0643\u0644 \u062e\u0627\u0637\u0626\u061f\n\u0631\u0628\u0645\u0627 \u064a\u0645\u0643\u0646\u0643 \u0623\u0646 \u062a\u0633\u0623\u0644 \u0646\u0641\u0633\u0643 \u0647\u0630\u0627 \u0627\u0644\u0633\u0624\u0627\u0644:\n\u201d\u0639\u0646\u062f\u0645\u0627 \u0623\u062a\u062c\u0627\u062f\u0644 \u0645\u0639 \u0634\u062e\u0635 \u0645\u0627\u060c \u0647\u0644 \u0623\u0647\u062a\u0645 \u0623\u0643\u062b\u0631 \u0628\u0630\u0644\u0643 \u0627\u0644\u0634\u062e\u0635\u060c \u0623\u0645 \u0628\u0627\u0644\u0641\u0648\u0632 \u0641\u064a \u0627\u0644\u062c\u062f\u0627\u0644\u061f\u201d\n\u0647\u0644 \u064a\u062f\u0641\u0639\u0646\u064a \u0643\u0628\u0631\u064a\u0627\u0626\u064a \u0625\u0644\u0649 \u0627\u0644\u062a\u0631\u0643\u064a\u0632 \u0639\u0644\u0649 \u0623\u0646 \u0623\u0643\u0648\u0646 \u0639\u0644\u0649 \u0635\u0648\u0627\u0628\u060c \u0628\u062f\u0644\u0627\u064b \u0645\u0646 \u0623\u0646 \u0623\u0643\u0648\u0646 \u0644\u0637\u064a\u0641\u0627\u064b\u061f\n\n\u0627\u0644\u0635\u0641\u0629 \u0627\u0644\u062b\u0627\u0646\u064a\u0629: \u0627\u0644\u0644\u0637\u0641 \u0645\u0639 \u0627\u0644\u062c\u0645\u064a\u0639.\n\u064a\u062c\u0628 \u0639\u0644\u0649 \u062e\u0627\u062f\u0645 \u0627\u0644\u0631\u0628 \u0623\u0646 \u064a\u0643\u0648\u0646 \u0644\u0637\u064a\u0641\u0627\u064b \u0645\u0639 \u0627\u0644\u062c\u0645\u064a\u0639.\n\u062d\u062a\u0649 \u0644\u0644\u0623\u0634\u062e\u0627\u0635 \u0627\u0644\u0630\u064a\u0646 \u064a\u0643\u0631\u0647\u0648\u0646\u0643 \u0648\u064a\u0631\u064a\u062f\u0648\u0646 \u0625\u064a\u0630\u0627\u0621\u0643.\n\u0623\u0639\u0644\u0645 \u0623\u0646 \u0647\u0630\u0627 \u0635\u0639\u0628.\n\u0646\u0639\u062a\u0642\u062f \u0623\u0646 \u0627\u0644\u0637\u0631\u064a\u0642\u0629 \u0644\u062d\u0645\u0627\u064a\u0629 \u0623\u0646\u0641\u0633\u0646\u0627 \u0645\u0646 \u0627\u0644\u0622\u062e\u0631\u064a\u0646 \u0647\u064a \u0623\u0646 \u0646\u0643\u0648\u0646 \u0623\u0642\u0648\u064a\u0627\u0621\u060c \u0648\u0623\u0646 \u0646\u0633\u062a\u062e\u062f\u0645 \u0627\u0644\u0642\u0648\u0629.\n\u0644\u0643\u0646 \u0627\u0646\u0638\u0631\u0648\u0627 \u0625\u0644\u0649 \u0645\u0627 \u064a\u0630\u0643\u0631\u0646\u0627 \u0628\u0647 \u0628\u0648\u0644\u0633 \u0641\u064a \u0631\u0633\u0627\u0644\u0629 \u0631\u0648\u0645\u064a\u0629 2:4\u060c \u0648\u0647\u0648:\n \u0623\u064e\u0645\u0652 \u062a\u064e\u0633\u0652\u062a\u064e\u0647\u0650\u064a\u0646\u064f \u0628\u0650\u063a\u0650\u0646\u064e\u0649 \u0644\u064f\u0637\u0652\u0641\u0650\u0647\u0650 \u0648\u064e\u0625\u0650\u0645\u0652\u0647\u064e\u0627\u0644\u0650\u0647\u0650 \u0648\u064e\u0637\u064f\u0648\u0644\u0650 \u0623\u064e\u0646\u064e\u0627\u062a\u0650\u0647\u0650 \u063a\u064e\u064a\u0652\u0631\u064e \u0639\u064e\u0627\u0644\u0650\u0645\u064d \u0623\u064e\u0646\u064e\u0651 \u0644\u064f\u0637\u0652\u0641\u064e \u0627\u0644\u0631\u0628 \u0625\u0650\u0646\u064e\u0651\u0645\u064e\u0627 \u064a\u064e\u0642\u0652\u062a\u064e\u0627\u062f\u064f\u0643\u064e \u0625\u0650\u0644\u064e\u0649 \u0627\u0644\u062a\u064e\u0651\u0648\u0652\u0628\u064e\u0629\u0650\u061f\u060c\n\u0643\u064a\u0641 \u0643\u0627\u0646 \u0627\u0644\u0631\u0628 \u064a\u0633\u0648\u0639 \u0644\u0637\u064a\u0641\u0627 \u0645\u0639\u0643, \u0639\u0646\u062f\u0645\u0627 \u0643\u0646\u062a \u0641\u064a \u0627\u0644\u062e\u0637\u064a\u0629 \u0648\u062a\u0628\u062a\u0639\u062f \u0639\u0646\u0647 \u0628\u0639\u064a\u062f\u0627\u061f\n\u0644\u0637\u0641\u0647 \u062c\u0639\u0644\u0643 \u062a\u062a\u0648\u0628\n\u0648\u0627\u0644\u0622\u0646 \u0644\u062f\u064a\u0643 \u0627\u0644\u0641\u0631\u0635\u0629 \u0644\u062a\u0642\u0644\u064a\u062f \u0627\u0644\u0645\u0633\u064a\u062d\u060c \u0648\u0623\u0646 \u062a\u0643\u0648\u0646 \u0644\u0637\u064a\u0641\u0627\u064b \u0645\u0639 \u0627\u0644\u062c\u0645\u064a\u0639.\n\n\u0627\u0644\u0635\u0641\u0629 \u0627\u0644\u062b\u0627\u0644\u062b\u0629: \u0627\u0644\u0635\u0628\u0631 \u0639\u0644\u0649 \u0627\u0644\u0634\u0631.\n\u0639\u0646\u062f\u0645\u0627 \u0646\u0634\u0627\u0631\u0643 \u062d\u0642\u064a\u0642\u0629 \u0627\u0644\u0625\u0646\u062c\u064a\u0644\u060c \u0633\u0646\u0648\u0627\u062c\u0647 \u0645\u0639\u0627\u0631\u0636\u0629 \u0645\u0646 \u0623\u0634\u062e\u0627\u0635 \u0644\u0627 \u064a\u0639\u062c\u0628\u0647\u0645 \u0645\u0627 \u0646\u0642\u0648\u0644\u0647.\n\u0647\u0644 \u062a\u062a\u0630\u0643\u0631 \u0643\u064a\u0641 \u0631\u062f \u0633\u062a\u064a\u0641\u0646 \u0639\u0644\u0649 \u0627\u0644\u0623\u0634\u062e\u0627\u0635 \u0627\u0644\u0630\u064a\u0646 \u0642\u062a\u0644\u0648\u0647\u061f\n\u064a\u0642\u0648\u0644 \u0633\u0641\u0631 \u0623\u0639\u0645\u0627\u0644 \u0627\u0644\u0631\u0633\u0644 7: 59-60:\n59  \"\u0641\u064e\u0643\u064e\u0627\u0646\u064f\u0648\u0627 \u064a\u064e\u0631\u0652\u062c\u064f\u0645\u064f\u0648\u0646\u064e \u0627\u0633\u0652\u062a\u0650\u0641\u064e\u0627\u0646\u064f\u0648\u0633\u064e \u0648\u064e\u0647\u064f\u0648\u064e \u064a\u064e\u062f\u0652\u0639\u064f\u0648 \u0648\u064e\u064a\u064e\u0642\u064f\u0648\u0644\u064f: \u00ab\u0623\u064e\u064a\u064f\u0651\u0647\u064e\u0627 \u0627\u0644\u0631\u064e\u0651\u0628\u064f\u0651 \u064a\u064e\u0633\u064f\u0648\u0639\u064f \u0627\u0642\u0652\u0628\u064e\u0644\u0652 \u0631\u064f\u0648\u062d\u0650\u064a\u00bb.\n60  \u062b\u064f\u0645\u064e\u0651 \u062c\u064e\u062b\u064e\u0627 \u0639\u064e\u0644\u064e\u0649 \u0631\u064f\u0643\u0652\u0628\u064e\u062a\u064e\u064a\u0652\u0647\u0650 \u0648\u064e\u0635\u064e\u0631\u064e\u062e\u064e \u0628\u0650\u0635\u064e\u0648\u0652\u062a\u064d \u0639\u064e\u0638\u0650\u064a\u0645\u064d: \u00ab\u064a\u064e\u0627 \u0631\u064e\u0628\u064f\u0651 \u0644\u0627\u064e \u062a\u064f\u0642\u0650\u0645\u0652 \u0644\u064e\u0647\u064f\u0645\u0652 \u0647\u064e\u0630\u0650\u0647\u0650 \u0627\u0644\u0652\u062e\u064e\u0637\u0650\u064a\u064e\u0651\u0629\u064e\u00bb. \u0648\u064e\u0625\u0650\u0630\u0652 \u0642\u064e\u0627\u0644\u064e \u0647\u064e\u0630\u064e\u0627 \u0631\u064e\u0642\u064e\u062f\u064e.\u201d.\n\n\u0627\u0644\u0644\u0647 \u0648\u062d\u062f\u0647 \u0647\u0648 \u0627\u0644\u0642\u0627\u062f\u0631 \u0639\u0644\u0649 \u0645\u0633\u0627\u0639\u062f\u062a\u0646\u0627 \u0639\u0644\u0649 \u062a\u062d\u0645\u0644 \u0627\u0644\u0634\u0631 \u0628\u0635\u0628\u0631 \u0643\u0645\u0627 \u0641\u0639\u0644 \u0633\u062a\u064a\u0641\u0646.\n\u0644\u0643\u0646\u0647 \u0633\u064a\u0633\u0627\u0639\u062f\u0646\u0627 \u0639\u0646\u062f\u0645\u0627 \u0646\u062f\u0639\u0648\u0647 \u0641\u064a \u0623\u0648\u0642\u0627\u062a \u0627\u0644\u0634\u062f\u0629.\n\u0633\u064a\u0633\u0627\u0639\u062f\u0646\u0627 \u0639\u0644\u0649 \u0627\u0644\u062b\u0642\u0629 \u0628\u0647\u060c \u0645\u0639 \u0627\u0644\u0639\u0644\u0645 \u0623\u0646 \u0623\u0631\u0648\u0627\u062d\u0646\u0627 \u0641\u064a \u0623\u0645\u0627\u0646 \u0628\u064a\u0646 \u064a\u062f\u064a\u0647\u060c \u0628\u063a\u0636 \u0627\u0644\u0646\u0638\u0631 \u0639\u0645\u0627 \u064a\u062d\u062f\u062b \u0644\u0623\u062c\u0633\u0627\u062f\u0646\u0627.\n\n\u0627\u0644\u062c\u0648\u062f\u0629 \u0627\u0644\u0631\u0627\u0628\u0639\u0629: \u0627\u0644\u062a\u0635\u062d\u064a\u062d \u0628\u0644\u0637\u0641.\n\u062a\u0635\u062d\u064a\u062d \u0627\u0644\u0646\u0627\u0633 \u0623\u0645\u0631 \u0635\u0639\u0628.\n\u0644\u0643\u0646 \u0625\u0630\u0627 \u0643\u0627\u0646 \u0627\u0628\u0646\u064a \u064a\u0641\u0639\u0644 \u0634\u064a\u0626\u0627\u064b \u062e\u0627\u0637\u0626\u0627\u064b\u060c \u0641\u0623\u0646\u0627 \u0623\u062e\u0628\u0631\u0647 \u0628\u0630\u0644\u0643 \u0644\u0623\u0646\u064a \u0623\u062d\u0628\u0647.\n\u0625\u0644\u064a\u0643 \u0627\u0644\u0633\u0624\u0627\u0644 \u0627\u0644\u0645\u0647\u0645 \u0627\u0644\u0630\u064a \u064a\u062c\u0628 \u0627\u0644\u062a\u0641\u0643\u064a\u0631 \u0641\u064a\u0647 \u0639\u0646\u062f\u0645\u0627 \u064a\u062a\u0639\u064a\u0646 \u0639\u0644\u064a\u0643 \u062a\u0635\u062d\u064a\u062d \u0634\u062e\u0635 \u0645\u0627:\n\u0647\u0644 \u064a\u0634\u0639\u0631 \u0637\u0641\u0644\u064a \u0623\u0648 \u0635\u062f\u064a\u0642\u064a \u0623\u0648 \u0632\u0648\u062c\u064a \u0628\u062d\u0628\u064a\u061f\n\u0623\u0645 \u0623\u0646\u0647\u0645 \u0644\u0627 \u064a\u0634\u0639\u0631\u0648\u0646 \u0625\u0644\u0627 \u0628\u063a\u0636\u0628\u064a\u061f\n\n\u0639\u0646\u062f\u0645\u0627 \u0646\u0635\u062d\u062d \u0628\u0627\u0644\u063a\u0636\u0628 \u0623\u0648 \u0627\u0644\u0625\u062d\u0628\u0627\u0637\u060c \u0641\u0625\u0646\u0646\u0627 \u0646\u062a\u0635\u0631\u0641 \u0648\u0643\u0623\u0646 \u0627\u0644\u0631\u0628\u0647 \u0644\u0627 \u064a\u0633\u062a\u0637\u064a\u0639 \u062a\u063a\u064a\u064a\u0631 \u0627\u0644\u0634\u062e\u0635 \u0627\u0644\u0622\u062e\u0631.\n\u0646\u0639\u062a\u0642\u062f \u0623\u0646\u0647 \u0628\u0625\u0645\u0643\u0627\u0646\u0646\u0627 \u0627\u0644\u0636\u063a\u0637 \u0639\u0644\u064a\u0647\u0645 \u0644\u0644\u062a\u063a\u064a\u064a\u0631\u060c \u0623\u0648 \u0627\u0644\u0635\u0631\u0627\u062e \u0628\u0635\u0648\u062a \u0623\u0639\u0644\u0649 \u062d\u062a\u0649 \u064a\u0633\u0644\u0643\u0648\u0627 \u0627\u0644\u0637\u0631\u064a\u0642 \u0627\u0644\u0635\u062d\u064a\u062d.\n\u0644\u0643\u0646 \u0627\u0644\u0645\u0639\u0644\u0645 \u0627\u0644\u0630\u064a \u064a\u0639\u0644\u0645 \u0623\u0646 \u0627\u0644\u0631\u0628 \u064a\u0645\u0644\u0643 \u0627\u0644\u0642\u0648\u0629 \u0627\u0644\u062d\u0642\u064a\u0642\u064a\u0629 \u0633\u064a\u0643\u0648\u0646 \u0644\u0637\u064a\u0641\u0627\u064b \u0648\u0635\u0628\u0648\u0631\u0627\u064b \u0648\u0631\u062d\u064a\u0645\u0627\u064b.\n\n\u0627\u0644\u062c\u0648\u062f\u0629 \u0627\u0644\u062e\u0627\u0645\u0633\u0629: \u0627\u0644\u0642\u062f\u0631\u0629 \u0639\u0644\u0649 \u0627\u0644\u062a\u062f\u0631\u064a\u0633.\n\u0647\u0644 \u062a\u0641\u0647\u0645 \u0643\u0644\u0645\u0629 \u0627\u0644\u0631\u0628 \u062c\u064a\u062f\u0627\u064b \u0628\u0645\u0627 \u064a\u0643\u0641\u064a \u0644\u0634\u0631\u062d\u0647\u0627 \u0644\u0644\u0622\u062e\u0631\u064a\u0646\u061f\n\u0647\u0644 \u062a\u062d\u0641\u0638 \u0627\u0644\u0646\u0635\u0648\u0635 \u0627\u0644\u0645\u0642\u062f\u0633\u0629 \u0644\u062a\u0643\u0648\u0646 \u062c\u0627\u0647\u0632\u0629 \u0644\u0625\u0631\u0634\u0627\u062f\u0643 \u0641\u064a \u0627\u0644\u062d\u064a\u0627\u0629 \u0648\u0645\u0634\u0627\u0631\u0643\u062a\u0647\u0627 \u0645\u0639 \u0627\u0644\u0622\u062e\u0631\u064a\u0646\u061f\n\u0633\u0646\u0628\u062f\u0623 \u0634\u064a\u0626\u0627\u064b \u062c\u062f\u064a\u062f\u0627\u064b \u0647\u0630\u0627 \u0627\u0644\u0634\u0647\u0631.\n\u0633\u0646\u0637\u0644\u0628 \u0645\u0646\u0643\u0645 \u062d\u0641\u0638 \u0622\u064a\u0629 \u0648\u0627\u062d\u062f\u0629 \u0645\u0646 \u0627\u0644\u0643\u062a\u0627\u0628 \u0627\u0644\u0645\u0642\u062f\u0633 \u0628\u062d\u0644\u0648\u0644 \u0646\u0647\u0627\u064a\u0629 \u0634\u0647\u0631 \u0645\u0627\u0631\u0633.\n\u0648\u0625\u0630\u0627 \u0627\u0633\u062a\u0637\u0639\u062a \u0623\u0646 \u062a\u0631\u062f\u062f\u0647\u0627 \u0644\u0623\u062d\u062f \u0642\u0627\u062f\u062a\u0646\u0627\u060c \u0628\u0623\u064a \u0644\u063a\u0629\u060c \u0641\u0633\u062a\u062d\u0635\u0644 \u0639\u0644\u0649 \u0645\u0644\u0635\u0642.\n\u064a\u0645\u0643\u0646\u0643 \u0648\u0636\u0639\u0647\u0627 \u0639\u0644\u0649 \u0632\u062c\u0627\u062c\u0629 \u0627\u0644\u0645\u0627\u0621 \u0623\u0648 \u062f\u0641\u062a\u0631 \u0627\u0644\u0645\u0644\u0627\u062d\u0638\u0627\u062a.\n\u0641\u064a \u0623\u064a \u0645\u0643\u0627\u0646 \u0633\u062a\u0631\u0627\u0647 \u0641\u064a\u0647\u060c \u0648\u0633\u062a\u0633\u062a\u0645\u0631 \u0641\u064a \u0645\u0645\u0627\u0631\u0633\u062a\u0647 \u0637\u0648\u0627\u0644 \u0627\u0644\u0639\u0627\u0645.\n\u062f\u0639\u0648\u0646\u0627 \u0646\u0642\u0631\u0623 \u0645\u0639\u064b\u0627 \u0622\u064a\u0629 \u0634\u0647\u0631 \u0645\u0627\u0631\u0633\u060c 2 \u062a\u064a\u0645\u0648\u062b\u0627\u0648\u0633 3:16.\n\u0627\u0644\u062c\u0645\u064a\u0639: \u201d\u0643\u064f\u0644\u064f\u0651 \u0627\u0644\u0652\u0643\u0650\u062a\u064e\u0627\u0628\u0650 \u0647\u064f\u0648\u064e \u0645\u064f\u0648\u062d\u0649\u064b \u0628\u0650\u0647\u0650 \u0645\u0650\u0646\u064e \u0627\u0644\u0644\u0647\u0650\u060c \u0648\u064e\u0646\u064e\u0627\u0641\u0650\u0639\u064c \u0644\u0650\u0644\u062a\u064e\u0651\u0639\u0652\u0644\u0650\u064a\u0645\u0650 \u0648\u064e\u0627\u0644\u062a\u064e\u0651\u0648\u0652\u0628\u0650\u064a\u062e\u0650\u060c \u0644\u0650\u0644\u062a\u064e\u0651\u0642\u0652\u0648\u0650\u064a\u0645\u0650 \u0648\u064e\u0627\u0644\u062a\u064e\u0651\u0623\u0652\u062f\u0650\u064a\u0628\u0650 \u0627\u0644\u064e\u0651\u0630\u0650\u064a \u0641\u0650\u064a \u0627\u0644\u0652\u0628\u0650\u0631\u0650\u0651\u201d.\n\n\u0643\u0644\u0646\u0627 \u0646\u062d\u062a\u0627\u062c \u0625\u0644\u0649 \u0627\u0644\u0645\u0633\u0627\u0639\u062f\u0629\u060c \u0644\u0646\u0633\u062a\u0645\u0631 \u0641\u064a \u0627\u0644\u0633\u064a\u0631 \u0641\u064a \u0627\u0644\u0627\u062a\u062c\u0627\u0647 \u0627\u0644\u0635\u062d\u064a\u062d.\n\u0646\u062d\u0646 \u0628\u062d\u0627\u062c\u0629 \u0625\u0644\u0649 \u0643\u0644\u0645\u0629 \u0627\u0644\u0627\u0628 \u0644\u062a\u0639\u0644\u064a\u0645\u0646\u0627 \u0648\u062a\u0635\u062d\u064a\u062d\u0646\u0627 \u0648\u062a\u062f\u0631\u064a\u0628\u0646\u0627 \u0639\u0644\u0649 \u0627\u0644\u0633\u064a\u0631 \u0641\u064a \u0637\u0631\u064a\u0642 \u0627\u0644\u0628\u0631.\n\u0648\u0646\u062d\u0646 \u0628\u062d\u0627\u062c\u0629 \u0625\u0644\u0649 \u0627\u0644\u0631\u0648\u062d \u0627\u0644\u0642\u062f\u0633 \u0644\u064a\u0633\u0627\u0639\u062f\u0646\u0627 \u0639\u0644\u0649 \u0641\u0647\u0645 \u0643\u0644\u0645\u0629 \u0627\u0644\u0631\u0628 \u0648\u062a\u0637\u0628\u064a\u0642\u0647\u0627\u060c \u0644\u0630\u0627 \u062f\u0639\u0648\u0646\u0627 \u0646\u0648\u062c\u0647 \u0642\u0644\u0648\u0628\u0646\u0627 \u0625\u0644\u0649 \u0627\u0644\u0633\u0645\u0627\u0621 \u0627\u0644\u0622\u0646 \u0628\u0627\u0644\u0635\u0644\u0627\u0629.\n\u064a\u0627 \u064a\u0633\u0648\u0639\u060c \u0644\u0627 \u064a\u0645\u0643\u0646\u0646\u0627 \u0627\u0644\u062a\u062d\u062f\u062b \u0625\u0644\u0649 \u0627\u0644\u0622\u0628 \u0625\u0644\u0627 \u0644\u0623\u0646\u0643 \u0628\u0646\u064a\u062a \u062c\u0633\u0631\u0627\u064b \u0628\u064a\u0646 \u0627\u0644\u0623\u0631\u0636 \u0648\u0627\u0644\u0633\u0645\u0627\u0621.\n\u0644\u0642\u062f \u062f\u0645\u0631\u062a \u0645\u0643\u0627\u0626\u062f \u0627\u0644\u0634\u064a\u0637\u0627\u0646 \u0648\u0641\u062a\u062d\u062a \u0623\u0639\u064a\u0646\u0646\u0627 \u0639\u0644\u0649 \u0627\u0644\u062d\u0642\u064a\u0642\u0629.\n\u064a\u0627 \u0623\u0628\u0627\u0646\u0627\u060c \u0646\u0634\u0643\u0631\u0643 \u0639\u0644\u0649 \u0645\u0646\u062d\u0646\u0627 \u0646\u0639\u0645\u0629 \u0627\u0644\u062a\u0648\u0628\u0629\u060c \u062d\u062a\u0649 \u0646\u062a\u0645\u0643\u0646 \u0645\u0646 \u0623\u0646 \u0646\u0643\u0648\u0646 \u0635\u0627\u062f\u0642\u064a\u0646 \u0645\u0639 \u0623\u0646\u0641\u0633\u0646\u0627 \u0648\u0645\u0639\u0643 \u0628\u0634\u0623\u0646 \u062e\u0637\u0627\u064a\u0627\u0646\u0627.\n\u0648\u0646\u0634\u0643\u0631\u0643 \u0623\u064a\u0647\u0627 \u0627\u0644\u0631\u0648\u062d \u0627\u0644\u0642\u062f\u0633\u060c \u0644\u0623\u0646\u0643 \u0645\u0646\u062d\u062a\u0646\u0627 \u0627\u0644\u0625\u064a\u0645\u0627\u0646 \u0644\u0646\u0644\u062c\u0623 \u0625\u0644\u0649 \u064a\u0633\u0648\u0639 \u0645\u0646 \u0623\u062c\u0644 \u062e\u0644\u0627\u0635\u0646\u0627.\n\u0627\u0641\u062a\u062d \u0639\u0642\u0648\u0644\u0646\u0627 \u0648\u0642\u0644\u0648\u0628\u0646\u0627 \u0644\u0641\u0647\u0645 \u0643\u0644\u0645\u0629 \u0627\u0644\u0631\u0628 \u0627\u0644\u0627\u0628 \u0648\u062a\u0637\u0628\u064a\u0642\u0647\u0627 \u0641\u064a \u062d\u064a\u0627\u062a\u0646\u0627.\n\u0633\u0627\u0639\u062f\u0646\u0627 \u0639\u0644\u0649 \u0628\u0630\u0644 \u0642\u0635\u0627\u0631\u0649 \u062c\u0647\u062f\u0646\u0627 \u0641\u064a \u0627\u0644\u0633\u0628\u0627\u0642 \u0627\u0644\u0630\u064a \u0648\u064f\u0636\u0639 \u0623\u0645\u0627\u0645\u0646\u0627\u060c \u0648\u062f\u0639\u0648\u0629 \u0627\u0644\u0622\u062e\u0631\u064a\u0646 \u0644\u0644\u0627\u0646\u0636\u0645\u0627\u0645 \u0625\u0644\u064a\u0646\u0627 \u0641\u064a \u0631\u062d\u0644\u0629 \u0627\u0644\u0648\u0635\u0648\u0644 \u0625\u0644\u0649 \u0627\u0644\u0643\u0645\u0627\u0644 \u0648\u0627\u0644\u0623\u0645\u0644 \u0648\u0627\u0644\u0633\u0645\u0627\u0621\u060c \u0622\u0645\u064a\u0646.\n\n\u0623\u0633\u0626\u0644\u0629 \u0644\u0644\u062a\u0623\u0645\u0644 \u0648\u0627\u0644\u0646\u0642\u0627\u0634\n1.  \u0627\u0642\u0631\u0623 \u0631\u0633\u0627\u0644\u0629 \u062a\u064a\u0645\u0648\u062b\u0627\u0648\u0633 \u0627\u0644\u062b\u0627\u0646\u064a\u0629 2:22 \u0648\u0627\u0644\u0645\u0632\u0645\u0648\u0631 119:35-37.\n\u0623) \u0623\u064a \u0645\u0646 \u201d\u0627\u0644\u0639\u0648\u0627\u0637\u0641 \u0627\u0644\u0634\u0628\u0627\u0628\u064a\u0629\u201d (\u0627\u0644\u0645\u062a\u0639\u0629\u060c \u0627\u0644\u0633\u0644\u0637\u0629\u060c \u0627\u0644\u0634\u0639\u0628\u064a\u0629\u060c \u0627\u0644\u0645\u0645\u062a\u0644\u0643\u0627\u062a\u060c \u0627\u0644\u0643\u0628\u0631\u064a\u0627\u0621) \u062a\u062c\u062f \u0642\u0644\u0628\u0643 \u064a\u0646\u062c\u0630\u0628 \u0625\u0644\u064a\u0647\u0627 \u0628\u0634\u0643\u0644 \u0637\u0628\u064a\u0639\u064a \u0639\u0646\u062f\u0645\u0627 \u062a\u0643\u0648\u0646 \u0645\u062a\u0648\u062a\u0631\u064b\u0627 \u0623\u0648 \u062a\u0628\u062d\u062b \u0639\u0646 \u0627\u0644\u0631\u0627\u062d\u0629\u061f\n\n2.  \u0627\u0642\u0631\u0623 \u0623\u0641\u0633\u0633 2: 1-5 \u0648\u062d\u0632\u0642\u064a\u0627\u0644 36: 26.\n\u0623) \u0645\u0627 \u0647\u0648 \u0627\u0644\u0636\u0631\u0648\u0631\u064a \u0644\u0644\u0627\u0646\u062a\u0642\u0627\u0644 \u0645\u0646 \u062d\u0627\u0644\u0629 \u201d\u0627\u0644\u0645\u0648\u062a\u201d \u0625\u0644\u0649 \u062d\u0627\u0644\u0629 \u201d\u0627\u0644\u062d\u064a\u0627\u0629\u201d\u061f\n\u0628) \u0647\u0644 \u064a\u0633\u0627\u0639\u062f\u0643 \u0627\u0644\u0625\u064a\u0645\u0627\u0646 \u0628\u0623\u0646 \u0627\u0644\u062a\u0648\u0628\u0629 \u0647\u064a \u0647\u0628\u0629 \u0645\u0646 \u0627\u0644\u0646\u0639\u0645\u0629 \u0639\u0644\u0649 \u0623\u0646 \u062a\u0643\u0648\u0646 \u0623\u0643\u062b\u0631 \u0635\u062f\u0642\u0627\u064b \u0645\u0639 \u0627\u0644\u0644\u0647 \u0628\u0634\u0623\u0646 \u062e\u0637\u064a\u0626\u062a\u0643\u061f\n\n3.  \u0627\u0642\u0631\u0623 \u0631\u0633\u0627\u0644\u0629 \u062a\u064a\u0645\u0648\u062b\u0627\u0648\u0633 \u0627\u0644\u062b\u0627\u0646\u064a\u0629 2:23-25\u0623 \u0648\u0631\u0633\u0627\u0644\u0629 \u0643\u0648\u0644\u0648\u0633\u064a 3:12-14.\n\u0623) \u0645\u0627 \u0647\u064a \u0635\u0641\u0627\u062a \u201d\u062e\u0627\u062f\u0645 \u0627\u0644\u0631\u0628\u201d \u0639\u0646\u062f \u0645\u0646\u0627\u0642\u0634\u0629 \u0627\u0644\u0622\u062e\u0631\u064a\u0646 \u0623\u0648 \u062a\u0635\u062d\u064a\u062d\u0647\u0645\u061f\n\u0628) \u0644\u0623\u0646 \u064a\u0633\u0648\u0639 \u0623\u062d\u0628\u0646\u0627 \u0628\u0635\u0628\u0631 \u0648\u0644\u0637\u0641 \u0639\u0638\u064a\u0645\u064a\u0646\u060c \u0641\u0645\u0646 \u0641\u064a \u062d\u064a\u0627\u062a\u0643 \u0633\u062a\u062d\u0628 \u0628\u0646\u0641\u0633 \u0647\u0630\u0647 \u0627\u0644\u0646\u0639\u0645\u0629- \u062d\u062a\u0649 \u0644\u0648 \u0627\u062e\u062a\u0644\u0641 \u0645\u0639\u0643 \u0623\u0648 \u0644\u0645 \u064a\u062d\u0628\u0643\u061f\n\n4.  \u0627\u0642\u0631\u0623 \u0631\u0648\u0645\u064a\u0629 10:9-11 \u0648\u0639\u0628\u0631\u0627\u0646\u064a\u064a\u0646 12:1-2.\n\u0623) \u0643\u064a\u0641 \u064a\u0633\u0627\u0639\u062f\u0646\u0627 \u062a\u062b\u0628\u064a\u062a \u0623\u0646\u0638\u0627\u0631\u0646\u0627 \u0639\u0644\u0649 \u064a\u0633\u0648\u0639 \u0641\u064a \u0627\u0644\u062a\u0648\u0628\u0629 \u0639\u0646 \u0627\u0644\u062e\u0637\u064a\u0626\u0629 \u0648\u0627\u0644\u0633\u064a\u0631 \u0641\u064a \u0627\u062a\u062c\u0627\u0647 \u062c\u062f\u064a\u062f\u061f\n\u0628) \u062a\u0630\u0643\u0631 \u0623\u0646 \u062a\u062d\u0641\u0638 \u0627\u0644\u0622\u064a\u0629 16 \u0645\u0646 \u0627\u0644\u0625\u0635\u062d\u0627\u062d \u0627\u0644\u062b\u0627\u0644\u062b \u0645\u0646 \u0631\u0633\u0627\u0644\u0629 \u062a\u064a\u0645\u0648\u062b\u0627\u0648\u0633 \u0627\u0644\u062b\u0627\u0646\u064a\u0629. \u0643\u064a\u0641 \u062a\u0633\u0627\u0639\u062f\u0646\u0627 \u0645\u0639\u0631\u0641\u0629 \u0643\u0644\u0645\u0629 \u0627\u0644\u0644\u0647 \u0639\u0644\u0649 \u062e\u0648\u0636 \u0645\u0627\u0631\u0627\u062b\u0648\u0646 \u0627\u0644\u0625\u064a\u0645\u0627\u0646\u061f","chinese_content":"\u4f60\u5728\u5f80\u54ea\u91cc\u5954\u8dd1\uff1f\n\u63d0\u6469\u592a\u540e\u4e66 2:22-26\n\u514b\u91cc\u65af\u00b7\u897f\u514b\u65af\u7267\u5e08\n2026\u5e743\u670815\u65e5\n\n\u57282019\u5e74\u4fc4\u52d2\u5188\u6ce2\u7279\u5170\u7684\u9a6c\u62c9\u677e\u6bd4\u8d5b\u4e2d\uff0c\u4e00\u4e9b\u6700\u4f18\u79c0\u7684\u8dd1\u6b65\u9009\u624b\u6700\u540e\u7adf\u7136\u8f93\u6389\u4e86\u6bd4\u8d5b\u3002\n\u4e0d\u662f\u56e0\u4e3a\u4ed6\u4eec\u8dd1\u5f97\u6162\uff0c\u800c\u662f\u56e0\u4e3a\u4ed6\u4eec\u8dd1\u9519\u4e86\u65b9\u5411\u3002\n\u8d5b\u9053\u4e0a\u6709\u4e00\u4e2a\u8f6c\u5f2f\uff0c\u4f46\u6807\u8bb0\u4e0d\u6e05\u3002\n\u6240\u4ee5\u5927\u7ea6\u670920\u540d\u8dd1\u5f97\u6700\u5feb\u7684\u9009\u624b\u671d\u9519\u8bef\u7684\u65b9\u5411\u8dd1\u4e86\u8d85\u8fc7\u4e00\u82f1\u91cc\uff01\n\u4ed6\u4eec\u5df2\u7ecf\u4e3a\u8fd9\u4e2a\u6bd4\u8d5b\u51c6\u5907\u4e86\u6570\u6708\u7684\u65f6\u95f4\uff0c\u53ef\u662f\u8fd9\u4e2a\u5931\u8bef\u8ba9\u4ed6\u4eec\u5728\u8fd9\u573a\u6bd4\u8d5b\u4e2d\u5931\u53bb\u4e86\u5b9d\u8d35\u7684\u51e0\u5206\u949f\u3002\n\u90a3\u4e9b\u7537\u5973\u9009\u624b\u8dd1\u5f97\u5f88\u5feb\u3002\n\u4f46\u4ed6\u4eec\u8f93\u6389\u4e86\u6bd4\u8d5b\uff0c\u56e0\u4e3a\u4ed6\u4eec\u8d70\u9519\u4e86\u8def\u3002\n\u4eca\u665a\u6211\u4eec\u7ee7\u7eed\u63d0\u6469\u592a\u540e\u4e66\u7cfb\u5217\u8bb2\u9053\u3002\n\u4f7f\u5f92\u4fdd\u7f57\u7ed9\u4ee5\u5f17\u6240\u7684\u57fa\u7763\u6559\u4f1a\u5e74\u8f7b\u7267\u5e08\u63d0\u6469\u592a\u5199\u4fe1\u3002\n\u4fdd\u7f57\u6b63\u5728\u4e3a\u63d0\u6469\u592a\u4e5f\u5728\u4e3a\u4eca\u5929\u7684\u6211\u4eec\uff0c\u63d0\u4f9b\u575a\u6301\u8d70\u5728\u6b63\u8def\u4e0a\u7684\u5efa\u8bae\u3002\n\u63d0\u6469\u592a\u540e\u4e66 2\uff1a22\u201326\n22 \u201c\u4f60\u8981\u9003\u907f\u5c11\u5e74\u7684\u79c1\u6b32\uff0c\u540c\u90a3\u6e05\u5fc3\u7977\u544a\u4e3b\u7684\u4eba\u8ffd\u6c42\u516c\u4e49\u3001\u4fe1\u5fb7\u3001\u4ec1\u7231\u3001\u548c\u5e73\u3002\n23 \u60df\u6709\u90a3\u611a\u62d9\u65e0\u5b66\u95ee\u7684\u8fa9\u8bba\uff0c\u603b\u8981\u5f03\u7edd\uff0c\u56e0\u4e3a\u77e5\u9053\u8fd9\u7b49\u4e8b\u662f\u8d77\u4e89\u7ade\u7684\u3002\n24 \u7136\u800c\u4e3b\u7684\u4ec6\u4eba\u4e0d\u53ef\u4e89\u7ade\uff1b\u53ea\u8981\u6e29\u6e29\u548c\u548c\u5730\u5f85\u4f17\u4eba\uff0c\u5584\u4e8e\u6559\u5bfc\uff0c\u5b58\u5fc3\u5fcd\u8010\uff0c\n25 \u7528\u6e29\u67d4\u529d\u6212\u90a3\u62b5\u6321\u7684\u4eba\uff0c\n\u6216\u8005\u4e0a\u5e1d\u7ed9\u4ed6\u4eec\u6094\u6539\u7684\u5fc3\uff0c\u53ef\u4ee5\u660e\u767d\u771f\u9053\uff0c\n26 \u53eb\u4ed6\u4eec\u8fd9\u5df2\u7ecf\u88ab\u9b54\u9b3c\u4efb\u610f\u63b3\u53bb\u7684\uff0c\u53ef\u4ee5\u9192\u609f\uff0c\u8131\u79bb\u4ed6\u7684\u7f51\u7f57\u3002\u201d\n\n\u6211\u4eec\u4e00\u8d77\u8bfb\u4ee5\u8d5b\u4e9a\u4e6640:8\uff1a\n\u201c\u8349\u5fc5\u67af\u5e72\uff0c\u82b1\u5fc5\u51cb\u6b8b\uff1b\u60df\u6709\u6211\u4eec\u4e0a\u5e1d\u7684\u8bdd\uff0c\u5fc5\u6c38\u8fdc\u7acb\u5b9a\u3002\u201d\n\n\u7b2c22\u8282\u8bf4\uff1a\n22 \u201c\u4f60\u8981\u9003\u907f\u5c11\u5e74\u7684\u79c1\u6b32\uff0c\u540c\u90a3\u6e05\u5fc3\u7977\u544a\u4e3b\u7684\u4eba\u8ffd\u6c42\u516c\u4e49\u3001\u4fe1\u5fb7\u3001\u4ec1\u7231\u3001\u548c\u5e73\u3002\u201d\n\n\u8fd9\u8282\u7ecf\u6587\u5b9e\u9645\u4e0a\u662f\u4eca\u5929\u8bb2\u9053\u7684\u603b\u7ed3\u3002\n\u6211\u4eec\u5728\u795e\u7684\u8bdd\u8bed\u4e2d\u7ecf\u5e38\u770b\u5230\u8fd9\u4e00\u70b9\u3002\n\u6709\u65f6\u4e00\u9996\u8bd7\u7bc7\u6216\u4e00\u4e2a\u6bb5\u843d\u7684\u7b2c\u4e00\u53e5\u8bdd\u5c31\u662f\u603b\u7ed3\u3002\n\u63a5\u4e0b\u6765\u7684\u8bdd\u662f\u5bf9\u6574\u7bc7\u8bd7\u7bc7\u3001\u6574\u4e2a\u6bb5\u843d\u6216\u7ae0\u8282\u7684\u89e3\u91ca\u3002\n\u6210\u719f\u7684\u7537\u5973\u57fa\u7763\u5f92\u662f\u90a3\u4e9b\u9009\u62e9\u8fdc\u79bb\u5e74\u8f7b\u65f6\u8bf1\u60d1\u6211\u4eec\u7684\u4e8b\u7269\u7684\u4eba\u3002\n\u6210\u719f\u7684\u4eba\u4e0d\u518d\u5145\u6ee1\u201c\u5c11\u5e74\u7684\u79c1\u6b32\u201d\uff0c\u800c\u662f\u5b66\u4e60\u8ffd\u6c42\u795e\u7684\u4ef7\u503c\u89c2\uff0c\u5305\u62ec\u516c\u4e49\u3001\u4fe1\u5fb7\u3001\u4ec1\u7231\u3001\u548c\u5e73\u3002\n\u4fdd\u7f57\u5e74\u8f7b\u65f6\u53eb\u626b\u7f57\u3002\n\u626b\u7f57\u5145\u6ee1\u4e86\u9a84\u50b2\u548c\u81ea\u4fe1\uff0c\u5229\u7528\u6743\u529b\u8feb\u5bb3\u57fa\u7763\u5f92\u5e76\u5c06\u4ed6\u4eec\u5173\u8fdb\u76d1\u72f1\u3002\n\u626b\u7f57\u6e34\u671b\u53d7\u6b22\u8fce\u5e76\u53d6\u5f97\u6210\u529f\uff0c\u751a\u81f3\u4e0d\u60dc\u4e3a\u4e86\u6ee1\u8db3\u81ea\u5df1\u7684\u9a84\u50b2\u800c\u4f24\u5bb3\u4ed6\u4eba\u3002\n\u4f46\u63d0\u6469\u592a\u540e\u4e66\u7684\u4e66\u4fe1\u662f\u7531\u6210\u719f\u7684\u4fe1\u5f92\u4fdd\u7f57\u5199\u7684\u3002\n\u4ed6\u660e\u767d\u81ea\u5df1\u5c11\u5e74\u7684\u79c1\u6b32\u9020\u6210\u4e86\u591a\u5927\u7684\u4f24\u5bb3\uff0c\u6240\u4ee5\u5728\u6b64\u8b66\u544a\u63d0\u6469\u592a\u8981\u8fdc\u907f\u8fd9\u4e00\u5207\u3002\n\u4fdd\u7f57\u5199\u8fd9\u5c01\u4fe1\u65f6\uff0c\u63d0\u6469\u592a\u5927\u7ea640\u5c81\u3002\n\u4f46\u4f60\u4e0d\u7528\u975e\u5f97\u5e74\u8f7b\u624d\u4f1a\u8ffd\u6c42\u201c\u5c11\u5e74\u7684\u79c1\u6b32\u201d\u3002\n\u621157\u5c81\uff0c\u4f46\u6211\u4ecd\u5728\u5b66\u4e60\u5982\u4f55\u4e0d\u65ad\u9003\u907f\u5c11\u5e74\u7684\u79c1\u6b32\u3002\n\u6211\u6709\u4e2a\u5927\u5b66\u670b\u53cb\u548c\u6211\u540c\u9f84\u3002\n\u4f46\u4ed6\u4f9d\u7136\u50cf35\u5e74\u524d\u90a3\u6837\u751f\u6d3b\u3002\n\u4ed6\u7684\u751f\u6d3b\u88ab\u6211\u4eec\u5927\u5b66\u65f6\u4ee3\u90a3\u79cd\u5c11\u5e74\u7684\u79c1\u6b32\u6240\u4e3b\u5bfc\u3002\n\u4ee5\u4e0b\u662f\u6211\u4eec\u8bb8\u591a\u4eba\u4f1a\u7ecf\u5386\u7684\u4e00\u4e9b\u5c11\u5e74\u7684\u79c1\u6b32\uff1a\n\n*   \u4eab\u4e50\uff1a\u6027\u65b9\u9762\u7684\u7f6a\u662f\u4eab\u4e50\u7f6a\u7684\u4e00\u4e2a\u5e38\u89c1\u4f8b\u5b50\uff0c\u4f46\u8fd9\u5e76\u4e0d\u662f\u552f\u4e00\u7684\u4f8b\u5b50\u3002\n\u5176\u4ed6\u7f6a\u6076\u7684\u4eab\u4e50\u4e5f\u53ef\u80fd\u6765\u81ea\u9152\u7cbe\u3001\u98df\u7269\u548c\u5404\u79cd\u5a31\u4e50\u3002\n\u53ea\u8981\u4f7f\u7528\u5f97\u5f53\uff0c\u8fd9\u4e9b\u4e1c\u897f\u672c\u6ca1\u4ec0\u4e48\u574f\u5904\u3002\n\u4f8b\u5982\uff0c\u6027\u5728\u57fa\u7763\u6559\u5a5a\u59fb\u8bed\u5883\u4e0b\u662f\u4e00\u79cd\u7f8e\u4e3d\u7684\u793c\u7269\u3002\n\u4f46\u5f53\u6211\u4eec\u7528\u9519\u8bef\u7684\u65b9\u5f0f\u4f7f\u7528\u4efb\u4f55\u4e1c\u897f\u65f6\uff0c\u6211\u4eec\u5c31\u7b49\u4e8e\u8d4b\u4e88\u4e86\u5b83\u64cd\u63a7\u6211\u4eec\u751f\u547d\u7684\u6743\u529b\u3002\n\u5f53\u6211\u4eec\u7528\u4e0a\u5e1d\u7684\u4efb\u4f55\u6069\u8d50\u6765\u586b\u8865\u5185\u5fc3\u7684\u7a7a\u865a\u65f6\uff0c\u90a3\u4e1c\u897f\u5c31\u6210\u4e86\u5047\u795e\u2014\u2014\u5076\u50cf\u3002\n\n*   \u6743\u529b\uff1a\u5e74\u8f7b\u65f6\uff0c\u6211\u4eec\u6709\u65f6\u4f1a\u611f\u5230\u65e0\u529b\u3001\u8f6f\u5f31\u6216\u80fd\u529b\u4e0d\u591f\u3002\n\u6211\u9752\u5c11\u5e74\u65f6\u671f\u4e5f\u66fe\u9971\u53d7\u8fd9\u4e9b\u611f\u53d7\u7684\u56f0\u6270\u3002\n\u6709\u4e9b\u4eba\u8ffd\u6c42\u6743\u529b\u662f\u4e3a\u4e86\u63a9\u76d6\u81ea\u5df1\u7684\u8f6f\u5f31\u611f\u3002\n\u4ed6\u4eec\u8ba4\u4e3a\u575a\u5f3a\u4f1a\u8ba9\u4ed6\u4eec\u611f\u5230\u5b89\u5168\u3002\n\u4f60\u77e5\u9053\u9738\u51cc\u8005\u5176\u5b9e\u5e76\u4e0d\u50cf\u8868\u9762\u770b\u8d77\u6765\u90a3\u4e48\u575a\u5f3a\u5417\uff1f\n\u9738\u51cc\u8005\u901a\u5e38\u662f\u90a3\u4e9b\u5bf9\u81ea\u5df1\u751f\u6d3b\u4e2d\u67d0\u4ef6\u4e8b\u611f\u5230\u65e0\u529b\u7684\u4eba\uff0c\u6240\u4ee5\u4ed6\u901a\u8fc7\u4f24\u5bb3\u522b\u4eba\u6765\u8ba9\u81ea\u5df1\u611f\u5230\u6709\u529b\u91cf\u3002\n\n*   \u53d7\u4eba\u8ffd\u6367\uff1a\u8fd9\u4e5f\u662f\u6211\u751f\u6d3b\u4e2d\u53e6\u4e00\u4e2a\u5f3a\u70c8\u7684\u8bf1\u60d1\u3002\n\u6211\u7ecf\u5e38\u62c5\u5fc3\u522b\u4eba\u662f\u5426\u559c\u6b22\u6211\u3002\n\u6211\u592a\u5728\u610f\u522b\u4eba\u7684\u770b\u6cd5\u4e86\u3002\n\u4f60\u5462\uff1f\n\u4f60\u4f1a\u6539\u53d8\u81ea\u5df1\u7684\u884c\u4e3a\u6216\u5916\u8c8c\u6765\u8ba9\u522b\u4eba\u559c\u6b22\u4f60\u5417\uff1f\n\u4f60\u662f\u5426\u89c9\u5f97\u81ea\u5df1\u7684\u884c\u4e3a\u6216\u5916\u8868\u5fc5\u987b\u7b26\u5408\u67d0\u79cd\u65b9\u5f0f\uff0c\u5426\u5219\u5c31\u4f1a\u88ab\u4eba\u62d2\u7edd\uff1f\n\n*   \u8d22\u5bcc\uff1a\u5bf9\u91d1\u94b1\u548c\u7269\u8d28\u7684\u70ed\u7231\u662f\u6211\u4eec\u5927\u591a\u6570\u4eba\u6240\u9762\u4e34\u7684\u95ee\u9898\u3002\n\u6211\u4eec\u60f3\u8981\u66f4\u591a\u4e1c\u897f\u5e26\u6765\u7684\u5b89\u5168\u611f\u548c\u8212\u9002\u611f\u3002\n\u8fd9\u66b4\u9732\u4e86\u6211\u4eec\u7f3a\u4e4f\u4fe1\u5fc3\u3002\n\u4e0a\u5e1d\u5e0c\u671b\u6211\u4eec\u660e\u767d\uff0c\u4ed6\u662f\u6211\u4eec\u7684\u5e87\u62a4\u6240\u548c\u5821\u5792\uff0c\u662f\u4f9b\u5e94\u6211\u4eec\u7684\u90a3\u4e00\u4f4d\u3002\n\u7269\u8d28\u7684\u4e1c\u897f\u627f\u8bfa\u4f1a\u5e26\u7ed9\u6211\u4eec\u5e78\u798f\uff0c\u4f46\u5b83\u4eec\u6c38\u8fdc\u65e0\u6cd5\u5151\u73b0\u627f\u8bfa\u3002\n\u56e0\u4e3a\u6211\u4eec\u7684\u5fc3\u603b\u4f1a\u6e34\u671b\u5f97\u5230\u66f4\u591a\u3002\n\n*   \u9a84\u50b2\uff1a\u8fd9\u5b9e\u9645\u4e0a\u662f\u6240\u6709\u7f6a\u6076\u80cc\u540e\u7684\u7f6a\u3002\n\u9a84\u50b2\u662f\u76f8\u4fe1\u81ea\u5df1\u771f\u7684\u914d\u5f97\u4e0a\u62e5\u6709\u8d22\u5bcc\u3001\u6743\u529b\u3001\u4eab\u4e50\u548c\u53d7\u4eba\u8ffd\u6367\u3002\n\u4e3a\u4ec0\u4e48\uff1f\u56e0\u4e3a\u6211\u5f88\u7279\u522b\u3002\n\u9a84\u50b2\u5bf9\u6211\u4eec\u4f4e\u8bed\uff0c\u8bf4\uff1a\n\u201c\u6ca1\u5173\u7cfb\uff0c\u4f60\u53ef\u4ee5\u505a\u5230\u7684\u2014\u2014\u4f60\u503c\u5f97\u62e5\u6709\u3002\u201d\n\u5e7f\u544a\u5546\u5bf9\u6211\u4eec\u8bf4\u7684\u4e5f\u662f\u540c\u6837\u7684\u8bdd\u3002\n\u201c\u4f60\u503c\u5f97\u62e5\u6709......\u53bb\u5427\uff0c\u4e70\u4e0b\u5b83\u3002\n\u4e5f\u8bb8\u518d\u591a\u4e70\u4e00\u4e9b\uff0c\u6ca1\u5173\u7cfb\u7684\u3002\u201d\n\u8fd9\u5c31\u662f\u4e3a\u4ec0\u4e48\u6211\u4eec\u770b\u5230\u8fd9\u4e48\u591a\u8fd9\u6837\u7684\u5e7f\u544a\uff0c\u56e0\u4e3a\u6211\u4eec\u7684\u9a84\u50b2\u8ba9\u6211\u4eec\u771f\u7684\u613f\u610f\u76f8\u4fe1\u8fd9\u4e9b\u4e8b\u60c5\u3002\n\n\u670b\u53cb\u4eec\uff0c\u6211\u80fd\u95ee\u4f60\u4eec\u4e00\u4e2a\u95ee\u9898\u5417\uff1f\n\u8fd9\u4e94\u4ef6\u4e8b\u4e2d\uff0c\u4f60\u89c9\u5f97\u54ea\u4e00\u4e2a\u6bd4\u8f83\u719f\u6089\uff1f\n\u4f60\u662f\u5728\u8ffd\u6c42\u9a84\u50b2\u3001\u8d22\u5bcc\u3001\u6743\u529b\u3001\u4eab\u4e50\u8fd8\u662f\u53d7\u4eba\u8ffd\u6367\uff1f\n\u6216\u8005\uff0c\u4e5f\u8bb8\u662f\u5176\u4ed6\u4ec0\u4e48\u5728\u8ba9\u4f60\u8fdc\u79bb\u4e0a\u5e1d\uff1f\n\u4f60\u7684\u5fc3\u4eca\u5929\u5728\u54ea\u91cc\uff0c\u4f60\u8981\u53bb\u54ea\u91cc\uff1f\n\u4f60\u8fd8\u8bb0\u5f97\u4e0a\u5e1d\u5728\u4e9a\u5f53\u5403\u4e86\u679c\u5b50\u540e\u5728\u56ed\u5b50\u91cc\u95ee\u4e86\u4ed6\u4ec0\u4e48\u5417\uff1f\n\u4e9a\u5f53\u548c\u590f\u5a03\u8eb2\u8d77\u6765\uff0c\u4e0a\u5e1d\u8bf4\uff1a\u201c\u4e9a\u5f53\uff0c\u4f60\u5728\u54ea\u91cc\uff1f\u201d\n\u4e0a\u5e1d\u4eca\u5929\u4e5f\u5728\u5411\u4e16\u4e0a\u6bcf\u4e2a\u4eba\u63d0\u51fa\u540c\u6837\u7684\u95ee\u9898\u3002\n\u4f60\u5728\u54ea\u91cc\uff1f\n\u4ed6\u5e76\u4e0d\u662f\u5728\u95ee\u4f60\u5177\u4f53\u7684\u4f4d\u7f6e\u3002\n\u4ed6\u5728\u95ee\u7684\u662f\uff1a\u201c\u4f60\u7684\u5fc3\u5728\u54ea\u91cc\uff1f\u201d\n\u56e0\u4e3a\u6211\u4eec\u7684\u5fc3\u5c31\u50cf\u6307\u5357\u9488\uff0c\u5f15\u5bfc\u6211\u4eec\u8d70\u5411\u6211\u4eec\u6700\u73cd\u89c6\u7684\u4e1c\u897f\u3002\n\u6211\u4eec\u5931\u4e27\u4e86\uff0c\u5374\u6d51\u7136\u4e0d\u89c9\uff0c\u56e0\u4e3a\u7f6a\u662f\u72e1\u733e\u7684\u3002\n\u6211\u4eec\u9700\u8981\u4e0a\u5e1d\u7684\u5e2e\u52a9\uff0c\u624d\u80fd\u770b\u6e05\u6211\u4eec\u5185\u5fc3\u53d1\u751f\u4e86\u4ec0\u4e48\u3002\n\u8ba9\u6211\u4eec\u4e00\u8d77\u8bfb\u8bd7\u7bc7139\uff1a23\u201324\uff0c\u4f5c\u4e3a\u7977\u544a\uff1a\n\u4f17\u4eba\uff1a23 \u201c\u4e0a\u5e1d\u554a\uff0c\u6c42\u4f60\u9274\u5bdf\u6211\uff0c\u77e5\u9053\u6211\u7684\u5fc3\u601d\uff1b\n\u8bd5\u70bc\u6211\uff0c\u77e5\u9053\u6211\u7684\u610f\u5ff5\uff0c\n24 \u770b\u5728\u6211\u91cc\u9762\u6709\u4ec0\u4e48\u6076\u884c\u6ca1\u6709\uff0c\n\u5f15\u5bfc\u6211\u8d70\u6c38\u751f\u7684\u9053\u8def\uff01\u201d\n\n\u6ca1\u6709\u4e0a\u5e1d\u7684\u5e2e\u52a9\uff0c\u6211\u4eec\u4e0d\u4f1a\u201c\u8d70\u6c38\u751f\u7684\u9053\u8def\u201d\u3002\n\u6211\u4eec\u4f1a\u8d70\u9519\u65b9\u5411\uff0c\u4f1a\u8ffd\u6c42\u8ba9\u8fdc\u79bb\u4e0a\u5e1d\u5fc3\u610f\u7684\u4e8b\u60c5\u3002\n\u4f46\u4e0a\u5e1d\u5982\u6b64\u5584\u826f\uff0c\u4e0d\u4f1a\u5750\u89c6\u6211\u4eec\u8d70\u8ff7\u5931\u4e27\u3002\n\u76f8\u53cd\uff0c\u4ed6\u53bb\u5bfb\u627e\u4ed6\u5931\u4e27\u7684\u7fa4\u7f8a\u3002\n\u4ed6\u6765\u5230\u6211\u4eec\u9762\u524d\uff0c\u4e3a\u6211\u4eec\u63d0\u4f9b\u4e86\u4e00\u6761\u8eb2\u907f\u548c\u5f97\u6551\u7684\u9053\u8def\u3002\n\u518d\u770b\u63d0\u6469\u592a\u540e\u4e662\uff1a25B-26\uff1a\n25b \u201c\u6216\u8005\u4e0a\u5e1d\u7ed9\u4ed6\u4eec\u6094\u6539\u7684\u5fc3\uff0c\u53ef\u4ee5\u660e\u767d\u771f\u9053\uff0c\n26 \u53eb\u4ed6\u4eec\u8fd9\u5df2\u7ecf\u88ab\u9b54\u9b3c\u4efb\u610f\u63b3\u53bb\u7684\uff0c\u53ef\u4ee5\u9192\u609f\uff0c\u8131\u79bb\u4ed6\u7684\u7f51\u7f57\u3002\u201d\n\n\u4f60\u77e5\u9053\u5417\uff1f\u5f53\u4f60\u88ab\u7f6a\u548c\u9b54\u9b3c\u6346\u7ed1\u65f6\uff0c\u4f60\u4f9d\u7136\u53ef\u80fd\u4f1a\u611f\u5230\u5341\u5206\u81ea\u7531\u3002\n\u7f6a\u611f\u89c9\u5c31\u50cf\u81ea\u7531\uff0c\u4f46\u5b9e\u9645\u4e0a\u6070\u6070\u76f8\u53cd\u3002\n\u7f51\u7f57\u957f\u8fd9\u6837\u3002\n\u8fd9\u662f\u4e00\u79cd\u9677\u9631\uff0c\u53ef\u4ee5\u6293\u4f4f\u4e00\u53ea\u5728\u5c0f\u8def\u4e0a\u81ea\u7531\u5954\u8dd1\u7684\u52a8\u7269\uff0c\u4f7f\u5176\u7a81\u7136\u9677\u5165\u5371\u9669\u4e4b\u4e2d\u3002\n\u6492\u65e6\u628a\u8c0e\u8a00\u5f53\u4f5c\u4e0a\u9762\u90a3\u573a\u9a6c\u62c9\u677e\u5927\u8d5b\u8d5b\u9053\u4e0a\u7684\u6807\u5fd7\uff0c\u6765\u6b3a\u9a97\u548c\u56f0\u4f4f\u6211\u4eec\u3002\n\u6492\u65e6\u60f3\u8ba9\u6211\u4eec\u8ffd\u9010\u4eab\u4e50\u3001\u6743\u529b\u3001\u53d7\u4eba\u8ffd\u6367\u3001\u8d22\u5bcc\u548c\u9a84\u50b2\u3002\n\u8fd9\u4e9b\u5076\u50cf\u627f\u8bfa\u7ed9\u6211\u4eec\u81ea\u7531\uff0c\u800c\u6211\u4eec\u6b63\u597d\u6e34\u671b\u81ea\u7531\u3002\n\u4e0d\u5e78\u7684\u662f\uff0c\u6211\u4eec\u76f8\u4fe1\u8fd9\u4e9b\u4e1c\u897f\u80fd\u5e2e\u52a9\u6211\u4eec\u611f\u5230\u6ee1\u8db3\u3001\u5b89\u5168\u548c\u5feb\u4e50\u3002\n\u4f46\u8fd9\u4e9b\u5076\u50cf\u662f\u9677\u9631\uff0c\u8ba9\u6211\u4eec\u8fdc\u79bb\u4e0a\u5e1d\uff0c\u8fdc\u79bb\u771f\u751f\u547d\u7684\u9053\u8def\u3002\n\u6492\u65e6\u60f3\u5bf9\u6211\u4eec\u9690\u85cf\u751f\u547d\u7684\u9053\u8def\uff0c\u8bf4\uff1a\n\u201c\u8d70\u8fd9\u6761\u8def\u53bb\u8ffd\u6c42\u80dc\u5229\u4e0e\u5e78\u798f\u5427\uff01\n\u6ca1\u9519\uff0c\u5c31\u662f\u8fd9\u6761\u8def\uff01\u8ddf\u6211\u6765\uff01\u201d\n\n\u90a3\u4e48\uff0c\u52a8\u7269\u600e\u4e48\u53ef\u80fd\u9003\u8131\u8fd9\u6837\u7684\u9677\u9631\u5462\uff1f\n\u8fd9\u662f\u4ed6\u81ea\u5df1\u80fd\u505a\u5230\u7684\u5417\uff1f\n\u4e0d\uff0c\u5154\u5b50\u5f88\u65e0\u52a9\u3002\n\u4ed6\u9700\u8981\u4e00\u4e2a\u66f4\u806a\u660e\u3001\u66f4\u5f3a\u58ee\u7684\u4eba\u6765\u6551\u4ed6\u9003\u51fa\u9677\u9631\u3002\n\u6211\u4eec\u4e5f\u9700\u8981\u66f4\u806a\u660e\u3001\u66f4\u5f3a\u5927\u7684\u4eba\u6765\u62ef\u6551\u6211\u4eec\u3002\n\u8fd9\u662f\u6211\u5e0c\u671b\u4f60\u4ece\u8fd9\u8282\u7ecf\u6587\u4e2d\u770b\u5230\u7684\u6700\u91cd\u8981\u7684\u4e00\u70b9\u3002\n\u6211\u4eec\u9700\u8981\u6551\u4e3b\uff0c\u56e0\u4e3a\u6211\u4eec\u65e0\u6cd5\u62ef\u6551\u81ea\u5df1\uff0c\u751a\u81f3\u65e0\u6cd5\u8f6c\u5411\u4e0a\u5e1d\u3002\n\u7075\u6027\u6b7b\u4ea1\u7684\u4eba\u5185\u5fc3\u65e0\u6cd5\u9009\u62e9\u751f\u547d\u3002\n\u8bf7\u770b\u7b2c25\u8282\u8bf4\u7684\uff1a\n\u201c\u4e0a\u5e1d\u7ed9\u4ed6\u4eec\u6094\u6539\u7684\u5fc3\u3002\u201d\n\n\u7ed9\uff08grant\uff09\u662f\u514d\u8d39\u8d60\u4e0e\u3002\n\u4e09\u5341\u5e74\u524d\uff0c\u4e0a\u5e1d\u8d50\u4e88\u6211\u6094\u6539\u7684\u6069\u8d50\u3002\n\u524d\u5341\u6765\u5e74\u6211\u4e00\u76f4\u8bf4\u5b87\u5b99\u4e2d\u6ca1\u6709\u4e0a\u5e1d\u3002\n\u4f46\u56e0\u4e3a\u4e0a\u5e1d\u7684\u826f\u5584\uff0c\u4ed6\u5411\u6211\u5c55\u793a\u4e86\u5564\u9152\u3001\u5973\u4eba\u548c\u4e16\u4fd7\u7684\u6210\u529f\u90fd\u6c38\u8fdc\u65e0\u6cd5\u6ee1\u8db3\u6211\u5185\u5fc3\u7684\u6e34\u671b\u3002\n\u8fd9\u5c31\u662f\u7b2c26\u8282\u201c\u53ef\u4ee5\u9192\u609f\u201d\u7684\u610f\u601d\u3002\n\u5f53\u4f60\u7684\u65b9\u5411\u611f\u6df7\u4e71\u65f6\uff0c\u4f60\u4f1a\u671d\u9519\u8bef\u7684\u65b9\u5411\u5954\u8dd1\u3002\n\u627e\u5230\u56de\u5bb6\u7684\u8def\u7684\u7b2c\u4e00\u6b65\u5c31\u662f\u8ba4\u8bc6\u5230\u4f60\u8ff7\u8def\u4e86\u3002\n\u4e39\u00b7\u9ea6\u514b\u9053\u5c14\u662f\u6ce2\u7279\u5170\u90a3\u573a\u9a6c\u62c9\u677e\u4e2d\u8d70\u8ff7\u8def\u7684\u8dd1\u6b65\u9009\u624b\u4e4b\u4e00\u3002\n\u4ed6\u8bf4\uff1a\u201c\u6211\u8f6c\u8fc7\u62d0\u89d2\uff0c\u770b\u523010\u4e2a\u4eba\u7ad9\u7740\u4e0d\u52a8......\n\u4ed6\u4eec\u4e92\u76f8\u770b\u7740\u5bf9\u65b9\uff0c\u5fc3\u60f3\u2018\u5443\uff0c\u8fd9\u611f\u89c9\u4e0d\u5bf9\u3002\u2018\u201d\n\n\u53e6\u4e00\u540d\u8dd1\u6b65\u9009\u624b\u624e\u514b\u00b7\u5361\u65af\u7279\u8bf4\uff0c\u4ed6\u8fdb\u5165\u4e00\u6761\u96a7\u9053\uff0c\u6c7d\u8f66\u4ee5\u6bcf\u5c0f\u65f655\u82f1\u91cc\u7684\u901f\u5ea6\u547c\u5578\u800c\u8fc7\u3002\n\u8fd9\u65f6\u4ed6\u610f\u8bc6\u5230\u81ea\u5df1\u504f\u79bb\u4e86\u8def\u7ebf\u3002\n\u5728\u4e0a\u5e1d\u8ba9\u6211\u9192\u609f\u4e4b\u524d\uff0c\u6211\u4ee5\u4e3a\u81ea\u5df1\u62e5\u6709\u201c\u771f\u7406\u7684\u77e5\u8bc6\u201d\u3002\n\u6211\u7684\u9a84\u50b2\u544a\u8bc9\u6211\uff0c\u6211\u8d70\u7684\u662f\u6b63\u786e\u7684\u9053\u8def\uff0c\u6211\u4e0d\u9700\u8981\u4efb\u4f55\u4e0a\u5e1d\u6307\u5f15\u6211\uff0c\u56e0\u4e3a\u6211\u5f88\u806a\u660e\u3002\n\u8bbd\u523a\u7684\u662f\uff0c\u6211\u592a\u611a\u8822\uff0c\u6ca1\u770b\u6e05\u6492\u65e6\u7684\u8be1\u8ba1\u3002\n\u6211\u88ab\u4ed6\u8c0e\u8a00\u7684\u7f51\u7f57\u56f0\u4f4f\u4e86\u3002\n\u6211\u76f8\u4fe1\u9b54\u9b3c\u7684\u627f\u8bfa\uff0c\u5373\u6211\u53ef\u4ee5\u901a\u8fc7\u9003\u907f\u4e0a\u5e1d\u627e\u5230\u5e78\u798f\u3002\n\u4f46\u540e\u6765\uff0c\u4e0a\u5e1d\u8d50\u7ed9\u4e86\u6211\u6094\u6539\u7684\u793c\u7269\u3002\n\u6094\u6539\u7684\u5e0c\u814a\u8bed\u5355\u8bcd\u662fmetanoia\u3002\n\u5b83\u7684\u610f\u601d\u662f\u201c\u5934\u8111\u7684\u6539\u53d8\u3001\u751f\u547d\u7684\u6539\u53d8\u548c\u76ee\u6807\u7684\u6539\u53d8\u201d\u3002\n\u8036\u7a23\u8d50\u7ed9\u6211\u4e00\u9897\u65b0\u5fc3\uff0c\u597d\u8ba9\u6211\u80fd\u201c\u6e05\u5fc3\u7977\u544a\u4e3b\u201d\uff0c\u6b63\u5982\u7b2c22\u8282\u6240\u8bf4\u3002\n\u6e05\u5fc3\u5c31\u662f\u8bda\u5b9e\u7684\u5fc3\u3002\n\u4e00\u9897\u5411\u4e0a\u5e1d\u547c\u558a\u7684\u5fc3\uff1a\u201c\u6211\u4e3a\u6211\u7684\u7f6a\u611f\u5230\u62b1\u6b49\uff0c\u8bf7\u539f\u8c05\u6211\u3002\n\u8bf7\u5e2e\u6211\u671d\u7740\u4f60\u8dd1\u53bb\uff0c\u800c\u4e0d\u662f\u9003\u907f\u4f60\u3002\u201d\n\u4fdd\u7f57\u5728\u7f57\u9a6c\u4e6610\uff1a9-11\u4e2d\u5199\u5f97\u975e\u5e38\u6e05\u695a\uff0c\u8bf4\u660e\u4e86\u4f60\u5982\u4f55\u624d\u80fd\u8f6c\u5411\u795e\u5e76\u5f97\u8499\u62ef\u6551\u3002\n9 \u201c\u4f60\u82e5\u53e3\u91cc\u8ba4\u8036\u7a23\u4e3a\u4e3b\uff0c\u5fc3\u91cc\u4fe1\u4e0a\u5e1d\u53eb\u4ed6\u4ece\u6b7b\u91cc\u590d\u6d3b\uff0c\u5c31\u5fc5\u5f97\u6551\u3002\n10 \u56e0\u4e3a\u4eba\u5fc3\u91cc\u76f8\u4fe1\uff0c\u5c31\u53ef\u4ee5\u79f0\u4e49\uff1b\u53e3\u91cc\u627f\u8ba4\uff0c\u5c31\u53ef\u4ee5\u5f97\u6551\u3002\n11\u7ecf\u4e0a\u8bf4\uff1a\u2018\u51e1\u4fe1\u4ed6\u7684\u4eba\uff0c\u5fc5\u4e0d\u81f3\u4e8e\u7f9e\u6127\u2019\u3002\u201d\n\n\u4f60\u662f\u5426\u53e3\u91cc\u627f\u8ba4\uff0c\u4ee5\u81f3\u4e8e\u5f97\u6551\uff1f\n\u5982\u679c\u4f60\u8fd8\u6ca1\u6709\uff0c\u4f60\u4e0d\u89c9\u5f97\u4eca\u5929\u5c31\u662f\u4e2a\u4f1f\u5927\u7684\u65e5\u5b50\u5417\uff1f\n\u5723\u7075\u5c31\u5728\u6211\u4eec\u4e2d\u95f4\uff0c\u4e5f\u8bb8\u7942\u6b63\u5bf9\u4f60\u7684\u5fc3\u4f4e\u58f0\u8bf4\uff1a\n\u201c\u8fdc\u79bb\u7f6a\u6076\u4e0e\u6b7b\u4ea1\u4e4b\u8def\uff01\n\u901a\u8fc7\u5ba3\u544a\u2018\u8036\u7a23\u662f\u4e3b\uff01\u2019\u6765\u9009\u62e9\u65b0\u7684\u751f\u547d\u548c\u65b0\u7684\u65b9\u5411\u3002\u201d\n\n\u4fdd\u7f57\u4e4b\u524d\u5199\u8fc7\u5173\u4e8e\u8fd9\u4e2a\u65b0\u65b9\u5411\u7684\u4e66\u4fe1\u3002\n\u90a3\u5c01\u4e66\u4fe1\u5199\u7ed9\u4e86\u4ee5\u5f17\u6240\u7684\u8fd9\u95f4\u6559\u4f1a\uff0c\u63d0\u6469\u592a\u73b0\u5728\u6b63\u5728\u90a3\u91cc\u62c5\u4efb\u7267\u5e08\u3002\n\u8bf7\u542c\u542c\u4fdd\u7f57\u5728\u4ee5\u5f17\u6240\u4e662\uff1a1-5\u4e2d\u5199\u7ed9\u57fa\u7763\u5f92\u7684\u8bdd\uff0c\u90a3\u91cc\u8bb2\u8ff0\u4e86\u795e\u5982\u4f55\u8d50\u7ed9\u4ed6\u4eec\u65b0\u751f\u547d\u548c\u65b0\u7684\u65b9\u5411\uff1a\n1 \u201c\u4f60\u4eec\u6b7b\u5728\u8fc7\u72af\u7f6a\u6076\u4e4b\u4e2d\uff0c\u4ed6\u53eb\u4f60\u4eec\u6d3b\u8fc7\u6765\u3002\n2 \u90a3\u65f6\uff0c\u4f60\u4eec\u5728\u5176\u4e2d\u884c\u4e8b\u4e3a\u4eba\uff0c\u968f\u4ece\u4eca\u4e16\u7684\u98ce\u4fd7\uff0c\u987a\u670d\u7a7a\u4e2d\u638c\u6743\u8005\u7684\u9996\u9886\uff0c\u5c31\u662f\u73b0\u4eca\u5728\u6096\u9006\u4e4b\u5b50\u5fc3\u4e2d\u8fd0\u884c\u7684\u90aa\u7075\u3002\n3 \u6211\u4eec\u4ece\u524d\u4e5f\u90fd\u5728\u4ed6\u4eec\u4e2d\u95f4\uff0c\u653e\u7eb5\u8089\u4f53\u7684\u79c1\u6b32\uff0c\u968f\u7740\u8089\u4f53\u548c\u5fc3\u4e2d\u6240\u559c\u597d\u7684\u53bb\u884c\uff0c\u672c\u4e3a\u53ef\u6012\u4e4b\u5b50\uff0c\u548c\u522b\u4eba\u4e00\u6837\u3002\n4 \u7136\u800c\u4e0a\u5e1d\u65e2\u6709\u4e30\u5bcc\u7684\u601c\u60af\uff0c\u56e0\u4ed6\u7231\u6211\u4eec\u7684\u5927\u7231\uff0c\n5 \u5f53\u6211\u4eec\u6b7b\u5728\u8fc7\u72af\u4e2d\u7684\u65f6\u5019\uff0c\u4fbf\u53eb\u6211\u4eec\u4e0e\u57fa\u7763\u4e00\u540c\u6d3b\u8fc7\u6765\uff08\u4f60\u4eec\u5f97\u6551\u662f\u672c\u4e4e\u6069\uff09\u3002\u201d\n\n\u201c\u7136\u800c\u4e0a\u5e1d\u201d\u662f\u6bcf\u4e2a\u4eba\u53ef\u4ee5\u8bf4\u51fa\u7684\u6700\u7f8e\u7684\u4e24\u4e2a\u8bcd\u3002\n\u4fdd\u7f57\u63d0\u9192\u4ee5\u5f17\u6240\u7684\u4fe1\u5f92\uff0c\u4ed6\u4eec\u66fe\u7ecf\u5c31\u50cf\u90a3\u53ea\u88ab\u56f0\u5728\u9677\u9631\u4e2d\u7684\u5154\u5b50\u4e00\u6837\u65e0\u52a9\u3002\n\u4f46\u4e0a\u5e1d\u4ecb\u5165\u8fdb\u6765\uff0c\u552f\u72ec\u51fa\u4e8e\u6069\u5178\uff0c\u552f\u72ec\u501f\u7740\u4fe1\u5fc3\uff0c\u552f\u72ec\u5728\u57fa\u7763\u91cc\u62ef\u6551\u4e86\u4ed6\u4eec\u3002\n\u4efb\u4f55\u4eba\u53ea\u8981\u76f8\u4fe1\u57fa\u7763\u5728\u5341\u5b57\u67b6\u4e0a\u727a\u7272\u662f\u4e3a\u4e86\u4f60\uff0c\u662f\u8981\u6d17\u51c0\u4f60\u7684\u7f6a\u548c\u7f9e\u803b\uff0c\u5c31\u90fd\u53ef\u4ee5\u5f97\u8499\u62ef\u6551\u3002\n\u5f53\u4f60\u76f8\u4fe1\u8fd9\u4e00\u70b9\u65f6\uff0c\u4f60\u4f1a\u83b7\u5f97\u65b0\u751f\u547d\uff0c\u8036\u7a23\u4f1a\u5f15\u5bfc\u4f60\u8d70\u4e0a\u4e00\u6761\u65b0\u7684\u9053\u8def\u3002\n\u51e0\u8282\u7ecf\u6587\u540e\uff0c\u5728\u4ee5\u5f17\u6240\u4e662\uff1a8\uff0c\u4fdd\u7f57\u8c08\u5230\u4e86\u8fd9\u4e2a\u65b0\u65b9\u5411\u3002\n\u548c\u6211\u4e00\u8d77\u8bfb\u8fd9\u6bb5\uff1a\n\u4f1a\u4f17\uff1a10 \u201c\u6211\u4eec\u539f\u662f\u4ed6\u7684\u5de5\u4f5c\uff0c\u5728\u57fa\u7763\u8036\u7a23\u91cc\u9020\u6210\u7684\uff0c\u4e3a\u8981\u53eb\u6211\u4eec\u884c\u5584\uff0c\u5c31\u662f\u4e0a\u5e1d\u6240\u9884\u5907\u53eb\u6211\u4eec\u884c\u7684\u3002\u201d\n\n\u4e3a\u4e86\u7ed3\u675f\u8fd9\u4e2a\u4fe1\u606f\uff0c\u8ba9\u6211\u4eec\u770b\u770b\u4ec0\u4e48\u662f\u884c\u5584\u3002\n\u8bb0\u4f4f\u4fdd\u7f57\u6b63\u5728\u5199\u4fe1\u7ed9\u63d0\u6469\u592a\uff0c\u6307\u5bfc\u4ed6\u9009\u62d4\u548c\u57f9\u8bad\u54ea\u4e9b\u4eba\u62c5\u4efb\u5723\u7ecf\u6559\u5e08\u3002\n\u5c06\u798f\u97f3\u7684\u597d\u6d88\u606f\u5206\u4eab\u7ed9\u8fd1\u5904\u548c\u8fdc\u65b9\u7684\u4eba\uff0c\u662f\u6211\u4eec\u4fe1\u5f92\u7684\u4f7f\u547d\u3002\n\u4f46\u8981\u5fe0\u5b9e\u5730\u505a\u5230\u8fd9\u4e00\u70b9\uff0c\u6211\u4eec\u5fc5\u987b\u8981\u6709\u4fdd\u7f57\u5728\u8fd9\u4e9b\u7ecf\u6587\u4e2d\u6240\u63cf\u8ff0\u7684\u54c1\u683c\u3002\n\u6211\u4eec\u65e0\u6cd5\u6539\u53d8\u4efb\u4f55\u4eba\u7684\u5fc3\u3002\n\u4f46\u6211\u4eec\u53ef\u4ee5\u6e29\u67d4\u3001\u5584\u610f\u3001\u8010\u5fc3\u5730\u544a\u8bc9\u4ed6\u4eec\u771f\u7406\u3002\n\u6211\u4eec\u53ef\u4ee5\u76f8\u4fe1\u4e0a\u5e1d\u4f1a\u5728\u5408\u9002\u7684\u65f6\u5019\u8d50\u4e88\u7942\u6240\u62e3\u9009\u7684\u5b69\u5b50\u4eec\u6094\u6539\u7684\u6069\u8d50\u3002\n\u5728\u4eca\u5929\u7ecf\u6587\u7684\u7b2c24\u548c25\u8282\u4e2d\uff0c\u6211\u770b\u5230\u795e\u5e0c\u671b\u5728\u4ed6\u4ec6\u4eba\u8eab\u4e0a\u57f9\u517b\u7684\u4e94\u79cd\u54c1\u8d28\uff1a\n\n\u54c1\u8d281\uff1a\u4e0d\u53ef\u4e89\u7ade\u3002\n\u6709\u4e9b\u4eba\u559c\u6b22\u4e89\u8bba\u3002\n\u5065\u5eb7\u7684\u8fa9\u8bba\u672c\u6ca1\u6709\u9519\u3002\n\u4f46\u4f60\u600e\u4e48\u77e5\u9053\u81ea\u5df1\u662f\u5728\u7f6a\u6076\u5730\u201c\u4e89\u7ade\u201d\u5462\uff1f\n\u4e5f\u8bb8\u4f60\u53ef\u4ee5\u95ee\u81ea\u5df1\u8fd9\u4e2a\u95ee\u9898\uff1a\n\u201c\u6211\u5728\u548c\u522b\u4eba\u4e89\u8bba\u7684\u65f6\u5019\uff0c\u66f4\u5728\u4e4e\u90a3\u4e2a\u4eba\uff0c\u8fd8\u662f\u66f4\u5728\u4e4e\u8d62\u5f97\u4e89\u8bba\uff1f\n\u96be\u9053\u6211\u7684\u9a84\u50b2\u8ba9\u6211\u53ea\u5728\u4e4e\u8bc1\u660e\u81ea\u5df1\u662f\u5bf9\u7684\uff0c\u800c\u4e0d\u5728\u4e4e\u5f85\u4eba\u53cb\u5584\u5417\uff1f\u201d\n\n\u54c1\u8d282\uff1a\u5584\u5f85\u6bcf\u4e00\u4e2a\u4eba\u3002\n\u4e3b\u7684\u4ec6\u4eba\u5fc5\u987b\u5584\u5f85\u6bcf\u4e00\u4e2a\u4eba\u3002\n\u5373\u4f7f\u662f\u5bf9\u90a3\u4e9b\u6068\u4f60\u3001\u60f3\u4f24\u5bb3\u4f60\u7684\u4eba\u3002\n\u8fd9\u5f88\u96be\uff0c\u6211\u77e5\u9053\u3002\n\u6211\u4eec\u8ba4\u4e3a\u4fdd\u62a4\u81ea\u5df1\u514d\u53d7\u4ed6\u4eba\u4f24\u5bb3\u7684\u65b9\u6cd5\u5c31\u662f\u575a\u5f3a\uff0c\u4f7f\u7528\u6743\u529b\u3002\n\u4f46\u770b\u770b\u4fdd\u7f57\u5728\u7f57\u9a6c\u4e662\uff1a4\u4e2d\u63d0\u9192\u6211\u4eec\u7684\u8bdd\uff1a\n\u201c\u4ed6\u7684\u6069\u6148\u662f\u9886\u4f60\u6094\u6539\u5462\u3002\u201d\n\u5f53\u4f60\u72af\u7f6a\u3001\u8fdc\u79bb\u8036\u7a23\u65f6\uff0c\u8036\u7a23\u5bf9\u4f60\u6709\u591a\u6069\u6148\uff1f\n\u4ed6\u7684\u6069\u6148\u662f\u8981\u9886\u4f60\u6094\u6539\uff0c\n\u6240\u4ee5\u73b0\u5728\u4f60\u6709\u673a\u4f1a\u6548\u6cd5\u57fa\u7763\uff0c\u5584\u5f85\u6bcf\u4e00\u4e2a\u4eba\u3002\n\n\u54c1\u8d28\u4e09\uff1a\u8010\u5fc3\u5fcd\u53d7\u90aa\u6076\u3002\n\u5f53\u6211\u4eec\u5206\u4eab\u798f\u97f3\u7684\u771f\u7406\u65f6\uff0c\u4f1a\u9047\u5230\u4e0d\u559c\u6b22\u6211\u4eec\u6240\u8bf4\u5185\u5bb9\u7684\u4eba\u53cd\u5bf9\u6211\u4eec\u3002\n\u4f60\u8fd8\u8bb0\u5f97\u53f8\u63d0\u53cd\u5bf9\u6740\u4ed6\u7684\u4eba\u662f\u600e\u4e48\u8bf4\u7684\u5417\uff1f\n\u4f7f\u5f92\u884c\u4f207\uff1a59\u201360\u8bf4\uff1a\n59 \u201c\u4ed6\u4eec\u6b63\u7528\u77f3\u5934\u6253\u7684\u65f6\u5019\uff0c\u53f8\u63d0\u53cd\u547c\u5401\u4e3b\u8bf4\uff1a\u2018\u6c42\u4e3b\u8036\u7a23\u63a5\u6536\u6211\u7684\u7075\u9b42\uff01\u2019\n60 \u53c8\u8dea\u4e0b\u5927\u58f0\u558a\u7740\u8bf4\uff1a\u2018\u4e3b\u554a\uff0c\u4e0d\u8981\u5c06\u8fd9\u7f6a\u5f52\u4e8e\u4ed6\u4eec\uff01\u2019\u201d\n\n\u53ea\u6709\u4e0a\u5e1d\u80fd\u50cf\u53f8\u63d0\u53cd\u90a3\u6837\u8010\u5fc3\u5fcd\u53d7\u90aa\u6076\u3002\n\u4f46\u5f53\u6211\u4eec\u5728\u56f0\u96be\u65f6\u523b\u547c\u5524\u4ed6\u65f6\uff0c\u4ed6\u4f1a\u5e2e\u52a9\u6211\u4eec\u3002\n\u7942\u4f1a\u5e2e\u52a9\u6211\u4eec\u4fe1\u9760\u7942\uff0c\u77e5\u9053\u65e0\u8bba\u6211\u4eec\u7684\u8eab\u4f53\u5982\u4f55\uff0c\u7075\u9b42\u90fd\u88ab\u5b89\u5168\u5730\u4ea4\u6258\u5728\u7942\u7684\u624b\u91cc\u4e86\u3002\n\n\u54c1\u8d284\uff1a\u4ee5\u6e29\u548c\u7684\u6001\u5ea6\u7ea0\u6b63\u3002\n\u7ea0\u6b63\u522b\u4eba\u5f88\u96be\u3002\n\u4f46\u5982\u679c\u6211\u513f\u5b50\u505a\u9519\u4e86\u4ec0\u4e48\uff0c\u6211\u4f1a\u544a\u8bc9\u4ed6\uff0c\u56e0\u4e3a\u6211\u7231\u4ed6\u3002\n\u8fd9\u662f\u4f60\u9700\u8981\u7ea0\u6b63\u67d0\u522b\u4eba\u65f6\u9700\u8981\u601d\u8003\u7684\u91cd\u8981\u95ee\u9898\uff1a\n\u201c\u6211\u7684\u5b69\u5b50\u3001\u670b\u53cb\u6216\u914d\u5076\u611f\u53d7\u5230\u6211\u7684\u7231\u4e86\u5417\uff1f\n\u8fd8\u662f\u4ed6\u4eec\u53ea\u611f\u53d7\u5230\u6211\u7684\u6124\u6012\uff1f\u201d\n\n\u5f53\u6211\u4eec\u7528\u6124\u6012\u6216\u632b\u8d25\u611f\u6765\u7ea0\u6b63\u65f6\uff0c\u6211\u4eec\u8868\u73b0\u5f97\u597d\u50cf\u4e0a\u5e1d\u65e0\u6cd5\u6539\u53d8\u5bf9\u65b9\u3002\n\u6211\u4eec\u4ee5\u4e3a\u53ef\u4ee5\u65bd\u538b\u8ba9\u4ed6\u4eec\u6539\u53d8\uff0c\u6216\u8005\u66f4\u5927\u58f0\u558a\u53eb\uff0c\u76f4\u5230\u4ed6\u4eec\u8d70\u4e0a\u6b63\u786e\u7684\u9053\u8def\u3002\n\u4f46\u4e00\u4f4d\u77e5\u9053\u4e0a\u5e1d\u62e5\u6709\u771f\u6b63\u6743\u80fd\u7684\u8001\u5e08\uff0c\u4f1a\u6e29\u67d4\u3001\u8010\u5fc3\u548c\u5584\u826f\u3002\n\n\u54c1\u8d285\uff1a\u80fd\u591f\u6559\u5bfc\u3002\n\u4f60\u662f\u5426\u8db3\u591f\u7406\u89e3\u795e\u7684\u8bdd\u8bed\uff0c\u4ee5\u81f3\u4e8e\u80fd\u591f\u5411\u4ed6\u4eba\u89e3\u91ca\uff1f\n\u4f60\u5728\u80cc\u8bf5\u7ecf\u6587\uff0c\u4ee5\u4fbf\u968f\u65f6\u5f15\u5bfc\u4f60\u7684\u751f\u6d3b\u5e76\u4e0e\u4ed6\u4eba\u5206\u4eab\u5417\uff1f\n\u6211\u4eec\u8fd9\u4e2a\u6708\u5c06\u5f00\u59cb\u4e00\u4e9b\u65b0\u7684\u4e8b\u60c5\u3002\n\u6211\u4eec\u8981\u4f60\u5728\u4e09\u6708\u5e95\u524d\u80cc\u8bf5\u4e00\u8282\u7ecf\u6587\u3002\n\u5982\u679c\u4f60\u80fd\u7528\u4efb\u4f55\u8bed\u8a00\u80cc\u7ed9\u6211\u4eec\u7684\u9886\u8896\uff0c\u4f60\u4f1a\u5f97\u5230\u4e00\u4e2a\u8d34\u7eb8\u3002\n\u4f60\u53ef\u4ee5\u628a\u5b83\u653e\u5728\u6c34\u74f6\u6216\u7b14\u8bb0\u672c\u4e0a\u3002\n\u4efb\u4f55\u4f60\u80fd\u770b\u5230\u7684\u5730\u65b9\u90fd\u53ef\u4ee5\uff0c\u8fd9\u6837\u4f60\u5168\u5e74\u90fd\u53ef\u4ee5\u6301\u7eed\u7ec3\u4e60\u3002\n\u8ba9\u6211\u4eec\u4e00\u8d77\u8bfb\u4e00\u4e0b\u63d0\u6469\u592a\u540e\u4e663\uff1a16\u8fd9\u5904\u4e09\u6708\u8981\u80cc\u7684\u7ecf\u6587\u3002\n\u4f1a\u4f17\uff1a\u201c\u5723\u7ecf\u90fd\u662f\u4e0a\u5e1d\u6240\u9ed8\u793a\u7684\uff0c\u4e8e\u6559\u8bad\u3001\u7763\u8d23\u3001\u4f7f\u4eba\u5f52\u6b63\u3001\u6559\u5bfc\u4eba\u5b66\u4e49\u90fd\u662f\u6709\u76ca\u7684\u3002\u201d\n\n\u6211\u4eec\u90fd\u9700\u8981\u5e2e\u52a9\uff0c\u7ee7\u7eed\u671d\u7740\u6b63\u786e\u7684\u65b9\u5411\u5954\u8dd1\u3002\n\u6211\u4eec\u9700\u8981\u795e\u7684\u8bdd\u8bed\u6765\u6559\u5bfc\u3001\u7ea0\u6b63\u548c\u8bad\u7ec3\u6211\u4eec\u8ba9\u6211\u4eec\u884c\u5728\u4e49\u4e2d\u3002\n\u6211\u4eec\u9700\u8981\u5723\u7075\u5e2e\u52a9\u6211\u4eec\u7406\u89e3\u5e76\u5e94\u7528\u5723\u7ecf\u7684\u8bdd\uff0c\u6240\u4ee5\u8ba9\u6211\u4eec\u73b0\u5728\u5c06\u5fc3\u8f6c\u5411\u5929\u5802\uff0c\u4e00\u8d77\u6765\u7977\u544a\u3002\n\u8036\u7a23\uff0c\u6211\u4eec\u4e4b\u6240\u4ee5\u80fd\u4e0e\u7236\u8bf4\u8bdd\uff0c\u90fd\u662f\u56e0\u4e3a\u4f60\u5728\u5730\u4e0a\u548c\u5929\u5802\u4e4b\u95f4\u67b6\u8d77\u4e86\u4e00\u5ea7\u6865\u6881\u3002\n\u4f60\u6467\u6bc1\u4e86\u9b54\u9b3c\u7684\u9677\u9631\uff0c\u8ba9\u6211\u4eec\u770b\u6e05\u4e86\u771f\u76f8\u3002\n\u5929\u7236\uff0c\u611f\u8c22\u4f60\u8d50\u7ed9\u6211\u4eec\u6094\u6539\u7684\u793c\u7269\uff0c\u8ba9\u6211\u4eec\u80fd\u5bf9\u81ea\u5df1\u548c\u4f60\u5766\u9648\u6211\u4eec\u7684\u7f6a\u3002\n\u611f\u8c22\u5723\u7075\uff0c\u8d50\u7ed9\u6211\u4eec\u4fe1\u5fc3\uff0c\u8ba9\u6211\u4eec\u8f6c\u5411\u8036\u7a23\u5bfb\u6c42\u6551\u8d4e\u3002\n\u6c42\u4f60\u6253\u5f00\u6211\u4eec\u7684\u5934\u8111\u548c\u5185\u5fc3\uff0c\u53eb\u6211\u4eec\u7406\u89e3\u5723\u7ecf\u7684\u8bdd\u8bed\u5e76\u5e94\u7528\u5230\u6211\u4eec\u7684\u751f\u6d3b\u4e2d\u3002\n\u6c42\u4f60\u5e2e\u52a9\u6211\u4eec\u62fc\u547d\u8dd1\u5b8c\u8fd9\u573a\u5145\u6ee1\u6311\u6218\u7684\u6bd4\u8d5b\uff0c\u5e76\u9080\u8bf7\u4ed6\u4eba\u52a0\u5165\u6211\u4eec\uff0c\u4e00\u8d77\u8e0f\u4e0a\u901a\u5f80\u5065\u5168\u3001\u76fc\u671b\u548c\u5929\u5802\u7684\u65c5\u7a0b\uff0c\u963f\u4eec\u3002\n\n\u4f9b\u9ed8\u60f3\u548c\u8ba8\u8bba\u7684\u95ee\u9898\n1.  \u8bfb\u63d0\u6469\u592a\u540e\u4e662\uff1a22\u548c\u8bd7\u7bc7119\uff1a35-37\u3002\na\uff09 \u5f53\u4f60\u611f\u5230\u538b\u529b\u6216\u5bfb\u6c42\u5b89\u6170\u65f6\uff0c\u4f60\u7684\u5185\u5fc3\u81ea\u7136\u4f1a\u8dd1\u5411\u54ea\u4e9b\u201c\u5c11\u5e74\u7684\u79c1\u6b32\u201d\uff08\u4eab\u4e50\u3001\u6743\u529b\u3001\u53d7\u4eba\u8ffd\u6367\u3001\u8d22\u5bcc\u3001\u9a84\u50b2\uff09\uff1f\n\n2.  \u8bfb\u4ee5\u5f17\u6240\u4e662\uff1a1-5\u548c\u4ee5\u897f\u7ed3\u4e6636\uff1a26\u3002\na\uff09\u4ece\u201c\u6b7b\u201d\u5230\u201c\u6d3b\u201d\u9700\u8981\u4ec0\u4e48\uff1f\nb\uff09\u76f8\u4fe1\u6094\u6539\u662f\u6069\u5178\u7684\u6069\u8d50\uff0c\u662f\u5426\u5e2e\u52a9\u4f60\u5bf9\u4e0a\u5e1d\u66f4\u8bda\u5b9e\u5730\u5766\u9648\u4f60\u7684\u7f6a\uff1f\n\n3.  \u8bf7\u9605\u8bfb\u63d0\u6469\u592a\u540e\u4e662\uff1a23-25a\u548c\u6b4c\u7f57\u897f\u4e663\uff1a12-14\u3002\na\uff09\u5728\u8fa9\u8bba\u6216\u7ea0\u6b63\u4ed6\u4eba\u65f6\uff0c\u201c\u4e3b\u7684\u4ec6\u4eba\u201d\u5177\u5907\u54ea\u4e9b\u54c1\u8d28\uff1f\nb\uff09\u56e0\u4e3a\u8036\u7a23\u4ee5\u6781\u5927\u7684\u8010\u5fc3\u548c\u6e29\u67d4\u7231\u6211\u4eec\uff0c\u4f60\u4f1a\u7528\u540c\u6837\u7684\u6069\u5178\u53bb\u7231\u751f\u547d\u4e2d\u7684\u54ea\u4e9b\u4eba\u2014\u2014\u5373\u4f7f\u4ed6\u4eec\u4e0d\u8d5e\u540c\u4f60\u4e5f\u4e0d\u559c\u6b22\u4f60\uff1f\n\n4.  \u8bfb\u7f57\u9a6c\u4e6610\uff1a9-11\u548c\u5e0c\u4f2f\u6765\u4e6612\uff1a1-2\u3002\na\uff09\u5b9a\u89c6\u8036\u7a23\u5982\u4f55\u5e2e\u52a9\u6211\u4eec\u8fdc\u79bb\u7f6a\u6076\uff0c\u8d70\u5411\u65b0\u7684\u65b9\u5411\uff1f\nb\uff09\u8bb0\u5f97\u80cc\u8bf5\u63d0\u6469\u592a\u540e\u4e663\uff1a16\u3002\u8ba4\u8bc6\u795e\u7684\u8bdd\u8bed\u5982\u4f55\u5e2e\u52a9\u6211\u4eec\u8dd1\u5b8c\u4fe1\u5fc3\u7684\u9a6c\u62c9\u677e\uff1f","english_content":"Where are you running?\n2 Timothy 2:22-26\nPastor Chris Sicks\nMarch 15, 2026\n\nAt the 2019 Marathon in Portland Oregon, some of the best runners actually lost the race.\nNot because they were slow, but because they went the wrong way.\nThere was a turn on the course that was not marked clearly.\nSo about 20 of the fastest runners ran more than a mile in the wrong direction!\nThe mistake added precious minutes to a race they had spent months preparing to run.\nThose men and women ran hard, and they ran fast.\nBut they lost the race, because they were on the wrong path.\nTonight we are continuing a sermon series in the book of 2 Timothy.\nThe apostle Paul is writing to Timothy, a young pastor of the Christian church in Ephesus.\nPaul is providing Timothy, and us today, with advice about how to stay on the correct path.\n2 Timothy 2:22\u201326\n22 \u201cSo flee youthful passions and pursue righteousness, faith, love, and peace, along with those who call on the Lord from a pure heart.\n23 Have nothing to do with foolish, ignorant controversies; you know that they breed quarrels.\n24 And the Lord\u2019s servant must not be quarrelsome but kind to everyone, able to teach, patiently enduring evil, \n25 correcting his opponents with gentleness.\nGod may perhaps grant them repentance leading to a knowledge of the truth, \n26 and they may come to their senses and escape from the snare of the devil, after being captured by him to do his will.\u201d\n\nTogether we read Isaiah 40:8:\n\"The grass withers, the flower fades, but the word of our God will stand forever.\u201d\n\nVerse 22 says: \n22 \"So flee youthful passions and pursue righteousness, faith, love, and peace, along with those who call on the Lord from a pure heart.\"\n\nThis verse is really a summary of today's sermon.\nWe see this often in God's Word.\nSometimes the first statement in a Psalm or a paragraph will be a summary.\nThen the words that follow are an explanation of the entire Psalm or paragraph or chapter.\nA mature Christian man or woman is someone who walks away from the things that tempted us when we were younger.\nInstead of \u201cyouthful passions\u201d a mature person is learning to pursue God\u2019s values, including Righteousness, Faith, Love, Peace.\nWhen Paul was a young man, he was named Saul.\nSaul was full of pride and self-confidence, using power to persecute Christians and put them in jail.\nSaul wanted to be popular and successful and was willing to hurt others because of his own pride.\nBut the letter of 2 Timothy was written by Paul the mature believer.\nHe understands how much damage his youthful passions did, and is warning Timothy about them. \nAt the time Paul writes this letter, Timothy is probably around 40 years old.\nBut you don't have to be young to run toward \"youthful passions.\u201d\nI am 57, but I am still learning to consistently flee from youthful passions.\nI have a friend from college who is the same age as me.\nBut he still lives like he did 35 years ago.\nHis life is dominated by the youthful passions of our college days.\nHere are some youthful passions many of us experience:\n\n* Pleasure: Sexual sin is a common example of the sin of pleasure, but it isn\u2019t the only one.\nOther sinful pleasures can include alcohol, food, and many kinds of entertainment.\nThese things are not bad if they are used correctly.\nSex, for example, is a beautiful gift in the context of Christian marriage.\nBut when we use anything the wrong way, we give it power over our lives.\nWhen we use any of God\u2019s gifts to fill the emptiness in our hearts, that thing becomes a false god--an idol.\n\n* Power: When we are young, we sometimes feel powerless, weak, or inadequate.\nI struggled with those feelings as a teenager.\nSome people pursue power to cover their feelings of weakness.\nThey think acting strong will help them feel safe.\nDid you know that a bully isn\u2019t actually as tough as he appears?\nA bully is usually someone who feels powerless about something in his life, so he hurts other people to make himself feel powerful.\n\n* Popularity: This has been another strong temptation in my life.\nI frequently worry if people like me.\nI care too much about the opinions of other people.\nHow about you?\nDo you ever change your behavior or appearance to make people like you?\nDo you think you have to act or look a certain way to avoid rejection?\n\n* Possessions: The love of money and material possessions is a problem for most of us.\nWe want the security and comfort of having more stuff.\nThis reveals a lack of faith.\nGod wants us to understand that he is our shelter and fortress, he is our provider.\nMaterial things promise happiness, but they can never keep their promise.\nBecause our hearts will always crave more.\n\n* Pride: This is really the sin underneath every other sin.\nPride is the belief that I actually deserve possessions, power, pleasure, and popularity.\nWhy? Because I am special.\nPride whispers lies to us, saying: \n\"It's okay, you can do that--You deserve it.\u201d\nAdvertisers say the same thing to us.\n\"You deserve it\u2026Go ahead, buy it.\nMaybe buy some more, it's okay.\u201d\nThat's why we see so many advertisements like this, because our pride actually wants to believe these things.\n\nMay I ask you a question my friends?\nWhich of these five things sounds familiar to you?\nAre you pursuing pride, possessions, power, pleasure, or popularity?\nOr maybe it is something else that leads you away from God?\nWhere is your heart today, and where are you going?\nDo you remember what God asked Adam in the garden, after he ate the fruit?\nAdam and Eve were hiding, and God said, \"Where are you, Adam?\" \nGod is asking the same thing to everyone on earth today.\nWhere are you?\nHe is not asking where you are physically.\nHe is asking, \"where is your heart?\" \nBecause our hearts are like a compass that leads us down the path toward the thing we value the most.\nWe get lost and we don\u2019t even know it because sin is sneaky.\nWe need God\u2019s help to see what\u2019s going on inside of us.\nLet\u2019s read Psalm 139:23\u201324 together, as a prayer: \nALL: 23 \u201cSearch me, O God, and know my heart!\nTest me and know my thoughts!\n24 And see if there be any grievous way in me,\nand lead me in the way everlasting!\u201d\n\nWithout God\u2019s help, we will not walk \u201cin the way everlasting.\u201d\nWe will run in the wrong direction, pursuing things that take us far from God\u2019s heart.\nBut God is so good that doesn\u2019t just watch us wander away and get lost.\nInstead, he seeks out His lost sheep.\nHe comes to us and offers a path of escape and rescue.\nLook at 2 Timothy 2:25b-26 again: \n25b \u201cGod may perhaps grant them repentance leading to a knowledge of the truth, \n26 and they may come to their senses and escape from the snare of the devil, after being captured by him to do his will.\u201d\n\nDid you know it is possible to feel completely free, when you are actually trapped by sin and the devil?\nSin feels like freedom, but it is the opposite.\nA snare looks like this.\nIt is a trap that grabs an animal that was running freely down a path, and then was suddenly in danger.\nSatan places lies like signs on the marathon course, to deceive and trap us. \nSatan wants us to run after Pleasure, Power, Popularity, Possessions, and Pride.\nThese idols promise us freedom, and freedom is what we want very much.\nUnfortunately, we believe such things can help us feel satisfied, safe, happy.\nBut these idols are traps that keep us from God and the path of true life.\nSatan wants to hide the path of life from us, saying: \n\u201cGo this way to victory and happiness!\nYes, that\u2019s the way! Follow me!\" \n\nSo, how can an animal escape a trap like this?\nIs it something he can do by himself?\nNo, the rabbit is helpless.\nHe needs someone smarter and stronger to come and get him out of the trap.\nWe need someone smarter and stronger to rescue us, too.\nThat is the most-important point I want you to see about this verse.\nWe need a Rescuer because we cannot save ourselves or even turn to God.\nHearts that are spiritually dead cannot choose life.\nLook at what verse 25 says: \n\"God may perhaps grant them repentance.\"\n\nA grant is a free gift.\nGod gave me the gift of repentance 30 years ago.\nFor 10 years I said there was no God in the universe.\nBut because God is kind, he showed me that beer, women, and earthly success could never satisfy the desires of my heart.\nThat's what \"come to their senses\" means in verse 26.\nWhen your sense of direction is confused you run in the wrong direction.\nThe first step to finding your way home is to recognize that you are lost.\nDan McDowell was one of the lost runners in that marathon in Portland.\nHe said: \u201cI came around the corner and saw 10 people just standing still\u2026 \nThey were looking at each other thinking \u2018Uh, this doesn\u2019t feel right.\u2019\u201d\n\nAnother runner, Zach Custer, said he entered a tunnel where cars zoomed past him at 55 miles per hour.\nThat\u2019s when he realized he had gone off course.\nBefore God brought me to my senses I thought I had \"knowledge of the truth.\u201d\nMy pride told me I was right path, and I didn\u2019t need any God to guide me because I was so smart.\nIronically, I was too stupid to see Satan's deception.\nI was captured in his snare of lies.\nI believed the devil's promise that I would find happiness running away from God.\nBut then, God gave me the gift of repentance.\nThe Greek word here for repentance is metanoia.\nIt means \"a change of mind, a change of life, and a change of purpose.\"\nJesus gave me a new heart so I could \"call on the Lord from a pure heart\" as verse 22 says.\nA pure heart is an honest heart.\nA heart that calls out to God, \"I am sorry for my sin, please forgive me.\nHelp me run toward you, not away from you.\"\nPaul wrote in Romans 10:9\u201311 a very clear explanation of how you can turn toward God and be saved \n9 \u201cIf you declare with your mouth, \u201cJesus is Lord,\u201d and believe in your heart that God raised him from the dead, you will be saved.\n10 For it is with your heart that you believe and are justified, and it is with your mouth that you profess your faith and are saved.\n11 As Scripture says, \u201cAnyone who believes in him will never be put to shame.\u201d\n\nHave you professed faith with your mouth, so you can be saved?\nIf you haven\u2019t, don\u2019t you think today would be a great day to do that?\nThe Holy Spirit is here among us, and perhaps he is whispering to your heart: \n\u201cTurn from the path of sin and death!\nChoose new life and a new direction, by declaring that \u2018Jesus is Lord!\u2019\u201d\n\nPaul wrote once before about that new direction.\nIt was in a letter to this same church in Ephesus, where Timothy is now serving as a pastor.\nListen to what Paul wrote to the Christian believers in Ephesians 2:1-5, about what God did to give them new life and a new direction: \n1 \"And you were dead in the trespasses and sins\n2 in which you once walked, following the course of this world, following the prince of the power of the air, the spirit that is now at work in the sons of disobedience--\n3 among whom we all once lived in the passions of our flesh, carrying out the desires of the body and the mind, and were by nature children of wrath, like the rest of mankind.\n4 But God, being rich in mercy, because of the great love with which he loved us,\n5 even when we were dead in our trespasses, made us alive together with Christ--by grace you have been saved!\"\n\n\u201cBut God\u201d are two of the most-beautiful words every spoken.\nPaul reminds the believers in Ephesus that they were once trapped and helpless like that rabbit in the snare.\nBut God stepped in to save them by grace alone, through faith alone, in Christ alone.\nAnyone can be saved, if you believe that Christ\u2019s sacrifice on the cross was for you, to wash you of sin and shame. \nWhen you believe that, you receive new life and Jesus puts you on a new path.\nA few verses later in Ephesians 2:8, Paul talks about that new direction.\nRead this together with me: \nALL: 10 \u201cFor we are his workmanship, created in Christ Jesus for good works, which God prepared beforehand, that we should walk in them.\u201d\n\nTo finish this message, let's look at what it looks like to walk in good works.\nRemember that Paul is writing to Timothy giving him guidance about who to select and train as Bible teachers.\nAnd our mission as believers is to share the Good News of the gospel with people both near and far.\nBut to do that faithfully, we must have the character Paul describes in these verses.\nWe cannot change the heart of anyone.\nBut we can tell them the truth gently, kindly, and patiently.\nAnd we can trust that God will grant repentance to his chosen children at the right time.\nIn verses 24 and 25 of today\u2019s passage I see five qualities God wants to develop in his servants: \n\nQuality 1: Not quarrelsome.\nSome people like to argue.\nThere is nothing wrong with healthy debate.\nBut how do you know when you are being sinfully \u201cquarrelsome\u201d?\nMaybe you can ask yourself this question: \n\u201cWhen am I arguing with someone, do I care more about that person, or about winning the argument?\nIs my pride causing me to focus on being right, instead of being kind?\u201d\n\nQuality 2: Kind to everyone.\nThe Lord's servant must be kind to everyone.\nEven to people who hate you and want to hurt you.\nThat's hard, I know.\nWe think that the way to protect ourselves from other people is to be strong, to use power.\nBut look at what Paul reminds us in Romans 2:4, that: \n\u201cGod\u2019s kindness is intended to lead you to repentance.\u201d\nHow kind was Jesus to you, when you were in sin and running far from him?\nHis kindness led you to repent,\nSo now you have the opportunity to imitate Christ, and be kind to everyone.\n\nQuality 3: Patiently enduring evil.\nWhen we are sharing the truth of the gospel, we will experience opposition from people who don\u2019t like what we are saying.\nDo you remember how Stephen responded to the people who killed him?\nActs 7:59\u201360 says: \n59 While they were stoning him, Stephen prayed, \u201cLord Jesus, receive my spirit.\u201d\n60 Then he fell on his knees and cried out, \u201cLord, do not hold this sin against them.\u201d\n\nOnly God can help us patiently endure evil like Stephen did.\nBut he will help us, when we call out to him in times of trouble.\nHe will help us trust Him, knowing our souls are safe in his hands, no matter what happens to our bodies.\n\nQuality 4: Correcting with gentleness.\nCorrecting people is hard.\nBut if my son is doing something wrong, I tell him because I love him.\nHere is the important question to think about when you have to correct someone: \n\u201cDoes my child, friend, or spouse feel my love?\nOr do they only feel my anger?\u201d\n\nWhen we correct with anger or frustration, we are acting like God can\u2019t change the other person.\nWe think we can pressure them to change, or shout louder until they get on the right path.\nBut a teacher who knows that God has the real power will be gentle, patient, and kind.\n\nQuality 5: Able to teach.\nDo you understand the Word of God well enough to explain it to others?\nAre you memorizing scripture, so you have it ready to guide you in life and to share with others?\nWe are going to start something new this month.\nWe are going to ask you to memorize one verse of scripture by the end of March.\nAnd if you can recite it to one of our leaders, in any language, you\u2019ll get a sticker.\nYou can put it on your water bottle or notebook.\nAnywhere that you\u2019ll see it and continue to practice it all year.\nLet\u2019s read together the verse for the month of March, 2 Timothy 3:16. \nALL: \u201cAll Scripture is God-breathed and is useful for teaching, rebuking, correcting and training in righteousness\u201d\n\nWe all need help, to keep running in the right direction.\nWe need the Word of God to teach, correct, and train us to walk in righteousness.\nAnd we need the Holy Spirit to help us understand and apply the Word, so let\u2019s turn our hearts to heaven now in prayer.\nJesus, we can only talk to the Father because you built a bridge between earth and heaven.\nYou destroyed the snares of the devil and opened our eyes to the truth.\nFather, thank you for giving us the gift of repentance, so we can be honest with ourselves and with you about our sin.\nAnd thank you, Holy Spirit, for giving us faith to turn to Jesus for our salvation.\nOpen our minds and hearts to understand and apply the Word to our lives.\nHelp us run hard the race set before us, inviting others to join us on the journey to wholeness, and hope, and heaven, amen.\n\nQuestions for Meditation and Discussion\n1) Read 2 Timothy 2:22 and Psalm 119:35-37.\na) Which of the \"youthful passions\" (Pleasure, Power, Popularity, Possessions, Pride) do you find your heart naturally running toward when you are stressed or seeking comfort?\n\n2) Read Ephesians 2:1-5 and Ezekiel 36:26.\na) What is necessary to go from being \"dead\" to \"alive\"?\nb) Does believing that repentance is a gift of grace help you be more honest with God about your sin?\n\n3) Read 2 Timothy 2:23-25a and Colossians 3:12-14.\na) What are the qualities of the \"Lord's servant\" when debating or correcting others?\nb) Because Jesus loved us with great patience and gentleness, who in your life will you love with that same grace--even if they disagree with you or don\u2019t like you?\n\n4) Read Romans 10:9-11 and Hebrews 12:1-2.\na) How does fixing our eyes on Jesus help us turn from sin and run in a new direction?\nb) Remember to memorize 2 Timothy 3:16. How does knowing the Word of God help us run the marathon of faith?","farsi-dari_content":"\u06a9\u062c\u0627 \u0641\u0631\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u061f\n\u062f\u0648\u0645 \u062a\u06cc\u0645\u0648\u062a\u0627\u0626\u0648\u0633 \u06f2:\u06f2\u06f2-\u06f2\u06f6\n\u06a9\u0634\u06cc\u0634 \u06a9\u0631\u06cc\u0633 \u0633\u06cc\u06a9\u0633\n\u06f1\u06f5 \u0645\u0627\u0631\u0633 \u06f2\u06f0\u06f2\u06f6\n\n\u062f\u0631 \u0645\u0627\u0631\u0627\u062a\u0646 \u06f2\u06f0\u06f1\u06f9 \u062f\u0631 \u067e\u0648\u0631\u062a\u0644\u0646\u062f\u060c \u0627\u0648\u0631\u06af\u0627\u0646\u060c \u0628\u0631\u062e\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u062f\u0648\u0646\u062f\u06af\u0627\u0646 \u0648\u0627\u0642\u0639\u0627\u064b \u0645\u0633\u0627\u0628\u0642\u0647 \u0631\u0627 \u0628\u0627\u062e\u062a\u0646\u062f.\n\u0646\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u06a9\u0647 \u06a9\u0646\u062f \u0628\u0648\u062f\u0646\u062f\u060c \u0628\u0644\u06a9\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u06a9\u0647 \u0631\u0627\u0647 \u0631\u0627 \u0627\u0634\u062a\u0628\u0627\u0647 \u0631\u0641\u062a\u0646\u062f.\n\u06cc\u06a9 \u067e\u06cc\u0686 \u062f\u0631 \u0645\u0633\u06cc\u0631 \u0648\u062c\u0648\u062f \u062f\u0627\u0634\u062a \u06a9\u0647 \u0628\u0647 \u0637\u0648\u0631 \u0648\u0627\u0636\u062d \u0639\u0644\u0627\u0645\u062a \u06af\u0630\u0627\u0631\u06cc \u0646\u0634\u062f\u0647 \u0628\u0648\u062f.\n\u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u062d\u062f\u0648\u062f \u06f2\u06f0 \u0646\u0641\u0631 \u0627\u0632 \u0633\u0631\u06cc\u0639\u200c\u062a\u0631\u06cc\u0646 \u062f\u0648\u0646\u062f\u06af\u0627\u0646 \u0628\u06cc\u0634 \u0627\u0632 \u06cc\u06a9 \u0645\u0627\u06cc\u0644 \u062f\u0631 \u062c\u0647\u062a \u0627\u0634\u062a\u0628\u0627\u0647 \u062f\u0648\u06cc\u062f\u0646\u062f!\n\u0627\u06cc\u0646 \u0627\u0634\u062a\u0628\u0627\u0647 \u062f\u0642\u0627\u06cc\u0642 \u06af\u0631\u0627\u0646\u0628\u0647\u0627\u06cc\u06cc \u0631\u0627 \u0628\u0647 \u0645\u0633\u0627\u0628\u0642\u0647\u200c\u0627\u06cc \u06a9\u0647 \u0645\u0627\u0647\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u0622\u0646 \u0622\u0645\u0627\u062f\u0647 \u0634\u062f\u0647 \u0628\u0648\u062f\u0646\u062f\u060c \u0627\u0636\u0627\u0641\u0647 \u06a9\u0631\u062f.\n\u0622\u0646 \u0645\u0631\u062f\u0627\u0646 \u0648 \u0632\u0646\u0627\u0646 \u0633\u062e\u062a \u062f\u0648\u06cc\u062f\u0646\u062f\u060c \u0648 \u062e\u06cc\u0644\u06cc \u0633\u0631\u06cc\u0639 \u0647\u0645 \u0645\u06cc\u200c\u062f\u0648\u06cc\u062f\u0646\u062f.\n\u0627\u0645\u0627 \u0622\u0646\u0647\u0627 \u0645\u0633\u0627\u0628\u0642\u0647 \u0631\u0627 \u0628\u0627\u062e\u062a\u0646\u062f\u060c \u0632\u06cc\u0631\u0627 \u062f\u0631 \u0645\u0633\u06cc\u0631 \u0627\u0634\u062a\u0628\u0627\u0647 \u0628\u0648\u062f\u0646\u062f.\n\u0627\u0645\u0634\u0628 \u0645\u0627 \u0628\u0647 \u0627\u062f\u0627\u0645\u0647\u200c\u06cc \u0633\u0644\u0633\u0644\u0647 \u0645\u0648\u0639\u0638\u0647\u200c\u0647\u0627\u06cc\u06cc \u062f\u0631 \u06a9\u062a\u0627\u0628 \u062f\u0648\u0645 \u062a\u06cc\u0645\u0648\u062a\u0627\u0626\u0648\u0633 \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u0645.\n\u067e\u0648\u0644\u0633 \u0631\u0633\u0648\u0644 \u062f\u0631 \u062d\u0627\u0644 \u0646\u0648\u0634\u062a\u0646 \u0628\u0647 \u062a\u06cc\u0645\u0648\u062a\u0627\u0648\u0633 \u060c \u06a9\u0634\u06cc\u0634 \u062c\u0648\u0627\u0646 \u06a9\u0644\u06cc\u0633\u0627\u06cc \u0645\u0633\u06cc\u062d\u06cc \u062f\u0631 \u0627\u0641\u0633\u0633 \u0627\u0633\u062a.\n\u067e\u0648\u0644\u0633 \u0628\u0647 \u062a\u06cc\u0645\u0648\u062a\u0627\u0626\u0648\u0633 \u0648 \u0645\u0627 \u0627\u0645\u0631\u0648\u0632\u060c \u062f\u0631 \u0645\u0648\u0631\u062f \u0686\u06af\u0648\u0646\u06af\u06cc \u0645\u0627\u0646\u062f\u0646 \u062f\u0631 \u0645\u0633\u06cc\u0631 \u062f\u0631\u0633\u062a\u060c \u062a\u0648\u0635\u06cc\u0647\u200c\u0647\u0627\u06cc\u06cc \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f.\n\u062f\u0648\u0645 \u062a\u06cc\u0645\u0648\u062a\u0627\u0626\u0648\u0633 \u06f2:\u06f2\u06f2-\u06f2\u06f6\n\u06f2\u06f2 \u00ab\u067e\u0633 \u0627\u0632 \u0634\u0647\u0648\u0627\u062a \u062c\u0648\u0627\u0646\u06cc \u0628\u06af\u0631\u06cc\u0632 \u0648 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0627 \u0642\u0644\u0628\u06cc \u067e\u0627\u06a9 \u0628\u0647 \u062f\u0631\u06af\u0627\u0647 \u062e\u062f\u0627\u0648\u0646\u062f \u062f\u0639\u0627 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u062f\u0631 \u067e\u06cc \u067e\u0627\u0631\u0633\u0627\u06cc\u06cc\u060c \u0627\u06cc\u0645\u0627\u0646\u060c \u0645\u062d\u0628\u062a \u0648 \u0622\u0631\u0627\u0645\u0634 \u0628\u0627\u0634.\n\u06f2\u06f3 \u0628\u0627 \u0628\u062d\u062b\u200c\u0647\u0627\u06cc \u0627\u062d\u0645\u0642\u0627\u0646\u0647 \u0648 \u062c\u0627\u0647\u0644\u0627\u0646\u0647 \u06a9\u0627\u0631\u06cc \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u060c \u0632\u06cc\u0631\u0627 \u0645\u06cc\u200c\u062f\u0627\u0646\u06cc \u06a9\u0647 \u0622\u0646\u0647\u0627 \u0646\u0632\u0627\u0639 \u0628\u0647 \u0628\u0627\u0631 \u0645\u06cc\u200c\u0622\u0648\u0631\u0646\u062f.\n\u06f2\u06f4 \u0648 \u0628\u0646\u062f\u0647 \u062e\u062f\u0627\u0648\u0646\u062f \u0646\u0628\u0627\u06cc\u062f \u0633\u062a\u06cc\u0632\u0647\u200c\u062c\u0648 \u0628\u0627\u0634\u062f\u060c \u0628\u0644\u06a9\u0647 \u0628\u0627\u06cc\u062f \u0628\u0627 \u0647\u0645\u0647 \u0645\u0647\u0631\u0628\u0627\u0646\u060c \u0642\u0627\u062f\u0631 \u0628\u0647 \u062a\u0639\u0644\u06cc\u0645\u060c \u0648 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0628\u062f\u06cc \u0635\u0628\u0648\u0631 \u0628\u0627\u0634\u062f.\n\u06f2\u06f5 \u0645\u062e\u0627\u0644\u0641\u0627\u0646 \u062e\u0648\u062f \u0631\u0627 \u0628\u0627 \u0645\u0644\u0627\u06cc\u0645\u062a \u0627\u0635\u0644\u0627\u062d \u0645\u06cc\u200c\u06a9\u0646\u062f.\n\u0634\u0627\u06cc\u062f \u062e\u062f\u0627 \u062a\u0648\u0628\u0647\u200c\u0627\u06cc \u0628\u0647 \u0627\u06cc\u0634\u0627\u0646 \u0639\u0637\u0627 \u06a9\u0646\u062f \u06a9\u0647 \u0628\u0647 \u0634\u0646\u0627\u062e\u062a \u062d\u0642\u06cc\u0642\u062a \u0628\u06cc\u0646\u062c\u0627\u0645\u062f\u060c\n\u06f2\u06f6 \u0648 \u0634\u0627\u06cc\u062f \u0628\u0647 \u062e\u0648\u062f \u0622\u06cc\u0646\u062f \u0648 \u0627\u0632 \u062f\u0627\u0645 \u0627\u0628\u0644\u06cc\u0633 \u0631\u0647\u0627\u06cc\u06cc \u06cc\u0627\u0628\u0646\u062f\u060c \u067e\u0633 \u0627\u0632 \u0622\u0646\u06a9\u0647 \u0628\u0631\u0627\u06cc \u0627\u0646\u062c\u0627\u0645 \u0627\u0631\u0627\u062f\u0647\u200c\u0627\u0634 \u0627\u0633\u06cc\u0631 \u0627\u0648 \u0634\u062f\u0647\u200c\u0627\u0646\u062f.\u00bb\n\n\u0628\u0627 \u0647\u0645 \u0627\u0634\u0639\u06cc\u0627 \u06f4\u06f0:\u06f8 \u0631\u0627 \u0645\u06cc\u200c\u062e\u0648\u0627\u0646\u06cc\u0645:\n\u00ab\u06af\u06cc\u0627\u0647 \u067e\u0698\u0645\u0631\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u06af\u0644 \u067e\u0698\u0645\u0631\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0627\u0645\u0627 \u06a9\u0644\u0627\u0645 \u062e\u062f\u0627\u06cc \u0645\u0627 \u062a\u0627 \u0627\u0628\u062f \u067e\u0627\u0628\u0631\u062c\u0627 \u062e\u0648\u0627\u0647\u062f \u0645\u0627\u0646\u062f.\u00bb\n\n\u0622\u06cc\u0647 \u06f2\u06f2 \u0645\u06cc\u200c\u06af\u0648\u06cc\u062f:\n\u06f2\u06f2 \u00ab\u067e\u0633 \u0627\u0632 \u0647\u0648\u0633\u200c\u0647\u0627\u06cc \u062c\u0648\u0627\u0646\u06cc \u0628\u06af\u0631\u06cc\u0632 \u0648 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0627 \u0642\u0644\u0628\u06cc \u067e\u0627\u06a9 \u0628\u0647 \u062f\u0631\u06af\u0627\u0647 \u062e\u062f\u0627\u0648\u0646\u062f \u062f\u0639\u0627 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u062f\u0631 \u067e\u06cc \u067e\u0627\u0631\u0633\u0627\u06cc\u06cc\u060c \u0627\u06cc\u0645\u0627\u0646\u060c \u0645\u062d\u0628\u062a \u0648 \u0622\u0631\u0627\u0645\u0634 \u0628\u0627\u0634.\u00bb\n\n\u0627\u06cc\u0646 \u0622\u06cc\u0647 \u062f\u0631 \u0648\u0627\u0642\u0639 \u062e\u0644\u0627\u0635\u0647 \u0627\u06cc \u0627\u0632 \u062e\u0637\u0628\u0647 \u0627\u0645\u0631\u0648\u0632 \u0627\u0633\u062a.\n\u0645\u0627 \u0627\u06cc\u0646 \u0631\u0627 \u0627\u063a\u0644\u0628 \u062f\u0631 \u06a9\u0644\u0627\u0645 \u062e\u062f\u0627 \u0645\u06cc\u200c\u0628\u06cc\u0646\u06cc\u0645.\n\u06af\u0627\u0647\u06cc \u0627\u0648\u0642\u0627\u062a \u0627\u0648\u0644\u06cc\u0646 \u062c\u0645\u0644\u0647 \u062f\u0631 \u06cc\u06a9 \u0645\u0632\u0645\u0648\u0631 \u06cc\u0627 \u06cc\u06a9 \u067e\u0627\u0631\u0627\u06af\u0631\u0627\u0641\u060c \u062e\u0644\u0627\u0635\u0647 \u0622\u0646 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.\n\u0633\u067e\u0633 \u06a9\u0644\u0645\u0627\u062a\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0645\u06cc\u200c\u0622\u06cc\u0646\u062f\u060c \u062a\u0648\u0636\u06cc\u062d\u06cc \u0628\u0631 \u06a9\u0644 \u0645\u0632\u0645\u0648\u0631 \u06cc\u0627 \u067e\u0627\u0631\u0627\u06af\u0631\u0627\u0641 \u06cc\u0627 \u0641\u0635\u0644 \u0647\u0633\u062a\u0646\u062f.\n\u06cc\u06a9 \u0645\u0631\u062f \u06cc\u0627 \u0632\u0646 \u0645\u0633\u06cc\u062d\u06cc \u0628\u0627\u0644\u063a \u06a9\u0633\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0627\u0632 \u0686\u06cc\u0632\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u062c\u0648\u0627\u0646\u06cc \u0645\u0627 \u0631\u0627 \u0648\u0633\u0648\u0633\u0647 \u0645\u06cc\u200c\u06a9\u0631\u062f\u0646\u062f\u060c \u062f\u0648\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f.\n\u0628\u0647 \u062c\u0627\u06cc \u00ab\u0634\u0648\u0631 \u0648 \u0634\u0648\u0642 \u062c\u0648\u0627\u0646\u06cc\u00bb\u060c \u06cc\u06a9 \u0641\u0631\u062f \u0628\u0627\u0644\u063a \u06cc\u0627\u062f \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f \u06a9\u0647 \u0627\u0631\u0632\u0634\u200c\u0647\u0627\u06cc \u0627\u0644\u0647\u06cc\u060c \u0627\u0632 \u062c\u0645\u0644\u0647 \u0639\u062f\u0627\u0644\u062a\u060c \u0627\u06cc\u0645\u0627\u0646\u060c \u0639\u0634\u0642 \u0648 \u0635\u0644\u062d \u0631\u0627 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0646\u062f.\n\u0648\u0642\u062a\u06cc \u067e\u0648\u0644\u0633 \u062c\u0648\u0627\u0646 \u0628\u0648\u062f\u060c \u0646\u0627\u0645\u0634 \u0631\u0627 \u0634\u0627\u0626\u0648\u0644 \u06af\u0630\u0627\u0634\u062a\u0646\u062f.\n\u0633\u0627\u0626\u0648\u0644 \u0633\u0631\u0634\u0627\u0631 \u0627\u0632 \u063a\u0631\u0648\u0631 \u0648 \u0627\u0639\u062a\u0645\u0627\u062f \u0628\u0647 \u0646\u0641\u0633 \u0628\u0648\u062f \u0648 \u0627\u0632 \u0642\u062f\u0631\u062a \u062e\u0648\u062f \u0628\u0631\u0627\u06cc \u0622\u0632\u0627\u0631 \u0648 \u0627\u0630\u06cc\u062a \u0645\u0633\u06cc\u062d\u06cc\u0627\u0646 \u0648 \u0632\u0646\u062f\u0627\u0646\u06cc \u06a9\u0631\u062f\u0646 \u0622\u0646\u0647\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0631\u062f.\n\u0633\u0627\u0626\u0648\u0644 \u0645\u06cc\u200c\u062e\u0648\u0627\u0633\u062a \u0645\u062d\u0628\u0648\u0628 \u0648 \u0645\u0648\u0641\u0642 \u0628\u0627\u0634\u062f \u0648 \u0628\u0647 \u062e\u0627\u0637\u0631 \u063a\u0631\u0648\u0631 \u062e\u0648\u062f\u0634 \u062d\u0627\u0636\u0631 \u0628\u0648\u062f \u0628\u0647 \u062f\u06cc\u06af\u0631\u0627\u0646 \u0622\u0633\u06cc\u0628 \u0628\u0631\u0633\u0627\u0646\u062f.\n\u0627\u0645\u0627 \u0646\u0627\u0645\u0647 \u062f\u0648\u0645 \u062a\u06cc\u0645\u0648\u062a\u0627\u0626\u0648\u0633 \u062a\u0648\u0633\u0637 \u067e\u0648\u0644\u0633\u060c \u0627\u06cc\u0645\u0627\u0646\u062f\u0627\u0631 \u0628\u0627\u0644\u063a\u060c \u0646\u0648\u0634\u062a\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a.\n\u0627\u0648 \u0645\u06cc\u200c\u062f\u0627\u0646\u062f \u06a9\u0647 \u0634\u0648\u0631 \u0648 \u0634\u0648\u0642 \u062c\u0648\u0627\u0646\u06cc\u200c\u0627\u0634 \u0686\u0642\u062f\u0631 \u0628\u0647 \u0627\u0648 \u0622\u0633\u06cc\u0628 \u0631\u0633\u0627\u0646\u062f\u0647 \u0627\u0633\u062a \u0648 \u062f\u0627\u0631\u062f \u0628\u0647 \u062a\u06cc\u0645\u0648\u062a\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u0622\u0646\u0647\u0627 \u0647\u0634\u062f\u0627\u0631 \u0645\u06cc\u200c\u062f\u0647\u062f.\n\u062f\u0631 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u067e\u0648\u0644\u0633 \u0627\u06cc\u0646 \u0646\u0627\u0645\u0647 \u0631\u0627 \u0645\u06cc\u200c\u0646\u0648\u06cc\u0633\u062f\u060c \u062a\u06cc\u0645\u0648\u062a\u0627\u0626\u0648\u0633 \u0627\u062d\u062a\u0645\u0627\u0644\u0627\u064b \u062d\u062f\u0648\u062f \u06f4\u06f0 \u0633\u0627\u0644 \u0633\u0646 \u062f\u0627\u0634\u062a\u0647 \u0627\u0633\u062a.\n\u0627\u0645\u0627 \u0644\u0627\u0632\u0645 \u0646\u06cc\u0633\u062a \u062c\u0648\u0627\u0646 \u0628\u0627\u0634\u06cc\u062f \u062a\u0627 \u0628\u0647 \u0633\u0645\u062a \u00ab\u0634\u0648\u0631 \u0648 \u0634\u0648\u0642\u200c\u0647\u0627\u06cc \u062c\u0648\u0627\u0646\u06cc\u00bb \u0628\u0631\u0648\u06cc\u062f.\n\u0645\u0646 \u06f5\u06f7 \u0633\u0627\u0644\u0645\u0647\u060c \u0627\u0645\u0627 \u0647\u0646\u0648\u0632 \u062f\u0627\u0631\u0645 \u06cc\u0627\u062f \u0645\u06cc\u200c\u06af\u06cc\u0631\u0645 \u06a9\u0647 \u0686\u0637\u0648\u0631 \u0627\u0632 \u0634\u0648\u0631 \u0648 \u0634\u0648\u0642\u200c\u0647\u0627\u06cc \u062c\u0648\u0627\u0646\u06cc \u0641\u0631\u0627\u0631 \u06a9\u0646\u0645.\n\u0645\u0646 \u06cc\u0647 \u062f\u0648\u0633\u062a \u0627\u0632 \u062f\u0648\u0631\u0627\u0646 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u062f\u0627\u0631\u0645 \u06a9\u0647 \u0647\u0645\u0633\u0646 \u062e\u0648\u062f\u0645\u0647.\n\u0627\u0645\u0627 \u0627\u0648 \u0647\u0646\u0648\u0632 \u0645\u062b\u0644 \u06f3\u06f5 \u0633\u0627\u0644 \u067e\u06cc\u0634 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f.\n\u0632\u0646\u062f\u06af\u06cc \u0627\u0648 \u062a\u062d\u062a \u0633\u0644\u0637\u0647 \u0634\u0648\u0631 \u0648 \u0634\u0648\u0642 \u062c\u0648\u0627\u0646\u06cc \u062f\u0648\u0631\u0627\u0646 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0645\u0627\u0633\u062a.\n\u062f\u0631 \u0627\u06cc\u0646\u062c\u0627 \u0628\u0647 \u0628\u0631\u062e\u06cc \u0627\u0632 \u0634\u0648\u0631 \u0648 \u0627\u0634\u062a\u06cc\u0627\u0642\u200c\u0647\u0627\u06cc \u062f\u0648\u0631\u0627\u0646 \u062c\u0648\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u0627 \u062a\u062c\u0631\u0628\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645\u060c \u0627\u0634\u0627\u0631\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645:\n\n*   \u0644\u0630\u062a: \u06af\u0646\u0627\u0647 \u062c\u0646\u0633\u06cc \u0646\u0645\u0648\u0646\u0647 \u0631\u0627\u06cc\u062c\u06cc \u0627\u0632 \u06af\u0646\u0627\u0647 \u0644\u0630\u062a \u0627\u0633\u062a\u060c \u0627\u0645\u0627 \u062a\u0646\u0647\u0627 \u0646\u0645\u0648\u0646\u0647 \u0646\u06cc\u0633\u062a.\n\u0627\u0632 \u062f\u06cc\u06af\u0631 \u0644\u0630\u062a\u200c\u0647\u0627\u06cc \u06af\u0646\u0627\u0647\u200c\u0622\u0644\u0648\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u0627\u0644\u06a9\u0644\u060c \u063a\u0630\u0627 \u0648 \u0627\u0646\u0648\u0627\u0639 \u0633\u0631\u06af\u0631\u0645\u06cc\u200c\u0647\u0627 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f.\n\u0627\u06cc\u0646 \u0686\u06cc\u0632\u0647\u0627 \u0627\u06af\u0631 \u062f\u0631\u0633\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u0648\u0646\u062f\u060c \u0628\u062f \u0646\u06cc\u0633\u062a\u0646\u062f.\n\u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644\u060c \u0631\u0627\u0628\u0637\u0647 \u062c\u0646\u0633\u06cc \u062f\u0631 \u0686\u0627\u0631\u0686\u0648\u0628 \u0627\u0632\u062f\u0648\u0627\u062c \u0645\u0633\u06cc\u062d\u06cc \u06cc\u06a9 \u0645\u0648\u0647\u0628\u062a \u0632\u06cc\u0628\u0627\u0633\u062a.\n\u0627\u0645\u0627 \u0648\u0642\u062a\u06cc \u0627\u0632 \u0647\u0631 \u0686\u06cc\u0632\u06cc \u0628\u0647 \u0631\u0648\u0634 \u0646\u0627\u062f\u0631\u0633\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645\u060c \u0628\u0647 \u0622\u0646 \u0642\u062f\u0631\u062a \u062a\u0633\u0644\u0637 \u0628\u0631 \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0631\u0627 \u0645\u06cc\u200c\u062f\u0647\u06cc\u0645.\n\u0648\u0642\u062a\u06cc \u0627\u0632 \u0647\u0631 \u06cc\u06a9 \u0627\u0632 \u0645\u0648\u0627\u0647\u0628 \u062e\u062f\u0627 \u0628\u0631\u0627\u06cc \u067e\u0631 \u06a9\u0631\u062f\u0646 \u062e\u0644\u0623 \u0642\u0644\u0628\u200c\u0647\u0627\u06cc\u0645\u0627\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645\u060c \u0622\u0646 \u0686\u06cc\u0632 \u0628\u0647 \u06cc\u06a9 \u062e\u062f\u0627\u06cc \u062f\u0631\u0648\u063a\u06cc\u0646- \u06cc\u06a9 \u0628\u062a - \u062a\u0628\u062f\u06cc\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f.\n\n*   \u0642\u062f\u0631\u062a: \u0648\u0642\u062a\u06cc \u062c\u0648\u0627\u0646 \u0647\u0633\u062a\u06cc\u0645\u060c \u06af\u0627\u0647\u06cc \u0627\u0648\u0642\u0627\u062a \u0627\u062d\u0633\u0627\u0633 \u0646\u0627\u062a\u0648\u0627\u0646\u06cc\u060c \u0636\u0639\u0641 \u06cc\u0627 \u0646\u0627\u06a9\u0627\u0641\u06cc \u0628\u0648\u062f\u0646 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645.\n\u0645\u0646 \u062f\u0631 \u0646\u0648\u062c\u0648\u0627\u0646\u06cc \u0628\u0627 \u0627\u06cc\u0646 \u0627\u062d\u0633\u0627\u0633\u0627\u062a \u062f\u0633\u062a \u0648 \u067e\u0646\u062c\u0647 \u0646\u0631\u0645 \u0645\u06cc\u200c\u06a9\u0631\u062f\u0645.\n\u0628\u0639\u0636\u06cc\u200c\u0647\u0627 \u062f\u0646\u0628\u0627\u0644 \u0642\u062f\u0631\u062a \u0645\u06cc\u200c\u06af\u0631\u062f\u0646\u062f \u062a\u0627 \u0636\u0639\u0641\u200c\u0647\u0627\u06cc\u0634\u0627\u0646 \u0631\u0627 \u0628\u067e\u0648\u0634\u0627\u0646\u0646\u062f.\n\u0622\u0646\u0647\u0627 \u0641\u06a9\u0631 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u06a9\u0647 \u0631\u0641\u062a\u0627\u0631 \u0642\u0648\u06cc \u0628\u0647 \u0622\u0646\u0647\u0627 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0627\u062d\u0633\u0627\u0633 \u0627\u0645\u0646\u06cc\u062a \u06a9\u0646\u0646\u062f.\n\u0622\u06cc\u0627 \u0645\u06cc\u200c\u062f\u0627\u0646\u0633\u062a\u06cc\u062f \u06a9\u0647 \u06cc\u06a9 \u0642\u0644\u062f\u0631 \u062f\u0631 \u0648\u0627\u0642\u0639 \u0622\u0646\u0642\u062f\u0631\u0647\u0627 \u0647\u0645 \u06a9\u0647 \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc\u200c\u0631\u0633\u062f \u0633\u0631\u0633\u062e\u062a \u0646\u06cc\u0633\u062a\u061f\n\u0642\u0644\u062f\u0631 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u06a9\u0633\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0645\u0648\u0631\u062f \u0686\u06cc\u0632\u06cc \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0627\u062d\u0633\u0627\u0633 \u0646\u0627\u062a\u0648\u0627\u0646\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u0647 \u062f\u06cc\u06af\u0631\u0627\u0646 \u0622\u0633\u06cc\u0628 \u0645\u06cc\u200c\u0631\u0633\u0627\u0646\u062f \u062a\u0627 \u0627\u062d\u0633\u0627\u0633 \u0642\u062f\u0631\u062a \u06a9\u0646\u062f.\n\n*   \u0645\u062d\u0628\u0648\u0628\u06cc\u062a: \u0627\u06cc\u0646 \u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0648\u0633\u0648\u0633\u0647\u200c\u0647\u0627\u06cc \u0642\u0648\u06cc \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u0645\u0646 \u0628\u0648\u062f\u0647 \u0627\u0633\u062a.\n\u0645\u0646 \u0627\u063a\u0644\u0628 \u0646\u06af\u0631\u0627\u0646 \u0627\u06cc\u0646 \u0647\u0633\u062a\u0645 \u06a9\u0647 \u0622\u06cc\u0627 \u0645\u0631\u062f\u0645 \u0627\u0632 \u0645\u0646 \u062e\u0648\u0634\u0634\u0627\u0646 \u0645\u06cc\u200c\u0622\u06cc\u062f \u06cc\u0627 \u0646\u0647.\n\u0645\u0646 \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u0628\u0647 \u0646\u0638\u0631\u0627\u062a \u062f\u06cc\u06af\u0631\u0627\u0646 \u0627\u0647\u0645\u06cc\u062a \u0645\u06cc\u200c\u062f\u0647\u0645.\n\u0634\u0645\u0627 \u0686\u0637\u0648\u0631\u061f\n\u0622\u06cc\u0627 \u062a\u0627 \u0628\u0647 \u062d\u0627\u0644 \u0631\u0641\u062a\u0627\u0631 \u06cc\u0627 \u0638\u0627\u0647\u0631 \u062e\u0648\u062f \u0631\u0627 \u062a\u063a\u06cc\u06cc\u0631 \u062f\u0627\u062f\u0647\u200c\u0627\u06cc\u062f \u062a\u0627 \u0645\u0631\u062f\u0645 \u0634\u0645\u0627 \u0631\u0627 \u062f\u0648\u0633\u062a \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u061f\n\u0622\u06cc\u0627 \u0641\u06a9\u0631 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0637\u0631\u062f \u0634\u062f\u0646\u060c \u0628\u0627\u06cc\u062f \u0631\u0641\u062a\u0627\u0631 \u06cc\u0627 \u0638\u0627\u0647\u0631 \u062e\u0627\u0635\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f\u061f\n\n*   \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627: \u0639\u0634\u0642 \u0628\u0647 \u067e\u0648\u0644 \u0648 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u0645\u0627\u062f\u06cc \u0628\u0631\u0627\u06cc \u0627\u06a9\u062b\u0631 \u0645\u0627 \u06cc\u06a9 \u0645\u0634\u06a9\u0644 \u0627\u0633\u062a.\n\u0645\u0627 \u0627\u0645\u0646\u06cc\u062a \u0648 \u0622\u0633\u0627\u06cc\u0634\u0650 \u062f\u0627\u0634\u062a\u0646 \u0686\u06cc\u0632\u0647\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0631\u0627 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u0645.\n\u0627\u06cc\u0646 \u0646\u0634\u0627\u0646 \u062f\u0647\u0646\u062f\u0647 \u0636\u0639\u0641 \u0627\u06cc\u0645\u0627\u0646 \u0627\u0633\u062a.\n\u062e\u062f\u0627 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u062f \u0645\u0627 \u062f\u0631\u06a9 \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0627\u0648 \u067e\u0646\u0627\u0647\u06af\u0627\u0647 \u0648 \u062f\u0698 \u0645\u0627\u0633\u062a\u060c \u0627\u0648 \u0631\u0648\u0632\u06cc\u200c\u062f\u0647\u0646\u062f\u0647\u200c\u06cc \u0645\u0627\u0633\u062a.\n\u0686\u06cc\u0632\u0647\u0627\u06cc \u0645\u0627\u062f\u06cc \u0646\u0648\u06cc\u062f \u062e\u0648\u0634\u0628\u062e\u062a\u06cc \u0645\u06cc\u200c\u062f\u0647\u0646\u062f\u060c \u0627\u0645\u0627 \u0647\u0631\u06af\u0632 \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0648\u0639\u062f\u0647 \u062e\u0648\u062f \u0639\u0645\u0644 \u06a9\u0646\u0646\u062f.\n\u0632\u06cc\u0631\u0627 \u0642\u0644\u0628\u200c\u0647\u0627\u06cc \u0645\u0627 \u0647\u0645\u06cc\u0634\u0647 \u0628\u06cc\u0634\u062a\u0631 \u062e\u0648\u0627\u0647\u0646\u062f \u062e\u0648\u0627\u0633\u062a.\n\n*   \u063a\u0631\u0648\u0631: \u0627\u06cc\u0646 \u062f\u0631 \u0648\u0627\u0642\u0639 \u06af\u0646\u0627\u0647\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0632\u06cc\u0631\u0628\u0646\u0627\u06cc \u0647\u0631 \u06af\u0646\u0627\u0647 \u062f\u06cc\u06af\u0631\u06cc \u0627\u0633\u062a.\n\u063a\u0631\u0648\u0631 \u06cc\u0639\u0646\u06cc \u0627\u06cc\u0646 \u0628\u0627\u0648\u0631 \u06a9\u0647 \u0645\u0646 \u0648\u0627\u0642\u0639\u0627\u064b \u0644\u0627\u06cc\u0642 \u062f\u0627\u0631\u0627\u06cc\u06cc\u060c \u0642\u062f\u0631\u062a\u060c \u0644\u0630\u062a \u0648 \u0645\u062d\u0628\u0648\u0628\u06cc\u062a \u0647\u0633\u062a\u0645.\n\u0686\u0631\u0627\u061f \u0686\u0648\u0646 \u0645\u0646 \u062e\u0627\u0635 \u0647\u0633\u062a\u0645.\n\u063a\u0631\u0648\u0631 \u062f\u0631 \u06af\u0648\u0634 \u0645\u0627 \u062f\u0631\u0648\u063a \u0632\u0645\u0632\u0645\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0645\u06cc\u200c\u06af\u0648\u06cc\u062f:\n\u00ab\u0627\u0634\u06a9\u0627\u0644\u06cc \u0646\u062f\u0627\u0631\u0647\u060c \u0645\u06cc\u200c\u062a\u0648\u0646\u06cc \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0631\u0648 \u0628\u06a9\u0646\u06cc-- \u0644\u06cc\u0627\u0642\u062a\u0634 \u0631\u0648 \u062f\u0627\u0631\u06cc.\u00bb\n\u062a\u0628\u0644\u06cc\u063a\u200c\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0647\u0645 \u0647\u0645\u06cc\u0646 \u0631\u0627 \u0628\u0647 \u0645\u0627 \u0645\u06cc\u200c\u06af\u0648\u06cc\u0646\u062f.\n\u00ab\u0644\u06cc\u0627\u0642\u062a\u0634 \u0631\u0648 \u062f\u0627\u0631\u06cc... \u0628\u0631\u0648\u060c \u0628\u062e\u0631\u0634.\u00bb\n\u0634\u0627\u06cc\u062f \u06a9\u0645\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0628\u062e\u0631\u0645\u060c \u0627\u0634\u06a9\u0627\u0644\u06cc \u0646\u062f\u0627\u0631\u062f.\n\u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0627\u0633\u062a \u06a9\u0647 \u0645\u0627 \u0627\u06cc\u0646\u0642\u062f\u0631 \u062a\u0628\u0644\u06cc\u063a\u0627\u062a \u0627\u06cc\u0646 \u0686\u0646\u06cc\u0646\u06cc \u0645\u06cc\u200c\u0628\u06cc\u0646\u06cc\u0645\u060c \u0686\u0648\u0646 \u063a\u0631\u0648\u0631 \u0645\u0627 \u062f\u0631 \u0648\u0627\u0642\u0639 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u062f \u0627\u06cc\u0646 \u0686\u06cc\u0632\u0647\u0627 \u0631\u0627 \u0628\u0627\u0648\u0631 \u06a9\u0646\u062f.\n\n\u0645\u06cc\u0634\u0647 \u06cc\u0647 \u0633\u0648\u0627\u0644 \u0627\u0632\u062a\u0648\u0646 \u0628\u067e\u0631\u0633\u0645 \u062f\u0648\u0633\u062a\u0627\u0646\u061f\n\u06a9\u062f\u0627\u0645 \u06cc\u06a9 \u0627\u0632 \u0627\u06cc\u0646 \u067e\u0646\u062c \u0645\u0648\u0631\u062f \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0622\u0634\u0646\u0627 \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc\u200c\u0631\u0633\u062f\u061f\n\u0622\u06cc\u0627 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u063a\u0631\u0648\u0631\u060c \u0645\u0627\u0644\u060c \u0642\u062f\u0631\u062a\u060c \u0644\u0630\u062a \u06cc\u0627 \u0645\u062d\u0628\u0648\u0628\u06cc\u062a \u0647\u0633\u062a\u06cc\u062f\u061f\n\u06cc\u0627 \u0634\u0627\u06cc\u062f \u0686\u06cc\u0632 \u062f\u06cc\u06af\u0631\u06cc \u0634\u0645\u0627 \u0631\u0627 \u0627\u0632 \u062e\u062f\u0627 \u062f\u0648\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f\u061f\n\u0627\u0645\u0631\u0648\u0632 \u062f\u0644\u062a \u06a9\u062c\u0627\u0633\u062a \u0648 \u0628\u0647 \u06a9\u062c\u0627 \u0645\u06cc\u200c\u0631\u0648\u06cc\u061f\n\u06cc\u0627\u062f\u062a \u0647\u0633\u062a \u062e\u062f\u0627 \u062a\u0648\u06cc \u0628\u0627\u063a \u0639\u062f\u0646\u060c \u0628\u0639\u062f \u0627\u0632 \u0627\u06cc\u0646\u06a9\u0647 \u0622\u062f\u0645 \u0627\u0632 \u0645\u06cc\u0648\u0647 \u062e\u0648\u0631\u062f\u060c \u0627\u0632\u0634 \u0686\u06cc \u067e\u0631\u0633\u06cc\u062f\u061f\n\u0622\u062f\u0645 \u0648 \u062d\u0648\u0627 \u067e\u0646\u0647\u0627\u0646 \u0634\u062f\u0647 \u0628\u0648\u062f\u0646\u062f \u0648 \u062e\u062f\u0627 \u06af\u0641\u062a: \u00ab\u06a9\u062c\u0627 \u0647\u0633\u062a\u06cc \u0622\u062f\u0645\u061f\u00bb\n\u0627\u0645\u0631\u0648\u0632 \u062e\u062f\u0627\u0648\u0646\u062f \u0627\u0632 \u0647\u0645\u0647 \u0631\u0648\u06cc \u0632\u0645\u06cc\u0646 \u0647\u0645\u06cc\u0646 \u0631\u0627 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u062f.\n\u06a9\u062c\u0627\u06cc\u06cc\u061f\n\u0627\u0648 \u0646\u0645\u06cc\u200c\u067e\u0631\u0633\u062f \u06a9\u0647 \u0634\u0645\u0627 \u0627\u0632 \u0646\u0638\u0631 \u0641\u06cc\u0632\u06cc\u06a9\u06cc \u06a9\u062c\u0627 \u0647\u0633\u062a\u06cc\u062f.\n\u0627\u0648 \u0645\u06cc\u200c\u067e\u0631\u0633\u062f: \u00ab\u0642\u0644\u0628\u062a \u06a9\u062c\u0627\u0633\u062a\u061f\u00bb\n\u0632\u06cc\u0631\u0627 \u0642\u0644\u0628\u200c\u0647\u0627\u06cc \u0645\u0627 \u0645\u0627\u0646\u0646\u062f \u0642\u0637\u0628\u200c\u0646\u0645\u0627\u06cc\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0645\u0627 \u0631\u0627 \u062f\u0631 \u0645\u0633\u06cc\u0631 \u0628\u0647 \u0633\u0645\u062a \u0686\u06cc\u0632\u06cc \u06a9\u0647 \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u0627\u0631\u0632\u0634 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0622\u0646 \u062f\u0627\u0631\u06cc\u0645\u060c \u0647\u062f\u0627\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.\n\u0645\u0627 \u06af\u0645 \u0645\u06cc\u200c\u0634\u0648\u06cc\u0645 \u0648 \u062d\u062a\u06cc \u0646\u0645\u06cc\u200c\u062f\u0627\u0646\u06cc\u0645\u060c \u0632\u06cc\u0631\u0627 \u06af\u0646\u0627\u0647 \u0645\u062e\u0641\u06cc\u0627\u0646\u0647 \u0639\u0645\u0644 \u0645\u06cc\u200c\u06a9\u0646\u062f.\n\u0645\u0627 \u0628\u0647 \u06a9\u0645\u06a9 \u062e\u062f\u0627 \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u06cc\u0645 \u062a\u0627 \u0628\u0628\u06cc\u0646\u06cc\u0645 \u062f\u0631 \u062f\u0631\u0648\u0646\u0645\u0627\u0646 \u0686\u0647 \u0645\u06cc\u200c\u06af\u0630\u0631\u062f.\n\u0628\u06cc\u0627\u06cc\u06cc\u062f \u0645\u0632\u0645\u0648\u0631 \u06f1\u06f3\u0669: \u06f2\u06f3-\u06f2\u06f4 \u0631\u0627 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u062f\u0639\u0627 \u0628\u0627 \u0647\u0645 \u0628\u062e\u0648\u0627\u0646\u06cc\u0645:\n\u0647\u0645\u0647: \u06f2\u06f3 \u00ab\u0627\u06cc \u062e\u062f\u0627\u060c \u0645\u0631\u0627 \u062a\u0641\u062a\u06cc\u0634 \u06a9\u0646 \u0648 \u062f\u0644 \u0645\u0631\u0627 \u0628\u0634\u0646\u0627\u0633!\u00bb\n\u0645\u0631\u0627 \u0628\u06cc\u0627\u0632\u0645\u0627\u06cc\u06cc\u062f \u0648 \u0627\u0641\u06a9\u0627\u0631\u0645 \u0631\u0627 \u0628\u062f\u0627\u0646\u06cc\u062f!\n\u06f2\u06f4 \u0648 \u0628\u0628\u06cc\u0646 \u06a9\u0647 \u0622\u06cc\u0627 \u062f\u0631 \u0645\u0646 \u0631\u0627\u0647 \u0628\u062f\u06cc \u0647\u0633\u062a\u060c\n\u0648 \u0645\u0631\u0627 \u0628\u0647 \u0631\u0627\u0647 \u062c\u0627\u0648\u062f\u0627\u0646\u06cc \u0647\u062f\u0627\u06cc\u062a \u0641\u0631\u0645\u0627!\u00bb\n\n\u0628\u062f\u0648\u0646 \u06cc\u0627\u0631\u06cc \u062e\u062f\u0627\u060c \u0645\u0627 \u00ab\u062f\u0631 \u0631\u0627\u0647 \u062c\u0627\u0648\u062f\u0627\u0646\u06cc\u00bb \u06af\u0627\u0645 \u0628\u0631 \u0646\u062e\u0648\u0627\u0647\u06cc\u0645 \u062f\u0627\u0634\u062a.\n\u0645\u0627 \u062f\u0631 \u0645\u0633\u06cc\u0631 \u0627\u0634\u062a\u0628\u0627\u0647 \u062e\u0648\u0627\u0647\u06cc\u0645 \u062f\u0648\u06cc\u062f \u0648 \u0686\u06cc\u0632\u0647\u0627\u06cc\u06cc \u0631\u0627 \u062f\u0646\u0628\u0627\u0644 \u062e\u0648\u0627\u0647\u06cc\u0645 \u06a9\u0631\u062f \u06a9\u0647 \u0645\u0627 \u0631\u0627 \u0627\u0632 \u0642\u0644\u0628 \u062e\u062f\u0627 \u062f\u0648\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f.\n\u0627\u0645\u0627 \u062e\u062f\u0627 \u0622\u0646\u0642\u062f\u0631 \u0645\u0647\u0631\u0628\u0627\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0641\u0642\u0637 \u0646\u0638\u0627\u0631\u0647\u200c\u06af\u0631 \u06af\u0645 \u0634\u062f\u0646 \u0648 \u062f\u0648\u0631 \u0634\u062f\u0646 \u0645\u0627 \u0646\u06cc\u0633\u062a.\n\u062f\u0631 \u0639\u0648\u0636\u060c \u0627\u0648 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u06af\u0648\u0633\u0641\u0646\u062f \u06af\u0645\u0634\u062f\u0647\u200c\u0627\u0634 \u0645\u06cc\u200c\u06af\u0631\u062f\u062f.\n\u0627\u0648 \u0628\u0647 \u0633\u0645\u062a \u0645\u0627 \u0645\u06cc\u200c\u0622\u06cc\u062f \u0648 \u0631\u0627\u0647 \u0641\u0631\u0627\u0631 \u0648 \u0646\u062c\u0627\u062a \u0631\u0627 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u062f\u0647\u062f.\n\u062f\u0648\u0628\u0627\u0631\u0647 \u0628\u0647 \u062f\u0648\u0645 \u062a\u06cc\u0645\u0648\u062a\u0627\u0626\u0648\u0633 \u06f2:\u06f2\u06f5\u0628-\u06f2\u06f6 \u0646\u06af\u0627\u0647 \u06a9\u0646\u06cc\u062f:\n\u06f2\u06f5\u0628 \u00ab\u0634\u0627\u06cc\u062f \u062e\u062f\u0627 \u062a\u0648\u0628\u0647\u200c\u0627\u06cc \u0628\u0647 \u0627\u06cc\u0634\u0627\u0646 \u0639\u0637\u0627 \u06a9\u0646\u062f \u06a9\u0647 \u0628\u0647 \u0634\u0646\u0627\u062e\u062a \u062d\u0642\u06cc\u0642\u062a \u0628\u06cc\u0646\u062c\u0627\u0645\u062f\u060c\n\u06f2\u06f6 \u0648 \u0634\u0627\u06cc\u062f \u0628\u0647 \u062e\u0648\u062f \u0622\u06cc\u0646\u062f \u0648 \u0627\u0632 \u062f\u0627\u0645 \u0627\u0628\u0644\u06cc\u0633 \u0631\u0647\u0627\u06cc\u06cc \u06cc\u0627\u0628\u0646\u062f\u060c \u067e\u0633 \u0627\u0632 \u0622\u0646\u06a9\u0647 \u0628\u0631\u0627\u06cc \u0627\u0646\u062c\u0627\u0645 \u0627\u0631\u0627\u062f\u0647\u200c\u0627\u0634 \u0627\u0633\u06cc\u0631 \u0627\u0648 \u0634\u062f\u0647\u200c\u0627\u0646\u062f.\u00bb\n\n\u0622\u06cc\u0627 \u0645\u06cc\u200c\u062f\u0627\u0646\u0633\u062a\u06cc\u062f \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u06a9\u0627\u0645\u0644\u0627\u064b \u0627\u062d\u0633\u0627\u0633 \u0622\u0632\u0627\u062f\u06cc \u06a9\u0646\u06cc\u062f\u060c \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u062f\u0631 \u0648\u0627\u0642\u0639 \u062f\u0631 \u062f\u0627\u0645 \u06af\u0646\u0627\u0647 \u0648 \u0634\u06cc\u0637\u0627\u0646 \u0647\u0633\u062a\u06cc\u062f\u061f\n\u06af\u0646\u0627\u0647 \u0645\u0627\u0646\u0646\u062f \u0622\u0632\u0627\u062f\u06cc \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc\u200c\u0631\u0633\u062f\u060c \u0627\u0645\u0627 \u0628\u0631\u0639\u06a9\u0633 \u0622\u0646 \u0627\u0633\u062a.\n\u06cc\u06a9 \u062f\u0627\u0645 \u0628\u0647 \u0627\u06cc\u0646 \u0634\u06a9\u0644 \u0627\u0633\u062a.\n\u0627\u06cc\u0646 \u062a\u0644\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062d\u06cc\u0648\u0627\u0646\u06cc \u0631\u0627 \u06a9\u0647 \u0622\u0632\u0627\u062f\u0627\u0646\u0647 \u062f\u0631 \u0645\u0633\u06cc\u0631\u06cc \u0645\u06cc\u200c\u062f\u0648\u06cc\u062f\u0647 \u0648 \u0646\u0627\u06af\u0647\u0627\u0646 \u062f\u0631 \u0645\u0639\u0631\u0636 \u062e\u0637\u0631 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0647\u060c \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f.\n\u0634\u06cc\u0637\u0627\u0646 \u062f\u0631\u0648\u063a\u200c\u0647\u0627 \u0631\u0627 \u0645\u0627\u0646\u0646\u062f \u0639\u0644\u0627\u0626\u0645 \u062f\u0631 \u0645\u0633\u06cc\u0631 \u0645\u0627\u0631\u0627\u062a\u0646 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u062f\u0647\u062f \u062a\u0627 \u0645\u0627 \u0631\u0627 \u0641\u0631\u06cc\u0628 \u062f\u0647\u062f \u0648 \u0628\u0647 \u062f\u0627\u0645 \u0628\u06cc\u0646\u062f\u0627\u0632\u062f.\n\u0634\u06cc\u0637\u0627\u0646 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u062f \u0645\u0627 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0644\u0630\u062a\u060c \u0642\u062f\u0631\u062a\u060c \u0645\u062d\u0628\u0648\u0628\u06cc\u062a\u060c \u062f\u0627\u0631\u0627\u06cc\u06cc \u0648 \u063a\u0631\u0648\u0631 \u0628\u0627\u0634\u06cc\u0645.\n\u0627\u06cc\u0646 \u0628\u062a\u200c\u0647\u0627 \u0628\u0647 \u0645\u0627 \u0648\u0639\u062f\u0647 \u0622\u0632\u0627\u062f\u06cc \u0645\u06cc\u200c\u062f\u0647\u0646\u062f\u060c \u0648 \u0622\u0632\u0627\u062f\u06cc \u0686\u06cc\u0632\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u0627 \u062e\u06cc\u0644\u06cc \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u0645.\n\u0645\u062a\u0623\u0633\u0641\u0627\u0646\u0647\u060c \u0645\u0627 \u0645\u0639\u062a\u0642\u062f\u06cc\u0645 \u06a9\u0647 \u0686\u0646\u06cc\u0646 \u0686\u06cc\u0632\u0647\u0627\u06cc\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0645\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u0646\u062f \u0627\u062d\u0633\u0627\u0633 \u0631\u0636\u0627\u06cc\u062a\u060c \u0627\u0645\u0646\u06cc\u062a \u0648 \u0634\u0627\u062f\u06cc \u06a9\u0646\u06cc\u0645.\n\u0627\u0645\u0627 \u0627\u06cc\u0646 \u0628\u062a\u200c\u0647\u0627 \u062f\u0627\u0645\u200c\u0647\u0627\u06cc\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0645\u0627 \u0631\u0627 \u0627\u0632 \u062e\u062f\u0627 \u0648 \u0645\u0633\u06cc\u0631 \u0632\u0646\u062f\u06af\u06cc \u062d\u0642\u06cc\u0642\u06cc \u062f\u0648\u0631 \u0646\u06af\u0647 \u0645\u06cc\u200c\u062f\u0627\u0631\u0646\u062f.\n\u0634\u06cc\u0637\u0627\u0646 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u062f \u0631\u0627\u0647 \u0632\u0646\u062f\u06af\u06cc \u0631\u0627 \u0627\u0632 \u0645\u0627 \u067e\u0646\u0647\u0627\u0646 \u06a9\u0646\u062f \u0648 \u0645\u06cc\u200c\u06af\u0648\u06cc\u062f:\n\u00ab\u0627\u0632 \u0627\u06cc\u0646 \u0631\u0627\u0647 \u0628\u0647 \u0633\u0648\u06cc \u067e\u06cc\u0631\u0648\u0632\u06cc \u0648 \u062e\u0648\u0634\u0628\u062e\u062a\u06cc \u0628\u0631\u0648!\u00bb\n\u0628\u0644\u0647\u060c \u0631\u0627\u0647 \u0647\u0645\u06cc\u0646\u0647! \u062f\u0646\u0628\u0627\u0644\u0645 \u0628\u06cc\u0627\u06cc\u062f!\n\n\u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646\u060c \u0686\u06af\u0648\u0646\u0647 \u06cc\u06a9 \u062d\u06cc\u0648\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0632 \u0686\u0646\u06cc\u0646 \u062a\u0644\u0647\u200c\u0627\u06cc \u0641\u0631\u0627\u0631 \u06a9\u0646\u062f\u061f\n\u0622\u06cc\u0627 \u06a9\u0627\u0631\u06cc \u0647\u0633\u062a \u06a9\u0647 \u062e\u0648\u062f\u0634 \u0628\u062a\u0648\u0627\u0646\u062f \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u062f\u061f\n\u0646\u0647\u060c \u062e\u0631\u06af\u0648\u0634 \u062f\u0631\u0645\u0627\u0646\u062f\u0647 \u0627\u0633\u062a.\n\u0627\u0648 \u0628\u0647 \u06a9\u0633\u06cc \u0628\u0627\u0647\u0648\u0634\u200c\u062a\u0631 \u0648 \u0642\u0648\u06cc\u200c\u062a\u0631 \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u062f \u062a\u0627 \u0628\u06cc\u0627\u06cc\u062f \u0648 \u0627\u0648 \u0631\u0627 \u0627\u0632 \u0627\u06cc\u0646 \u0645\u062e\u0645\u0635\u0647 \u0628\u06cc\u0631\u0648\u0646 \u0628\u06cc\u0627\u0648\u0631\u062f.\n\u0645\u0627 \u0628\u0647 \u06a9\u0633\u06cc \u0628\u0627\u0647\u0648\u0634\u200c\u062a\u0631 \u0648 \u0642\u0648\u06cc\u200c\u062a\u0631 \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u06cc\u0645 \u062a\u0627 \u0645\u0627 \u0631\u0627 \u0646\u062c\u0627\u062a \u062f\u0647\u062f.\n\u0627\u06cc\u0646 \u0645\u0647\u0645\u062a\u0631\u06cc\u0646 \u0646\u06a9\u062a\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u0645 \u062f\u0631 \u0645\u0648\u0631\u062f \u0627\u06cc\u0646 \u0622\u06cc\u0647 \u0628\u0647 \u0622\u0646 \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f.\n\u0645\u0627 \u0628\u0647 \u06cc\u06a9 \u0646\u062c\u0627\u062a\u200c\u062f\u0647\u0646\u062f\u0647 \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u06cc\u0645 \u0632\u06cc\u0631\u0627 \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u0645 \u062e\u0648\u062f\u0645\u0627\u0646 \u0631\u0627 \u0646\u062c\u0627\u062a \u062f\u0647\u06cc\u0645 \u06cc\u0627 \u062d\u062a\u06cc \u0628\u0647 \u062e\u062f\u0627 \u0631\u0648\u06cc \u0622\u0648\u0631\u06cc\u0645.\n\u0642\u0644\u0628\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0632 \u0646\u0638\u0631 \u0631\u0648\u062d\u0627\u0646\u06cc \u0645\u0631\u062f\u0647 \u0647\u0633\u062a\u0646\u062f\u060c \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u062d\u06cc\u0627\u062a \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u0646\u062f.\n\u0628\u0628\u06cc\u0646\u06cc\u062f \u0622\u06cc\u0647 \u06f2\u06f5 \u0686\u0647 \u0645\u06cc\u200c\u06af\u0648\u06cc\u062f:\n\u00ab\u0634\u0627\u06cc\u062f \u062e\u062f\u0627 \u062a\u0648\u0628\u0647 \u0622\u0646\u0647\u0627 \u0631\u0627 \u0628\u067e\u0630\u06cc\u0631\u062f.\u00bb\n\n\u06a9\u0645\u06a9 \u0647\u0632\u06cc\u0646\u0647 \u06cc\u06a9 \u0647\u062f\u06cc\u0647 \u0631\u0627\u06cc\u06af\u0627\u0646 \u0627\u0633\u062a.\n\u062e\u062f\u0627\u0648\u0646\u062f \u0633\u06cc \u0633\u0627\u0644 \u067e\u06cc\u0634 \u0628\u0647 \u0645\u0646 \u0645\u0648\u0647\u0628\u062a \u062a\u0648\u0628\u0647 \u0631\u0627 \u0639\u0637\u0627 \u06a9\u0631\u062f.\n\u062f\u0647 \u0633\u0627\u0644 \u06af\u0641\u062a\u0645 \u06a9\u0647 \u062f\u0631 \u062c\u0647\u0627\u0646 \u0647\u0633\u062a\u06cc \u062e\u062f\u0627\u06cc\u06cc \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0631\u062f.\n\u0627\u0645\u0627 \u0627\u0632 \u0622\u0646\u062c\u0627 \u06a9\u0647 \u062e\u062f\u0627 \u0645\u0647\u0631\u0628\u0627\u0646 \u0627\u0633\u062a\u060c \u0628\u0647 \u0645\u0646 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f \u06a9\u0647 \u0622\u0628\u062c\u0648\u060c \u0632\u0646\u0627\u0646 \u0648 \u0645\u0648\u0641\u0642\u06cc\u062a\u200c\u0647\u0627\u06cc \u062f\u0646\u06cc\u0648\u06cc \u0647\u0631\u06af\u0632 \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u062e\u0648\u0627\u0633\u062a\u0647\u200c\u0647\u0627\u06cc \u0642\u0644\u0628\u06cc \u0645\u0631\u0627 \u0628\u0631\u0622\u0648\u0631\u062f\u0647 \u06a9\u0646\u0646\u062f.\n\u0645\u0646\u0638\u0648\u0631 \u0627\u0632 \u00ab\u0628\u0647 \u062e\u0648\u062f \u0622\u06cc\u0646\u062f\u00bb \u062f\u0631 \u0622\u06cc\u0647 \u06f2\u06f6 \u0647\u0645\u06cc\u0646 \u0627\u0633\u062a.\n\u0648\u0642\u062a\u06cc \u062d\u0633 \u062c\u0647\u062a\u200c\u06cc\u0627\u0628\u06cc\u200c\u062a\u0627\u0646 \u062f\u0686\u0627\u0631 \u0645\u0634\u06a9\u0644 \u0634\u0648\u062f\u060c \u062f\u0631 \u062c\u0647\u062a \u0627\u0634\u062a\u0628\u0627\u0647 \u062d\u0631\u06a9\u062a \u062e\u0648\u0627\u0647\u06cc\u062f \u06a9\u0631\u062f.\n\u0627\u0648\u0644\u06cc\u0646 \u0642\u062f\u0645 \u0628\u0631\u0627\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0646 \u0631\u0627\u0647 \u062e\u0627\u0646\u0647\u060c \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062a\u0634\u062e\u06cc\u0635 \u062f\u0647\u06cc\u062f \u06af\u0645 \u0634\u062f\u0647\u200c\u0627\u06cc\u062f.\n\u062f\u0646 \u0645\u06a9\u200c\u062f\u0627\u0648\u0644 \u06cc\u06a9\u06cc \u0627\u0632 \u062f\u0648\u0646\u062f\u06af\u0627\u0646\u06cc \u0628\u0648\u062f \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u0645\u0627\u0631\u0627\u062a\u0646 \u062f\u0631 \u067e\u0648\u0631\u062a\u0644\u0646\u062f \u0634\u06a9\u0633\u062a \u062e\u0648\u0631\u062f.\n\u0627\u0648 \u06af\u0641\u062a: \u00ab\u0627\u0632 \u06af\u0648\u0634\u0647 \u062e\u06cc\u0627\u0628\u0627\u0646 \u06a9\u0647 \u0631\u062f \u0634\u062f\u0645\u060c \u062f\u06cc\u062f\u0645 \u062f\u0647 \u0646\u0641\u0631 \u0628\u06cc\u200c\u062d\u0631\u06a9\u062a \u0627\u06cc\u0633\u062a\u0627\u062f\u0647\u200c\u0627\u0646\u062f...\n\u0622\u0646\u0647\u0627 \u0628\u0647 \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u0646\u06af\u0627\u0647 \u0645\u06cc\u200c\u06a9\u0631\u062f\u0646\u062f \u0648 \u0641\u06a9\u0631 \u0645\u06cc\u200c\u06a9\u0631\u062f\u0646\u062f \u201d\u0627\u0647\u060c \u0627\u06cc\u0646 \u062f\u0631\u0633\u062a \u0628\u0647 \u0646\u0638\u0631 \u0646\u0645\u06cc\u200c\u0631\u0633\u062f.\u201d\u2033\n\n\u0632\u06a9 \u06a9\u0627\u0633\u062a\u0631\u060c \u062f\u0648\u0646\u062f\u0647 \u062f\u06cc\u06af\u0631\u06cc\u060c \u06af\u0641\u062a \u06a9\u0647 \u0648\u0627\u0631\u062f \u062a\u0648\u0646\u0644\u06cc \u0634\u062f\u0647 \u06a9\u0647 \u0645\u0627\u0634\u06cc\u0646\u200c\u0647\u0627 \u0628\u0627 \u0633\u0631\u0639\u062a \u06f5\u06f5 \u0645\u0627\u06cc\u0644 \u062f\u0631 \u0633\u0627\u0639\u062a \u0627\u0632 \u06a9\u0646\u0627\u0631\u0634 \u0631\u062f \u0645\u06cc\u200c\u0634\u062f\u0646\u062f.\n\u0622\u0646 \u0645\u0648\u0642\u0639 \u0628\u0648\u062f \u06a9\u0647 \u0641\u0647\u0645\u06cc\u062f \u0627\u0632 \u0645\u0633\u06cc\u0631 \u0627\u0635\u0644\u06cc\u200c\u0627\u0634 \u062e\u0627\u0631\u062c \u0634\u062f\u0647 \u0627\u0633\u062a.\n\u0642\u0628\u0644 \u0627\u0632 \u0627\u06cc\u0646\u06a9\u0647 \u062e\u062f\u0627 \u0645\u0631\u0627 \u0628\u0647 \u0647\u0648\u0634 \u0628\u06cc\u0627\u0648\u0631\u062f\u060c \u0641\u06a9\u0631 \u0645\u06cc\u200c\u06a9\u0631\u062f\u0645 \u06a9\u0647 \u00ab\u062d\u0642\u06cc\u0642\u062a \u0631\u0627 \u0645\u06cc\u200c\u0634\u0646\u0627\u0633\u0645\u00bb.\n\u063a\u0631\u0648\u0631\u0645 \u0628\u0647 \u0645\u0646 \u0645\u06cc\u200c\u06af\u0641\u062a \u06a9\u0647 \u0631\u0627\u0647 \u062f\u0631\u0633\u062a \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0631\u062f\u0647\u200c\u0627\u0645 \u0648 \u0628\u0647 \u0647\u06cc\u0686 \u062e\u062f\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0647\u062f\u0627\u06cc\u062a\u0645 \u0646\u06cc\u0627\u0632 \u0646\u062f\u0627\u0631\u0645\u060c \u0686\u0648\u0646 \u062e\u06cc\u0644\u06cc \u0628\u0627\u0647\u0648\u0634 \u0647\u0633\u062a\u0645.\n\u0627\u0632 \u0642\u0636\u0627\u060c \u0645\u0646 \u0622\u0646\u0642\u062f\u0631 \u0627\u062d\u0645\u0642 \u0628\u0648\u062f\u0645 \u06a9\u0647 \u0641\u0631\u06cc\u0628 \u0634\u06cc\u0637\u0627\u0646 \u0631\u0627 \u0646\u062f\u06cc\u062f\u0645.\n\u0645\u0646 \u062f\u0631 \u062f\u0627\u0645 \u062f\u0631\u0648\u063a\u200c\u0647\u0627\u06cc\u0634 \u0627\u0633\u06cc\u0631 \u0634\u062f\u0645.\n\u0645\u0646 \u0648\u0639\u062f\u0647 \u0634\u06cc\u0637\u0627\u0646 \u0631\u0627 \u0628\u0627\u0648\u0631 \u06a9\u0631\u062f\u0645 \u06a9\u0647 \u0628\u0627 \u0641\u0631\u0627\u0631 \u0627\u0632 \u062e\u062f\u0627\u060c \u062e\u0648\u0634\u0628\u062e\u062a\u06cc \u0631\u0627 \u062e\u0648\u0627\u0647\u0645 \u06cc\u0627\u0641\u062a.\n\u0627\u0645\u0627 \u0628\u0639\u062f\u060c \u062e\u062f\u0627 \u0628\u0647 \u0645\u0646 \u0645\u0648\u0647\u0628\u062a \u062a\u0648\u0628\u0647 \u0631\u0627 \u062f\u0627\u062f.\n\u06a9\u0644\u0645\u0647 \u06cc\u0648\u0646\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u062a\u0648\u0628\u0647 \u062f\u0631 \u0627\u06cc\u0646\u062c\u0627 \u0645\u062a\u0627\u0646\u0648\u06cc\u0627 (metanoia) \u0627\u0633\u062a.\n\u06cc\u0639\u0646\u06cc \u00ab\u062a\u063a\u06cc\u06cc\u0631 \u0641\u06a9\u0631\u060c \u062a\u063a\u06cc\u06cc\u0631 \u0632\u0646\u062f\u06af\u06cc \u0648 \u062a\u063a\u06cc\u06cc\u0631 \u0647\u062f\u0641\u00bb.\n\u0639\u06cc\u0633\u06cc \u0628\u0647 \u0645\u0646 \u0642\u0644\u0628\u06cc \u062a\u0627\u0632\u0647 \u0628\u062e\u0634\u06cc\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u0645 \u0647\u0645\u0627\u0646\u0637\u0648\u0631 \u06a9\u0647 \u0622\u06cc\u0647 \u06f2\u06f2 \u0645\u06cc\u200c\u06af\u0648\u06cc\u062f\u060c \u00ab\u062e\u062f\u0627\u0648\u0646\u062f \u0631\u0627 \u0627\u0632 \u062f\u0644\u06cc \u067e\u0627\u06a9 \u0628\u062e\u0648\u0627\u0646\u0645\u00bb.\n\u0642\u0644\u0628 \u067e\u0627\u06a9\u060c \u0642\u0644\u0628 \u0635\u0627\u062f\u0642 \u0627\u0633\u062a.\n\u0642\u0644\u0628\u06cc \u06a9\u0647 \u062e\u062f\u0627 \u0631\u0627 \u0635\u062f\u0627 \u0645\u06cc\u200c\u0632\u0646\u062f: \u00ab\u0627\u0632 \u06af\u0646\u0627\u0647 \u062e\u0648\u062f \u067e\u0634\u06cc\u0645\u0627\u0646\u0645\u060c \u0644\u0637\u0641\u0627\u064b \u0645\u0631\u0627 \u0628\u0628\u062e\u0634.\u00bb\n\u06a9\u0645\u06a9\u0645 \u06a9\u0646 \u0628\u0647 \u0633\u0645\u062a\u062a \u0628\u062f\u0648\u0645\u060c \u0646\u0647 \u0627\u06cc\u0646\u06a9\u0647 \u0627\u0632\u062a \u0641\u0631\u0627\u0631 \u06a9\u0646\u0645.\n\u067e\u0648\u0644\u0633 \u062f\u0631 \u0631\u0648\u0645\u06cc\u0627\u0646 \u06f1\u06f0: \u06f9-\u06f1\u06f1 \u062a\u0648\u0636\u06cc\u062d \u0628\u0633\u06cc\u0627\u0631 \u0631\u0648\u0634\u0646\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u0686\u06af\u0648\u0646\u06af\u06cc \u0628\u0627\u0632\u06af\u0634\u062a \u0628\u0647 \u0633\u0648\u06cc \u062e\u062f\u0627 \u0648 \u0646\u062c\u0627\u062a \u06cc\u0627\u0641\u062a\u0646 \u0646\u0648\u0634\u062a.\n\u06f9 \u00ab\u0627\u06af\u0631 \u0628\u0647 \u0632\u0628\u0627\u0646 \u062e\u0648\u062f \u0627\u0639\u062a\u0631\u0627\u0641 \u06a9\u0646\u06cc \u06a9\u0647 \u00ab\u0639\u06cc\u0633\u06cc \u062e\u062f\u0627\u0648\u0646\u062f \u0627\u0633\u062a\u00bb \u0648 \u062f\u0631 \u0642\u0644\u0628 \u062e\u0648\u062f \u0627\u06cc\u0645\u0627\u0646 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc \u06a9\u0647 \u062e\u062f\u0627 \u0627\u0648 \u0631\u0627 \u0627\u0632 \u0645\u0631\u062f\u06af\u0627\u0646 \u0628\u0631\u062e\u06cc\u0632\u0627\u0646\u06cc\u062f\u060c \u0646\u062c\u0627\u062a \u062e\u0648\u0627\u0647\u06cc \u06cc\u0627\u0641\u062a.\u00bb\n\u06f1\u06f0 \u0632\u06cc\u0631\u0627 \u0628\u0627 \u0642\u0644\u0628 \u062e\u0648\u062f \u0627\u06cc\u0645\u0627\u0646 \u0645\u06cc\u200c\u0622\u0648\u0631\u06cc\u062f \u0648 \u067e\u0627\u0631\u0633\u0627 \u0634\u0645\u0631\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u06cc\u062f\u060c \u0648 \u0628\u0627 \u0632\u0628\u0627\u0646 \u062e\u0648\u062f \u0627\u06cc\u0645\u0627\u0646 \u062e\u0648\u062f \u0631\u0627 \u0627\u0638\u0647\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f \u0648 \u0646\u062c\u0627\u062a \u0645\u06cc\u200c\u06cc\u0627\u0628\u06cc\u062f.\n\u06f1\u06f1 \u0686\u0646\u0627\u0646\u06a9\u0647 \u06a9\u062a\u0627\u0628 \u0645\u0642\u062f\u0633 \u0645\u06cc\u200c\u06af\u0648\u06cc\u062f: \u00ab\u0647\u0631 \u06a9\u0647 \u0628\u0647 \u0627\u0648 \u0627\u06cc\u0645\u0627\u0646 \u0622\u0648\u0631\u062f\u060c \u0647\u0631\u06af\u0632 \u0634\u0631\u0645\u0646\u062f\u0647 \u0646\u062e\u0648\u0627\u0647\u062f \u0634\u062f.\u00bb\n\n\u0622\u06cc\u0627 \u0628\u0627 \u0632\u0628\u0627\u0646 \u062e\u0648\u062f \u0627\u06cc\u0645\u0627\u0646 \u062e\u0648\u062f \u0631\u0627 \u0627\u0639\u0644\u0627\u0645 \u06a9\u0631\u062f\u06cc \u062a\u0627 \u0646\u062c\u0627\u062a \u06cc\u0627\u0628\u06cc\u061f\n\u0627\u06af\u0631 \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0631\u0627 \u0646\u06a9\u0631\u062f\u0647\u200c\u0627\u06cc\u062f\u060c \u0641\u06a9\u0631 \u0646\u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f \u0627\u0645\u0631\u0648\u0632 \u0631\u0648\u0632 \u062e\u06cc\u0644\u06cc \u062e\u0648\u0628\u06cc \u0628\u0631\u0627\u06cc \u0627\u0646\u062c\u0627\u0645 \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0628\u0627\u0634\u062f\u061f\n\u0631\u0648\u062d \u0627\u0644\u0642\u062f\u0633 \u0627\u06cc\u0646\u062c\u0627 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0645\u0627\u0633\u062a\u060c \u0648 \u0634\u0627\u06cc\u062f \u0627\u0648 \u062f\u0627\u0631\u062f \u062f\u0631 \u0642\u0644\u0628 \u0634\u0645\u0627 \u0632\u0645\u0632\u0645\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f:\n\u00ab\u0627\u0632 \u0631\u0627\u0647 \u06af\u0646\u0627\u0647 \u0648 \u0645\u0631\u06af \u0628\u0627\u0632\u06af\u0631\u062f\u06cc\u062f!\u00bb\n\u0628\u0627 \u0627\u0639\u0644\u0627\u0645 \u0627\u06cc\u0646\u06a9\u0647 \u00ab\u0639\u06cc\u0633\u06cc \u062e\u062f\u0627\u0648\u0646\u062f \u0627\u0633\u062a!\u00bb \u0632\u0646\u062f\u06af\u06cc \u062c\u062f\u06cc\u062f \u0648 \u0645\u0633\u06cc\u0631 \u062c\u062f\u06cc\u062f\u06cc \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.\n\n\u067e\u0648\u0644\u0633 \u0642\u0628\u0644\u0627\u064b \u06cc\u06a9 \u0628\u0627\u0631 \u062f\u0631 \u0645\u0648\u0631\u062f \u0622\u0646 \u062c\u0647\u062a \u062c\u062f\u06cc\u062f \u0646\u0648\u0634\u062a.\n\u0627\u06cc\u0646 \u062f\u0631 \u0646\u0627\u0645\u0647\u200c\u0627\u06cc \u0628\u0647 \u0647\u0645\u0627\u0646 \u06a9\u0644\u06cc\u0633\u0627\u06cc \u0627\u0641\u0633\u0633 \u0628\u0648\u062f\u060c \u062c\u0627\u06cc\u06cc \u06a9\u0647 \u062a\u06cc\u0645\u0648\u062a\u0627\u0626\u0648\u0633 \u0627\u06a9\u0646\u0648\u0646 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06a9\u0634\u06cc\u0634 \u062e\u062f\u0645\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f.\n\u0628\u0647 \u0622\u0646\u0686\u0647 \u067e\u0648\u0644\u0633 \u062f\u0631 \u0627\u0641\u0633\u0633\u06cc\u0627\u0646 \u06f2: \u06f1-\u06f5 \u0628\u0647 \u0645\u0624\u0645\u0646\u0627\u0646 \u0645\u0633\u06cc\u062d\u06cc \u0646\u0648\u0634\u062a\u060c \u062f\u0631 \u0645\u0648\u0631\u062f \u0622\u0646\u0686\u0647 \u062e\u062f\u0627 \u0628\u0631\u0627\u06cc \u0628\u062e\u0634\u06cc\u062f\u0646 \u0632\u0646\u062f\u06af\u06cc \u062c\u062f\u06cc\u062f \u0648 \u062c\u0647\u062a\u06cc \u0646\u0648 \u0628\u0647 \u0622\u0646\u0647\u0627 \u0627\u0646\u062c\u0627\u0645 \u062f\u0627\u062f\u060c \u06af\u0648\u0634 \u062f\u0647\u06cc\u062f:\n\u06f1 \u00ab\u0648 \u0634\u0645\u0627 \u062f\u0631 \u062e\u0637\u0627\u06cc\u0627 \u0648 \u06af\u0646\u0627\u0647\u0627\u0646 \u062e\u0648\u062f \u0645\u0631\u062f\u0647 \u0628\u0648\u062f\u06cc\u062f.\u00bb\n\u06f2 \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u0632\u0645\u0627\u0646\u06cc \u06af\u0627\u0645 \u0628\u0631\u0645\u06cc\u200c\u062f\u0627\u0634\u062a\u06cc\u062f\u060c \u062f\u0631 \u067e\u06cc\u0631\u0648\u06cc \u0627\u0632 \u0631\u0627\u0647 \u0627\u06cc\u0646 \u062c\u0647\u0627\u0646\u060c \u062f\u0631 \u067e\u06cc\u0631\u0648\u06cc \u0627\u0632 \u0631\u0626\u06cc\u0633 \u0642\u062f\u0631\u062a \u0647\u0648\u0627\u060c \u0647\u0645\u0627\u0646 \u0631\u0648\u062d\u06cc \u06a9\u0647 \u0627\u06a9\u0646\u0648\u0646 \u062f\u0631 \u0641\u0631\u0632\u0646\u062f\u0627\u0646 \u0645\u0639\u0635\u06cc\u062a \u0639\u0645\u0644 \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c\n\u06f3 \u06a9\u0647 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0622\u0646\u0647\u0627\u060c \u0647\u0645\u0647 \u0645\u0627 \u0632\u0645\u0627\u0646\u06cc \u062f\u0631 \u0634\u0647\u0648\u0627\u062a \u0646\u0641\u0633\u0627\u0646\u06cc \u062e\u0648\u062f \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u200c\u06a9\u0631\u062f\u06cc\u0645 \u0648 \u062e\u0648\u0627\u0633\u062a\u0647\u200c\u0647\u0627\u06cc \u062a\u0646 \u0648 \u0631\u0648\u0627\u0646 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u062c\u0627 \u0645\u06cc\u200c\u0622\u0648\u0631\u062f\u06cc\u0645 \u0648 \u0645\u0627\u0646\u0646\u062f \u0633\u0627\u06cc\u0631 \u0645\u0631\u062f\u0645\u060c \u0630\u0627\u062a\u0627\u064b \u0641\u0631\u0632\u0646\u062f\u0627\u0646 \u062e\u0634\u0645 \u0628\u0648\u062f\u06cc\u0645.\n\u06f4 \u0627\u0645\u0627 \u062e\u062f\u0627\u060c \u06a9\u0647 \u062f\u0631 \u0631\u062d\u0645\u062a \u0648 \u0628\u062e\u0634\u0634\u060c \u062f\u0648\u0644\u062a\u0645\u0646\u062f \u0627\u0633\u062a\u060c \u0628\u0647 \u0633\u0628\u0628 \u0645\u062d\u0628\u062a \u0639\u0638\u06cc\u0645\u06cc \u06a9\u0647 \u0628\u0647 \u0645\u0627 \u062f\u0627\u0634\u062a\u060c\n\u06f5 \u062d\u062a\u06cc \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u062f\u0631 \u06af\u0646\u0627\u0647\u0627\u0646 \u062e\u0648\u062f \u0645\u0631\u062f\u0647 \u0628\u0648\u062f\u06cc\u0645\u060c \u0645\u0627 \u0631\u0627 \u0628\u0627 \u0645\u0633\u06cc\u062d \u0632\u0646\u062f\u0647 \u06af\u0631\u062f\u0627\u0646\u06cc\u062f- \u0627\u0632 \u0631\u0627\u0647 \u0641\u06cc\u0636 \u0646\u062c\u0627\u062a \u06cc\u0627\u0641\u062a\u0647\u200c\u0627\u06cc\u062f!\n\n\u00ab\u0627\u0645\u0627 \u062e\u062f\u0627\u00bb \u062f\u0648 \u062a\u0627 \u0627\u0632 \u0632\u06cc\u0628\u0627\u062a\u0631\u06cc\u0646 \u06a9\u0644\u0645\u0627\u062a\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0647\u0631 \u06a9\u0633\u06cc \u0628\u0631 \u0632\u0628\u0627\u0646 \u0645\u06cc\u200c\u0622\u0648\u0631\u062f.\n\u067e\u0648\u0644\u0633 \u0628\u0647 \u0645\u0624\u0645\u0646\u0627\u0646 \u0627\u0641\u0633\u0633 \u06cc\u0627\u062f\u0622\u0648\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0622\u0646\u0647\u0627 \u0632\u0645\u0627\u0646\u06cc \u0645\u0627\u0646\u0646\u062f \u0622\u0646 \u062e\u0631\u06af\u0648\u0634 \u062f\u0631 \u062f\u0627\u0645 \u06af\u0631\u0641\u062a\u0627\u0631 \u0648 \u062f\u0631\u0645\u0627\u0646\u062f\u0647 \u0628\u0648\u062f\u0646\u062f.\n\u0627\u0645\u0627 \u062e\u062f\u0627 \u0641\u0642\u0637 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0641\u06cc\u0636\u060c \u0641\u0642\u0637 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0627\u06cc\u0645\u0627\u0646\u060c \u0641\u0642\u0637 \u062f\u0631 \u0645\u0633\u06cc\u062d\u060c \u0628\u0631\u0627\u06cc \u0646\u062c\u0627\u062a \u0622\u0646\u0647\u0627 \u0648\u0627\u0631\u062f \u0639\u0645\u0644 \u0634\u062f.\n\u0647\u0631 \u06a9\u0633\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0646\u062c\u0627\u062a \u06cc\u0627\u0628\u062f\u060c \u0627\u06af\u0631 \u0628\u0627\u0648\u0631 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0642\u0631\u0628\u0627\u0646\u06cc \u0645\u0633\u06cc\u062d \u0628\u0631 \u0631\u0648\u06cc \u0635\u0644\u06cc\u0628 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0628\u0648\u062f \u062a\u0627 \u0634\u0645\u0627 \u0631\u0627 \u0627\u0632 \u06af\u0646\u0627\u0647 \u0648 \u0634\u0631\u0645 \u0628\u0634\u0648\u06cc\u062f.\n\u0648\u0642\u062a\u06cc \u0628\u0647 \u0627\u06cc\u0646 \u0627\u06cc\u0645\u0627\u0646 \u0628\u06cc\u0627\u0648\u0631\u06cc\u062f\u060c \u0632\u0646\u062f\u06af\u06cc \u062c\u062f\u06cc\u062f\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f \u0648 \u0639\u06cc\u0633\u06cc \u0634\u0645\u0627 \u0631\u0627 \u062f\u0631 \u0645\u0633\u06cc\u0631 \u062c\u062f\u06cc\u062f\u06cc \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u062f\u0647\u062f.\n\u0686\u0646\u062f \u0622\u06cc\u0647 \u0628\u0639\u062f \u062f\u0631 \u0627\u0641\u0633\u0633\u06cc\u0627\u0646 \u06f2:\u06f8\u060c \u067e\u0648\u0644\u0633 \u062f\u0631\u0628\u0627\u0631\u0647 \u0622\u0646 \u062c\u0647\u062a \u062c\u062f\u06cc\u062f \u0635\u062d\u0628\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f.\n\u0627\u06cc\u0646\u0648 \u0628\u0627 \u0645\u0646 \u0628\u062e\u0648\u0646:\n\u0647\u0645\u0647: \u06f1\u06f0 \u00ab\u0632\u06cc\u0631\u0627 \u0645\u0627 \u0633\u0627\u062e\u062a\u0647\u200c\u06cc \u062f\u0633\u062a \u0627\u0648 \u0647\u0633\u062a\u06cc\u0645\u060c \u0622\u0641\u0631\u06cc\u062f\u0647 \u0634\u062f\u0647 \u062f\u0631 \u0645\u0633\u06cc\u062d \u0639\u06cc\u0633\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u0647\u0627\u06cc \u0646\u06cc\u06a9\u0648\u060c \u06a9\u0647 \u062e\u062f\u0627 \u0627\u0632 \u0642\u0628\u0644 \u0645\u0647\u06cc\u0627 \u06a9\u0631\u062f \u062a\u0627 \u062f\u0631 \u0622\u0646\u0647\u0627 \u0633\u0644\u0648\u06a9 \u06a9\u0646\u06cc\u0645.\u00bb\n\n\u0628\u0631\u0627\u06cc \u062a\u06a9\u0645\u06cc\u0644 \u0627\u06cc\u0646 \u067e\u06cc\u0627\u0645\u060c \u0628\u06cc\u0627\u06cc\u06cc\u062f \u0646\u06af\u0627\u0647\u06cc \u0628\u0647 \u0686\u06af\u0648\u0646\u06af\u06cc \u0627\u0646\u062c\u0627\u0645 \u06a9\u0627\u0631\u0647\u0627\u06cc \u0646\u06cc\u06a9 \u0628\u06cc\u0646\u062f\u0627\u0632\u06cc\u0645.\n\u0628\u0647 \u06cc\u0627\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u067e\u0648\u0644\u0633 \u0628\u0647 \u062a\u06cc\u0645\u0648\u062a\u0627\u0626\u0648\u0633 \u0645\u06cc\u200c\u0646\u0648\u06cc\u0633\u062f \u0648 \u0628\u0647 \u0627\u0648 \u0631\u0627\u0647\u0646\u0645\u0627\u06cc\u06cc \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0686\u0647 \u06a9\u0633\u0627\u0646\u06cc \u0631\u0627 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0645\u0639\u0644\u0645\u0627\u0646 \u06a9\u062a\u0627\u0628 \u0645\u0642\u062f\u0633 \u0627\u0646\u062a\u062e\u0627\u0628 \u0648 \u0622\u0645\u0648\u0632\u0634 \u062f\u0647\u062f.\n\u0648 \u0645\u0627\u0645\u0648\u0631\u06cc\u062a \u0645\u0627 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0627\u06cc\u0645\u0627\u0646\u062f\u0627\u0631\u0627\u0646 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0645\u0698\u062f\u0647 \u0627\u0646\u062c\u06cc\u0644 \u0631\u0627 \u0628\u0627 \u0645\u0631\u062f\u0645 \u062f\u0648\u0631 \u0648 \u0646\u0632\u062f\u06cc\u06a9 \u0628\u0647 \u0627\u0634\u062a\u0631\u0627\u06a9 \u0628\u06af\u0630\u0627\u0631\u06cc\u0645.\n\u0627\u0645\u0627 \u0628\u0631\u0627\u06cc \u0627\u0646\u062c\u0627\u0645 \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0628\u0627 \u0627\u06cc\u0645\u0627\u0646\u060c \u0628\u0627\u06cc\u062f \u0634\u062e\u0635\u06cc\u062a\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u0645 \u06a9\u0647 \u067e\u0648\u0644\u0633 \u062f\u0631 \u0627\u06cc\u0646 \u0622\u06cc\u0627\u062a \u062a\u0648\u0635\u06cc\u0641 \u0645\u06cc\u200c\u06a9\u0646\u062f.\n\u0645\u0627 \u0646\u0645\u06cc\u062a\u0648\u0646\u06cc\u0645 \u0642\u0644\u0628 \u06a9\u0633\u06cc \u0631\u0648 \u0639\u0648\u0636 \u06a9\u0646\u06cc\u0645.\n\u0627\u0645\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u0645 \u062d\u0642\u06cc\u0642\u062a \u0631\u0627 \u0628\u0627 \u0645\u0644\u0627\u06cc\u0645\u062a\u060c \u0645\u0647\u0631\u0628\u0627\u0646\u06cc \u0648 \u0635\u0628\u0631 \u0628\u0647 \u0622\u0646\u0647\u0627 \u0628\u06af\u0648\u06cc\u06cc\u0645.\n\u0648 \u0645\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u0645 \u0627\u0639\u062a\u0645\u0627\u062f \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u062e\u062f\u0627\u0648\u0646\u062f \u062f\u0631 \u0632\u0645\u0627\u0646 \u0645\u0646\u0627\u0633\u0628 \u062a\u0648\u0628\u0647 \u0631\u0627 \u0628\u0647 \u0641\u0631\u0632\u0646\u062f\u0627\u0646 \u0628\u0631\u06af\u0632\u06cc\u062f\u0647 \u062e\u0648\u062f \u0639\u0637\u0627 \u062e\u0648\u0627\u0647\u062f \u06a9\u0631\u062f.\n\u062f\u0631 \u0622\u06cc\u0627\u062a \u06f2\u06f4 \u0648 \u06f2\u06f5 \u0645\u062a\u0646 \u0627\u0645\u0631\u0648\u0632\u060c \u067e\u0646\u062c \u0648\u06cc\u0698\u06af\u06cc \u0631\u0627 \u0645\u06cc\u200c\u0628\u06cc\u0646\u0645 \u06a9\u0647 \u062e\u062f\u0627 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u062f \u062f\u0631 \u0628\u0646\u062f\u06af\u0627\u0646\u0634 \u067e\u0631\u0648\u0631\u0634 \u062f\u0647\u062f:\n\n\u0648\u06cc\u0698\u06af\u06cc \u0627\u0648\u0644: \u0627\u0647\u0644 \u062f\u0639\u0648\u0627 \u0648 \u062c\u062f\u0644 \u0646\u06cc\u0633\u062a.\n\u0628\u0639\u0636\u06cc\u200c\u0647\u0627 \u062f\u0648\u0633\u062a \u062f\u0627\u0631\u0646\u062f \u0628\u062d\u062b \u0648 \u062c\u062f\u0644 \u06a9\u0646\u0646\u062f.\n\u0628\u062d\u062b \u0633\u0627\u0644\u0645 \u0647\u06cc\u0686 \u0627\u0634\u06a9\u0627\u0644\u06cc \u0646\u062f\u0627\u0631\u062f.\n\u0627\u0645\u0627 \u0627\u0632 \u06a9\u062c\u0627 \u0645\u06cc\u200c\u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u0686\u0647 \u0632\u0645\u0627\u0646\u06cc \u062f\u0627\u0631\u06cc\u062f \u0628\u0647 \u0637\u0648\u0631 \u06af\u0646\u0627\u0647\u200c\u0622\u0644\u0648\u062f\u06cc \u00ab\u0633\u062a\u06cc\u0632\u0647\u200c\u062c\u0648\u00bb \u0645\u06cc\u200c\u0634\u0648\u06cc\u062f\u061f\n\u0634\u0627\u06cc\u062f \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u06cc\u0646 \u0633\u0648\u0627\u0644 \u0631\u0627 \u0627\u0632 \u062e\u0648\u062f\u062a\u0627\u0646 \u0628\u067e\u0631\u0633\u06cc\u062f:\n\u00ab\u0648\u0642\u062a\u06cc \u0628\u0627 \u06a9\u0633\u06cc \u0628\u062d\u062b \u0645\u06cc\u200c\u06a9\u0646\u0645\u060c \u0622\u06cc\u0627 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0647 \u0622\u0646 \u0634\u062e\u0635 \u0627\u0647\u0645\u06cc\u062a \u0645\u06cc\u200c\u062f\u0647\u0645 \u06cc\u0627 \u0628\u0647 \u0628\u0631\u0646\u062f\u0647 \u0634\u062f\u0646 \u062f\u0631 \u0628\u062d\u062b\u061f\n\u0622\u06cc\u0627 \u063a\u0631\u0648\u0631\u0645 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u0628\u0647 \u062c\u0627\u06cc \u0645\u0647\u0631\u0628\u0627\u0646 \u0628\u0648\u062f\u0646\u060c \u0631\u0648\u06cc \u062f\u0631\u0633\u062a \u0628\u0648\u062f\u0646 \u062a\u0645\u0631\u06a9\u0632 \u06a9\u0646\u0645\u061f\n\n\u0648\u06cc\u0698\u06af\u06cc \u062f\u0648\u0645: \u0628\u0627 \u0647\u0645\u0647 \u0645\u0647\u0631\u0628\u0627\u0646 \u0627\u0633\u062a.\n\u0628\u0646\u062f\u0647 \u062e\u062f\u0627 \u0628\u0627\u06cc\u062f \u0628\u0627 \u0647\u0645\u0647 \u0645\u0647\u0631\u0628\u0627\u0646 \u0628\u0627\u0634\u062f.\n\u062d\u062a\u06cc \u0628\u0647 \u0622\u062f\u0645\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0632\u062a \u0645\u062a\u0646\u0641\u0631\u0646 \u0648 \u0645\u06cc\u200c\u062e\u0648\u0627\u0646 \u0628\u0647\u062a \u0622\u0633\u06cc\u0628 \u0628\u0632\u0646\u0646.\n\u0633\u062e\u062a\u0647\u060c \u0645\u06cc\u200c\u062f\u0648\u0646\u0645.\n\u0645\u0627 \u0641\u06a9\u0631 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0631\u0627\u0647 \u0645\u062d\u0627\u0641\u0638\u062a \u0627\u0632 \u062e\u0648\u062f\u0645\u0627\u0646 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u062f\u06cc\u06af\u0631\u0627\u0646\u060c \u0642\u0648\u06cc \u0628\u0648\u062f\u0646 \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0642\u062f\u0631\u062a \u0627\u0633\u062a.\n\u0627\u0645\u0627 \u0628\u0647 \u0622\u0646\u0686\u0647 \u067e\u0648\u0644\u0633 \u062f\u0631 \u0631\u0648\u0645\u06cc\u0627\u0646 \u06f2:\u06f4 \u0628\u0647 \u0645\u0627 \u06cc\u0627\u062f\u0622\u0648\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f:\n\u00ab\u0645\u0647\u0631\u0628\u0627\u0646\u06cc \u062e\u062f\u0627 \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0634\u0645\u0627 \u0631\u0627 \u0628\u0647 \u062a\u0648\u0628\u0647 \u0647\u062f\u0627\u06cc\u062a \u06a9\u0646\u062f.\u00bb\n\u0648\u0642\u062a\u06cc \u062f\u0631 \u06af\u0646\u0627\u0647 \u0628\u0648\u062f\u06cc\u062f \u0648 \u0627\u0632 \u0627\u0648 \u0641\u0631\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0631\u062f\u06cc\u062f\u060c \u0639\u06cc\u0633\u06cc \u0686\u0642\u062f\u0631 \u0628\u0627 \u0634\u0645\u0627 \u0645\u0647\u0631\u0628\u0627\u0646 \u0628\u0648\u062f\u061f\n\u0645\u0647\u0631\u0628\u0627\u0646\u06cc \u0627\u0648 \u062a\u0648 \u0631\u0627 \u0628\u0647 \u062a\u0648\u0628\u0647 \u0648\u0627\u062f\u0627\u0634\u062a\u060c\n\u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0627\u06a9\u0646\u0648\u0646 \u0634\u0645\u0627 \u0627\u06cc\u0646 \u0641\u0631\u0635\u062a \u0631\u0627 \u062f\u0627\u0631\u06cc\u062f \u06a9\u0647 \u0627\u0632 \u0645\u0633\u06cc\u062d \u062a\u0642\u0644\u06cc\u062f \u06a9\u0646\u06cc\u062f \u0648 \u0628\u0627 \u0647\u0645\u0647 \u0645\u0647\u0631\u0628\u0627\u0646 \u0628\u0627\u0634\u06cc\u062f.\n\n\u0648\u06cc\u0698\u06af\u06cc \u0633\u0648\u0645: \u0635\u0628\u0631 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0628\u062f\u06cc.\n\u0648\u0642\u062a\u06cc \u062d\u0642\u06cc\u0642\u062a \u0627\u0646\u062c\u06cc\u0644 \u0631\u0627 \u0628\u0647 \u0627\u0634\u062a\u0631\u0627\u06a9 \u0645\u06cc\u200c\u06af\u0630\u0627\u0631\u06cc\u0645\u060c \u0628\u0627 \u0645\u062e\u0627\u0644\u0641\u062a \u0627\u0641\u0631\u0627\u062f\u06cc \u0645\u0648\u0627\u062c\u0647 \u062e\u0648\u0627\u0647\u06cc\u0645 \u0634\u062f \u06a9\u0647 \u062d\u0631\u0641\u200c\u0647\u0627\u06cc \u0645\u0627 \u0631\u0627 \u062f\u0648\u0633\u062a \u0646\u062f\u0627\u0631\u0646\u062f.\n\u06cc\u0627\u062f\u062a \u0647\u0633\u062a \u0627\u0633\u062a\u06cc\u0641\u0627\u0646 \u0686\u0637\u0648\u0631 \u0628\u0647 \u0642\u0627\u062a\u0644\u0627\u0646\u0634 \u0648\u0627\u06a9\u0646\u0634 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u061f\n\u0627\u0639\u0645\u0627\u0644 \u0631\u0633\u0648\u0644\u0627\u0646 \u06f7: \u06f5\u06f9-\u06f6\u06f0 \u0645\u06cc\u200c\u06af\u0648\u06cc\u062f:\n\u06f5\u06f9 \u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u0627\u0648 \u0631\u0627 \u0633\u0646\u06af\u0633\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0631\u062f\u0646\u062f\u060c \u0627\u0633\u062a\u06cc\u0641\u0627\u0646 \u062f\u0639\u0627 \u06a9\u0631\u062f \u0648 \u06af\u0641\u062a: \u00ab\u0627\u06cc \u0639\u06cc\u0633\u06cc \u062e\u062f\u0627\u0648\u0646\u062f\u060c \u0631\u0648\u062d \u0645\u0631\u0627 \u0628\u067e\u0630\u06cc\u0631.\u00bb\n\u06f6\u06f0 \u0633\u067e\u0633 \u0628\u0647 \u0632\u0627\u0646\u0648 \u0627\u0641\u062a\u0627\u062f \u0648 \u0641\u0631\u06cc\u0627\u062f \u0632\u062f: \u00ab\u062e\u062f\u0627\u0648\u0646\u062f\u0627\u060c \u0627\u06cc\u0646 \u06af\u0646\u0627\u0647 \u0631\u0627 \u0628\u0647 \u062d\u0633\u0627\u0628 \u0627\u06cc\u0634\u0627\u0646 \u0646\u06af\u0630\u0627\u0631.\u00bb\n\n\u0641\u0642\u0637 \u062e\u062f\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0645\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u062f \u062a\u0627 \u0645\u0627\u0646\u0646\u062f \u0627\u0633\u062a\u06cc\u0641\u0627\u0646\u060c \u0628\u0627 \u0635\u0628\u0631 \u0648 \u0634\u06a9\u06cc\u0628\u0627\u06cc\u06cc \u0628\u062f\u06cc \u0631\u0627 \u062a\u062d\u0645\u0644 \u06a9\u0646\u06cc\u0645.\n\u0627\u0645\u0627 \u0627\u0648 \u0628\u0647 \u0645\u0627 \u06a9\u0645\u06a9 \u062e\u0648\u0627\u0647\u062f \u06a9\u0631\u062f\u060c \u0648\u0642\u062a\u06cc \u06a9\u0647 \u062f\u0631 \u0645\u0648\u0627\u0642\u0639 \u0633\u062e\u062a\u06cc \u0627\u0648 \u0631\u0627 \u0635\u062f\u0627 \u0628\u0632\u0646\u06cc\u0645.\n\u0627\u0648 \u0628\u0647 \u0645\u0627 \u06a9\u0645\u06a9 \u062e\u0648\u0627\u0647\u062f \u06a9\u0631\u062f \u062a\u0627 \u0628\u0647 \u0627\u0648 \u0627\u0639\u062a\u0645\u0627\u062f \u06a9\u0646\u06cc\u0645\u060c \u0648 \u0628\u062f\u0627\u0646\u06cc\u0645 \u06a9\u0647 \u0631\u0648\u062d \u0645\u0627 \u062f\u0631 \u062f\u0633\u062a\u0627\u0646 \u0627\u0648\u0633\u062a\u060c \u0641\u0627\u0631\u063a \u0627\u0632 \u0627\u06cc\u0646\u06a9\u0647 \u0686\u0647 \u0627\u062a\u0641\u0627\u0642\u06cc \u0628\u0631\u0627\u06cc \u0628\u062f\u0646 \u0645\u0627 \u0645\u06cc\u200c\u0627\u0641\u062a\u062f.\n\n\u0648\u06cc\u0698\u06af\u06cc \u0686\u0647\u0627\u0631\u0645: \u0627\u0635\u0644\u0627\u062d \u06a9\u0631\u062f\u0646 \u0628\u0627 \u0645\u0644\u0627\u06cc\u0645\u062a.\n\u0627\u0635\u0644\u0627\u062d \u0627\u0641\u0631\u0627\u062f \u06a9\u0627\u0631 \u0633\u062e\u062a\u06cc \u0627\u0633\u062a.\n\u0627\u0645\u0627 \u0627\u06af\u0631 \u067e\u0633\u0631\u0645 \u06a9\u0627\u0631 \u0627\u0634\u062a\u0628\u0627\u0647\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u062f\u0647\u062f\u060c \u0628\u0647 \u0627\u0648 \u0645\u06cc\u200c\u06af\u0648\u06cc\u0645 \u0686\u0648\u0646 \u062f\u0648\u0633\u062a\u0634 \u062f\u0627\u0631\u0645.\n\u0627\u06cc\u0646 \u0633\u0648\u0627\u0644 \u0645\u0647\u0645\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0648\u0642\u062a\u06cc \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u06a9\u0633\u06cc \u0631\u0627 \u0627\u0635\u0644\u0627\u062d \u06a9\u0646\u06cc\u062f\u060c \u0628\u0627\u06cc\u062f \u0628\u0647 \u0622\u0646 \u0641\u06a9\u0631 \u06a9\u0646\u06cc\u062f:\n\u00ab\u0622\u06cc\u0627 \u0641\u0631\u0632\u0646\u062f\u060c \u062f\u0648\u0633\u062a \u06cc\u0627 \u0647\u0645\u0633\u0631\u0645 \u0639\u0634\u0642 \u0645\u0631\u0627 \u062d\u0633 \u0645\u06cc\u200c\u06a9\u0646\u062f\u061f\u00bb\n\u06cc\u0627 \u0641\u0642\u0637 \u062e\u0634\u0645 \u0645\u0631\u0627 \u062d\u0633 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u061f\n\n\u0648\u0642\u062a\u06cc \u0628\u0627 \u0639\u0635\u0628\u0627\u0646\u06cc\u062a \u06cc\u0627 \u0646\u0627\u0627\u0645\u06cc\u062f\u06cc \u062f\u06cc\u06af\u0631\u0627\u0646 \u0631\u0627 \u0627\u0635\u0644\u0627\u062d \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645\u060c \u0637\u0648\u0631\u06cc \u0631\u0641\u062a\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0627\u0646\u06af\u0627\u0631 \u062e\u062f\u0627 \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0637\u0631\u0641 \u0645\u0642\u0627\u0628\u0644 \u0631\u0627 \u062a\u063a\u06cc\u06cc\u0631 \u062f\u0647\u062f.\n\u0645\u0627 \u0641\u06a9\u0631 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u0645 \u0622\u0646\u0647\u0627 \u0631\u0627 \u0628\u0631\u0627\u06cc \u062a\u063a\u06cc\u06cc\u0631 \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u0645\u060c \u06cc\u0627 \u0628\u0644\u0646\u062f\u062a\u0631 \u0641\u0631\u06cc\u0627\u062f \u0628\u0632\u0646\u06cc\u0645 \u062a\u0627 \u062f\u0631 \u0645\u0633\u06cc\u0631 \u062f\u0631\u0633\u062a \u0642\u0631\u0627\u0631 \u0628\u06af\u06cc\u0631\u0646\u062f.\n\u0627\u0645\u0627 \u0645\u0639\u0644\u0645\u06cc \u06a9\u0647 \u0645\u06cc\u200c\u062f\u0627\u0646\u062f \u0642\u062f\u0631\u062a \u0648\u0627\u0642\u0639\u06cc \u062f\u0633\u062a \u062e\u062f\u0627\u0633\u062a\u060c \u0645\u0644\u0627\u06cc\u0645\u060c \u0635\u0628\u0648\u0631 \u0648 \u0645\u0647\u0631\u0628\u0627\u0646 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.\n\n\u0648\u06cc\u0698\u06af\u06cc \u067e\u0646\u062c\u0645: \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u062a\u062f\u0631\u06cc\u0633\n\u0622\u06cc\u0627 \u06a9\u0644\u0627\u0645 \u062e\u062f\u0627 \u0631\u0627 \u0628\u0647 \u0627\u0646\u062f\u0627\u0632\u0647 \u06a9\u0627\u0641\u06cc \u062e\u0648\u0628 \u0645\u06cc\u200c\u0641\u0647\u0645\u06cc\u062f \u06a9\u0647 \u0622\u0646 \u0631\u0627 \u0628\u0631\u0627\u06cc \u062f\u06cc\u06af\u0631\u0627\u0646 \u062a\u0648\u0636\u06cc\u062d \u062f\u0647\u06cc\u062f\u061f\n\u0622\u06cc\u0627 \u0634\u0645\u0627 \u062f\u0631 \u062d\u0627\u0644 \u062d\u0641\u0638 \u06a9\u0631\u062f\u0646 \u0622\u06cc\u0627\u062a \u06a9\u062a\u0627\u0628 \u0645\u0642\u062f\u0633 \u0647\u0633\u062a\u06cc\u062f\u060c \u062a\u0627 \u0622\u0646 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0631\u0627\u0647\u0646\u0645\u0627\u06cc\u06cc \u062e\u0648\u062f \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u0648 \u0628\u0647 \u0627\u0634\u062a\u0631\u0627\u06a9 \u06af\u0630\u0627\u0634\u062a\u0646 \u0628\u0627 \u062f\u06cc\u06af\u0631\u0627\u0646 \u0622\u0645\u0627\u062f\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f\u061f\n\u0642\u0631\u0627\u0631\u0647 \u0627\u06cc\u0646 \u0645\u0627\u0647 \u06cc\u0647 \u06a9\u0627\u0631 \u062c\u062f\u06cc\u062f \u0634\u0631\u0648\u0639 \u06a9\u0646\u06cc\u0645.\n\u0627\u0632 \u0634\u0645\u0627 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u0645 \u06a9\u0647 \u062a\u0627 \u067e\u0627\u06cc\u0627\u0646 \u0645\u0627\u0647 \u0645\u0627\u0631\u0633 \u06cc\u06a9 \u0622\u06cc\u0647 \u0627\u0632 \u06a9\u062a\u0627\u0628 \u0645\u0642\u062f\u0633 \u0631\u0627 \u062d\u0641\u0638 \u06a9\u0646\u06cc\u062f.\n\u0648 \u0627\u06af\u0631 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0647\u0631 \u0632\u0628\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0647\u0628\u0631\u0627\u0646 \u0645\u0627 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f\u060c \u06cc\u06a9 \u0628\u0631\u0686\u0633\u0628 \u062f\u0631\u06cc\u0627\u0641\u062a \u062e\u0648\u0627\u0647\u06cc\u062f \u06a9\u0631\u062f.\n\u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0622\u0646 \u0631\u0627 \u0631\u0648\u06cc \u0628\u0637\u0631\u06cc \u0622\u0628 \u06cc\u0627 \u062f\u0641\u062a\u0631\u0686\u0647 \u06cc\u0627\u062f\u062f\u0627\u0634\u062a \u062e\u0648\u062f \u0628\u0686\u0633\u0628\u0627\u0646\u06cc\u062f.\n\u0647\u0631 \u062c\u0627\u06cc\u06cc \u06a9\u0647 \u0622\u0646 \u0631\u0627 \u0628\u0628\u06cc\u0646\u06cc\u062f \u0648 \u062a\u0645\u0627\u0645 \u0633\u0627\u0644 \u0628\u0647 \u062a\u0645\u0631\u06cc\u0646 \u0622\u0646 \u0627\u062f\u0627\u0645\u0647 \u062f\u0647\u06cc\u062f.\n\u0628\u06cc\u0627\u06cc\u06cc\u062f \u0622\u06cc\u0647 \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0645\u0627\u0647 \u0645\u0627\u0631\u0633\u060c \u062f\u0648\u0645 \u062a\u06cc\u0645\u0648\u062a\u0627\u0626\u0648\u0633 \u06f3:\u06f1\u06f6 \u0631\u0627 \u0628\u0627 \u0647\u0645 \u0628\u062e\u0648\u0627\u0646\u06cc\u0645.\n\u0647\u0645\u0647: \u00ab\u062a\u0645\u0627\u0645 \u06a9\u062a\u0627\u0628 \u0645\u0642\u062f\u0633 \u0627\u0644\u0647\u0627\u0645 \u062e\u062f\u0627\u0633\u062a \u0648 \u0628\u0631\u0627\u06cc \u062a\u0639\u0644\u06cc\u0645\u060c \u062a\u0648\u0628\u06cc\u062e\u060c \u0627\u0635\u0644\u0627\u062d \u0648 \u062a\u0631\u0628\u06cc\u062a \u062f\u0631 \u067e\u0627\u0631\u0633\u0627\u06cc\u06cc \u0645\u0641\u06cc\u062f \u0627\u0633\u062a.\u00bb\n\n\u0647\u0645\u0647 \u0645\u0627 \u0628\u0631\u0627\u06cc \u0627\u062f\u0627\u0645\u0647 \u062f\u0627\u062f\u0646 \u062f\u0631 \u0645\u0633\u06cc\u0631 \u062f\u0631\u0633\u062a \u0628\u0647 \u06a9\u0645\u06a9 \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u06cc\u0645.\n\u0645\u0627 \u0628\u0647 \u06a9\u0644\u0627\u0645 \u062e\u062f\u0627 \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u06cc\u0645 \u062a\u0627 \u0645\u0627 \u0631\u0627 \u062a\u0639\u0644\u06cc\u0645 \u062f\u0647\u062f\u060c \u0627\u0635\u0644\u0627\u062d \u06a9\u0646\u062f \u0648 \u0628\u0631\u0627\u06cc \u06af\u0627\u0645 \u0628\u0631\u062f\u0627\u0634\u062a\u0646 \u062f\u0631 \u0631\u0627\u0647 \u062f\u0631\u0633\u062a \u062a\u0631\u0628\u06cc\u062a \u06a9\u0646\u062f.\n\u0648 \u0645\u0627 \u0628\u0647 \u0631\u0648\u062d \u0627\u0644\u0642\u062f\u0633 \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u06cc\u0645 \u062a\u0627 \u0628\u0647 \u0645\u0627 \u062f\u0631 \u062f\u0631\u06a9 \u0648 \u0628\u0647 \u06a9\u0627\u0631\u06af\u06cc\u0631\u06cc \u06a9\u0644\u0627\u0645 \u06a9\u0645\u06a9 \u06a9\u0646\u062f\u060c \u067e\u0633 \u0628\u06cc\u0627\u06cc\u06cc\u062f \u0627\u06a9\u0646\u0648\u0646 \u062f\u0631 \u062f\u0639\u0627\u060c \u0642\u0644\u0628\u200c\u0647\u0627\u06cc\u0645\u0627\u0646 \u0631\u0627 \u0628\u0647 \u0633\u0648\u06cc \u0622\u0633\u0645\u0627\u0646 \u0628\u06af\u0631\u062f\u0627\u0646\u06cc\u0645.\n\u0627\u06cc \u0639\u06cc\u0633\u06cc\u060c \u0645\u0627 \u0641\u0642\u0637 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u0645 \u0628\u0627 \u067e\u062f\u0631 \u0635\u062d\u0628\u062a \u06a9\u0646\u06cc\u0645 \u0632\u06cc\u0631\u0627 \u062a\u0648 \u067e\u0644\u06cc \u0628\u06cc\u0646 \u0632\u0645\u06cc\u0646 \u0648 \u0622\u0633\u0645\u0627\u0646 \u0633\u0627\u062e\u062a\u0647\u200c\u0627\u06cc.\n\u062a\u0648 \u062f\u0627\u0645\u200c\u0647\u0627\u06cc \u0634\u06cc\u0637\u0627\u0646 \u0631\u0627 \u0627\u0632 \u0628\u06cc\u0646 \u0628\u0631\u062f\u06cc \u0648 \u0686\u0634\u0645\u0627\u0646 \u0645\u0627 \u0631\u0627 \u0628\u0647 \u0631\u0648\u06cc \u062d\u0642\u06cc\u0642\u062a \u06af\u0634\u0648\u062f\u06cc.\n\u067e\u062f\u0631\u060c \u0627\u0632 \u062a\u0648 \u0633\u067e\u0627\u0633\u06af\u0632\u0627\u0631\u0645 \u06a9\u0647 \u0628\u0647 \u0645\u0627 \u0647\u062f\u06cc\u0647 \u062a\u0648\u0628\u0647 \u0631\u0627 \u0639\u0637\u0627 \u06a9\u0631\u062f\u06cc \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u0645 \u0628\u0627 \u062e\u0648\u062f\u0645\u0627\u0646 \u0648 \u0628\u0627 \u062a\u0648 \u062f\u0631 \u0645\u0648\u0631\u062f \u06af\u0646\u0627\u0647\u0627\u0646\u0645\u0627\u0646 \u0635\u0627\u062f\u0642 \u0628\u0627\u0634\u06cc\u0645.\n\u0648 \u0627\u06cc \u0631\u0648\u062d \u0627\u0644\u0642\u062f\u0633\u060c \u0627\u0632 \u062a\u0648 \u0633\u067e\u0627\u0633\u06af\u0632\u0627\u0631\u0645 \u06a9\u0647 \u0628\u0647 \u0645\u0627 \u0627\u06cc\u0645\u0627\u0646 \u0639\u0637\u0627 \u0641\u0631\u0645\u0648\u062f\u06cc \u062a\u0627 \u0628\u0631\u0627\u06cc \u0646\u062c\u0627\u062a \u062e\u0648\u062f \u0628\u0647 \u0639\u06cc\u0633\u06cc \u0645\u0633\u06cc\u062d \u0631\u0648\u06cc \u0622\u0648\u0631\u06cc\u0645.\n\u0630\u0647\u0646 \u0648 \u0642\u0644\u0628 \u062e\u0648\u062f \u0631\u0627 \u0628\u0627\u0632 \u06a9\u0646\u06cc\u0645 \u062a\u0627 \u06a9\u0644\u0627\u0645 \u0631\u0627 \u0628\u0641\u0647\u0645\u06cc\u0645 \u0648 \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0628\u0647 \u06a9\u0627\u0631 \u0628\u0628\u0631\u06cc\u0645.\n\u06a9\u0645\u06a9\u0645\u0627\u0646 \u06a9\u0646 \u062a\u0627 \u062f\u0631 \u0645\u0633\u0627\u0628\u0642\u0647\u200c\u0627\u06cc \u06a9\u0647 \u067e\u06cc\u0634 \u0631\u0648\u06cc\u0645\u0627\u0646 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0647\u060c \u0628\u0627 \u0642\u062f\u0631\u062a \u0628\u062f\u0648\u06cc\u0645 \u0648 \u062f\u06cc\u06af\u0631\u0627\u0646 \u0631\u0627 \u062f\u0639\u0648\u062a \u06a9\u0646\u06cc\u0645 \u062a\u0627 \u062f\u0631 \u0633\u0641\u0631 \u0628\u0647 \u0633\u0648\u06cc \u06a9\u0645\u0627\u0644\u060c \u0627\u0645\u06cc\u062f \u0648 \u0628\u0647\u0634\u062a \u200b\u200b\u0628\u0647 \u0645\u0627 \u0628\u067e\u06cc\u0648\u0646\u062f\u0646\u062f\u060c \u0622\u0645\u06cc\u0646.\n\n\u0633\u0648\u0627\u0644\u0627\u062a\u06cc \u0628\u0631\u0627\u06cc \u0645\u062f\u06cc\u062a\u06cc\u0634\u0646 \u0648 \u0628\u062d\u062b\n1.  \u062f\u0648\u0645 \u062a\u06cc\u0645\u0648\u062a\u0627\u0626\u0648\u0633 \u06f2:\u06f2\u06f2 \u0648 \u0645\u0632\u0645\u0648\u0631 \u06f1\u06f1\u06f9:\u06f3\u06f5-\u06f3\u06f7 \u0631\u0627 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f.\n\u0627\u0644\u0641) \u0648\u0642\u062a\u06cc \u0627\u0633\u062a\u0631\u0633 \u062f\u0627\u0631\u06cc\u062f \u06cc\u0627 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0622\u0631\u0627\u0645\u0634 \u0647\u0633\u062a\u06cc\u062f\u060c \u0642\u0644\u0628\u062a\u0627\u0646 \u0628\u0647 \u0637\u0648\u0631 \u0637\u0628\u06cc\u0639\u06cc \u0628\u0647 \u0633\u0645\u062a \u06a9\u062f\u0627\u0645 \u06cc\u06a9 \u0627\u0632 \u00ab\u0627\u0634\u062a\u06cc\u0627\u0642\u200c\u0647\u0627\u06cc \u062c\u0648\u0627\u0646\u06cc\u00bb (\u0644\u0630\u062a\u060c \u0642\u062f\u0631\u062a\u060c \u0645\u062d\u0628\u0648\u0628\u06cc\u062a\u060c \u062f\u0627\u0631\u0627\u06cc\u06cc\u060c \u063a\u0631\u0648\u0631) \u06af\u0631\u0627\u06cc\u0634 \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f\u061f\n\n2.  \u0627\u0641\u0633\u0633\u06cc\u0627\u0646 \u06f2: \u06f1-\u06f5 \u0648 \u062d\u0632\u0642\u06cc\u0627\u0644 \u06f3\u06f6:\u06f2\u06f6 \u0631\u0627 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f.\n\u0627\u0644\u0641) \u0628\u0631\u0627\u06cc \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0646 \u0627\u0632 \u00ab\u0645\u0631\u062f\u0647\u00bb \u0628\u0647 \u00ab\u0632\u0646\u062f\u0647\u00bb \u0686\u0647 \u0686\u06cc\u0632\u06cc \u0644\u0627\u0632\u0645 \u0627\u0633\u062a\u061f\n\u0628) \u0622\u06cc\u0627 \u0628\u0627\u0648\u0631 \u0628\u0647 \u0627\u06cc\u0646\u06a9\u0647 \u062a\u0648\u0628\u0647 \u0647\u062f\u06cc\u0647\u200c\u0627\u06cc \u0627\u0632 \u062c\u0627\u0646\u0628 \u0644\u0637\u0641 \u0627\u0644\u0647\u06cc \u0627\u0633\u062a\u060c \u0628\u0647 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u062f\u0631 \u0645\u0648\u0631\u062f \u06af\u0646\u0627\u0647 \u062e\u0648\u062f \u0628\u0627 \u062e\u062f\u0627 \u0635\u0627\u062f\u0642\u200c\u062a\u0631 \u0628\u0627\u0634\u06cc\u062f\u061f\n\n3.  \u062f\u0648\u0645 \u062a\u06cc\u0645\u0648\u062a\u0627\u0626\u0648\u0633 \u06f2:\u06f2\u06f3-\u06f2\u06f5 \u0648 \u06a9\u0648\u0644\u0633\u06cc\u0627\u0646 \u06f3:\u06f1\u06f2-\u06f1\u06f4 \u0631\u0627 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f.\n\u0627\u0644\u0641) \u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u00ab\u0628\u0646\u062f\u0647\u200c\u06cc \u062e\u062f\u0627\u0648\u0646\u062f\u00bb \u0647\u0646\u06af\u0627\u0645 \u0628\u062d\u062b \u06cc\u0627 \u0627\u0635\u0644\u0627\u062d \u062f\u06cc\u06af\u0631\u0627\u0646 \u0686\u06cc\u0633\u062a\u061f\n\u0628) \u0627\u0632 \u0622\u0646\u062c\u0627 \u06a9\u0647 \u0639\u06cc\u0633\u06cc \u0645\u0627 \u0631\u0627 \u0628\u0627 \u0635\u0628\u0631 \u0648 \u0645\u0644\u0627\u06cc\u0645\u062a \u0628\u0633\u06cc\u0627\u0631 \u062f\u0648\u0633\u062a \u062f\u0627\u0634\u062a\u060c \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0686\u0647 \u06a9\u0633\u06cc \u0631\u0627 \u0628\u0627 \u0647\u0645\u0627\u0646 \u0644\u0637\u0641 \u062f\u0648\u0633\u062a \u062e\u0648\u0627\u0647\u06cc\u062f \u062f\u0627\u0634\u062a- \u062d\u062a\u06cc \u0627\u06af\u0631 \u0628\u0627 \u0634\u0645\u0627 \u0645\u062e\u0627\u0644\u0641 \u0628\u0627\u0634\u0646\u062f \u06cc\u0627 \u0634\u0645\u0627 \u0631\u0627 \u062f\u0648\u0633\u062a \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u061f\n\n4.  \u0631\u0648\u0645\u06cc\u0627\u0646 \u06f1\u06f0: \u06f9-\u06f1\u06f1 \u0648 \u0639\u0628\u0631\u0627\u0646\u06cc\u0627\u0646 \u06f1\u06f2: \u06f1-\u06f2 \u0631\u0627 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f.\n\u0627\u0644\u0641) \u0686\u06af\u0648\u0646\u0647 \u0686\u0634\u0645 \u062f\u0648\u062e\u062a\u0646 \u0628\u0647 \u0639\u06cc\u0633\u06cc \u0628\u0647 \u0645\u0627 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u0627\u0632 \u06af\u0646\u0627\u0647 \u0631\u0648\u06cc \u0628\u0631\u06af\u0631\u062f\u0627\u0646\u06cc\u0645 \u0648 \u062f\u0631 \u0645\u0633\u06cc\u0631 \u062c\u062f\u06cc\u062f\u06cc \u06af\u0627\u0645 \u0628\u0631\u062f\u0627\u0631\u06cc\u0645\u061f\n\u0628) \u0628\u0647 \u06cc\u0627\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u062f\u0648\u0645 \u062a\u06cc\u0645\u0648\u062a\u0627\u0626\u0648\u0633 \u06f3:\u06f1\u06f6 \u0631\u0627 \u062d\u0641\u0638 \u06a9\u0646\u06cc\u062f. \u062f\u0627\u0646\u0633\u062a\u0646 \u06a9\u0644\u0627\u0645 \u062e\u062f\u0627 \u0686\u06af\u0648\u0646\u0647 \u0628\u0647 \u0645\u0627 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u062f\u0631 \u0645\u0627\u0631\u0627\u062a\u0646 \u0627\u06cc\u0645\u0627\u0646 \u0628\u062f\u0648\u06cc\u0645\u061f","francais_content":"O\u00f9 cours-tu?\n2 Timoth\u00e9e 2:22-26\nPasteur Chris Sicks\n15 Mars 2026\n\nLors du Marathon de Portland (Oregon) en 2019, certains des meilleurs coureurs ont en r\u00e9alit\u00e9 perdu la course.\nNon pas parce qu\u2019ils \u00e9taient lents, mais parce qu\u2019ils ont pris la mauvaise direction.\nIl y avait un virage sur le parcours qui n\u2019\u00e9tait pas clairement indiqu\u00e9.\nAinsi, une vingtaine des coureurs les plus rapides ont parcouru plus d\u2019un mile dans la mauvaise direction!\nCette erreur a ajout\u00e9 de pr\u00e9cieuses minutes \u00e0 une course pour laquelle ils s\u2019\u00e9taient pr\u00e9par\u00e9s pendant des mois.\nCes hommes et ces femmes couraient avec acharnement, et ils couraient vite.\nMais ils ont perdu la course, car ils \u00e9taient sur la mauvaise voie.\nCe soir, nous poursuivons une s\u00e9rie de sermons sur le livre de la deuxi\u00e8me \u00e9p\u00eetre \u00e0 Timoth\u00e9e.\nL\u2019ap\u00f4tre Paul \u00e9crit \u00e0 Timoth\u00e9e, un jeune pasteur de l\u2019\u00c9glise chr\u00e9tienne d\u2019\u00c9ph\u00e8se.\nPaul donne \u00e0 Timoth\u00e9e, et \u00e0 nous aujourd\u2019hui, des conseils sur la mani\u00e8re de rester sur le droit chemin.\n2 Timoth\u00e9e 2:22-26\n22 \u00ab Fuis les passions de la jeunesse, et recherche la justice, la foi, la charit\u00e9, la paix, avec ceux qui invoquent le Seigneur d'un coeur pur.\n23 Repousse les discussions folles et inutiles, sachant qu'elles font na\u00eetre des querelles.\n24 Or, il ne faut pas qu'un serviteur du Seigneur ait des querelles; il doit, au contraire, avoir de la condescendance pour tous, \u00eatre propre \u00e0 enseigner, dou\u00e9 de patience;\n25 il doit redresser avec douceur les adversaires, \ndans l'esp\u00e9rance que Dieu leur donnera la repentance pour arriver \u00e0 la connaissance de la v\u00e9rit\u00e9,\n26 et que, revenus \u00e0 leur bon sens, ils se d\u00e9gageront des pi\u00e8ges du diable, qui s'est empar\u00e9 d'eux pour les soumettre \u00e0 sa volont\u00e9.\n\nEnsemble, nous lisons \u00c9sa\u00efe 40:8:\n\u00ab L\u2019herbe se dess\u00e8che, la fleur se fane, mais la parole de notre Dieu subsiste \u00e9ternellement. \u00bb\n\nLe verset 22 dit:\n22 \u00ab Fuis les passions de la jeunesse, et recherche la justice, la foi, la charit\u00e9, la paix, avec ceux qui invoquent le Seigneur d'un coeur pur. \u00bb\n\nCe verset r\u00e9sume en r\u00e9alit\u00e9 le sermon d\u2019aujourd\u2019hui.\nOn le voit souvent dans la Parole de Dieu.\nParfois, la premi\u00e8re phrase d\u2019un psaume ou d\u2019un paragraphe est un r\u00e9sum\u00e9.\nLes mots qui suivent constituent une explication du psaume entier, du paragraphe ou du chapitre.\nUn homme ou une femme chr\u00e9tien(ne) m\u00fbr(e) est quelqu\u2019un qui se d\u00e9tourne des choses qui nous tentaient quand nous \u00e9tions plus jeunes.\nAu lieu des \u00ab passions de la jeunesse \u00bb, une personne mature apprend \u00e0 rechercher les valeurs de Dieu, notamment la justice, la foi, l\u2019amour et la paix.\nLorsque Paul \u00e9tait jeune, il s\u2019appelait Saul.\nSaul \u00e9tait plein d\u2019orgueil et de confiance en lui, utilisant son pouvoir pour pers\u00e9cuter les chr\u00e9tiens et les mettre en prison.\nSaul voulait \u00eatre populaire et r\u00e9ussir, et \u00e9tait pr\u00eat \u00e0 blesser les autres par orgueil.\nMais la deuxi\u00e8me lettre \u00e0 Timoth\u00e9e a \u00e9t\u00e9 \u00e9crite par Paul, un croyant m\u00fbr.\nIl comprend les d\u00e9g\u00e2ts que ses passions de jeunesse ont caus\u00e9s et il met Timothy en garde \u00e0 ce sujet.\nAu moment o\u00f9 Paul \u00e9crit cette lettre, Timoth\u00e9e a probablement une quarantaine d\u2019ann\u00e9es.\nMais il n\u2019est pas n\u00e9cessaire d\u2019\u00eatre jeune pour se lancer dans des \u00ab passions de jeunesse \u00bb.\nJ\u2019ai 57 ans, mais j\u2019apprends encore \u00e0 fuir constamment les passions de ma jeunesse.\nJ\u2019ai un ami de la fac qui a le m\u00eame \u00e2ge que moi.\nMais il vit toujours comme il y a 35 ans.\nSa vie est domin\u00e9e par les passions de jeunesse de nos ann\u00e9es universitaires.\nVoici quelques passions de jeunesse que beaucoup d\u2019entre nous connaissent:\n\n*   Le plaisir: Le p\u00e9ch\u00e9 sexuel est un exemple courant de p\u00e9ch\u00e9 de plaisir, mais ce n\u2019est pas le seul.\nParmi les autres plaisirs coupables, on peut citer l\u2019alcool, la nourriture et de nombreux types de divertissements.\nCes objets ne sont pas mauvais s\u2019ils sont utilis\u00e9s correctement.\nLe sexe, par exemple, est un beau cadeau dans le contexte du mariage chr\u00e9tien.\nMais lorsque nous utilisons quelque chose de mani\u00e8re inappropri\u00e9e, nous lui donnons du pouvoir sur nos vies.\nLorsque nous utilisons un don de Dieu pour combler le vide de notre c\u0153ur, ce don devient un faux dieu, une idole.\n\n*   Le pouvoir: Quand on est jeune, on se sent parfois impuissant, faible ou inad\u00e9quat.\nJ\u2019ai eu du mal \u00e0 g\u00e9rer ces sentiments durant mon adolescence.\nCertaines personnes recherchent le pouvoir pour masquer leur sentiment de faiblesse.\nIls pensent qu\u2019adopter une attitude forte les aidera \u00e0 se sentir en s\u00e9curit\u00e9.\nSaviez-vous qu\u2019un tyran n\u2019est pas aussi dur qu\u2019il en a l\u2019air?\nUn tyran est g\u00e9n\u00e9ralement quelqu\u2019un qui se sent impuissant face \u00e0 un probl\u00e8me dans sa vie, et qui, par cons\u00e9quent, blesse les autres pour se sentir puissant.\n\n*   La popularit\u00e9: voil\u00e0 une autre forte tentation dans ma vie.\nJe me demande souvent si les gens m\u2019aiment bien.\nJe me soucie trop de l\u2019opinion des autres.\nEt toi?\nVous arrive-t-il de modifier votre comportement ou votre apparence pour plaire aux autres?\nPensez-vous que vous devez agir ou para\u00eetre d\u2019une certaine mani\u00e8re pour \u00e9viter le rejet?\n\n*   Les possessions: L\u2019amour de l\u2019argent et des biens mat\u00e9riels est un probl\u00e8me pour la plupart d\u2019entre nous.\nNous voulons la s\u00e9curit\u00e9 et le confort que procure la possession de plus de biens.\nCela r\u00e9v\u00e8le un manque de foi.\nDieu veut que nous comprenions qu\u2019il est notre refuge et notre forteresse, qu\u2019il est notre pourvoyeur.\nLes biens mat\u00e9riels promettent le bonheur, mais ils ne peuvent jamais tenir leurs promesses.\nParce que nos c\u0153urs en voudront toujours plus.\n\n*   L\u2019orgueil: c\u2019est v\u00e9ritablement le p\u00e9ch\u00e9 qui se cache derri\u00e8re tous les autres p\u00e9ch\u00e9s.\nL\u2019orgueil est la conviction que je m\u00e9rite r\u00e9ellement les possessions, le pouvoir, le plaisir et la popularit\u00e9.\nPourquoi? Parce que je suis sp\u00e9cial.\nL\u2019orgueil nous murmure des mensonges, en disant:\n\u00ab C\u2019est bon, tu peux le faire\u2026 Tu le m\u00e9rites. \u00bb\nLes annonceurs nous disent la m\u00eame chose.\n\u00ab Tu le m\u00e9rites\u2026 Vas-y, ach\u00e8te-le. \u00bb\nPeut-\u00eatre en acheter d\u2019autres, ce n\u2019est pas grave.\nC\u2019est pourquoi on voit autant de publicit\u00e9s de ce genre, parce que notre fiert\u00e9 a envie de croire \u00e0 ces choses.\n\nPuis-je vous poser une question, mes amis?\nLaquelle de ces cinq choses vous semble famili\u00e8re?\nRecherchez-vous la fiert\u00e9, les possessions, le pouvoir, le plaisir ou la popularit\u00e9?\nOu peut-\u00eatre est-ce autre chose qui vous \u00e9loigne de Dieu?\nO\u00f9 est ton c\u0153ur aujourd\u2019hui, et o\u00f9 vas-tu?\nTe souviens-tu de ce que Dieu a demand\u00e9 \u00e0 Adam dans le jardin, apr\u00e8s qu\u2019il eut mang\u00e9 le fruit?\nAdam et \u00c8ve se cachaient, et Dieu leur dit: \u00ab O\u00f9 es-tu, Adam ? \u00bb\nAujourd\u2019hui, Dieu demande la m\u00eame chose \u00e0 tous les habitants de la terre.\nO\u00f9 es-tu?\nIl ne vous demande pas o\u00f9 vous vous trouvez physiquement.\nIl demande: \u00ab O\u00f9 est ton c\u0153ur ? \u00bb\nCar notre c\u0153ur est comme une boussole qui nous guide sur le chemin qui nous est le plus pr\u00e9cieux.\nOn se perd sans m\u00eame s\u2019en rendre compte, car le p\u00e9ch\u00e9 est sournois.\nNous avons besoin de l\u2019aide de Dieu pour voir ce qui se passe en nous.\nLisons ensemble le Psaume 139:23\u201324, comme une pri\u00e8re:\nTOUS: 23 \u00ab Sonde-moi, \u00f4 Dieu, et connais mon coeur!\u00bb \n\u00c9prouve-moi, et connais mes pens\u00e9es! \n24 Regarde si je suis sur une mauvaise voie, \nEt conduis-moi sur la voie de l'\u00e9ternit\u00e9!\n\nSans l\u2019aide de Dieu, nous ne marcherons pas \u00ab sur le chemin de l\u2019\u00e9ternit\u00e9 \u00bb.\nNous courrons dans la mauvaise direction, poursuivant des choses qui nous \u00e9loignent du c\u0153ur de Dieu.\nMais Dieu est si bon qu\u2019il ne reste pas les bras crois\u00e9s \u00e0 nous regarder nous \u00e9garer et nous perdre.\nAu contraire, il part \u00e0 la recherche de ses brebis perdues.\nIl vient \u00e0 nous et nous offre une voie d\u2019\u00e9vasion et de sauvetage.\nRelisez 2 Timoth\u00e9e 2:25b-26:\n25b \u00ab dans l'esp\u00e9rance que Dieu leur donnera la repentance pour arriver \u00e0 la connaissance de la v\u00e9rit\u00e9,\n26 et que, revenus \u00e0 leur bon sens, ils se d\u00e9gageront des pi\u00e8ges du diable, qui s'est empar\u00e9 d'eux pour les soumettre \u00e0 sa volont\u00e9.\n\nSaviez-vous qu\u2019il est possible de se sentir totalement libre, m\u00eame lorsqu\u2019on est prisonnier du p\u00e9ch\u00e9 et du diable?\nLe p\u00e9ch\u00e9 donne l\u2019impression d\u2019\u00eatre une libert\u00e9, mais c\u2019est tout le contraire.\nVoici \u00e0 quoi ressemble un pi\u00e8ge.\nC\u2019est un pi\u00e8ge qui capture un animal qui courait librement sur un chemin et qui s\u2019est soudainement retrouv\u00e9 en danger.\nSatan s\u00e8me des mensonges comme des panneaux sur le parcours d\u2019un marathon, pour nous tromper et nous pi\u00e9ger.\nSatan veut que nous courions apr\u00e8s le plaisir, le pouvoir, la popularit\u00e9, les possessions et l\u2019orgueil.\nCes idoles nous promettent la libert\u00e9, et la libert\u00e9 est ce que nous d\u00e9sirons ardemment.\nMalheureusement, nous pensons que de telles choses peuvent nous aider \u00e0 nous sentir satisfaits, en s\u00e9curit\u00e9 et heureux.\nMais ces idoles sont des pi\u00e8ges qui nous \u00e9loignent de Dieu et du chemin de la vraie vie.\nSatan veut nous cacher le chemin de la vie, en disant:\n\u00ab Suivez ce chemin vers la victoire et le bonheur! \u00bb\nOui, c\u2019est par l\u00e0! Suivez-moi !\n\nAlors, comment un animal peut-il \u00e9chapper \u00e0 un pi\u00e8ge comme celui-ci?\nEst-ce quelque chose qu\u2019il peut faire seul?\nNon, le lapin est sans d\u00e9fense.\nIl a besoin de quelqu\u2019un de plus intelligent et de plus fort pour venir le sortir de ce pi\u00e8ge.\nNous avons aussi besoin de quelqu\u2019un de plus intelligent et de plus fort pour nous sauver.\nVoil\u00e0 le point le plus important que je veux que vous reteniez \u00e0 propos de ce verset.\nNous avons besoin d\u2019un Sauveur car nous ne pouvons pas nous sauver nous-m\u00eames ni m\u00eame nous tourner vers Dieu.\nUn c\u0153ur spirituellement mort ne peut choisir la vie.\nVoyez ce que dit le verset 25:\n\u00ab Dieu leur accordera peut-\u00eatre le repentance. \u00bb\n\nUne subvention est un cadeau gratuit.\nIl y a 30 ans, Dieu m\u2019a fait le don du repentir.\nPendant dix ans, j\u2019ai affirm\u00e9 qu\u2019il n\u2019y avait pas de Dieu dans l\u2019univers.\nMais comme Dieu est bon, il m\u2019a montr\u00e9 que la bi\u00e8re, les femmes et le succ\u00e8s terrestre ne pourraient jamais satisfaire les d\u00e9sirs de mon c\u0153ur.\nC\u2019est ce que signifie \u00ab revenir \u00e0 la raison \u00bb au verset 26.\nLorsque votre sens de l\u2019orientation est perturb\u00e9, vous courez dans la mauvaise direction.\nLa premi\u00e8re \u00e9tape pour retrouver son chemin est de reconna\u00eetre qu\u2019on est perdu.\nDan McDowell \u00e9tait l\u2019un des coureurs disparus lors de ce marathon de Portland.\nIl a d\u00e9clar\u00e9: \u00ab J\u2019ai tourn\u00e9 au coin de la rue et j\u2019ai vu 10 personnes qui restaient immobiles\u2026\nIls se regardaient en pensant: \u00ab Euh, \u00e7a ne me semble pas normal. \u00bb\n\nUn autre coureur, Zach Custer, a d\u00e9clar\u00e9 \u00eatre entr\u00e9 dans un tunnel o\u00f9 les voitures le d\u00e9passaient \u00e0 88 km\/h.\nC\u2019est alors qu\u2019il s\u2019est rendu compte qu\u2019il s\u2019\u00e9tait \u00e9gar\u00e9.\nAvant que Dieu ne me ram\u00e8ne \u00e0 la raison, je pensais avoir la \u00ab connaissance de la v\u00e9rit\u00e9 \u00bb.\nMon orgueil me disait que j\u2019\u00e9tais sur la bonne voie et que je n\u2019avais besoin d\u2019aucun Dieu pour me guider, car j\u2019\u00e9tais si intelligent.\nIroniquement, j\u2019\u00e9tais trop stupide pour voir la tromperie de Satan.\nJe suis tomb\u00e9e dans son pi\u00e8ge de mensonges.\nJ\u2019ai cru \u00e0 la promesse du diable selon laquelle je trouverais le bonheur en fuyant Dieu.\nMais ensuite, Dieu m\u2019a fait le don du repentir.\nLe mot grec utilis\u00e9 ici pour d\u00e9signer le repentir est metanoia.\nCela signifie \u00ab un changement d\u2019avis, un changement de vie et un changement d\u2019objectif \u00bb.\nJ\u00e9sus m\u2019a donn\u00e9 un c\u0153ur nouveau afin que je puisse \u00ab invoquer le Seigneur d\u2019un c\u0153ur pur \u00bb, comme le dit le verset 22.\nUn c\u0153ur pur est un c\u0153ur honn\u00eate.\nUn c\u0153ur qui implore Dieu: \u00ab Je regrette mon p\u00e9ch\u00e9, pardonne-moi. \u00bb\nAide-moi \u00e0 courir vers toi, et non \u00e0 m\u2019\u00e9loigner de toi.\nDans Romains 10:9-11, Paul explique tr\u00e8s clairement comment se tourner vers Dieu et \u00eatre sauv\u00e9.\n9 Si tu confesses de ta bouche le Seigneur J\u00e9sus, et si tu crois dans ton coeur que Dieu l'a ressuscit\u00e9 des morts, tu seras sauv\u00e9.\n10 Car c'est en croyant du coeur qu'on parvient \u00e0 la justice, et c'est en confessant de la bouche qu'on parvient au salut, selon ce que dit l'\u00c9criture:\n11 Quiconque croit en lui ne sera point confus. \u00bb\n\nAs-tu profess\u00e9 ta foi de ta bouche, afin d\u2019\u00eatre sauv\u00e9?\nSi vous ne l\u2019avez pas encore fait, ne pensez-vous pas qu\u2019aujourd\u2019hui serait le jour id\u00e9al pour le faire?\nLe Saint-Esprit est parmi nous, et peut-\u00eatre murmure-t-il \u00e0 votre c\u0153ur:\n\u00ab D\u00e9tourne-toi du chemin du p\u00e9ch\u00e9 et de la mort!\u00bb\nChoisissez une vie nouvelle et une nouvelle direction en d\u00e9clarant: \u00ab J\u00e9sus est Seigneur ! \u00bb\n\nPaul avait d\u00e9j\u00e0 \u00e9crit une fois \u00e0 propos de cette nouvelle orientation.\nC\u2019\u00e9tait dans une lettre adress\u00e9e \u00e0 cette m\u00eame \u00c9glise d\u2019\u00c9ph\u00e8se, o\u00f9 Timoth\u00e9e exerce maintenant la fonction de pasteur.\n\u00c9coutez ce que Paul a \u00e9crit aux croyants chr\u00e9tiens dans \u00c9ph\u00e9siens 2:1-5, \u00e0 propos de ce que Dieu a fait pour leur donner une vie nouvelle et une nouvelle direction:\n1 \u00ab Vous \u00e9tiez morts par vos offenses et par vos p\u00e9ch\u00e9s,\n2 dans lesquels vous marchiez autrefois, selon le train de ce monde, selon le prince de la puissance de l'air, de l'esprit qui agit maintenant dans les fils de la r\u00e9bellion.\n3 Nous tous aussi, nous \u00e9tions de leur nombre, et nous vivions autrefois selon les convoitises de notre chair, accomplissant les volont\u00e9s de la chair et de nos pens\u00e9es, et nous \u00e9tions par nature des enfants de col\u00e8re, comme les autres...\n4 Mais Dieu, qui est riche en mis\u00e9ricorde, \u00e0 cause du grand amour dont il nous a aim\u00e9s,\n5 nous qui \u00e9tions morts par nos offenses, nous a rendus \u00e0 la vie avec Christ (c'est par gr\u00e2ce que vous \u00eates sauv\u00e9s) !\n\n\u00ab Mais Dieu \u00bb sont deux des plus beaux mots jamais prononc\u00e9s.\nPaul rappelle aux croyants d\u2019\u00c9ph\u00e8se qu\u2019ils \u00e9taient autrefois pris au pi\u00e8ge et impuissants comme ce lapin pris au collet.\nMais Dieu est intervenu pour les sauver par la gr\u00e2ce seule, par la foi seule, en Christ seul.\nN\u2019importe qui peut \u00eatre sauv\u00e9, s\u2019il croit que le sacrifice du Christ sur la croix \u00e9tait pour lui, pour le laver du p\u00e9ch\u00e9 et de la honte.\nLorsque vous croyez cela, vous recevez une vie nouvelle et J\u00e9sus vous engage sur un nouveau chemin.\nQuelques versets plus loin, dans \u00c9ph\u00e9siens 2:8, Paul parle de cette nouvelle direction.\nLisez ceci ensemble:\nTOUS: 10 \u00ab Car nous sommes son ouvrage, ayant \u00e9t\u00e9 cr\u00e9\u00e9s en J\u00e9sus Christ pour de bonnes oeuvres, que Dieu a pr\u00e9par\u00e9es d'avance, afin que nous les pratiquions. \u00bb\n\nPour conclure ce message, voyons ce que signifie vivre en faisant le bien.\nN\u2019oubliez pas que Paul \u00e9crit \u00e0 Timoth\u00e9e pour lui donner des conseils sur les personnes \u00e0 choisir et \u00e0 former comme enseignants bibliques.\nEt notre mission, en tant que croyants, est de partager la Bonne Nouvelle de l\u2019\u00c9vangile avec les gens, proches ou lointains.\nMais pour le faire fid\u00e8lement, nous devons avoir le caract\u00e8re que Paul d\u00e9crit dans ces versets.\nNous ne pouvons changer le c\u0153ur de personne.\nMais nous pouvons leur dire la v\u00e9rit\u00e9 avec douceur, gentillesse et patience.\nEt nous pouvons avoir confiance que Dieu accordera le repentir \u00e0 ses enfants \u00e9lus au moment opportun.\nDans les versets 24 et 25 du passage d\u2019aujourd\u2019hui, je vois cinq qualit\u00e9s que Dieu veut d\u00e9velopper chez ses serviteurs:\n\nQualit\u00e9 1: Non querelleur.\nCertaines personnes aiment argumenter.\nIl n\u2019y a rien de mal \u00e0 un d\u00e9bat sain.\nMais comment savoir si l\u2019on se comporte de mani\u00e8re p\u00e9cheresse et \u00ab querelleuse \u00bb?\nVous pouvez peut-\u00eatre vous poser cette question:\n\u00ab Quand je me dispute avec quelqu\u2019un, est-ce que je me soucie plus de cette personne ou de gagner la dispute? \u00bb\nEst-ce mon orgueil qui me pousse \u00e0 me concentrer sur le fait d\u2019avoir raison, au lieu d\u2019\u00eatre gentil?\n\nQualit\u00e9 2: Gentil envers tout le monde.\nLe serviteur du Seigneur doit \u00eatre bienveillant envers tous.\nM\u00eame aux personnes qui vous ha\u00efssent et veulent vous faire du mal.\nC\u2019est difficile, je sais.\nNous pensons que le meilleur moyen de se prot\u00e9ger des autres est d\u2019\u00eatre fort, d\u2019utiliser la force.\nMais regardez ce que Paul nous rappelle dans Romains 2:4:\n\u00ab La bont\u00e9 de Dieu a pour but de vous amener \u00e0 la repentance. \u00bb\nAvec quelle bont\u00e9 J\u00e9sus a-t-il \u00e9t\u00e9 envers vous, lorsque vous \u00e9tiez dans le p\u00e9ch\u00e9 et que vous fuyiez loin de lui?\nSa bont\u00e9 vous a conduits \u00e0 vous repentir.\nVous avez maintenant l\u2019occasion d\u2019imiter le Christ et d\u2019\u00eatre bienveillant envers tous.\n\nQualit\u00e9 3: Endurer patiemment le mal.\nLorsque nous partageons la v\u00e9rit\u00e9 de l\u2019\u00c9vangile, nous rencontrons l\u2019opposition de personnes qui n\u2019aiment pas ce que nous disons.\nVous souvenez-vous de la r\u00e9action de Stephen face \u00e0 ceux qui l\u2019ont tu\u00e9?\nActes 7:59-60 dit:\n59 Et ils lapidaient \u00c9tienne, qui priait et disait: Seigneur J\u00e9sus, re\u00e7ois mon esprit!\n60 Puis, s'\u00e9tant mis \u00e0 genoux, il s'\u00e9cria d'une voix forte: Seigneur, ne leur impute pas ce p\u00e9ch\u00e9! Et, apr\u00e8s ces paroles, il s'endormit. \n\nSeul Dieu peut nous aider \u00e0 endurer patiemment le mal comme l\u2019a fait \u00c9tienne.\nMais il nous aidera, lorsque nous l\u2019invoquerons dans les moments difficiles.\nIl nous aidera \u00e0 lui faire confiance, sachant que nos \u00e2mes sont en s\u00e9curit\u00e9 entre ses mains, quoi qu\u2019il arrive \u00e0 nos corps.\n\nQualit\u00e9 4: Corriger avec douceur.\nCorriger les gens est difficile.\nMais si mon fils fait quelque chose de mal, je le lui dis parce que je l\u2019aime.\nVoici la question importante \u00e0 se poser lorsqu\u2019on doit corriger quelqu\u2019un:\n\u00ab Mon enfant, mon ami ou mon conjoint ressent-il mon amour? \u00bb\nOu bien ne ressentent-ils que ma col\u00e8re?\n\nLorsque nous corrigeons avec col\u00e8re ou frustration, nous agissons comme si Dieu ne pouvait pas changer l\u2019autre personne.\nNous pensons pouvoir les contraindre \u00e0 changer, ou crier plus fort jusqu\u2019\u00e0 ce qu\u2019ils prennent le bon chemin.\nMais un enseignant qui sait que Dieu d\u00e9tient le v\u00e9ritable pouvoir sera doux, patient et bienveillant.\n\nQualit\u00e9 5: Capable d\u2019enseigner.\nComprenez-vous suffisamment la Parole de Dieu pour l\u2019expliquer aux autres?\nM\u00e9morisez-vous des passages des \u00c9critures afin de les avoir sous la main pour vous guider dans la vie et pour les partager avec les autres?\nNous allons commencer quelque chose de nouveau ce mois-ci.\nNous allons vous demander de m\u00e9moriser un verset biblique d\u2019ici la fin du mois de mars.\nEt si vous parvenez \u00e0 la r\u00e9citer \u00e0 l\u2019un de nos dirigeants, dans n\u2019importe quelle langue, vous recevrez un autocollant.\nVous pouvez le coller sur votre bouteille d\u2019eau ou votre cahier.\nPartout o\u00f9 vous le verrez et continuerez \u00e0 le pratiquer toute l\u2019ann\u00e9e.\nLisons ensemble le verset du mois de mars, 2 Timoth\u00e9e 3:16.\nTOUS: \u00ab Toute \u00c9criture est inspir\u00e9e de Dieu, et utile pour enseigner, pour convaincre, pour corriger, pour instruire dans la justice,\u00bb\n\nNous avons tous besoin d\u2019aide pour continuer \u00e0 avancer dans la bonne direction.\nNous avons besoin de la Parole de Dieu pour nous enseigner, nous corriger et nous former \u00e0 marcher dans la justice.\nEt nous avons besoin du Saint-Esprit pour nous aider \u00e0 comprendre et \u00e0 appliquer la Parole, alors tournons maintenant nos c\u0153urs vers le ciel dans la pri\u00e8re.\nJ\u00e9sus, nous ne pouvons parler au P\u00e8re que parce que tu as construit un pont entre la terre et le ciel.\nVous avez d\u00e9truit les pi\u00e8ges du diable et ouvert nos yeux \u00e0 la v\u00e9rit\u00e9.\nP\u00e8re, merci de nous avoir donn\u00e9 le don du repentir, afin que nous puissions \u00eatre honn\u00eates avec nous-m\u00eames et avec toi au sujet de notre p\u00e9ch\u00e9.\nEt merci, Esprit Saint, de nous donner la foi pour nous tourner vers J\u00e9sus pour notre salut.\nOuvrons nos esprits et nos c\u0153urs pour comprendre et appliquer la Parole \u00e0 nos vies.\nAidez-nous \u00e0 courir avec ardeur la course qui nous est propos\u00e9e, en invitant les autres \u00e0 se joindre \u00e0 nous sur le chemin de la pl\u00e9nitude, de l\u2019espoir et du ciel, amen.\n\nQuestions pour la m\u00e9ditation et la discussion\n1.  Lisez 2 Timoth\u00e9e 2:22 et Psaume 119:35-37.\na) Vers laquelle des \u00ab passions de jeunesse \u00bb (plaisir, pouvoir, popularit\u00e9, possessions, orgueil) votre c\u0153ur se tourne-t-il naturellement lorsque vous \u00eates stress\u00e9 ou que vous recherchez du r\u00e9confort?\n\n2.  Lisez \u00c9ph\u00e9siens 2:1-5 et \u00c9z\u00e9chiel 36:26.\na) Que faut-il pour passer de l\u2019\u00e9tat \u00ab mort \u00bb \u00e0 l\u2019\u00e9tat \u00ab vivant \u00bb?\nb) Le fait de croire que le repentir est un don de la gr\u00e2ce vous aide-t-il \u00e0 \u00eatre plus honn\u00eate avec Dieu au sujet de votre p\u00e9ch\u00e9?\n\n3.  Lisez 2 Timoth\u00e9e 2:23-25a et Colossiens 3:12-14.\na) Quelles sont les qualit\u00e9s du \u00ab serviteur du Seigneur \u00bb lorsqu\u2019il d\u00e9bat ou corrige les autres?\nb) Parce que J\u00e9sus nous a aim\u00e9s avec une grande patience et une grande douceur, qui dans votre vie aimerez-vous avec cette m\u00eame gr\u00e2ce, m\u00eame s\u2019ils ne sont pas d\u2019accord avec vous ou ne vous aiment pas?\n\n4.  Lisez Romains 10:9-11 et H\u00e9breux 12:1-2.\na) Comment le fait de fixer nos yeux sur J\u00e9sus nous aide-t-il \u00e0 nous d\u00e9tourner du p\u00e9ch\u00e9 et \u00e0 nous engager dans une nouvelle direction?\nb) N\u2019oubliez pas de m\u00e9moriser 2 Timoth\u00e9e 3:16. Comment la connaissance de la Parole de Dieu nous aide-t-elle \u00e0 courir le marathon de la foi?","hindi_content":"\u0906\u092a \u0915\u0939\u093e\u0901 \u092d\u093e\u0917 \u0930\u0939\u0947 \u0939\u0948\u0902?\n2 \u0924\u093f\u092e\u094b\u0925\u0940 2:22-26\n\u092a\u093e\u0938\u094d\u091f\u0930 \u0915\u094d\u0930\u093f\u0938 \u0938\u093f\u0915\u094d\u0938\n15 \u092e\u093e\u0930\u094d\u091a, 2026\n\n2019 \u092e\u0947\u0902 \u092a\u094b\u0930\u094d\u091f\u0932\u0948\u0902\u0921, \u0913\u0930\u0947\u0917\u0928 \u092e\u0947\u0902 \u0906\u092f\u094b\u091c\u093f\u0924 \u092e\u0948\u0930\u093e\u0925\u0928 \u092e\u0947\u0902, \u0915\u0941\u091b \u092c\u0947\u0939\u0924\u0930\u0940\u0928 \u0927\u093e\u0935\u0915 \u0935\u093e\u0938\u094d\u0924\u0935 \u092e\u0947\u0902 \u0926\u094c\u0921\u093c \u0939\u093e\u0930 \u0917\u090f\u0964\n\u0907\u0938\u0932\u093f\u090f \u0928\u0939\u0940\u0902 \u0915\u093f \u0935\u0947 \u0927\u0940\u092e\u0947 \u0925\u0947, \u092c\u0932\u094d\u0915\u093f \u0907\u0938\u0932\u093f\u090f \u0915\u093f \u0935\u0947 \u0917\u0932\u0924 \u0930\u093e\u0938\u094d\u0924\u0947 \u092a\u0930 \u091a\u0932\u0947 \u0917\u090f \u0925\u0947\u0964\n\u0915\u094b\u0930\u094d\u0938 \u092a\u0930 \u090f\u0915 \u092e\u094b\u0921\u093c \u0910\u0938\u093e \u0925\u093e \u091c\u093f\u0938\u0947 \u0938\u094d\u092a\u0937\u094d\u091f \u0930\u0942\u092a \u0938\u0947 \u091a\u093f\u0939\u094d\u0928\u093f\u0924 \u0928\u0939\u0940\u0902 \u0915\u093f\u092f\u093e \u0917\u092f\u093e \u0925\u093e\u0964\n\u0924\u094b \u0932\u0917\u092d\u0917 20 \u0938\u092c\u0938\u0947 \u0924\u0947\u091c \u0927\u093e\u0935\u0915 \u0917\u0932\u0924 \u0926\u093f\u0936\u093e \u092e\u0947\u0902 \u090f\u0915 \u092e\u0940\u0932 \u0938\u0947 \u0905\u0927\u093f\u0915 \u0926\u094c\u0921\u093c \u0917\u090f!\n\u0907\u0938 \u0917\u0932\u0924\u0940 \u0915\u0940 \u0935\u091c\u0939 \u0938\u0947 \u0909\u0938 \u0926\u094c\u0921\u093c \u092e\u0947\u0902 \u0915\u0941\u091b \u0915\u0940\u092e\u0924\u0940 \u092e\u093f\u0928\u091f \u092c\u0930\u094d\u092c\u093e\u0926 \u0939\u094b \u0917\u090f, \u091c\u093f\u0938\u0915\u0940 \u0924\u0948\u092f\u093e\u0930\u0940 \u092e\u0947\u0902 \u0909\u0928\u094d\u0939\u094b\u0902\u0928\u0947 \u092e\u0939\u0940\u0928\u094b\u0902 \u092c\u093f\u0924\u093e\u090f \u0925\u0947\u0964\n\u0935\u0947 \u092a\u0941\u0930\u0941\u0937 \u0914\u0930 \u092e\u0939\u093f\u0932\u093e\u090f\u0902 \u092a\u0942\u0930\u0940 \u0924\u093e\u0915\u0924 \u0938\u0947 \u0914\u0930 \u092c\u0939\u0941\u0924 \u0924\u0947\u091c\u0940 \u0938\u0947 \u0926\u094c\u0921\u093c\u0947\u0964\n\u0932\u0947\u0915\u093f\u0928 \u0935\u0947 \u0926\u094c\u0921\u093c \u0939\u093e\u0930 \u0917\u090f, \u0915\u094d\u092f\u094b\u0902\u0915\u093f \u0935\u0947 \u0917\u0932\u0924 \u0930\u093e\u0938\u094d\u0924\u0947 \u092a\u0930 \u0925\u0947\u0964\n\u0906\u091c \u0930\u093e\u0924 \u0939\u092e 2 \u0924\u093f\u092e\u094b\u0925\u0940 \u0915\u0940 \u092a\u0941\u0938\u094d\u0924\u0915 \u092e\u0947\u0902 \u0909\u092a\u0926\u0947\u0936\u094b\u0902 \u0915\u0940 \u0936\u094d\u0930\u0943\u0902\u0916\u0932\u093e \u091c\u093e\u0930\u0940 \u0930\u0916 \u0930\u0939\u0947 \u0939\u0948\u0902\u0964\n\u092a\u094d\u0930\u0947\u0930\u093f\u0924 \u092a\u094c\u0932\u0941\u0938, \u0907\u092b\u093f\u0938\u0941\u0938 \u092e\u0947\u0902 \u0938\u094d\u0925\u093f\u0924 \u0908\u0938\u093e\u0908 \u091a\u0930\u094d\u091a \u0915\u0947 \u092f\u0941\u0935\u093e \u092a\u093e\u0926\u0930\u0940 \u0924\u093f\u092e\u094b\u0925\u0940 \u0915\u094b \u092a\u0924\u094d\u0930 \u0932\u093f\u0916 \u0930\u0939\u0947 \u0939\u0948\u0902\u0964\n\u092a\u094c\u0932\u0941\u0938 \u0906\u091c \u0924\u0940\u092e\u094b\u0925\u0940 \u0914\u0930 \u0939\u092e \u0938\u092d\u0940 \u0915\u094b \u0938\u0939\u0940 \u0930\u093e\u0938\u094d\u0924\u0947 \u092a\u0930 \u092c\u0928\u0947 \u0930\u0939\u0928\u0947 \u0915\u0947 \u092c\u093e\u0930\u0947 \u092e\u0947\u0902 \u0938\u0932\u093e\u0939 \u0926\u0947 \u0930\u0939\u093e \u0939\u0948\u0964\n2 \u0924\u093f\u092e\u094b\u0925\u0940 2:22\u201326\n22 \u201c\u0907\u0938\u0932\u093f\u090f \u091c\u0935\u093e\u0928\u0940 \u0915\u0940 \u0935\u093e\u0938\u0928\u093e\u0913\u0902 \u0938\u0947 \u0926\u0942\u0930 \u0930\u0939\u094b \u0914\u0930 \u0909\u0928 \u0932\u094b\u0917\u094b\u0902 \u0915\u0947 \u0938\u093e\u0925 \u0927\u093e\u0930\u094d\u092e\u093f\u0915\u0924\u093e, \u0935\u093f\u0936\u094d\u0935\u093e\u0938, \u092a\u094d\u0930\u0947\u092e \u0914\u0930 \u0936\u093e\u0902\u0924\u093f \u0915\u093e \u0905\u0928\u0941\u0938\u0930\u0923 \u0915\u0930\u094b \u091c\u094b \u0936\u0941\u0926\u094d\u0927 \u0939\u0943\u0926\u092f \u0938\u0947 \u092a\u094d\u0930\u092d\u0941 \u0915\u094b \u092a\u0941\u0915\u093e\u0930\u0924\u0947 \u0939\u0948\u0902\u0964\n23 \u092e\u0942\u0930\u094d\u0916\u0924\u093e\u092a\u0942\u0930\u094d\u0923 \u0914\u0930 \u0905\u091c\u094d\u091e\u093e\u0928\u0924\u093e\u092a\u0942\u0930\u094d\u0923 \u0935\u093f\u0935\u093e\u0926\u094b\u0902 \u0938\u0947 \u0926\u0942\u0930 \u0930\u0939\u094b; \u0924\u0941\u092e \u091c\u093e\u0928\u0924\u0947 \u0939\u094b \u0915\u093f \u0935\u0947 \u091d\u0917\u0921\u093c\u0947 \u092a\u0948\u0926\u093e \u0915\u0930\u0924\u0947 \u0939\u0948\u0902\u0964\n24 \u0914\u0930 \u092a\u094d\u0930\u092d\u0941 \u0915\u0947 \u0938\u0947\u0935\u0915 \u0915\u094b \u091d\u0917\u0921\u093c\u093e\u0932\u0942 \u0928\u0939\u0940\u0902 \u0939\u094b\u0928\u093e \u091a\u093e\u0939\u093f\u090f, \u092c\u0932\u094d\u0915\u093f \u0938\u092c\u0915\u0947 \u092a\u094d\u0930\u0924\u093f \u0926\u092f\u093e\u0932\u0941, \u0938\u093f\u0916\u093e\u0928\u0947 \u092e\u0947\u0902 \u0938\u0915\u094d\u0937\u092e \u0914\u0930 \u092c\u0941\u0930\u093e\u0908 \u0915\u094b \u0927\u0940\u0930\u091c\u092a\u0942\u0930\u094d\u0935\u0915 \u0938\u0939\u0928\u0947 \u0935\u093e\u0932\u093e \u0939\u094b\u0928\u093e \u091a\u093e\u0939\u093f\u090f\u0964\n25. \u0905\u092a\u0928\u0947 \u0935\u093f\u0930\u094b\u0927\u093f\u092f\u094b\u0902 \u0915\u094b \u0935\u093f\u0928\u092e\u094d\u0930\u0924\u093e \u0938\u0947 \u0938\u0941\u0927\u093e\u0930\u0928\u093e\u0964\n\u0936\u093e\u092f\u0926 \u0908\u0936\u094d\u0935\u0930 \u0909\u0928\u094d\u0939\u0947\u0902 \u092a\u0936\u094d\u091a\u093e\u0924\u093e\u092a \u0915\u0930\u0928\u0947 \u0915\u093e \u0905\u0935\u0938\u0930 \u092a\u094d\u0930\u0926\u093e\u0928 \u0915\u0930\u0947 \u091c\u093f\u0938\u0938\u0947 \u0935\u0947 \u0938\u0924\u094d\u092f \u0915\u0947 \u091c\u094d\u091e\u093e\u0928 \u0915\u0940 \u0913\u0930 \u0905\u0917\u094d\u0930\u0938\u0930 \u0939\u094b\u0902\u0964\n26 \u0914\u0930 \u0935\u0947 \u0939\u094b\u0936 \u092e\u0947\u0902 \u0906\u0915\u0930 \u0936\u0948\u0924\u093e\u0928 \u0915\u0947 \u092b\u0902\u0926\u0947 \u0938\u0947 \u092c\u091a \u0928\u093f\u0915\u0932\u0947\u0902\u0917\u0947, \u091c\u092c \u0935\u0939 \u0909\u0928\u094d\u0939\u0947\u0902 \u0905\u092a\u0928\u0940 \u0907\u091a\u094d\u091b\u093e \u092a\u0942\u0930\u0940 \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u092a\u0915\u0921\u093c \u0932\u0947\u0924\u093e \u0939\u0948\u0964\n\n\u0939\u092e \u0938\u092c \u092e\u093f\u0932\u0915\u0930 \u092f\u0936\u093e\u092f\u093e\u0939 40:8 \u092a\u0922\u093c\u0924\u0947 \u0939\u0948\u0902:\n\u0918\u093e\u0938 \u0938\u0942\u0916 \u091c\u093e\u0924\u0940 \u0939\u0948, \u092b\u0942\u0932 \u092e\u0941\u0930\u091d\u093e \u091c\u093e\u0924\u0947 \u0939\u0948\u0902, \u092a\u0930\u0928\u094d\u0924\u0941 \u0939\u092e\u093e\u0930\u0947 \u092a\u0930\u092e\u0947\u0936\u094d\u0935\u0930 \u0915\u093e \u0935\u091a\u0928 \u0938\u0926\u093e \u092c\u0928\u093e \u0930\u0939\u0947\u0917\u093e\u0964\n\n\u0936\u094d\u0932\u094b\u0915 22 \u0915\u0939\u0924\u093e \u0939\u0948:\n22 \u201d\u0907\u0938\u0932\u093f\u090f \u091c\u0935\u093e\u0928\u0940 \u0915\u0940 \u0935\u093e\u0938\u0928\u093e\u0913\u0902 \u0938\u0947 \u0926\u0942\u0930 \u0930\u0939\u094b \u0914\u0930 \u0909\u0928 \u0932\u094b\u0917\u094b\u0902 \u0915\u0947 \u0938\u093e\u0925 \u0927\u093e\u0930\u094d\u092e\u093f\u0915\u0924\u093e, \u0935\u093f\u0936\u094d\u0935\u093e\u0938, \u092a\u094d\u0930\u0947\u092e \u0914\u0930 \u0936\u093e\u0902\u0924\u093f \u0915\u093e \u0905\u0928\u0941\u0938\u0930\u0923 \u0915\u0930\u094b \u091c\u094b \u0936\u0941\u0926\u094d\u0927 \u0939\u0943\u0926\u092f \u0938\u0947 \u092a\u094d\u0930\u092d\u0941 \u0915\u094b \u092a\u0941\u0915\u093e\u0930\u0924\u0947 \u0939\u0948\u0902\u0964\u201d\n\n\u092f\u0939 \u0936\u094d\u0932\u094b\u0915 \u0935\u093e\u0938\u094d\u0924\u0935 \u092e\u0947\u0902 \u0906\u091c \u0915\u0947 \u0909\u092a\u0926\u0947\u0936 \u0915\u093e \u0938\u093e\u0930\u093e\u0902\u0936 \u0939\u0948\u0964\n\u0939\u092e\u0947\u0902 \u092f\u0939 \u092c\u093e\u0924 \u092a\u0930\u092e\u0947\u0936\u094d\u0935\u0930 \u0915\u0947 \u0935\u091a\u0928 \u092e\u0947\u0902 \u0905\u0915\u094d\u0938\u0930 \u0926\u0947\u0916\u0928\u0947 \u0915\u094b \u092e\u093f\u0932\u0924\u0940 \u0939\u0948\u0964\n\u0915\u092d\u0940-\u0915\u092d\u0940 \u0915\u093f\u0938\u0940 \u092d\u091c\u0928 \u092f\u093e \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 \u0915\u093e \u092a\u0939\u0932\u093e \u0915\u0925\u0928 \u0938\u093e\u0930\u093e\u0902\u0936 \u0939\u094b\u0924\u093e \u0939\u0948\u0964\n\u0907\u0938\u0915\u0947 \u092c\u093e\u0926 \u0906\u0928\u0947 \u0935\u093e\u0932\u0947 \u0936\u092c\u094d\u0926 \u092a\u0942\u0930\u0947 \u092d\u091c\u0928 \u092f\u093e \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 \u092f\u093e \u0905\u0927\u094d\u092f\u093e\u092f \u0915\u0940 \u0935\u094d\u092f\u093e\u0916\u094d\u092f\u093e \u0939\u0948\u0902\u0964\n\u090f\u0915 \u092a\u0930\u093f\u092a\u0915\u094d\u0935 \u0908\u0938\u093e\u0908 \u092a\u0941\u0930\u0941\u0937 \u092f\u093e \u092e\u0939\u093f\u0932\u093e \u0935\u0939 \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u0939\u094b\u0924\u093e \u0939\u0948 \u091c\u094b \u0909\u0928 \u091a\u0940\u091c\u094b\u0902 \u0938\u0947 \u0926\u0942\u0930 \u0930\u0939\u0924\u093e \u0939\u0948 \u091c\u094b \u0939\u092e\u0947\u0902 \u092c\u091a\u092a\u0928 \u092e\u0947\u0902 \u0932\u0941\u092d\u093e\u0924\u0940 \u0925\u0940\u0902\u0964\n\u090f\u0915 \u092a\u0930\u093f\u092a\u0915\u094d\u0935 \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u201d\u092f\u0941\u0935\u093e\u0935\u0938\u094d\u0925\u093e \u0915\u0947 \u091c\u0941\u0928\u0942\u0928\u201d \u0915\u0947 \u092c\u091c\u093e\u092f \u0908\u0936\u094d\u0935\u0930 \u0915\u0947 \u092e\u0942\u0932\u094d\u092f\u094b\u0902, \u091c\u0948\u0938\u0947 \u0915\u093f \u0927\u093e\u0930\u094d\u092e\u093f\u0915\u0924\u093e, \u0935\u093f\u0936\u094d\u0935\u093e\u0938, \u092a\u094d\u0930\u0947\u092e \u0914\u0930 \u0936\u093e\u0902\u0924\u093f \u0915\u093e \u0905\u0928\u0941\u0938\u0930\u0923 \u0915\u0930\u0928\u093e \u0938\u0940\u0916 \u0930\u0939\u093e \u0939\u0948\u0964\n\u091c\u092c \u092a\u094c\u0932\u0941\u0938 \u091c\u0935\u093e\u0928 \u0925\u093e, \u0924\u092c \u0909\u0938\u0915\u093e \u0928\u093e\u092e \u0936\u093e\u090a\u0932 \u0930\u0916\u093e \u0917\u092f\u093e \u0925\u093e\u0964\n\u0936\u093e\u090a\u0932 \u0905\u0939\u0902\u0915\u093e\u0930 \u0914\u0930 \u0906\u0924\u094d\u092e\u0935\u093f\u0936\u094d\u0935\u093e\u0938 \u0938\u0947 \u092d\u0930\u093e \u0939\u0941\u0906 \u0925\u093e, \u0914\u0930 \u0909\u0938\u0928\u0947 \u0905\u092a\u0928\u0940 \u0936\u0915\u094d\u0924\u093f \u0915\u093e \u0926\u0941\u0930\u0941\u092a\u092f\u094b\u0917 \u0915\u0930\u0924\u0947 \u0939\u0941\u090f \u0908\u0938\u093e\u0907\u092f\u094b\u0902 \u0915\u094b \u0938\u0924\u093e\u092f\u093e \u0914\u0930 \u0909\u0928\u094d\u0939\u0947\u0902 \u091c\u0947\u0932 \u092e\u0947\u0902 \u0921\u093e\u0932 \u0926\u093f\u092f\u093e\u0964\n\u0936\u093e\u090a\u0932 \u0932\u094b\u0915\u092a\u094d\u0930\u093f\u092f \u0914\u0930 \u0938\u092b\u0932 \u0939\u094b\u0928\u093e \u091a\u093e\u0939\u0924\u093e \u0925\u093e \u0914\u0930 \u0905\u092a\u0928\u0947 \u0905\u0939\u0902\u0915\u093e\u0930 \u0915\u0947 \u0915\u093e\u0930\u0923 \u0926\u0942\u0938\u0930\u094b\u0902 \u0915\u094b \u0928\u0941\u0915\u0938\u093e\u0928 \u092a\u0939\u0941\u0902\u091a\u093e\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u092d\u0940 \u0924\u0948\u092f\u093e\u0930 \u0925\u093e\u0964\n\u0932\u0947\u0915\u093f\u0928 2 \u0924\u0940\u092e\u0941\u0925\u093f\u092f\u0941\u0938 \u0915\u093e \u092a\u0924\u094d\u0930 \u092a\u0930\u093f\u092a\u0915\u094d\u0935 \u0935\u093f\u0936\u094d\u0935\u093e\u0938\u0940 \u092a\u094c\u0932\u0941\u0938 \u0926\u094d\u0935\u093e\u0930\u093e \u0932\u093f\u0916\u093e \u0917\u092f\u093e \u0925\u093e\u0964\n\u0935\u0939 \u0938\u092e\u091d\u0924\u093e \u0939\u0948 \u0915\u093f \u0909\u0938\u0915\u0940 \u091c\u0935\u093e\u0928\u0940 \u0915\u0940 \u092d\u093e\u0935\u0928\u093e\u0913\u0902 \u0928\u0947 \u0915\u093f\u0924\u0928\u093e \u0928\u0941\u0915\u0938\u093e\u0928 \u092a\u0939\u0941\u0902\u091a\u093e\u092f\u093e \u0939\u0948, \u0914\u0930 \u0935\u0939 \u0924\u093f\u092e\u094b\u0925\u0940 \u0915\u094b \u0907\u0938\u0915\u0947 \u092c\u093e\u0930\u0947 \u092e\u0947\u0902 \u091a\u0947\u0924\u093e\u0935\u0928\u0940 \u0926\u0947 \u0930\u0939\u093e \u0939\u0948\u0964\n\u091c\u093f\u0938 \u0938\u092e\u092f \u092a\u094c\u0932\u0941\u0938 \u0928\u0947 \u092f\u0939 \u092a\u0924\u094d\u0930 \u0932\u093f\u0916\u093e, \u0909\u0938 \u0938\u092e\u092f \u0924\u0940\u092e\u094b\u0925\u0940 \u0915\u0940 \u0909\u092e\u094d\u0930 \u0938\u0902\u092d\u0935\u0924\u0903 \u0932\u0917\u092d\u0917 40 \u0935\u0930\u094d\u0937 \u0925\u0940\u0964\n\u0932\u0947\u0915\u093f\u0928 \u201d\u092f\u0941\u0935\u093e \u091c\u094b\u0936\u201d \u0915\u0940 \u0913\u0930 \u0926\u094c\u0921\u093c\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0906\u092a\u0915\u094b \u092f\u0941\u0935\u093e \u0939\u094b\u0928\u0947 \u0915\u0940 \u0906\u0935\u0936\u094d\u092f\u0915\u0924\u093e \u0928\u0939\u0940\u0902 \u0939\u0948\u0964\n\u092e\u0947\u0930\u0940 \u0909\u092e\u094d\u0930 57 \u0938\u093e\u0932 \u0939\u0948, \u0932\u0947\u0915\u093f\u0928 \u092e\u0948\u0902 \u0905\u092d\u0940 \u092d\u0940 \u092f\u0941\u0935\u093e\u0935\u0938\u094d\u0925\u093e \u0915\u0947 \u091c\u0941\u0928\u0942\u0928 \u0938\u0947 \u0932\u0917\u093e\u0924\u093e\u0930 \u0926\u0942\u0930 \u092d\u093e\u0917\u0928\u093e \u0938\u0940\u0916 \u0930\u0939\u093e \u0939\u0942\u0901\u0964\n\u0915\u0949\u0932\u0947\u091c \u092e\u0947\u0902 \u092e\u0947\u0930\u0940 \u090f\u0915 \u0926\u094b\u0938\u094d\u0924 \u0925\u0940 \u091c\u094b \u092e\u0947\u0930\u0940 \u0939\u0940 \u0909\u092e\u094d\u0930 \u0915\u0940 \u0925\u0940\u0964\n\u0932\u0947\u0915\u093f\u0928 \u0935\u0939 \u0906\u091c \u092d\u0940 \u0935\u0948\u0938\u0947 \u0939\u0940 \u091c\u0940\u0935\u0928 \u092f\u093e\u092a\u0928 \u0915\u0930\u0924\u093e \u0939\u0948 \u091c\u0948\u0938\u0947 35 \u0938\u093e\u0932 \u092a\u0939\u0932\u0947 \u0915\u0930\u0924\u093e \u0925\u093e\u0964\n\u0909\u0928\u0915\u093e \u091c\u0940\u0935\u0928 \u0939\u092e\u093e\u0930\u0947 \u0915\u0949\u0932\u0947\u091c \u0915\u0947 \u0926\u093f\u0928\u094b\u0902 \u0915\u0947 \u092f\u0941\u0935\u093e \u091c\u094b\u0936 \u0938\u0947 \u092d\u0930\u093e \u0939\u0941\u0906 \u0939\u0948\u0964\n\u092f\u0939\u093e\u0902 \u0915\u0941\u091b \u0910\u0938\u0947 \u092f\u0941\u0935\u093e\u0935\u0938\u094d\u0925\u093e \u0915\u0947 \u091c\u0941\u0928\u0942\u0928 \u0926\u093f\u090f \u0917\u090f \u0939\u0948\u0902 \u091c\u093f\u0928\u0915\u093e \u0905\u0928\u0941\u092d\u0935 \u0939\u092e\u092e\u0947\u0902 \u0938\u0947 \u0915\u0908 \u0932\u094b\u0917 \u0915\u0930\u0924\u0947 \u0939\u0948\u0902:\n\n*   \u0906\u0928\u0902\u0926: \u092f\u094c\u0928 \u092a\u093e\u092a \u0906\u0928\u0902\u0926 \u0915\u0947 \u092a\u093e\u092a \u0915\u093e \u090f\u0915 \u0938\u093e\u092e\u093e\u0928\u094d\u092f \u0909\u0926\u093e\u0939\u0930\u0923 \u0939\u0948, \u0932\u0947\u0915\u093f\u0928 \u092f\u0939 \u090f\u0915\u092e\u093e\u0924\u094d\u0930 \u0909\u0926\u093e\u0939\u0930\u0923 \u0928\u0939\u0940\u0902 \u0939\u0948\u0964\n\u0905\u0928\u094d\u092f \u092a\u093e\u092a\u092a\u0942\u0930\u094d\u0923 \u0938\u0941\u0916\u094b\u0902 \u092e\u0947\u0902 \u0936\u0930\u093e\u092c, \u092d\u094b\u091c\u0928 \u0914\u0930 \u0915\u0908 \u092a\u094d\u0930\u0915\u093e\u0930 \u0915\u0947 \u092e\u0928\u094b\u0930\u0902\u091c\u0928 \u0936\u093e\u092e\u093f\u0932 \u0939\u094b \u0938\u0915\u0924\u0947 \u0939\u0948\u0902\u0964\n\u0905\u0917\u0930 \u0907\u0928 \u091a\u0940\u091c\u094b\u0902 \u0915\u093e \u0938\u0939\u0940 \u0924\u0930\u0940\u0915\u0947 \u0938\u0947 \u0907\u0938\u094d\u0924\u0947\u092e\u093e\u0932 \u0915\u093f\u092f\u093e \u091c\u093e\u090f \u0924\u094b \u092f\u0947 \u092c\u0941\u0930\u0940 \u0928\u0939\u0940\u0902 \u0939\u0948\u0902\u0964\n\u0909\u0926\u093e\u0939\u0930\u0923 \u0915\u0947 \u0932\u093f\u090f, \u0908\u0938\u093e\u0908 \u0935\u093f\u0935\u093e\u0939 \u0915\u0947 \u0938\u0902\u0926\u0930\u094d\u092d \u092e\u0947\u0902 \u0938\u0947\u0915\u094d\u0938 \u090f\u0915 \u0938\u0941\u0902\u0926\u0930 \u0909\u092a\u0939\u093e\u0930 \u0939\u0948\u0964\n\u0932\u0947\u0915\u093f\u0928 \u091c\u092c \u0939\u092e \u0915\u093f\u0938\u0940 \u092d\u0940 \u091a\u0940\u091c \u0915\u093e \u0917\u0932\u0924 \u0924\u0930\u0940\u0915\u0947 \u0938\u0947 \u0907\u0938\u094d\u0924\u0947\u092e\u093e\u0932 \u0915\u0930\u0924\u0947 \u0939\u0948\u0902, \u0924\u094b \u0939\u092e \u0909\u0938\u0947 \u0905\u092a\u0928\u0947 \u091c\u0940\u0935\u0928 \u092a\u0930 \u0939\u093e\u0935\u0940 \u0939\u094b\u0928\u0947 \u0915\u0940 \u0936\u0915\u094d\u0924\u093f \u0926\u0947 \u0926\u0947\u0924\u0947 \u0939\u0948\u0902\u0964\n\u091c\u092c \u0939\u092e \u0905\u092a\u0928\u0947 \u0926\u093f\u0932 \u0915\u0947 \u0916\u093e\u0932\u0940\u092a\u0928 \u0915\u094b \u092d\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0908\u0936\u094d\u0935\u0930 \u0915\u0947 \u0915\u093f\u0938\u0940 \u092d\u0940 \u0909\u092a\u0939\u093e\u0930 \u0915\u093e \u0909\u092a\u092f\u094b\u0917 \u0915\u0930\u0924\u0947 \u0939\u0948\u0902, \u0924\u094b \u0935\u0939 \u091a\u0940\u091c \u090f\u0915 \u091d\u0942\u0920\u093e \u0926\u0947\u0935\u0924\u093e- \u090f\u0915 \u092e\u0942\u0930\u094d\u0924\u093f \u092c\u0928 \u091c\u093e\u0924\u0940 \u0939\u0948\u0964\n\n*   \u0936\u0915\u094d\u0924\u093f: \u091c\u092c \u0939\u092e \u092f\u0941\u0935\u093e \u0939\u094b\u0924\u0947 \u0939\u0948\u0902, \u0924\u094b \u0915\u092d\u0940-\u0915\u092d\u0940 \u0939\u092e \u0936\u0915\u094d\u0924\u093f\u0939\u0940\u0928, \u0915\u092e\u091c\u094b\u0930 \u092f\u093e \u0905\u092a\u0930\u094d\u092f\u093e\u092a\u094d\u0924 \u092e\u0939\u0938\u0942\u0938 \u0915\u0930\u0924\u0947 \u0939\u0948\u0902\u0964\n\u0915\u093f\u0936\u094b\u0930\u093e\u0935\u0938\u094d\u0925\u093e \u092e\u0947\u0902 \u092e\u0941\u091d\u0947 \u0907\u0928 \u092d\u093e\u0935\u0928\u093e\u0913\u0902 \u0938\u0947 \u091c\u0942\u091d\u0928\u093e \u092a\u0921\u093c\u093e\u0964\n\u0915\u0941\u091b \u0932\u094b\u0917 \u0905\u092a\u0928\u0940 \u0915\u092e\u091c\u094b\u0930\u0940 \u0915\u0940 \u092d\u093e\u0935\u0928\u093e\u0913\u0902 \u0915\u094b \u091b\u0941\u092a\u093e\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0938\u0924\u094d\u0924\u093e \u0939\u093e\u0938\u093f\u0932 \u0915\u0930\u0928\u0947 \u0915\u0940 \u0915\u094b\u0936\u093f\u0936 \u0915\u0930\u0924\u0947 \u0939\u0948\u0902\u0964\n\u0909\u0928\u094d\u0939\u0947\u0902 \u0932\u0917\u0924\u093e \u0939\u0948 \u0915\u093f \u092e\u091c\u092c\u0942\u0924 \u092c\u0928\u0915\u0930 \u0930\u0939\u0928\u0947 \u0938\u0947 \u0909\u0928\u094d\u0939\u0947\u0902 \u0938\u0941\u0930\u0915\u094d\u0937\u093f\u0924 \u092e\u0939\u0938\u0942\u0938 \u0915\u0930\u0928\u0947 \u092e\u0947\u0902 \u092e\u0926\u0926 \u092e\u093f\u0932\u0947\u0917\u0940\u0964\n\u0915\u094d\u092f\u093e \u0906\u092a \u091c\u093e\u0928\u0924\u0947 \u0939\u0948\u0902 \u0915\u093f \u090f\u0915 \u0927\u092e\u0915\u093e\u0928\u0947 \u0935\u093e\u0932\u093e \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u0935\u093e\u0938\u094d\u0924\u0935 \u092e\u0947\u0902 \u0909\u0924\u0928\u093e \u0924\u093e\u0915\u0924\u0935\u0930 \u0928\u0939\u0940\u0902 \u0939\u094b\u0924\u093e \u091c\u093f\u0924\u0928\u093e \u0935\u0939 \u0926\u093f\u0916\u0924\u093e \u0939\u0948?\n\u090f\u0915 \u0927\u092e\u0915\u093e\u0928\u0947 \u0935\u093e\u0932\u093e \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u0906\u092e\u0924\u094c\u0930 \u092a\u0930 \u0935\u0939 \u0939\u094b\u0924\u093e \u0939\u0948 \u091c\u094b \u0905\u092a\u0928\u0947 \u091c\u0940\u0935\u0928 \u092e\u0947\u0902 \u0915\u093f\u0938\u0940 \u091a\u0940\u091c \u0915\u094b \u0932\u0947\u0915\u0930 \u0916\u0941\u0926 \u0915\u094b \u0936\u0915\u094d\u0924\u093f\u0939\u0940\u0928 \u092e\u0939\u0938\u0942\u0938 \u0915\u0930\u0924\u093e \u0939\u0948, \u0907\u0938\u0932\u093f\u090f \u0935\u0939 \u0916\u0941\u0926 \u0915\u094b \u0936\u0915\u094d\u0924\u093f\u0936\u093e\u0932\u0940 \u092e\u0939\u0938\u0942\u0938 \u0915\u0930\u093e\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0926\u0942\u0938\u0930\u094b\u0902 \u0915\u094b \u091a\u094b\u091f \u092a\u0939\u0941\u0902\u091a\u093e\u0924\u093e \u0939\u0948\u0964\n\n*   \u0932\u094b\u0915\u092a\u094d\u0930\u093f\u092f\u0924\u093e: \u092f\u0939 \u092e\u0947\u0930\u0947 \u091c\u0940\u0935\u0928 \u092e\u0947\u0902 \u090f\u0915 \u0914\u0930 \u092a\u094d\u0930\u092c\u0932 \u092a\u094d\u0930\u0932\u094b\u092d\u0928 \u0930\u0939\u093e \u0939\u0948\u0964\n\u092e\u0941\u091d\u0947 \u0905\u0915\u094d\u0938\u0930 \u091a\u093f\u0902\u0924\u093e \u0930\u0939\u0924\u0940 \u0939\u0948 \u0915\u093f \u0932\u094b\u0917 \u092e\u0941\u091d\u0947 \u092a\u0938\u0902\u0926 \u0915\u0930\u0924\u0947 \u0939\u0948\u0902 \u092f\u093e \u0928\u0939\u0940\u0902\u0964\n\u092e\u0941\u091d\u0947 \u0926\u0942\u0938\u0930\u094b\u0902 \u0915\u0940 \u0930\u093e\u092f \u0915\u0940 \u092c\u0939\u0941\u0924 \u091c\u094d\u092f\u093e\u0926\u093e \u092a\u0930\u0935\u093e\u0939 \u0939\u0948\u0964\n\u0906\u092a \u0915\u0948\u0938\u0947 \u0939\u0948\u0902?\n\u0915\u094d\u092f\u093e \u0906\u092a \u0915\u092d\u0940 \u0932\u094b\u0917\u094b\u0902 \u0915\u094b \u0906\u0915\u0930\u094d\u0937\u093f\u0924 \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0905\u092a\u0928\u0947 \u0935\u094d\u092f\u0935\u0939\u093e\u0930 \u092f\u093e \u0926\u093f\u0916\u093e\u0935\u091f \u092e\u0947\u0902 \u092c\u0926\u0932\u093e\u0935 \u0915\u0930\u0924\u0947 \u0939\u0948\u0902?\n\u0915\u094d\u092f\u093e \u0906\u092a\u0915\u094b \u0932\u0917\u0924\u093e \u0939\u0948 \u0915\u093f \u0905\u0938\u094d\u0935\u0940\u0915\u0943\u0924\u093f \u0938\u0947 \u092c\u091a\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0906\u092a\u0915\u094b \u090f\u0915 \u0928\u093f\u0936\u094d\u091a\u093f\u0924 \u0924\u0930\u0940\u0915\u0947 \u0938\u0947 \u0935\u094d\u092f\u0935\u0939\u093e\u0930 \u0915\u0930\u0928\u093e \u092f\u093e \u0926\u093f\u0916\u0928\u093e \u092a\u0921\u093c\u0924\u093e \u0939\u0948?\n\n*   \u0938\u0902\u092a\u0924\u094d\u0924\u093f \u0915\u0947 \u092a\u094d\u0930\u0924\u093f \u0906\u0915\u0930\u094d\u0937\u0923: \u0927\u0928 \u0914\u0930 \u092d\u094c\u0924\u093f\u0915 \u0938\u0902\u092a\u0924\u094d\u0924\u093f \u0915\u0947 \u092a\u094d\u0930\u0924\u093f \u092a\u094d\u0930\u0947\u092e \u0939\u092e\u092e\u0947\u0902 \u0938\u0947 \u0905\u0927\u093f\u0915\u093e\u0902\u0936 \u0932\u094b\u0917\u094b\u0902 \u0915\u0947 \u0932\u093f\u090f \u090f\u0915 \u0938\u092e\u0938\u094d\u092f\u093e \u0939\u0948\u0964\n\u0939\u092e \u0905\u0927\u093f\u0915 \u0938\u093e\u092e\u093e\u0928 \u0930\u0916\u0928\u0947 \u0938\u0947 \u092e\u093f\u0932\u0928\u0947 \u0935\u093e\u0932\u0940 \u0938\u0941\u0930\u0915\u094d\u0937\u093e \u0914\u0930 \u0906\u0930\u093e\u092e \u091a\u093e\u0939\u0924\u0947 \u0939\u0948\u0902\u0964\n\u0907\u0938\u0938\u0947 \u0906\u0938\u094d\u0925\u093e \u0915\u0940 \u0915\u092e\u0940 \u0915\u093e \u092a\u0924\u093e \u091a\u0932\u0924\u093e \u0939\u0948\u0964\n\u0908\u0936\u094d\u0935\u0930 \u091a\u093e\u0939\u0924\u093e \u0939\u0948 \u0915\u093f \u0939\u092e \u092f\u0939 \u0938\u092e\u091d\u0947\u0902 \u0915\u093f \u0935\u0939 \u0939\u092e\u093e\u0930\u093e \u0906\u0936\u094d\u0930\u092f \u0914\u0930 \u0915\u093f\u0932\u093e \u0939\u0948, \u0935\u0939 \u0939\u092e\u093e\u0930\u093e \u092a\u093e\u0932\u0928\u0939\u093e\u0930 \u0939\u0948\u0964\n\u092d\u094c\u0924\u093f\u0915 \u0935\u0938\u094d\u0924\u0941\u090f\u0902 \u0938\u0941\u0916 \u0915\u093e \u0935\u093e\u0926\u093e \u0924\u094b \u0915\u0930\u0924\u0940 \u0939\u0948\u0902, \u0932\u0947\u0915\u093f\u0928 \u0935\u0947 \u0905\u092a\u0928\u093e \u0935\u093e\u0926\u093e \u0915\u092d\u0940 \u092a\u0942\u0930\u093e \u0928\u0939\u0940\u0902 \u0915\u0930 \u0938\u0915\u0924\u0940\u0902\u0964\n\u0915\u094d\u092f\u094b\u0902\u0915\u093f \u0939\u092e\u093e\u0930\u0947 \u0926\u093f\u0932 \u0939\u092e\u0947\u0936\u093e \u0914\u0930 \u0905\u0927\u093f\u0915 \u092a\u093e\u0928\u0947 \u0915\u0940 \u0932\u093e\u0932\u0938\u093e \u0930\u0916\u0947\u0902\u0917\u0947\u0964\n\n*   \u0905\u0939\u0902\u0915\u093e\u0930: \u0935\u093e\u0938\u094d\u0924\u0935 \u092e\u0947\u0902 \u092f\u0939\u0940 \u0939\u0930 \u0926\u0942\u0938\u0930\u0947 \u092a\u093e\u092a \u0915\u093e \u092e\u0942\u0932 \u092a\u093e\u092a \u0939\u0948\u0964\n\u0905\u092d\u093f\u092e\u093e\u0928 \u0935\u0939 \u0935\u093f\u0936\u094d\u0935\u093e\u0938 \u0939\u0948 \u0915\u093f \u092e\u0948\u0902 \u0935\u093e\u0938\u094d\u0924\u0935 \u092e\u0947\u0902 \u0938\u0902\u092a\u0924\u094d\u0924\u093f, \u0936\u0915\u094d\u0924\u093f, \u0938\u0941\u0916 \u0914\u0930 \u0932\u094b\u0915\u092a\u094d\u0930\u093f\u092f\u0924\u093e \u0915\u093e \u0939\u0915\u0926\u093e\u0930 \u0939\u0942\u0902\u0964\n\u0915\u094d\u092f\u094b\u0902? \u0915\u094d\u092f\u094b\u0902\u0915\u093f \u092e\u0948\u0902 \u0916\u093e\u0938 \u0939\u0942\u0901\u0964\n\u0905\u0939\u0902\u0915\u093e\u0930 \u0939\u092e\u0947\u0902 \u091d\u0942\u0920 \u092b\u0941\u0938\u092b\u0941\u0938\u093e\u0924\u093e \u0939\u0948, \u0915\u0939\u0924\u093e \u0939\u0948:\n\u201d\u0915\u094b\u0908 \u092c\u093e\u0924 \u0928\u0939\u0940\u0902, \u0924\u0941\u092e \u0910\u0938\u093e \u0915\u0930 \u0938\u0915\u0924\u0947 \u0939\u094b\u2014\u0924\u0941\u092e \u0907\u0938\u0915\u0947 \u0939\u0915\u0926\u093e\u0930 \u0939\u094b\u0964\u201d\n\u0935\u093f\u091c\u094d\u091e\u093e\u092a\u0928\u0926\u093e\u0924\u093e \u092d\u0940 \u0939\u092e\u0938\u0947 \u092f\u0939\u0940 \u092c\u093e\u0924 \u0915\u0939\u0924\u0947 \u0939\u0948\u0902\u0964\n\u201d\u0906\u092a \u0907\u0938\u0915\u0947 \u0939\u0915\u0926\u093e\u0930 \u0939\u0948\u0902... \u0906\u0917\u0947 \u092c\u0922\u093c\u093f\u090f, \u0907\u0938\u0947 \u0916\u0930\u0940\u0926 \u0932\u0940\u091c\u093f\u090f\u0964\u201d\n\u0939\u094b \u0938\u0915\u0924\u093e \u0939\u0948 \u0915\u0941\u091b \u0914\u0930 \u0916\u0930\u0940\u0926 \u0932\u0947\u0902, \u0915\u094b\u0908 \u092c\u093e\u0924 \u0928\u0939\u0940\u0902\u0964\n\u0907\u0938\u0940\u0932\u093f\u090f \u0939\u092e\u0947\u0902 \u0907\u0938 \u0924\u0930\u0939 \u0915\u0947 \u0907\u0924\u0928\u0947 \u0938\u093e\u0930\u0947 \u0935\u093f\u091c\u094d\u091e\u093e\u092a\u0928 \u0926\u0947\u0916\u0928\u0947 \u0915\u094b \u092e\u093f\u0932\u0924\u0947 \u0939\u0948\u0902, \u0915\u094d\u092f\u094b\u0902\u0915\u093f \u0939\u092e\u093e\u0930\u093e \u0938\u094d\u0935\u093e\u092d\u093f\u092e\u093e\u0928 \u0935\u093e\u0938\u094d\u0924\u0935 \u092e\u0947\u0902 \u0907\u0928 \u092c\u093e\u0924\u094b\u0902 \u092a\u0930 \u0935\u093f\u0936\u094d\u0935\u093e\u0938 \u0915\u0930\u0928\u093e \u091a\u093e\u0939\u0924\u093e \u0939\u0948\u0964\n\n\u0915\u094d\u092f\u093e \u092e\u0948\u0902 \u0906\u092a \u0932\u094b\u0917\u094b\u0902 \u0938\u0947 \u090f\u0915 \u092a\u094d\u0930\u0936\u094d\u0928 \u092a\u0942\u091b \u0938\u0915\u0924\u093e \u0939\u0942\u0901?\n\u0907\u0928 \u092a\u093e\u0902\u091a \u091a\u0940\u091c\u094b\u0902 \u092e\u0947\u0902 \u0938\u0947 \u0915\u094c\u0928 \u0938\u0940 \u092c\u093e\u0924 \u0906\u092a\u0915\u094b \u091c\u093e\u0928\u0940-\u092a\u0939\u091a\u093e\u0928\u0940 \u0932\u0917\u0924\u0940 \u0939\u0948?\n\u0915\u094d\u092f\u093e \u0906\u092a \u0917\u094c\u0930\u0935, \u0938\u0902\u092a\u0924\u094d\u0924\u093f, \u0936\u0915\u094d\u0924\u093f, \u0938\u0941\u0916 \u092f\u093e \u0932\u094b\u0915\u092a\u094d\u0930\u093f\u092f\u0924\u093e \u0915\u0940 \u0924\u0932\u093e\u0936 \u092e\u0947\u0902 \u0939\u0948\u0902?\n\u092f\u093e \u0936\u093e\u092f\u0926 \u0915\u094b\u0908 \u0914\u0930 \u092c\u093e\u0924 \u0939\u0948 \u091c\u094b \u0906\u092a\u0915\u094b \u0908\u0936\u094d\u0935\u0930 \u0938\u0947 \u0926\u0942\u0930 \u0932\u0947 \u091c\u093e\u0924\u0940 \u0939\u0948?\n\u0906\u091c \u0906\u092a\u0915\u093e \u092e\u0928 \u0915\u0939\u093e\u0901 \u0939\u0948, \u0914\u0930 \u0906\u092a \u0915\u0939\u093e\u0901 \u091c\u093e \u0930\u0939\u0947 \u0939\u0948\u0902?\n\u0915\u094d\u092f\u093e \u0906\u092a\u0915\u094b \u092f\u093e\u0926 \u0939\u0948 \u0915\u093f \u0906\u0926\u092e \u0928\u0947 \u092c\u0917\u0940\u091a\u0947 \u092e\u0947\u0902 \u092b\u0932 \u0916\u093e\u0928\u0947 \u0915\u0947 \u092c\u093e\u0926 \u0909\u0938\u0938\u0947 \u0915\u094d\u092f\u093e \u092a\u0942\u091b\u093e \u0925\u093e?\n\u0906\u0926\u092e \u0914\u0930 \u0939\u0935\u094d\u0935\u093e \u091b\u093f\u092a\u0947 \u0939\u0941\u090f \u0925\u0947, \u0914\u0930 \u092d\u0917\u0935\u093e\u0928 \u0928\u0947 \u0915\u0939\u093e, \u201d\u0906\u0926\u092e, \u0924\u0941\u092e \u0915\u0939\u093e\u0901 \u0939\u094b?\u201d\n\u0906\u091c \u0908\u0936\u094d\u0935\u0930 \u092a\u0943\u0925\u094d\u0935\u0940 \u092a\u0930 \u092e\u094c\u091c\u0942\u0926 \u0939\u0930 \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u0938\u0947 \u092f\u0939\u0940 \u0905\u092a\u0947\u0915\u094d\u0937\u093e \u0915\u0930 \u0930\u0939\u093e \u0939\u0948\u0964\n\u0906\u092a \u0915\u0939\u093e\u0902 \u0939\u0948\u0902?\n\u0935\u0939 \u0906\u092a\u0938\u0947 \u092f\u0939 \u0928\u0939\u0940\u0902 \u092a\u0942\u091b \u0930\u0939\u093e \u0939\u0948 \u0915\u093f \u0906\u092a \u0936\u093e\u0930\u0940\u0930\u093f\u0915 \u0930\u0942\u092a \u0938\u0947 \u0915\u0939\u093e\u0901 \u0939\u0948\u0902\u0964\n\u0935\u0939 \u092a\u0942\u091b \u0930\u0939\u093e \u0939\u0948, \u201d\u0924\u0941\u092e\u094d\u0939\u093e\u0930\u093e \u0926\u093f\u0932 \u0915\u0939\u093e\u0901 \u0939\u0948?\u201d\n\u0915\u094d\u092f\u094b\u0902\u0915\u093f \u0939\u092e\u093e\u0930\u093e \u0926\u093f\u0932 \u090f\u0915 \u0915\u0902\u092a\u093e\u0938 \u0915\u0940 \u0924\u0930\u0939 \u0939\u0948 \u091c\u094b \u0939\u092e\u0947\u0902 \u0909\u0938 \u0930\u093e\u0938\u094d\u0924\u0947 \u092a\u0930 \u0932\u0947 \u091c\u093e\u0924\u093e \u0939\u0948 \u091c\u093f\u0938 \u091a\u0940\u091c \u0915\u094b \u0939\u092e \u0938\u092c\u0938\u0947 \u091c\u094d\u092f\u093e\u0926\u093e \u092e\u0939\u0924\u094d\u0935 \u0926\u0947\u0924\u0947 \u0939\u0948\u0902\u0964\n\u0939\u092e \u092d\u091f\u0915 \u091c\u093e\u0924\u0947 \u0939\u0948\u0902 \u0914\u0930 \u0939\u092e\u0947\u0902 \u092a\u0924\u093e \u092d\u0940 \u0928\u0939\u0940\u0902 \u091a\u0932\u0924\u093e \u0915\u094d\u092f\u094b\u0902\u0915\u093f \u092a\u093e\u092a \u092c\u0939\u0941\u0924 \u091a\u093e\u0932\u093e\u0915 \u0939\u094b\u0924\u093e \u0939\u0948\u0964\n\u0939\u092e\u0947\u0902 \u0905\u092a\u0928\u0947 \u092d\u0940\u0924\u0930 \u091a\u0932 \u0930\u0939\u0940 \u092c\u093e\u0924\u094b\u0902 \u0915\u094b \u0938\u092e\u091d\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0908\u0936\u094d\u0935\u0930 \u0915\u0940 \u0938\u0939\u093e\u092f\u0924\u093e \u0915\u0940 \u0906\u0935\u0936\u094d\u092f\u0915\u0924\u093e \u0939\u0948\u0964\n\u0906\u0907\u090f, \u092d\u091c\u0928 \u0938\u0902\u0939\u093f\u0924\u093e 139:23-24 \u0915\u094b \u090f\u0915 \u092a\u094d\u0930\u093e\u0930\u094d\u0925\u0928\u093e \u0915\u0947 \u0930\u0942\u092a \u092e\u0947\u0902 \u092e\u093f\u0932\u0915\u0930 \u092a\u0922\u093c\u0947\u0902:\n\u0938\u092d\u0940: 23 \u201c\u0939\u0947 \u0908\u0936\u094d\u0935\u0930, \u092e\u0947\u0930\u0940 \u0916\u094b\u091c \u0915\u0930\u094b \u0914\u0930 \u092e\u0947\u0930\u0947 \u0939\u0943\u0926\u092f \u0915\u094b \u091c\u093e\u0928\u094b!\n\u092e\u0947\u0930\u0940 \u092a\u0930\u0940\u0915\u094d\u0937\u093e \u0932\u094b \u0914\u0930 \u092e\u0947\u0930\u0947 \u0935\u093f\u091a\u093e\u0930 \u091c\u093e\u0928\u094b!\n24 \u0914\u0930 \u0926\u0947\u0916\u094b \u0915\u093f \u0915\u094d\u092f\u093e \u092e\u0941\u091d\u092e\u0947\u0902 \u0915\u094b\u0908 \u0917\u0902\u092d\u0940\u0930 \u0926\u094b\u0937 \u0939\u0948\u0964\n\u0914\u0930 \u092e\u0941\u091d\u0947 \u0905\u0928\u0928\u094d\u0924 \u092e\u093e\u0930\u094d\u0917 \u092a\u0930 \u0932\u0947 \u091a\u0932\u094b!\n\n\u0908\u0936\u094d\u0935\u0930 \u0915\u0940 \u0938\u0939\u093e\u092f\u0924\u093e \u0915\u0947 \u092c\u093f\u0928\u093e, \u0939\u092e \u201d\u0905\u0928\u0902\u0924 \u0915\u093e\u0932 \u0915\u0947 \u092e\u093e\u0930\u094d\u0917\u201d \u092a\u0930 \u0928\u0939\u0940\u0902 \u091a\u0932 \u092a\u093e\u090f\u0902\u0917\u0947\u0964\n\u0939\u092e \u0917\u0932\u0924 \u0926\u093f\u0936\u093e \u092e\u0947\u0902 \u0926\u094c\u0921\u093c\u0947\u0902\u0917\u0947, \u0909\u0928 \u091a\u0940\u091c\u094b\u0902 \u0915\u093e \u092a\u0940\u091b\u093e \u0915\u0930\u0947\u0902\u0917\u0947 \u091c\u094b \u0939\u092e\u0947\u0902 \u0908\u0936\u094d\u0935\u0930 \u0915\u0947 \u0939\u0943\u0926\u092f \u0938\u0947 \u0926\u0942\u0930 \u0932\u0947 \u091c\u093e\u090f\u0902\u0917\u0940\u0964\n\u0932\u0947\u0915\u093f\u0928 \u0908\u0936\u094d\u0935\u0930 \u0907\u0924\u0928\u093e \u0926\u092f\u093e\u0932\u0941 \u0939\u0948 \u0915\u093f \u0935\u0939 \u0939\u092e\u0947\u0902 \u092f\u0942\u0902 \u0939\u0940 \u092d\u091f\u0915\u0924\u0947 \u0914\u0930 \u0916\u094b \u091c\u093e\u0924\u0947 \u0939\u0941\u090f \u0928\u0939\u0940\u0902 \u0926\u0947\u0916\u0924\u093e\u0964\n\u0907\u0938\u0915\u0947 \u092c\u091c\u093e\u092f, \u0935\u0939 \u0905\u092a\u0928\u0940 \u0916\u094b\u0908 \u0939\u0941\u0908 \u092d\u0947\u0921\u093c\u094b\u0902 \u0915\u094b \u0916\u094b\u091c\u0924\u093e \u0939\u0948\u0964\n\u0935\u0939 \u0939\u092e\u093e\u0930\u0947 \u092a\u093e\u0938 \u0906\u0924\u093e \u0939\u0948 \u0914\u0930 \u0939\u092e\u0947\u0902 \u092c\u091a\u0928\u0947 \u0914\u0930 \u092c\u091a\u093e\u0935 \u0915\u093e \u0930\u093e\u0938\u094d\u0924\u093e \u0926\u093f\u0916\u093e\u0924\u093e \u0939\u0948\u0964\n2 \u0924\u093f\u092e\u094b\u0925\u0940 2:25\u0916-26 \u0915\u094b \u092b\u093f\u0930 \u0938\u0947 \u0926\u0947\u0916\u0947\u0902:\n25\u0916 \u201c\u0939\u094b \u0938\u0915\u0924\u093e \u0939\u0948 \u0915\u093f \u0908\u0936\u094d\u0935\u0930 \u0909\u0928\u094d\u0939\u0947\u0902 \u092a\u0936\u094d\u091a\u093e\u0924\u093e\u092a \u0915\u0930\u0928\u0947 \u0915\u093e \u0905\u0935\u0938\u0930 \u092a\u094d\u0930\u0926\u093e\u0928 \u0915\u0930\u0947 \u091c\u093f\u0938\u0938\u0947 \u0935\u0947 \u0938\u0924\u094d\u092f \u0915\u0947 \u091c\u094d\u091e\u093e\u0928 \u0915\u0940 \u0913\u0930 \u0905\u0917\u094d\u0930\u0938\u0930 \u0939\u094b\u0902\u0964\n26 \u0914\u0930 \u0935\u0947 \u0939\u094b\u0936 \u092e\u0947\u0902 \u0906\u0915\u0930 \u0936\u0948\u0924\u093e\u0928 \u0915\u0947 \u092b\u0902\u0926\u0947 \u0938\u0947 \u092c\u091a \u0928\u093f\u0915\u0932\u0947\u0902\u0917\u0947, \u091c\u092c \u0935\u0939 \u0909\u0928\u094d\u0939\u0947\u0902 \u0905\u092a\u0928\u0940 \u0907\u091a\u094d\u091b\u093e \u092a\u0942\u0930\u0940 \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u092a\u0915\u0921\u093c \u0932\u0947\u0924\u093e \u0939\u0948\u0964\n\n\u0915\u094d\u092f\u093e \u0906\u092a \u091c\u093e\u0928\u0924\u0947 \u0939\u0948\u0902 \u0915\u093f \u092a\u0942\u0930\u0940 \u0924\u0930\u0939 \u0938\u0947 \u0938\u094d\u0935\u0924\u0902\u0924\u094d\u0930 \u092e\u0939\u0938\u0942\u0938 \u0915\u0930\u0928\u093e \u0938\u0902\u092d\u0935 \u0939\u0948, \u091c\u092c\u0915\u093f \u0935\u093e\u0938\u094d\u0924\u0935 \u092e\u0947\u0902 \u0906\u092a \u092a\u093e\u092a \u0914\u0930 \u0936\u0948\u0924\u093e\u0928 \u0915\u0947 \u091a\u0902\u0917\u0941\u0932 \u092e\u0947\u0902 \u092b\u0902\u0938\u0947 \u0939\u0941\u090f \u0939\u0948\u0902?\n\u092a\u093e\u092a \u0938\u094d\u0935\u0924\u0902\u0924\u094d\u0930\u0924\u093e \u091c\u0948\u0938\u093e \u092a\u094d\u0930\u0924\u0940\u0924 \u0939\u094b\u0924\u093e \u0939\u0948, \u0932\u0947\u0915\u093f\u0928 \u0935\u093e\u0938\u094d\u0924\u0935 \u092e\u0947\u0902 \u092f\u0939 \u0907\u0938\u0915\u0947 \u0935\u093f\u092a\u0930\u0940\u0924 \u0939\u0948\u0964\n\u0938\u094d\u0928\u0948\u092f\u0930 \u0907\u0938 \u0924\u0930\u0939 \u0926\u093f\u0916\u0924\u093e \u0939\u0948\u0964\n\u092f\u0939 \u090f\u0915 \u0910\u0938\u093e \u091c\u093e\u0932 \u0939\u0948 \u091c\u094b \u0915\u093f\u0938\u0940 \u0910\u0938\u0947 \u091c\u093e\u0928\u0935\u0930 \u0915\u094b \u092a\u0915\u0921\u093c \u0932\u0947\u0924\u093e \u0939\u0948 \u091c\u094b \u0915\u093f\u0938\u0940 \u0930\u093e\u0938\u094d\u0924\u0947 \u092a\u0930 \u0938\u094d\u0935\u0924\u0902\u0924\u094d\u0930 \u0930\u0942\u092a \u0938\u0947 \u0926\u094c\u0921\u093c \u0930\u0939\u093e \u0925\u093e \u0914\u0930 \u0905\u091a\u093e\u0928\u0915 \u0916\u0924\u0930\u0947 \u092e\u0947\u0902 \u092a\u0921\u093c \u0917\u092f\u093e\u0964\n\u0936\u0948\u0924\u093e\u0928 \u0939\u092e\u0947\u0902 \u0927\u094b\u0916\u093e \u0926\u0947\u0928\u0947 \u0914\u0930 \u092b\u0902\u0938\u093e\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u092e\u0948\u0930\u093e\u0925\u0928 \u0915\u0947 \u0930\u093e\u0938\u094d\u0924\u0947 \u092a\u0930 \u0938\u0902\u0915\u0947\u0924\u094b\u0902 \u0915\u0940 \u0924\u0930\u0939 \u091d\u0942\u0920 \u0932\u0917\u093e\u0924\u093e \u0939\u0948\u0964\n\u0936\u0948\u0924\u093e\u0928 \u091a\u093e\u0939\u0924\u093e \u0939\u0948 \u0915\u093f \u0939\u092e \u0938\u0941\u0916, \u0936\u0915\u094d\u0924\u093f, \u0932\u094b\u0915\u092a\u094d\u0930\u093f\u092f\u0924\u093e, \u0938\u0902\u092a\u0924\u094d\u0924\u093f \u0914\u0930 \u0905\u0939\u0902\u0915\u093e\u0930 \u0915\u0947 \u092a\u0940\u091b\u0947 \u092d\u093e\u0917\u0947\u0902\u0964\n\u092f\u0947 \u092e\u0942\u0930\u094d\u0924\u093f\u092f\u093e\u0902 \u0939\u092e\u0947\u0902 \u0906\u091c\u093e\u0926\u0940 \u0915\u093e \u0935\u093e\u0926\u093e \u0915\u0930\u0924\u0940 \u0939\u0948\u0902, \u0914\u0930 \u0906\u091c\u093e\u0926\u0940 \u0939\u0940 \u0935\u0939 \u091a\u0940\u091c \u0939\u0948 \u091c\u093f\u0938\u0947 \u0939\u092e \u092c\u0939\u0941\u0924 \u091a\u093e\u0939\u0924\u0947 \u0939\u0948\u0902\u0964\n\u0926\u0941\u0930\u094d\u092d\u093e\u0917\u094d\u092f\u0935\u0936, \u0939\u092e \u092e\u093e\u0928\u0924\u0947 \u0939\u0948\u0902 \u0915\u093f \u0910\u0938\u0940 \u091a\u0940\u091c\u0947\u0902 \u0939\u092e\u0947\u0902 \u0938\u0902\u0924\u0941\u0937\u094d\u091f, \u0938\u0941\u0930\u0915\u094d\u0937\u093f\u0924 \u0914\u0930 \u0916\u0941\u0936 \u092e\u0939\u0938\u0942\u0938 \u0915\u0930\u0928\u0947 \u092e\u0947\u0902 \u092e\u0926\u0926 \u0915\u0930 \u0938\u0915\u0924\u0940 \u0939\u0948\u0902\u0964\n\u0932\u0947\u0915\u093f\u0928 \u092f\u0947 \u092e\u0942\u0930\u094d\u0924\u093f\u092f\u093e\u0901 \u0910\u0938\u0947 \u091c\u093e\u0932 \u0939\u0948\u0902 \u091c\u094b \u0939\u092e\u0947\u0902 \u0908\u0936\u094d\u0935\u0930 \u0914\u0930 \u0938\u091a\u094d\u091a\u0947 \u091c\u0940\u0935\u0928 \u0915\u0947 \u092e\u093e\u0930\u094d\u0917 \u0938\u0947 \u0926\u0942\u0930 \u0930\u0916\u0924\u0947 \u0939\u0948\u0902\u0964\n\u0936\u0948\u0924\u093e\u0928 \u0939\u092e\u0938\u0947 \u091c\u0940\u0935\u0928 \u0915\u093e \u092e\u093e\u0930\u094d\u0917 \u091b\u0941\u092a\u093e\u0928\u093e \u091a\u093e\u0939\u0924\u093e \u0939\u0948, \u0914\u0930 \u0915\u0939\u0924\u093e \u0939\u0948:\n\u201c\u0935\u093f\u091c\u092f \u0914\u0930 \u0916\u0941\u0936\u0940 \u0915\u0947 \u0932\u093f\u090f \u0907\u0938 \u092e\u093e\u0930\u094d\u0917 \u092a\u0930 \u091a\u0932\u094b!\u201d\n\u0939\u093e\u0901, \u092f\u0939\u0940 \u0930\u093e\u0938\u094d\u0924\u093e \u0939\u0948! \u092e\u0947\u0930\u0947 \u092a\u0940\u091b\u0947 \u0906\u0913!\n\n\u0924\u094b, \u0907\u0938 \u0924\u0930\u0939 \u0915\u0947 \u091c\u093e\u0932 \u0938\u0947 \u0915\u094b\u0908 \u091c\u093e\u0928\u0935\u0930 \u0915\u0948\u0938\u0947 \u092c\u091a \u0938\u0915\u0924\u093e \u0939\u0948?\n\u0915\u094d\u092f\u093e \u0935\u0939 \u0907\u0938\u0947 \u0916\u0941\u0926 \u0915\u0930 \u0938\u0915\u0924\u093e \u0939\u0948?\n\u0928\u0939\u0940\u0902, \u0916\u0930\u0917\u094b\u0936 \u0905\u0938\u0939\u093e\u092f \u0939\u0948\u0964\n\u0909\u0938\u0947 \u0907\u0938 \u091c\u093e\u0932 \u0938\u0947 \u0928\u093f\u0915\u093e\u0932\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0915\u093f\u0938\u0940 \u0905\u0927\u093f\u0915 \u092c\u0941\u0926\u094d\u0927\u093f\u092e\u093e\u0928 \u0914\u0930 \u092e\u091c\u092c\u0942\u0924 \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u0915\u0940 \u091c\u0930\u0942\u0930\u0924 \u0939\u0948\u0964\n\u0939\u092e\u0947\u0902 \u092d\u0940 \u0915\u093f\u0938\u0940 \u0910\u0938\u0947 \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u0915\u0940 \u091c\u0930\u0942\u0930\u0924 \u0939\u0948 \u091c\u094b \u0939\u092e\u0938\u0947 \u091c\u094d\u092f\u093e\u0926\u093e \u092c\u0941\u0926\u094d\u0927\u093f\u092e\u093e\u0928 \u0914\u0930 \u092e\u091c\u092c\u0942\u0924 \u0939\u094b, \u0924\u093e\u0915\u093f \u0935\u0939 \u0939\u092e\u0947\u0902 \u092c\u091a\u093e \u0938\u0915\u0947\u0964\n\u0907\u0938 \u0936\u094d\u0932\u094b\u0915 \u0915\u0947 \u092c\u093e\u0930\u0947 \u092e\u0947\u0902 \u092e\u0948\u0902 \u091a\u093e\u0939\u0924\u093e \u0939\u0942\u0902 \u0915\u093f \u0906\u092a \u0938\u092c\u0938\u0947 \u092e\u0939\u0924\u094d\u0935\u092a\u0942\u0930\u094d\u0923 \u092c\u093e\u0924 \u092f\u0939\u0940 \u0938\u092e\u091d\u0947\u0902\u0964\n\u0939\u092e\u0947\u0902 \u090f\u0915 \u0909\u0926\u094d\u0927\u093e\u0930\u0915\u0930\u094d\u0924\u093e \u0915\u0940 \u0906\u0935\u0936\u094d\u092f\u0915\u0924\u093e \u0939\u0948 \u0915\u094d\u092f\u094b\u0902\u0915\u093f \u0939\u092e \u0938\u094d\u0935\u092f\u0902 \u0915\u094b \u092c\u091a\u093e \u0928\u0939\u0940\u0902 \u0938\u0915\u0924\u0947 \u0914\u0930 \u0928 \u0939\u0940 \u0908\u0936\u094d\u0935\u0930 \u0915\u0940 \u0936\u0930\u0923 \u0932\u0947 \u0938\u0915\u0924\u0947 \u0939\u0948\u0902\u0964\n\u091c\u093f\u0928 \u0939\u0943\u0926\u092f\u094b\u0902 \u092e\u0947\u0902 \u0906\u0927\u094d\u092f\u093e\u0924\u094d\u092e\u093f\u0915 \u092e\u0943\u0924\u094d\u092f\u0941 \u0939\u094b \u091a\u0941\u0915\u0940 \u0939\u0948, \u0935\u0947 \u091c\u0940\u0935\u0928 \u0915\u093e \u091a\u0941\u0928\u093e\u0935 \u0928\u0939\u0940\u0902 \u0915\u0930 \u0938\u0915\u0924\u0947\u0964\n\u0936\u094d\u0932\u094b\u0915 25 \u092e\u0947\u0902 \u0915\u094d\u092f\u093e \u0915\u0939\u093e \u0917\u092f\u093e \u0939\u0948, \u0909\u0938\u0947 \u0926\u0947\u0916\u0947\u0902:\n\u201d\u0939\u094b \u0938\u0915\u0924\u093e \u0939\u0948 \u0908\u0936\u094d\u0935\u0930 \u0909\u0928\u094d\u0939\u0947\u0902 \u092a\u0936\u094d\u091a\u093e\u0924\u093e\u092a \u0915\u0930\u0928\u0947 \u0915\u0940 \u0936\u0915\u094d\u0924\u093f \u092a\u094d\u0930\u0926\u093e\u0928 \u0915\u0930\u0947\u0964\u201d\n\n\u0905\u0928\u0941\u0926\u093e\u0928 \u090f\u0915 \u0928\u093f\u0903\u0936\u0941\u0932\u094d\u0915 \u0909\u092a\u0939\u093e\u0930 \u0939\u0948\u0964\n\u0908\u0936\u094d\u0935\u0930 \u0928\u0947 \u092e\u0941\u091d\u0947 30 \u0938\u093e\u0932 \u092a\u0939\u0932\u0947 \u092a\u0936\u094d\u091a\u093e\u0924\u093e\u092a \u0915\u093e \u0935\u0930\u0926\u093e\u0928 \u0926\u093f\u092f\u093e \u0925\u093e\u0964\n\u092e\u0948\u0902\u0928\u0947 10 \u0938\u093e\u0932 \u0924\u0915 \u0915\u0939\u093e \u0915\u093f \u092c\u094d\u0930\u0939\u094d\u092e\u093e\u0902\u0921 \u092e\u0947\u0902 \u0915\u094b\u0908 \u0908\u0936\u094d\u0935\u0930 \u0928\u0939\u0940\u0902 \u0939\u0948\u0964\n\u0932\u0947\u0915\u093f\u0928 \u0908\u0936\u094d\u0935\u0930 \u0915\u0940 \u0915\u0943\u092a\u093e \u0938\u0947, \u0909\u0928\u094d\u0939\u094b\u0902\u0928\u0947 \u092e\u0941\u091d\u0947 \u0926\u093f\u0916\u093e\u092f\u093e \u0915\u093f \u092c\u0940\u092f\u0930, \u0938\u094d\u0924\u094d\u0930\u093f\u092f\u093e\u0901 \u0914\u0930 \u0938\u093e\u0902\u0938\u093e\u0930\u093f\u0915 \u0938\u092b\u0932\u0924\u093e \u092e\u0947\u0930\u0947 \u0926\u093f\u0932 \u0915\u0940 \u0907\u091a\u094d\u091b\u093e\u0913\u0902 \u0915\u094b \u0915\u092d\u0940 \u0938\u0902\u0924\u0941\u0937\u094d\u091f \u0928\u0939\u0940\u0902 \u0915\u0930 \u0938\u0915\u0924\u0940\u0902\u0964\n\u0936\u094d\u0932\u094b\u0915 26 \u092e\u0947\u0902 \u201d\u0939\u094b\u0936 \u092e\u0947\u0902 \u0906 \u091c\u093e\u0928\u093e\u201d \u0915\u093e \u092f\u0939\u0940 \u0905\u0930\u094d\u0925 \u0939\u0948\u0964\n\u091c\u092c \u0906\u092a\u0915\u0940 \u0926\u093f\u0936\u093e \u0915\u0940 \u0938\u092e\u091d \u092d\u094d\u0930\u092e\u093f\u0924 \u0939\u094b \u091c\u093e\u0924\u0940 \u0939\u0948 \u0924\u094b \u0906\u092a \u0917\u0932\u0924 \u0926\u093f\u0936\u093e \u092e\u0947\u0902 \u0926\u094c\u0921\u093c\u0928\u0947 \u0932\u0917\u0924\u0947 \u0939\u0948\u0902\u0964\n\u0918\u0930 \u0932\u094c\u091f\u0928\u0947 \u0915\u093e \u092a\u0939\u0932\u093e \u0915\u0926\u092e \u092f\u0939 \u0938\u094d\u0935\u0940\u0915\u093e\u0930 \u0915\u0930\u0928\u093e \u0939\u0948 \u0915\u093f \u0906\u092a \u0916\u094b \u0917\u090f \u0939\u0948\u0902\u0964\n\u092a\u094b\u0930\u094d\u091f\u0932\u0948\u0902\u0921 \u092e\u0947\u0902 \u0939\u0941\u0908 \u0909\u0938 \u092e\u0948\u0930\u093e\u0925\u0928 \u092e\u0947\u0902 \u0932\u093e\u092a\u0924\u093e \u0939\u0941\u090f \u0927\u093e\u0935\u0915\u094b\u0902 \u092e\u0947\u0902 \u0921\u0948\u0928 \u092e\u0948\u0915\u0921\u0949\u0935\u0947\u0932 \u092d\u0940 \u0936\u093e\u092e\u093f\u0932 \u0925\u0947\u0964\n\u0909\u0928\u094d\u0939\u094b\u0902\u0928\u0947 \u0915\u0939\u093e: \u201c\u092e\u0948\u0902 \u0915\u094b\u0928\u0947 \u0938\u0947 \u092e\u0941\u0921\u093c\u093e \u0914\u0930 \u0926\u0947\u0916\u093e \u0915\u093f 10 \u0932\u094b\u0917 \u092c\u0938 \u0938\u094d\u0925\u093f\u0930 \u0916\u0921\u093c\u0947 \u0925\u0947\u2026\u201d\n\u0935\u0947 \u090f\u0915-\u0926\u0942\u0938\u0930\u0947 \u0915\u094b \u0926\u0947\u0916 \u0930\u0939\u0947 \u0925\u0947 \u0914\u0930 \u0938\u094b\u091a \u0930\u0939\u0947 \u0925\u0947, \u2018\u0909\u0939, \u092f\u0939 \u0920\u0940\u0915 \u0928\u0939\u0940\u0902 \u0932\u0917 \u0930\u0939\u093e \u0939\u0948\u0964\u2019\n\n\u090f\u0915 \u0905\u0928\u094d\u092f \u0927\u093e\u0935\u0915, \u091c\u093c\u0948\u0915 \u0915\u0938\u094d\u091f\u0930 \u0928\u0947 \u092c\u0924\u093e\u092f\u093e \u0915\u093f \u0935\u0939 \u090f\u0915 \u0938\u0941\u0930\u0902\u0917 \u092e\u0947\u0902 \u0926\u093e\u0916\u093f\u0932 \u0939\u0941\u0906, \u091c\u0939\u093e\u0902 \u0938\u0947 \u0917\u093e\u0921\u093c\u093f\u092f\u093e\u0902 55 \u092e\u0940\u0932 \u092a\u094d\u0930\u0924\u093f \u0918\u0902\u091f\u0947 \u0915\u0940 \u0930\u092b\u094d\u0924\u093e\u0930 \u0938\u0947 \u0909\u0938\u0915\u0947 \u092a\u093e\u0938 \u0938\u0947 \u0917\u0941\u091c\u093c\u0930 \u0930\u0939\u0940 \u0925\u0940\u0902\u0964\n\u0924\u092d\u0940 \u0909\u0928\u094d\u0939\u0947\u0902 \u090f\u0939\u0938\u093e\u0938 \u0939\u0941\u0906 \u0915\u093f \u0935\u0947 \u0905\u092a\u0928\u0947 \u0930\u093e\u0938\u094d\u0924\u0947 \u0938\u0947 \u092d\u091f\u0915 \u0917\u090f \u0939\u0948\u0902\u0964\n\u0908\u0936\u094d\u0935\u0930 \u0926\u094d\u0935\u093e\u0930\u093e \u092e\u0941\u091d\u0947 \u0939\u094b\u0936 \u092e\u0947\u0902 \u0932\u093e\u0928\u0947 \u0938\u0947 \u092a\u0939\u0932\u0947, \u092e\u0948\u0902 \u0938\u094b\u091a\u0924\u093e \u0925\u093e \u0915\u093f \u092e\u0941\u091d\u0947 \u201d\u0938\u0924\u094d\u092f \u0915\u093e \u091c\u094d\u091e\u093e\u0928\u201d \u0939\u0948\u0964\n\u092e\u0947\u0930\u0947 \u0905\u0939\u0902\u0915\u093e\u0930 \u0928\u0947 \u092e\u0941\u091d\u0947 \u092c\u0924\u093e\u092f\u093e \u0915\u093f \u092e\u0948\u0902 \u0938\u0939\u0940 \u0930\u093e\u0938\u094d\u0924\u0947 \u092a\u0930 \u0939\u0942\u0902, \u0914\u0930 \u092e\u0941\u091d\u0947 \u092e\u093e\u0930\u094d\u0917\u0926\u0930\u094d\u0936\u0928 \u0915\u0947 \u0932\u093f\u090f \u0915\u093f\u0938\u0940 \u092d\u0917\u0935\u093e\u0928 \u0915\u0940 \u091c\u0930\u0942\u0930\u0924 \u0928\u0939\u0940\u0902 \u0939\u0948 \u0915\u094d\u092f\u094b\u0902\u0915\u093f \u092e\u0948\u0902 \u092c\u0939\u0941\u0924 \u092c\u0941\u0926\u094d\u0927\u093f\u092e\u093e\u0928 \u0925\u093e\u0964\n\u0935\u093f\u0921\u0902\u092c\u0928\u093e \u092f\u0939 \u0939\u0948 \u0915\u093f \u092e\u0948\u0902 \u0936\u0948\u0924\u093e\u0928 \u0915\u0947 \u0927\u094b\u0916\u0947 \u0915\u094b \u0938\u092e\u091d\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u092c\u0939\u0941\u0924 \u092e\u0942\u0930\u094d\u0916 \u0925\u093e\u0964\n\u092e\u0948\u0902 \u0909\u0938\u0915\u0947 \u091d\u0942\u0920 \u0915\u0947 \u091c\u093e\u0932 \u092e\u0947\u0902 \u092b\u0902\u0938 \u0917\u092f\u093e \u0925\u093e\u0964\n\u092e\u0948\u0902\u0928\u0947 \u0936\u0948\u0924\u093e\u0928 \u0915\u0947 \u0907\u0938 \u0935\u093e\u0926\u0947 \u092a\u0930 \u0935\u093f\u0936\u094d\u0935\u093e\u0938 \u0915\u093f\u092f\u093e \u0915\u093f \u092d\u0917\u0935\u093e\u0928 \u0938\u0947 \u0926\u0942\u0930 \u092d\u093e\u0917\u0928\u0947 \u0938\u0947 \u092e\u0941\u091d\u0947 \u0916\u0941\u0936\u0940 \u092e\u093f\u0932\u0947\u0917\u0940\u0964\n\u0932\u0947\u0915\u093f\u0928 \u092b\u093f\u0930, \u0908\u0936\u094d\u0935\u0930 \u0928\u0947 \u092e\u0941\u091d\u0947 \u092a\u0936\u094d\u091a\u093e\u0924\u093e\u092a \u0915\u093e \u0935\u0930\u0926\u093e\u0928 \u0926\u093f\u092f\u093e\u0964\n\u092f\u0939\u093e\u0902 \u092a\u0936\u094d\u091a\u093e\u0924\u093e\u092a \u0915\u0947 \u0932\u093f\u090f \u092a\u094d\u0930\u092f\u0941\u0915\u094d\u0924 \u0917\u094d\u0930\u0940\u0915 \u0936\u092c\u094d\u0926 \u092e\u0947\u091f\u093e\u0928\u094b\u0907\u092f\u093e \u0939\u0948\u0964\n\u0907\u0938\u0915\u093e \u0905\u0930\u094d\u0925 \u0939\u0948 \u201d\u0935\u093f\u091a\u093e\u0930\u0927\u093e\u0930\u093e \u092e\u0947\u0902 \u092a\u0930\u093f\u0935\u0930\u094d\u0924\u0928, \u091c\u0940\u0935\u0928 \u092e\u0947\u0902 \u092a\u0930\u093f\u0935\u0930\u094d\u0924\u0928 \u0914\u0930 \u0909\u0926\u094d\u0926\u0947\u0936\u094d\u092f \u092e\u0947\u0902 \u092a\u0930\u093f\u0935\u0930\u094d\u0924\u0928\u0964\u201d\n\u092f\u0940\u0936\u0941 \u0928\u0947 \u092e\u0941\u091d\u0947 \u090f\u0915 \u0928\u092f\u093e \u0939\u0943\u0926\u092f \u0926\u093f\u092f\u093e \u0924\u093e\u0915\u093f \u092e\u0948\u0902 \u201d\u0936\u0941\u0926\u094d\u0927 \u0939\u0943\u0926\u092f \u0938\u0947 \u092a\u094d\u0930\u092d\u0941 \u0915\u094b \u092a\u0941\u0915\u093e\u0930 \u0938\u0915\u0942\u0901\u201d \u091c\u0948\u0938\u093e \u0915\u093f \u092a\u0926 22 \u092e\u0947\u0902 \u0915\u0939\u093e \u0917\u092f\u093e \u0939\u0948\u0964\n\u0936\u0941\u0926\u094d\u0927 \u0939\u0943\u0926\u092f \u0939\u0940 \u0908\u092e\u093e\u0928\u0926\u093e\u0930 \u0939\u0943\u0926\u092f \u0939\u094b\u0924\u093e \u0939\u0948\u0964\n\u090f\u0915 \u0910\u0938\u093e \u0939\u0943\u0926\u092f \u091c\u094b \u0908\u0936\u094d\u0935\u0930 \u0938\u0947 \u092a\u094d\u0930\u093e\u0930\u094d\u0925\u0928\u093e \u0915\u0930\u0924\u093e \u0939\u0948, \u201d\u092e\u0941\u091d\u0947 \u0905\u092a\u0928\u0947 \u092a\u093e\u092a \u0915\u0947 \u0932\u093f\u090f \u0916\u0947\u0926 \u0939\u0948, \u0915\u0943\u092a\u092f\u093e \u092e\u0941\u091d\u0947 \u0915\u094d\u0937\u092e\u093e \u0915\u0930 \u0926\u0940\u091c\u093f\u090f\u0964\u201d\n\u092e\u0941\u091d\u0947 \u0906\u092a\u0915\u0940 \u0913\u0930 \u0926\u094c\u0921\u093c\u0928\u0947 \u092e\u0947\u0902 \u092e\u0926\u0926 \u0915\u0930\u0947\u0902, \u0906\u092a\u0938\u0947 \u0926\u0942\u0930 \u092d\u093e\u0917\u0928\u0947 \u092e\u0947\u0902 \u0928\u0939\u0940\u0902\u0964\u201d\n\u092a\u094c\u0932\u0941\u0938 \u0928\u0947 \u0930\u094b\u092e\u093f\u092f\u094b\u0902 10:9-11 \u092e\u0947\u0902 \u092c\u0939\u0941\u0924 \u0938\u094d\u092a\u0937\u094d\u091f \u0930\u0942\u092a \u0938\u0947 \u092c\u0924\u093e\u092f\u093e \u0939\u0948 \u0915\u093f \u0906\u092a \u0915\u0948\u0938\u0947 \u092a\u0930\u092e\u0947\u0936\u094d\u0935\u0930 \u0915\u0940 \u0913\u0930 \u092e\u0941\u0921\u093c \u0938\u0915\u0924\u0947 \u0939\u0948\u0902 \u0914\u0930 \u0909\u0926\u094d\u0927\u093e\u0930 \u092a\u093e \u0938\u0915\u0924\u0947 \u0939\u0948\u0902\u0964\n9 \u201c\u092f\u0926\u093f \u0924\u0941\u092e \u0905\u092a\u0928\u0947 \u092e\u0941\u0901\u0939 \u0938\u0947 \u092f\u0939 \u0938\u094d\u0935\u0940\u0915\u093e\u0930 \u0915\u0930\u094b \u0915\u093f \u201c\u092f\u0940\u0936\u0941 \u092a\u094d\u0930\u092d\u0941 \u0939\u0948,\u201d \u0914\u0930 \u0905\u092a\u0928\u0947 \u0939\u0943\u0926\u092f \u092e\u0947\u0902 \u0935\u093f\u0936\u094d\u0935\u093e\u0938 \u0915\u0930\u094b \u0915\u093f \u092a\u0930\u092e\u0947\u0936\u094d\u0935\u0930 \u0928\u0947 \u0909\u0938\u0947 \u092e\u0930\u0947 \u0939\u0941\u0913\u0902 \u092e\u0947\u0902 \u0938\u0947 \u091c\u093f\u0932\u093e\u092f\u093e \u0939\u0948, \u0924\u094b \u0924\u0941\u092e \u0909\u0926\u094d\u0927\u093e\u0930 \u092a\u093e\u0913\u0917\u0947\u0964\u201d\n10 \u0915\u094d\u092f\u094b\u0902\u0915\u093f \u0939\u0943\u0926\u092f \u0938\u0947 \u0935\u093f\u0936\u094d\u0935\u093e\u0938 \u0915\u0930\u0928\u0947 \u092a\u0930 \u0939\u0940 \u0927\u0930\u094d\u092e\u0940 \u0920\u0939\u0930\u093e\u092f\u093e \u091c\u093e\u0924\u093e \u0939\u0948, \u0914\u0930 \u092e\u0941\u0916 \u0938\u0947 \u0935\u093f\u0936\u094d\u0935\u093e\u0938 \u0938\u094d\u0935\u0940\u0915\u093e\u0930 \u0915\u0930\u0928\u0947 \u092a\u0930 \u0909\u0926\u094d\u0927\u093e\u0930 \u092a\u093e\u092f\u093e \u091c\u093e\u0924\u093e \u0939\u0948\u0964\n11 \u091c\u0948\u0938\u093e \u0915\u093f \u092a\u0935\u093f\u0924\u094d\u0930\u0936\u093e\u0938\u094d\u0924\u094d\u0930 \u092e\u0947\u0902 \u0915\u0939\u093e \u0917\u092f\u093e \u0939\u0948, \u201c\u091c\u094b \u0915\u094b\u0908 \u0909\u0938 \u092a\u0930 \u0935\u093f\u0936\u094d\u0935\u093e\u0938 \u0915\u0930\u0924\u093e \u0939\u0948, \u0935\u0939 \u0915\u092d\u0940 \u0932\u091c\u094d\u091c\u093f\u0924 \u0928\u0939\u0940\u0902 \u0939\u094b\u0917\u093e\u0964\u201d\n\n\u0915\u094d\u092f\u093e \u0906\u092a\u0928\u0947 \u0905\u092a\u0928\u0947 \u092e\u0941\u0916 \u0938\u0947 \u0935\u093f\u0936\u094d\u0935\u093e\u0938 \u0915\u0940 \u0905\u092d\u093f\u0935\u094d\u092f\u0915\u094d\u0924\u093f \u0915\u0940 \u0939\u0948, \u0924\u093e\u0915\u093f \u0906\u092a \u0909\u0926\u094d\u0927\u093e\u0930 \u092a\u093e \u0938\u0915\u0947\u0902?\n\u0905\u0917\u0930 \u0906\u092a\u0928\u0947 \u0910\u0938\u093e \u0928\u0939\u0940\u0902 \u0915\u093f\u092f\u093e \u0939\u0948, \u0924\u094b \u0915\u094d\u092f\u093e \u0906\u092a\u0915\u094b \u0928\u0939\u0940\u0902 \u0932\u0917\u0924\u093e \u0915\u093f \u0906\u091c \u0910\u0938\u093e \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u090f\u0915 \u092c\u0947\u0939\u0924\u0930\u0940\u0928 \u0926\u093f\u0928 \u0939\u094b\u0917\u093e?\n\u092a\u0935\u093f\u0924\u094d\u0930 \u0906\u0924\u094d\u092e\u093e \u0939\u092e\u093e\u0930\u0947 \u092c\u0940\u091a \u092e\u094c\u091c\u0942\u0926 \u0939\u0948, \u0914\u0930 \u0936\u093e\u092f\u0926 \u0935\u0939 \u0906\u092a\u0915\u0947 \u0939\u0943\u0926\u092f \u092e\u0947\u0902 \u0915\u0941\u091b \u092b\u0941\u0938\u092b\u0941\u0938\u093e \u0930\u0939\u093e \u0939\u0948:\n\u201c\u092a\u093e\u092a \u0914\u0930 \u092e\u0943\u0924\u094d\u092f\u0941 \u0915\u0947 \u092e\u093e\u0930\u094d\u0917 \u0938\u0947 \u092e\u0941\u0921\u093c \u091c\u093e\u0913!\u201d\n\u201d\u092f\u0940\u0936\u0941 \u0915\u094b \u092a\u094d\u0930\u092d\u0941 \u0918\u094b\u0937\u093f\u0924 \u0915\u0930\u0915\u0947 \u090f\u0915 \u0928\u092f\u093e \u091c\u0940\u0935\u0928 \u0914\u0930 \u090f\u0915 \u0928\u0908 \u0926\u093f\u0936\u093e \u091a\u0941\u0928\u0947\u0902!\u201d\n\n\u092a\u0949\u0932 \u0928\u0947 \u0907\u0938\u0938\u0947 \u092a\u0939\u0932\u0947 \u092d\u0940 \u0909\u0938 \u0928\u0908 \u0926\u093f\u0936\u093e \u0915\u0947 \u092c\u093e\u0930\u0947 \u092e\u0947\u0902 \u0932\u093f\u0916\u093e \u0925\u093e\u0964\n\u092f\u0939 \u092a\u0924\u094d\u0930 \u0907\u092b\u093f\u0938\u0941\u0938 \u0915\u0947 \u0909\u0938\u0940 \u091a\u0930\u094d\u091a \u0915\u094b \u0932\u093f\u0916\u093e \u0917\u092f\u093e \u0925\u093e, \u091c\u0939\u093e\u0902 \u0924\u093f\u092e\u094b\u0925\u0940 \u0905\u092c \u090f\u0915 \u092a\u093e\u0926\u0930\u0940 \u0915\u0947 \u0930\u0942\u092a \u092e\u0947\u0902 \u0938\u0947\u0935\u093e \u0915\u0930 \u0930\u0939\u0947 \u0939\u0948\u0902\u0964\n\u0938\u0941\u0928\u093f\u090f \u092a\u094c\u0932\u0941\u0938 \u0928\u0947 \u0907\u092b\u093f\u0938\u093f\u092f\u094b\u0902 2:1-5 \u092e\u0947\u0902 \u092e\u0938\u0940\u0939\u0940 \u0935\u093f\u0936\u094d\u0935\u093e\u0938\u093f\u092f\u094b\u0902 \u0915\u094b \u0915\u094d\u092f\u093e \u0932\u093f\u0916\u093e \u0939\u0948, \u091c\u093f\u0938\u092e\u0947\u0902 \u092c\u0924\u093e\u092f\u093e \u0917\u092f\u093e \u0939\u0948 \u0915\u093f \u092a\u0930\u092e\u0947\u0936\u094d\u0935\u0930 \u0928\u0947 \u0909\u0928\u094d\u0939\u0947\u0902 \u0928\u092f\u093e \u091c\u0940\u0935\u0928 \u0914\u0930 \u0928\u0908 \u0926\u093f\u0936\u093e \u0926\u0947\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0915\u094d\u092f\u093e \u0915\u093f\u092f\u093e:\n1 \u201d\u0914\u0930 \u0924\u0941\u092e \u0905\u092a\u0930\u093e\u0927\u094b\u0902 \u0914\u0930 \u092a\u093e\u092a\u094b\u0902 \u092e\u0947\u0902 \u092e\u0930\u0947 \u0939\u0941\u090f \u0925\u0947\u0964\u201d\n2 \u091c\u093f\u0938 \u092e\u093e\u0930\u094d\u0917 \u092a\u0930 \u0924\u0941\u092e \u090f\u0915 \u0938\u092e\u092f \u0907\u0938 \u0938\u0902\u0938\u093e\u0930 \u0915\u0947 \u092e\u093e\u0930\u094d\u0917 \u0915\u093e \u0905\u0928\u0941\u0938\u0930\u0923 \u0915\u0930\u0924\u0947 \u0939\u0941\u090f, \u0935\u093e\u092f\u0941 \u0915\u0947 \u0938\u093e\u092e\u0930\u094d\u0925\u094d\u092f \u0915\u0947 \u0938\u094d\u0935\u093e\u092e\u0940, \u0909\u0938 \u0906\u0924\u094d\u092e\u093e \u0915\u0947 \u092a\u0940\u091b\u0947 \u091a\u0932\u0924\u0947 \u0925\u0947 \u091c\u094b \u0905\u092c \u0905\u0935\u091c\u094d\u091e\u093e \u0915\u0947 \u092a\u0941\u0924\u094d\u0930\u094b\u0902 \u092e\u0947\u0902 \u0915\u093e\u0930\u094d\u092f\u0930\u0924 \u0939\u0948\u2014\n3 \u0939\u092e \u0938\u092c \u092d\u0940 \u090f\u0915 \u0938\u092e\u092f \u0905\u092a\u0928\u0940 \u0926\u0947\u0939 \u0915\u0940 \u0935\u093e\u0938\u0928\u093e\u0913\u0902 \u092e\u0947\u0902 \u091c\u0940\u0924\u0947 \u0925\u0947, \u0936\u0930\u0940\u0930 \u0914\u0930 \u092e\u0928 \u0915\u0940 \u0907\u091a\u094d\u091b\u093e\u0913\u0902 \u0915\u094b \u092a\u0942\u0930\u093e \u0915\u0930\u0924\u0947 \u0925\u0947, \u0914\u0930 \u0938\u094d\u0935\u092d\u093e\u0935 \u0938\u0947 \u0915\u094d\u0930\u094b\u0927 \u0915\u0940 \u0938\u0902\u0924\u093e\u0928 \u0925\u0947, \u091c\u0948\u0938\u0947 \u092c\u093e\u0915\u0940 \u092e\u0928\u0941\u0937\u094d\u092f \u091c\u093e\u0924\u093f\u0964\n4 \u092a\u0930\u0928\u094d\u0924\u0941 \u092a\u0930\u092e\u0947\u0936\u094d\u0935\u0930, \u091c\u094b \u0905\u0924\u094d\u092f\u0902\u0924 \u0926\u092f\u093e\u0932\u0941 \u0939\u0948, \u0909\u0938\u0928\u0947 \u0939\u092e\u0947\u0902 \u091c\u093f\u0938 \u092e\u0939\u093e\u0928 \u092a\u094d\u0930\u0947\u092e \u0938\u0947 \u092a\u094d\u0930\u0947\u092e \u0915\u093f\u092f\u093e \u0939\u0948, \u0909\u0938\u0915\u0947 \u0915\u093e\u0930\u0923 \u0910\u0938\u093e \u0915\u093f\u092f\u093e \u0939\u0948\u0964\n5 \u091c\u092c \u0939\u092e \u0905\u092a\u0928\u0947 \u092a\u093e\u092a\u094b\u0902 \u092e\u0947\u0902 \u092e\u0930\u0947 \u0939\u0941\u090f \u0925\u0947, \u0924\u092c \u092d\u0940 \u0909\u0938\u0928\u0947 \u0939\u092e\u0947\u0902 \u092e\u0938\u0940\u0939 \u0915\u0947 \u0938\u093e\u0925 \u091c\u0940\u0935\u093f\u0924 \u0915\u093f\u092f\u093e\u2014\u0905\u0928\u0941\u0917\u094d\u0930\u0939 \u0938\u0947 \u0939\u0940 \u0924\u0941\u092e \u092c\u091a\u093e\u090f \u0917\u090f \u0939\u094b!\n\n\u201d\u0932\u0947\u0915\u093f\u0928 \u092d\u0917\u0935\u093e\u0928\u201d \u092f\u0947 \u0926\u094b \u0936\u092c\u094d\u0926 \u0905\u092c \u0924\u0915 \u092c\u094b\u0932\u0947 \u0917\u090f \u0938\u092c\u0938\u0947 \u0916\u0942\u092c\u0938\u0942\u0930\u0924 \u0936\u092c\u094d\u0926\u094b\u0902 \u092e\u0947\u0902 \u0938\u0947 \u0939\u0948\u0902\u0964\n\u092a\u094c\u0932\u0941\u0938 \u0907\u092b\u093f\u0938\u0941\u0938 \u0915\u0947 \u0935\u093f\u0936\u094d\u0935\u093e\u0938\u093f\u092f\u094b\u0902 \u0915\u094b \u092f\u093e\u0926 \u0926\u093f\u0932\u093e\u0924\u093e \u0939\u0948 \u0915\u093f \u0935\u0947 \u092d\u0940 \u090f\u0915 \u0938\u092e\u092f \u0909\u0938 \u0916\u0930\u0917\u094b\u0936 \u0915\u0940 \u0924\u0930\u0939 \u092b\u0901\u0938\u0947 \u0939\u0941\u090f \u0914\u0930 \u0905\u0938\u0939\u093e\u092f \u0925\u0947 \u091c\u094b \u091c\u093e\u0932 \u092e\u0947\u0902 \u092b\u0901\u0938\u093e \u0939\u0941\u0906 \u0925\u093e\u0964\n\u0932\u0947\u0915\u093f\u0928 \u092a\u0930\u092e\u0947\u0936\u094d\u0935\u0930 \u0928\u0947 \u0915\u0947\u0935\u0932 \u0905\u092a\u0928\u0940 \u0915\u0943\u092a\u093e \u0938\u0947, \u0915\u0947\u0935\u0932 \u0905\u092a\u0928\u0947 \u0935\u093f\u0936\u094d\u0935\u093e\u0938 \u0915\u0947 \u0926\u094d\u0935\u093e\u0930\u093e, \u0914\u0930 \u0915\u0947\u0935\u0932 \u092e\u0938\u0940\u0939 \u0915\u0947 \u092e\u093e\u0927\u094d\u092f\u092e \u0938\u0947 \u0909\u0928\u094d\u0939\u0947\u0902 \u092c\u091a\u093e\u092f\u093e\u0964\n\u0915\u094b\u0908 \u092d\u0940 \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u0909\u0926\u094d\u0927\u093e\u0930 \u092a\u093e \u0938\u0915\u0924\u093e \u0939\u0948, \u092f\u0926\u093f \u0906\u092a \u092f\u0939 \u0935\u093f\u0936\u094d\u0935\u093e\u0938 \u0915\u0930\u0924\u0947 \u0939\u0948\u0902 \u0915\u093f \u0915\u094d\u0930\u0942\u0938 \u092a\u0930 \u092e\u0938\u0940\u0939 \u0915\u093e \u092c\u0932\u093f\u0926\u093e\u0928 \u0906\u092a\u0915\u0947 \u0932\u093f\u090f \u0925\u093e, \u0924\u093e\u0915\u093f \u0935\u0939 \u0906\u092a\u0915\u094b \u092a\u093e\u092a \u0914\u0930 \u0936\u0930\u094d\u092e \u0938\u0947 \u0927\u094b \u0938\u0915\u0947\u0964\n\u091c\u092c \u0906\u092a \u0907\u0938 \u092c\u093e\u0924 \u092a\u0930 \u0935\u093f\u0936\u094d\u0935\u093e\u0938 \u0915\u0930\u0924\u0947 \u0939\u0948\u0902, \u0924\u094b \u0906\u092a\u0915\u094b \u0928\u092f\u093e \u091c\u0940\u0935\u0928 \u092a\u094d\u0930\u093e\u092a\u094d\u0924 \u0939\u094b\u0924\u093e \u0939\u0948 \u0914\u0930 \u092f\u0940\u0936\u0941 \u0906\u092a\u0915\u094b \u090f\u0915 \u0928\u090f \u092e\u093e\u0930\u094d\u0917 \u092a\u0930 \u0932\u0947 \u091c\u093e\u0924\u093e \u0939\u0948\u0964\n\u0915\u0941\u091b \u091b\u0902\u0926\u094b\u0902 \u092c\u093e\u0926 \u0907\u092b\u093f\u0938\u093f\u092f\u094b\u0902 2:8 \u092e\u0947\u0902, \u092a\u094c\u0932\u0941\u0938 \u0909\u0938 \u0928\u0908 \u0926\u093f\u0936\u093e \u0915\u0947 \u092c\u093e\u0930\u0947 \u092e\u0947\u0902 \u092c\u093e\u0924 \u0915\u0930\u0924\u093e \u0939\u0948\u0964\n\u0907\u0938\u0947 \u092e\u0947\u0930\u0947 \u0938\u093e\u0925 \u092a\u0922\u093c\u093f\u090f:\n\u0938\u092d\u0940: 10 \u201c\u0915\u094d\u092f\u094b\u0902\u0915\u093f \u0939\u092e \u0909\u0938\u0915\u0940 \u0930\u091a\u0928\u093e \u0939\u0948\u0902, \u092e\u0938\u0940\u0939 \u092f\u0940\u0936\u0941 \u092e\u0947\u0902 \u092d\u0932\u0947 \u0915\u093e\u092e\u094b\u0902 \u0915\u0947 \u0932\u093f\u090f \u0938\u0943\u091c\u093f\u0924 \u0915\u093f\u090f \u0917\u090f \u0939\u0948\u0902, \u091c\u093f\u0928\u094d\u0939\u0947\u0902 \u092a\u0930\u092e\u0947\u0936\u094d\u0935\u0930 \u0928\u0947 \u092a\u0939\u0932\u0947 \u0938\u0947 \u0924\u0948\u092f\u093e\u0930 \u0915\u093f\u092f\u093e \u0925\u093e, \u0924\u093e\u0915\u093f \u0939\u092e \u0909\u0928\u092e\u0947\u0902 \u091a\u0932\u0947\u0902\u0964\u201d\n\n\u0907\u0938 \u0938\u0902\u0926\u0947\u0936 \u0915\u094b \u0938\u092e\u093e\u092a\u094d\u0924 \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f, \u0906\u0907\u090f \u0926\u0947\u0916\u0947\u0902 \u0915\u093f \u0905\u091a\u094d\u091b\u0947 \u0915\u093e\u0930\u094d\u092f\u094b\u0902 \u0915\u0947 \u092e\u093e\u0930\u094d\u0917 \u092a\u0930 \u091a\u0932\u0928\u093e \u0915\u0948\u0938\u093e \u0926\u093f\u0916\u0924\u093e \u0939\u0948\u0964\n\u092f\u093e\u0926 \u0930\u0916\u0947\u0902 \u0915\u093f \u092a\u094c\u0932\u0941\u0938 \u0924\u0940\u092e\u094b\u0925\u0940 \u0915\u094b \u0932\u093f\u0916 \u0930\u0939\u093e \u0939\u0948 \u0914\u0930 \u0909\u0938\u0947 \u092e\u093e\u0930\u094d\u0917\u0926\u0930\u094d\u0936\u0928 \u0926\u0947 \u0930\u0939\u093e \u0939\u0948 \u0915\u093f \u092c\u093e\u0907\u092c\u0932 \u0936\u093f\u0915\u094d\u0937\u0915\u094b\u0902 \u0915\u0947 \u0930\u0942\u092a \u092e\u0947\u0902 \u0915\u093f\u0938\u0947 \u091a\u0941\u0928\u0928\u093e \u0914\u0930 \u092a\u094d\u0930\u0936\u093f\u0915\u094d\u0937\u093f\u0924 \u0915\u0930\u0928\u093e \u0939\u0948\u0964\n\u0914\u0930 \u0935\u093f\u0936\u094d\u0935\u093e\u0938\u093f\u092f\u094b\u0902 \u0915\u0947 \u0930\u0942\u092a \u092e\u0947\u0902 \u0939\u092e\u093e\u0930\u093e \u092e\u093f\u0936\u0928 \u0926\u0942\u0930-\u0926\u0942\u0930 \u0924\u0915 \u0915\u0947 \u0932\u094b\u0917\u094b\u0902 \u0915\u0947 \u0938\u093e\u0925 \u0938\u0941\u0938\u092e\u093e\u091a\u093e\u0930 \u0915\u0940 \u0916\u0941\u0936\u0916\u092c\u0930\u0940 \u0938\u093e\u091d\u093e \u0915\u0930\u0928\u093e \u0939\u0948\u0964\n\u0932\u0947\u0915\u093f\u0928 \u0910\u0938\u093e \u0908\u092e\u093e\u0928\u0926\u093e\u0930\u0940 \u0938\u0947 \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f, \u0939\u092e\u093e\u0930\u0947 \u092a\u093e\u0938 \u0935\u0939 \u091a\u0930\u093f\u0924\u094d\u0930 \u0939\u094b\u0928\u093e \u091a\u093e\u0939\u093f\u090f \u091c\u093f\u0938\u0915\u093e \u0935\u0930\u094d\u0923\u0928 \u092a\u094c\u0932\u0941\u0938 \u0928\u0947 \u0907\u0928 \u091b\u0902\u0926\u094b\u0902 \u092e\u0947\u0902 \u0915\u093f\u092f\u093e \u0939\u0948\u0964\n\u0939\u092e \u0915\u093f\u0938\u0940 \u0915\u093e \u0939\u0943\u0926\u092f \u0928\u0939\u0940\u0902 \u092c\u0926\u0932 \u0938\u0915\u0924\u0947\u0964\n\u0932\u0947\u0915\u093f\u0928 \u0939\u092e \u0909\u0928\u094d\u0939\u0947\u0902 \u0938\u091a\u094d\u091a\u093e\u0908 \u0935\u093f\u0928\u092e\u094d\u0930\u0924\u093e, \u0926\u092f\u093e\u0932\u0941\u0924\u093e \u0914\u0930 \u0927\u0948\u0930\u094d\u092f \u0938\u0947 \u092c\u0924\u093e \u0938\u0915\u0924\u0947 \u0939\u0948\u0902\u0964\n\u0914\u0930 \u0939\u092e \u092d\u0930\u094b\u0938\u093e \u0930\u0916 \u0938\u0915\u0924\u0947 \u0939\u0948\u0902 \u0915\u093f \u0908\u0936\u094d\u0935\u0930 \u0905\u092a\u0928\u0947 \u091a\u0941\u0928\u0947 \u0939\u0941\u090f \u092c\u091a\u094d\u091a\u094b\u0902 \u0915\u094b \u0938\u0939\u0940 \u0938\u092e\u092f \u092a\u0930 \u092a\u0936\u094d\u091a\u093e\u0924\u093e\u092a \u0915\u0930\u0928\u0947 \u0915\u093e \u0905\u0935\u0938\u0930 \u092a\u094d\u0930\u0926\u093e\u0928 \u0915\u0930\u0947\u0917\u093e\u0964\n\u0906\u091c \u0915\u0947 \u092a\u093e\u0920 \u0915\u0947 \u092a\u0926 24 \u0914\u0930 25 \u092e\u0947\u0902 \u092e\u0941\u091d\u0947 \u0935\u0947 \u092a\u093e\u0901\u091a \u0917\u0941\u0923 \u0926\u093f\u0916\u093e\u0908 \u0926\u0947\u0924\u0947 \u0939\u0948\u0902 \u091c\u093f\u0928\u094d\u0939\u0947\u0902 \u092a\u0930\u092e\u0947\u0936\u094d\u0935\u0930 \u0905\u092a\u0928\u0947 \u0938\u0947\u0935\u0915\u094b\u0902 \u092e\u0947\u0902 \u0935\u093f\u0915\u0938\u093f\u0924 \u0915\u0930\u0928\u093e \u091a\u093e\u0939\u0924\u093e \u0939\u0948:\n\n\u0917\u0941\u0923 1: \u091d\u0917\u0921\u093c\u093e\u0932\u0942 \u0928\u0939\u0940\u0902\u0964\n\u0915\u0941\u091b \u0932\u094b\u0917\u094b\u0902 \u0915\u094b \u092c\u0939\u0938 \u0915\u0930\u0928\u093e \u092a\u0938\u0902\u0926 \u0939\u094b\u0924\u093e \u0939\u0948\u0964\n\u0938\u094d\u0935\u0938\u094d\u0925 \u092c\u0939\u0938 \u092e\u0947\u0902 \u0915\u0941\u091b \u092d\u0940 \u0917\u0932\u0924 \u0928\u0939\u0940\u0902 \u0939\u0948\u0964\n\u0932\u0947\u0915\u093f\u0928 \u0906\u092a\u0915\u094b \u0915\u0948\u0938\u0947 \u092a\u0924\u093e \u091a\u0932\u0947\u0917\u093e \u0915\u093f \u0906\u092a \u0915\u092c \u091c\u093e\u0928\u092c\u0942\u091d\u0915\u0930 \u201d\u091d\u0917\u0921\u093c\u093e\u0932\u0942\u201d \u0935\u094d\u092f\u0935\u0939\u093e\u0930 \u0915\u0930 \u0930\u0939\u0947 \u0939\u0948\u0902?\n\u0936\u093e\u092f\u0926 \u0906\u092a \u0916\u0941\u0926 \u0938\u0947 \u092f\u0939 \u0938\u0935\u093e\u0932 \u092a\u0942\u091b \u0938\u0915\u0924\u0947 \u0939\u0948\u0902:\n\u201d\u091c\u092c \u092e\u0948\u0902 \u0915\u093f\u0938\u0940 \u0938\u0947 \u092c\u0939\u0938 \u0915\u0930 \u0930\u0939\u093e \u0939\u094b\u0924\u093e \u0939\u0942\u0902, \u0924\u094b \u0915\u094d\u092f\u093e \u092e\u0941\u091d\u0947 \u0909\u0938 \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u0915\u0940 \u091c\u094d\u092f\u093e\u0926\u093e \u092a\u0930\u0935\u093e\u0939 \u0939\u094b\u0924\u0940 \u0939\u0948, \u092f\u093e \u092c\u0939\u0938 \u091c\u0940\u0924\u0928\u0947 \u0915\u0940?\u201d\n\u0915\u094d\u092f\u093e \u092e\u0947\u0930\u093e \u0905\u0939\u0902\u0915\u093e\u0930 \u092e\u0941\u091d\u0947 \u0926\u092f\u093e\u0932\u0941 \u0939\u094b\u0928\u0947 \u0915\u0947 \u092c\u091c\u093e\u092f \u0938\u0939\u0940 \u0939\u094b\u0928\u0947 \u092a\u0930 \u0927\u094d\u092f\u093e\u0928 \u0915\u0947\u0902\u0926\u094d\u0930\u093f\u0924 \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u092a\u094d\u0930\u0947\u0930\u093f\u0924 \u0915\u0930 \u0930\u0939\u093e \u0939\u0948?\n\n\u0917\u0941\u0923 2: \u0938\u092d\u0940 \u0915\u0947 \u092a\u094d\u0930\u0924\u093f \u0926\u092f\u093e\u0932\u0941 \u0939\u094b\u0928\u093e\u0964\n\u0908\u0936\u094d\u0935\u0930 \u0915\u0947 \u0938\u0947\u0935\u0915 \u0915\u094b \u0938\u092d\u0940 \u0915\u0947 \u092a\u094d\u0930\u0924\u093f \u0926\u092f\u093e\u0932\u0941 \u0939\u094b\u0928\u093e \u091a\u093e\u0939\u093f\u090f\u0964\n\u092f\u0939\u093e\u0902 \u0924\u0915 \u200b\u200b\u0915\u093f \u0909\u0928 \u0932\u094b\u0917\u094b\u0902 \u0915\u0947 \u0932\u093f\u090f \u092d\u0940 \u091c\u094b \u0906\u092a\u0938\u0947 \u0928\u092b\u0930\u0924 \u0915\u0930\u0924\u0947 \u0939\u0948\u0902 \u0914\u0930 \u0906\u092a\u0915\u094b \u0928\u0941\u0915\u0938\u093e\u0928 \u092a\u0939\u0941\u0902\u091a\u093e\u0928\u093e \u091a\u093e\u0939\u0924\u0947 \u0939\u0948\u0902\u0964\n\u092e\u0941\u091d\u0947 \u092a\u0924\u093e \u0939\u0948, \u092f\u0939 \u092e\u0941\u0936\u094d\u0915\u093f\u0932 \u0939\u0948\u0964\n\u0939\u092e \u0938\u094b\u091a\u0924\u0947 \u0939\u0948\u0902 \u0915\u093f \u0926\u0942\u0938\u0930\u094b\u0902 \u0938\u0947 \u0916\u0941\u0926 \u0915\u094b \u092c\u091a\u093e\u0928\u0947 \u0915\u093e \u0924\u0930\u0940\u0915\u093e \u092e\u091c\u092c\u0942\u0924 \u0939\u094b\u0928\u093e, \u0936\u0915\u094d\u0924\u093f \u0915\u093e \u0909\u092a\u092f\u094b\u0917 \u0915\u0930\u0928\u093e \u0939\u0948\u0964\n\u0932\u0947\u0915\u093f\u0928 \u0930\u094b\u092e\u093f\u092f\u094b\u0902 2:4 \u092e\u0947\u0902 \u092a\u094c\u0932\u0941\u0938 \u0939\u092e\u0947\u0902 \u091c\u094b \u092f\u093e\u0926 \u0926\u093f\u0932\u093e\u0924\u093e \u0939\u0948, \u0909\u0938 \u092a\u0930 \u0927\u094d\u092f\u093e\u0928 \u0926\u0947\u0902:\n\u0908\u0936\u094d\u0935\u0930 \u0915\u0940 \u0915\u0943\u092a\u093e \u0915\u093e \u0909\u0926\u094d\u0926\u0947\u0936\u094d\u092f \u0906\u092a\u0915\u094b \u092a\u0936\u094d\u091a\u093e\u0924\u093e\u092a \u0915\u0940 \u0913\u0930 \u0932\u0947 \u091c\u093e\u0928\u093e \u0939\u0948\u0964\n\u091c\u092c \u0906\u092a \u092a\u093e\u092a \u092e\u0947\u0902 \u0921\u0942\u092c\u0947 \u0939\u0941\u090f \u0925\u0947 \u0914\u0930 \u092f\u0940\u0936\u0941 \u0938\u0947 \u0926\u0942\u0930 \u092d\u093e\u0917 \u0930\u0939\u0947 \u0925\u0947, \u0924\u092c \u092f\u0940\u0936\u0941 \u0928\u0947 \u0906\u092a\u0915\u0947 \u092a\u094d\u0930\u0924\u093f \u0915\u093f\u0924\u0928\u0940 \u0926\u092f\u093e\u0932\u0941\u0924\u093e \u0926\u093f\u0916\u093e\u0908?\n\u0909\u0928\u0915\u0940 \u0926\u092f\u093e\u0932\u0941\u0924\u093e \u0928\u0947 \u0906\u092a\u0915\u094b \u092a\u0936\u094d\u091a\u093e\u0924\u093e\u092a \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u092a\u094d\u0930\u0947\u0930\u093f\u0924 \u0915\u093f\u092f\u093e\u0964\n\u0924\u094b \u0905\u092c \u0906\u092a\u0915\u0947 \u092a\u093e\u0938 \u092e\u0938\u0940\u0939 \u0915\u093e \u0905\u0928\u0941\u0915\u0930\u0923 \u0915\u0930\u0928\u0947 \u0914\u0930 \u0938\u092d\u0940 \u0915\u0947 \u092a\u094d\u0930\u0924\u093f \u0926\u092f\u093e\u0932\u0941 \u0939\u094b\u0928\u0947 \u0915\u093e \u0905\u0935\u0938\u0930 \u0939\u0948\u0964\n\n\u0917\u0941\u0923 3: \u092c\u0941\u0930\u093e\u0908 \u0915\u094b \u0927\u0948\u0930\u094d\u092f\u092a\u0942\u0930\u094d\u0935\u0915 \u0938\u0939\u0928 \u0915\u0930\u0928\u093e\u0964\n\u091c\u092c \u0939\u092e \u0938\u0941\u0938\u092e\u093e\u091a\u093e\u0930 \u0915\u0940 \u0938\u091a\u094d\u091a\u093e\u0908 \u0938\u093e\u091d\u093e \u0915\u0930 \u0930\u0939\u0947 \u0939\u094b\u0924\u0947 \u0939\u0948\u0902, \u0924\u094b \u0939\u092e\u0947\u0902 \u0909\u0928 \u0932\u094b\u0917\u094b\u0902 \u0915\u0947 \u0935\u093f\u0930\u094b\u0927 \u0915\u093e \u0938\u093e\u092e\u0928\u093e \u0915\u0930\u0928\u093e \u092a\u0921\u093c\u0947\u0917\u093e \u091c\u093f\u0928\u094d\u0939\u0947\u0902 \u0939\u092e\u093e\u0930\u0940 \u092c\u093e\u0924\u0947\u0902 \u092a\u0938\u0902\u0926 \u0928\u0939\u0940\u0902 \u0906\u0924\u0940\u0902\u0964\n\u0915\u094d\u092f\u093e \u0906\u092a\u0915\u094b \u092f\u093e\u0926 \u0939\u0948 \u0915\u093f \u0938\u094d\u091f\u0940\u092b\u0928 \u0928\u0947 \u0909\u0938\u0947 \u092e\u093e\u0930\u0928\u0947 \u0935\u093e\u0932\u094b\u0902 \u0915\u094b \u0915\u094d\u092f\u093e \u091c\u0935\u093e\u092c \u0926\u093f\u092f\u093e \u0925\u093e?\n\u092a\u094d\u0930\u0947\u0930\u093f\u0924\u094b\u0902 \u0915\u0947 \u0915\u093e\u092e 7:59-60 \u092e\u0947\u0902 \u0932\u093f\u0916\u093e \u0939\u0948:\n59 \u091c\u092c \u0935\u0947 \u0909\u0938\u0947 \u092a\u0924\u094d\u0925\u0930 \u092e\u093e\u0930 \u0930\u0939\u0947 \u0925\u0947, \u0924\u092c \u0938\u094d\u091f\u0940\u092b\u0928 \u0928\u0947 \u092a\u094d\u0930\u093e\u0930\u094d\u0925\u0928\u093e \u0915\u0940, \u201c\u092a\u094d\u0930\u092d\u0941 \u092f\u0940\u0936\u0941, \u092e\u0947\u0930\u0940 \u0906\u0924\u094d\u092e\u093e \u0915\u094b \u0917\u094d\u0930\u0939\u0923 \u0915\u0930\u094b\u0964\u201d\n60 \u0924\u092c \u0935\u0939 \u0918\u0941\u091f\u0928\u094b\u0902 \u0915\u0947 \u092c\u0932 \u0917\u093f\u0930 \u092a\u0921\u093c\u093e \u0914\u0930 \u091a\u093f\u0932\u094d\u0932\u093e\u0915\u0930 \u092c\u094b\u0932\u093e, \u201c\u0939\u0947 \u092a\u094d\u0930\u092d\u0941, \u0907\u0938 \u092a\u093e\u092a \u0915\u0947 \u0932\u093f\u090f \u0909\u0928\u094d\u0939\u0947\u0902 \u0926\u094b\u0937\u0940 \u0928 \u0920\u0939\u0930\u093e\u0928\u093e\u0964\u201d\n\n\u0915\u0947\u0935\u0932 \u0908\u0936\u094d\u0935\u0930 \u0939\u0940 \u0939\u092e\u0947\u0902 \u0938\u094d\u091f\u0940\u092b\u0928 \u0915\u0940 \u0924\u0930\u0939 \u0927\u0948\u0930\u094d\u092f\u092a\u0942\u0930\u094d\u0935\u0915 \u092c\u0941\u0930\u093e\u0908 \u0915\u094b \u0938\u0939\u0928\u0947 \u092e\u0947\u0902 \u092e\u0926\u0926 \u0915\u0930 \u0938\u0915\u0924\u093e \u0939\u0948\u0964\n\u0932\u0947\u0915\u093f\u0928 \u091c\u092c \u0939\u092e \u0938\u0902\u0915\u091f \u0915\u0947 \u0938\u092e\u092f \u0909\u0938\u0938\u0947 \u092e\u0926\u0926 \u092e\u093e\u0902\u0917\u0947\u0902\u0917\u0947, \u0924\u094b \u0935\u0939 \u0939\u092e\u093e\u0930\u0940 \u092e\u0926\u0926 \u0915\u0930\u0947\u0917\u093e\u0964\n\u0935\u0939 \u0939\u092e\u0947\u0902 \u0909\u0938 \u092a\u0930 \u092d\u0930\u094b\u0938\u093e \u0915\u0930\u0928\u0947 \u092e\u0947\u0902 \u092e\u0926\u0926 \u0915\u0930\u0947\u0917\u093e, \u092f\u0939 \u091c\u093e\u0928\u0924\u0947 \u0939\u0941\u090f \u0915\u093f \u0939\u092e\u093e\u0930\u0940 \u0906\u0924\u094d\u092e\u093e\u090f\u0902 \u0909\u0938\u0915\u0947 \u0939\u093e\u0925\u094b\u0902 \u092e\u0947\u0902 \u0938\u0941\u0930\u0915\u094d\u0937\u093f\u0924 \u0939\u0948\u0902, \u091a\u093e\u0939\u0947 \u0939\u092e\u093e\u0930\u0947 \u0936\u0930\u0940\u0930 \u0915\u0947 \u0938\u093e\u0925 \u0915\u0941\u091b \u092d\u0940 \u0939\u094b \u091c\u093e\u090f\u0964\n\n\u0917\u0941\u0923 4: \u0915\u094b\u092e\u0932\u0924\u093e \u0938\u0947 \u0938\u0941\u0927\u093e\u0930 \u0915\u0930\u0928\u093e\u0964\n\u0932\u094b\u0917\u094b\u0902 \u0915\u094b \u0938\u0941\u0927\u093e\u0930\u0928\u093e \u0915\u0920\u093f\u0928 \u0939\u0948\u0964\n\u0932\u0947\u0915\u093f\u0928 \u0905\u0917\u0930 \u092e\u0947\u0930\u093e \u092c\u0947\u091f\u093e \u0915\u0941\u091b \u0917\u0932\u0924 \u0915\u0930 \u0930\u0939\u093e \u0939\u094b\u0924\u093e \u0939\u0948, \u0924\u094b \u092e\u0948\u0902 \u0909\u0938\u0947 \u092c\u0924\u093e\u0924\u093e \u0939\u0942\u0901 \u0915\u094d\u092f\u094b\u0902\u0915\u093f \u092e\u0948\u0902 \u0909\u0938\u0938\u0947 \u092a\u094d\u092f\u093e\u0930 \u0915\u0930\u0924\u093e \u0939\u0942\u0901\u0964\n\u0915\u093f\u0938\u0940 \u0915\u094b \u0938\u0941\u0927\u093e\u0930\u0928\u0947 \u0915\u0947 \u0938\u092e\u092f \u0906\u092a\u0915\u094b \u0928\u093f\u092e\u094d\u0928\u0932\u093f\u0916\u093f\u0924 \u092e\u0939\u0924\u094d\u0935\u092a\u0942\u0930\u094d\u0923 \u092a\u094d\u0930\u0936\u094d\u0928 \u092a\u0930 \u0935\u093f\u091a\u093e\u0930 \u0915\u0930\u0928\u093e \u091a\u093e\u0939\u093f\u090f:\n\u0915\u094d\u092f\u093e \u092e\u0947\u0930\u0947 \u092c\u091a\u094d\u091a\u0947, \u0926\u094b\u0938\u094d\u0924 \u092f\u093e \u091c\u0940\u0935\u0928\u0938\u093e\u0925\u0940 \u0915\u094b \u092e\u0947\u0930\u093e \u092a\u094d\u092f\u093e\u0930 \u092e\u0939\u0938\u0942\u0938 \u0939\u094b\u0924\u093e \u0939\u0948?\n\u092f\u093e \u092b\u093f\u0930 \u0909\u0928\u094d\u0939\u0947\u0902 \u0938\u093f\u0930\u094d\u092b \u092e\u0947\u0930\u093e \u0917\u0941\u0938\u094d\u0938\u093e \u0939\u0940 \u092e\u0939\u0938\u0942\u0938 \u0939\u094b\u0924\u093e \u0939\u0948?\n\n\u091c\u092c \u0939\u092e \u0915\u094d\u0930\u094b\u0927 \u092f\u093e \u0915\u0941\u0902\u0920\u093e \u0938\u0947 \u0938\u0941\u0927\u093e\u0930 \u0915\u0930\u0924\u0947 \u0939\u0948\u0902, \u0924\u094b \u0939\u092e \u0910\u0938\u093e \u0935\u094d\u092f\u0935\u0939\u093e\u0930 \u0915\u0930 \u0930\u0939\u0947 \u0939\u094b\u0924\u0947 \u0939\u0948\u0902 \u092e\u093e\u0928\u094b \u092d\u0917\u0935\u093e\u0928 \u0926\u0942\u0938\u0930\u0947 \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u0915\u094b \u092c\u0926\u0932 \u0928\u0939\u0940\u0902 \u0938\u0915\u0924\u0947\u0964\n\u0939\u092e\u0947\u0902 \u0932\u0917\u0924\u093e \u0939\u0948 \u0915\u093f \u0939\u092e \u0909\u0928 \u092a\u0930 \u0926\u092c\u093e\u0935 \u0921\u093e\u0932\u0915\u0930 \u0909\u0928\u094d\u0939\u0947\u0902 \u092c\u0926\u0932 \u0938\u0915\u0924\u0947 \u0939\u0948\u0902, \u092f\u093e \u0924\u092c \u0924\u0915 \u091c\u094b\u0930 \u0938\u0947 \u091a\u093f\u0932\u094d\u0932\u093e \u0938\u0915\u0924\u0947 \u0939\u0948\u0902 \u091c\u092c \u0924\u0915 \u0935\u0947 \u0938\u0939\u0940 \u0930\u093e\u0938\u094d\u0924\u0947 \u092a\u0930 \u0928 \u0906 \u091c\u093e\u090f\u0902\u0964\n\u0932\u0947\u0915\u093f\u0928 \u091c\u094b \u0936\u093f\u0915\u094d\u0937\u0915 \u092f\u0939 \u091c\u093e\u0928\u0924\u093e \u0939\u0948 \u0915\u093f \u0905\u0938\u0932\u0940 \u0936\u0915\u094d\u0924\u093f \u0908\u0936\u094d\u0935\u0930 \u0915\u0947 \u092a\u093e\u0938 \u0939\u0948, \u0935\u0939 \u0915\u094b\u092e\u0932, \u0927\u0948\u0930\u094d\u092f\u0935\u093e\u0928 \u0914\u0930 \u0926\u092f\u093e\u0932\u0941 \u0939\u094b\u0917\u093e\u0964\n\n\u0917\u0941\u0923 5: \u092a\u0922\u093c\u093e\u0928\u0947 \u092e\u0947\u0902 \u0938\u0915\u094d\u0937\u092e\u0964\n\u0915\u094d\u092f\u093e \u0906\u092a \u092a\u0930\u092e\u0947\u0936\u094d\u0935\u0930 \u0915\u0947 \u0935\u091a\u0928 \u0915\u094b \u0907\u0924\u0928\u0940 \u0905\u091a\u094d\u091b\u0940 \u0924\u0930\u0939 \u0938\u092e\u091d\u0924\u0947 \u0939\u0948\u0902 \u0915\u093f \u0906\u092a \u0907\u0938\u0947 \u0926\u0942\u0938\u0930\u094b\u0902 \u0915\u094b \u0938\u092e\u091d\u093e \u0938\u0915\u0947\u0902?\n\u0915\u094d\u092f\u093e \u0906\u092a \u0927\u0930\u094d\u092e\u0917\u094d\u0930\u0902\u0925\u094b\u0902 \u0915\u094b \u092f\u093e\u0926 \u0915\u0930 \u0930\u0939\u0947 \u0939\u0948\u0902, \u0924\u093e\u0915\u093f \u0935\u0947 \u0906\u092a\u0915\u0947 \u091c\u0940\u0935\u0928 \u092e\u0947\u0902 \u092e\u093e\u0930\u094d\u0917\u0926\u0930\u094d\u0936\u0928 \u0915\u0930 \u0938\u0915\u0947\u0902 \u0914\u0930 \u0906\u092a \u0909\u0928\u094d\u0939\u0947\u0902 \u0926\u0942\u0938\u0930\u094b\u0902 \u0915\u0947 \u0938\u093e\u0925 \u0938\u093e\u091d\u093e \u0915\u0930 \u0938\u0915\u0947\u0902?\n\u0939\u092e \u0907\u0938 \u092e\u0939\u0940\u0928\u0947 \u0915\u0941\u091b \u0928\u092f\u093e \u0936\u0941\u0930\u0942 \u0915\u0930\u0928\u0947 \u091c\u093e \u0930\u0939\u0947 \u0939\u0948\u0902\u0964\n\u0939\u092e \u0906\u092a\u0938\u0947 \u092e\u093e\u0930\u094d\u091a \u0915\u0947 \u0905\u0902\u0924 \u0924\u0915 \u092c\u093e\u0907\u092c\u0932 \u0915\u093e \u090f\u0915 \u0936\u094d\u0932\u094b\u0915 \u092f\u093e\u0926 \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0915\u0939\u0947\u0902\u0917\u0947\u0964\n\u0914\u0930 \u0905\u0917\u0930 \u0906\u092a \u0907\u0938\u0947 \u0939\u092e\u093e\u0930\u0947 \u0915\u093f\u0938\u0940 \u0928\u0947\u0924\u093e \u0915\u094b \u0915\u093f\u0938\u0940 \u092d\u0940 \u092d\u093e\u0937\u093e \u092e\u0947\u0902 \u0938\u0941\u0928\u093e \u0938\u0915\u0924\u0947 \u0939\u0948\u0902, \u0924\u094b \u0906\u092a\u0915\u094b \u090f\u0915 \u0938\u094d\u091f\u093f\u0915\u0930 \u092e\u093f\u0932\u0947\u0917\u093e\u0964\n\u0906\u092a \u0907\u0938\u0947 \u0905\u092a\u0928\u0940 \u092a\u093e\u0928\u0940 \u0915\u0940 \u092c\u094b\u0924\u0932 \u092f\u093e \u0928\u094b\u091f\u092c\u0941\u0915 \u092a\u0930 \u0932\u0917\u093e \u0938\u0915\u0924\u0947 \u0939\u0948\u0902\u0964\n\u0906\u092a \u0907\u0938\u0947 \u0915\u0939\u0940\u0902 \u092d\u0940 \u0926\u0947\u0916 \u0938\u0915\u0924\u0947 \u0939\u0948\u0902 \u0914\u0930 \u092a\u0942\u0930\u0947 \u0938\u093e\u0932 \u0907\u0938\u0915\u093e \u0905\u092d\u094d\u092f\u093e\u0938 \u0915\u0930\u0924\u0947 \u0930\u0939 \u0938\u0915\u0924\u0947 \u0939\u0948\u0902\u0964\n\u0906\u0907\u090f \u092e\u093e\u0930\u094d\u091a \u092e\u0939\u0940\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0928\u093f\u0930\u094d\u0927\u093e\u0930\u093f\u0924 \u0935\u091a\u0928, 2 \u0924\u0940\u092e\u0941\u0925\u093f\u092f\u0941\u0938 3:16 \u0915\u094b \u090f\u0915 \u0938\u093e\u0925 \u092a\u0922\u093c\u0947\u0902\u0964\n\u0938\u092d\u0940: \u201c\u0938\u0902\u092a\u0942\u0930\u094d\u0923 \u092a\u0935\u093f\u0924\u094d\u0930\u0936\u093e\u0938\u094d\u0924\u094d\u0930 \u0908\u0936\u094d\u0935\u0930 \u0915\u0940 \u092a\u094d\u0930\u0947\u0930\u0923\u093e \u0938\u0947 \u0932\u093f\u0916\u093e \u0917\u092f\u093e \u0939\u0948 \u0914\u0930 \u092f\u0939 \u0936\u093f\u0915\u094d\u0937\u093e \u0926\u0947\u0928\u0947, \u092b\u091f\u0915\u093e\u0930\u0928\u0947, \u0938\u0941\u0927\u093e\u0930\u0928\u0947 \u0914\u0930 \u0927\u093e\u0930\u094d\u092e\u093f\u0915\u0924\u093e \u092e\u0947\u0902 \u092a\u094d\u0930\u0936\u093f\u0915\u094d\u0937\u0923 \u0926\u0947\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0909\u092a\u092f\u094b\u0917\u0940 \u0939\u0948\u0964\u201d\n\n\u0938\u0939\u0940 \u0926\u093f\u0936\u093e \u092e\u0947\u0902 \u0906\u0917\u0947 \u092c\u0922\u093c\u0924\u0947 \u0930\u0939\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0939\u092e \u0938\u092d\u0940 \u0915\u094b \u092e\u0926\u0926 \u0915\u0940 \u091c\u0930\u0942\u0930\u0924 \u0939\u0948\u0964\n\u0939\u092e\u0947\u0902 \u092a\u0930\u092e\u0947\u0936\u094d\u0935\u0930 \u0915\u0947 \u0935\u091a\u0928 \u0915\u0940 \u0906\u0935\u0936\u094d\u092f\u0915\u0924\u093e \u0939\u0948 \u091c\u094b \u0939\u092e\u0947\u0902 \u0938\u093f\u0916\u093e\u090f, \u0939\u092e\u093e\u0930\u0940 \u0917\u0932\u0924\u093f\u092f\u094b\u0902 \u0915\u094b \u0938\u0941\u0927\u093e\u0930\u0947 \u0914\u0930 \u0939\u092e\u0947\u0902 \u0927\u093e\u0930\u094d\u092e\u093f\u0915\u0924\u093e \u0915\u0947 \u092e\u093e\u0930\u094d\u0917 \u092a\u0930 \u091a\u0932\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u092a\u094d\u0930\u0936\u093f\u0915\u094d\u0937\u093f\u0924 \u0915\u0930\u0947\u0964\n\u0914\u0930 \u0939\u092e\u0947\u0902 \u092a\u0935\u093f\u0924\u094d\u0930 \u0906\u0924\u094d\u092e\u093e \u0915\u0940 \u0906\u0935\u0936\u094d\u092f\u0915\u0924\u093e \u0939\u0948 \u0924\u093e\u0915\u093f \u0935\u0939 \u0939\u092e\u0947\u0902 \u0935\u091a\u0928 \u0915\u094b \u0938\u092e\u091d\u0928\u0947 \u0914\u0930 \u0909\u0938 \u092a\u0930 \u0905\u092e\u0932 \u0915\u0930\u0928\u0947 \u092e\u0947\u0902 \u092e\u0926\u0926 \u0915\u0930\u0947, \u0907\u0938\u0932\u093f\u090f \u0906\u0907\u090f \u0905\u092c \u0939\u092e \u092a\u094d\u0930\u093e\u0930\u094d\u0925\u0928\u093e \u092e\u0947\u0902 \u0905\u092a\u0928\u093e \u0939\u0943\u0926\u092f \u0938\u094d\u0935\u0930\u094d\u0917 \u0915\u0940 \u0913\u0930 \u092e\u094b\u0921\u093c\u0947\u0902\u0964\n\u0939\u0947 \u092f\u0940\u0936\u0941, \u0939\u092e \u092a\u093f\u0924\u093e \u0938\u0947 \u0915\u0947\u0935\u0932 \u0907\u0938\u0932\u093f\u090f \u092c\u093e\u0924 \u0915\u0930 \u0938\u0915\u0924\u0947 \u0939\u0948\u0902 \u0915\u094d\u092f\u094b\u0902\u0915\u093f \u0906\u092a\u0928\u0947 \u092a\u0943\u0925\u094d\u0935\u0940 \u0914\u0930 \u0938\u094d\u0935\u0930\u094d\u0917 \u0915\u0947 \u092c\u0940\u091a \u090f\u0915 \u0938\u0947\u0924\u0941 \u092c\u0928\u093e\u092f\u093e \u0939\u0948\u0964\n\u0906\u092a\u0928\u0947 \u0936\u0948\u0924\u093e\u0928 \u0915\u0947 \u091c\u093e\u0932 \u0915\u094b \u0928\u0937\u094d\u091f \u0915\u0930 \u0926\u093f\u092f\u093e \u0914\u0930 \u0938\u0924\u094d\u092f \u0915\u0947 \u092a\u094d\u0930\u0924\u093f \u0939\u092e\u093e\u0930\u0940 \u0906\u0902\u0916\u0947\u0902 \u0916\u094b\u0932 \u0926\u0940\u0902\u0964\n\u0939\u0947 \u092a\u093f\u0924\u093e, \u0939\u092e\u0947\u0902 \u092a\u0936\u094d\u091a\u093e\u0924\u093e\u092a \u0915\u093e \u0909\u092a\u0939\u093e\u0930 \u0926\u0947\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0927\u0928\u094d\u092f\u0935\u093e\u0926, \u0924\u093e\u0915\u093f \u0939\u092e \u0905\u092a\u0928\u0947 \u092a\u093e\u092a\u094b\u0902 \u0915\u0947 \u092c\u093e\u0930\u0947 \u092e\u0947\u0902 \u0938\u094d\u0935\u092f\u0902 \u0938\u0947 \u0914\u0930 \u0906\u092a\u0938\u0947 \u0908\u092e\u093e\u0928\u0926\u093e\u0930 \u0939\u094b \u0938\u0915\u0947\u0902\u0964\n\u0914\u0930 \u0939\u0947 \u092a\u0935\u093f\u0924\u094d\u0930 \u0906\u0924\u094d\u092e\u093e, \u0939\u092e\u0947\u0902 \u092f\u0940\u0936\u0941 \u0915\u0940 \u0936\u0930\u0923 \u092e\u0947\u0902 \u0909\u0926\u094d\u0927\u093e\u0930 \u0915\u0947 \u0932\u093f\u090f \u0935\u093f\u0936\u094d\u0935\u093e\u0938 \u0926\u0947\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0906\u092a\u0915\u093e \u0927\u0928\u094d\u092f\u0935\u093e\u0926\u0964\n\u0939\u092e\u0947\u0902 \u0905\u092a\u0928\u0947 \u092e\u0928 \u0914\u0930 \u0939\u0943\u0926\u092f \u0915\u094b \u0916\u094b\u0932\u0928\u093e \u091a\u093e\u0939\u093f\u090f \u0924\u093e\u0915\u093f \u0939\u092e \u092a\u0930\u092e\u0947\u0936\u094d\u0935\u0930 \u0915\u0947 \u0935\u091a\u0928 \u0915\u094b \u0938\u092e\u091d \u0938\u0915\u0947\u0902 \u0914\u0930 \u0909\u0938\u0947 \u0905\u092a\u0928\u0947 \u091c\u0940\u0935\u0928 \u092e\u0947\u0902 \u0932\u093e\u0917\u0942 \u0915\u0930 \u0938\u0915\u0947\u0902\u0964\n\u0939\u092e\u0947\u0902 \u0907\u0938 \u0926\u094c\u0921\u093c \u092e\u0947\u0902 \u092a\u0942\u0930\u0940 \u0932\u0917\u0928 \u0938\u0947 \u0926\u094c\u0921\u093c\u0928\u0947 \u092e\u0947\u0902 \u092e\u0926\u0926 \u0915\u0930\u0947\u0902, \u0914\u0930 \u0926\u0942\u0938\u0930\u094b\u0902 \u0915\u094b \u092d\u0940 \u092a\u0942\u0930\u094d\u0923\u0924\u093e, \u0906\u0936\u093e \u0914\u0930 \u0938\u094d\u0935\u0930\u094d\u0917 \u0915\u0940 \u092f\u093e\u0924\u094d\u0930\u093e \u092e\u0947\u0902 \u0939\u092e\u093e\u0930\u0947 \u0938\u093e\u0925 \u0936\u093e\u092e\u093f\u0932 \u0939\u094b\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0906\u092e\u0902\u0924\u094d\u0930\u093f\u0924 \u0915\u0930\u0947\u0902, \u0906\u092e\u0940\u0928\u0964\n\n\u0927\u094d\u092f\u093e\u0928 \u0914\u0930 \u091a\u0930\u094d\u091a\u093e \u0915\u0947 \u0932\u093f\u090f \u092a\u094d\u0930\u0936\u094d\u0928\n1.  2 \u0924\u093f\u092e\u094b\u0925\u0940 2:22 \u0914\u0930 \u092d\u091c\u0928 \u0938\u0902\u0939\u093f\u0924\u093e 119:35-37 \u092a\u0922\u093c\u0947\u0902\u0964\n\u0915) \u0924\u0928\u093e\u0935\u0917\u094d\u0930\u0938\u094d\u0924 \u0939\u094b\u0928\u0947 \u092f\u093e \u0906\u0930\u093e\u092e \u0915\u0940 \u0924\u0932\u093e\u0936 \u092e\u0947\u0902 \u0906\u092a\u0915\u093e \u0926\u093f\u0932 \u0938\u094d\u0935\u093e\u092d\u093e\u0935\u093f\u0915 \u0930\u0942\u092a \u0938\u0947 \u0915\u093f\u0928 \u201d\u092f\u0941\u0935\u093e\u0935\u0938\u094d\u0925\u093e \u0915\u0940 \u092d\u093e\u0935\u0928\u093e\u0913\u0902\u201d (\u0906\u0928\u0902\u0926, \u0936\u0915\u094d\u0924\u093f, \u0932\u094b\u0915\u092a\u094d\u0930\u093f\u092f\u0924\u093e, \u0938\u0902\u092a\u0924\u094d\u0924\u093f, \u0905\u092d\u093f\u092e\u093e\u0928) \u0915\u0940 \u0913\u0930 \u0906\u0915\u0930\u094d\u0937\u093f\u0924 \u0939\u094b\u0924\u093e \u0939\u0948?\n\n2.  \u0907\u092b\u093f\u0938\u093f\u092f\u094b\u0902 2:1-5 \u0914\u0930 \u092f\u0939\u0947\u091c\u0915\u0947\u0932 36:26 \u092a\u0922\u093c\u0947\u0902\u0964\n\u0915) \u201d\u092e\u0943\u0924\u201d \u0938\u0947 \u201d\u091c\u0940\u0935\u093f\u0924\u201d \u0939\u094b\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0915\u094d\u092f\u093e \u0906\u0935\u0936\u094d\u092f\u0915 \u0939\u0948?\n\u0916) \u0915\u094d\u092f\u093e \u092f\u0939 \u092e\u093e\u0928\u0928\u093e \u200b\u200b\u0915\u093f \u092a\u0936\u094d\u091a\u093e\u0924\u093e\u092a \u0908\u0936\u094d\u0935\u0930 \u0915\u0940 \u0915\u0943\u092a\u093e \u0915\u093e \u0909\u092a\u0939\u093e\u0930 \u0939\u0948, \u0906\u092a\u0915\u094b \u0905\u092a\u0928\u0947 \u092a\u093e\u092a\u094b\u0902 \u0915\u0947 \u092c\u093e\u0930\u0947 \u092e\u0947\u0902 \u0908\u0936\u094d\u0935\u0930 \u0915\u0947 \u092a\u094d\u0930\u0924\u093f \u0905\u0927\u093f\u0915 \u0908\u092e\u093e\u0928\u0926\u093e\u0930 \u0939\u094b\u0928\u0947 \u092e\u0947\u0902 \u092e\u0926\u0926 \u0915\u0930\u0924\u093e \u0939\u0948?\n\n3.  2 \u0924\u093f\u092e\u094b\u0925\u0940 2:23-25\u0915 \u0914\u0930 \u0915\u0941\u0932\u0941\u0938\u094d\u0938\u093f\u092f\u094b\u0902 3:12-14 \u092a\u0922\u093c\u0947\u0902\u0964\n\u0915) \u0926\u0942\u0938\u0930\u094b\u0902 \u0938\u0947 \u092c\u0939\u0938 \u0915\u0930\u0924\u0947 \u092f\u093e \u0909\u0928\u094d\u0939\u0947\u0902 \u0938\u0941\u0927\u093e\u0930\u0924\u0947 \u0938\u092e\u092f \u201d\u092a\u094d\u0930\u092d\u0941 \u0915\u0947 \u0938\u0947\u0935\u0915\u201d \u0915\u0947 \u0915\u094d\u092f\u093e \u0917\u0941\u0923 \u0939\u094b\u0924\u0947 \u0939\u0948\u0902?\n\u0916) \u0915\u094d\u092f\u094b\u0902\u0915\u093f \u092f\u0940\u0936\u0941 \u0928\u0947 \u0939\u092e\u0947\u0902 \u092c\u0921\u093c\u0947 \u0927\u0940\u0930\u091c \u0914\u0930 \u0915\u094b\u092e\u0932\u0924\u093e \u0938\u0947 \u092a\u094d\u0930\u0947\u092e \u0915\u093f\u092f\u093e, \u0924\u094b \u0906\u092a \u0905\u092a\u0928\u0947 \u091c\u0940\u0935\u0928 \u092e\u0947\u0902 \u0915\u093f\u0938\u0947 \u0909\u0938\u0940 \u0915\u0943\u092a\u093e \u0938\u0947 \u092a\u094d\u0930\u0947\u092e \u0915\u0930\u0947\u0902\u0917\u0947\u2014\u092d\u0932\u0947 \u0939\u0940 \u0935\u0947 \u0906\u092a\u0938\u0947 \u0905\u0938\u0939\u092e\u0924 \u0939\u094b\u0902 \u092f\u093e \u0906\u092a\u0915\u094b \u092a\u0938\u0902\u0926 \u0928 \u0915\u0930\u0924\u0947 \u0939\u094b\u0902?\n\n4.  \u0930\u094b\u092e\u093f\u092f\u094b\u0902 10:9-11 \u0914\u0930 \u0907\u092c\u094d\u0930\u093e\u0928\u093f\u092f\u094b\u0902 12:1-2 \u092a\u0922\u093c\u0947\u0902\u0964\n\u0915) \u092f\u0940\u0936\u0941 \u092a\u0930 \u0905\u092a\u0928\u0940 \u0928\u093f\u0917\u093e\u0939\u0947\u0902 \u091f\u093f\u0915\u093e\u090f \u0930\u0916\u0928\u0947 \u0938\u0947 \u0939\u092e\u0947\u0902 \u092a\u093e\u092a \u0938\u0947 \u0926\u0942\u0930 \u0930\u0939\u0928\u0947 \u0914\u0930 \u090f\u0915 \u0928\u0908 \u0926\u093f\u0936\u093e \u092e\u0947\u0902 \u0906\u0917\u0947 \u092c\u0922\u093c\u0928\u0947 \u092e\u0947\u0902 \u0915\u0948\u0938\u0947 \u092e\u0926\u0926 \u092e\u093f\u0932\u0924\u0940 \u0939\u0948?\n\u0916) 2 \u0924\u093f\u092e\u094b\u0925\u0940 3:16 \u0915\u094b \u092f\u093e\u0926 \u0915\u0930\u0928\u093e \u0928 \u092d\u0942\u0932\u0947\u0902\u0964 \u092a\u0930\u092e\u0947\u0936\u094d\u0935\u0930 \u0915\u0947 \u0935\u091a\u0928 \u0915\u094b \u091c\u093e\u0928\u0928\u093e \u0939\u092e\u0947\u0902 \u0935\u093f\u0936\u094d\u0935\u093e\u0938 \u0915\u0940 \u092e\u0948\u0930\u093e\u0925\u0928 \u0926\u094c\u0921\u093c\u0928\u0947 \u092e\u0947\u0902 \u0915\u0948\u0938\u0947 \u092e\u0926\u0926 \u0915\u0930\u0924\u093e \u0939\u0948?","korean_content":"\uc5b4\ub514\ub97c \ub2ec\ub9ac\uace0 \uc788\ub098\uc694?\n\ub514\ubaa8\ub370\ud6c4\uc11c 2:22-26\n\ud06c\ub9ac\uc2a4 \uc2dd\uc2a4 \ubaa9\uc0ac\n2026\ub144 3\uc6d4 15\uc77c\n\n2019\ub144 \uc624\ub9ac\uac74\uc8fc \ud3ec\ud2c0\ub79c\ub4dc \ub9c8\ub77c\ud1a4\uc5d0\uc11c \ucd5c\uace0\uc758 \ub7ec\ub108\ub4e4\uc774 \uc2e4\uc81c\ub85c \ub808\uc774\uc2a4\uc5d0\uc11c \ud328\ubc30\ud588\uc2b5\ub2c8\ub2e4.\n\ub290\ub9ac\uae30 \ub54c\ubb38\uc774 \uc544\ub2c8\ub77c \uc798\ubabb\ub41c \uae38\uc744 \uac14\uae30 \ub54c\ubb38\uc785\ub2c8\ub2e4.\n\ucf54\uc2a4\uc5d0 \uba85\ud655\ud558\uac8c \ud45c\uc2dc\ub418\uc9c0 \uc54a\uc740 \ud134\uc774 \uc788\uc5c8\uc2b5\ub2c8\ub2e4.\n\uadf8\ub798\uc11c \uac00\uc7a5 \ube60\ub978 \ub7ec\ub108 \uc911 \uc57d 20\uba85\uc774 \uc798\ubabb\ub41c \ubc29\ud5a5\uc73c\ub85c 1\ub9c8\uc77c \uc774\uc0c1\uc744 \ub2ec\ub838\uc2b5\ub2c8\ub2e4!\n\uc774 \uc2e4\uc218\ub85c \uc778\ud574 \uba87 \ub2ec \ub3d9\uc548 \uc900\ube44\ud574 \uc628 \ub808\uc774\uc2a4\uc5d0 \uadc0\uc911\ud55c \uc2dc\uac04\uc774 \ucd94\uac00\ub418\uc5c8\uc2b5\ub2c8\ub2e4.\n\uadf8 \ub0a8\uc790\uc640 \uc5ec\uc790\ub294 \uc5f4\uc2ec\ud788 \ub2ec\ub838\uace0, \ube60\ub974\uac8c \ub2ec\ub838\uc2b5\ub2c8\ub2e4.\n\ud558\uc9c0\ub9cc \uadf8\ub4e4\uc740 \uc798\ubabb\ub41c \uae38\uc744 \ud0dd\ud588\uae30 \ub54c\ubb38\uc5d0 \uacbd\uc8fc\uc5d0\uc11c \ud328\ubc30\ud588\uc2b5\ub2c8\ub2e4.\n\uc624\ub298 \ubc24\uc5d0\ub294 \ub514\ubaa8\ub370\ud6c4\uc11c \uc124\uad50 \uc2dc\ub9ac\uc988\ub97c \uc774\uc5b4\uac11\ub2c8\ub2e4.\n\uc0ac\ub3c4 \ubc14\uc6b8\uc740 \uc5d0\ubca0\uc18c \uad50\ud68c\uc758 \uc80a\uc740 \ubaa9\ud68c\uc790 \ub514\ubaa8\ub370\uc5d0\uac8c \ud3b8\uc9c0\ub97c \uc4f0\uace0 \uc788\uc2b5\ub2c8\ub2e4.\n\ubc14\uc6b8\uc740 \ub514\ubaa8\ub370\uc5d0\uac8c, \uadf8\ub9ac\uace0 \uc624\ub298\ub0a0 \uc6b0\ub9ac\uc5d0\uac8c \uc62c\ubc14\ub978 \uae38\uc744 \uac00\ub294 \ubc29\ubc95\uc5d0 \ub300\ud55c \uc870\uc5b8\uc744 \uc81c\uacf5\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4.\n\ub514\ubaa8\ub370\ud6c4\uc11c 2:22-26\n22 \u201d\uadf8\ub7ec\ubbc0\ub85c \uc80a\uc740 \ub0a0\uc758 \uc815\uc695\uc744 \ud53c\ud558\uace0 \uc21c\uc218\ud55c \ub9c8\uc74c\uc73c\ub85c \uc8fc\ub2d8\uc744 \ubd80\ub974\ub294 \uc0ac\ub78c\ub4e4\uacfc \ud568\uaed8 \uc758\uc640 \ubbff\uc74c\uacfc \uc0ac\ub791\uacfc \ud3c9\ud654\ub97c \ucd94\uad6c\ud558\uc2ed\uc2dc\uc624.\n23 \uc5b4\ub9ac\uc11d\uace0 \ubb34\uc9c0\ud55c \ub17c\uc7c1\uc740 \ub2e4\ud23c\uc744 \ub0b3\ub294\ub2e4\ub294 \uac83\uc744 \uc54c\uae30 \ub54c\ubb38\uc5d0 \uc544\ubb34 \uad00\ub828\uc774 \uc5c6\uc2b5\ub2c8\ub2e4.\n24 \uc8fc\ub2d8\uc758 \uc885\uc740 \ub2e4\ud22c\uc9c0 \ub9d0\uace0 \ubaa8\ub4e0 \uc0ac\ub78c\uc5d0\uac8c \uce5c\uc808\ud558\uace0 \uac00\ub974\uce60 \uc904 \uc54c\uba70 \uc545\uc744 \ucc38\uc744 \uc904 \uc54c\uc544\uc57c \ud569\ub2c8\ub2e4,\n25 \uc0c1\ub300\ub97c \uc628\ud654\ud558\uac8c \uad50\uc815\ud569\ub2c8\ub2e4.\n\ud558\ub098\ub2d8\uaed8\uc11c \uadf8\ub4e4\uc5d0\uac8c \ud68c\uac1c\ub97c \ud5c8\ub77d\ud558\uc154\uc11c \uc9c4\ub9ac\ub97c \uae68\ub2eb\uac8c \ud558\uc2e4 \uc218\ub3c4 \uc788\uc2b5\ub2c8\ub2e4,\n26 \uadf8\ub9ac\uace0 \uadf8\ub4e4\uc740 \ub9c8\uadc0\uc5d0\uac8c \ubd99\uc7a1\ud600 \ub9c8\uadc0\uc758 \ub73b\uc744 \ud589\ud558\ub2e4\uac00 \uc815\uc2e0\uc744 \ucc28\ub9ac\uace0 \ub9c8\uadc0\uc758 \uc62c\ubb34\uc5d0\uc11c \ubc97\uc5b4\ub098\uac8c \ub420 \uac83\uc785\ub2c8\ub2e4.\u201d\n\n\uc774\uc0ac\uc57c\uc11c 40:8\uc744 \ub2e4 \uac19\uc774 \uc77d\uaca0\uc2b5\ub2c8\ub2e4. \n\u201d\ud480\uc740 \uc2dc\ub4e4\uace0 \uaf43\uc740 \uc9c0\uc9c0\ub9cc \uc6b0\ub9ac \ud558\ub098\ub2d8\uc758 \ub9d0\uc500\uc740 \uc601\uc6d0\ud788 \uc11c\ub9ac\ub77c.\u201d\n\n22\uc808\uc740 \uc774\ub807\uac8c \ub9d0\ud569\ub2c8\ub2e4:\n22 \u201d\uadf8\ub7ec\ubbc0\ub85c \uc80a\uc740 \ub0a0\uc758 \uc815\uc695\uc744 \ud53c\ud558\uace0 \uc21c\uc218\ud55c \ub9c8\uc74c\uc73c\ub85c \uc8fc\ub2d8\uc744 \ubd80\ub974\ub294 \uc0ac\ub78c\ub4e4\uacfc \ud568\uaed8 \uc758\uc640 \ubbff\uc74c\uacfc \uc0ac\ub791\uacfc \ud3c9\ud654\ub97c \ucd94\uad6c\ud558\uc2ed\uc2dc\uc624.\u201d\n\n\uc774 \uad6c\uc808\uc740 \uc0ac\uc2e4 \uc624\ub298 \uc124\uad50\ub97c \uc694\uc57d\ud55c \uac83\uc785\ub2c8\ub2e4.\n\uc6b0\ub9ac\ub294 \ud558\ub098\ub2d8\uc758 \ub9d0\uc500\uc5d0\uc11c \uc774\ub97c \uc790\uc8fc \ubcfc \uc218 \uc788\uc2b5\ub2c8\ub2e4.\n\ub54c\ub85c\ub294 \uc2dc\ud3b8\uc774\ub098 \ub2e8\ub77d\uc758 \uccab \ubb38\uc7a5\uc774 \uc694\uc57d\uc778 \uacbd\uc6b0\uac00 \uc788\uc2b5\ub2c8\ub2e4.\n\uadf8\ub7f0 \ub2e4\uc74c \uc774\uc5b4\uc9c0\ub294 \ub2e8\uc5b4\ub294 \uc2dc\ud3b8 \uc804\uccb4 \ub610\ub294 \ub2e8\ub77d\uc774\ub098 \uc7a5\uc5d0 \ub300\ud55c \uc124\uba85\uc785\ub2c8\ub2e4.\n\uc131\uc219\ud55c \uadf8\ub9ac\uc2a4\ub3c4\uc778 \ub0a8\uc131 \ub610\ub294 \uc5ec\uc131\uc740 \uc5b4\ub838\uc744 \ub54c \uc6b0\ub9ac\ub97c \uc720\ud639\ud588\ub358 \uac83\ub4e4\ub85c\ubd80\ud130 \uba40\uc5b4\uc9c0\ub294 \uc0ac\ub78c\uc785\ub2c8\ub2e4.\n\uc131\uc219\ud55c \uc0ac\ub78c\uc740 \u2018\uc80a\uc74c\uc758 \uc5f4\uc815\u2019 \ub300\uc2e0 \uc758, \ubbff\uc74c, \uc0ac\ub791, \ud3c9\ud654\ub97c \ud3ec\ud568\ud55c \ud558\ub098\ub2d8\uc758 \uac00\uce58\ub97c \ucd94\uad6c\ud558\ub294 \ubc95\uc744 \ubc30\uc6c1\ub2c8\ub2e4.\n\ubc14\uc6b8\uc740 \uc80a\uc740 \uc2dc\uc808 \uc0ac\uc6b8\uc774\ub77c\ub294 \uc774\ub984\uc744 \uac00\uc84c\uc2b5\ub2c8\ub2e4.\n\uc0ac\uc6b8\uc740 \uad50\ub9cc\uacfc \uc790\uc2e0\uac10\uc73c\ub85c \uac00\ub4dd \ucc28\uc11c \uad8c\ub825\uc744 \uc774\uc6a9\ud574 \uae30\ub3c5\uad50\uc778\ub4e4\uc744 \ud54d\ubc15\ud558\uace0 \uac10\uc625\uc5d0 \uac00\ub450\uc5c8\uc2b5\ub2c8\ub2e4.\n\uc0ac\uc6b8\uc740 \uc778\uae30\uc640 \uc131\uacf5\uc744 \uc6d0\ud588\uace0 \uc790\uc2e0\uc758 \uc790\uc874\uc2ec \ub54c\ubb38\uc5d0 \ub2e4\ub978 \uc0ac\ub78c\uc5d0\uac8c \uc0c1\ucc98\ub97c \uc8fc\ub824\uace0 \ud588\uc2b5\ub2c8\ub2e4.\n\ud558\uc9c0\ub9cc \ub514\ubaa8\ub370\ud6c4\uc11c\ub294 \uc131\uc219\ud55c \uc2e0\uc790 \ubc14\uc6b8\uc774 \uc4f4 \ud3b8\uc9c0\uc785\ub2c8\ub2e4.\n\uadf8\ub294 \uc80a\uc740 \uc2dc\uc808\uc758 \uc5f4\uc815\uc774 \uc5bc\ub9c8\ub098 \ud070 \ud53c\ud574\ub97c \uc785\ud614\ub294\uc9c0 \uc798 \uc54c\uace0 \uc788\uc73c\uba70 \ud2f0\ubaa8\uc2dc\uc5d0\uac8c \uacbd\uace0\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4.\n\ubc14\uc6b8\uc774 \uc774 \ud3b8\uc9c0\ub97c \uc4f8 \ub2f9\uc2dc \ub514\ubaa8\ub370\uc758 \ub098\uc774\ub294 40\uc138 \uc815\ub3c4\uc600\uc744 \uac83\uc785\ub2c8\ub2e4.\n\ud558\uc9c0\ub9cc \u201d\uc80a\uc74c\uc758 \uc5f4\uc815\u201d\uc744 \ud5a5\ud574 \ub2ec\ub824\uac00\uae30 \uc704\ud574 \ubc18\ub4dc\uc2dc \uc80a\uc744 \ud544\uc694\ub294 \uc5c6\uc2b5\ub2c8\ub2e4.\n\uc800\ub294 57\uc0b4\uc774\uc9c0\ub9cc \uc5ec\uc804\ud788 \uc80a\uc74c\uc758 \uc5f4\uc815\uc744 \uc783\uc9c0 \uc54a\ub294 \ubc95\uc744 \ubc30\uc6b0\uace0 \uc788\uc2b5\ub2c8\ub2e4.\n\uc800\uc640 \ub3d9\uac11\uc778 \ub300\ud559 \uce5c\uad6c\uac00 \uc788\uc2b5\ub2c8\ub2e4.\n\ud558\uc9c0\ub9cc \uadf8\ub294 \uc5ec\uc804\ud788 35\ub144 \uc804\uacfc \uac19\uc740 \uc0b6\uc744 \uc0b4\uace0 \uc788\uc2b5\ub2c8\ub2e4.\n\uadf8\uc758 \uc0b6\uc740 \ub300\ud559 \uc2dc\uc808\uc758 \uc80a\uc740 \uc5f4\uc815\uc774 \uc9c0\ubc30\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4.\n\ub9ce\uc740 \uc0ac\ub78c\ub4e4\uc774 \uacbd\ud5d8\ud558\ub294 \uc80a\uc740 \uc2dc\uc808\uc758 \uc5f4\uc815\uc744 \uc18c\uac1c\ud569\ub2c8\ub2e4:\n\n*   \ucf8c\ub77d: \uc131\uc801\uc778 \uc8c4\ub294 \ucf8c\ub77d\uc758 \uc8c4\uc758 \uc77c\ubc18\uc801\uc778 \uc608\uc774\uc9c0\ub9cc, \uadf8\uac83\ub9cc\uc774 \uc720\uc77c\ud55c \uc8c4\ub294 \uc544\ub2d9\ub2c8\ub2e4.\n\ub2e4\ub978 \uc8c4\uc545\ub41c \ucf8c\ub77d\uc5d0\ub294 \uc220, \uc74c\uc2dd, \ub2e4\uc591\ud55c \uc885\ub958\uc758 \uc624\ub77d\uc774 \ud3ec\ud568\ub420 \uc218 \uc788\uc2b5\ub2c8\ub2e4.\n\uc62c\ubc14\ub974\uac8c \uc0ac\uc6a9\ud55c\ub2e4\uba74 \ub098\uc058\uc9c0 \uc54a\uc2b5\ub2c8\ub2e4.\n\uc608\ub97c \ub4e4\uc5b4, \uc139\uc2a4\ub294 \uae30\ub3c5\uad50 \uacb0\ud63c\uc758 \ub9e5\ub77d\uc5d0\uc11c \ubcfc \ub54c \uc544\ub984\ub2e4\uc6b4 \uc120\ubb3c\uc785\ub2c8\ub2e4.\n\ud558\uc9c0\ub9cc \uc798\ubabb\ub41c \ubc29\uc2dd\uc73c\ub85c \ubb34\uc5b8\uac00\ub97c \uc0ac\uc6a9\ud560 \ub54c, \uc6b0\ub9ac\ub294 \uc6b0\ub9ac\uc758 \uc0b6\uc744 \uc9c0\ubc30\ud558\ub294 \ud798\uc744 \uac16\uac8c \ub429\ub2c8\ub2e4.\n\ud558\ub098\ub2d8\uc758 \uc120\ubb3c \uc911 \uc5b4\ub5a4 \uac83\uc774\ub4e0 \uc6b0\ub9ac \ub9c8\uc74c\uc758 \uacf5\ud5c8\ud568\uc744 \ucc44\uc6b0\uae30 \uc704\ud574 \uc0ac\uc6a9\ud55c\ub2e4\uba74, \uadf8\uac83\uc740 \uac70\uc9d3 \uc2e0, \uc989 \uc6b0\uc0c1\uc774 \ub429\ub2c8\ub2e4.\n\n*   \ud798: \uc5b4\ub838\uc744 \ub54c \uc6b0\ub9ac\ub294 \ub54c\ub54c\ub85c \ubb34\ub825\ud558\uace0 \ub098\uc57d\ud558\uac70\ub098 \ubd80\uc801\uc808\ud558\ub2e4\uace0 \ub290\ub08d\ub2c8\ub2e4.\n\uc800\ub294 10\ub300 \uc2dc\uc808\uc5d0 \uadf8\ub7f0 \uac10\uc815\uc73c\ub85c \ud798\ub4e4\uc5c8\uc2b5\ub2c8\ub2e4.\n\uc5b4\ub5a4 \uc0ac\ub78c\ub4e4\uc740 \uc790\uc2e0\uc758 \ub098\uc57d\ud568\uc744 \uac10\ucd94\uae30 \uc704\ud574 \uad8c\ub825\uc744 \ucd94\uad6c\ud569\ub2c8\ub2e4.\n\uac15\uc778\ud558\uac8c \ud589\ub3d9\ud558\uba74 \uc548\uc804\ud558\ub2e4\uace0 \ub290\ub07c\ub294 \ub370 \ub3c4\uc6c0\uc774 \ub41c\ub2e4\uace0 \uc0dd\uac01\ud569\ub2c8\ub2e4.\n\uad34\ub86d\ud798\uc744 \ub2f9\ud558\ub294 \uc0ac\ub78c\uc774 \uc2e4\uc81c\ub85c\ub294 \ubcf4\uae30\ub9cc\ud07c \uac15\ud558\uc9c0 \uc54a\ub2e4\ub294 \uc0ac\uc2e4\uc744 \uc54c\uace0 \uacc4\uc168\ub098\uc694?\n\uad34\ub86d\ud798\uc744 \ub2f9\ud558\ub294 \uc0ac\ub78c\uc740 \ubcf4\ud1b5 \uc790\uc2e0\uc758 \uc0b6\uc5d0\uc11c \ubb34\uc5b8\uac00\uc5d0 \ub300\ud574 \ubb34\ub825\uac10\uc744 \ub290\ub07c\uae30 \ub54c\ubb38\uc5d0 \uc790\uc2e0\uc774 \uac15\ud558\ub2e4\uace0 \ub290\ub07c\uae30 \uc704\ud574 \ub2e4\ub978 \uc0ac\ub78c\uc5d0\uac8c \uc0c1\ucc98\ub97c \uc8fc\ub294 \uc0ac\ub78c\uc785\ub2c8\ub2e4.\n\n*   \uc778\uae30: \uc774\uac83\uc740 \uc81c \uc778\uc0dd\uc5d0\uc11c \ub610 \ub2e4\ub978 \uac15\ub825\ud55c \uc720\ud639\uc774\uc5c8\uc2b5\ub2c8\ub2e4.\n\uc0ac\ub78c\ub4e4\uc774 \uc800\ub97c \uc88b\uc544\ud558\ub294\uc9c0 \uc790\uc8fc \uac71\uc815\ud569\ub2c8\ub2e4.\n\ub2e4\ub978 \uc0ac\ub78c\uc758 \uc758\uacac\uc5d0 \ub108\ubb34 \uc2e0\uacbd\uc744 \ub9ce\uc774 \uc501\ub2c8\ub2e4.\n\uc5ec\ub7ec\ubd84\uc740 \uc5b4\ub5a0\uc2e0\uac00\uc694?\n\uc0ac\ub78c\ub4e4\uc774 \ub098\ub97c \uc88b\uc544\ud558\uac8c \ub9cc\ub4e4\uae30 \uc704\ud574 \ud589\ub3d9\uc774\ub098 \uc678\ubaa8\ub97c \ubc14\uafbc \uc801\uc774 \uc788\ub098\uc694?\n\uac70\uc808\uc744 \ud53c\ud558\uae30 \uc704\ud574 \ud2b9\uc815 \ubc29\uc2dd\uc73c\ub85c \ud589\ub3d9\ud558\uac70\ub098 \uc678\ubaa8\ub97c \uac16\ucdb0\uc57c \ud55c\ub2e4\uace0 \uc0dd\uac01\ud558\uc2dc\ub098\uc694?\n\n*   \uc18c\uc720\ubb3c: \ub3c8\uacfc \ubb3c\uc9c8\uc801 \uc18c\uc720\uc5d0 \ub300\ud55c \uc0ac\ub791\uc740 \uc6b0\ub9ac \ub300\ubd80\ubd84\uc5d0\uac8c \ubb38\uc81c\uac00 \ub429\ub2c8\ub2e4.\n\uc6b0\ub9ac\ub294 \ub354 \ub9ce\uc740 \ubb3c\uac74\uc744 \uc548\uc804\ud558\uac8c \ubcf4\uad00\ud558\uace0 \ud3b8\uc548\ud558\uac8c \uc0ac\uc6a9\ud560 \uc218 \uc788\uae30\ub97c \uc6d0\ud569\ub2c8\ub2e4.\n\uc774\ub294 \ubbff\uc74c\uc774 \ubd80\uc871\ud558\ub2e4\ub294 \uac83\uc744 \ub4dc\ub7ec\ub0c5\ub2c8\ub2e4.\n\ud558\ub098\ub2d8\uc740 \uc6b0\ub9ac\uac00 \uadf8\ubd84\uc774 \uc6b0\ub9ac\uc758 \ud53c\ub09c\ucc98\uc774\uc790 \uc694\uc0c8\uc774\uba70, \uc6b0\ub9ac\uc758 \uacf5\uae09\uc790\uc784\uc744 \uc774\ud574\ud558\uae30\ub97c \uc6d0\ud558\uc2ed\ub2c8\ub2e4.\n\ubb3c\uc9c8\uc801\uc778 \uac83\uc740 \ud589\ubcf5\uc744 \uc57d\uc18d\ud558\uc9c0\ub9cc \uacb0\ucf54 \uadf8 \uc57d\uc18d\uc744 \uc9c0\ud0ac \uc218\ub294 \uc5c6\uc2b5\ub2c8\ub2e4.\n\uc6b0\ub9ac\uc758 \ub9c8\uc74c\uc740 \uc5b8\uc81c\ub098 \ub354 \ub9ce\uc740 \uac83\uc744 \uac08\ub9dd\ud558\uae30 \ub54c\ubb38\uc785\ub2c8\ub2e4.\n\n*   \uad50\ub9cc: \uad50\ub9cc\uc740 \ub2e4\ub978 \ubaa8\ub4e0 \uc8c4\uc758 \ubc11\ubc14\ub2e5\uc5d0 \uae54\ub824 \uc788\ub294 \uc8c4\uc545\uc785\ub2c8\ub2e4.\n\uad50\ub9cc\uc740 \ub0b4\uac00 \uc2e4\uc81c\ub85c \uc18c\uc720, \uad8c\ub825, \ucf8c\ub77d, \uc778\uae30\ub97c \ub204\ub9b4 \uc790\uaca9\uc774 \uc788\ub2e4\ub294 \ubbff\uc74c\uc785\ub2c8\ub2e4.\n\uc65c\uc694? \uc800\ub294 \ud2b9\ubcc4\ud558\uae30 \ub54c\ubb38\uc785\ub2c8\ub2e4.\n\uad50\ub9cc\uc740 \uc6b0\ub9ac\uc5d0\uac8c \uac70\uc9d3\ub9d0\uc744 \uc18d\uc0ad\uc785\ub2c8\ub2e4:\n\u201d\uad1c\ucc2e\uc544, \ub10c \ud560 \uc218 \uc788\uc5b4. \ub10c \uadf8\ub7f4 \uc790\uaca9\uc774 \uc788\uc5b4.\u201d\n\uad11\uace0\uc8fc\ub4e4\ub3c4 \uac19\uc740 \ub9d0\uc744 \ud569\ub2c8\ub2e4.\n\u201d\ub2f9\uc2e0\uc740 \uadf8\ub7f4 \uc790\uaca9\uc774 \uc788\uc2b5\ub2c8\ub2e4...\uc5b4\uc11c \uad6c\ub9e4\ud558\uc138\uc694.\n\uc870\uae08 \ub354 \uc0ac\uba74 \uad1c\ucc2e\uc544\uc694.\u201d\n\uc6b0\ub9ac\uac00 \uc774\ub7f0 \uad11\uace0\ub97c \ub9ce\uc774 \ubcf4\ub294 \uc774\uc720\ub294 \uc6b0\ub9ac\uc758 \uc790\uc874\uc2ec\uc774 \uc2e4\uc81c\ub85c \uc774\ub7f0 \ub9d0\uc744 \ubbff\uace0 \uc2f6\uc5b4\ud558\uae30 \ub54c\ubb38\uc785\ub2c8\ub2e4.\n\n\uc9c8\ubb38 \ud558\ub098 \ud574\ub3c4 \ub420\uae4c\uc694?\n\uc774 \ub2e4\uc12f \uac00\uc9c0 \uc911 \uc775\uc219\ud55c \uac83\uc740 \ubb34\uc5c7\uc778\uac00\uc694?\n\uc790\uc874\uc2ec, \uc18c\uc720\ubb3c, \uad8c\ub825, \ucf8c\ub77d, \uc778\uae30 \ub4f1\uc744 \ucd94\uad6c\ud558\uace0 \uc788\ub098\uc694?\n\uc544\ub2c8\uba74 \ud558\ub098\ub2d8\uc73c\ub85c\ubd80\ud130 \uba40\uc5b4\uc9c0\uac8c \ud558\ub294 \ub2e4\ub978 \ubb34\uc5b8\uac00\uac00 \uc788\uc744\uae4c\uc694?\n\uc624\ub298 \ub2f9\uc2e0\uc758 \ub9c8\uc74c\uc740 \uc5b4\ub514\uc5d0 \uc788\uc73c\uba70 \uc5b4\ub514\ub85c \uac00\uace0 \uc788\ub098\uc694?\n\uc544\ub2f4\uc774 \uc120\uc545\uacfc\ub97c \ub530\uba39\uc740 \ud6c4 \ud558\ub098\ub2d8\uaed8\uc11c \ub3d9\uc0b0\uc5d0\uc11c \uc544\ub2f4\uc5d0\uac8c \ubb3c\uc73c\uc2e0 \uac83\uc744 \uae30\uc5b5\ud558\uc2dc\ub098\uc694?\n\uc544\ub2f4\uacfc \ud558\uc640\uac00 \uc228\uc5b4 \uc788\uc744 \ub54c \ud558\ub098\ub2d8\uc774 \u201d\uc544\ub2f4\uc544, \uc5b4\ub514 \uc788\ub290\ub0d0?\u201d\ub77c\uace0 \ubb3c\uc73c\uc168\uc5b4\uc694.\n\ud558\ub098\ub2d8\uc740 \uc624\ub298\ub0a0 \uc774 \ub545\uc758 \ubaa8\ub4e0 \uc0ac\ub78c\uc5d0\uac8c\ub3c4 \uac19\uc740 \uac83\uc744 \uc694\uad6c\ud558\uace0 \uacc4\uc2ed\ub2c8\ub2e4.\n\uc5b4\ub514 \uacc4\uc2e0\uac00\uc694?\n\ubb3c\ub9ac\uc801\uc73c\ub85c \uc5b4\ub514\uc5d0 \uc788\ub294\uc9c0 \ubb3b\ub294 \uac83\uc774 \uc544\ub2d9\ub2c8\ub2e4.\n\uadf8\ub294 \u201d\ub2f9\uc2e0\uc758 \ub9c8\uc74c\uc740 \uc5b4\ub514\uc5d0 \uc788\uc2b5\ub2c8\uae4c?\u201d\ub77c\uace0 \ubb3b\uace0 \uc788\uc2b5\ub2c8\ub2e4.\n\uc6b0\ub9ac\uc758 \ub9c8\uc74c\uc740 \uc6b0\ub9ac\uac00 \uac00\uc7a5 \uc18c\uc911\ud788 \uc5ec\uae30\ub294 \uac83\uc744 \ud5a5\ud55c \uae38\ub85c \uc778\ub3c4\ud558\ub294 \ub098\uce68\ubc18\uacfc \uac19\uae30 \ub54c\ubb38\uc785\ub2c8\ub2e4.\n\uc8c4\ub294 \uad50\ud65c\ud558\uae30 \ub54c\ubb38\uc5d0 \uc6b0\ub9ac\ub294 \uae38\uc744 \uc783\uace0 \uc790\uc2e0\ub3c4 \ubaa8\ub974\uac8c \ube60\uc838\ub4ed\ub2c8\ub2e4.\n\uc6b0\ub9ac \ub0b4\uba74\uc5d0\uc11c \ubb34\uc2a8 \uc77c\uc774 \uc77c\uc5b4\ub098\uace0 \uc788\ub294\uc9c0 \ud655\uc778\ud558\ub824\uba74 \ud558\ub098\ub2d8\uc758 \ub3c4\uc6c0\uc774 \ud544\uc694\ud569\ub2c8\ub2e4.\n\uc2dc\ud3b8 139\ud3b8 23~24\uc808\uc744 \ud568\uaed8 \uae30\ub3c4\ubb38\uc73c\ub85c \uc77d\uc5b4 \ubd05\uc2dc\ub2e4:\n\ubaa8\ub450: 23 \u201d\ud558\ub098\ub2d8\uc774\uc5ec, \ub098\ub97c \ucc3e\uc73c\uc2dc\uace0 \ub0b4 \ub9c8\uc74c\uc744 \uc544\uc18c\uc11c!\n\ub098\ub97c \ud14c\uc2a4\ud2b8\ud558\uace0 \ub0b4 \uc0dd\uac01\uc744 \uc54c\uc544\ubcf4\uc138\uc694!\n24 \uadf8\ub9ac\uace0 \ub0b4 \uc548\uc5d0 \uc2ac\ud508 \uae38\uc774 \uc788\ub294\uc9c0 \uc0b4\ud3b4\ubcf4\uc138\uc694,\n\uc601\uc6d0\ud55c \uae38\ub85c \uc778\ub3c4\ud558\uc18c\uc11c!\u201d\n\n\ud558\ub098\ub2d8\uc758 \ub3c4\uc6c0 \uc5c6\uc774\ub294 \uc6b0\ub9ac\ub294 \u201d\uc601\uc6d0\ud55c \uae38\u201d\uc744 \uac77\uc9c0 \ubabb\ud560 \uac83\uc785\ub2c8\ub2e4.\n\uc6b0\ub9ac\ub294 \ud558\ub098\ub2d8\uc758 \ub9c8\uc74c\uc5d0\uc11c \uba40\uc5b4\uc9c0\ub294 \uac83\ub4e4\uc744 \ucd94\uad6c\ud558\uba70 \uc798\ubabb\ub41c \ubc29\ud5a5\uc73c\ub85c \ub2ec\ub824\uac08 \uac83\uc785\ub2c8\ub2e4.\n\ud558\uc9c0\ub9cc \ud558\ub098\ub2d8\uc740 \ub108\ubb34 \uc120\ud558\uc154\uc11c \uc6b0\ub9ac\uac00 \ubc29\ud669\ud558\uace0 \uae38\uc744 \uc783\ub294 \uac83\uc744 \uadf8\ub0e5 \uc9c0\ucf1c\ubcf4\uc2dc\uc9c0 \uc54a\uc73c\uc2ed\ub2c8\ub2e4.\n\ub300\uc2e0 \uc8fc\ub2d8\uc740 \uc783\uc5b4\ubc84\ub9b0 \uc591\uc744 \ucc3e\uc73c\uc2ed\ub2c8\ub2e4.\n\uadf8\ubd84\uc740 \uc6b0\ub9ac\uc5d0\uac8c \uc624\uc154\uc11c \ud0c8\ucd9c\uacfc \uad6c\ucd9c\uc758 \uae38\uc744 \uc81c\uc2dc\ud558\uc2ed\ub2c8\ub2e4.\n\ub514\ubaa8\ub370\ud6c4\uc11c 2\uc7a5 25\uc808\ubd80\ud130 26\uc808\uc744 \ub2e4\uc2dc \ubcf4\uc138\uc694:\n25b \u201d\ud558\ub098\ub2d8\uaed8\uc11c\ub294 \uc544\ub9c8\ub3c4 \uadf8\ub4e4\uc5d0\uac8c \ud68c\uac1c\ub97c \ud5c8\ub77d\ud558\uc154\uc11c \uc9c4\ub9ac\ub97c \uc54c\uac8c \ud558\uc2e4\uc9c0\ub3c4 \ubaa8\ub985\ub2c8\ub2e4,\n26 \uadf8\ub9ac\uace0 \uadf8\ub4e4\uc740 \ub9c8\uadc0\uc5d0\uac8c \ubd99\uc7a1\ud600 \ub9c8\uadc0\uc758 \ub73b\uc744 \ud589\ud558\ub2e4\uac00 \uc815\uc2e0\uc744 \ucc28\ub9ac\uace0 \ub9c8\uadc0\uc758 \uc62c\ubb34\uc5d0\uc11c \ubc97\uc5b4\ub098\uac8c \ub420 \uac83\uc785\ub2c8\ub2e4.\u201d\n\n\uc2e4\uc81c\ub85c \uc8c4\uc640 \ub9c8\uadc0\uc5d0 \uac07\ud600 \uc788\uc744 \ub54c \uc644\uc804\ud55c \uc790\uc720\ub97c \ub290\ub084 \uc218 \uc788\ub2e4\ub294 \uac83\uc744 \uc54c\uace0 \uacc4\uc168\ub098\uc694?\n\uc8c4\ub294 \uc790\uc720\ucc98\ub7fc \ub290\uaef4\uc9c0\uc9c0\ub9cc \uc0ac\uc2e4\uc740 \uadf8 \ubc18\ub300\uc785\ub2c8\ub2e4.\n\uc62c\ubb34\ub294 \uc774\ub807\uac8c \uc0dd\uacbc\uc2b5\ub2c8\ub2e4.\n\uae38\uc744 \uc790\uc720\ub86d\uac8c \ub2ec\ub9ac\ub2e4\uac00 \uac11\uc790\uae30 \uc704\ud5d8\uc5d0 \ucc98\ud55c \ub3d9\ubb3c\uc744 \uc7a1\ub294 \ub36b\uc785\ub2c8\ub2e4.\n\uc0ac\ud0c4\uc740 \uc6b0\ub9ac\ub97c \uc18d\uc774\uace0 \ud568\uc815\uc5d0 \ube60\ub728\ub9ac\uae30 \uc704\ud574 \ub9c8\ub77c\ud1a4 \ucf54\uc2a4\uc5d0 \ud45c\uc9c0\ud310\ucc98\ub7fc \uac70\uc9d3\ub9d0\uc744 \ubc30\uce58\ud569\ub2c8\ub2e4.\n\uc0ac\ud0c4\uc740 \uc6b0\ub9ac\uac00 \ucf8c\ub77d, \uad8c\ub825, \uc778\uae30, \uc18c\uc720, \uad50\ub9cc\uc744 \uc887\uc544 \ub2ec\ub824\uac00\uae30\ub97c \uc6d0\ud569\ub2c8\ub2e4.\n\uc774\ub7ec\ud55c \uc6b0\uc0c1\uc740 \uc6b0\ub9ac\uc5d0\uac8c \uc790\uc720\ub97c \uc57d\uc18d\ud558\uace0, \uc790\uc720\ub294 \uc6b0\ub9ac\uac00 \uadf8\ud1a0\ub85d \uc6d0\ud558\ub294 \uac83\uc785\ub2c8\ub2e4.\n\ud558\uc9c0\ub9cc \uc774\ub7ec\ud55c \uac83\ub4e4\uc774 \ub9cc\uc871\uac10, \uc548\uc804, \ud589\ubcf5\uc744 \ub290\ub07c\ub294 \ub370 \ub3c4\uc6c0\uc774 \ub420 \uc218 \uc788\ub2e4\uace0 \ubbff\uc2b5\ub2c8\ub2e4.\n\uadf8\ub7ec\ub098 \uc774\ub7ec\ud55c \uc6b0\uc0c1\uc740 \uc6b0\ub9ac\ub97c \ud558\ub098\ub2d8\uacfc \ucc38\ub41c \uc0dd\uba85\uc758 \uae38\uc5d0\uc11c \uba40\uc5b4\uc9c0\uac8c \ud558\ub294 \ud568\uc815\uc785\ub2c8\ub2e4.\n\uc0ac\ud0c4\uc740 \uc0dd\uba85\uc758 \uae38\uc744 \uc6b0\ub9ac\uc5d0\uac8c\uc11c \uc228\uae30\uace0 \uc2f6\uc5b4 \ud569\ub2c8\ub2e4:\n\u201d\uc2b9\ub9ac\uc640 \ud589\ubcf5\uc744 \ud5a5\ud574 \uc774 \uae38\uc744 \uac00\uc138\uc694!\n\ub124, \uc800 \uae38\uc774\uc5d0\uc694! \ub0a0 \ub530\ub77c\uc640!\u201d\n\n\uadf8\ub807\ub2e4\uba74 \ub3d9\ubb3c\uc740 \uc5b4\ub5bb\uac8c \uc774\ub7f0 \ub36b\uc5d0\uc11c \ud0c8\ucd9c\ud560 \uc218 \uc788\uc744\uae4c\uc694?\n\ud63c\uc790\uc11c \ud560 \uc218 \uc788\ub294 \uc77c\uc778\uac00\uc694?\n\uc544\ub2c8\uc694, \ud1a0\ub07c\ub294 \ubb34\ub825\ud569\ub2c8\ub2e4.\n\uadf8\ub294 \ub354 \ub611\ub611\ud558\uace0 \uac15\ud55c \uc0ac\ub78c\uc774 \uc640\uc11c \uadf8\ub97c \ud568\uc815\uc5d0\uc11c \uad6c\ud574\uc918\uc57c \ud569\ub2c8\ub2e4.\n\uc6b0\ub9ac\ub3c4 \uc6b0\ub9ac\ub97c \uad6c\ud574\uc904 \ub354 \ub611\ub611\ud558\uace0 \uac15\ud55c \uc0ac\ub78c\uc774 \ud544\uc694\ud569\ub2c8\ub2e4.\n\uc774\uac83\uc774 \uc81c\uac00 \uc774 \uad6c\uc808\uc5d0\uc11c \uac00\uc7a5 \uc911\uc694\ud558\uac8c \ubcf4\uace0 \uc2f6\uc740 \uc810\uc785\ub2c8\ub2e4.\n\uc6b0\ub9ac\ub294 \uc2a4\uc2a4\ub85c\ub97c \uad6c\ud558\uac70\ub098 \uc2e0\uc5d0\uac8c \uc758\uc9c0\ud560 \uc218 \uc5c6\uae30 \ub54c\ubb38\uc5d0 \uad6c\uc870\uc790\uac00 \ud544\uc694\ud569\ub2c8\ub2e4.\n\uc601\uc801\uc73c\ub85c \uc8fd\uc740 \ub9c8\uc74c\uc740 \uc0dd\uba85\uc744 \uc120\ud0dd\ud560 \uc218 \uc5c6\uc2b5\ub2c8\ub2e4.\n25\uc808\uc758 \ub0b4\uc6a9\uc744 \ubcf4\uc138\uc694:\n\u201d\ud558\ub098\ub2d8\uaed8\uc11c \uadf8\ub4e4\uc5d0\uac8c \ud68c\uac1c\ub97c \ud5c8\ub77d\ud558\uc2e4\uc9c0\ub3c4 \ubaa8\ub985\ub2c8\ub2e4.\u201d\n\n\ubcf4\uc870\uae08\uc740 \ubb34\ub8cc \uc120\ubb3c\uc785\ub2c8\ub2e4.\n\ud558\ub098\ub2d8\uc740 30\ub144 \uc804 \uc800\uc5d0\uac8c \ud68c\uac1c\uc758 \uc120\ubb3c\uc744 \uc8fc\uc168\uc2b5\ub2c8\ub2e4.\n10\ub144 \ub3d9\uc548 \uc800\ub294 \uc6b0\uc8fc\uc5d0\ub294 \uc2e0\uc774 \uc5c6\ub2e4\uace0 \ub9d0\ud588\uc2b5\ub2c8\ub2e4.\n\ud558\uc9c0\ub9cc \ud558\ub098\ub2d8\uc740 \uce5c\uc808\ud558\uc2e0 \ubd84\uc774\uc2dc\uae30\uc5d0 \ub9e5\uc8fc, \uc5ec\uc790, \uc138\uc0c1\uc758 \uc131\uacf5\uc774 \uacb0\ucf54 \uc81c \ub9c8\uc74c\uc758 \uc695\ub9dd\uc744 \ucda9\uc871\uc2dc\ud0ac \uc218 \uc5c6\ub2e4\ub294 \uac83\uc744 \ubcf4\uc5ec \uc8fc\uc168\uc2b5\ub2c8\ub2e4.\n\uc774\uac83\uc774 26\uc808\uc5d0\uc11c \u201d\uc815\uc2e0\uc744 \ucc28\ub9ac\uace0\u201d\uac00 \uc758\ubbf8\ud558\ub294 \ubc14\uc785\ub2c8\ub2e4.\n\ubc29\ud5a5 \uac10\uac01\uc774 \ud63c\ub780\uc2a4\ub7ec\uc6b0\uba74 \uc798\ubabb\ub41c \ubc29\ud5a5\uc73c\ub85c \ub2ec\ub9ac\uac8c \ub429\ub2c8\ub2e4.\n\uae38\uc744 \ucc3e\uae30 \uc704\ud55c \uccab \ubc88\uc9f8 \ub2e8\uacc4\ub294 \uae38\uc744 \uc783\uc5c8\ub2e4\ub294 \uc0ac\uc2e4\uc744 \uc778\uc2dd\ud558\ub294 \uac83\uc785\ub2c8\ub2e4.\n\ub304 \ub9e5\ub3c4\uc6f0\uc740 \ud3ec\ud2c0\ub79c\ub4dc\uc5d0\uc11c \uc5f4\ub9b0 \ub9c8\ub77c\ud1a4 \ub300\ud68c\uc5d0\uc11c \uae38\uc744 \uc783\uc740 \uc8fc\uc790 \uc911 \ud55c \uba85\uc774\uc5c8\uc2b5\ub2c8\ub2e4.\n\uadf8\ub294 \uc774\ub807\uac8c \ub9d0\ud588\uc2b5\ub2c8\ub2e4: \u201d\ubaa8\ud241\uc774\ub97c \ub3cc\uc558\ub294\ub370 10\uba85\uc774 \uac00\ub9cc\ud788 \uc11c \uc788\ub294 \uac83\uc744 \ubcf4\uc558\uc2b5\ub2c8\ub2e4...\n\uadf8\ub4e4\uc740 \uc11c\ub85c\ub97c \ubcf4\uba70 \u2018\uc5b4, \uc774\uac74 \uc544\ub2cc \uac83 \uac19\uc544\u2018\ub77c\uace0 \uc0dd\uac01\ud588\uc2b5\ub2c8\ub2e4.\u201d\n\n\ub610 \ub2e4\ub978 \ub7ec\ub108\uc778 \uc7ad \ucee4\uc2a4\ud130\ub294 \uc2dc\uc18d 55\ub9c8\uc77c\ub85c \uc790\ub3d9\ucc28\uac00 \uc9c0\ub098\uac00\ub294 \ud130\ub110\uc5d0 \ub4e4\uc5b4\uc130\ub2e4\uace0 \ub9d0\ud588\uc2b5\ub2c8\ub2e4.\n\uadf8\ub54c \uadf8\ub294 \uc790\uc2e0\uc774 \uae38\uc744 \ubc97\uc5b4\ub0ac\ub2e4\ub294 \uac83\uc744 \uae68\ub2ec\uc558\uc2b5\ub2c8\ub2e4.\n\ud558\ub098\ub2d8\uaed8\uc11c \uc81c\uac8c \uc815\uc2e0\uc744 \ucc28\ub9ac\uae30 \uc804\uc5d0\ub294 \uc81c\uac00 \u201d\uc9c4\ub9ac\uc5d0 \ub300\ud55c \uc9c0\uc2dd\u201d\uc744 \uac00\uc9c0\uace0 \uc788\ub2e4\uace0 \uc0dd\uac01\ud588\uc2b5\ub2c8\ub2e4.\n\ub0b4 \uc790\uc874\uc2ec\uc740 \ub0b4\uac00 \uc633\uc740 \uae38\uc774\ub77c\uace0 \ub9d0\ud588\uace0, \ub0b4\uac00 \ub108\ubb34 \ub611\ub611\ud574\uc11c \ub098\ub97c \uc778\ub3c4\ud574 \uc904 \uc2e0\uc774 \ud544\uc694 \uc5c6\ub2e4\uace0 \uc0dd\uac01\ud588\uc2b5\ub2c8\ub2e4.\n\uc544\uc774\ub7ec\ub2c8\ud558\uac8c\ub3c4 \uc800\ub294 \ub108\ubb34 \uc5b4\ub9ac\uc11d\uc5b4\uc11c \uc0ac\ud0c4\uc758 \uc18d\uc784\uc218\ub97c \uc54c\uc544\ucc28\ub9ac\uc9c0 \ubabb\ud588\uc2b5\ub2c8\ub2e4.\n\ub098\ub294 \uadf8\uc758 \uac70\uc9d3\ub9d0\uc758 \uc62c\ubb34\uc5d0 \uac78\ub824\ub4e4\uc5c8\uc2b5\ub2c8\ub2e4.\n\ud558\ub098\ub2d8\uc73c\ub85c\ubd80\ud130 \ub3c4\ub9dd\uce58\uba74 \ud589\ubcf5\uc744 \ucc3e\uc744 \uc218 \uc788\ub2e4\ub294 \uc545\ub9c8\uc758 \uc57d\uc18d\uc744 \ubbff\uc5c8\uc2b5\ub2c8\ub2e4.\n\ud558\uc9c0\ub9cc \uadf8\ub54c \ud558\ub098\ub2d8\uaed8\uc11c \ud68c\uac1c\ub77c\ub294 \uc120\ubb3c\uc744 \uc8fc\uc168\uc2b5\ub2c8\ub2e4.\n\uc5ec\uae30\uc11c \ud68c\uac1c\ub97c \ub73b\ud558\ub294 \ud5ec\ub77c\uc5b4\ub294 \uba54\ud0c0\ub178\uc774\uc544\uc785\ub2c8\ub2e4.\n\u201d\ub9c8\uc74c\uc758 \ubcc0\ud654, \uc0b6\uc758 \ubcc0\ud654, \ubaa9\uc801\uc758 \ubcc0\ud654\u201d\ub97c \uc758\ubbf8\ud569\ub2c8\ub2e4.\n22\uc808 \ub9d0\uc500\ucc98\ub7fc \u201d\uae68\ub057\ud55c \ub9c8\uc74c\uc73c\ub85c \uc8fc\ub2d8\uc744 \ubd80\ub97c \uc218 \uc788\ub3c4\ub85d\u201d \uc608\uc218\ub2d8\uaed8\uc11c \uc0c8 \ub9c8\uc74c\uc744 \uc8fc\uc168\uc2b5\ub2c8\ub2e4.\n\uc21c\uc218\ud55c \ub9c8\uc74c\uc740 \uc815\uc9c1\ud55c \ub9c8\uc74c\uc785\ub2c8\ub2e4.\n\ud558\ub098\ub2d8\uaed8 \u201d\uc81c \uc8c4\ub97c \uc6a9\uc11c\ud574 \uc8fc\uc138\uc694.\u201d\ub77c\uace0 \uae30\ub3c4\ud558\ub294 \ub9c8\uc74c.\n\ub0b4\uac00 \ub2f9\uc2e0\uc5d0\uac8c\uc11c \uba40\uc5b4\uc9c0\uc9c0 \uc54a\uace0 \ub2f9\uc2e0\uc744 \ud5a5\ud574 \ub2ec\ub824\uac08 \uc218 \uc788\ub3c4\ub85d \ub3c4\uc640\uc8fc\uc138\uc694.\u201d\n\ubc14\uc6b8\uc740 \ub85c\ub9c8\uc11c 10\uc7a5 9~11\uc808\uc5d0\uc11c \ud558\ub098\ub2d8\uc744 \ud5a5\ud574 \ub3cc\uc774\ucf1c \uad6c\uc6d0\ubc1b\uc744 \uc218 \uc788\ub294 \ubc29\ubc95\uc744 \ub9e4\uc6b0 \uba85\ud655\ud558\uac8c \uc124\uba85\ud588\uc2b5\ub2c8\ub2e4.\n9 \u201d\ub124\uac00 \ub9cc\uc77c \ub124 \uc785\uc73c\ub85c \uc608\uc218\ub97c \uc8fc\ub85c \uc2dc\uc778\ud558\uba70 \ud558\ub098\ub2d8\uaed8\uc11c \uadf8\ub97c \uc8fd\uc740 \uc790 \uac00\uc6b4\ub370\uc11c \uc0b4\ub9ac\uc2e0 \uac83\uc744 \ub124 \ub9c8\uc74c\uc5d0 \ubbff\uc73c\uba74 \uad6c\uc6d0\uc744 \uc5bb\uc73c\ub9ac\ub77c.\u201d\n10 \ub9c8\uc74c\uc73c\ub85c \ubbff\uc5b4 \uc758\ub86d\ub2e4 \ud558\uc2ec\uc744 \uc5bb\uace0 \uc785\uc73c\ub85c \uc2dc\uc778\ud558\uc5ec \uad6c\uc6d0\uc744 \uc5bb\uc73c\ub2c8, \uc774\ub294 \ub108\ud76c\uac00 \ubbff\uc74c\uc73c\ub85c \ub9d0\ubbf8\uc554\uc544 \uc758\ub86d\ub2e4 \ud558\uc2ec\uc744 \uc5bb\uace0 \uc785\uc73c\ub85c \uc2dc\uc778\ud558\uc5ec \uad6c\uc6d0\uc744 \uc5bb\uc74c\uc774\ub77c.\n11 \uc131\uacbd\uc5d0 \u201d\uadf8\ub97c \ubbff\ub294 \uc0ac\ub78c\uc740 \ub204\uad6c\ub4e0\uc9c0 \ubd80\ub044\ub7ec\uc6c0\uc744 \ub2f9\ud558\uc9c0 \uc54a\uc744 \uac83\uc774\ub2e4\u201d\ub77c\uace0 \ub9d0\uc500\ud558\uc168\uc2b5\ub2c8\ub2e4.\n\n\uad6c\uc6d0\uc744 \ubc1b\uae30 \uc704\ud574 \uc785\uc73c\ub85c \ubbff\uc74c\uc744 \uace0\ubc31\ud558\uc168\ub098\uc694?\n\uc544\uc9c1 \ud574\ubcf4\uc9c0 \uc54a\uc558\ub2e4\uba74 \uc624\ub298\uc774 \uc88b\uc740 \ub0a0\uc774 \uc544\ub2d0\uae4c \uc2f6\uc9c0 \uc54a\ub098\uc694?\n\uc131\ub839\uaed8\uc11c \uc6b0\ub9ac \uac00\uc6b4\ub370 \uacc4\uc2dc\uba70 \uc544\ub9c8\ub3c4 \uc5ec\ub7ec\ubd84\uc758 \ub9c8\uc74c\uc5d0 \uc18d\uc0ad\uc774\uace0 \uacc4\uc2e4 \uac83\uc785\ub2c8\ub2e4:\n\u201d\uc8c4\uc640 \uc0ac\ub9dd\uc758 \uae38\uc5d0\uc11c \ub3cc\uc774\ud0a4\ub77c!\n\u2018\uc608\uc218\ub2d8\uc740 \uc8fc\ub2d8\uc774\uc2ed\ub2c8\ub2e4\u2018\ub77c\uace0 \uc120\uc5b8\ud568\uc73c\ub85c\uc368 \uc0c8\ub85c\uc6b4 \uc0b6\uacfc \uc0c8\ub85c\uc6b4 \ubc29\ud5a5\uc744 \uc120\ud0dd\ud558\uc138\uc694!\u201d\n\nPaul\uc740 \uc774\uc804\uc5d0 \uc774 \uc0c8\ub85c\uc6b4 \ubc29\ud5a5\uc5d0 \ub300\ud574 \uae00\uc744 \uc4f4 \uc801\uc774 \uc788\uc2b5\ub2c8\ub2e4.\n\ub514\ubaa8\ub370\uac00 \ud604\uc7ac \ubaa9\ud68c\uc790\ub85c \uc12c\uae30\uace0 \uc788\ub294 \uc5d0\ubca0\uc18c\uc758 \ubc14\ub85c \uadf8 \uad50\ud68c\uc5d0 \ubcf4\ub0b8 \ud3b8\uc9c0\uc600\uc2b5\ub2c8\ub2e4.\n\uc5d0\ubca0\uc18c\uc11c 2\uc7a5 1-5\uc808\uc5d0\uc11c \ubc14\uc6b8\uc774 \uae30\ub3c5\uad50 \uc2e0\uc790\ub4e4\uc5d0\uac8c \ud558\ub098\ub2d8\uaed8\uc11c \uadf8\ub4e4\uc5d0\uac8c \uc0c8 \uc0dd\uba85\uacfc \uc0c8 \ubc29\ud5a5\uc744 \uc8fc\uc2dc\uae30 \uc704\ud574 \uc5b4\ub5a4 \uc77c\uc744 \ud558\uc168\ub294\uc9c0\uc5d0 \ub300\ud574 \uc4f4 \uae00\uc744 \ub4e4\uc5b4\ubcf4\uc138\uc694:\n1 \u201d\uadf8\ub9ac\uace0 \ub2f9\uc2e0\uc740 \ud5c8\ubb3c\uacfc \uc8c4\ub85c \uc8fd\uc5c8\uc2b5\ub2c8\ub2e4.\n2 \ub108\ud76c\uac00 \ud55c\ub54c \uc774 \uc138\uc0c1 \ud48d\uc870\ub97c \ub530\ub77c, \uacf5\uc911\uc758 \uad8c\uc138 \uc7a1\uc740 \uc790, \uace7 \uc9c0\uae08 \ubd88\uc21c\uc885\uc758 \uc544\ub4e4\ub4e4 \uac00\uc6b4\ub370\uc11c \uc5ed\uc0ac\ud558\ub294 \uc601\uc744 \ub530\ub77c \uac78\uc5c8\ub358 \uadf8 \uae38..\n3 \uc6b0\ub9ac \ubaa8\ub450\ub294 \ud55c\ub54c \uc721\uccb4\uc758 \uc815\uc695\uc5d0 \ube60\uc838 \ubab8\uacfc \ub9c8\uc74c\uc758 \uc695\ub9dd\uc744 \uc887\uc544 \uc0b4\uc558\uc73c\uba70, \ub2e4\ub978 \uc778\ub958\uc640 \ub9c8\ucc2c\uac00\uc9c0\ub85c \ubcf8\uc9c8\uc801\uc73c\ub85c \uc9c4\ub178\uc758 \uc790\ub140\uc600\uc2b5\ub2c8\ub2e4.\n4 \uadf8\ub7ec\ub098 \ud558\ub098\ub2d8\uaed8\uc11c\ub294 \uc6b0\ub9ac\ub97c \uc0ac\ub791\ud558\uc2e0 \ud070 \uc0ac\ub791 \ub54c\ubb38\uc5d0 \uc790\ube44\uac00 \ud48d\ubd80\ud558\uc168\uc2b5\ub2c8\ub2e4,\n5 \uc6b0\ub9ac\uac00 \uc6b0\ub9ac\uc758 \ud5c8\ubb3c\ub85c \uc8fd\uc5c8\uc744 \ub54c\uc5d0\ub3c4 \uadf8\ub9ac\uc2a4\ub3c4\uc640 \ud568\uaed8 \uc6b0\ub9ac\ub97c \uc0b4\ub9ac\uc168\uc73c\ub2c8, \uc5ec\ub7ec\ubd84\uc740 \uc740\ud61c\ub85c \uad6c\uc6d0\uc744 \uc5bb\uc5c8\uc2b5\ub2c8\ub2e4!\u201d\n\n\u201d\ud558\uc9c0\ub9cc \ud558\ub098\ub2d8\u201d\uc740 \ubaa8\ub4e0 \ub9d0 \uc911\uc5d0\uc11c \uac00\uc7a5 \uc544\ub984\ub2e4\uc6b4 \ub450 \ub2e8\uc5b4\uc785\ub2c8\ub2e4.\n\ubc14\uc6b8\uc740 \uc5d0\ubca0\uc18c\uc758 \uc2e0\uc790\ub4e4\uc5d0\uac8c \uc790\uc2e0\ub4e4\ub3c4 \ud55c\ub54c \uc62c\ubb34\uc5d0 \uac78\ub9b0 \ud1a0\ub07c\ucc98\ub7fc \uac07\ud600 \ubb34\uae30\ub825\ud55c \uc874\uc7ac\uc600\uc74c\uc744 \uc0c1\uae30\uc2dc\ud0b5\ub2c8\ub2e4.\n\uadf8\ub7ec\ub098 \ud558\ub098\ub2d8\uc740 \uc624\uc9c1 \uc740\ud61c\ub85c, \uc624\uc9c1 \ubbff\uc74c\uc73c\ub85c, \uc624\uc9c1 \uadf8\ub9ac\uc2a4\ub3c4 \uc548\uc5d0\uc11c\ub9cc \uadf8\ub4e4\uc744 \uad6c\uc6d0\ud558\uae30 \uc704\ud574 \uac1c\uc785\ud558\uc168\uc2b5\ub2c8\ub2e4.\n\uadf8\ub9ac\uc2a4\ub3c4\uc758 \uc2ed\uc790\uac00 \ud76c\uc0dd\uc774 \uc8c4\uc640 \ubd80\ub044\ub7ec\uc6c0\uc744 \uc53b\uc5b4\uc8fc\uae30 \uc704\ud55c \uac83\uc784\uc744 \ubbff\ub294\ub2e4\uba74 \ub204\uad6c\ub098 \uad6c\uc6d0\ubc1b\uc744 \uc218 \uc788\uc2b5\ub2c8\ub2e4.\n\uc774\ub97c \ubbff\uc73c\uba74 \uc0c8 \uc0dd\uba85\uc744 \uc5bb\uac8c \ub418\uace0 \uc608\uc218\ub2d8\uc740 \uc5ec\ub7ec\ubd84\uc744 \uc0c8\ub85c\uc6b4 \uae38\ub85c \uc778\ub3c4\ud558\uc2ed\ub2c8\ub2e4.\n\uba87 \uad6c\uc808 \ud6c4 \uc5d0\ubca0\uc18c\uc11c 2\uc7a5 8\uc808\uc5d0\uc11c \ubc14\uc6b8\uc740 \uadf8 \uc0c8\ub85c\uc6b4 \ubc29\ud5a5\uc5d0 \ub300\ud574 \uc774\uc57c\uae30\ud569\ub2c8\ub2e4.\n\uc774 \uae00\uc744 \ud568\uaed8 \uc77d\uc5b4\ubcf4\uc138\uc694:\n\ubaa8\ub450: 10 \u201d\uc6b0\ub9ac\ub294 \uadf8\uc758 \ub9cc\ub4dc\uc2e0 \ubc14\ub77c \uadf8\ub9ac\uc2a4\ub3c4 \uc608\uc218 \uc548\uc5d0\uc11c \uc120\ud55c \uc77c\uc744 \uc704\ud558\uc5ec \uc9c0\uc73c\uc2ec\uc744 \ubc1b\uc740 \uc790\ub2c8 \uc774 \uc77c\uc740 \ud558\ub098\ub2d8\uc774 \ubbf8\ub9ac \uc608\ube44\ud558\uc0ac \uc6b0\ub9ac\ub85c \uadf8 \uac00\uc6b4\ub370 \ud589\ud558\uac8c \ud558\ub824 \ud558\uc2ec\uc774\ub2c8\ub77c.\u201d\n\n\uc774 \uba54\uc2dc\uc9c0\ub97c \ub9c8\ubb34\ub9ac\ud558\uba74\uc11c \uc120\ud55c \uc77c\uc744 \ud589\ud558\ub294 \uac83\uc774 \uc5b4\ub5a4 \ubaa8\uc2b5\uc778\uc9c0 \uc0b4\ud3b4\ubd05\uc2dc\ub2e4.\n\ubc14\uc6b8\uc740 \ub514\ubaa8\ub370\uc5d0\uac8c \uc131\uacbd \uad50\uc0ac\ub85c \ub204\uad6c\ub97c \uc120\ubc1c\ud558\uace0 \ud6c8\ub828\uc2dc\ud0ac \uac83\uc778\uc9c0\uc5d0 \ub300\ud55c \uc9c0\uce68\uc744 \uc81c\uacf5\ud558\ub294 \ud3b8\uc9c0\ub97c \uc4f0\uace0 \uc788\ub2e4\ub294 \uc0ac\uc2e4\uc744 \uae30\uc5b5\ud558\uc138\uc694.\n\uadf8\ub9ac\uace0 \uc2e0\uc790\ub85c\uc11c \uc6b0\ub9ac\uc758 \uc0ac\uba85\uc740 \uac00\uae4c\uc6b4 \uacf3\uacfc \uba3c \uacf3\uc758 \uc0ac\ub78c\ub4e4\uc5d0\uac8c \ubcf5\uc74c\uc758 \uae30\uc05c \uc18c\uc2dd\uc744 \uc804\ud558\ub294 \uac83\uc785\ub2c8\ub2e4.\n\ud558\uc9c0\ub9cc \uc774\ub97c \ucda9\uc2e4\ud788 \uc218\ud589\ud558\ub824\uba74 \ubc14\uc6b8\uc774 \uc774 \uad6c\uc808\uc5d0\uc11c \ubb18\uc0ac\ud558\ub294 \uc131\ud488\uc744 \uac00\uc838\uc57c \ud569\ub2c8\ub2e4.\n\uc0ac\ub78c\uc758 \ub9c8\uc74c\uc740 \ubc14\uafc0 \uc218 \uc5c6\uc2b5\ub2c8\ub2e4.\n\ud558\uc9c0\ub9cc \uc6b0\ub9ac\ub294 \uadf8\ub4e4\uc5d0\uac8c \ubd80\ub4dc\ub7fd\uace0 \uce5c\uc808\ud558\uba70 \uc778\ub0b4\uc2ec\uc744 \uac00\uc9c0\uace0 \uc9c4\uc2e4\uc744 \ub9d0\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4.\n\uadf8\ub9ac\uace0 \uc6b0\ub9ac\ub294 \ud558\ub098\ub2d8\uaed8\uc11c \uc120\ud0dd\ud558\uc2e0 \uc790\ub140\ub4e4\uc5d0\uac8c \uc801\uc808\ud55c \ub54c\uc5d0 \ud68c\uac1c\ub97c \ud5c8\ub77d\ud558\uc2e4 \uac83\uc744 \ubbff\uc744 \uc218 \uc788\uc2b5\ub2c8\ub2e4.\n\uc624\ub298 \ubcf8\ubb38 24\uc808\uacfc 25\uc808\uc5d0\ub294 \ud558\ub098\ub2d8\uaed8\uc11c \uc885\ub4e4\uc5d0\uac8c\uc11c \uac1c\ubc1c\ud558\uae30\ub97c \uc6d0\ud558\uc2dc\ub294 \ub2e4\uc12f \uac00\uc9c0 \ud2b9\uc131\uc774 \ub098\uc640 \uc788\uc2b5\ub2c8\ub2e4:\n\n\ud488\uc9c8 1: \ub2e4\ud23c\uc774 \uc5c6\uc2b5\ub2c8\ub2e4.\n\uc5b4\ub5a4 \uc0ac\ub78c\ub4e4\uc740 \ub17c\uc7c1\uc744 \uc88b\uc544\ud569\ub2c8\ub2e4.\n\uac74\uc804\ud55c \ud1a0\ub860\uc740 \uc798\ubabb\ub41c \uac83\uc774 \uc544\ub2d9\ub2c8\ub2e4.\n\ud558\uc9c0\ub9cc \uc790\uc2e0\uc774 \uc5b8\uc81c \uc8c4\uc545\uc2a4\ub7fd\uac8c \u2018\ub2e4\ud22c\uace0\u2019 \uc788\ub294\uc9c0 \uc5b4\ub5bb\uac8c \uc54c \uc218 \uc788\uc744\uae4c\uc694?\n\uc2a4\uc2a4\ub85c\uc5d0\uac8c \uc774\ub7f0 \uc9c8\ubb38\uc744 \ub358\uc838\ubcf4\uc138\uc694:\n\u201d\ub204\uad70\uac00\uc640 \ub17c\uc7c1\uc744 \ud560 \ub54c \uadf8 \uc0ac\ub78c\uc744 \ub354 \uc911\uc694\ud558\uac8c \uc0dd\uac01\ud558\ub098\uc694, \uc544\ub2c8\uba74 \ub17c\uc7c1\uc5d0\uc11c \uc774\uae30\ub294 \uac83\uc774 \ub354 \uc911\uc694\ud558\ub098\uc694?\n\uc790\uc874\uc2ec \ub54c\ubb38\uc5d0 \uce5c\uc808 \ub300\uc2e0 \uc633\uc740 \uac83\uc5d0\ub9cc \uc9d1\uc911\ud558\uac8c \ub418\ub294 \uac74 \uc544\ub2d0\uae4c\uc694?\u201d\n\n\ud488\uc9c8 2: \ubaa8\ub4e0 \uc0ac\ub78c\uc5d0\uac8c \uce5c\uc808\ud569\ub2c8\ub2e4.\n\uc8fc\uc758 \uc885\uc740 \ubaa8\ub4e0 \uc0ac\ub78c\uc5d0\uac8c \uce5c\uc808\ud574\uc57c \ud569\ub2c8\ub2e4.\n\uc2ec\uc9c0\uc5b4 \ub2f9\uc2e0\uc744 \ubbf8\uc6cc\ud558\uace0 \ub2f9\uc2e0\uc744 \ud574\uce58\uace0 \uc2f6\uc5b4\ud558\ub294 \uc0ac\ub78c\ub4e4\uc5d0\uac8c\ub3c4\uc694.\n\uc5b4\ub835\ub2e4\ub294 \uac70 \uc54c\uc544\uc694.\n\uc6b0\ub9ac\ub294 \ub2e4\ub978 \uc0ac\ub78c\ub4e4\ub85c\ubd80\ud130 \uc790\uc2e0\uc744 \ubcf4\ud638\ud558\ub294 \ubc29\ubc95\uc740 \uac15\ud574\uc838\uc11c \uad8c\ub825\uc744 \uc0ac\uc6a9\ud558\ub294 \uac83\uc774\ub77c\uace0 \uc0dd\uac01\ud569\ub2c8\ub2e4.\n\ud558\uc9c0\ub9cc \ub85c\ub9c8\uc11c 2\uc7a5 4\uc808\uc5d0\uc11c \ubc14\uc6b8\uc774 \uc6b0\ub9ac\uc5d0\uac8c \uc0c1\uae30\uc2dc\ucf1c \uc8fc\ub294 \ub0b4\uc6a9\uc744 \ubcf4\uc138\uc694:\n\u201d\ud558\ub098\ub2d8\uc758 \uce5c\uc808\uc740 \ub2f9\uc2e0\uc744 \ud68c\uac1c\ub85c \uc774\ub04c\uae30 \uc704\ud55c \uac83\uc785\ub2c8\ub2e4.\u201d\n\uc5ec\ub7ec\ubd84\uc774 \uc8c4\uc5d0 \ube60\uc838 \uc8fc\ub2d8\uc744 \uba40\ub9ac\ud558\uace0 \uc788\uc744 \ub54c \uc608\uc218\ub2d8\uc740 \uc5ec\ub7ec\ubd84\uc5d0\uac8c \uc5bc\ub9c8\ub098 \uce5c\uc808\ud558\uc168\ub098\uc694?\n\uadf8\ubd84\uc758 \uce5c\uc808\ub85c \uc778\ud574 \ud68c\uac1c\ud558\uac8c \ub418\uc5c8\uc2b5\ub2c8\ub2e4,\n\uc774\uc81c \uc5ec\ub7ec\ubd84\uc740 \uadf8\ub9ac\uc2a4\ub3c4\ub97c \ubcf8\ubc1b\uc544 \ubaa8\ub4e0 \uc0ac\ub78c\uc5d0\uac8c \uce5c\uc808\ud558\uac8c \ub300\ud560 \uc218 \uc788\ub294 \uae30\ud68c\ub97c \uac16\uac8c \ub418\uc5c8\uc2b5\ub2c8\ub2e4.\n\n\ud488\uc9c8 3: \uc545\uc744 \ucc38\uc744\uc131 \uc788\uac8c \uacac\ub38c\ub0c5\ub2c8\ub2e4.\n\ubcf5\uc74c\uc758 \uc9c4\ub9ac\ub97c \uc804\ud560 \ub54c \uc6b0\ub9ac\ub294 \uc6b0\ub9ac\uac00 \ub9d0\ud558\ub294 \uac83\uc744 \uc88b\uc544\ud558\uc9c0 \uc54a\ub294 \uc0ac\ub78c\ub4e4\uc758 \ubc18\ub300\ub97c \uacbd\ud5d8\ud558\uac8c \ub429\ub2c8\ub2e4.\n\uc2a4\ud2f0\ube10\uc774 \uc790\uc2e0\uc744 \uc8fd\uc778 \uc0ac\ub78c\ub4e4\uc5d0\uac8c \uc5b4\ub5bb\uac8c \ub300\uc751\ud588\ub294\uc9c0 \uae30\uc5b5\ud558\uc2dc\ub098\uc694?\n\uc0ac\ub3c4\ud589\uc804 7\uc7a5 59~60\uc808\uc740 \uc774\ub807\uac8c \ub9d0\ud569\ub2c8\ub2e4:\n59 \uadf8\ub4e4\uc774 \ub3cc\ub85c \uce58\ub294 \ub3d9\uc548 \uc2a4\ub370\ubc18\uc740 \u201d\uc8fc \uc608\uc218\ub2d8, \uc81c \uc601\ud63c\uc744 \ubc1b\uc73c\uc18c\uc11c\u201d\ub77c\uace0 \uae30\ub3c4\ud588\uc2b5\ub2c8\ub2e4.\n60 \uadf8\ub7ec\uc790 \uadf8\ub294 \ubb34\ub98e\uc744 \uafc7\uace0 \u201d\uc8fc\ub2d8, \uc774 \uc8c4\ub97c \uadf8\ub4e4\uc5d0\uac8c \ub4a4\uc9d1\uc5b4\uc50c\uc6b0\uc9c0 \ub9c8\uc138\uc694.\u201d\ub77c\uace0 \uc678\ucce4\uc2b5\ub2c8\ub2e4.\n\n\uc624\uc9c1 \ud558\ub098\ub2d8\ub9cc\uc774 \uc2a4\ub370\ubc18\ucc98\ub7fc \uc545\uc744 \ucc38\uc744\uc131 \uc788\uac8c \uacac\ub514\ub3c4\ub85d \ub3c4\uc640\uc8fc\uc2e4 \uc218 \uc788\uc2b5\ub2c8\ub2e4.\n\uadf8\ub7ec\ub098 \uc6b0\ub9ac\uac00 \uc5b4\ub824\uc6c0\uc5d0 \ucc98\ud588\uc744 \ub54c \uadf8\ubd84\uc744 \ubd80\ub974\uba74 \uadf8\ubd84\uc740 \uc6b0\ub9ac\ub97c \ub3c4\uc640\uc8fc\uc2e4 \uac83\uc785\ub2c8\ub2e4.\n\uc6b0\ub9ac\uc758 \uc721\uc2e0\uc5d0 \uc5b4\ub5a4 \uc77c\uc774 \uc77c\uc5b4\ub098\ub354\ub77c\ub3c4 \uc6b0\ub9ac\uc758 \uc601\ud63c\uc774 \uadf8\ubd84\uc758 \uc190\uc5d0 \uc548\uc804\ud558\ub2e4\ub294 \uac83\uc744 \uc54c\uace0 \uadf8\ubd84\uc744 \uc2e0\ub8b0\ud558\ub3c4\ub85d \ub3c4\uc640\uc8fc\uc2e4 \uac83\uc785\ub2c8\ub2e4.\n\n\ud488\uc9c8 4: \ubd80\ub4dc\ub7fd\uac8c \uc218\uc815\ud569\ub2c8\ub2e4.\n\uc0ac\ub78c\uc744 \ubc14\ub85c\uc7a1\ub294 \uac83\uc740 \uc5b4\ub824\uc6b4 \uc77c\uc785\ub2c8\ub2e4.\n\ud558\uc9c0\ub9cc \uc544\ub4e4\uc774 \ubb54\uac00 \uc798\ubabb\ud558\uace0 \uc788\ub2e4\uba74 \uc0ac\ub791\ud558\uae30 \ub54c\ubb38\uc5d0 \uc544\ub4e4\uc5d0\uac8c \ub9d0\ud569\ub2c8\ub2e4.\n\ub204\uad70\uac00\ub97c \uc218\uc815\ud574\uc57c \ud560 \ub54c \uace0\ub824\ud574\uc57c \ud560 \uc911\uc694\ud55c \uc9c8\ubb38\uc740 \ub2e4\uc74c\uacfc \uac19\uc2b5\ub2c8\ub2e4:\n\u201d\ub0b4 \uc790\ub140, \uce5c\uad6c, \ubc30\uc6b0\uc790\uac00 \ub0b4 \uc0ac\ub791\uc744 \ub290\ub07c\uace0 \uc788\ub098\uc694?\n\uc544\ub2c8\uba74 \ub0b4 \ubd84\ub178\ub9cc \ub290\ub07c\ub294 \uac78\uae4c\uc694?\u201d\n\n\ubd84\ub178\ub098 \uc88c\uc808\uac10\uc73c\ub85c \ub300\uc751\ud558\ub294 \uac83\uc740 \uc0c1\ub300\ubc29\uc744 \ubcc0\ud654\uc2dc\ud0ac \uc218 \uc5c6\ub294 \uac83\ucc98\ub7fc \ud589\ub3d9\ud558\ub294 \uac83\uc785\ub2c8\ub2e4.\n\uc6b0\ub9ac\ub294 \uadf8\ub4e4\uc774 \ubcc0\ud654\ud558\ub3c4\ub85d \uc555\ub825\uc744 \uac00\ud558\uac70\ub098 \uc62c\ubc14\ub978 \uae38\ub85c \uac08 \ub54c\uae4c\uc9c0 \ub354 \ud070 \uc18c\ub9ac\ub85c \uc678\uce60 \uc218 \uc788\ub2e4\uace0 \uc0dd\uac01\ud569\ub2c8\ub2e4.\n\uadf8\ub7ec\ub098 \ud558\ub098\ub2d8\uc774 \uc9c4\uc815\ud55c \ub2a5\ub825\uc744 \uac00\uc9c0\uace0 \uacc4\uc2e0\ub2e4\ub294 \uac83\uc744 \uc544\ub294 \uad50\uc0ac\ub294 \uc628\uc720\ud558\uace0 \uc778\ub0b4\uc2ec \uc788\uace0 \uce5c\uc808\ud560 \uac83\uc785\ub2c8\ub2e4.\n\n\ud488\uc9c8 5: \uac00\ub974\uce60 \uc218 \uc788\uc2b5\ub2c8\ub2e4.\n\ub2e4\ub978 \uc0ac\ub78c\uc5d0\uac8c \uc124\uba85\ud560 \uc218 \uc788\uc744 \ub9cc\ud07c \ud558\ub098\ub2d8\uc758 \ub9d0\uc500\uc744 \uc798 \uc774\ud574\ud558\uace0 \uc788\ub098\uc694?\n\uc778\uc0dd\uc758 \uc9c0\uce68\uc774 \ub418\uace0 \ub2e4\ub978 \uc0ac\ub78c\ub4e4\uacfc \ub098\ub20c \uc218 \uc788\ub3c4\ub85d \uc131\uacbd \ub9d0\uc500\uc744 \uc554\uc1a1\ud558\uace0 \uc788\ub098\uc694?\n\uc774\ubc88 \ub2ec\uc5d0 \uc0c8\ub85c\uc6b4 \uac83\uc744 \uc2dc\uc791\ud558\ub824\uace0 \ud569\ub2c8\ub2e4.\n3\uc6d4 \ub9d0\uae4c\uc9c0 \uc131\uacbd \uad6c\uc808 \ud55c \uad6c\uc808\uc744 \uc678\uc6b0\ub3c4\ub85d \uc694\uccad\ud560 \uac83\uc785\ub2c8\ub2e4.\n\uadf8\ub9ac\uace0 \uc5b4\ub5a4 \uc5b8\uc5b4\ub85c\ub4e0 \ub9ac\ub354\uc5d0\uac8c \uc774 \uad6c\uc808\uc744 \uc678\uc6b0\uba74 \uc2a4\ud2f0\ucee4\ub97c \ubc1b\uc744 \uc218 \uc788\uc2b5\ub2c8\ub2e4.\n\ubb3c\ubcd1\uc774\ub098 \ub178\ud2b8\ubd81\uc5d0 \ubd80\ucc29\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4.\n\uc5b4\ub514\uc11c\ub4e0 \ubcfc \uc218 \uc788\uace0 \uc77c \ub144 \ub0b4\ub0b4 \uacc4\uc18d \uc5f0\uc2b5\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4.\n3\uc6d4\uc758 \ub9d0\uc500\uc778 \ub514\ubaa8\ub370\ud6c4\uc11c 3\uc7a5 16\uc808 \ub9d0\uc500\uc744 \ud568\uaed8 \uc77d\uc5b4\ubcf4\uaca0\uc2b5\ub2c8\ub2e4.\n\ubaa8\ub450: \u201d\ubaa8\ub4e0 \uc131\uacbd\uc740 \ud558\ub098\ub2d8\uc758 \uac10\ub3d9\uc73c\ub85c \ub41c \uac83\uc73c\ub85c \uad50\ud6c8\uacfc \ucc45\ub9dd\uacfc \ubc14\ub974\uac8c \ud568\uacfc \uc758\ub85c \uad50\uc721\ud558\uae30\uc5d0 \uc720\uc775\ud558\ub2e4\u201d\n\n\uc6b0\ub9ac \ubaa8\ub450\ub294 \uc62c\ubc14\ub978 \ubc29\ud5a5\uc73c\ub85c \uacc4\uc18d \ub2ec\ub9ac\uae30 \uc704\ud574 \ub3c4\uc6c0\uc774 \ud544\uc694\ud569\ub2c8\ub2e4.\n\uc6b0\ub9ac\ub294 \uc758\ub85c \ud589\ud558\ub3c4\ub85d \uac00\ub974\uce58\uace0, \ubc14\ub85c\uc7a1\uace0, \ud6c8\ub828\ud558\uae30 \uc704\ud574 \ud558\ub098\ub2d8\uc758 \ub9d0\uc500\uc774 \ud544\uc694\ud569\ub2c8\ub2e4.\n\uadf8\ub9ac\uace0 \ub9d0\uc500\uc744 \uc774\ud574\ud558\uace0 \uc801\uc6a9\ud560 \uc218 \uc788\ub3c4\ub85d \uc131\ub839\ub2d8\uc758 \ub3c4\uc6c0\uc774 \ud544\uc694\ud558\ub2c8 \uc9c0\uae08 \uae30\ub3c4\ud558\uba74\uc11c \ub9c8\uc74c\uc744 \ud558\ub298\ub85c \ud5a5\ud569\uc2dc\ub2e4.\n\uc608\uc218\ub2d8, \ub2f9\uc2e0\uc774 \ub545\uacfc \ud558\ub298 \uc0ac\uc774\uc5d0 \ub2e4\ub9ac\ub97c \ub193\uc73c\uc168\uae30\uc5d0 \uc6b0\ub9ac\ub294 \uc544\ubc84\uc9c0\uc640 \ub300\ud654\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4.\n\uc545\ub9c8\uc758 \uc62c\ubb34\ub97c \ud30c\uad34\ud558\uace0 \uc9c4\ub9ac\uc5d0 \ub208\uc744 \ub728\uac8c \ud558\uc168\uc2b5\ub2c8\ub2e4.\n\uc544\ubc84\uc9c0, \ud68c\uac1c\uc758 \uc120\ubb3c\uc744 \uc8fc\uc154\uc11c \uc6b0\ub9ac \uc790\uc2e0\uacfc \uc8fc\ub2d8\uaed8 \uc6b0\ub9ac\uc758 \uc8c4\uc5d0 \ub300\ud574 \uc815\uc9c1\ud558\uac8c \ub9d0\ud560 \uc218 \uc788\uac8c \ud574\uc8fc\uc154\uc11c \uac10\uc0ac\ud569\ub2c8\ub2e4.\n\uadf8\ub9ac\uace0 \uad6c\uc6d0\uc744 \uc704\ud574 \uc608\uc218\ub2d8\uaed8 \uc758\uc9c0\ud560 \uc218 \uc788\ub294 \ubbff\uc74c\uc744 \uc8fc\uc2e0 \uc131\ub839\ub2d8, \uac10\uc0ac\ud569\ub2c8\ub2e4.\n\ub9d0\uc500\uc744 \uc774\ud574\ud558\uace0 \uc0b6\uc5d0 \uc801\uc6a9\ud558\uae30 \uc704\ud574 \ub9c8\uc74c\uacfc \ub9c8\uc74c\uc744 \uc5f4\uc5b4\ubcf4\uc138\uc694.\n\uc6b0\ub9ac \uc55e\uc5d0 \ub193\uc778 \uacbd\uc8fc\ub97c \uc5f4\uc2ec\ud788 \ub2ec\ub824\uac00\uac8c \ud558\uc2dc\uace0, \uc628\uc804\ud568\uacfc \ud76c\ub9dd\uacfc \ucc9c\uad6d\uc744 \ud5a5\ud55c \uc5ec\uc815\uc5d0 \ub2e4\ub978 \uc0ac\ub78c\ub4e4\uc744 \ucd08\ub300\ud558\uac8c \ud558\uc18c\uc11c, \uc544\uba58.\n\n\ubb35\uc0c1\uacfc \ub098\ub214\uc744 \uc704\ud55c \uc9c8\ubb38\ub4e4\n1.  \ub514\ubaa8\ub370\ud6c4\uc11c 2:22 \ubc0f \uc2dc\ud3b8 119:35-37\uc744 \uc77d\uc5b4\ubcf4\uc138\uc694.\na) \uc2a4\ud2b8\ub808\uc2a4\ub97c \ubc1b\uac70\ub098 \uc704\ub85c\ub97c \ubc1b\uace0 \uc2f6\uc744 \ub54c \ub9c8\uc74c\uc774 \uc790\uc5f0\uc2a4\ub7fd\uac8c \u2018\uc80a\uc740 \uc5f4\uc815\u2018(\ucf8c\ub77d, \uad8c\ub825, \uc778\uae30, \uc18c\uc720, \uc790\uc874\uc2ec) \uc911 \uc5b4\ub5a4 \uac83\uc744 \ud5a5\ud574 \ub2ec\ub824\uac00\uac8c \ub418\ub098\uc694?\n\n2.  \uc5d0\ubca0\uc18c\uc11c 2:1-5 \ubc0f \uc5d0\uc2a4\uac94 36:26\uc744 \uc77d\uc5b4\ubcf4\uc138\uc694.\na) \u2018\uc8fd\uc740 \uc0c1\ud0dc\u2018\uc5d0\uc11c \u2018\uc0b4\uc544 \uc788\ub294 \uc0c1\ud0dc\u2018\uac00 \ub418\ub824\uba74 \ubb34\uc5c7\uc774 \ud544\uc694\ud55c\uac00\uc694?\nb) \ud68c\uac1c\uac00 \uc740\ud61c\uc758 \uc120\ubb3c\uc774\ub77c\uace0 \ubbff\ub294 \uac83\uc774 \ud558\ub098\ub2d8\uaed8 \uc790\uc2e0\uc758 \uc8c4\uc5d0 \ub300\ud574 \ub354 \uc194\uc9c1\ud574\uc9c0\ub294 \ub370 \ub3c4\uc6c0\uc774 \ub418\ub098\uc694?\n\n3.  \ub514\ubaa8\ub370\ud6c4\uc11c 2\uc7a5 23~25\uc808\uacfc \uace8\ub85c\uc0c8\uc11c 3\uc7a5 12~14\uc808\uc744 \uc77d\uc2b5\ub2c8\ub2e4.\na) \ub2e4\ub978 \uc0ac\ub78c\uc744 \ud1a0\ub860\ud558\uac70\ub098 \uad50\uc815\ud560 \ub54c \u2018\uc8fc\uc758 \uc885\u2019\uc758 \uc790\uc9c8\uc740 \ubb34\uc5c7\uc778\uac00\uc694?\nb) \uc608\uc218\ub2d8\uc740 \uc6b0\ub9ac\ub97c \ud070 \uc778\ub0b4\uc640 \uc628\uc720\ud568\uc73c\ub85c \uc0ac\ub791\ud558\uc168\ub294\ub370, \uc5ec\ub7ec\ubd84\uc740 \uc5ec\ub7ec\ubd84\uacfc \uc758\uacac\uc774 \ub2e4\ub974\uac70\ub098 \ub9c8\uc74c\uc5d0 \ub4e4\uc9c0 \uc54a\ub354\ub77c\ub3c4 \uac19\uc740 \uc740\ud61c\ub85c \uc0ac\ub791\ud560 \uc218 \uc788\ub294 \uc0ac\ub78c\uc774 \ub204\uad6c\uc778\uac00\uc694?\n\n4.  \ub85c\ub9c8\uc11c 10\uc7a5 9~11\uc808\uacfc \ud788\ube0c\ub9ac\uc11c 12\uc7a5 1~2\uc808\uc744 \uc77d\uc5b4 \ubcf4\uc138\uc694.\n\ub2f5) \uc608\uc218\ub2d8\uaed8 \uc2dc\uc120\uc744 \uace0\uc815\ud558\ub294 \uac83\uc774 \uc8c4\uc5d0\uc11c \ub3cc\uc774\ucf1c \uc0c8\ub85c\uc6b4 \ubc29\ud5a5\uc73c\ub85c \ub2ec\ub824\uac00\ub294 \ub370 \uc5b4\ub5bb\uac8c \ub3c4\uc6c0\uc774 \ub418\ub098\uc694?\nb) \ub514\ubaa8\ub370\ud6c4\uc11c 3:16\uc744 \uc678\uc6b0\ub294 \uac83\uc744 \uc78a\uc9c0 \ub9c8\uc138\uc694. \ud558\ub098\ub2d8\uc758 \ub9d0\uc500\uc744 \uc544\ub294 \uac83\uc774 \uc2e0\uc559\uc758 \ub9c8\ub77c\ud1a4\uc744 \ub2ec\ub9ac\ub294 \ub370 \uc5b4\ub5bb\uac8c \ub3c4\uc6c0\uc774 \ub418\ub098\uc694?","mongolian_content":"\u0427\u0438 \u0445\u0430\u0430\u0448\u0430\u0430 \u0433\u04af\u0439\u0436 \u0431\u0430\u0439\u0433\u0430\u0430 \u044e\u043c \u0431\u044d?\n2 \u0422\u0438\u043c\u043e\u0442 2:22-26\n\u041f\u0430\u0441\u0442\u043e\u0440 \u041a\u0440\u0438\u0441 \u0421\u0438\u043a\u0441\n2026 \u043e\u043d\u044b 3-\u0440 \u0441\u0430\u0440\u044b\u043d 15\n\n2019 \u043e\u043d\u044b \u041e\u0440\u0435\u0433\u043e\u043d \u043c\u0443\u0436\u0438\u0439\u043d \u041f\u043e\u0440\u0442\u043b\u0435\u043d\u0434 \u0445\u043e\u0442\u043e\u0434 \u0431\u043e\u043b\u0441\u043e\u043d \u043c\u0430\u0440\u0430\u0444\u043e\u043d\u0434 \u0448\u0438\u043b\u0434\u044d\u0433 \u0433\u04af\u0439\u0433\u0447\u0434\u0438\u0439\u043d \u0437\u0430\u0440\u0438\u043c \u043d\u044c \u0443\u0440\u0430\u043b\u0434\u0430\u0430\u043d\u0434 \u044f\u043b\u0430\u0433\u0434\u0441\u0430\u043d.\n\u0422\u044d\u0434 \u0443\u0434\u0430\u0430\u043d \u0431\u0430\u0439\u0441\u0430\u043d \u0443\u0447\u0440\u0430\u0430\u0441 \u0431\u0438\u0448, \u0445\u0430\u0440\u0438\u043d \u0431\u0443\u0440\u0443\u0443 \u0437\u0430\u043c\u0430\u0430\u0440 \u044f\u0432\u0441\u0430\u043d \u0443\u0447\u0440\u0430\u0430\u0441 \u0442\u044d\u0440.\n\u0417\u0430\u043c \u0434\u044d\u044d\u0440 \u0442\u043e\u0434\u043e\u0440\u0445\u043e\u0439 \u0442\u044d\u043c\u0434\u044d\u0433\u043b\u044d\u0433\u0434\u044d\u044d\u0433\u04af\u0439 \u044d\u0440\u0433\u044d\u043b\u0442 \u0433\u0430\u0440\u0441\u0430\u043d.\n\u0422\u0438\u0439\u043c\u044d\u044d\u0441 \u0445\u0430\u043c\u0433\u0438\u0439\u043d \u0445\u0443\u0440\u0434\u0430\u043d \u0433\u04af\u0439\u0433\u0447\u0434\u0438\u0439\u043d 20 \u043e\u0440\u0447\u0438\u043c \u043d\u044c \u0431\u0443\u0440\u0443\u0443 \u0447\u0438\u0433\u043b\u044d\u043b\u0434 \u043d\u044d\u0433 \u043c\u0438\u043b\u044d\u044d\u0441 \u0438\u043b\u04af\u04af \u0433\u04af\u0439\u0441\u044d\u043d!\n\u042d\u043d\u044d \u0430\u043b\u0434\u0430\u0430 \u043d\u044c \u0442\u044d\u0434\u043d\u0438\u0439 \u0445\u044d\u0434\u044d\u043d \u0441\u0430\u0440\u044b\u043d \u0442\u0443\u0440\u0448 \u0433\u04af\u0439\u0445\u044d\u044d\u0440 \u0431\u044d\u043b\u0434\u044d\u0436 \u0431\u0430\u0439\u0441\u0430\u043d \u0443\u0440\u0430\u043b\u0434\u0430\u0430\u043d\u0434 \u04af\u043d\u044d\u0442\u044d\u0439 \u043c\u0438\u043d\u0443\u0442\u0443\u0443\u0434\u044b\u0433 \u043d\u044d\u043c\u0441\u044d\u043d.\n\u0422\u044d\u0434\u0433\u044d\u044d\u0440 \u044d\u0440\u044d\u0433\u0442\u044d\u0439, \u044d\u043c\u044d\u0433\u0442\u044d\u0439 \u0445\u04af\u043c\u04af\u04af\u0441 \u0448\u0430\u0440\u0433\u0443\u0443 \u0433\u04af\u0439\u0436, \u0445\u0443\u0440\u0434\u0430\u043d \u0433\u04af\u0439\u0432.\n\u0413\u044d\u0432\u0447 \u0442\u044d\u0434 \u0431\u0443\u0440\u0443\u0443 \u0437\u0430\u043c\u0430\u0430\u0440 \u044f\u0432\u0441\u0430\u043d \u0442\u0443\u043b \u0443\u0440\u0430\u043b\u0434\u0430\u0430\u043d\u0434 \u044f\u043b\u0430\u0433\u0434\u0441\u0430\u043d.\n\u04e8\u043d\u04e9\u04e9 \u043e\u0440\u043e\u0439 \u0431\u0438\u0434 2 \u0422\u0438\u043c\u043e\u0442 \u043d\u043e\u043c\u044b\u043d \u0446\u0443\u0432\u0440\u0430\u043b \u043d\u043e\u043c\u043b\u043e\u043b\u044b\u0433 \u04af\u0440\u0433\u044d\u043b\u0436\u043b\u04af\u04af\u043b\u0436 \u0431\u0430\u0439\u043d\u0430.\n\u042d\u043b\u0447 \u041f\u0430\u0443\u043b \u0415\u0444\u0435\u0441 \u0434\u044d\u0445 \u0425\u0440\u0438\u0441\u0442\u0438\u0439\u043d \u0441\u04af\u043c\u0438\u0439\u043d \u0437\u0430\u043b\u0443\u0443 \u043f\u0430\u0441\u0442\u043e\u0440 \u0422\u0438\u043c\u043e\u0442\u043e\u0434 \u0437\u0430\u0445\u0438\u0434\u0430\u043b \u0431\u0438\u0447\u0438\u0436 \u0431\u0430\u0439\u043d\u0430.\n\u041f\u0430\u0443\u043b \u0422\u0438\u043c\u043e\u0442\u043e\u0434 \u0431\u043e\u043b\u043e\u043d \u04e9\u043d\u04e9\u04e9\u0434\u04e9\u0440 \u0431\u0438\u0434\u044d\u043d\u0434 \u0437\u04e9\u0432 \u0437\u0430\u043c \u0434\u044d\u044d\u0440 \u0445\u044d\u0440\u0445\u044d\u043d \u04af\u043b\u0434\u044d\u0445 \u0442\u0430\u043b\u0430\u0430\u0440 \u0437\u04e9\u0432\u043b\u04e9\u0433\u04e9\u04e9 \u04e9\u0433\u0447 \u0431\u0430\u0439\u043d\u0430.\n2 \u0422\u0438\u043c\u043e\u0442 2:22\u201326\n22 \u0422\u0438\u0439\u043c\u044d\u044d\u0441 \u0437\u0430\u043b\u0443\u0443 \u043d\u0430\u0441\u043d\u044b \u0445\u04af\u0441\u044d\u043b \u0442\u0430\u0447\u0430\u0430\u043b\u0430\u0430\u0441 \u0437\u0443\u0433\u0442\u0430\u0436, \u0446\u044d\u0432\u044d\u0440 \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b\u044d\u044d\u0441 \u042d\u0437\u044d\u043d\u0438\u0439\u0433 \u0434\u0443\u0443\u0434\u0434\u0430\u0433 \u0445\u04af\u043c\u04af\u04af\u0441\u0438\u0439\u043d \u0445\u0430\u043c\u0442 \u0437\u04e9\u0432 \u0448\u0443\u0434\u0430\u0440\u0433\u0430 \u0431\u0430\u0439\u0434\u0430\u043b, \u0438\u0442\u0433\u044d\u043b, \u0445\u0430\u0439\u0440 \u0431\u0430 \u0430\u043c\u0430\u0440 \u0442\u0430\u0439\u0432\u043d\u044b\u0433 \u044d\u0440\u044d\u043b\u0445\u0438\u0439\u043b.\n23 \u041c\u0443\u043d\u0445\u0430\u0433, \u043c\u044d\u0434\u043b\u044d\u0433\u0433\u04af\u0439 \u043c\u0430\u0440\u0433\u0430\u0430\u043d\u0442\u0430\u0439 \u0445\u043e\u043b\u0431\u043e\u043e\u0442\u043e\u0439 \u044e\u0443 \u0447 \u0431\u04af\u04af \u0431\u0430\u0439; \u0442\u044d\u0434 \u0445\u044d\u0440\u04af\u04af\u043b \u043c\u0430\u0440\u0433\u0430\u0430\u043d \u04af\u04af\u0441\u0433\u044d\u0434\u044d\u0433 \u0433\u044d\u0434\u0433\u0438\u0439\u0433 \u0447\u0438 \u043c\u044d\u0434\u043d\u044d.\n24 \u042d\u0437\u044d\u043d\u0438\u0439 \u0437\u0430\u0440\u0446 \u0445\u044d\u0440\u04af\u04af\u043b\u0447 \u0431\u0438\u0448, \u0445\u0430\u0440\u0438\u043d \u0431\u04af\u0445 \u0445\u04af\u043d\u0434 \u044d\u0435\u043b\u0434\u044d\u0433, \u0437\u0430\u0430\u0445 \u0447\u0430\u0434\u0432\u0430\u0440\u0442\u0430\u0439, \u0431\u0443\u0437\u0430\u0440 \u043c\u0443\u0443\u0433 \u0442\u044d\u0432\u0447\u044d\u044d\u0440\u0442\u044d\u0439 \u0442\u044d\u0432\u0447\u0438\u0445 \u0451\u0441\u0442\u043e\u0439.\n25 \u04e9\u0440\u0441\u04e9\u043b\u0434\u04e9\u0433\u0447\u0434\u04e9\u04e9 \u0437\u04e9\u04e9\u043b\u04e9\u043d \u0431\u0430\u0439\u0434\u043b\u0430\u0430\u0440 \u0437\u0430\u0441\u0430\u0436 \u0431\u0430\u0439\u0432.\n\u0411\u0443\u0440\u0445\u0430\u043d \u0442\u044d\u0434\u044d\u043d\u0434 \u04af\u043d\u044d\u043d\u0438\u0439\u0433 \u043c\u044d\u0434\u044d\u0445\u044d\u0434 \u0445\u04af\u0440\u0433\u044d\u0445 \u0433\u044d\u043c\u0448\u043b\u0438\u0439\u0433 \u04e9\u0433\u0447 \u043c\u0430\u0433\u0430\u0434\u0433\u04af\u0439,\n26 \u0422\u044d\u0434 \u0443\u0445\u0430\u0430\u043d \u043e\u0440\u0436, \u0447\u04e9\u0442\u0433\u04e9\u0440\u0438\u0439\u043d \u0445\u04af\u0441\u043b\u0438\u0439\u0433 \u0431\u0438\u0435\u043b\u04af\u04af\u043b\u044d\u0445\u044d\u044d\u0440 \u0442\u04af\u04af\u043d\u0434 \u0431\u0430\u0440\u0438\u0433\u0434\u0441\u0430\u043d\u044b \u0434\u0430\u0440\u0430\u0430 \u0442\u04af\u04af\u043d\u0438\u0439 \u0443\u0440\u0445\u0438\u043d\u0430\u0430\u0441 \u0437\u0443\u0433\u0442\u0430\u0436 \u043c\u0430\u0433\u0430\u0434\u0433\u04af\u0439 \u044e\u043c.\n\n\u0411\u0438\u0434 \u0445\u0430\u043c\u0442\u0434\u0430\u0430 \u0418\u0441\u0430\u0438\u0430 40:8-\u0433 \u0443\u043d\u0448\u0434\u0430\u0433:\n\u201d\u04e8\u0432\u0441 \u0445\u0430\u0442\u0430\u0436, \u0446\u044d\u0446\u044d\u0433 \u0433\u0430\u043d\u0434\u0430\u0436, \u0445\u0430\u0440\u0438\u043d \u0431\u0438\u0434\u043d\u0438\u0439 \u0411\u0443\u0440\u0445\u0430\u043d\u044b \u04af\u0433 \u043c\u04e9\u043d\u0445\u04e9\u0434 \u043e\u0440\u0448\u0438\u043d\u043e.\u201d\n\n22-\u0440 \u0437\u04af\u0439\u043b\u0434:\n22 \u0422\u0438\u0439\u043c\u044d\u044d\u0441 \u0437\u0430\u043b\u0443\u0443 \u043d\u0430\u0441\u043d\u044b \u0445\u04af\u0441\u044d\u043b \u0442\u0430\u0447\u0430\u0430\u043b\u0430\u0430\u0441 \u0437\u0443\u0433\u0442\u0430\u0436, \u0446\u044d\u0432\u044d\u0440 \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b\u044d\u044d\u0441 \u042d\u0437\u044d\u043d\u0438\u0439\u0433 \u0434\u0443\u0443\u0434\u0434\u0430\u0433 \u0445\u04af\u043c\u04af\u04af\u0441\u0438\u0439\u043d \u0445\u0430\u043c\u0442 \u0437\u04e9\u0432 \u0448\u0443\u0434\u0430\u0440\u0433\u0430 \u0431\u0430\u0439\u0434\u0430\u043b, \u0438\u0442\u0433\u044d\u043b, \u0445\u0430\u0439\u0440 \u0431\u0430 \u0430\u043c\u0430\u0440 \u0442\u0430\u0439\u0432\u043d\u044b\u0433 \u044d\u0440\u044d\u043b\u0445\u0438\u0439\u043b.\n\n\u042d\u043d\u044d \u0448\u04af\u043b\u044d\u0433 \u0431\u043e\u043b \u04e9\u043d\u04e9\u04e9\u0434\u0440\u0438\u0439\u043d \u043d\u043e\u043c\u043b\u043e\u043b\u044b\u043d \u0445\u0443\u0440\u0430\u0430\u043d\u0433\u0443\u0439 \u044e\u043c.\n\u0411\u0438\u0434 \u04af\u04af\u043d\u0438\u0439\u0433 \u0411\u0443\u0440\u0445\u0430\u043d\u044b \u04af\u0433\u044d\u043d\u0434 \u043e\u043b\u043e\u043d\u0442\u0430\u0430 \u0445\u0430\u0440\u0434\u0430\u0433.\n\u0417\u0430\u0440\u0438\u043c\u0434\u0430\u0430 \u0414\u0443\u0443\u043b\u0430\u043b \u044d\u0441\u0432\u044d\u043b \u0434\u043e\u0433\u043e\u043b \u043c\u04e9\u0440\u0438\u0439\u043d \u044d\u0445\u043d\u0438\u0439 \u04e9\u0433\u04af\u04af\u043b\u0431\u044d\u0440 \u043d\u044c \u0445\u0443\u0440\u0430\u0430\u043d\u0433\u0443\u0439 \u0431\u0430\u0439\u0445 \u0431\u043e\u043b\u043d\u043e.\n\u0414\u0430\u0440\u0430\u0430 \u043d\u044c \u0434\u0430\u0440\u0430\u0430\u0445 \u04af\u0433\u0441 \u043d\u044c \u0414\u0443\u0443\u043b\u0430\u043b \u044d\u0441\u0432\u044d\u043b \u0434\u043e\u0433\u043e\u043b \u043c\u04e9\u0440 \u044d\u0441\u0432\u044d\u043b \u0431\u04af\u043b\u0433\u0438\u0439\u043d \u0431\u04af\u0445\u044d\u043b \u0431\u04af\u0442\u044d\u043d \u0442\u0430\u0439\u043b\u0431\u0430\u0440 \u044e\u043c.\n\u0422\u04e9\u043b\u04e9\u0432\u0448\u0441\u04e9\u043d \u0425\u0440\u0438\u0441\u0442\u044d\u0434 \u0438\u0442\u0433\u044d\u0433\u0447 \u044d\u0440\u044d\u0433\u0442\u044d\u0439 \u044d\u0441\u0432\u044d\u043b \u044d\u043c\u044d\u0433\u0442\u044d\u0439 \u0445\u04af\u043d \u0431\u043e\u043b \u0431\u0438\u0434\u043d\u0438\u0439\u0433 \u0437\u0430\u043b\u0443\u0443 \u0431\u0430\u0439\u0445\u0430\u0434 \u0443\u0440\u0443\u0443 \u0442\u0430\u0442\u0434\u0430\u0433 \u0431\u0430\u0439\u0441\u0430\u043d \u0437\u04af\u0439\u043b\u0441\u044d\u044d\u0441 \u0445\u043e\u043b\u0434\u0434\u043e\u0433 \u0445\u04af\u043d \u044e\u043c.\n\u0422\u04e9\u043b\u04e9\u0432\u0448\u0441\u04e9\u043d \u0445\u04af\u043d \u201c\u0437\u0430\u043b\u0443\u0443 \u043d\u0430\u0441\u043d\u044b \u0445\u04af\u0441\u044d\u043b \u0442\u044d\u043c\u04af\u04af\u043b\u043b\u0438\u0439\u043d\u201d \u043e\u0440\u043e\u043d\u0434 \u0417\u04e9\u0432\u0442 \u0431\u0430\u0439\u0434\u0430\u043b, \u0418\u0442\u0433\u044d\u043b, \u0425\u0430\u0439\u0440, \u042d\u043d\u0445 \u0442\u0430\u0439\u0432\u0430\u043d \u0437\u044d\u0440\u044d\u0433 \u0411\u0443\u0440\u0445\u0430\u043d\u044b \u04af\u043d\u044d\u0442 \u0437\u04af\u0439\u043b\u0441\u0438\u0439\u0433 \u044d\u0440\u044d\u043b\u0445\u0438\u0439\u043b\u0436 \u0441\u0443\u0440\u0447 \u0431\u0430\u0439\u043d\u0430.\n\u041f\u0430\u0443\u043b\u044b\u0433 \u0437\u0430\u043b\u0443\u0443 \u0431\u0430\u0439\u0445\u0430\u0434 \u043d\u044c \u0421\u0430\u0443\u043b \u0433\u044d\u0434\u044d\u0433 \u0431\u0430\u0439\u0432.\n\u0421\u0430\u0443\u043b \u0431\u0430\u0440\u0434\u0430\u043c \u0437\u0430\u043d, \u04e9\u04e9\u0440\u0442\u04e9\u04e9 \u0438\u0442\u0433\u044d\u043b\u0442\u044d\u0439\u0433\u044d\u044d\u0440 \u0434\u04af\u04af\u0440\u044d\u043d \u0431\u0430\u0439\u0441\u0430\u043d \u0431\u04e9\u0433\u04e9\u04e9\u0434 \u0425\u0440\u0438\u0441\u0442\u044d\u0434 \u0438\u0442\u0433\u044d\u0433\u0447\u0434\u0438\u0439\u0433 \u0445\u0430\u0432\u0447\u0438\u0436, \u0448\u043e\u0440\u043e\u043d\u0434 \u0445\u0438\u0439\u0445 \u044d\u0440\u0445 \u043c\u044d\u0434\u043b\u044d\u044d \u0430\u0448\u0438\u0433\u043b\u0430\u0436 \u0431\u0430\u0439\u0432.\n\u0421\u0430\u0443\u043b \u0430\u043b\u0434\u0430\u0440\u0442\u0430\u0439, \u0430\u043c\u0436\u0438\u043b\u0442\u0442\u0430\u0439 \u0431\u0430\u0439\u0445\u044b\u0433 \u0445\u04af\u0441\u0434\u044d\u0433 \u0431\u0430\u0439\u0441\u0430\u043d \u0431\u04e9\u0433\u04e9\u04e9\u0434 \u04e9\u04e9\u0440\u0438\u0439\u043d\u0445\u04e9\u04e9 \u0431\u0430\u0440\u0434\u0430\u043c \u0437\u0430\u043d\u0433\u0430\u0430\u0441 \u0431\u043e\u043b\u0436 \u0431\u0443\u0441\u0434\u044b\u0433 \u0433\u043e\u043c\u0434\u043e\u043e\u0445\u043e\u0434 \u0431\u044d\u043b\u044d\u043d \u0431\u0430\u0439\u0432.\n\u0413\u044d\u0445\u0434\u044d\u044d 2 \u0422\u0438\u043c\u043e\u0442\u044b\u043d \u0437\u0430\u0445\u0438\u0434\u043b\u044b\u0433 \u0442\u04e9\u043b\u04e9\u0432\u0448\u0441\u04e9\u043d \u0438\u0442\u0433\u044d\u0433\u0447 \u041f\u0430\u0443\u043b \u0431\u0438\u0447\u0441\u044d\u043d.\n\u0422\u044d\u0440 \u0437\u0430\u043b\u0443\u0443 \u043d\u0430\u0441\u043d\u044b \u0445\u04af\u0441\u044d\u043b \u0442\u044d\u043c\u04af\u04af\u043b\u044d\u043b \u043d\u044c \u0445\u044d\u0440 \u0438\u0445 \u0445\u043e\u0440 \u0445\u04e9\u043d\u04e9\u04e9\u043b \u0443\u0447\u0440\u0443\u0443\u043b\u0441\u043d\u044b\u0433 \u043e\u0439\u043b\u0433\u043e\u0436 \u0431\u0430\u0439\u0433\u0430\u0430 \u0431\u04e9\u0433\u04e9\u04e9\u0434 \u0422\u0438\u043c\u043e\u0442\u043e\u0434 \u0442\u044d\u0434\u0433\u044d\u044d\u0440\u0438\u0439\u043d \u0442\u0430\u043b\u0430\u0430\u0440 \u0430\u043d\u0445\u0430\u0430\u0440\u0443\u0443\u043b\u0436 \u0431\u0430\u0439\u043d\u0430.\n\u041f\u0430\u0443\u043b \u044d\u043d\u044d \u0437\u0430\u0445\u0438\u0434\u043b\u044b\u0433 \u0431\u0438\u0447\u0438\u0436 \u0431\u0430\u0439\u0445 \u04af\u0435\u0434 \u0422\u0438\u043c\u043e\u0442 40 \u043e\u0440\u0447\u0438\u043c \u043d\u0430\u0441\u0442\u0430\u0439 \u0431\u0430\u0439\u0441\u0430\u043d \u0431\u0430\u0439\u0445.\n\u0413\u044d\u0445\u0434\u044d\u044d \u201d\u0437\u0430\u043b\u0443\u0443 \u043d\u0430\u0441\u043d\u044b \u0445\u04af\u0441\u044d\u043b \u0442\u044d\u043c\u04af\u04af\u043b\u044d\u043b\u201d \u0440\u04af\u04af \u0433\u04af\u0439\u0445\u0438\u0439\u043d \u0442\u0443\u043b\u0434 \u0437\u0430\u043b\u0443\u0443 \u0431\u0430\u0439\u0445 \u0430\u043b\u0431\u0430\u0433\u04af\u0439.\n\u0411\u0438 57 \u043d\u0430\u0441\u0442\u0430\u0439 \u0447 \u0437\u0430\u043b\u0443\u0443 \u043d\u0430\u0441\u043d\u044b \u0445\u04af\u0441\u044d\u043b \u0442\u044d\u043c\u04af\u04af\u043b\u043b\u044d\u044d\u0441\u044d\u044d \u0442\u0443\u0443\u0448\u0442\u0430\u0439 \u0437\u0443\u0433\u0442\u0430\u0436 \u0441\u0443\u0440\u0447 \u0431\u0430\u0439\u043d\u0430.\n\u041d\u0430\u0434\u0430\u0434 \u043a\u043e\u043b\u043b\u0435\u0436\u0438\u0439\u043d \u043d\u0430\u0434\u0442\u0430\u0439 \u0447\u0430\u0446\u0443\u0443 \u043d\u044d\u0433 \u043d\u0430\u0439\u0437 \u0431\u0438\u0439.\n\u0413\u044d\u0445\u0434\u044d\u044d \u0442\u044d\u0440 35 \u0436\u0438\u043b\u0438\u0439\u043d \u04e9\u043c\u043d\u04e9\u0445 \u0448\u0438\u0433\u044d\u044d \u043b \u0430\u043c\u044c\u0434\u0430\u0440\u0447 \u0431\u0430\u0439\u043d\u0430.\n\u0422\u04af\u04af\u043d\u0438\u0439 \u0430\u043c\u044c\u0434\u0440\u0430\u043b\u044b\u0433 \u0431\u0438\u0434\u043d\u0438\u0439 \u043a\u043e\u043b\u043b\u0435\u0436\u0438\u0439\u043d \u04af\u0435\u0438\u0439\u043d \u0437\u0430\u043b\u0443\u0443 \u043d\u0430\u0441\u043d\u044b \u0445\u04af\u0441\u044d\u043b \u0442\u044d\u043c\u04af\u04af\u043b\u044d\u043b \u0434\u0430\u0432\u0430\u043c\u0433\u0430\u0439\u043b\u0434\u0430\u0433.\n\u0411\u0438\u0434\u043d\u0438\u0439 \u043e\u043b\u043e\u043d\u0445\u044b\u043d \u043c\u044d\u0434\u044d\u0440\u0434\u044d\u0433 \u0437\u0430\u043b\u0443\u0443 \u043d\u0430\u0441\u043d\u044b \u0437\u0430\u0440\u0438\u043c \u0445\u04af\u0441\u044d\u043b \u0442\u044d\u043c\u04af\u04af\u043b\u043b\u0438\u0439\u0433 \u044d\u043d\u0434 \u043e\u0440\u0443\u0443\u043b\u0430\u0432.\n\n*   \u0422\u0430\u0430\u0448\u0430\u0430\u043b: \u0411\u044d\u043b\u0433\u0438\u0439\u043d \u043d\u04af\u0433\u044d\u043b \u0431\u043e\u043b \u0442\u0430\u0430\u0448\u0430\u0430\u043b\u044b\u043d \u043d\u04af\u0433\u043b\u0438\u0439\u043d \u043d\u0438\u0439\u0442\u043b\u044d\u0433 \u0436\u0438\u0448\u044d\u044d \u0431\u043e\u043b\u043e\u0432\u0447 \u0446\u043e\u0440\u044b\u043d \u0433\u0430\u043d\u0446 \u0436\u0438\u0448\u044d\u044d \u0431\u0438\u0448 \u044e\u043c.\n\u0411\u0443\u0441\u0430\u0434 \u043d\u04af\u0433\u044d\u043b\u0442 \u0442\u0430\u0430\u0448\u0430\u0430\u043b\u0434 \u0430\u0440\u0445\u0438, \u0445\u043e\u043e\u043b \u0445\u04af\u043d\u0441 \u0431\u043e\u043b\u043e\u043d \u043e\u043b\u043e\u043d \u0442\u04e9\u0440\u043b\u0438\u0439\u043d \u0437\u0443\u0433\u0430\u0430 \u0446\u044d\u043d\u0433\u044d\u043b \u043e\u0440\u0436 \u0431\u043e\u043b\u043d\u043e.\n\u042d\u0434\u0433\u044d\u044d\u0440 \u0437\u04af\u0439\u043b\u0441\u0438\u0439\u0433 \u0437\u04e9\u0432 \u0430\u0448\u0438\u0433\u043b\u0430\u0432\u0430\u043b \u0442\u0438\u0439\u043c \u0447 \u043c\u0443\u0443 \u0431\u0438\u0448.\n\u0416\u0438\u0448\u044d\u044d\u043b\u0431\u044d\u043b, \u0425\u0440\u0438\u0441\u0442\u0438\u0439\u043d \u0448\u0430\u0448\u043d\u044b \u0433\u044d\u0440\u043b\u044d\u043b\u0442\u0438\u0439\u043d \u0445\u04af\u0440\u044d\u044d\u043d\u0434 \u0441\u0435\u043a\u0441 \u0431\u043e\u043b \u0433\u0430\u0439\u0445\u0430\u043b\u0442\u0430\u0439 \u0431\u044d\u043b\u044d\u0433 \u044e\u043c.\n\u0413\u044d\u0445\u0434\u044d\u044d \u0431\u0438\u0434 \u0430\u043b\u0438\u0432\u0430\u0430 \u0437\u04af\u0439\u043b\u0438\u0439\u0433 \u0431\u0443\u0440\u0443\u0443\u0433\u0430\u0430\u0440 \u0430\u0448\u0438\u0433\u043b\u0430\u0445 \u04af\u0435\u0434 \u0442\u04af\u04af\u043d\u0434\u044d\u044d \u0430\u043c\u044c\u0434\u0440\u0430\u043b\u0434\u0430\u0430 \u0445\u04af\u0447 \u0447\u0430\u0434\u0430\u043b \u04e9\u0433\u0434\u04e9\u0433.\n\u0411\u0438\u0434 \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b \u0434\u044d\u0445 \u0445\u043e\u043e\u0441\u043e\u043d \u0437\u0430\u0439\u0433 \u0434\u04af\u04af\u0440\u0433\u044d\u0445\u0438\u0439\u043d \u0442\u0443\u043b\u0434 \u0411\u0443\u0440\u0445\u0430\u043d\u044b \u044f\u043c\u0430\u0440 \u043d\u044d\u0433\u044d\u043d \u0431\u044d\u043b\u0433\u0438\u0439\u0433 \u0430\u0448\u0438\u0433\u043b\u0430\u0445 \u04af\u0435\u0434 \u0442\u044d\u0440 \u0437\u04af\u0439\u043b \u0445\u0443\u0443\u0440\u0430\u043c\u0447 \u0431\u0443\u0440\u0445\u0430\u043d- \u0448\u04af\u0442\u044d\u044d\u043d \u0431\u043e\u043b\u0434\u043e\u0433.\n\n*   \u0425\u04af\u0447 \u0447\u0430\u0434\u0430\u043b: \u0411\u0438\u0434 \u0437\u0430\u043b\u0443\u0443 \u0431\u0430\u0439\u0445\u0434\u0430\u0430 \u0437\u0430\u0440\u0438\u043c\u0434\u0430\u0430 \u0445\u04af\u0447\u0433\u04af\u0439, \u0441\u0443\u043b \u0434\u043e\u0440\u043e\u0439 \u044d\u0441\u0432\u044d\u043b \u0447\u0430\u0434\u0432\u0430\u0440\u0433\u04af\u0439 \u043c\u044d\u0442 \u0441\u0430\u043d\u0430\u0433\u0434\u0434\u0430\u0433.\n\u0411\u0438 \u04e9\u0441\u0432\u04e9\u0440 \u043d\u0430\u0441\u0430\u043d\u0434\u0430\u0430 \u044d\u0434\u0433\u044d\u044d\u0440 \u043c\u044d\u0434\u0440\u044d\u043c\u0436\u04af\u04af\u0434\u0442\u044d\u0439 \u0442\u044d\u043c\u0446\u044d\u0436 \u0431\u0430\u0439\u0441\u0430\u043d.\n\u0417\u0430\u0440\u0438\u043c \u0445\u04af\u043c\u04af\u04af\u0441 \u0441\u0443\u043b \u0434\u043e\u0440\u043e\u0439 \u0431\u0430\u0439\u0434\u043b\u0430\u0430 \u043d\u0443\u0443\u0445\u044b\u043d \u0442\u0443\u043b\u0434 \u044d\u0440\u0445 \u043c\u044d\u0434\u043b\u0438\u0439\u0433 \u044d\u0440\u044d\u043b\u0445\u0438\u0439\u043b\u0434\u044d\u0433.\n\u0422\u044d\u0434 \u0445\u04af\u0447\u0442\u044d\u0439 \u04af\u0439\u043b\u0434\u044d\u043b \u0445\u0438\u0439\u0445 \u043d\u044c \u04e9\u04e9\u0440\u0441\u0434\u0438\u0439\u0433\u04e9\u04e9 \u0430\u044e\u0443\u043b\u0433\u04af\u0439 \u0433\u044d\u0436 \u043c\u044d\u0434\u0440\u044d\u0445\u044d\u0434 \u0442\u0443\u0441\u0430\u043b\u043d\u0430 \u0433\u044d\u0436 \u0431\u043e\u0434\u0434\u043e\u0433.\n\u0414\u044d\u044d\u0440\u044d\u043b\u0445\u044d\u0433\u0447 \u0445\u04af\u043d \u04af\u043d\u044d\u043d\u0434\u044d\u044d \u0445\u0430\u0440\u0430\u0433\u0434\u0430\u0436 \u0431\u0430\u0439\u0433\u0430\u0430 \u0448\u0438\u0433\u044d\u044d \u0442\u0438\u0439\u043c \u0447 \u0445\u0430\u0442\u0443\u0443 \u0431\u0438\u0448 \u0433\u044d\u0434\u0433\u0438\u0439\u0433 \u0442\u0430 \u043c\u044d\u0434\u044d\u0445 \u04af\u04af?\n\u0414\u044d\u044d\u0440\u044d\u043b\u0445\u044d\u0433\u0447 \u0433\u044d\u0434\u044d\u0433 \u043d\u044c \u0438\u0445\u044d\u0432\u0447\u043b\u044d\u043d \u0430\u043c\u044c\u0434\u0440\u0430\u043b\u0434\u0430\u0430 \u044f\u043c\u0430\u0440 \u043d\u044d\u0433\u044d\u043d \u0437\u04af\u0439\u043b\u0434 \u0445\u04af\u0447\u0433\u04af\u0439 \u043c\u044d\u0442 \u0441\u0430\u043d\u0430\u0433\u0434\u0434\u0430\u0433, \u0442\u0438\u0439\u043c\u044d\u044d\u0441 \u04e9\u04e9\u0440\u0438\u0439\u0433\u04e9\u04e9 \u0445\u04af\u0447\u0438\u0440\u0445\u044d\u0433 \u043c\u044d\u0442 \u043c\u044d\u0434\u0440\u04af\u04af\u043b\u044d\u0445\u0438\u0439\u043d \u0442\u0443\u043b\u0434 \u0431\u0443\u0441\u0430\u0434 \u0445\u04af\u043c\u04af\u04af\u0441\u0438\u0439\u0433 \u0433\u043e\u043c\u0434\u043e\u043e\u0434\u043e\u0433 \u0445\u04af\u043d\u0438\u0439\u0433 \u0445\u044d\u043b\u0434\u044d\u0433.\n\n*   \u0410\u043b\u0434\u0430\u0440 \u043d\u044d\u0440: \u042d\u043d\u044d \u0431\u043e\u043b \u043c\u0438\u043d\u0438\u0439 \u0430\u043c\u044c\u0434\u0440\u0430\u043b\u0434 \u0442\u043e\u0445\u0438\u043e\u043b\u0434\u0441\u043e\u043d \u0431\u0430\u0441 \u043d\u044d\u0433\u044d\u043d \u0445\u04af\u0447\u0442\u044d\u0439 \u0443\u0440\u0443\u0443 \u0442\u0430\u0442\u0430\u043b\u0442 \u0431\u0430\u0439\u0441\u0430\u043d.\n\u0425\u04af\u043c\u04af\u04af\u0441 \u043d\u0430\u0434\u0430\u0434 \u0434\u0443\u0440\u0442\u0430\u0439 \u0431\u043e\u043b \u0431\u0438 \u0438\u0445\u044d\u0432\u0447\u043b\u044d\u043d \u0441\u0430\u043d\u0430\u0430 \u0437\u043e\u0432\u0434\u043e\u0433.\n\u0411\u0438 \u0431\u0443\u0441\u0430\u0434 \u0445\u04af\u043c\u04af\u04af\u0441\u0438\u0439\u043d \u0441\u0430\u043d\u0430\u043b \u0431\u043e\u0434\u043b\u044b\u0433 \u0445\u044d\u0442\u044d\u0440\u0445\u0438\u0439 \u0438\u0445 \u0430\u043d\u0445\u0430\u0430\u0440\u0434\u0430\u0433.\n\u0427\u0438\u043d\u0438\u0439 \u0445\u0443\u0432\u044c\u0434 \u044f\u043c\u0430\u0440 \u0432\u044d?\n\u0422\u0430 \u0445\u04af\u043c\u04af\u04af\u0441\u0442 \u0442\u0430\u0430\u043b\u0430\u0433\u0434\u0430\u0445\u044b\u043d \u0442\u0443\u043b\u0434 \u0437\u0430\u043d \u0430\u0432\u0438\u0440 \u044d\u0441\u0432\u044d\u043b \u0433\u0430\u0434\u0430\u0430\u0434 \u0442\u04e9\u0440\u0445\u04e9\u04e9 \u04e9\u04e9\u0440\u0447\u0438\u043b\u0434\u04e9\u0433 \u04af\u04af?\n\u0422\u0430\u0442\u0433\u0430\u043b\u0437\u0430\u0445\u0430\u0430\u0441 \u0437\u0430\u0439\u043b\u0441\u0445\u0438\u0439\u0445\u0438\u0439\u043d \u0442\u0443\u043b\u0434 \u0442\u043e\u0434\u043e\u0440\u0445\u043e\u0439 \u0431\u0430\u0439\u0434\u043b\u0430\u0430\u0440 \u0431\u0438\u0435\u044d \u0430\u0432\u0447 \u044f\u0432\u0430\u0445 \u044d\u0441\u0432\u044d\u043b \u0445\u0430\u0440\u0430\u0433\u0434\u0430\u0445 \u0451\u0441\u0442\u043e\u0439 \u0433\u044d\u0436 \u0442\u0430 \u0431\u043e\u0434\u043e\u0436 \u0431\u0430\u0439\u043d\u0430 \u0443\u0443?\n\n*   \u042d\u0434 \u0445\u04e9\u0440\u04e9\u043d\u0433\u04e9: \u041c\u04e9\u043d\u0433\u04e9 \u0431\u043e\u043b\u043e\u043d \u044d\u0434 \u0445\u04e9\u0440\u04e9\u043d\u0433\u04e9\u0434 \u0434\u0443\u0440\u043b\u0430\u0445 \u043d\u044c \u0431\u0438\u0434\u043d\u0438\u0439 \u0438\u0445\u044d\u043d\u0445\u0438\u0439\u043d \u0445\u0443\u0432\u044c\u0434 \u0430\u0441\u0443\u0443\u0434\u0430\u043b \u044e\u043c.\n\u0411\u0438\u0434 \u0438\u043b\u04af\u04af \u0438\u0445 \u0437\u04af\u0439\u043b\u0442\u044d\u0439 \u0431\u0430\u0439\u0445\u044b\u043d \u0430\u044e\u0443\u043b\u0433\u04af\u0439 \u0431\u0430\u0439\u0434\u0430\u043b, \u0442\u0430\u0432 \u0442\u0443\u0445\u044b\u0433 \u0445\u04af\u0441\u0447 \u0431\u0430\u0439\u043d\u0430.\n\u042d\u043d\u044d \u043d\u044c \u0438\u0442\u0433\u044d\u043b\u0433\u04af\u0439 \u0431\u0430\u0439\u0434\u043b\u044b\u0433 \u0445\u0430\u0440\u0443\u0443\u043b\u0436 \u0431\u0430\u0439\u043d\u0430.\n\u0411\u0443\u0440\u0445\u0430\u043d \u0431\u0438\u0434\u043d\u0438\u0439 \u0445\u043e\u0440\u0433\u043e\u0434\u043e\u0445 \u0433\u0430\u0437\u0430\u0440, \u0446\u0430\u0439\u0437, \u0431\u0438\u0434\u043d\u0438\u0439 \u0445\u0430\u043d\u0433\u0430\u043d \u043d\u0438\u0439\u043b\u04af\u04af\u043b\u044d\u0433\u0447 \u0433\u044d\u0434\u0433\u0438\u0439\u0433 \u0431\u0438\u0434\u043d\u044d\u044d\u0441 \u043e\u0439\u043b\u0433\u043e\u043e\u0441\u043e\u0439 \u0433\u044d\u0436 \u0445\u04af\u0441\u0434\u044d\u0433.\n\u041c\u0430\u0442\u0435\u0440\u0438\u0430\u043b\u043b\u0430\u0433 \u0437\u04af\u0439\u043b\u0441 \u0430\u0437 \u0436\u0430\u0440\u0433\u0430\u043b\u044b\u0433 \u0430\u043c\u043b\u0430\u0434\u0430\u0433 \u0447 \u0445\u044d\u0437\u044d\u044d \u0447 \u0430\u043c\u043b\u0430\u043b\u0442\u0430\u0430 \u0431\u0438\u0435\u043b\u04af\u04af\u043b\u0436 \u0447\u0430\u0434\u0430\u0445\u0433\u04af\u0439.\n\u0423\u0447\u0438\u0440 \u043d\u044c \u0431\u0438\u0434\u043d\u0438\u0439 \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b \u04af\u0440\u0433\u044d\u043b\u0436 \u0438\u043b\u04af\u04af \u0438\u0445\u0438\u0439\u0433 \u0445\u04af\u0441\u044d\u0445 \u0431\u043e\u043b\u043d\u043e.\n\n*   \u0411\u0430\u0440\u0434\u0430\u043c\u043d\u0430\u043b: \u042d\u043d\u044d \u0431\u043e\u043b \u04af\u043d\u044d\u043d\u0434\u044d\u044d \u0431\u0443\u0441\u0430\u0434 \u0431\u04af\u0445 \u043d\u04af\u0433\u043b\u0438\u0439\u043d \u0446\u0430\u0430\u043d\u0430 \u043d\u0443\u0443\u0433\u0434\u0430\u0436 \u0431\u0443\u0439 \u043d\u04af\u0433\u044d\u043b \u044e\u043c.\n\u0411\u0430\u0440\u0434\u0430\u043c\u043d\u0430\u043b \u0433\u044d\u0434\u044d\u0433 \u0431\u043e\u043b \u0431\u0438 \u044d\u0434 \u0445\u04e9\u0440\u04e9\u043d\u0433\u04e9, \u044d\u0440\u0445 \u043c\u044d\u0434\u044d\u043b, \u0442\u0430\u0430\u0448\u0430\u0430\u043b, \u0430\u043b\u0434\u0430\u0440 \u043d\u044d\u0440\u0438\u0439\u0433 \u0445\u04af\u0440\u0442\u044d\u0445 \u0451\u0441\u0442\u043e\u0439 \u0433\u044d\u0441\u044d\u043d \u0438\u0442\u0433\u044d\u043b \u04af\u043d\u044d\u043c\u0448\u0438\u043b \u044e\u043c.\n\u042f\u0430\u0433\u0430\u0430\u0434? \u0423\u0447\u0438\u0440 \u043d\u044c \u0431\u0438 \u043e\u043d\u0446\u0433\u043e\u0439.\n\u0411\u0430\u0440\u0434\u0430\u043c\u043d\u0430\u043b \u0431\u0438\u0434\u044d\u043d\u0434 \u0445\u0443\u0434\u0430\u043b \u0448\u0438\u0432\u043d\u044d\u0436, \u0438\u043d\u0433\u044d\u0436 \u0445\u044d\u043b\u0434\u044d\u0433:\n\u201d\u0417\u04af\u0433\u044d\u044d\u0440 \u0434\u044d\u044d, \u0447\u0438 \u04af\u04af\u043d\u0438\u0439\u0433 \u0445\u0438\u0439\u0436 \u0447\u0430\u0434\u043d\u0430- \u0427\u0438 \u04af\u04af\u043d\u0438\u0439\u0433 \u0445\u04af\u0440\u0442\u044d\u0445 \u0451\u0441\u0442\u043e\u0439.\u201d\n\u0417\u0430\u0440 \u0441\u0443\u0440\u0442\u0430\u043b\u0447\u0438\u043b\u0433\u0430\u0430\u043d\u044b \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u0443\u0434 \u0431\u0438\u0434\u044d\u043d\u0434 \u0447 \u043c\u04e9\u043d \u0430\u0434\u0438\u043b \u0437\u04af\u0439\u043b \u0445\u044d\u043b\u0434\u044d\u0433.\n\u201d\u0427\u0438 \u04af\u04af\u043d\u0438\u0439\u0433 \u0445\u04af\u0440\u0442\u044d\u0445 \u044d\u0440\u0445\u0442\u044d\u0439... \u0417\u0430, \u0445\u0443\u0434\u0430\u043b\u0434\u0430\u0436 \u0430\u0432.\u201d\n\u041c\u0430\u0433\u0430\u0434\u0433\u04af\u0439 \u0434\u0430\u0445\u0438\u0430\u0434 \u0445\u0443\u0434\u0430\u043b\u0434\u0430\u0436 \u0430\u0432, \u0437\u04af\u0433\u044d\u044d\u0440 \u0434\u044d\u044d.\u201d\n\u0422\u0438\u0439\u043c \u0443\u0447\u0440\u0430\u0430\u0441 \u0431\u0438\u0434 \u0438\u0439\u043c\u044d\u0440\u0445\u04af\u04af \u043e\u043b\u043e\u043d \u0437\u0430\u0440 \u0441\u0443\u0440\u0442\u0430\u043b\u0447\u0438\u043b\u0433\u0430\u0430\u0433 \u0445\u0430\u0440\u0434\u0430\u0433, \u0443\u0447\u0438\u0440 \u043d\u044c \u0431\u0438\u0434\u043d\u0438\u0439 \u0431\u0430\u0440\u0434\u0430\u043c \u0437\u0430\u043d \u04af\u043d\u044d\u043d\u0434\u044d\u044d \u044d\u0434\u0433\u044d\u044d\u0440 \u0437\u04af\u0439\u043b\u0434 \u0438\u0442\u0433\u044d\u0445\u0438\u0439\u0433 \u0445\u04af\u0441\u0434\u044d\u0433.\n\n\u041d\u0430\u0439\u0437\u0443\u0443\u0434 \u0430\u0430, \u0442\u0430 \u043d\u0430\u0440\u0430\u0430\u0441 \u043d\u044d\u0433 \u0430\u0441\u0443\u0443\u043b\u0442 \u0430\u0441\u0443\u0443\u0436 \u0431\u043e\u043b\u043e\u0445 \u0443\u0443?\n\u042d\u0434\u0433\u044d\u044d\u0440 \u0442\u0430\u0432\u0430\u043d \u0437\u04af\u0439\u043b\u0438\u0439\u043d \u0430\u043b\u044c \u043d\u044c \u0442\u0430\u043d\u0434 \u0442\u0430\u043d\u0438\u043b \u0441\u043e\u043d\u0441\u043e\u0433\u0434\u043e\u0436 \u0431\u0430\u0439\u043d\u0430 \u0432\u044d?\n\u0422\u0430 \u0431\u0430\u0440\u0434\u0430\u043c\u043d\u0430\u043b, \u044d\u0434 \u0445\u04e9\u0440\u04e9\u043d\u0433\u04e9, \u044d\u0440\u0445 \u043c\u044d\u0434\u044d\u043b, \u0437\u0443\u0433\u0430\u0430 \u0446\u044d\u043d\u0433\u044d\u043b \u044d\u0441\u0432\u044d\u043b \u0430\u043b\u0434\u0430\u0440 \u043d\u044d\u0440\u0438\u0439\u0433 \u0445\u04e9\u04e9\u0446\u04e9\u043b\u0434\u04e9\u0436 \u0431\u0430\u0439\u043d\u0430 \u0443\u0443?\n\u042d\u0441\u0432\u044d\u043b \u044d\u043d\u044d \u043d\u044c \u0442\u0430\u043d\u044b\u0433 \u0411\u0443\u0440\u0445\u0430\u043d\u0430\u0430\u0441 \u0445\u043e\u043b\u0434\u0443\u0443\u043b\u0434\u0430\u0433 \u04e9\u04e9\u0440 \u0437\u04af\u0439\u043b \u0431\u0430\u0439\u0436 \u0431\u043e\u043b\u043e\u0445 \u0443\u0443?\n\u04e8\u043d\u04e9\u04e9\u0434\u04e9\u0440 \u0447\u0438\u043d\u0438\u0439 \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b \u0445\u0430\u0430\u043d\u0430 \u0431\u0430\u0439\u043d\u0430, \u0447\u0438 \u0445\u0430\u0430\u0448\u0430\u0430 \u044f\u0432\u0436 \u0431\u0430\u0439\u043d\u0430 \u0432\u044d?\n\u0411\u0443\u0440\u0445\u0430\u043d \u0410\u0434\u0430\u043c\u044b\u0433 \u0436\u0438\u043c\u0441 \u0438\u0434\u0441\u044d\u043d\u0438\u0439 \u0434\u0430\u0440\u0430\u0430 \u0446\u044d\u0446\u044d\u0440\u043b\u044d\u0433\u0442 \u044e\u0443 \u0433\u044d\u0436 \u0430\u0441\u0443\u0443\u0441\u043d\u044b\u0433 \u0447\u0438 \u0441\u0430\u043d\u0430\u0436 \u0431\u0430\u0439\u043d\u0430 \u0443\u0443?\n\u0410\u0434\u0430\u043c \u0415\u0432\u0430 \u0445\u043e\u0451\u0440 \u043d\u0443\u0443\u0433\u0434\u0430\u0436 \u0431\u0430\u0439\u0441\u0430\u043d \u0431\u04e9\u0433\u04e9\u04e9\u0434 \u0411\u0443\u0440\u0445\u0430\u043d \u201d\u0410\u0434\u0430\u043c \u0430\u0430, \u0447\u0438 \u0445\u0430\u0430\u043d\u0430 \u0431\u0430\u0439\u043d\u0430?\u201d \u0433\u044d\u0436 \u0430\u0441\u0443\u0443\u0432.\n\u0411\u0443\u0440\u0445\u0430\u043d \u04e9\u043d\u04e9\u04e9\u0434\u04e9\u0440 \u0434\u044d\u043b\u0445\u0438\u0439 \u0434\u044d\u044d\u0440\u0445 \u0431\u04af\u0445 \u0445\u04af\u043d\u044d\u044d\u0441 \u044f\u0433 \u0430\u0434\u0438\u043b\u0445\u0430\u043d \u0437\u04af\u0439\u043b\u0438\u0439\u0433 \u0445\u04af\u0441\u044d\u0436 \u0431\u0430\u0439\u043d\u0430.\n\u0427\u0438 \u0445\u0430\u0430\u043d\u0430 \u0431\u0430\u0439\u043d\u0430?\n\u0422\u044d\u0440 \u0447\u0430\u043c\u0430\u0439\u0433 \u0431\u0438\u0435 \u043c\u0430\u0445\u0431\u043e\u0434\u0438\u0439\u043d \u0445\u0443\u0432\u044c\u0434 \u0445\u0430\u0430\u043d\u0430 \u0431\u0430\u0439\u0433\u0430\u0430\u0433 \u0447\u0438\u043d\u044c \u0430\u0441\u0443\u0443\u0445\u0433\u04af\u0439 \u0431\u0430\u0439\u043d\u0430.\n\u0422\u044d\u0440 \u201d\u0417\u04af\u0440\u0445 \u0447\u0438\u043d\u044c \u0445\u0430\u0430\u043d\u0430 \u0431\u0430\u0439\u043d\u0430?\u201d \u0433\u044d\u0436 \u0430\u0441\u0443\u0443\u0436 \u0431\u0430\u0439\u043d\u0430.\n\u0423\u0447\u0438\u0440 \u043d\u044c \u0431\u0438\u0434\u043d\u0438\u0439 \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b \u0431\u043e\u043b \u0431\u0438\u0434\u043d\u0438\u0439 \u0445\u0430\u043c\u0433\u0438\u0439\u043d \u0438\u0445 \u04af\u043d\u044d\u043b\u0434\u044d\u0433 \u0437\u04af\u0439\u043b \u0440\u04af\u04af \u0445\u04e9\u0442\u04e9\u043b\u0434\u04e9\u0433 \u043b\u0443\u0443\u0436\u0438\u043d \u0448\u0438\u0433 \u044e\u043c.\n\u041d\u04af\u0433\u044d\u043b \u0431\u043e\u043b \u0437\u0430\u043b\u044c\u0442\u0430\u0439 \u0443\u0447\u0440\u0430\u0430\u0441 \u0431\u0438\u0434 \u0442\u04e9\u04e9\u0440\u04e9\u043b\u0434\u04e9\u0436, \u04af\u04af\u043d\u0438\u0439\u0433\u044d\u044d \u0447 \u043c\u044d\u0434\u0434\u044d\u0433\u0433\u04af\u0439.\n\u0411\u0438\u0434\u043d\u0438\u0439 \u0434\u043e\u0442\u043e\u0440 \u044e\u0443 \u0431\u043e\u043b\u0436 \u0431\u0430\u0439\u0433\u0430\u0430\u0433 \u0445\u0430\u0440\u0430\u0445\u044b\u043d \u0442\u0443\u043b\u0434 \u0431\u0438\u0434\u044d\u043d\u0434 \u0411\u0443\u0440\u0445\u0430\u043d\u044b \u0442\u0443\u0441\u043b\u0430\u043c\u0436 \u0445\u044d\u0440\u044d\u0433\u0442\u044d\u0439.\n\u0414\u0443\u0443\u043b\u0430\u043b 139:23\u201324-\u0438\u0439\u0433 \u0437\u0430\u043b\u0431\u0438\u0440\u0430\u043b \u0431\u043e\u043b\u0433\u043e\u043d \u0445\u0430\u043c\u0442\u0434\u0430\u0430 \u0443\u043d\u0448\u0438\u0446\u0433\u0430\u0430\u044f:\n\u0411\u04ae\u0413\u0414: 23 \u201c\u04e8\u04e9, \u0411\u0443\u0440\u0445\u0430\u043d \u043c\u0438\u043d\u044c, \u043d\u0430\u043c\u0430\u0439\u0433 \u0448\u0430\u043b\u0433\u0430\u0436, \u0437\u04af\u0440\u0445\u0438\u0439\u0433 \u043c\u0438\u043d\u044c \u043c\u044d\u0434\u044d\u044d\u0447!\n\u041d\u0430\u043c\u0430\u0439\u0433 \u0441\u043e\u0440\u044c\u0436 \u04af\u0437\u044d\u044d\u0434, \u043c\u0438\u043d\u0438\u0439 \u0431\u043e\u0434\u043b\u044b\u0433 \u043c\u044d\u0434!\n24 \u041d\u0430\u0434\u0430\u0434 \u044f\u043c\u0430\u0440 \u043d\u044d\u0433\u044d\u043d \u0433\u0430\u0439 \u0437\u043e\u0432\u043b\u043e\u043d \u0431\u0430\u0439\u0433\u0430\u0430 \u044d\u0441\u044d\u0445\u0438\u0439\u0433 \u0445\u0430\u0440 \u0434\u0430\u0430.\n\u043c\u04e9\u043d \u043d\u0430\u043c\u0430\u0439\u0433 \u043c\u04e9\u043d\u0445\u0438\u0439\u043d \u0437\u0430\u043c\u0434 \u0445\u04e9\u0442\u043b\u04e9\u04e9\u0447!\n\n\u0411\u0443\u0440\u0445\u0430\u043d\u044b \u0442\u0443\u0441\u043b\u0430\u043c\u0436\u0433\u04af\u0439\u0433\u044d\u044d\u0440 \u0431\u0438\u0434 \u201d\u043c\u04e9\u043d\u0445\u0438\u0439\u043d \u0437\u0430\u043c\u0430\u0430\u0440\u201d \u0430\u043b\u0445\u0430\u0445\u0433\u04af\u0439.\n\u0411\u0438\u0434 \u0411\u0443\u0440\u0445\u0430\u043d\u044b \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b\u044d\u044d\u0441 \u0445\u043e\u043b\u0434\u0443\u0443\u043b\u0430\u0445 \u0437\u04af\u0439\u043b\u0441\u0438\u0439\u0433 \u0445\u04e9\u04e9\u0436, \u0431\u0443\u0440\u0443\u0443 \u0447\u0438\u0433\u043b\u044d\u043b\u0434 \u0433\u04af\u0439\u0445 \u0431\u043e\u043b\u043d\u043e.\n\u0413\u044d\u0445\u0434\u044d\u044d \u0411\u0443\u0440\u0445\u0430\u043d \u043c\u0430\u0448 \u0441\u0430\u0439\u043d \u0443\u0447\u0440\u0430\u0430\u0441 \u0431\u0438\u0434\u043d\u0438\u0439\u0433 \u0437\u04af\u0433\u044d\u044d\u0440 \u043b \u0442\u044d\u043d\u04af\u04af\u0447\u0438\u043b\u0436, \u0442\u04e9\u04e9\u0440\u04e9\u0445\u0438\u0439\u0433 \u0445\u0430\u0440\u0430\u0430\u0434 \u0441\u0443\u0443\u0434\u0430\u0433\u0433\u04af\u0439.\n\u04ae\u04af\u043d\u0438\u0439 \u043e\u0440\u043e\u043d\u0434 \u0442\u044d\u0440 \u0442\u04e9\u04e9\u0440\u0441\u04e9\u043d \u0445\u043e\u043d\u0438\u043e \u0445\u0430\u0439\u0436 \u043e\u043b\u0434\u043e\u0433.\n\u0422\u044d\u0440 \u0431\u0438\u0434\u044d\u043d \u0434\u044d\u044d\u0440 \u0438\u0440\u0436, \u0437\u0443\u0433\u0442\u0430\u0445, \u0430\u0432\u0440\u0430\u0445 \u0437\u0430\u043c\u044b\u0433 \u0441\u0430\u043d\u0430\u043b \u0431\u043e\u043b\u0433\u043e\u0434\u043e\u0433.\n2 \u0422\u0438\u043c\u043e\u0442 2:25b-26-\u0433 \u0434\u0430\u0445\u0438\u043d \u0445\u0430\u0440\u0430\u0430\u0440\u0430\u0439:\n25\u0431 \u201c\u0411\u0443\u0440\u0445\u0430\u043d \u0442\u044d\u0434\u044d\u043d\u0434 \u04af\u043d\u044d\u043d\u0438\u0439 \u043c\u044d\u0434\u043b\u044d\u0433\u0442 \u0445\u04af\u0440\u0433\u044d\u0445 \u0433\u044d\u043c\u0448\u043b\u0438\u0439\u0433 \u04e9\u0433\u0447 \u043c\u0430\u0433\u0430\u0434\u0433\u04af\u0439,\n26 \u0422\u044d\u0434 \u0443\u0445\u0430\u0430\u043d \u043e\u0440\u0436, \u0447\u04e9\u0442\u0433\u04e9\u0440\u0438\u0439\u043d \u0445\u04af\u0441\u043b\u0438\u0439\u0433 \u0431\u0438\u0435\u043b\u04af\u04af\u043b\u044d\u0445\u044d\u044d\u0440 \u0442\u04af\u04af\u043d\u0434 \u0431\u0430\u0440\u0438\u0433\u0434\u0441\u0430\u043d\u044b \u0434\u0430\u0440\u0430\u0430 \u0442\u04af\u04af\u043d\u0438\u0439 \u0443\u0440\u0445\u0438\u043d\u0430\u0430\u0441 \u0437\u0443\u0433\u0442\u0430\u0436 \u043c\u0430\u0433\u0430\u0434\u0433\u04af\u0439 \u044e\u043c.\n\n\u0422\u0430 \u043d\u04af\u0433\u044d\u043b \u0431\u043e\u043b\u043e\u043d \u0447\u04e9\u0442\u0433\u04e9\u0440\u0442 \u0443\u0440\u0445\u0438\u0434\u0441\u0430\u043d \u04af\u0435\u0434\u044d\u044d \u0431\u04af\u0440\u044d\u043d \u044d\u0440\u0445 \u0447\u04e9\u043b\u04e9\u04e9\u0442\u044d\u0439 \u0431\u0430\u0439\u0445 \u0431\u043e\u043b\u043e\u043c\u0436\u0442\u043e\u0439 \u0433\u044d\u0434\u0433\u0438\u0439\u0433 \u043c\u044d\u0434\u044d\u0445 \u04af\u04af?\n\u041d\u04af\u0433\u044d\u043b \u043d\u044c \u044d\u0440\u0445 \u0447\u04e9\u043b\u04e9\u04e9 \u043c\u044d\u0442 \u0441\u0430\u043d\u0430\u0433\u0434\u0434\u0430\u0433 \u0447 \u044d\u0441\u0440\u044d\u0433\u044d\u044d\u0440\u044d\u044d \u044e\u043c.\n\u0423\u0440\u0445\u0438 \u0438\u0439\u043c\u044d\u0440\u0445\u04af\u04af \u0445\u0430\u0440\u0430\u0433\u0434\u0430\u0436 \u0431\u0430\u0439\u043d\u0430.\n\u042d\u043d\u044d \u0431\u043e\u043b \u0437\u0430\u043c\u0430\u0430\u0440 \u0447\u04e9\u043b\u04e9\u04e9\u0442\u044d\u0439 \u0433\u04af\u0439\u0436 \u044f\u0432\u0430\u0430\u0434 \u0433\u044d\u043d\u044d\u0442 \u0430\u044e\u0443\u043b\u0434 \u043e\u0440\u0441\u043e\u043d \u0430\u043c\u044c\u0442\u043d\u044b\u0433 \u0431\u0430\u0440\u044c\u0436 \u0430\u0432\u0434\u0430\u0433 \u0443\u0440\u0445\u0438 \u044e\u043c.\n\u0421\u0430\u0442\u0430\u043d \u0431\u0438\u0434\u043d\u0438\u0439\u0433 \u043c\u044d\u0445\u044d\u043b\u0436, \u0443\u0440\u0445\u0438\u0434\u0430\u0445\u044b\u043d \u0442\u0443\u043b\u0434 \u043c\u0430\u0440\u0430\u0444\u043e\u043d\u044b \u0437\u0430\u043c \u0434\u044d\u044d\u0440 \u0442\u044d\u043c\u0434\u044d\u0433 \u043c\u044d\u0442 \u0445\u0443\u0434\u0430\u043b \u0445\u0443\u0443\u0440\u043c\u0430\u0433 \u0437\u04af\u0439\u043b\u0441\u0438\u0439\u0433 \u0431\u0430\u0439\u0440\u043b\u0443\u0443\u043b\u0434\u0430\u0433.\n\u0421\u0430\u0442\u0430\u043d \u0431\u0438\u0434\u043d\u0438\u0439\u0433 \u0422\u0430\u0430\u0448\u0430\u0430\u043b, \u042d\u0440\u0445 \u043c\u044d\u0434\u044d\u043b, \u0410\u043b\u0434\u0430\u0440 \u043d\u044d\u0440, \u042d\u0434 \u0445\u04e9\u0440\u04e9\u043d\u0433\u04e9, \u0411\u0430\u0440\u0434\u0430\u043c\u043d\u0430\u043b\u044b\u043d \u0430\u0440\u0430\u0430\u0441 \u0433\u04af\u0439\u0445\u0438\u0439\u0433 \u0445\u04af\u0441\u0434\u044d\u0433.\n\u042d\u0434\u0433\u044d\u044d\u0440 \u0448\u04af\u0442\u044d\u044d\u043d\u04af\u04af\u0434 \u0431\u0438\u0434\u044d\u043d\u0434 \u044d\u0440\u0445 \u0447\u04e9\u043b\u04e9\u04e9\u0433 \u0430\u043c\u043b\u0430\u0434\u0430\u0433 \u0431\u04e9\u0433\u04e9\u04e9\u0434 \u044d\u0440\u0445 \u0447\u04e9\u043b\u04e9\u04e9 \u0431\u043e\u043b \u0431\u0438\u0434\u043d\u0438\u0439 \u043c\u0430\u0448 \u0438\u0445 \u0445\u04af\u0441\u0447 \u0431\u0443\u0439 \u0437\u04af\u0439\u043b \u044e\u043c.\n\u0425\u0430\u0440\u0430\u043c\u0441\u0430\u043b\u0442\u0430\u0439 \u043d\u044c \u0431\u0438\u0434 \u0438\u0439\u043c\u044d\u0440\u0445\u04af\u04af \u0437\u04af\u0439\u043b\u0441 \u0431\u0438\u0434\u043d\u0438\u0439\u0433 \u0441\u044d\u0442\u0433\u044d\u043b \u0445\u0430\u043d\u0433\u0430\u043b\u0443\u0443\u043d, \u0430\u044e\u0443\u043b\u0433\u04af\u0439, \u0430\u0437 \u0436\u0430\u0440\u0433\u0430\u043b\u0442\u0430\u0439 \u0431\u0430\u0439\u0445\u0430\u0434 \u0442\u0443\u0441\u0430\u043b\u0434\u0430\u0433 \u0433\u044d\u0436 \u04af\u0437\u0434\u044d\u0433.\n\u0413\u044d\u0445\u0434\u044d\u044d \u044d\u0434\u0433\u044d\u044d\u0440 \u0448\u04af\u0442\u044d\u044d\u043d\u04af\u04af\u0434 \u0431\u043e\u043b \u0431\u0438\u0434\u043d\u0438\u0439\u0433 \u0411\u0443\u0440\u0445\u0430\u043d\u0430\u0430\u0441 \u0431\u043e\u043b\u043e\u043d \u0436\u0438\u043d\u0445\u044d\u043d\u044d \u0430\u043c\u044c\u0434\u0440\u0430\u043b\u044b\u043d \u0437\u0430\u043c\u0430\u0430\u0441 \u0445\u043e\u043b\u0434\u0443\u0443\u043b\u0434\u0430\u0433 \u0443\u0440\u0445\u0438 \u044e\u043c.\n\u0421\u0430\u0442\u0430\u043d \u0430\u043c\u044c\u0434\u0440\u0430\u043b\u044b\u043d \u0437\u0430\u043c\u044b\u0433 \u0431\u0438\u0434\u043d\u044d\u044d\u0441 \u043d\u0443\u0443\u0445\u044b\u0433 \u0445\u04af\u0441\u0434\u044d\u0433 \u0431\u04e9\u0433\u04e9\u04e9\u0434 \u0438\u043d\u0433\u044d\u0436 \u0445\u044d\u043b\u0434\u044d\u0433:\n\u201d\u042f\u043b\u0430\u043b\u0442, \u0430\u0437 \u0436\u0430\u0440\u0433\u0430\u043b\u044b\u043d \u0442\u04e9\u043b\u04e9\u04e9 \u044d\u043d\u044d \u0437\u0430\u043c\u0430\u0430\u0440 \u044f\u0432!\u201d\n\u0422\u0438\u0439\u043c \u044d\u044d, \u044d\u043d\u044d \u0431\u043e\u043b \u0437\u0430\u043c! \u041d\u0430\u043c\u0430\u0439\u0433 \u0434\u0430\u0433\u0430!\n\n\u0422\u044d\u0433\u044d\u0445\u044d\u044d\u0440 \u0430\u043c\u044c\u0442\u0430\u043d \u0438\u0439\u043c \u0445\u0430\u0432\u0445\u043d\u0430\u0430\u0441 \u044f\u0430\u0436 \u043c\u0443\u043b\u0442\u0430\u0440\u0447 \u0447\u0430\u0434\u0430\u0445 \u0432\u044d?\n\u0422\u044d\u0440 \u04e9\u04e9\u0440\u04e9\u04e9 \u0445\u0438\u0439\u0436 \u0447\u0430\u0434\u0430\u0445 \u0437\u04af\u0439\u043b \u043c\u04e9\u043d \u04af\u04af?\n\u04ae\u0433\u04af\u0439 \u044d\u044d, \u0442\u0443\u0443\u043b\u0430\u0439 \u0430\u0440\u0447\u0430\u0430\u0433\u04af\u0439 \u0431\u0430\u0439\u043d\u0430.\n\u0422\u04af\u04af\u043d\u0438\u0439\u0433 \u0445\u0430\u0432\u0445\u043d\u0430\u0430\u0441 \u0433\u0430\u0440\u0433\u0430\u0445 \u0438\u043b\u04af\u04af \u0443\u0445\u0430\u0430\u043b\u0430\u0433, \u0445\u04af\u0447\u0442\u044d\u0439 \u0445\u04af\u043d \u0445\u044d\u0440\u044d\u0433\u0442\u044d\u0439.\n\u0411\u0438\u0434\u043d\u0438\u0439\u0433 \u0430\u0432\u0440\u0430\u0445\u044b\u043d \u0442\u0443\u043b\u0434 \u0431\u0438\u0434\u044d\u043d\u0434 \u0438\u043b\u04af\u04af \u0443\u0445\u0430\u0430\u043b\u0430\u0433, \u0438\u043b\u04af\u04af \u0445\u04af\u0447\u0442\u044d\u0439 \u0445\u04af\u043d \u0445\u044d\u0440\u044d\u0433\u0442\u044d\u0439.\n\u042d\u043d\u044d \u0431\u043e\u043b \u044d\u043d\u044d \u0448\u04af\u043b\u0433\u0438\u0439\u043d \u0442\u0430\u043b\u0430\u0430\u0440 \u0442\u0430 \u0431\u04af\u0445\u044d\u043d\u0434 \u0445\u044d\u043b\u044d\u0445\u0438\u0439\u0433 \u0445\u04af\u0441\u0441\u044d\u043d \u0445\u0430\u043c\u0433\u0438\u0439\u043d \u0447\u0443\u0445\u0430\u043b \u0437\u04af\u0439\u043b \u044e\u043c.\n\u0411\u0438\u0434 \u04e9\u04e9\u0440\u0441\u0434\u0438\u0439\u0433\u04e9\u04e9 \u0430\u0432\u0430\u0440\u0447 \u0447\u0430\u0434\u0430\u0445\u0433\u04af\u0439, \u0442\u044d\u0440 \u0447 \u0431\u0430\u0439\u0442\u0443\u0433\u0430\u0439 \u0411\u0443\u0440\u0445\u0430\u043d\u0434 \u0445\u0430\u043d\u0434\u0430\u0436 \u0447\u0430\u0434\u0430\u0445\u0433\u04af\u0439 \u0442\u0443\u043b \u0431\u0438\u0434\u044d\u043d\u0434 \u0410\u0432\u0440\u0430\u0433\u0447 \u0445\u044d\u0440\u044d\u0433\u0442\u044d\u0439.\n\u0421\u04af\u043d\u0441\u043b\u044d\u0433\u044d\u044d\u0440 \u04af\u0445\u0441\u044d\u043d \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b \u0430\u043c\u044c\u0434\u0440\u0430\u043b\u044b\u0433 \u0441\u043e\u043d\u0433\u043e\u0436 \u0447\u0430\u0434\u0430\u0445\u0433\u04af\u0439.\n25-\u0440 \u0437\u04af\u0439\u043b\u0434 \u044e\u0443 \u0433\u044d\u0436 \u0445\u044d\u043b\u0441\u043d\u0438\u0439\u0433 \u0445\u0430\u0440\u0430\u0430\u0440\u0430\u0439:\n\u201d\u0411\u0443\u0440\u0445\u0430\u043d \u0442\u044d\u0434\u044d\u043d\u0434 \u0433\u044d\u043c\u0448\u043b\u0438\u0439\u0433 \u043d\u044c \u04e9\u0433\u0447 \u043c\u0430\u0433\u0430\u0434\u0433\u04af\u0439.\u201d\n\n\u0422\u044d\u0442\u0433\u044d\u043b\u044d\u0433 \u0431\u043e\u043b \u04af\u043d\u044d\u0433\u04af\u0439 \u0431\u044d\u043b\u044d\u0433 \u044e\u043c.\n\u0411\u0443\u0440\u0445\u0430\u043d \u043d\u0430\u0434\u0430\u0434 30 \u0436\u0438\u043b\u0438\u0439\u043d \u04e9\u043c\u043d\u04e9 \u0433\u044d\u043c\u0448\u043b\u0438\u0439\u043d \u0431\u044d\u043b\u0433\u0438\u0439\u0433 \u04e9\u0433\u0441\u04e9\u043d.\n\u0411\u0438 10 \u0436\u0438\u043b\u0438\u0439\u043d \u0442\u0443\u0440\u0448 \u043e\u0440\u0447\u043b\u043e\u043d \u0435\u0440\u0442\u04e9\u043d\u0446\u04e9\u0434 \u0411\u0443\u0440\u0445\u0430\u043d \u0431\u0430\u0439\u0445\u0433\u04af\u0439 \u0433\u044d\u0436 \u0445\u044d\u043b\u0441\u044d\u043d.\n\u0413\u044d\u0432\u0447 \u0411\u0443\u0440\u0445\u0430\u043d \u044d\u043d\u044d\u0440\u044d\u043d\u0433\u04af\u0439 \u0443\u0447\u0440\u0430\u0430\u0441 \u0448\u0430\u0440 \u0430\u0439\u0440\u0430\u0433, \u044d\u043c\u044d\u0433\u0442\u044d\u0439\u0447\u04af\u04af\u0434, \u0434\u044d\u043b\u0445\u0438\u0439\u043d \u0430\u043c\u0436\u0438\u043b\u0442 \u0445\u044d\u0437\u044d\u044d \u0447 \u043c\u0438\u043d\u0438\u0439 \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b\u0438\u0439\u043d \u0445\u04af\u0441\u043b\u0438\u0439\u0433 \u0445\u0430\u043d\u0433\u0430\u0436 \u0447\u0430\u0434\u0430\u0445\u0433\u04af\u0439 \u0433\u044d\u0434\u0433\u0438\u0439\u0433 \u043d\u0430\u0434\u0430\u0434 \u0445\u0430\u0440\u0443\u0443\u043b\u0441\u0430\u043d.\n26-\u0440 \u0437\u04af\u0439\u043b\u0434 \u0433\u0430\u0440\u0434\u0430\u0433 \u201d\u0443\u0445\u0430\u0430\u043d \u043e\u0440\u043e\u0445\u201d \u0433\u044d\u0434\u044d\u0433 \u043d\u044c \u04af\u04af\u043d\u0438\u0439\u0433 \u043b \u0445\u044d\u043b\u0436 \u0431\u0430\u0439\u0433\u0430\u0430 \u044e\u043c.\n\u0427\u0438\u0433\u043b\u044d\u043b\u044d\u044d \u043e\u0439\u043b\u0433\u043e\u0445\u0433\u04af\u0439 \u0431\u043e\u043b \u0442\u0430 \u0431\u0443\u0440\u0443\u0443 \u0447\u0438\u0433\u043b\u044d\u043b\u0434 \u0433\u04af\u0439\u0434\u044d\u0433.\n\u0413\u044d\u0440\u0442\u044d\u044d \u0445\u0430\u0440\u0438\u0445 \u0437\u0430\u043c\u0430\u0430 \u043e\u043b\u043e\u0445 \u044d\u0445\u043d\u0438\u0439 \u0430\u043b\u0445\u0430\u043c \u0431\u043e\u043b \u0442\u0430 \u0442\u04e9\u04e9\u0440\u0441\u04e9\u043d \u0433\u044d\u0434\u0433\u044d\u044d \u0445\u04af\u043b\u044d\u044d\u043d \u0437\u04e9\u0432\u0448\u04e9\u04e9\u0440\u04e9\u0445 \u044f\u0432\u0434\u0430\u043b \u044e\u043c.\n\u0414\u044d\u043d \u041c\u0430\u043a\u0434\u0430\u0443\u044d\u043b\u043b \u0431\u043e\u043b \u041f\u043e\u0440\u0442\u043b\u0435\u043d\u0434\u044b\u043d \u043c\u0430\u0440\u0430\u0444\u043e\u043d\u0434 \u0430\u043b\u0434\u0441\u0430\u043d \u0433\u04af\u0439\u0433\u0447\u0434\u0438\u0439\u043d \u043d\u044d\u0433 \u0431\u0430\u0439\u0432.\n\u0422\u044d\u0440 \u0445\u044d\u043b\u044d\u0445\u0434\u044d\u044d: \u201d\u0411\u0438 \u0431\u0443\u043b\u0430\u043d \u0442\u043e\u0439\u0440\u043e\u043e\u0434 10 \u0445\u04af\u043d \u0437\u04af\u0433\u044d\u044d\u0440 \u043b \u0445\u04e9\u0434\u04e9\u043b\u0433\u04e9\u04e9\u043d\u0433\u04af\u0439 \u0437\u043e\u0433\u0441\u043e\u0436 \u0431\u0430\u0439\u0445\u044b\u0433 \u0445\u0430\u0440\u0441\u0430\u043d...\u201d \u0433\u044d\u0436\u044d\u044d.\n\u0422\u044d\u0434 \u0431\u0438\u0435 \u0431\u0438\u0435 \u0440\u04af\u04af\u0433\u044d\u044d \u0445\u0430\u0440\u0430\u043d \u2018\u04e8\u04e9, \u044d\u043d\u044d \u0437\u04e9\u0432 \u0441\u0430\u043d\u0430\u0433\u0434\u0430\u0445\u0433\u04af\u0439 \u0431\u0430\u0439\u043d\u0430\u2019 \u0433\u044d\u0436 \u0431\u043e\u0434\u043e\u0436 \u0431\u0430\u0439\u0432.\n\n\u04e8\u04e9\u0440 \u043d\u044d\u0433 \u0433\u04af\u0439\u0433\u0447 \u0417\u0430\u043a \u041a\u0430\u0441\u0442\u0435\u0440 \u0446\u0430\u0433\u0442 55 \u043c\u0438\u043b\u0438\u0439\u043d \u0445\u0443\u0440\u0434\u0442\u0430\u0439 \u043c\u0430\u0448\u0438\u043d\u0443\u0443\u0434 \u0442\u04af\u04af\u043d\u0438\u0439 \u0445\u0430\u0436\u0443\u0443\u0433\u0430\u0430\u0440 \u04e9\u043d\u0433\u04e9\u0440\u0447 \u0431\u0430\u0439\u0441\u0430\u043d \u0445\u043e\u043d\u0433\u0438\u043b \u0440\u0443\u0443 \u043e\u0440\u0441\u043e\u043d \u0433\u044d\u0436\u044d\u044d.\n\u0422\u044d\u0440 \u04af\u0435\u0434 \u043b \u0442\u044d\u0440 \u0437\u0430\u043c\u0430\u0430\u0441\u0430\u0430 \u0445\u0430\u0437\u0430\u0439\u0441\u043d\u0430\u0430 \u0443\u0445\u0430\u0430\u0440\u0441\u0430\u043d.\n\u0411\u0443\u0440\u0445\u0430\u043d \u043d\u0430\u043c\u0430\u0439\u0433 \u0443\u0445\u0430\u0430\u043d \u043e\u0440\u0443\u0443\u043b\u0430\u0445\u0430\u0430\u0441 \u04e9\u043c\u043d\u04e9 \u0431\u0438 \u201d\u04af\u043d\u044d\u043d\u0438\u0439\u0433 \u043c\u044d\u0434\u0434\u044d\u0433\u201d \u0433\u044d\u0436 \u0431\u043e\u0434\u0434\u043e\u0433 \u0431\u0430\u0439\u0441\u0430\u043d.\n\u041c\u0438\u043d\u0438\u0439 \u0431\u0430\u0440\u0434\u0430\u043c \u0437\u0430\u043d \u043d\u0430\u0434\u0430\u0434 \u0437\u04e9\u0432 \u0437\u0430\u043c \u0433\u044d\u0434\u0433\u0438\u0439\u0433 \u0445\u044d\u043b\u0436 \u0431\u0430\u0439\u0441\u0430\u043d \u0431\u04e9\u0433\u04e9\u04e9\u0434 \u0431\u0438 \u043c\u0430\u0448 \u0443\u0445\u0430\u0430\u043d\u0442\u0430\u0439 \u0431\u0430\u0439\u0441\u0430\u043d \u0442\u0443\u043b \u043d\u0430\u043c\u0430\u0439\u0433 \u0447\u0438\u0433\u043b\u04af\u04af\u043b\u044d\u0445 \u044f\u043c\u0430\u0440 \u0447 \u0431\u0443\u0440\u0445\u0430\u043d \u0445\u044d\u0440\u044d\u0433\u0433\u04af\u0439 \u0431\u0430\u0439\u0441\u0430\u043d.\n\u0425\u0430\u0447\u0438\u0440\u0445\u0430\u043b\u0442\u0430\u0439 \u043d\u044c, \u0431\u0438 \u0421\u0430\u0442\u0430\u043d\u044b \u0445\u0443\u0443\u0440\u0430\u043d \u043c\u044d\u0445\u043b\u044d\u043b\u0442\u0438\u0439\u0433 \u043e\u043b\u0436 \u0445\u0430\u0440\u0430\u0445\u0430\u0430\u0440 \u0445\u044d\u0442\u044d\u0440\u0445\u0438\u0439 \u0442\u044d\u043d\u044d\u0433 \u0431\u0430\u0439\u0441\u0430\u043d.\n\u0411\u0438 \u0442\u04af\u04af\u043d\u0438\u0439 \u0445\u0443\u0434\u0430\u043b \u0445\u0443\u0443\u0440\u043c\u0430\u0433\u0438\u0439\u043d \u0443\u0440\u0445\u0438\u043d\u0434 \u0431\u0430\u0440\u0438\u0433\u0434\u0441\u0430\u043d.\n\u0411\u0443\u0440\u0445\u0430\u043d\u0430\u0430\u0441 \u0437\u0443\u0433\u0442\u0430\u0436 \u0430\u0437 \u0436\u0430\u0440\u0433\u0430\u043b\u044b\u0433 \u043e\u043b\u043d\u043e \u0433\u044d\u0441\u044d\u043d \u0447\u04e9\u0442\u0433\u04e9\u0440\u0438\u0439\u043d \u0430\u043c\u043b\u0430\u043b\u0442\u0430\u0434 \u0431\u0438 \u0438\u0442\u0433\u044d\u0441\u044d\u043d.\n\u0413\u044d\u0445\u0434\u044d\u044d \u0411\u0443\u0440\u0445\u0430\u043d \u043d\u0430\u0434\u0430\u0434 \u0433\u044d\u043c\u0448\u043b\u0438\u0439\u043d \u0431\u044d\u043b\u0433\u0438\u0439\u0433 \u04e9\u0433\u0441\u04e9\u043d.\n\u042d\u043d\u0434 \u0433\u044d\u043c\u0448\u0438\u043b \u0433\u044d\u0441\u044d\u043d \u0443\u0442\u0433\u0430\u0442\u0430\u0439 \u0433\u0440\u0435\u043a \u04af\u0433 \u043d\u044c metanoia \u044e\u043c.\n\u042d\u043d\u044d \u043d\u044c \u201d\u043e\u044e\u0443\u043d \u0441\u0430\u043d\u0430\u0430\u043d\u044b \u04e9\u04e9\u0440\u0447\u043b\u04e9\u043b\u0442, \u0430\u043c\u044c\u0434\u0440\u0430\u043b\u044b\u043d \u04e9\u04e9\u0440\u0447\u043b\u04e9\u043b\u0442, \u0437\u043e\u0440\u0438\u043b\u0433\u044b\u043d \u04e9\u04e9\u0440\u0447\u043b\u04e9\u043b\u0442\u201d \u0433\u044d\u0441\u044d\u043d \u0443\u0442\u0433\u0430\u0442\u0430\u0439.\n22-\u0440 \u0437\u04af\u0439\u043b\u0434 \u0445\u044d\u043b\u0441\u044d\u043d\u0447\u043b\u044d\u043d \u0431\u0438 \u201d\u0446\u044d\u0432\u044d\u0440 \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b\u044d\u044d\u0441 \u042d\u0437\u044d\u043d\u0438\u0439\u0433 \u0434\u0443\u0443\u0434\u0430\u0445\u201d \u0431\u043e\u043b\u043e\u043c\u0436\u0442\u043e\u0439 \u0431\u0430\u0439\u0445\u044b\u043d \u0442\u0443\u043b\u0434 \u0415\u0441\u04af\u0441 \u043d\u0430\u0434\u0430\u0434 \u0448\u0438\u043d\u044d \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b \u04e9\u0433\u0441\u04e9\u043d.\n\u0426\u044d\u0432\u044d\u0440 \u0437\u04af\u0440\u0445 \u0431\u043e\u043b \u0448\u0443\u0434\u0430\u0440\u0433\u0430 \u0437\u04af\u0440\u0445 \u044e\u043c.\n\u0411\u0443\u0440\u0445\u0430\u043d\u0434 \u0445\u0430\u043d\u0434\u0430\u043d \u201d\u0411\u0438 \u043d\u04af\u0433\u043b\u044d\u044d \u0443\u0443\u0447\u0438\u043b\u0436 \u0431\u0430\u0439\u043d\u0430, \u043d\u0430\u043c\u0430\u0439\u0433 \u0443\u0443\u0447\u043b\u0430\u0430\u0447\u201d \u0433\u044d\u0436 \u0434\u0443\u0443\u0434\u0434\u0430\u0433 \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b.\n\u0427\u0430\u043c\u0430\u0430\u0441 \u0445\u043e\u043b\u0434\u043e\u0445 \u0431\u0438\u0448, \u0447\u0430\u043c \u0440\u0443\u0443 \u0433\u04af\u0439\u0445\u044d\u0434 \u043c\u0438\u043d\u044c \u0442\u0443\u0441\u043b\u0430\u0430\u0447.\u201d\n\u041f\u0430\u0443\u043b \u0420\u043e\u043c 10:9\u201311-\u0434 \u0411\u0443\u0440\u0445\u0430\u043d \u0440\u0443\u0443 \u0445\u044d\u0440\u0445\u044d\u043d \u044d\u0440\u0433\u044d\u0436, \u0430\u0432\u0440\u0430\u0433\u0434\u0430\u0445 \u0442\u0430\u043b\u0430\u0430\u0440 \u043c\u0430\u0448 \u0442\u043e\u0434\u043e\u0440\u0445\u043e\u0439 \u0442\u0430\u0439\u043b\u0431\u0430\u0440 \u0431\u0438\u0447\u0441\u044d\u043d \u0431\u0430\u0439\u0434\u0430\u0433.\n9 \u0425\u044d\u0440\u044d\u0432 \u0447\u0438 \u0430\u043c\u0430\u0430\u0440\u0430\u0430 \u0415\u0441\u04af\u0441 \u0431\u043e\u043b \u042d\u0437\u044d\u043d \u0433\u044d\u0436 \u0442\u0443\u043d\u0445\u0430\u0433\u043b\u0430\u0436, \u0411\u0443\u0440\u0445\u0430\u043d \u0422\u04af\u04af\u043d\u0438\u0439\u0433 \u04af\u0445\u044d\u0433\u0441\u0434\u044d\u044d\u0441 \u0430\u043c\u0438\u043b\u0443\u0443\u043b\u0441\u0430\u043d \u0433\u044d\u0434\u044d\u0433\u0442 \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b\u0434\u044d\u044d \u0438\u0442\u0433\u044d\u0432\u044d\u043b \u0430\u0432\u0440\u0430\u0433\u0434\u0430\u0445 \u0431\u043e\u043b\u043d\u043e.\n10 \u0423\u0447\u0438\u0440 \u043d\u044c \u0447\u0438 \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b\u044d\u044d\u0440\u044d\u044d \u0438\u0442\u0433\u044d\u0436, \u0437\u04e9\u0432\u0442\u0433\u04e9\u0433\u0434\u0434\u04e9\u0433. \u0410\u043c\u0430\u0430\u0440\u0430\u0430 \u0438\u0442\u0433\u044d\u043b\u044d\u044d \u0442\u0443\u043d\u0445\u0430\u0433\u043b\u0430\u0436, \u0430\u0432\u0440\u0430\u0433\u0434\u0434\u0430\u0433.\n11 \u0421\u0443\u0434\u0430\u0440\u0442 \u201d\u0422\u04af\u04af\u043d\u0434 \u0438\u0442\u0433\u044d\u0434\u044d\u0433 \u0445\u04af\u043d \u0445\u044d\u0437\u044d\u044d \u0447 \u0438\u0447\u0433\u044d\u0432\u0442\u044d\u0440 \u0431\u0430\u0439\u0434\u0430\u043b\u0434 \u043e\u0440\u043e\u0445\u0433\u04af\u0439\u201d \u0433\u044d\u0436 \u0445\u044d\u043b\u0441\u044d\u043d \u0431\u0430\u0439\u0434\u0430\u0433.\n\n\u0427\u0438 \u0430\u0432\u0440\u0430\u0433\u0434\u0430\u0445\u044b\u043d \u0442\u0443\u043b\u0434 \u0430\u043c\u0430\u0430\u0440\u0430\u0430 \u0438\u0442\u0433\u044d\u043b\u044d\u044d \u0442\u0443\u043d\u0445\u0430\u0433\u043b\u0430\u0441\u0430\u043d \u0443\u0443?\n\u0425\u044d\u0440\u044d\u0432 \u0442\u0430 \u0442\u044d\u0433\u044d\u044d\u0433\u04af\u0439 \u0431\u043e\u043b \u04e9\u043d\u04e9\u04e9\u0434\u04e9\u0440 \u04af\u04af\u043d\u0438\u0439\u0433 \u0445\u0438\u0439\u0445\u044d\u0434 \u0441\u0430\u0439\u0445\u0430\u043d \u04e9\u0434\u04e9\u0440 \u0431\u043e\u043b\u043d\u043e \u0433\u044d\u0436 \u0431\u043e\u0434\u043e\u0445\u0433\u04af\u0439 \u0431\u0430\u0439\u043d\u0430 \u0443\u0443?\n\u0410\u0440\u0438\u0443\u043d \u0421\u04af\u043d\u0441 \u0431\u0438\u0434\u043d\u0438\u0439 \u0434\u0443\u043d\u0434 \u0431\u0430\u0439\u0433\u0430\u0430 \u0431\u04e9\u0433\u04e9\u04e9\u0434 \u043c\u0430\u0433\u0430\u0434\u0433\u04af\u0439 \u0442\u044d\u0440 \u0442\u0430\u043d\u044b \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b\u0434 \u0448\u0438\u0432\u043d\u044d\u0436 \u0431\u0430\u0439\u0436 \u043c\u0430\u0433\u0430\u0434\u0433\u04af\u0439 \u044e\u043c:\n\u201d\u041d\u04af\u0433\u044d\u043b \u0431\u0430 \u04af\u0445\u043b\u0438\u0439\u043d \u0437\u0430\u043c\u0430\u0430\u0441 \u044d\u0440\u0433\u044d!\n\u201c\u0415\u0441\u04af\u0441 \u0431\u043e\u043b \u042d\u0437\u044d\u043d!\u201d \u0433\u044d\u0436 \u0442\u0443\u043d\u0445\u0430\u0433\u043b\u0430\u0441\u043d\u0430\u0430\u0440 \u0448\u0438\u043d\u044d \u0430\u043c\u044c\u0434\u0440\u0430\u043b, \u0448\u0438\u043d\u044d \u0447\u0438\u0433\u043b\u044d\u043b\u0438\u0439\u0433 \u0441\u043e\u043d\u0433\u043e\u043e\u0440\u043e\u0439.\n\n\u041f\u0430\u0443\u043b \u04e9\u043c\u043d\u04e9 \u043d\u044c \u044d\u043d\u044d \u0448\u0438\u043d\u044d \u0447\u0438\u0433\u043b\u044d\u043b\u0438\u0439\u043d \u0442\u0430\u043b\u0430\u0430\u0440 \u043d\u044d\u0433 \u0443\u0434\u0430\u0430 \u0431\u0438\u0447\u0441\u044d\u043d.\n\u042d\u043d\u044d \u043d\u044c \u0422\u0438\u043c\u043e\u0442 \u043e\u0434\u043e\u043e \u043f\u0430\u0441\u0442\u043e\u0440\u043e\u043e\u0440 \u04af\u0439\u043b\u0447\u0438\u043b\u0436 \u0431\u0430\u0439\u0433\u0430\u0430 \u0415\u0444\u0435\u0441 \u0434\u044d\u0445 \u0441\u04af\u043c\u0434 \u0431\u0438\u0447\u0441\u044d\u043d \u0437\u0430\u0445\u0438\u0434\u0430\u043b\u0434\u0430\u0430 \u0431\u0430\u0439\u0441\u0430\u043d \u044e\u043c.\n\u0415\u0444\u0435\u0441 2:1-5-\u0434 \u041f\u0430\u0443\u043b \u0425\u0440\u0438\u0441\u0442\u044d\u0434 \u0438\u0442\u0433\u044d\u0433\u0447\u0434\u044d\u0434 \u0411\u0443\u0440\u0445\u0430\u043d \u0442\u044d\u0434\u044d\u043d\u0434 \u0448\u0438\u043d\u044d \u0430\u043c\u044c\u0434\u0440\u0430\u043b, \u0448\u0438\u043d\u044d \u0447\u0438\u0433\u043b\u044d\u043b \u04e9\u0433\u04e9\u0445\u0438\u0439\u043d \u0442\u0443\u043b\u0434 \u044e\u0443 \u0445\u0438\u0439\u0441\u044d\u043d \u0442\u0430\u043b\u0430\u0430\u0440 \u044e\u0443 \u0433\u044d\u0436 \u0431\u0438\u0447\u0441\u044d\u043d\u0438\u0439\u0433 \u0441\u043e\u043d\u0441\u043e\u043e\u0440\u043e\u0439:\n1 \u201d\u0422\u0430 \u043d\u0430\u0440 \u0433\u044d\u043c \u0431\u0443\u0440\u0443\u0443 \u0431\u043e\u043b\u043e\u043d \u043d\u04af\u0433\u043b\u04af\u04af\u0434\u0438\u0439\u043d\u0445\u044d\u044d \u0434\u0443\u043d\u0434 \u04af\u0445\u0441\u044d\u043d \u0431\u0430\u0439\u0441\u0430\u043d.\n2 \u0422\u0430 \u043d\u0430\u0440 \u043d\u044d\u0433\u044d\u043d \u0446\u0430\u0433\u0442 \u044d\u043d\u044d \u0435\u0440\u0442\u04e9\u043d\u0446\u0438\u0439\u043d \u0437\u0430\u043c\u0430\u0430\u0440, \u0430\u0433\u0430\u0430\u0440\u044b\u043d \u0445\u04af\u0447\u043d\u0438\u0439 \u043d\u043e\u0451\u0440\u0445\u043e\u0433\u0447 \u0431\u0443\u044e\u0443 \u044d\u0434\u04af\u0433\u044d\u044d \u0434\u0443\u0443\u043b\u0433\u0430\u0432\u0430\u0440\u0433\u04af\u0439 \u0445\u04e9\u0432\u0433\u04af\u04af\u0434\u044d\u0434 \u0430\u0436\u0438\u043b\u043b\u0430\u0436 \u0431\u0443\u0439 \u0441\u04af\u043d\u0441\u0438\u0439\u0433 \u0434\u0430\u0433\u0430\u0436, \u0442\u044d\u0440 \u0441\u04af\u043d\u0441\u044d\u044d\u0440 \u0430\u043b\u0445\u0430\u0436 \u0431\u0430\u0439\u0441\u0430\u043d.\n3 \u0411\u0438\u0434 \u0431\u04af\u0433\u0434\u044d\u044d\u0440\u044d\u044d \u043d\u044d\u0433\u044d\u043d \u0446\u0430\u0433\u0442 \u0442\u044d\u0434\u043d\u0438\u0439 \u0434\u0443\u043d\u0434 \u043c\u0430\u0445\u0430\u043d \u0431\u0438\u0435\u0438\u0439\u043d \u0445\u04af\u0441\u044d\u043b \u0442\u0430\u0447\u0430\u0430\u043b\u0434\u0430\u0430 \u0430\u0432\u0442\u0430\u043d, \u0431\u0438\u0435 \u043c\u0430\u0445\u0431\u043e\u0434\u044c \u0431\u043e\u043b\u043e\u043d \u043e\u044e\u0443\u043d \u0443\u0445\u0430\u0430\u043d\u044b \u0445\u04af\u0441\u043b\u04af\u04af\u0434\u0438\u0439\u0433 \u0433\u04af\u0439\u0446\u044d\u043b\u0434\u04af\u04af\u043b\u0436 \u0430\u043c\u044c\u0434\u0430\u0440\u0447 \u0431\u0430\u0439\u0441\u0430\u043d \u0431\u04e9\u0433\u04e9\u04e9\u0434 \u0431\u0443\u0441\u0430\u0434 \u0445\u04af\u043c\u04af\u04af\u0441\u0438\u0439\u043d \u0430\u0434\u0438\u043b \u0442\u04e9\u0440\u04e9\u043b\u0445\u04e9\u04e9\u0441\u04e9\u04e9 \u0443\u0443\u0440 \u0445\u0438\u043b\u044d\u043d\u0433\u0438\u0439\u043d \u0445\u04af\u04af\u0445\u0434\u04af\u04af\u0434 \u0431\u0430\u0439\u0441\u0430\u043d.\n4 \u0425\u0430\u0440\u0438\u043d \u0411\u0443\u0440\u0445\u0430\u043d \u0431\u0438\u0434\u043d\u0438\u0439\u0433 \u0445\u0430\u0439\u0440\u043b\u0430\u0441\u0430\u043d \u0430\u0433\u0443\u0443 \u0445\u0430\u0439\u0440\u044b\u043d\u0445\u0430\u0430 \u0443\u043b\u043c\u0430\u0430\u0441 \u04e9\u0440\u0448\u04e9\u04e9\u043b\u04e9\u04e9\u0440 \u0431\u0430\u044f\u043d \u0431\u0430\u0439\u0441\u0430\u043d.\n5 \u0411\u0438\u0434\u043d\u0438\u0439\u0433 \u0433\u044d\u043c \u043d\u04af\u0433\u043b\u044d\u044d\u0441 \u0431\u043e\u043b\u0436 \u04af\u0445\u0441\u044d\u043d \u0431\u0430\u0439\u0445\u0430\u0434 \u0425\u0440\u0438\u0441\u0442\u0442\u044d\u0439 \u0445\u0430\u043c\u0442 \u0430\u043c\u0438\u043b\u0443\u0443\u043b\u0441\u0430\u043d. \u0422\u0430 \u043d\u0430\u0440 \u043d\u0438\u0433\u04af\u04af\u043b\u0441\u043b\u044d\u044d\u0440 \u0430\u0432\u0440\u0430\u0433\u0434\u0441\u0430\u043d \u044e\u043c.\n\n\u201d\u0413\u044d\u0445\u0434\u044d\u044d \u0411\u0443\u0440\u0445\u0430\u043d\u201d \u0433\u044d\u0434\u044d\u0433 \u043d\u044c \u0445\u04af\u043d \u0431\u04af\u0440\u0438\u0439\u043d \u0445\u044d\u043b\u0434\u044d\u0433 \u0445\u0430\u043c\u0433\u0438\u0439\u043d \u04af\u0437\u044d\u0441\u0433\u044d\u043b\u044d\u043d\u0442\u044d\u0439 \u0445\u043e\u0451\u0440 \u04af\u0433 \u044e\u043c.\n\u041f\u0430\u0443\u043b \u0415\u0444\u0435\u0441 \u0434\u044d\u0445 \u0438\u0442\u0433\u044d\u0433\u0447\u0434\u044d\u0434 \u043d\u044d\u0433\u044d\u043d \u0446\u0430\u0433\u0442 \u0442\u044d\u0434 \u0445\u0430\u0432\u0445\u0430\u043d\u0434 \u043e\u0440\u0441\u043e\u043d \u0442\u0443\u0443\u043b\u0430\u0439 \u0448\u0438\u0433 \u0445\u0430\u0432\u0445\u0430\u043d\u0434 \u043e\u0440\u0436, \u0430\u0440\u0447\u0430\u0430\u0433\u04af\u0439 \u0431\u0430\u0439\u0441\u0430\u043d \u0433\u044d\u0434\u0433\u0438\u0439\u0433 \u0441\u0430\u043d\u0443\u0443\u043b\u0434\u0430\u0433.\n\u0413\u044d\u0432\u0447 \u0411\u0443\u0440\u0445\u0430\u043d \u0442\u044d\u0434\u043d\u0438\u0439\u0433 \u0437\u04e9\u0432\u0445\u04e9\u043d \u043d\u0438\u0433\u04af\u04af\u043b\u0441\u043b\u044d\u044d\u0440, \u0437\u04e9\u0432\u0445\u04e9\u043d \u0438\u0442\u0433\u044d\u043b\u044d\u044d\u0440, \u0437\u04e9\u0432\u0445\u04e9\u043d \u0425\u0440\u0438\u0441\u0442\u044d\u0434 \u0438\u0442\u0433\u044d\u0445 \u0437\u0430\u043c\u0430\u0430\u0440 \u0430\u0432\u0440\u0430\u0445\u0430\u0430\u0440 \u043e\u0440\u043e\u043b\u0446\u0441\u043e\u043d.\n\u0425\u044d\u0440\u044d\u0432 \u0442\u0430 \u0425\u0440\u0438\u0441\u0442\u0438\u0439\u043d \u0437\u0430\u0433\u0430\u043b\u043c\u0430\u0439 \u0434\u044d\u044d\u0440\u0445 \u0437\u043e\u043b\u0438\u043e\u0441\u043b\u043e\u043b \u0442\u0430\u043d\u044b \u0442\u04e9\u043b\u04e9\u04e9, \u0442\u0430\u043d\u044b\u0433 \u043d\u04af\u0433\u044d\u043b \u0431\u043e\u043b\u043e\u043d \u0438\u0447\u0433\u04af\u04af\u0440\u044d\u044d\u0441 \u0446\u044d\u0432\u044d\u0440\u043b\u044d\u0445\u0438\u0439\u043d \u0442\u0443\u043b\u0434 \u0431\u0430\u0439\u0441\u0430\u043d \u0433\u044d\u0434\u044d\u0433\u0442 \u0438\u0442\u0433\u044d\u0434\u044d\u0433 \u0431\u043e\u043b \u0445\u044d\u043d \u0447 \u0430\u0432\u0440\u0430\u0433\u0434\u0430\u0436 \u0447\u0430\u0434\u043d\u0430.\n\u0422\u0430 \u04af\u04af\u043d\u0434 \u0438\u0442\u0433\u044d\u0445 \u04af\u0435\u0434 \u0448\u0438\u043d\u044d \u0430\u043c\u044c\u0434\u0440\u0430\u043b\u044b\u0433 \u0445\u04af\u043b\u044d\u044d\u043d \u0430\u0432\u0447, \u0415\u0441\u04af\u0441 \u0442\u0430\u043d\u044b\u0433 \u0448\u0438\u043d\u044d \u0437\u0430\u043c\u0434 \u043e\u0440\u0443\u0443\u043b\u043d\u0430.\n\u0415\u0444\u0435\u0441 2:8-\u0434 \u0445\u044d\u0434\u044d\u043d \u0437\u04af\u0439\u043b\u0438\u0439\u043d \u0434\u0430\u0440\u0430\u0430 \u041f\u0430\u0443\u043b \u0442\u044d\u0440 \u0448\u0438\u043d\u044d \u0447\u0438\u0433\u043b\u044d\u043b\u0438\u0439\u043d \u0442\u0430\u043b\u0430\u0430\u0440 \u04e9\u0433\u04af\u04af\u043b\u0434\u044d\u0433.\n\u041d\u0430\u0434\u0442\u0430\u0439 \u0445\u0430\u043c\u0442 \u04af\u04af\u043d\u0438\u0439\u0433 \u0443\u043d\u0448\u0430\u0430\u0440\u0430\u0439:\n\u0411\u04ae\u0413\u0414: 10 \u201c\u0423\u0447\u0438\u0440 \u043d\u044c \u0431\u0438\u0434 \u0431\u043e\u043b \u0422\u04af\u04af\u043d\u0438\u0439 \u0431\u04af\u0442\u044d\u044d\u043b \u0431\u04e9\u0433\u04e9\u04e9\u0434 \u0425\u0440\u0438\u0441\u0442 \u0415\u0441\u04af\u0441 \u0434\u043e\u0442\u043e\u0440 \u0441\u0430\u0439\u043d \u04af\u0439\u043b\u0441\u0438\u0439\u043d \u0442\u04e9\u043b\u04e9\u04e9 \u0431\u04af\u0442\u044d\u044d\u0433\u0434\u0441\u044d\u043d. \u0411\u0443\u0440\u0445\u0430\u043d \u044d\u0434\u0433\u044d\u044d\u0440 \u04af\u0439\u043b\u0441\u0438\u0439\u0433 \u0431\u0438\u0434\u043d\u0438\u0439\u0433 \u0442\u044d\u0434\u0433\u044d\u044d\u0440\u0438\u0439\u043d \u0434\u043e\u0442\u043e\u0440 \u0430\u043b\u0445\u0443\u0443\u043b\u0430\u0445\u044b\u043d \u0442\u0443\u043b\u0434 \u0443\u0440\u044c\u0434\u0447\u0438\u043b\u0430\u043d \u0431\u044d\u043b\u0442\u0433\u044d\u0441\u044d\u043d.\u201d\n\n\u042d\u043d\u044d \u0437\u0430\u0445\u0438\u0430\u0441\u044b\u0433 \u0434\u0443\u0443\u0441\u0433\u0430\u0445\u044b\u043d \u0442\u0443\u043b\u0434 \u0441\u0430\u0439\u043d \u04af\u0439\u043b\u0441\u044d\u044d\u0440 \u0430\u043b\u0445\u0430\u0445 \u044f\u043c\u0430\u0440 \u0431\u0430\u0439\u0434\u0433\u0438\u0439\u0433 \u0445\u0430\u0440\u0446\u0433\u0430\u0430\u044f.\n\u041f\u0430\u0443\u043b \u0422\u0438\u043c\u043e\u0442\u043e\u0434 \u0411\u0438\u0431\u043b\u0438\u0439\u043d \u0431\u0430\u0433\u0448\u0430\u0430\u0440 \u0445\u044d\u043d\u0438\u0439\u0433 \u0441\u043e\u043d\u0433\u043e\u0436, \u0441\u0443\u0440\u0433\u0430\u0445 \u0442\u0430\u043b\u0430\u0430\u0440 \u0437\u04e9\u0432\u043b\u04e9\u0433\u04e9\u04e9 \u04e9\u0433\u04e9\u0445\u0438\u0439\u0433 \u0437\u0430\u0445\u0438\u0434\u0430\u043b\u0434\u0430\u0430 \u0431\u0438\u0447\u0441\u044d\u043d \u0433\u044d\u0434\u0433\u0438\u0439\u0433 \u0441\u0430\u043d\u0430\u0430\u0440\u0430\u0439.\n\u0418\u0442\u0433\u044d\u0433\u0447\u0434\u0438\u0439\u043d \u0445\u0443\u0432\u044c\u0434 \u0431\u0438\u0434\u043d\u0438\u0439 \u044d\u0440\u0445\u044d\u043c \u0437\u043e\u0440\u0438\u043b\u0433\u043e \u0431\u043e\u043b \u0441\u0430\u0439\u043d \u043c\u044d\u0434\u044d\u044d\u043d\u0438\u0439 \u0441\u0430\u0439\u043d \u043c\u044d\u0434\u044d\u044d\u0433 \u043e\u0439\u0440 \u0434\u043e\u0442\u043d\u044b \u0431\u043e\u043b\u043e\u043d \u0430\u043b\u0441 \u0445\u043e\u043b\u044b\u043d \u0445\u04af\u043c\u04af\u04af\u0441\u0442 \u0445\u0443\u0432\u0430\u0430\u043b\u0446\u0430\u0445 \u044f\u0432\u0434\u0430\u043b \u044e\u043c.\n\u0413\u044d\u0445\u0434\u044d\u044d \u04af\u04af\u043d\u0438\u0439\u0433 \u04af\u043d\u044d\u043d\u0447\u044d\u044d\u0440 \u0445\u0438\u0439\u0445\u0438\u0439\u043d \u0442\u0443\u043b\u0434 \u0431\u0438\u0434 \u044d\u0434\u0433\u044d\u044d\u0440 \u0448\u04af\u043b\u044d\u0433\u0442 \u041f\u0430\u0443\u043b\u044b\u043d \u0434\u04af\u0440\u0441\u044d\u043b\u0441\u044d\u043d \u0437\u0430\u043d \u0447\u0430\u043d\u0430\u0440\u0442\u0430\u0439 \u0431\u0430\u0439\u0445 \u0451\u0441\u0442\u043e\u0439.\n\u0411\u0438\u0434 \u0445\u044d\u043d\u0438\u0439 \u0447 \u0441\u044d\u0442\u0433\u044d\u043b\u0438\u0439\u0433 \u04e9\u04e9\u0440\u0447\u0438\u043b\u0436 \u0447\u0430\u0434\u0430\u0445\u0433\u04af\u0439.\n\u0413\u044d\u0445\u0434\u044d\u044d \u0431\u0438\u0434 \u0442\u044d\u0434\u044d\u043d\u0434 \u04af\u043d\u044d\u043d\u0438\u0439\u0433 \u0437\u04e9\u04e9\u043b\u04e9\u043d, \u044d\u0435\u043b\u0434\u044d\u0433, \u0442\u044d\u0432\u0447\u044d\u044d\u0440\u0442\u044d\u0439 \u0445\u044d\u043b\u0436 \u0447\u0430\u0434\u043d\u0430.\n\u0411\u0443\u0440\u0445\u0430\u043d \u0441\u043e\u043d\u0433\u043e\u0441\u043e\u043d \u0445\u04af\u04af\u0445\u0434\u04af\u04af\u0434\u0434\u044d\u044d \u0437\u04e9\u0432 \u0446\u0430\u0433\u0442 \u043d\u044c \u0433\u044d\u043c\u0448\u043b\u0438\u0439\u0433 \u043e\u043b\u0433\u043e\u043d\u043e \u0433\u044d\u0434\u044d\u0433\u0442 \u0431\u0438\u0434 \u0438\u0442\u0433\u044d\u0436 \u0431\u043e\u043b\u043d\u043e.\n\u04e8\u043d\u04e9\u04e9\u0434\u0440\u0438\u0439\u043d \u0445\u044d\u0441\u0433\u0438\u0439\u043d 24, 25-\u0440 \u0437\u04af\u0439\u043b\u0434 \u0431\u0438 \u0411\u0443\u0440\u0445\u0430\u043d \u04af\u0439\u043b\u0447\u043b\u044d\u0433\u0447\u0434\u044d\u0434\u044d\u044d \u0445\u04e9\u0433\u0436\u04af\u04af\u043b\u044d\u0445\u0438\u0439\u0433 \u0445\u04af\u0441\u0434\u044d\u0433 \u0442\u0430\u0432\u0430\u043d \u0447\u0430\u043d\u0430\u0440\u044b\u0433 \u0445\u0430\u0440\u0436 \u0431\u0430\u0439\u043d\u0430:\n\n\u0427\u0430\u043d\u0430\u0440 1: \u0425\u044d\u0440\u04af\u04af\u043b\u0447 \u0431\u0438\u0448.\n\u0417\u0430\u0440\u0438\u043c \u0445\u04af\u043c\u04af\u04af\u0441 \u043c\u0430\u0440\u0433\u0430\u0445 \u0434\u0443\u0440\u0442\u0430\u0439 \u0431\u0430\u0439\u0434\u0430\u0433.\n\u042d\u0440\u04af\u04af\u043b \u043c\u044d\u0442\u0433\u044d\u043b\u0446\u044d\u044d\u043d\u0434 \u0431\u0443\u0440\u0443\u0443 \u0437\u04af\u0439\u043b \u0431\u0430\u0439\u0445\u0433\u04af\u0439.\n\u0413\u044d\u0445\u0434\u044d\u044d \u0442\u0430 \u043d\u04af\u0433\u044d\u043b\u0442 \u201c\u0445\u044d\u0440\u04af\u04af\u043b \u043c\u0430\u0440\u0433\u0430\u0430\u043d\u201d \u0445\u0438\u0439\u0436 \u0431\u0430\u0439\u0433\u0430\u0430\u0433\u0430\u0430 \u044f\u0430\u0436 \u043c\u044d\u0434\u044d\u0445 \u0432\u044d?\n\u041c\u0430\u0433\u0430\u0434\u0433\u04af\u0439 \u0442\u0430 \u04e9\u04e9\u0440\u04e9\u04e9\u0441\u04e9\u04e9 \u044d\u043d\u044d \u0430\u0441\u0443\u0443\u043b\u0442\u044b\u0433 \u0430\u0441\u0443\u0443\u0436 \u0431\u043e\u043b\u043e\u0445 \u044e\u043c:\n\u201d\u0411\u0438 \u0445\u044d\u043d \u043d\u044d\u0433\u044d\u043d\u0442\u044d\u0439 \u043c\u0430\u0440\u0433\u0430\u043b\u0434\u0430\u0445 \u04af\u0435\u0434\u044d\u044d \u0442\u044d\u0440 \u0445\u04af\u043d\u0438\u0439\u0445\u044d\u044d \u0442\u0430\u043b\u0430\u0430\u0440 \u044d\u0441\u0432\u044d\u043b \u043c\u0430\u0440\u0433\u0430\u0430\u043d\u0434 \u044f\u043b\u0430\u0445 \u0442\u0430\u043b\u0430\u0430\u0440 \u0438\u043b\u04af\u04af \u0438\u0445 \u0441\u0430\u043d\u0430\u0430 \u0442\u0430\u0432\u044c\u0434\u0430\u0433 \u0443\u0443?\u201d\n\u041c\u0438\u043d\u0438\u0439 \u0431\u0430\u0440\u0434\u0430\u043c \u0437\u0430\u043d \u043d\u0430\u043c\u0430\u0439\u0433 \u0441\u0430\u0439\u0445\u0430\u043d \u0441\u044d\u0442\u0433\u044d\u043b\u0442\u044d\u0439 \u0431\u0430\u0439\u0445\u044b\u043d \u043e\u0440\u043e\u043d\u0434 \u0437\u04e9\u0432 \u0431\u0430\u0439\u0445 \u0442\u0430\u043b \u0434\u044d\u044d\u0440 \u0430\u043d\u0445\u0430\u0430\u0440\u043b\u0430\u0430 \u0442\u04e9\u0432\u043b\u04e9\u0440\u04af\u04af\u043b\u044d\u0445\u044d\u0434 \u0445\u04af\u0440\u0433\u044d\u0436 \u0431\u0430\u0439\u043d\u0430 \u0443\u0443?\u201d\n\n\u0427\u0430\u043d\u0430\u0440 2: \u0411\u04af\u0445 \u0445\u04af\u043d\u0434 \u044d\u0435\u043b\u0434\u044d\u0433 \u0445\u0430\u043d\u0434\u0434\u0430\u0433.\n\u042d\u0437\u044d\u043d\u0438\u0439 \u0437\u0430\u0440\u0446 \u0445\u04af\u043d \u0431\u04af\u0440\u0442\u044d\u0439 \u044d\u0435\u043b\u0434\u044d\u0433 \u0445\u0430\u0440\u044c\u0446\u0430\u0445 \u0451\u0441\u0442\u043e\u0439.\n\u0427\u0430\u043c\u0430\u0439\u0433 \u04af\u0437\u044d\u043d \u044f\u0434\u0430\u0436, \u0447\u0430\u043c\u0430\u0439\u0433 \u0433\u043e\u043c\u0434\u043e\u043e\u0445\u044b\u0433 \u0445\u04af\u0441\u0434\u044d\u0433 \u0445\u04af\u043c\u04af\u04af\u0441\u0442 \u0447 \u0433\u044d\u0441\u044d\u043d.\n\u042d\u043d\u044d \u0445\u044d\u0446\u04af\u04af \u0433\u044d\u0434\u0433\u0438\u0439\u0433 \u0431\u0438 \u043c\u044d\u0434\u044d\u0436 \u0431\u0430\u0439\u043d\u0430.\n\u0411\u0438\u0434 \u04e9\u04e9\u0440\u0441\u0434\u0438\u0439\u0433\u04e9\u04e9 \u0431\u0443\u0441\u0430\u0434 \u0445\u04af\u043c\u04af\u04af\u0441\u044d\u044d\u0441 \u0445\u0430\u043c\u0433\u0430\u0430\u043b\u0430\u0445 \u0430\u0440\u0433\u0430 \u0431\u043e\u043b \u0445\u04af\u0447\u0442\u044d\u0439 \u0431\u0430\u0439\u0436, \u044d\u0440\u0445 \u043c\u044d\u0434\u043b\u044d\u044d \u0430\u0448\u0438\u0433\u043b\u0430\u0445 \u0433\u044d\u0436 \u0431\u043e\u0434\u0434\u043e\u0433.\n\u0413\u044d\u0445\u0434\u044d\u044d \u041f\u0430\u0443\u043b \u0420\u043e\u043c 2:4-\u0442 \u0431\u0438\u0434\u044d\u043d\u0434 \u044e\u0443 \u0433\u044d\u0436 \u0441\u0430\u043d\u0443\u0443\u043b\u0436 \u0431\u0430\u0439\u0433\u0430\u0430\u0433 \u0445\u0430\u0440\u0430\u0430\u0440\u0430\u0439:\n\u201d\u0411\u0443\u0440\u0445\u0430\u043d\u044b \u043d\u0438\u0433\u04af\u04af\u043b\u0441\u044d\u043b \u043d\u044c \u0442\u0430\u043d\u044b\u0433 \u0433\u044d\u043c\u0448\u0438\u043b\u0434 \u0445\u04e9\u0442\u043b\u04e9\u0445 \u0437\u043e\u0440\u0438\u043b\u0433\u043e\u0442\u043e\u0439 \u044e\u043c.\u201d\n\u0427\u0438 \u043d\u04af\u0433\u044d\u043b \u04af\u0439\u043b\u0434\u044d\u0436, \u0442\u04af\u04af\u043d\u044d\u044d\u0441 \u0445\u043e\u043b \u0437\u0443\u0433\u0442\u0430\u0436 \u0431\u0430\u0439\u0445 \u04af\u0435\u0434 \u0415\u0441\u04af\u0441 \u0447\u0430\u043c\u0434 \u0445\u044d\u0440 \u0438\u0445 \u044d\u043d\u044d\u0440\u044d\u043d\u0433\u04af\u0439 \u0445\u0430\u043d\u0434\u0441\u0430\u043d \u0431\u044d?\n\u0422\u04af\u04af\u043d\u0438\u0439 \u0441\u0430\u0439\u0445\u0430\u043d \u0441\u044d\u0442\u0433\u044d\u043b \u0447\u0430\u043c\u0430\u0439\u0433 \u0433\u044d\u043c\u0448\u0438\u0445\u044d\u0434 \u0445\u04af\u0440\u0433\u044d\u0441\u044d\u043d,\n\u0422\u0438\u0439\u043c\u044d\u044d\u0441 \u043e\u0434\u043e\u043e \u0442\u0430 \u0425\u0440\u0438\u0441\u0442\u0438\u0439\u0433 \u0434\u0443\u0443\u0440\u0430\u0439\u0436, \u0445\u04af\u043d \u0431\u04af\u0440\u0442 \u044d\u0435\u043b\u0434\u044d\u0433 \u0445\u0430\u043d\u0434\u0430\u0445 \u0431\u043e\u043b\u043e\u043c\u0436\u0442\u043e\u0439 \u0431\u043e\u043b\u043b\u043e\u043e.\n\n3-\u0440 \u0447\u0430\u043d\u0430\u0440: \u041c\u0443\u0443 \u043c\u0443\u0443\u0433 \u0442\u044d\u0432\u0447\u044d\u044d\u0440\u0442\u044d\u0439\u0433\u044d\u044d\u0440 \u0442\u044d\u0432\u0447\u0438\u0445.\n\u0411\u0438\u0434 \u0441\u0430\u0439\u043d \u043c\u044d\u0434\u044d\u044d\u043d\u0438\u0439 \u04af\u043d\u044d\u043d\u0438\u0439\u0433 \u0445\u0443\u0432\u0430\u0430\u043b\u0446\u0430\u0445\u0434\u0430\u0430 \u0431\u0438\u0434\u043d\u0438\u0439 \u0445\u044d\u043b\u0436 \u0431\u0430\u0439\u0433\u0430\u0430 \u0437\u04af\u0439\u043b\u0434 \u0434\u0443\u0440\u0433\u04af\u0439 \u0445\u04af\u043c\u04af\u04af\u0441\u0438\u0439\u043d \u044d\u0441\u044d\u0440\u0433\u04af\u04af\u0446\u044d\u043b\u0442\u044d\u0439 \u0442\u0443\u043b\u0433\u0430\u0440\u0430\u0445 \u0431\u043e\u043b\u043d\u043e.\n\u0421\u0442\u0435\u0444\u0430\u043d \u04e9\u04e9\u0440\u0438\u0439\u0433 \u043d\u044c \u0445\u04e9\u043d\u04e9\u04e9\u0441\u04e9\u043d \u0445\u04af\u043c\u04af\u04af\u0441\u0442 \u0445\u044d\u0440\u0445\u044d\u043d \u0445\u0430\u0440\u0438\u0443 \u04af\u0439\u043b\u0434\u044d\u043b \u04af\u0437\u04af\u04af\u043b\u0441\u043d\u0438\u0439\u0433 \u0441\u0430\u043d\u0430\u0436 \u0431\u0430\u0439\u043d\u0430 \u0443\u0443?\n\u04ae\u0439\u043b\u0441 7:59\u201360-\u0434 \u0438\u043d\u0433\u044d\u0436 \u0445\u044d\u043b\u0441\u044d\u043d \u0431\u0430\u0439\u0434\u0430\u0433:\n59 \u0422\u044d\u0434 \u0442\u04af\u04af\u043d \u0440\u04af\u04af \u0447\u0443\u043b\u0443\u0443 \u0448\u0438\u0434\u044d\u0436 \u0431\u0430\u0439\u0445 \u0437\u0443\u0443\u0440 \u0421\u0442\u0435\u0444\u0430\u043d \u0437\u0430\u043b\u0431\u0438\u0440\u0447, \u2014\u042d\u0437\u044d\u043d \u0415\u0441\u04af\u0441 \u044d\u044d, \u043c\u0438\u043d\u0438\u0439 \u0441\u04af\u043d\u0441\u0438\u0439\u0433 \u0445\u04af\u043b\u044d\u044d\u043d \u0430\u0432\u0430\u0430\u0447 \u0433\u044d\u0436 \u0445\u044d\u043b\u044d\u0432.\n60 \u0422\u044d\u0433\u044d\u044d\u0434 \u04e9\u0432\u0434\u04e9\u0433 \u0441\u04e9\u0445\u0440\u04e9\u043d \u201d\u042d\u0437\u044d\u043d \u043c\u0438\u043d\u044c, \u044d\u043d\u044d \u043d\u04af\u0433\u043b\u0438\u0439\u0433 \u0442\u044d\u0434\u044d\u043d\u0434 \u0431\u04af\u04af \u0442\u043e\u0445\u043e\u043e\u0447\u201d \u0433\u044d\u0436 \u0445\u0430\u0448\u0445\u0438\u0440\u0430\u0432.\n\n\u0417\u04e9\u0432\u0445\u04e9\u043d \u0411\u0443\u0440\u0445\u0430\u043d \u043b \u0431\u0438\u0434\u044d\u043d\u0434 \u0421\u0442\u0435\u0444\u0430\u043d \u0448\u0438\u0433 \u0431\u0443\u0437\u0430\u0440 \u043c\u0443\u0443\u0433 \u0442\u044d\u0432\u0447\u044d\u044d\u0440\u0442\u044d\u0439\u0433\u044d\u044d\u0440 \u0442\u044d\u0432\u0447\u0438\u0445\u044d\u0434 \u0442\u0443\u0441\u0430\u043b\u0436 \u0447\u0430\u0434\u043d\u0430.\n\u0413\u044d\u0445\u0434\u044d\u044d \u0431\u0438\u0434 \u0437\u043e\u0432\u043b\u043e\u043d \u0431\u044d\u0440\u0445\u0448\u044d\u044d\u043b\u0438\u0439\u043d \u04af\u0435\u0434 \u0422\u04af\u04af\u043d \u0440\u04af\u04af \u0437\u0430\u043b\u0433\u0430\u0445\u0430\u0434 \u0422\u044d\u0440 \u0431\u0438\u0434\u044d\u043d\u0434 \u0442\u0443\u0441\u043b\u0430\u0445 \u0431\u043e\u043b\u043d\u043e.\n\u0411\u0438\u0434\u043d\u0438\u0439 \u0431\u0438\u0435\u0434 \u044e\u0443 \u0447 \u0442\u043e\u0445\u0438\u043e\u043b\u0434\u0441\u043e\u043d \u0431\u0430\u0439\u0441\u0430\u043d \u0431\u0438\u0434\u043d\u0438\u0439 \u0441\u04af\u043d\u0441 \u0442\u04af\u04af\u043d\u0438\u0439 \u0433\u0430\u0440\u0442 \u0430\u044e\u0443\u043b\u0433\u04af\u0439 \u0431\u0430\u0439\u0433\u0430\u0430\u0433 \u043c\u044d\u0434\u044d\u0436, \u0422\u044d\u0440 \u0431\u0438\u0434\u044d\u043d\u0434 \u0422\u04af\u04af\u043d\u0434 \u0438\u0442\u0433\u044d\u0445\u044d\u0434 \u0442\u0443\u0441\u043b\u0430\u0445 \u0431\u043e\u043b\u043d\u043e.\n\n\u0427\u0430\u043d\u0430\u0440 4: \u0417\u04e9\u04e9\u043b\u04e9\u043d \u0431\u0430\u0439\u0434\u043b\u0430\u0430\u0440 \u0437\u0430\u0441\u0430\u0445.\n\u0425\u04af\u043c\u04af\u04af\u0441\u0438\u0439\u0433 \u0437\u0430\u0441\u0430\u0445 \u043d\u044c \u0445\u044d\u0446\u04af\u04af \u0431\u0430\u0439\u0434\u0430\u0433.\n\u0413\u044d\u0445\u0434\u044d\u044d \u0445\u044d\u0440\u044d\u0432 \u043c\u0438\u043d\u0438\u0439 \u0445\u04af\u04af \u044f\u043c\u0430\u0440 \u043d\u044d\u0433\u044d\u043d \u0431\u0443\u0440\u0443\u0443 \u0437\u04af\u0439\u043b \u0445\u0438\u0439\u0436 \u0431\u0430\u0439\u0432\u0430\u043b \u0431\u0438 \u0442\u04af\u04af\u043d\u0434 \u0445\u0430\u0439\u0440\u0442\u0430\u0439 \u0443\u0447\u0440\u0430\u0430\u0441 \u0445\u044d\u043b\u0434\u044d\u0433.\n\u0425\u044d\u043d \u043d\u044d\u0433\u043d\u0438\u0439\u0433 \u0437\u0430\u0441\u0430\u0445 \u0448\u0430\u0430\u0440\u0434\u043b\u0430\u0433\u0430\u0442\u0430\u0439 \u04af\u0435\u0434 \u0431\u043e\u0434\u043e\u0445 \u0451\u0441\u0442\u043e\u0439 \u0447\u0443\u0445\u0430\u043b \u0430\u0441\u0443\u0443\u043b\u0442 \u044d\u043d\u0434 \u0431\u0430\u0439\u043d\u0430:\n\u201d\u041c\u0438\u043d\u0438\u0439 \u0445\u04af\u04af\u0445\u044d\u0434, \u043d\u0430\u0439\u0437 \u044d\u0441\u0432\u044d\u043b \u0445\u0430\u043d\u044c \u043c\u0438\u043d\u0438\u0439 \u0445\u0430\u0439\u0440\u044b\u0433 \u043c\u044d\u0434\u044d\u0440\u0447 \u0431\u0430\u0439\u043d\u0430 \u0443\u0443?\u201d\n\u042d\u0441\u0432\u044d\u043b \u0442\u044d\u0434 \u0437\u04e9\u0432\u0445\u04e9\u043d \u043c\u0438\u043d\u0438\u0439 \u0443\u0443\u0440\u044b\u0433 \u043b \u043c\u044d\u0434\u044d\u0440\u0447 \u0431\u0430\u0439\u043d\u0430 \u0443\u0443?\n\n\u0411\u0438\u0434 \u0443\u0443\u0440 \u0445\u0438\u043b\u044d\u043d \u044d\u0441\u0432\u044d\u043b \u0431\u0443\u0445\u0438\u043c\u0434\u043b\u0430\u0430\u0440 \u0430\u043b\u0434\u0430\u0430\u0433\u0430\u0430 \u0437\u0430\u0441\u0430\u0445\u0434\u0430\u0430 \u0411\u0443\u0440\u0445\u0430\u043d \u043d\u04e9\u0433\u04e9\u04e9 \u0445\u04af\u043d\u0438\u0439\u0433 \u04e9\u04e9\u0440\u0447\u0438\u043b\u0436 \u0447\u0430\u0434\u0430\u0445\u0433\u04af\u0439 \u044e\u043c \u0448\u0438\u0433 \u0430\u0430\u0448\u0438\u043b\u0436 \u0431\u0430\u0439\u0433\u0430\u0430 \u0445\u044d\u0440\u044d\u0433 \u044e\u043c.\n\u0411\u0438\u0434 \u0442\u044d\u0434\u043d\u0438\u0439\u0433 \u04e9\u04e9\u0440\u0447\u043b\u04e9\u0445\u0438\u0439\u0433 \u0448\u0430\u0445\u0430\u0436 \u0447\u0430\u0434\u043d\u0430, \u044d\u0441\u0432\u044d\u043b \u0437\u04e9\u0432 \u0437\u0430\u043c\u0434 \u043e\u0440\u043e\u0445 \u0445\u04af\u0440\u0442\u044d\u043b \u043d\u044c \u0447\u0430\u043d\u0433\u0430\u0430\u0440 \u0445\u0430\u0448\u0433\u0438\u0440\u0447 \u0447\u0430\u0434\u043d\u0430 \u0433\u044d\u0436 \u0431\u043e\u0434\u043e\u0436 \u0431\u0430\u0439\u043d\u0430.\n\u0413\u044d\u0445\u0434\u044d\u044d \u0411\u0443\u0440\u0445\u0430\u043d \u0436\u0438\u043d\u0445\u044d\u043d\u044d \u0445\u04af\u0447 \u0447\u0430\u0434\u0430\u043b\u0442\u0430\u0439 \u0433\u044d\u0434\u0433\u0438\u0439\u0433 \u043c\u044d\u0434\u0434\u044d\u0433 \u0431\u0430\u0433\u0448 \u0437\u04e9\u04e9\u043b\u04e9\u043d, \u0442\u044d\u0432\u0447\u044d\u044d\u0440\u0442\u044d\u0439, \u0441\u0430\u0439\u0445\u0430\u043d \u0441\u044d\u0442\u0433\u044d\u043b\u0442\u044d\u0439 \u0431\u0430\u0439\u0445 \u0431\u043e\u043b\u043d\u043e.\n\n\u0427\u0430\u043d\u0430\u0440 5: \u0411\u0430\u0433\u0448\u043b\u0430\u0445 \u0447\u0430\u0434\u0432\u0430\u0440\u0442\u0430\u0439.\n\u0422\u0430 \u0411\u0443\u0440\u0445\u0430\u043d\u044b \u04af\u0433\u0438\u0439\u0433 \u0431\u0443\u0441\u0434\u0430\u0434 \u0442\u0430\u0439\u043b\u0431\u0430\u0440\u043b\u0430\u0445 \u0445\u044d\u043c\u0436\u044d\u044d\u043d\u0438\u0439 \u0441\u0430\u0439\u043d \u043e\u0439\u043b\u0433\u043e\u0436 \u0431\u0430\u0439\u043d\u0430 \u0443\u0443?\n\u0422\u0430 \u0430\u043c\u044c\u0434\u0440\u0430\u043b\u0434\u0430\u0430 \u0443\u0434\u0438\u0440\u0434\u0430\u043d \u0447\u0438\u0433\u043b\u04af\u04af\u043b\u0436, \u0431\u0443\u0441\u0430\u0434\u0442\u0430\u0439 \u0445\u0443\u0432\u0430\u0430\u043b\u0446\u0430\u0445\u0430\u0434 \u0431\u044d\u043b\u044d\u043d \u0431\u0430\u0439\u0445\u044b\u043d \u0442\u0443\u043b\u0434 \u0441\u0443\u0434\u0440\u044b\u0433 \u0446\u044d\u044d\u0436\u0438\u043b\u0436 \u0431\u0430\u0439\u043d\u0430 \u0443\u0443?\n\u042d\u043d\u044d \u0441\u0430\u0440\u0434 \u0431\u0438\u0434 \u0448\u0438\u043d\u044d \u0437\u04af\u0439\u043b \u044d\u0445\u043b\u04af\u04af\u043b\u044d\u0445 \u0433\u044d\u0436 \u0431\u0430\u0439\u043d\u0430.\n\u0411\u0438\u0434 \u0442\u0430\u043d\u0430\u0430\u0441 \u0433\u0443\u0440\u0430\u0432\u0434\u0443\u0433\u0430\u0430\u0440 \u0441\u0430\u0440\u044b\u043d \u0441\u04af\u04af\u043b \u0433\u044d\u0445\u044d\u0434 \u0441\u0443\u0434\u0440\u044b\u043d \u043d\u044d\u0433 \u0431\u0430\u0434\u0433\u0438\u0439\u0433 \u0446\u044d\u044d\u0436\u043b\u044d\u0445\u0438\u0439\u0433 \u0445\u04af\u0441\u044d\u0445 \u0431\u043e\u043b\u043d\u043e.\n\u0425\u044d\u0440\u044d\u0432 \u0442\u0430 \u04af\u04af\u043d\u0438\u0439\u0433 \u043c\u0430\u043d\u0430\u0439 \u0443\u0434\u0438\u0440\u0434\u0430\u0433\u0447\u0434\u044b\u043d \u043d\u044d\u0433\u044d\u043d\u0434 \u044f\u043c\u0430\u0440 \u0447 \u0445\u044d\u043b\u044d\u044d\u0440 \u0443\u043d\u0448\u0438\u0436 \u04e9\u0433\u0432\u04e9\u043b \u0442\u0430\u043d\u0434 \u043d\u0430\u0430\u043b\u0442 \u04e9\u0433\u04e9\u0445 \u0431\u043e\u043b\u043d\u043e.\n\u0422\u0430 \u04af\u04af\u043d\u0438\u0439\u0433 \u0443\u0441\u043d\u044b \u0441\u0430\u0432 \u044d\u0441\u0432\u044d\u043b \u0434\u044d\u0432\u0442\u044d\u0440 \u0434\u044d\u044d\u0440\u044d\u044d \u0445\u0438\u0439\u0436 \u0431\u043e\u043b\u043d\u043e.\n\u0425\u0430\u0430\u043d\u0430 \u0447 \u0445\u0430\u0440\u0441\u0430\u043d \u0447\u0438 \u04af\u04af\u043d\u0438\u0439\u0433\u044d\u044d \u0436\u0438\u043b\u0438\u0439\u043d \u0442\u0443\u0440\u0448 \u04af\u0440\u0433\u044d\u043b\u0436\u043b\u04af\u04af\u043b\u044d\u043d \u0445\u0438\u0439\u0445 \u0431\u043e\u043b\u043d\u043e.\n\u0413\u0443\u0440\u0430\u0432\u0434\u0443\u0433\u0430\u0430\u0440 \u0441\u0430\u0440\u044b\u043d 2 \u0422\u0438\u043c\u043e\u0442 3:16-\u0433 \u0445\u0430\u043c\u0442\u0434\u0430\u0430 \u0443\u043d\u0448\u0438\u0446\u0433\u0430\u0430\u044f.\n\u0411\u04ae\u0413\u0414: \u201c\u0421\u0443\u0434\u0430\u0440 \u0431\u04af\u0440 \u0411\u0443\u0440\u0445\u0430\u043d\u044b \u0430\u043c\u044c\u0441\u0433\u0430\u043b\u0441\u043d\u0430\u0430\u0440 \u0431\u04e9\u0433\u04e9\u04e9\u0434 \u0437\u04e9\u0432\u0442 \u0431\u0430\u0439\u0434\u0430\u043b\u0434 \u0437\u0430\u0430\u0445, \u0437\u044d\u043c\u043b\u044d\u0445, \u0437\u0430\u043b\u0440\u0443\u0443\u043b\u0430\u0445, \u0441\u0443\u0440\u0433\u0430\u0445\u0430\u0434 \u0442\u0443\u0441\u0442\u0430\u0439\u201d\n\n\u0417\u04e9\u0432 \u0447\u0438\u0433\u043b\u044d\u043b\u0434 \u0433\u04af\u0439\u0445\u044d\u0434 \u0431\u0438\u0434\u044d\u043d\u0434 \u0431\u04af\u0433\u0434\u044d\u0434 \u043d\u044c \u0442\u0443\u0441\u043b\u0430\u043c\u0436 \u0445\u044d\u0440\u044d\u0433\u0442\u044d\u0439.\n\u0417\u04e9\u0432 \u0448\u0443\u0434\u0430\u0440\u0433\u0430\u0430\u0440 \u0430\u043b\u0445\u0430\u0445\u044b\u043d \u0442\u0443\u043b\u0434 \u0431\u0438\u0434\u044d\u043d\u0434 \u0411\u0443\u0440\u0445\u0430\u043d\u044b \u04af\u0433 \u0445\u044d\u0440\u044d\u0433\u0442\u044d\u0439, \u0437\u0430\u0441\u0430\u0436 \u0437\u0430\u043b\u0440\u0443\u0443\u043b\u0436, \u0441\u0443\u0440\u0433\u0430\u0434\u0430\u0433.\n\u041c\u04e9\u043d \u0431\u0438\u0434\u044d\u043d\u0434 \u04ae\u0433\u0438\u0439\u0433 \u043e\u0439\u043b\u0433\u043e\u0436, \u0445\u044d\u0440\u044d\u0433\u0436\u04af\u04af\u043b\u044d\u0445\u044d\u0434 \u0442\u0443\u0441\u043b\u0430\u0445 \u0410\u0440\u0438\u0443\u043d \u0421\u04af\u043d\u0441 \u0445\u044d\u0440\u044d\u0433\u0442\u044d\u0439 \u0442\u0443\u043b \u0437\u0430\u043b\u0431\u0438\u0440\u043b\u0430\u0430\u0440 \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b\u044d\u044d \u0442\u044d\u043d\u0433\u044d\u0440 \u04e9\u04e9\u0434 \u044d\u0440\u0433\u04af\u04af\u043b\u0446\u0433\u044d\u044d\u0435.\n\u0415\u0441\u04af\u0441 \u044d\u044d, \u0431\u0438\u0434 \u0437\u04e9\u0432\u0445\u04e9\u043d \u0422\u0430 \u0433\u0430\u0437\u0430\u0440 \u0442\u044d\u043d\u0433\u044d\u0440\u0438\u0439\u043d \u0445\u043e\u043e\u0440\u043e\u043d\u0434 \u0433\u04af\u04af\u0440 \u0431\u0430\u0440\u044c\u0441\u0430\u043d \u0443\u0447\u0440\u0430\u0430\u0441 \u043b \u042d\u0446\u044d\u0433\u0442\u044d\u0439 \u044f\u0440\u044c\u0436 \u0447\u0430\u0434\u043d\u0430.\n\u0422\u0430 \u0447\u04e9\u0442\u0433\u04e9\u0440\u0438\u0439\u043d \u0443\u0440\u0445\u0438\u0433 \u0443\u0441\u0442\u0433\u0430\u0436, \u0431\u0438\u0434\u043d\u0438\u0439 \u043d\u04af\u0434\u0438\u0439\u0433 \u04af\u043d\u044d\u043d\u0434 \u043d\u044d\u044d\u0441\u044d\u043d.\n\u0410\u0430\u0432 \u0430\u0430, \u0431\u0438\u0434\u044d\u043d\u0434 \u0433\u044d\u043c \u043d\u04af\u0433\u043b\u0438\u0439\u043d\u0445\u044d\u044d \u0442\u0430\u043b\u0430\u0430\u0440 \u04e9\u04e9\u0440\u0441\u0434\u04e9\u0434\u04e9\u04e9 \u0431\u043e\u043b\u043e\u043d \u0442\u0430\u043d\u0434 \u04af\u043d\u044d\u043d\u0447 \u0431\u0430\u0439\u0445\u044b\u043d \u0442\u0443\u043b\u0434 \u0433\u044d\u043c\u0448\u043b\u0438\u0439\u043d \u0431\u044d\u043b\u0433\u0438\u0439\u0433 \u04e9\u0433\u0441\u04e9\u043d\u0434 \u0431\u0430\u044f\u0440\u043b\u0430\u043b\u0430\u0430.\n\u0410\u0440\u0438\u0443\u043d \u0421\u04af\u043d\u0441 \u043c\u0438\u043d\u044c, \u0431\u0438\u0434\u044d\u043d\u0434 \u0430\u0432\u0440\u0430\u043b\u044b\u043d\u0445\u0430\u0430 \u0442\u04e9\u043b\u04e9\u04e9 \u0415\u0441\u04af\u0441 \u0440\u04af\u04af \u044d\u0440\u0433\u044d\u0445 \u0438\u0442\u0433\u044d\u043b\u0438\u0439\u0433 \u04e9\u0433\u0441\u04e9\u043d\u0434 \u0431\u0430\u044f\u0440\u043b\u0430\u043b\u0430\u0430.\n\u04ae\u0433\u0438\u0439\u0433 \u043e\u0439\u043b\u0433\u043e\u0436, \u0430\u043c\u044c\u0434\u0440\u0430\u043b\u0434\u0430\u0430 \u0445\u044d\u0440\u044d\u0433\u0436\u04af\u04af\u043b\u044d\u0445\u0438\u0439\u043d \u0442\u0443\u043b\u0434 \u0431\u0438\u0434\u043d\u0438\u0439 \u043e\u044e\u0443\u043d \u0443\u0445\u0430\u0430\u043d, \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b\u0438\u0439\u0433 \u043d\u044d\u044d.\n\u0411\u0438\u0434\u043d\u0438\u0439 \u04e9\u043c\u043d\u04e9 \u0442\u0430\u0432\u044c\u0441\u0430\u043d \u0443\u0440\u0430\u043b\u0434\u0430\u0430\u043d\u0434 \u0448\u0430\u0440\u0433\u0443\u0443 \u0433\u04af\u0439\u0445\u044d\u0434 \u0431\u0438\u0434\u044d\u043d\u0434 \u0442\u0443\u0441\u043b\u0430\u0430\u0447, \u0431\u0443\u0441\u0434\u044b\u0433 \u0431\u04af\u0440\u044d\u043d \u0431\u04af\u0442\u044d\u043d \u0431\u0430\u0439\u0434\u0430\u043b, \u043d\u0430\u0439\u0434\u0432\u0430\u0440, \u0434\u0438\u0432\u0430\u0430\u0436\u0438\u043d\u0433\u0438\u0439\u043d \u0430\u044f\u043b\u0430\u043b\u0434 \u0431\u0438\u0434\u044d\u043d\u0442\u044d\u0439 \u043d\u044d\u0433\u0434\u044d\u0445\u0438\u0439\u0433 \u0443\u0440\u0438\u0430\u0440\u0430\u0439, \u0430\u043c\u0435\u043d.\n\n\u0411\u044f\u0441\u0430\u043b\u0433\u0430\u043b \u0431\u043e\u043b\u043e\u043d \u0445\u044d\u043b\u044d\u043b\u0446\u04af\u04af\u043b\u0433\u0438\u0439\u043d \u0430\u0441\u0443\u0443\u043b\u0442\u0443\u0443\u0434\n1.  2 \u0422\u0438\u043c\u043e\u0442 2:22 \u0431\u043e\u043b\u043e\u043d \u0414\u0443\u0443\u043b\u0430\u043b 119:35-37-\u0433 \u0443\u043d\u0448\u0438\u043d\u0430 \u0443\u0443.\na) \u0421\u0442\u0440\u0435\u0441\u0441\u0442\u044d\u0439 \u04af\u0435\u0434\u044d\u044d \u044d\u0441\u0432\u044d\u043b \u0442\u0430\u0439\u0442\u0433\u0430\u0440\u0430\u043b \u044d\u0440\u044d\u043b\u0445\u0438\u0439\u043b\u044d\u0445 \u04af\u0435\u0434\u044d\u044d \u0437\u04af\u0440\u0445 \u0441\u044d\u0442\u0433\u044d\u043b \u0447\u0438\u043d\u044c \u201d\u0437\u0430\u043b\u0443\u0443 \u043d\u0430\u0441\u043d\u044b \u0445\u04af\u0441\u044d\u043b \u0442\u044d\u043c\u04af\u04af\u043b\u044d\u043b\u201d-\u0438\u0439\u043d (\u0422\u0430\u0430\u0448\u0430\u0430\u043b, \u042d\u0440\u0445 \u043c\u044d\u0434\u044d\u043b, \u0410\u043b\u0434\u0430\u0440 \u043d\u044d\u0440, \u042d\u0434 \u0445\u04e9\u0440\u04e9\u043d\u0433\u04e9, \u0411\u0430\u0440\u0434\u0430\u043c\u043d\u0430\u043b) \u0430\u043b\u0438\u043d\u0434 \u043d\u044c \u0431\u0430\u0439\u0433\u0430\u043b\u0438\u0430\u0441\u0430\u0430 \u0442\u044d\u043c\u04af\u04af\u043b\u0434\u044d\u0433 \u0432\u044d?\n\n2.  \u0415\u0444\u0435\u0441 2:1-5 \u0431\u043e\u043b\u043e\u043d \u0415\u0437\u0435\u043a\u0438\u0435\u043b 36:26-\u0433 \u0443\u043d\u0448\u0438\u043d\u0430 \u0443\u0443.\n\u0430) \u201d\u04ae\u0445\u0441\u044d\u043d\u201d \u0431\u0430\u0439\u0434\u043b\u0430\u0430\u0441 \u201d\u0430\u043c\u044c\u0434\u201d \u0431\u043e\u043b\u043e\u0445\u044b\u043d \u0442\u0443\u043b\u0434 \u044e\u0443 \u0448\u0430\u0430\u0440\u0434\u043b\u0430\u0433\u0430\u0442\u0430\u0439 \u0432\u044d?\n\u0431) \u0413\u044d\u043c\u0448\u0438\u043b \u0431\u043e\u043b \u043d\u0438\u0433\u04af\u04af\u043b\u0441\u043b\u0438\u0439\u043d \u0431\u044d\u043b\u044d\u0433 \u0433\u044d\u0434\u044d\u0433\u0442 \u0438\u0442\u0433\u044d\u0445 \u043d\u044c \u043d\u04af\u0433\u043b\u0438\u0439\u043d\u0445\u044d\u044d \u0442\u0430\u043b\u0430\u0430\u0440 \u0411\u0443\u0440\u0445\u0430\u043d\u0434 \u0438\u043b\u04af\u04af \u04af\u043d\u044d\u043d\u0447 \u0431\u0430\u0439\u0445\u0430\u0434 \u0442\u0430\u043d\u044c \u0442\u0443\u0441\u0430\u043b\u0434\u0430\u0433 \u0443\u0443?\n\n3.  2 \u0422\u0438\u043c\u043e\u0442 2:23-25\u0430 \u0431\u043e\u043b\u043e\u043d \u041a\u043e\u043b\u043e\u0441\u0430\u0439 3:12-14-\u0438\u0439\u0433 \u0443\u043d\u0448\u0438\u043d\u0430 \u0443\u0443.\n\u0430) \u0411\u0443\u0441\u0434\u044b\u0433 \u043c\u044d\u0442\u0433\u044d\u043b\u0446\u044d\u0445 \u044d\u0441\u0432\u044d\u043b \u0437\u0430\u043b\u0440\u0443\u0443\u043b\u0430\u0445\u0434\u0430\u0430 \u201d\u042d\u0437\u044d\u043d\u0438\u0439 \u0437\u0430\u0440\u0446\u201d \u044f\u043c\u0430\u0440 \u0447\u0430\u043d\u0430\u0440\u0443\u0443\u0434\u044b\u0433 \u0438\u043b\u044d\u0440\u0445\u0438\u0439\u043b\u0434\u044d\u0433 \u0432\u044d?\n\u0431) \u0415\u0441\u04af\u0441 \u0431\u0438\u0434\u043d\u0438\u0439\u0433 \u0430\u0441\u0430\u0440 \u0438\u0445 \u0442\u044d\u0432\u0447\u044d\u044d\u0440, \u044d\u0435\u043b\u0434\u044d\u0433 \u0431\u0430\u0439\u0434\u043b\u0430\u0430\u0440 \u0445\u0430\u0439\u0440\u043b\u0430\u0434\u0430\u0433 \u0431\u0430\u0439\u0441\u0430\u043d \u0442\u0443\u043b \u0442\u0430 \u0430\u043c\u044c\u0434\u0440\u0430\u043b\u0434\u0430\u0430 \u0445\u044d\u043d\u0438\u0439\u0433 \u0442\u044d\u0440\u0445\u04af\u04af \u043d\u0438\u0433\u04af\u04af\u043b\u0441\u043b\u044d\u044d\u0440 \u0445\u0430\u0439\u0440\u043b\u0430\u0445 \u0432\u044d-- \u0445\u044d\u0434\u0438\u0439 \u0442\u044d\u0434 \u0442\u0430\u043d\u0442\u0430\u0439 \u0441\u0430\u043d\u0430\u043b \u043d\u0438\u0439\u043b\u044d\u0445\u0433\u04af\u0439 \u044d\u0441\u0432\u044d\u043b \u0442\u0430\u043d\u0434 \u0434\u0443\u0440\u0433\u04af\u0439 \u0431\u0430\u0439\u0441\u0430\u043d \u0447 \u0433\u044d\u0441\u044d\u043d?\n\n4.  \u0420\u043e\u043c 10:9-11 \u0431\u043e\u043b\u043e\u043d \u0415\u0432\u0440\u0435\u0439 12:1-2-\u044b\u0433 \u0443\u043d\u0448\u0438\u043d\u0430 \u0443\u0443.\n\u0430) \u0415\u0441\u04af\u0441 \u0440\u04af\u04af \u0445\u0430\u0440\u0446\u0430\u0430 \u0447\u0438\u0433\u043b\u04af\u04af\u043b\u044d\u0445 \u043d\u044c \u0431\u0438\u0434\u043d\u0438\u0439\u0433 \u043d\u04af\u0433\u043b\u044d\u044d\u0441 \u044d\u0440\u0433\u044d\u0436, \u0448\u0438\u043d\u044d \u0447\u0438\u0433\u043b\u044d\u043b\u0434 \u0433\u04af\u0439\u0445\u044d\u0434 \u0445\u044d\u0440\u0445\u044d\u043d \u0442\u0443\u0441\u0430\u043b\u0434\u0430\u0433 \u0432\u044d?\n\u0431) 2 \u0422\u0438\u043c\u043e\u0442 3:16-\u0433 \u0446\u044d\u044d\u0436\u043b\u044d\u0445\u044d\u044d \u0441\u0430\u043d\u0430\u0430\u0440\u0430\u0439. \u0411\u0443\u0440\u0445\u0430\u043d\u044b \u04af\u0433\u0438\u0439\u0433 \u043c\u044d\u0434\u044d\u0445 \u043d\u044c \u0431\u0438\u0434\u044d\u043d\u0434 \u0438\u0442\u0433\u044d\u043b\u0438\u0439\u043d \u043c\u0430\u0440\u0430\u0444\u043e\u043d\u044b\u0433 \u0433\u04af\u0439\u0445\u044d\u0434 \u0445\u044d\u0440\u0445\u044d\u043d \u0442\u0443\u0441\u0430\u043b\u0434\u0430\u0433 \u0432\u044d?","portuguese_content":"Para onde voc\u00ea est\u00e1 correndo?\n2 Tim\u00f3teo 2:22-26\nPastor Chris Sicks\n15 de mar\u00e7o de 2026\n\nNa maratona de 2019 em Portland, Oregon, alguns dos melhores corredores acabaram perdendo a prova.\nN\u00e3o porque fossem lentos, mas porque foram pelo caminho errado.\nHavia uma curva no percurso que n\u00e3o estava claramente sinalizada.\nAssim, cerca de 20 dos corredores mais r\u00e1pidos correram mais de uma milha na dire\u00e7\u00e3o errada!\nO erro acrescentou minutos preciosos a uma corrida para a qual eles haviam se preparado durante meses.\nAqueles homens e mulheres correram muito e correram r\u00e1pido.\nMas eles perderam a corrida porque estavam no caminho errado.\nEsta noite daremos continuidade \u00e0 s\u00e9rie de serm\u00f5es baseados no livro de 2 Tim\u00f3teo.\nO ap\u00f3stolo Paulo est\u00e1 escrevendo a Tim\u00f3teo, um jovem pastor da igreja crist\u00e3 em \u00c9feso.\nPaulo est\u00e1 dando a Tim\u00f3teo, e a n\u00f3s hoje, conselhos sobre como permanecer no caminho certo.\n2 Tim\u00f3teo 2:22-26\n22 \u201cFuja, pois, das paix\u00f5es da mocidade e busque a justi\u00e7a, a f\u00e9, o amor e a paz, juntamente com aqueles que invocam o Senhor de cora\u00e7\u00e3o puro.\n23 Evite discuss\u00f5es tolas e sem sentido, pois voc\u00ea sabe que elas geram contendas.\n24 Ao servo do Senhor n\u00e3o conv\u00e9m contender, mas sim ser am\u00e1vel para com todos, apto para ensinar, paciente, suportando o mal,\n25 corrigindo seus oponentes com gentileza.\nTalvez Deus lhes conceda o arrependimento que os leva ao conhecimento da verdade.\n26 e poder\u00e3o cair em si e escapar do la\u00e7o do diabo, que os prendeu para fazerem a sua vontade.\u201d\n\nJuntos leiamos Isa\u00edas 40:8:\n\u201cA erva seca, a flor murcha, mas a palavra do nosso Deus permanece para sempre.\u201d\n\nO vers\u00edculo 22 diz:\n22 \u201cFuja, pois, das paix\u00f5es da mocidade e busque a justi\u00e7a, a f\u00e9, o amor e a paz, juntamente com aqueles que invocam o Senhor com um cora\u00e7\u00e3o puro.\u201d\n\nEste vers\u00edculo \u00e9, na verdade, um resumo do serm\u00e3o de hoje.\nVemos isso frequentemente na Palavra de Deus.\n\u00c0s vezes, a primeira declara\u00e7\u00e3o em um Salmo ou em um par\u00e1grafo ser\u00e1 um resumo.\nAs palavras que se seguem s\u00e3o, ent\u00e3o, uma explica\u00e7\u00e3o de todo o Salmo, par\u00e1grafo ou cap\u00edtulo.\nUm crist\u00e3o maduro, homem ou mulher, \u00e9 algu\u00e9m que se afasta das coisas que o tentaram quando era mais jovem.\nEm vez de \u201cpaix\u00f5es da juventude\u201d, uma pessoa madura aprende a buscar os valores de Deus, incluindo Justi\u00e7a, F\u00e9, Amor e Paz.\nQuando Paulo era jovem, seu nome era Saulo.\nSaul era cheio de orgulho e autoconfian\u00e7a, usando seu poder para perseguir crist\u00e3os e prend\u00ea-los.\nSaul queria ser popular e bem-sucedido e estava disposto a magoar os outros por causa do seu pr\u00f3prio orgulho.\nMas a carta de 2 Tim\u00f3teo foi escrita por Paulo, o crente maduro.\nEle entende o quanto suas paix\u00f5es juvenis o prejudicaram e est\u00e1 alertando Timothy sobre elas.\nNa \u00e9poca em que Paulo escreveu esta carta, Tim\u00f3teo provavelmente tinha cerca de 40 anos.\nMas voc\u00ea n\u00e3o precisa ser jovem para se deixar levar pelas \u201cpaix\u00f5es da juventude\u201d.\nTenho 57 anos, mas ainda estou aprendendo a fugir consistentemente das paix\u00f5es da juventude.\nTenho um amigo da faculdade que tem a mesma idade que eu.\nMas ele ainda vive como vivia h\u00e1 35 anos.\nSua vida \u00e9 dominada pelas paix\u00f5es juvenis dos tempos de faculdade.\nAqui est\u00e3o algumas paix\u00f5es juvenis que muitos de n\u00f3s experimentamos:\n\n*   Prazer: O pecado sexual \u00e9 um exemplo comum do pecado do prazer, mas n\u00e3o \u00e9 o \u00fanico.\nOutros prazeres pecaminosos podem incluir \u00e1lcool, comida e muitos tipos de entretenimento.\nEssas coisas n\u00e3o s\u00e3o ruins se forem usadas corretamente.\nO sexo, por exemplo, \u00e9 uma bela d\u00e1diva no contexto do casamento crist\u00e3o.\nMas quando usamos qualquer coisa de forma errada, damos a ela poder sobre nossas vidas.\nQuando usamos qualquer um dos dons de Deus para preencher o vazio em nossos cora\u00e7\u00f5es, essa coisa se torna um falso deus \u2013 um \u00eddolo.\n\n*   Poder: Quando somos jovens, \u00e0s vezes nos sentimos impotentes, fracos ou inadequados.\nEu tive dificuldades com esses sentimentos na adolesc\u00eancia.\nAlgumas pessoas buscam o poder para encobrir seus sentimentos de fraqueza.\nEles acham que agir com firmeza os ajudar\u00e1 a se sentirem seguros.\nVoc\u00ea sabia que um valent\u00e3o nem sempre \u00e9 t\u00e3o dur\u00e3o quanto parece?\nUm valent\u00e3o geralmente \u00e9 algu\u00e9m que se sente impotente em rela\u00e7\u00e3o a algo em sua vida, ent\u00e3o machuca outras pessoas para se sentir poderoso.\n\n*   Popularidade: Esta tem sido outra forte tenta\u00e7\u00e3o na minha vida.\nEu me preocupo frequentemente se as pessoas gostam de mim.\nEu me importo demais com a opini\u00e3o dos outros.\nE voc\u00ea?\nVoc\u00ea j\u00e1 mudou seu comportamento ou apar\u00eancia para agradar \u00e0s pessoas?\nVoc\u00ea acha que precisa agir ou se vestir de uma determinada maneira para evitar a rejei\u00e7\u00e3o?\n\n*   Posses: O amor ao dinheiro e aos bens materiais \u00e9 um problema para a maioria de n\u00f3s.\nQueremos a seguran\u00e7a e o conforto de ter mais coisas.\nIsso revela uma falta de f\u00e9.\nDeus quer que entendamos que ele \u00e9 nosso ref\u00fagio e fortaleza, ele \u00e9 nosso provedor.\nOs bens materiais prometem felicidade, mas nunca podem cumprir essa promessa.\nPorque nossos cora\u00e7\u00f5es sempre desejar\u00e3o mais.\n\n*   Orgulho: Este \u00e9, na verdade, o pecado que est\u00e1 por tr\u00e1s de todos os outros pecados.\nOrgulho \u00e9 a cren\u00e7a de que eu realmente mere\u00e7o posses, poder, prazer e popularidade.\nPor qu\u00ea? Porque eu sou especial.\nO orgulho sussurra mentiras para n\u00f3s, dizendo:\n\u201cEst\u00e1 tudo bem, voc\u00ea consegue fazer isso \u2014 voc\u00ea merece.\u201d\nOs anunciantes nos dizem a mesma coisa.\nVoc\u00ea merece... V\u00e1 em frente, compre.\nTalvez compre mais alguns, n\u00e3o tem problema.\u201d\n\u00c9 por isso que vemos tantos an\u00fancios como este, porque o nosso orgulho nos leva a querer acreditar nessas coisas.\n\nPosso fazer uma pergunta a voc\u00eas, meus amigos?\nQual dessas cinco coisas lhe parece familiar?\nVoc\u00ea est\u00e1 em busca de orgulho, bens materiais, poder, prazer ou popularidade?\nOu talvez seja outra coisa que te afaste de Deus?\nOnde est\u00e1 seu cora\u00e7\u00e3o hoje, e para onde voc\u00ea est\u00e1 indo?\nVoc\u00ea se lembra do que Deus perguntou a Ad\u00e3o no jardim, depois que ele comeu o fruto?\nAd\u00e3o e Eva estavam escondidos, e Deus disse: \u201cOnde voc\u00ea est\u00e1, Ad\u00e3o?\u201d\nDeus est\u00e1 pedindo a mesma coisa a todos na Terra hoje.\nOnde voc\u00ea est\u00e1?\nEle n\u00e3o est\u00e1 perguntando onde voc\u00ea est\u00e1 fisicamente.\nEle est\u00e1 perguntando: \u201cOnde est\u00e1 o seu cora\u00e7\u00e3o?\u201d\nPorque nossos cora\u00e7\u00f5es s\u00e3o como uma b\u00fassola que nos guia pelo caminho em dire\u00e7\u00e3o \u00e0quilo que mais valorizamos.\nNos perdemos sem nem perceber, porque o pecado \u00e9 trai\u00e7oeiro.\nPrecisamos da ajuda de Deus para enxergar o que se passa dentro de n\u00f3s.\nVamos ler juntos o Salmo 139:23-24, como uma ora\u00e7\u00e3o:\nTODOS: 23 \u201cSonda-me, \u00f3 Deus, e conhece o meu cora\u00e7\u00e3o!\nTeste-me e descubra o que penso!\n24 E vede se h\u00e1 em mim algum caminho mau,\ne guia-me pelo caminho eterno!\n\nSem a ajuda de Deus, n\u00e3o trilharemos o \u201ccaminho eterno\u201d.\nCorreremos na dire\u00e7\u00e3o errada, buscando coisas que nos afastam do cora\u00e7\u00e3o de Deus.\nMas Deus \u00e9 t\u00e3o bom que n\u00e3o fica apenas observando enquanto nos afastamos e nos perdemos.\nEm vez disso, ele procura suas ovelhas perdidas.\nEle vem at\u00e9 n\u00f3s e oferece um caminho de fuga e resgate.\nVeja novamente 2 Tim\u00f3teo 2:25b-26:\n25b \u201cTalvez Deus lhes conceda o arrependimento que leva ao conhecimento da verdade,\n26 e poder\u00e3o cair em si e escapar do la\u00e7o do diabo, que os prendeu para fazerem a sua vontade.\u201d\n\nVoc\u00ea sabia que \u00e9 poss\u00edvel sentir-se completamente livre quando, na verdade, se est\u00e1 preso pelo pecado e pelo diabo?\nO pecado d\u00e1 a sensa\u00e7\u00e3o de liberdade, mas \u00e9 o oposto.\nUma caixa de bateria tem esta apar\u00eancia.\n\u00c9 uma armadilha que captura um animal que estava correndo livremente por uma trilha e, de repente, se viu em perigo.\nSatan\u00e1s coloca mentiras como placas ao longo do percurso da maratona, para nos enganar e nos aprisionar.\nSatan\u00e1s quer que corramos atr\u00e1s do prazer, do poder, da popularidade, das posses e do orgulho.\nEsses \u00eddolos nos prometem liberdade, e a liberdade \u00e9 algo que desejamos muito.\nInfelizmente, acreditamos que essas coisas podem nos ajudar a nos sentir satisfeitos, seguros e felizes.\nMas esses \u00eddolos s\u00e3o armadilhas que nos afastam de Deus e do caminho da verdadeira vida.\nSatan\u00e1s quer esconder de n\u00f3s o caminho da vida, dizendo:\n\u201cSiga este caminho para a vit\u00f3ria e a felicidade!\nSim, \u00e9 por a\u00ed! Sigam-me!\n\nEnt\u00e3o, como um animal pode escapar de uma armadilha como essa?\n\u00c9 algo que ele consegue fazer sozinho?\nN\u00e3o, o coelho est\u00e1 indefeso.\nEle precisa de algu\u00e9m mais inteligente e mais forte para vir resgat\u00e1-lo dessa armadilha.\nPrecisamos de algu\u00e9m mais inteligente e mais forte para nos resgatar tamb\u00e9m.\nEsse \u00e9 o ponto mais importante que quero que voc\u00ea entenda sobre esse vers\u00edculo.\nPrecisamos de um Salvador porque n\u00e3o podemos nos salvar sozinhos, nem mesmo recorrer a Deus.\nCora\u00e7\u00f5es espiritualmente mortos n\u00e3o podem escolher a vida.\nVeja o que diz o vers\u00edculo 25:\n\u201cTalvez Deus lhes conceda o arrependimento.\u201d\n\nUma subven\u00e7\u00e3o \u00e9 um presente gratuito.\nDeus me deu o dom do arrependimento h\u00e1 30 anos.\nDurante 10 anos eu disse que n\u00e3o havia Deus no universo.\nMas, como Deus \u00e9 bondoso, ele me mostrou que cerveja, mulheres e sucesso terreno jamais poderiam satisfazer os desejos do meu cora\u00e7\u00e3o.\n\u00c9 isso que significa \u201ccair em si\u201d no vers\u00edculo 26.\nQuando seu senso de dire\u00e7\u00e3o est\u00e1 confuso, voc\u00ea corre na dire\u00e7\u00e3o errada.\nO primeiro passo para encontrar o caminho de casa \u00e9 reconhecer que voc\u00ea est\u00e1 perdido.\nDan McDowell foi um dos corredores que se perderam naquela maratona em Portland.\nEle disse: \u201cVirei a esquina e vi 10 pessoas simplesmente paradas\u2026\nEles se entreolharam pensando: \u201cHum, isso n\u00e3o me parece certo.\u201d\n\nOutro corredor, Zach Custer, disse que entrou em um t\u00fanel onde os carros passaram por ele a 88 quil\u00f4metros por hora.\nFoi ent\u00e3o que ele percebeu que havia se desviado do caminho.\nAntes de Deus me trazer de volta \u00e0 realidade, eu pensava que tinha \u201cconhecimento da verdade\u201d.\nMeu orgulho me dizia que eu estava no caminho certo e que n\u00e3o precisava de Deus para me guiar, pois eu era muito inteligente.\nIronicamente, eu era muito est\u00fapido para perceber o engano de Satan\u00e1s.\nFui apanhado na sua armadilha de mentiras.\nAcreditei na promessa do diabo de que encontraria a felicidade fugindo de Deus.\nMas ent\u00e3o, Deus me deu o dom do arrependimento.\nA palavra grega para arrependimento neste contexto \u00e9 metanoia.\nSignifica \u201cuma mudan\u00e7a de mentalidade, uma mudan\u00e7a de vida e uma mudan\u00e7a de prop\u00f3sito\u201d.\nJesus me deu um novo cora\u00e7\u00e3o para que eu pudesse \u201cinvocar o Senhor com um cora\u00e7\u00e3o puro\u201d, como diz o vers\u00edculo 22.\nUm cora\u00e7\u00e3o puro \u00e9 um cora\u00e7\u00e3o honesto.\nUm cora\u00e7\u00e3o que clama a Deus: \u201cSinto muito pelo meu pecado, por favor, me perdoe.\u201d\nAjude-me a correr em sua dire\u00e7\u00e3o, n\u00e3o a fugir de voc\u00ea.\u201d\nPaulo escreveu em Romanos 10:9-11 uma explica\u00e7\u00e3o muito clara de como voc\u00ea pode se voltar para Deus e ser salvo.\n9 A saber: Se com a tua boca confessares ao Senhor Jesus, e em teu cora\u00e7\u00e3o creres que Deus o ressuscitou dentre os mortos, ser\u00e1s salvo.\n10 Pois \u00e9 com o cora\u00e7\u00e3o que se cr\u00ea para a justi\u00e7a, e com a boca se confessa para a salva\u00e7\u00e3o.\n11 Como diz a Escritura: \u201cTodo aquele que nele cr\u00ea jamais ser\u00e1 envergonhado\u201d.\n\nVoc\u00ea j\u00e1 confessou sua f\u00e9 com a boca, para que possa ser salvo?\nSe voc\u00ea ainda n\u00e3o fez isso, n\u00e3o acha que hoje seria um \u00f3timo dia para fazer?\nO Esp\u00edrito Santo est\u00e1 aqui entre n\u00f3s, e talvez Ele esteja sussurrando ao seu cora\u00e7\u00e3o:\n\u201cAfastem-se do caminho do pecado e da morte!\nEscolha uma nova vida e uma nova dire\u00e7\u00e3o, declarando que \u2018Jesus \u00e9 o Senhor!\u2019\u201d\n\nPaulo j\u00e1 havia escrito antes sobre essa nova dire\u00e7\u00e3o.\nFoi em uma carta para essa mesma igreja em \u00c9feso, onde Tim\u00f3teo agora serve como pastor.\nOu\u00e7a o que Paulo escreveu aos crist\u00e3os em Ef\u00e9sios 2:1-5, sobre o que Deus fez para lhes dar nova vida e uma nova dire\u00e7\u00e3o:\n1 \u201cE voc\u00eas estavam mortos em seus delitos e pecados.\u201d\n2 nos quais outrora andastes, seguindo o curso deste mundo, seguindo o pr\u00edncipe da potestade do ar, o esp\u00edrito que agora atua nos filhos da desobedi\u00eancia.\n3 Entre os quais todos n\u00f3s tamb\u00e9m viv\u00edamos outrora, segundo as inclina\u00e7\u00f5es da nossa carne, fazendo a vontade da carne e da mente, e \u00e9ramos por natureza filhos da ira, como tamb\u00e9m os demais.\n4 Mas Deus, sendo rico em miseric\u00f3rdia, por causa do grande amor com que nos amou,\n5 Mesmo quando est\u00e1vamos mortos em nossos pecados, nos deu vida juntamente com Cristo \u2014 pela gra\u00e7a voc\u00eas foram salvos!\n\n\u201cMas Deus\u201d s\u00e3o duas das palavras mais belas j\u00e1 ditas.\nPaulo lembra aos crentes em \u00c9feso que eles tamb\u00e9m estiveram presos e indefesos como aquele coelho na armadilha.\nMas Deus interveio para salv\u00e1-los somente pela gra\u00e7a, somente pela f\u00e9, somente em Cristo.\nQualquer pessoa pode ser salva, se acreditar que o sacrif\u00edcio de Cristo na cruz foi por ela, para purific\u00e1-la do pecado e da vergonha.\nQuando voc\u00ea cr\u00ea nisso, recebe uma nova vida e Jesus o coloca em um novo caminho.\nAlguns vers\u00edculos depois, em Ef\u00e9sios 2:8, Paulo fala sobre essa nova dire\u00e7\u00e3o.\nLeiam comigo:\nTODOS: 10 \u201cPois somos cria\u00e7\u00e3o de Deus realizada em Cristo Jesus para fazermos boas obras, as quais Deus preparou de antem\u00e3o para que n\u00f3s as pratic\u00e1ssemos.\u201d\n\nPara finalizar esta mensagem, vejamos o que significa praticar o bem.\nLembre-se de que Paulo est\u00e1 escrevendo a Tim\u00f3teo, dando-lhe orienta\u00e7\u00f5es sobre quem selecionar e treinar como mestres da B\u00edblia.\nE a nossa miss\u00e3o como crentes \u00e9 compartilhar as Boas Novas do Evangelho com pessoas pr\u00f3ximas e distantes.\nMas para fazer isso fielmente, precisamos ter o car\u00e1ter que Paulo descreve nesses vers\u00edculos.\nN\u00e3o podemos mudar o cora\u00e7\u00e3o de ningu\u00e9m.\nMas podemos dizer-lhes a verdade com delicadeza, gentileza e paci\u00eancia.\nE podemos confiar que Deus conceder\u00e1 o arrependimento aos seus filhos escolhidos no momento certo.\nNos vers\u00edculos 24 e 25 da passagem de hoje, vejo cinco qualidades que Deus deseja desenvolver em seus servos:\n\nQualidade 1: N\u00e3o \u00e9 briguento.\nAlgumas pessoas gostam de discutir.\nN\u00e3o h\u00e1 nada de errado com um debate saud\u00e1vel.\nMas como saber quando voc\u00ea est\u00e1 sendo pecaminosamente \u201cbriguento\u201d?\nTalvez voc\u00ea possa se fazer esta pergunta:\n\u201cQuando estou discutindo com algu\u00e9m, me importo mais com essa pessoa ou em vencer a discuss\u00e3o?\u201d\nSer\u00e1 que meu orgulho est\u00e1 me fazendo focar em estar certo, em vez de ser gentil?\n\nQualidade 2: Gentil com todos.\nO servo do Senhor deve ser bondoso para com todos.\nAt\u00e9 mesmo para pessoas que te odeiam e querem te machucar.\n\u00c9 dif\u00edcil, eu sei.\nAcreditamos que a melhor forma de nos protegermos dos outros \u00e9 sermos fortes, usarmos o poder.\nMas observe o que Paulo nos lembra em Romanos 2:4:\n\u201cA bondade de Deus tem o prop\u00f3sito de te levar ao arrependimento.\u201d\nQu\u00e3o bondoso foi Jesus para com voc\u00ea, quando voc\u00ea estava em pecado e fugindo dele?\nA bondade dele te levou ao arrependimento,\nAgora voc\u00ea tem a oportunidade de imitar a Cristo e ser bondoso com todos.\n\nQualidade 3: Suportar o mal com paci\u00eancia.\nAo compartilharmos a verdade do evangelho, enfrentaremos oposi\u00e7\u00e3o de pessoas que n\u00e3o gostam do que estamos dizendo.\nVoc\u00ea se lembra de como Stephen reagiu \u00e0s pessoas que o mataram?\nAtos 7:59-60 diz:\n59 E apedrejavam Est\u00eav\u00e3o, que invocava e dizia: Senhor Jesus, recebe o meu esp\u00edrito!\n60 Ent\u00e3o, ajoelhando-se, clamou em alta voz: Senhor, n\u00e3o lhes imputes este pecado! \n\nS\u00f3 Deus pode nos ajudar a suportar o mal com paci\u00eancia, como Estev\u00e3o fez.\nMas ele nos ajudar\u00e1 quando clamarmos a ele em momentos de dificuldade.\nEle nos ajudar\u00e1 a confiar Nele, sabendo que nossas almas est\u00e3o seguras em Suas m\u00e3os, n\u00e3o importa o que aconte\u00e7a com nossos corpos.\n\nQualidade 4: Corrigir com delicadeza.\nCorrigir as pessoas \u00e9 dif\u00edcil.\nMas se meu filho est\u00e1 fazendo algo errado, eu digo a ele porque o amo.\nEis a quest\u00e3o importante a considerar quando tiver de corrigir algu\u00e9m:\nMeu filho, amigo ou c\u00f4njuge sente o meu amor?\nOu ser\u00e1 que eles s\u00f3 sentem a minha raiva?\u201d\n\nQuando corrigimos com raiva ou frustra\u00e7\u00e3o, estamos agindo como se Deus n\u00e3o pudesse mudar a outra pessoa.\nAcreditamos que podemos pression\u00e1-los para que mudem, ou gritar mais alto at\u00e9 que entrem no caminho certo.\nMas um professor que sabe que Deus tem o verdadeiro poder ser\u00e1 gentil, paciente e bondoso.\n\nQualidade 5: Capacidade de ensinar.\nVoc\u00ea compreende a Palavra de Deus suficientemente bem para explic\u00e1-la aos outros?\nVoc\u00ea est\u00e1 memorizando as escrituras para t\u00ea-las \u00e0 m\u00e3o como guia na vida e para compartilhar com os outros?\nVamos come\u00e7ar algo novo este m\u00eas.\nVamos pedir que voc\u00eas memorizem um vers\u00edculo das Escrituras at\u00e9 o final de mar\u00e7o.\nE se voc\u00ea conseguir recit\u00e1-la para um de nossos l\u00edderes, em qualquer idioma, voc\u00ea ganhar\u00e1 um adesivo.\nVoc\u00ea pode coloc\u00e1-lo em sua garrafa de \u00e1gua ou caderno.\nEm qualquer lugar que voc\u00ea veja e continue praticando durante todo o ano.\nVamos ler juntos o vers\u00edculo do m\u00eas de mar\u00e7o, 2 Tim\u00f3teo 3:16.\nTODOS: \u201cToda a Escritura \u00e9 inspirada por Deus e \u00fatil para o ensino, para a repreens\u00e3o, para a corre\u00e7\u00e3o e para a instru\u00e7\u00e3o na justi\u00e7a.\u201d\n\nTodos precisamos de ajuda para continuarmos correndo na dire\u00e7\u00e3o certa.\nPrecisamos da Palavra de Deus para nos ensinar, corrigir e treinar a andar em retid\u00e3o.\nE precisamos do Esp\u00edrito Santo para nos ajudar a compreender e aplicar a Palavra, ent\u00e3o voltemos nossos cora\u00e7\u00f5es para o c\u00e9u agora em ora\u00e7\u00e3o.\nJesus, s\u00f3 podemos falar com o Pai porque voc\u00ea construiu uma ponte entre a terra e o c\u00e9u.\nTu destru\u00edste as armadilhas do diabo e abriste os nossos olhos para a verdade.\nPai, obrigado por nos dares o dom do arrependimento, para que possamos ser honestos conosco mesmos e contigo a respeito de nossos pecados.\nE obrigada, Esp\u00edrito Santo, por nos dar f\u00e9 para nos voltarmos para Jesus em busca da nossa salva\u00e7\u00e3o.\nAbrir nossas mentes e cora\u00e7\u00f5es para compreender e aplicar a Palavra em nossas vidas.\nAjuda-nos a correr com afinco a corrida que nos foi proposta, convidando outros a se juntarem a n\u00f3s na jornada rumo \u00e0 plenitude, \u00e0 esperan\u00e7a e ao para\u00edso. Am\u00e9m.\n\nPerguntas para Medita\u00e7\u00e3o e Discuss\u00e3o\n1.  Leia 2 Tim\u00f3teo 2:22 e Salmo 119:35-37.\na) Qual das \u201cpaix\u00f5es da juventude\u201d (prazer, poder, popularidade, bens materiais, orgulho) seu cora\u00e7\u00e3o naturalmente busca quando voc\u00ea est\u00e1 estressado ou em busca de conforto?\n\n2.  Leia Ef\u00e9sios 2:1-5 e Ezequiel 36:26.\na) O que \u00e9 necess\u00e1rio para passar de \u201cmorto\u201d para \u201cvivo\u201d?\nb) Acreditar que o arrependimento \u00e9 uma d\u00e1diva da gra\u00e7a ajuda voc\u00ea a ser mais honesto com Deus sobre seus pecados?\n\n3.  Leia 2 Tim\u00f3teo 2:23-25a e Colossenses 3:12-14.\na) Quais s\u00e3o as qualidades do \u201cservo do Senhor\u201d ao debater ou corrigir os outros?\nb) Porque Jesus nos amou com grande paci\u00eancia e gentileza, quem em sua vida voc\u00ea amar\u00e1 com essa mesma gra\u00e7a, mesmo que essa pessoa discorde de voc\u00ea ou n\u00e3o goste de voc\u00ea?\n\n4.  Leia Romanos 10:9-11 e Hebreus 12:1-2.\na) De que forma fixar os nossos olhos em Jesus nos ajuda a afastar-nos do pecado e a seguir numa nova dire\u00e7\u00e3o?\nb) Lembre-se de memorizar 2 Tim\u00f3teo 3:16. Como o conhecimento da Palavra de Deus nos ajuda a correr a maratona da f\u00e9?","russian_content":"\u041a\u0443\u0434\u0430 \u0442\u044b \u0431\u0435\u0436\u0438\u0448\u044c?\n2 \u0422\u0438\u043c\u043e\u0444\u0435\u044e 2:22-26\n\u041f\u0430\u0441\u0442\u043e\u0440 \u041a\u0440\u0438\u0441 \u0421\u0438\u043a\u0441\n15 \u043c\u0430\u0440\u0442\u0430 2026 \u0433.\n\n\u041d\u0430 \u043c\u0430\u0440\u0430\u0444\u043e\u043d\u0435 2019 \u0433\u043e\u0434\u0430 \u0432 \u041f\u043e\u0440\u0442\u043b\u0435\u043d\u0434\u0435, \u0448\u0442\u0430\u0442 \u041e\u0440\u0435\u0433\u043e\u043d, \u043d\u0435\u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u0438\u0437 \u043b\u0443\u0447\u0448\u0438\u0445 \u0431\u0435\u0433\u0443\u043d\u043e\u0432 \u0432 \u0438\u0442\u043e\u0433\u0435 \u043f\u0440\u043e\u0438\u0433\u0440\u0430\u043b\u0438 \u0437\u0430\u0431\u0435\u0433.\n\u041d\u0435 \u043f\u043e\u0442\u043e\u043c\u0443, \u0447\u0442\u043e \u043e\u043d\u0438 \u0435\u0445\u0430\u043b\u0438 \u043c\u0435\u0434\u043b\u0435\u043d\u043d\u043e, \u0430 \u043f\u043e\u0442\u043e\u043c\u0443, \u0447\u0442\u043e \u043e\u043d\u0438 \u043f\u043e\u0448\u043b\u0438 \u043d\u0435 \u0432 \u0442\u0443 \u0441\u0442\u043e\u0440\u043e\u043d\u0443.\n\u041d\u0430 \u0442\u0440\u0430\u0441\u0441\u0435 \u0431\u044b\u043b \u043f\u043e\u0432\u043e\u0440\u043e\u0442, \u043a\u043e\u0442\u043e\u0440\u044b\u0439 \u043d\u0435 \u0431\u044b\u043b \u0447\u0435\u0442\u043a\u043e \u043e\u0431\u043e\u0437\u043d\u0430\u0447\u0435\u043d.\n\u0422\u0430\u043a\u0438\u043c \u043e\u0431\u0440\u0430\u0437\u043e\u043c, \u043e\u043a\u043e\u043b\u043e 20 \u0441\u0430\u043c\u044b\u0445 \u0431\u044b\u0441\u0442\u0440\u044b\u0445 \u0431\u0435\u0433\u0443\u043d\u043e\u0432 \u043f\u0440\u043e\u0431\u0435\u0436\u0430\u043b\u0438 \u0431\u043e\u043b\u0435\u0435 \u043c\u0438\u043b\u0438 \u0432 \u043d\u0435\u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e\u043c \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u0438\u0438!\n\u042d\u0442\u0430 \u043e\u0448\u0438\u0431\u043a\u0430 \u0434\u043e\u0431\u0430\u0432\u0438\u043b\u0430 \u0434\u0440\u0430\u0433\u043e\u0446\u0435\u043d\u043d\u044b\u0435 \u043c\u0438\u043d\u0443\u0442\u044b \u043a \u0437\u0430\u0431\u0435\u0433\u0443, \u043a \u043a\u043e\u0442\u043e\u0440\u043e\u043c\u0443 \u043e\u043d\u0438 \u0433\u043e\u0442\u043e\u0432\u0438\u043b\u0438\u0441\u044c \u043c\u0435\u0441\u044f\u0446\u0430\u043c\u0438.\n\u042d\u0442\u0438 \u043c\u0443\u0436\u0447\u0438\u043d\u044b \u0438 \u0436\u0435\u043d\u0449\u0438\u043d\u044b \u0431\u0435\u0436\u0430\u043b\u0438 \u0438\u0437\u043e \u0432\u0441\u0435\u0445 \u0441\u0438\u043b \u0438 \u043e\u0447\u0435\u043d\u044c \u0431\u044b\u0441\u0442\u0440\u043e.\n\u041d\u043e \u043e\u043d\u0438 \u043f\u0440\u043e\u0438\u0433\u0440\u0430\u043b\u0438 \u0433\u043e\u043d\u043a\u0443, \u043f\u043e\u0442\u043e\u043c\u0443 \u0447\u0442\u043e \u0441\u0432\u0435\u0440\u043d\u0443\u043b\u0438 \u043d\u0430 \u043d\u0435\u0432\u0435\u0440\u043d\u044b\u0439 \u043f\u0443\u0442\u044c.\n\u0421\u0435\u0433\u043e\u0434\u043d\u044f \u0432\u0435\u0447\u0435\u0440\u043e\u043c \u043c\u044b \u043f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u043c \u0446\u0438\u043a\u043b \u043f\u0440\u043e\u043f\u043e\u0432\u0435\u0434\u0435\u0439 \u043f\u043e \u043a\u043d\u0438\u0433\u0435 2 \u0422\u0438\u043c\u043e\u0444\u0435\u044e.\n\u0410\u043f\u043e\u0441\u0442\u043e\u043b \u041f\u0430\u0432\u0435\u043b \u043f\u0438\u0448\u0435\u0442 \u0422\u0438\u043c\u043e\u0444\u0435\u044e, \u043c\u043e\u043b\u043e\u0434\u043e\u043c\u0443 \u043f\u0430\u0441\u0442\u043e\u0440\u0443 \u0445\u0440\u0438\u0441\u0442\u0438\u0430\u043d\u0441\u043a\u043e\u0439 \u0446\u0435\u0440\u043a\u0432\u0438 \u0432 \u042d\u0444\u0435\u0441\u0435.\n\u0421\u0435\u0433\u043e\u0434\u043d\u044f \u041f\u0430\u0432\u0435\u043b \u0434\u0430\u0435\u0442 \u0422\u0438\u043c\u043e\u0444\u0435\u044e, \u0430 \u0432\u043c\u0435\u0441\u0442\u0435 \u0441 \u043d\u0438\u043c \u0438 \u043d\u0430\u043c, \u0441\u043e\u0432\u0435\u0442\u044b \u043e \u0442\u043e\u043c, \u043a\u0430\u043a \u043e\u0441\u0442\u0430\u0432\u0430\u0442\u044c\u0441\u044f \u043d\u0430 \u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e\u043c \u043f\u0443\u0442\u0438.\n2 \u0422\u0438\u043c\u043e\u0444\u0435\u044e 2:22\u201326\n22 \u00ab\u041f\u043e\u044d\u0442\u043e\u043c\u0443 \u0438\u0437\u0431\u0435\u0433\u0430\u0439\u0442\u0435 \u044e\u043d\u043e\u0448\u0435\u0441\u043a\u0438\u0445 \u0441\u0442\u0440\u0430\u0441\u0442\u0435\u0439 \u0438 \u0441\u0442\u0440\u0435\u043c\u0438\u0442\u0435\u0441\u044c \u043a \u043f\u0440\u0430\u0432\u0435\u0434\u043d\u043e\u0441\u0442\u0438, \u0432\u0435\u0440\u0435, \u043b\u044e\u0431\u0432\u0438 \u0438 \u043c\u0438\u0440\u0443 \u0432\u043c\u0435\u0441\u0442\u0435 \u0441 \u0442\u0435\u043c\u0438, \u043a\u0442\u043e \u043f\u0440\u0438\u0437\u044b\u0432\u0430\u0435\u0442 \u0413\u043e\u0441\u043f\u043e\u0434\u0430 \u043e\u0442 \u0447\u0438\u0441\u0442\u043e\u0433\u043e \u0441\u0435\u0440\u0434\u0446\u0430.\n23. \u041d\u0435 \u0432\u0441\u0442\u0443\u043f\u0430\u0439\u0442\u0435 \u0432 \u0433\u043b\u0443\u043f\u044b\u0435, \u043d\u0435\u0432\u0435\u0436\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0435 \u0441\u043f\u043e\u0440\u044b; \u0432\u044b \u0437\u043d\u0430\u0435\u0442\u0435, \u0447\u0442\u043e \u043e\u043d\u0438 \u043f\u043e\u0440\u043e\u0436\u0434\u0430\u044e\u0442 \u0441\u0441\u043e\u0440\u044b.\n24 \u0418 \u0440\u0430\u0431 \u0413\u043e\u0441\u043f\u043e\u0434\u0435\u043d\u044c \u043d\u0435 \u0434\u043e\u043b\u0436\u0435\u043d \u0431\u044b\u0442\u044c \u0441\u0432\u0430\u0440\u043b\u0438\u0432\u044b\u043c, \u043d\u043e \u0434\u043e\u0431\u0440\u044b\u043c \u043a\u043e \u0432\u0441\u0435\u043c, \u0441\u043f\u043e\u0441\u043e\u0431\u043d\u044b\u043c \u0443\u0447\u0438\u0442\u044c, \u0442\u0435\u0440\u043f\u0435\u043b\u0438\u0432\u043e \u043f\u0435\u0440\u0435\u043d\u043e\u0441\u044f\u0449\u0438\u043c \u0437\u043b\u043e,\n25. \u043c\u044f\u0433\u043a\u043e \u043f\u043e\u043f\u0440\u0430\u0432\u043b\u044f\u044f \u0441\u0432\u043e\u0438\u0445 \u043f\u0440\u043e\u0442\u0438\u0432\u043d\u0438\u043a\u043e\u0432.\n\u0412\u043e\u0437\u043c\u043e\u0436\u043d\u043e, \u0411\u043e\u0433 \u0434\u0430\u0440\u0443\u0435\u0442 \u0438\u043c \u043f\u043e\u043a\u0430\u044f\u043d\u0438\u0435, \u0432\u0435\u0434\u0443\u0449\u0435\u0435 \u043a \u043f\u043e\u0437\u043d\u0430\u043d\u0438\u044e \u0438\u0441\u0442\u0438\u043d\u044b.\n26 \u0418 \u043e\u043d\u0438 \u043f\u0440\u0438\u0434\u0443\u0442 \u0432 \u0441\u0435\u0431\u044f \u0438 \u0432\u044b\u0440\u0432\u0443\u0442\u0441\u044f \u0438\u0437 \u0441\u0435\u0442\u0438 \u0434\u044c\u044f\u0432\u043e\u043b\u0430, \u043f\u043e\u0441\u043b\u0435 \u0442\u043e\u0433\u043e \u043a\u0430\u043a \u0431\u0443\u0434\u0443\u0442 \u0437\u0430\u0445\u0432\u0430\u0447\u0435\u043d\u044b \u0438\u043c, \u0447\u0442\u043e\u0431\u044b \u0438\u0441\u043f\u043e\u043b\u043d\u044f\u0442\u044c \u0435\u0433\u043e \u0432\u043e\u043b\u044e.\n\n\u0412\u043c\u0435\u0441\u0442\u0435 \u043c\u044b \u0447\u0438\u0442\u0430\u0435\u043c \u0418\u0441\u0430\u0438\u044e 40:8:\n\u00ab\u0422\u0440\u0430\u0432\u0430 \u0437\u0430\u0441\u044b\u0445\u0430\u0435\u0442, \u0446\u0432\u0435\u0442\u043e\u043a \u0443\u0432\u044f\u0434\u0430\u0435\u0442, \u043d\u043e \u0441\u043b\u043e\u0432\u043e \u0411\u043e\u0433\u0430 \u043d\u0430\u0448\u0435\u0433\u043e \u043f\u0440\u0435\u0431\u0443\u0434\u0435\u0442 \u0432\u043e\u0432\u0435\u043a\u00bb.\n\n\u0412 22-\u043c \u0441\u0442\u0438\u0445\u0435 \u0433\u043e\u0432\u043e\u0440\u0438\u0442\u0441\u044f:\n22 \u00ab\u041f\u043e\u044d\u0442\u043e\u043c\u0443 \u0438\u0437\u0431\u0435\u0433\u0430\u0439\u0442\u0435 \u044e\u043d\u043e\u0448\u0435\u0441\u043a\u0438\u0445 \u0441\u0442\u0440\u0430\u0441\u0442\u0435\u0439 \u0438 \u0441\u0442\u0440\u0435\u043c\u0438\u0442\u0435\u0441\u044c \u043a \u043f\u0440\u0430\u0432\u0435\u0434\u043d\u043e\u0441\u0442\u0438, \u0432\u0435\u0440\u0435, \u043b\u044e\u0431\u0432\u0438 \u0438 \u043c\u0438\u0440\u0443 \u0432\u043c\u0435\u0441\u0442\u0435 \u0441 \u0442\u0435\u043c\u0438, \u043a\u0442\u043e \u043f\u0440\u0438\u0437\u044b\u0432\u0430\u0435\u0442 \u0413\u043e\u0441\u043f\u043e\u0434\u0430 \u043e\u0442 \u0447\u0438\u0441\u0442\u043e\u0433\u043e \u0441\u0435\u0440\u0434\u0446\u0430\u00bb.\n\n\u042d\u0442\u043e\u0442 \u0441\u0442\u0438\u0445, \u043f\u043e \u0441\u0443\u0442\u0438, \u044f\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u043a\u0440\u0430\u0442\u043a\u0438\u043c \u0438\u0437\u043b\u043e\u0436\u0435\u043d\u0438\u0435\u043c \u0441\u0435\u0433\u043e\u0434\u043d\u044f\u0448\u043d\u0435\u0439 \u043f\u0440\u043e\u043f\u043e\u0432\u0435\u0434\u0438.\n\u041c\u044b \u0447\u0430\u0441\u0442\u043e \u0432\u0438\u0434\u0438\u043c \u044d\u0442\u043e \u0432 \u0421\u043b\u043e\u0432\u0435 \u0411\u043e\u0436\u044c\u0435\u043c.\n\u0418\u043d\u043e\u0433\u0434\u0430 \u043f\u0435\u0440\u0432\u043e\u0435 \u0443\u0442\u0432\u0435\u0440\u0436\u0434\u0435\u043d\u0438\u0435 \u0432 \u043f\u0441\u0430\u043b\u043c\u0435 \u0438\u043b\u0438 \u0430\u0431\u0437\u0430\u0446\u0435 \u043f\u0440\u0435\u0434\u0441\u0442\u0430\u0432\u043b\u044f\u0435\u0442 \u0441\u043e\u0431\u043e\u0439 \u043a\u0440\u0430\u0442\u043a\u043e\u0435 \u0438\u0437\u043b\u043e\u0436\u0435\u043d\u0438\u0435 \u0441\u0443\u0442\u0438.\n\u0414\u0430\u043b\u0435\u0435 \u0441\u043b\u0435\u0434\u0443\u044e\u0442 \u0441\u043b\u043e\u0432\u0430, \u0441\u043e\u0434\u0435\u0440\u0436\u0430\u0449\u0438\u0435 \u043e\u0431\u044a\u044f\u0441\u043d\u0435\u043d\u0438\u0435 \u0432\u0441\u0435\u0433\u043e \u043f\u0441\u0430\u043b\u043c\u0430, \u0430\u0431\u0437\u0430\u0446\u0430 \u0438\u043b\u0438 \u0433\u043b\u0430\u0432\u044b.\n\u0417\u0440\u0435\u043b\u044b\u0439 \u0445\u0440\u0438\u0441\u0442\u0438\u0430\u043d\u0438\u043d, \u043c\u0443\u0436\u0447\u0438\u043d\u0430 \u0438\u043b\u0438 \u0436\u0435\u043d\u0449\u0438\u043d\u0430, \u2014 \u044d\u0442\u043e \u0442\u043e\u0442, \u043a\u0442\u043e \u043e\u0442\u0432\u043e\u0440\u0430\u0447\u0438\u0432\u0430\u0435\u0442\u0441\u044f \u043e\u0442 \u0442\u043e\u0433\u043e, \u0447\u0442\u043e \u0438\u0441\u043a\u0443\u0448\u0430\u043b\u043e \u043d\u0430\u0441 \u0432 \u043c\u043e\u043b\u043e\u0434\u043e\u0441\u0442\u0438.\n\u0412\u043c\u0435\u0441\u0442\u043e \u00ab\u044e\u043d\u043e\u0448\u0435\u0441\u043a\u0438\u0445 \u0441\u0442\u0440\u0430\u0441\u0442\u0435\u0439\u00bb \u0437\u0440\u0435\u043b\u044b\u0439 \u0447\u0435\u043b\u043e\u0432\u0435\u043a \u0443\u0447\u0438\u0442\u0441\u044f \u0441\u043b\u0435\u0434\u043e\u0432\u0430\u0442\u044c \u0411\u043e\u0436\u044c\u0438\u043c \u0446\u0435\u043d\u043d\u043e\u0441\u0442\u044f\u043c, \u0432\u043a\u043b\u044e\u0447\u0430\u044f \u043f\u0440\u0430\u0432\u0435\u0434\u043d\u043e\u0441\u0442\u044c, \u0432\u0435\u0440\u0443, \u043b\u044e\u0431\u043e\u0432\u044c \u0438 \u043c\u0438\u0440.\n\u0412 \u044e\u043d\u043e\u0441\u0442\u0438 \u041f\u0430\u0432\u043b\u0430 \u0437\u0432\u0430\u043b\u0438 \u0421\u0430\u0443\u043b.\n\u0421\u0430\u0443\u043b \u0431\u044b\u043b \u043f\u043e\u043b\u043e\u043d \u0433\u043e\u0440\u0434\u043e\u0441\u0442\u0438 \u0438 \u0441\u0430\u043c\u043e\u0443\u0432\u0435\u0440\u0435\u043d\u043d\u043e\u0441\u0442\u0438, \u0438\u0441\u043f\u043e\u043b\u044c\u0437\u0443\u044f \u0441\u0432\u043e\u044e \u0432\u043b\u0430\u0441\u0442\u044c \u0434\u043b\u044f \u043f\u0440\u0435\u0441\u043b\u0435\u0434\u043e\u0432\u0430\u043d\u0438\u044f \u0445\u0440\u0438\u0441\u0442\u0438\u0430\u043d \u0438 \u0437\u0430\u043a\u043b\u044e\u0447\u0435\u043d\u0438\u044f \u0438\u0445 \u0432 \u0442\u044e\u0440\u044c\u043c\u0443.\n\u0421\u0430\u0443\u043b \u0441\u0442\u0440\u0435\u043c\u0438\u043b\u0441\u044f \u043a \u043f\u043e\u043f\u0443\u043b\u044f\u0440\u043d\u043e\u0441\u0442\u0438 \u0438 \u0443\u0441\u043f\u0435\u0445\u0443 \u0438 \u0431\u044b\u043b \u0433\u043e\u0442\u043e\u0432 \u043f\u0440\u0438\u0447\u0438\u043d\u0438\u0442\u044c \u0431\u043e\u043b\u044c \u0434\u0440\u0443\u0433\u0438\u043c \u0438\u0437-\u0437\u0430 \u0441\u043e\u0431\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0439 \u0433\u043e\u0440\u0434\u043e\u0441\u0442\u0438.\n\u041d\u043e \u043f\u043e\u0441\u043b\u0430\u043d\u0438\u0435 \u043a\u043e 2 \u0422\u0438\u043c\u043e\u0444\u0435\u044e \u0431\u044b\u043b\u043e \u043d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u041f\u0430\u0432\u043b\u043e\u043c, \u0437\u0440\u0435\u043b\u044b\u043c \u0432\u0435\u0440\u0443\u044e\u0449\u0438\u043c.\n\u041e\u043d \u043f\u043e\u043d\u0438\u043c\u0430\u0435\u0442, \u043a\u0430\u043a\u043e\u0439 \u0432\u0440\u0435\u0434 \u043d\u0430\u043d\u0435\u0441\u043b\u0438 \u0435\u043c\u0443 \u0435\u0433\u043e \u044e\u043d\u043e\u0448\u0435\u0441\u043a\u0438\u0435 \u0441\u0442\u0440\u0430\u0441\u0442\u0438, \u0438 \u043f\u0440\u0435\u0434\u0443\u043f\u0440\u0435\u0436\u0434\u0430\u0435\u0442 \u0422\u0438\u043c\u043e\u0444\u0435\u044f \u043e\u0431 \u044d\u0442\u043e\u043c.\n\u041d\u0430 \u043c\u043e\u043c\u0435\u043d\u0442 \u043d\u0430\u043f\u0438\u0441\u0430\u043d\u0438\u044f \u044d\u0442\u043e\u0433\u043e \u043f\u0438\u0441\u044c\u043c\u0430 \u041f\u0430\u0432\u043b\u043e\u043c \u0422\u0438\u043c\u043e\u0444\u0435\u044e, \u0432\u0435\u0440\u043e\u044f\u0442\u043d\u043e, \u0431\u044b\u043b\u043e \u043e\u043a\u043e\u043b\u043e 40 \u043b\u0435\u0442.\n\u041d\u043e \u0434\u043b\u044f \u0442\u043e\u0433\u043e, \u0447\u0442\u043e\u0431\u044b \u0441\u0442\u0440\u0435\u043c\u0438\u0442\u044c\u0441\u044f \u043a \u00ab\u044e\u043d\u043e\u0448\u0435\u0441\u043a\u0438\u043c \u0443\u0432\u043b\u0435\u0447\u0435\u043d\u0438\u044f\u043c\u00bb, \u043d\u0435 \u043e\u0431\u044f\u0437\u0430\u0442\u0435\u043b\u044c\u043d\u043e \u0431\u044b\u0442\u044c \u043c\u043e\u043b\u043e\u0434\u044b\u043c.\n\u041c\u043d\u0435 57 \u043b\u0435\u0442, \u043d\u043e \u044f \u0432\u0441\u0451 \u0435\u0449\u0451 \u0443\u0447\u0443\u0441\u044c \u043f\u043e\u0441\u0442\u043e\u044f\u043d\u043d\u043e \u0443\u0431\u0435\u0433\u0430\u0442\u044c \u043e\u0442 \u044e\u043d\u043e\u0448\u0435\u0441\u043a\u0438\u0445 \u0443\u0432\u043b\u0435\u0447\u0435\u043d\u0438\u0439.\n\u0423 \u043c\u0435\u043d\u044f \u0435\u0441\u0442\u044c \u0434\u0440\u0443\u0433 \u0438\u0437 \u043a\u043e\u043b\u043b\u0435\u0434\u0436\u0430, \u043a\u043e\u0442\u043e\u0440\u044b\u0439 \u043c\u043e\u0435\u0433\u043e \u0432\u043e\u0437\u0440\u0430\u0441\u0442\u0430.\n\u041d\u043e \u043e\u043d \u043f\u043e-\u043f\u0440\u0435\u0436\u043d\u0435\u043c\u0443 \u0436\u0438\u0432\u0451\u0442 \u0442\u0430\u043a \u0436\u0435, \u043a\u0430\u043a \u0438 35 \u043b\u0435\u0442 \u043d\u0430\u0437\u0430\u0434.\n\u0412 \u0435\u0433\u043e \u0436\u0438\u0437\u043d\u0438 \u0434\u043e\u043c\u0438\u043d\u0438\u0440\u0443\u044e\u0442 \u044e\u043d\u043e\u0448\u0435\u0441\u043a\u0438\u0435 \u0443\u0432\u043b\u0435\u0447\u0435\u043d\u0438\u044f \u0441\u0442\u0443\u0434\u0435\u043d\u0447\u0435\u0441\u043a\u0438\u0445 \u043b\u0435\u0442.\n\u0412\u043e\u0442 \u043d\u0435\u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u044e\u043d\u043e\u0448\u0435\u0441\u043a\u0438\u0435 \u0443\u0432\u043b\u0435\u0447\u0435\u043d\u0438\u044f, \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u0438\u0441\u043f\u044b\u0442\u044b\u0432\u0430\u044e\u0442 \u043c\u043d\u043e\u0433\u0438\u0435 \u0438\u0437 \u043d\u0430\u0441:\n\n*   \u0423\u0434\u043e\u0432\u043e\u043b\u044c\u0441\u0442\u0432\u0438\u0435: \u0421\u0435\u043a\u0441\u0443\u0430\u043b\u044c\u043d\u044b\u0439 \u0433\u0440\u0435\u0445 \u2014 \u0440\u0430\u0441\u043f\u0440\u043e\u0441\u0442\u0440\u0430\u043d\u0435\u043d\u043d\u044b\u0439 \u043f\u0440\u0438\u043c\u0435\u0440 \u0433\u0440\u0435\u0445\u0430 \u0443\u0434\u043e\u0432\u043e\u043b\u044c\u0441\u0442\u0432\u0438\u044f, \u043d\u043e \u043d\u0435 \u0435\u0434\u0438\u043d\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0439.\n\u041a \u0434\u0440\u0443\u0433\u0438\u043c \u0433\u0440\u0435\u0445\u043e\u0432\u043d\u044b\u043c \u0443\u0434\u043e\u0432\u043e\u043b\u044c\u0441\u0442\u0432\u0438\u044f\u043c \u043c\u043e\u0436\u043d\u043e \u043e\u0442\u043d\u0435\u0441\u0442\u0438 \u0430\u043b\u043a\u043e\u0433\u043e\u043b\u044c, \u0435\u0434\u0443 \u0438 \u0440\u0430\u0437\u043b\u0438\u0447\u043d\u044b\u0435 \u0432\u0438\u0434\u044b \u0440\u0430\u0437\u0432\u043b\u0435\u0447\u0435\u043d\u0438\u0439.\n\u042d\u0442\u0438 \u0432\u0435\u0449\u0438 \u043d\u0435 \u0442\u0430\u043a \u0443\u0436 \u043f\u043b\u043e\u0445\u0438, \u0435\u0441\u043b\u0438 \u0438\u0445 \u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e \u0438\u0441\u043f\u043e\u043b\u044c\u0437\u043e\u0432\u0430\u0442\u044c.\n\u0421\u0435\u043a\u0441, \u043d\u0430\u043f\u0440\u0438\u043c\u0435\u0440, \u044f\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u043f\u0440\u0435\u043a\u0440\u0430\u0441\u043d\u044b\u043c \u0434\u0430\u0440\u043e\u043c \u0432 \u043a\u043e\u043d\u0442\u0435\u043a\u0441\u0442\u0435 \u0445\u0440\u0438\u0441\u0442\u0438\u0430\u043d\u0441\u043a\u043e\u0433\u043e \u0431\u0440\u0430\u043a\u0430.\n\u041d\u043e \u043a\u043e\u0433\u0434\u0430 \u043c\u044b \u0438\u0441\u043f\u043e\u043b\u044c\u0437\u0443\u0435\u043c \u0447\u0442\u043e-\u043b\u0438\u0431\u043e \u043d\u0435\u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e, \u043c\u044b \u043d\u0430\u0434\u0435\u043b\u044f\u0435\u043c \u044d\u0442\u043e \u0432\u043b\u0430\u0441\u0442\u044c\u044e \u043d\u0430\u0434 \u0441\u0432\u043e\u0435\u0439 \u0436\u0438\u0437\u043d\u044c\u044e.\n\u041a\u043e\u0433\u0434\u0430 \u043c\u044b \u0438\u0441\u043f\u043e\u043b\u044c\u0437\u0443\u0435\u043c \u043a\u0430\u043a\u0438\u0435-\u043b\u0438\u0431\u043e \u0434\u0430\u0440\u044b \u0411\u043e\u0436\u044c\u0438, \u0447\u0442\u043e\u0431\u044b \u0437\u0430\u043f\u043e\u043b\u043d\u0438\u0442\u044c \u043f\u0443\u0441\u0442\u043e\u0442\u0443 \u0432 \u043d\u0430\u0448\u0438\u0445 \u0441\u0435\u0440\u0434\u0446\u0430\u0445, \u044d\u0442\u0430 \u0432\u0435\u0449\u044c \u0441\u0442\u0430\u043d\u043e\u0432\u0438\u0442\u0441\u044f \u043b\u043e\u0436\u043d\u044b\u043c \u0431\u043e\u0433\u043e\u043c \u2014 \u0438\u0434\u043e\u043b\u043e\u043c.\n\n*   \u0412\u043b\u0430\u0441\u0442\u044c: \u0412 \u043c\u043e\u043b\u043e\u0434\u043e\u0441\u0442\u0438 \u043c\u044b \u0438\u043d\u043e\u0433\u0434\u0430 \u0447\u0443\u0432\u0441\u0442\u0432\u0443\u0435\u043c \u0441\u0435\u0431\u044f \u0431\u0435\u0441\u0441\u0438\u043b\u044c\u043d\u044b\u043c\u0438, \u0441\u043b\u0430\u0431\u044b\u043c\u0438 \u0438\u043b\u0438 \u043d\u0435\u043f\u043e\u043b\u043d\u043e\u0446\u0435\u043d\u043d\u044b\u043c\u0438.\n\u0412 \u043f\u043e\u0434\u0440\u043e\u0441\u0442\u043a\u043e\u0432\u043e\u043c \u0432\u043e\u0437\u0440\u0430\u0441\u0442\u0435 \u044f \u0431\u043e\u0440\u043e\u043b\u0441\u044f \u0441 \u044d\u0442\u0438\u043c\u0438 \u0447\u0443\u0432\u0441\u0442\u0432\u0430\u043c\u0438.\n\u041d\u0435\u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u043b\u044e\u0434\u0438 \u0441\u0442\u0440\u0435\u043c\u044f\u0442\u0441\u044f \u043a \u0432\u043b\u0430\u0441\u0442\u0438, \u0447\u0442\u043e\u0431\u044b \u0441\u043a\u0440\u044b\u0442\u044c \u0441\u0432\u043e\u044e \u0441\u043b\u0430\u0431\u043e\u0441\u0442\u044c.\n\u041e\u043d\u0438 \u0441\u0447\u0438\u0442\u0430\u044e\u0442, \u0447\u0442\u043e, \u0434\u0435\u043c\u043e\u043d\u0441\u0442\u0440\u0438\u0440\u0443\u044f \u0441\u0438\u043b\u0443 \u0434\u0443\u0445\u0430, \u043e\u043d\u0438 \u043f\u043e\u0447\u0443\u0432\u0441\u0442\u0432\u0443\u044e\u0442 \u0441\u0435\u0431\u044f \u0432 \u0431\u0435\u0437\u043e\u043f\u0430\u0441\u043d\u043e\u0441\u0442\u0438.\n\u0410 \u0432\u044b \u0437\u043d\u0430\u043b\u0438, \u0447\u0442\u043e \u0445\u0443\u043b\u0438\u0433\u0430\u043d \u043d\u0430 \u0441\u0430\u043c\u043e\u043c \u0434\u0435\u043b\u0435 \u043d\u0435 \u0442\u0430\u043a\u043e\u0439 \u0443\u0436 \u0438 \u043a\u0440\u0443\u0442\u043e\u0439, \u043a\u0430\u043a \u043a\u0430\u0436\u0435\u0442\u0441\u044f?\n\u041e\u0431\u044b\u0447\u043d\u043e \u0445\u0443\u043b\u0438\u0433\u0430\u043d\u043e\u043c \u043d\u0430\u0437\u044b\u0432\u0430\u044e\u0442 \u0447\u0435\u043b\u043e\u0432\u0435\u043a\u0430, \u043a\u043e\u0442\u043e\u0440\u044b\u0439 \u0447\u0443\u0432\u0441\u0442\u0432\u0443\u0435\u0442 \u0441\u0435\u0431\u044f \u0431\u0435\u0441\u0441\u0438\u043b\u044c\u043d\u044b\u043c \u0432 \u0447\u0435\u043c-\u0442\u043e \u0432 \u0441\u0432\u043e\u0435\u0439 \u0436\u0438\u0437\u043d\u0438, \u043f\u043e\u044d\u0442\u043e\u043c\u0443 \u043e\u043d \u043f\u0440\u0438\u0447\u0438\u043d\u044f\u0435\u0442 \u0431\u043e\u043b\u044c \u0434\u0440\u0443\u0433\u0438\u043c \u043b\u044e\u0434\u044f\u043c, \u0447\u0442\u043e\u0431\u044b \u043f\u043e\u0447\u0443\u0432\u0441\u0442\u0432\u043e\u0432\u0430\u0442\u044c \u0441\u0435\u0431\u044f \u0441\u0438\u043b\u044c\u043d\u044b\u043c.\n\n*   \u041f\u043e\u043f\u0443\u043b\u044f\u0440\u043d\u043e\u0441\u0442\u044c: \u044d\u0442\u043e \u0435\u0449\u0435 \u043e\u0434\u043d\u043e \u0441\u0438\u043b\u044c\u043d\u043e\u0435 \u0438\u0441\u043a\u0443\u0448\u0435\u043d\u0438\u0435 \u0432 \u043c\u043e\u0435\u0439 \u0436\u0438\u0437\u043d\u0438.\n\u041c\u0435\u043d\u044f \u0447\u0430\u0441\u0442\u043e \u0431\u0435\u0441\u043f\u043e\u043a\u043e\u0438\u0442, \u043d\u0440\u0430\u0432\u043b\u044e\u0441\u044c \u043b\u0438 \u044f \u043b\u044e\u0434\u044f\u043c.\n\u041c\u043d\u0435 \u0441\u043b\u0438\u0448\u043a\u043e\u043c \u0432\u0430\u0436\u043d\u043e \u043c\u043d\u0435\u043d\u0438\u0435 \u0434\u0440\u0443\u0433\u0438\u0445 \u043b\u044e\u0434\u0435\u0439.\n\u0410 \u0442\u044b?\n\u0412\u044b \u043a\u043e\u0433\u0434\u0430-\u043d\u0438\u0431\u0443\u0434\u044c \u043c\u0435\u043d\u044f\u043b\u0438 \u0441\u0432\u043e\u0435 \u043f\u043e\u0432\u0435\u0434\u0435\u043d\u0438\u0435 \u0438\u043b\u0438 \u0432\u043d\u0435\u0448\u043d\u043e\u0441\u0442\u044c, \u0447\u0442\u043e\u0431\u044b \u043f\u043e\u043d\u0440\u0430\u0432\u0438\u0442\u044c\u0441\u044f \u043b\u044e\u0434\u044f\u043c?\n\u041a\u0430\u043a \u0432\u044b \u0434\u0443\u043c\u0430\u0435\u0442\u0435, \u043d\u0443\u0436\u043d\u043e \u043b\u0438 \u0432\u0435\u0441\u0442\u0438 \u0441\u0435\u0431\u044f \u0438\u043b\u0438 \u0432\u044b\u0433\u043b\u044f\u0434\u0435\u0442\u044c \u043e\u043f\u0440\u0435\u0434\u0435\u043b\u0451\u043d\u043d\u044b\u043c \u043e\u0431\u0440\u0430\u0437\u043e\u043c, \u0447\u0442\u043e\u0431\u044b \u0438\u0437\u0431\u0435\u0436\u0430\u0442\u044c \u043e\u0442\u043a\u0430\u0437\u0430?\n\n*   \u0418\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u043e: \u041b\u044e\u0431\u043e\u0432\u044c \u043a \u0434\u0435\u043d\u044c\u0433\u0430\u043c \u0438 \u043c\u0430\u0442\u0435\u0440\u0438\u0430\u043b\u044c\u043d\u044b\u043c \u0431\u043b\u0430\u0433\u0430\u043c \u2014 \u043f\u0440\u043e\u0431\u043b\u0435\u043c\u0430 \u0434\u043b\u044f \u0431\u043e\u043b\u044c\u0448\u0438\u043d\u0441\u0442\u0432\u0430 \u0438\u0437 \u043d\u0430\u0441.\n\u041c\u044b \u0445\u043e\u0442\u0438\u043c \u0447\u0443\u0432\u0441\u0442\u0432\u043e\u0432\u0430\u0442\u044c \u0441\u0435\u0431\u044f \u0432 \u0431\u0435\u0437\u043e\u043f\u0430\u0441\u043d\u043e\u0441\u0442\u0438 \u0438 \u043a\u043e\u043c\u0444\u043e\u0440\u0442\u0435, \u0438\u043c\u0435\u044f \u0431\u043e\u043b\u044c\u0448\u0435 \u0432\u0435\u0449\u0435\u0439.\n\u042d\u0442\u043e \u0441\u0432\u0438\u0434\u0435\u0442\u0435\u043b\u044c\u0441\u0442\u0432\u0443\u0435\u0442 \u043e \u043d\u0435\u0434\u043e\u0441\u0442\u0430\u0442\u043a\u0435 \u0432\u0435\u0440\u044b.\n\u0411\u043e\u0433 \u0445\u043e\u0447\u0435\u0442, \u0447\u0442\u043e\u0431\u044b \u043c\u044b \u043f\u043e\u043d\u044f\u043b\u0438, \u0447\u0442\u043e \u041e\u043d \u2014 \u043d\u0430\u0448\u0435 \u0443\u0431\u0435\u0436\u0438\u0449\u0435 \u0438 \u043a\u0440\u0435\u043f\u043e\u0441\u0442\u044c, \u041e\u043d \u2014 \u043d\u0430\u0448 \u043a\u043e\u0440\u043c\u0438\u0442\u0435\u043b\u044c.\n\u041c\u0430\u0442\u0435\u0440\u0438\u0430\u043b\u044c\u043d\u044b\u0435 \u0432\u0435\u0449\u0438 \u0441\u0443\u043b\u044f\u0442 \u0441\u0447\u0430\u0441\u0442\u044c\u0435, \u043d\u043e \u043e\u043d\u0438 \u043d\u0438\u043a\u043e\u0433\u0434\u0430 \u043d\u0435 \u0441\u043c\u043e\u0433\u0443\u0442 \u0441\u0434\u0435\u0440\u0436\u0430\u0442\u044c \u0441\u0432\u043e\u0435\u0433\u043e \u043e\u0431\u0435\u0449\u0430\u043d\u0438\u044f.\n\u041f\u043e\u0442\u043e\u043c\u0443 \u0447\u0442\u043e \u043d\u0430\u0448\u0438 \u0441\u0435\u0440\u0434\u0446\u0430 \u0432\u0441\u0435\u0433\u0434\u0430 \u0431\u0443\u0434\u0443\u0442 \u0436\u0430\u0436\u0434\u0430\u0442\u044c \u0431\u043e\u043b\u044c\u0448\u0435\u0433\u043e.\n\n*   \u0413\u043e\u0440\u0434\u044b\u043d\u044f: \u044d\u0442\u043e, \u043f\u043e \u0441\u0443\u0442\u0438, \u0433\u0440\u0435\u0445, \u043b\u0435\u0436\u0430\u0449\u0438\u0439 \u0432 \u043e\u0441\u043d\u043e\u0432\u0435 \u0432\u0441\u0435\u0445 \u043e\u0441\u0442\u0430\u043b\u044c\u043d\u044b\u0445 \u0433\u0440\u0435\u0445\u043e\u0432.\n\u0413\u043e\u0440\u0434\u043e\u0441\u0442\u044c \u2014 \u044d\u0442\u043e \u0443\u0431\u0435\u0436\u0434\u0435\u043d\u0438\u0435 \u0432 \u0442\u043e\u043c, \u0447\u0442\u043e \u044f \u0434\u0435\u0439\u0441\u0442\u0432\u0438\u0442\u0435\u043b\u044c\u043d\u043e \u0437\u0430\u0441\u043b\u0443\u0436\u0438\u0432\u0430\u044e \u043c\u0430\u0442\u0435\u0440\u0438\u0430\u043b\u044c\u043d\u044b\u0445 \u0431\u043b\u0430\u0433, \u0432\u043b\u0430\u0441\u0442\u0438, \u0443\u0434\u043e\u0432\u043e\u043b\u044c\u0441\u0442\u0432\u0438\u0439 \u0438 \u043f\u043e\u043f\u0443\u043b\u044f\u0440\u043d\u043e\u0441\u0442\u0438.\n\u041f\u043e\u0447\u0435\u043c\u0443? \u041f\u043e\u0442\u043e\u043c\u0443 \u0447\u0442\u043e \u044f \u043e\u0441\u043e\u0431\u0435\u043d\u043d\u044b\u0439.\n\u0413\u043e\u0440\u0434\u043e\u0441\u0442\u044c \u043d\u0430\u0448\u0435\u043f\u0442\u044b\u0432\u0430\u0435\u0442 \u043d\u0430\u043c \u043b\u043e\u0436\u044c, \u0433\u043e\u0432\u043e\u0440\u044f:\n\u00ab\u0412\u0441\u0451 \u0432 \u043f\u043e\u0440\u044f\u0434\u043a\u0435, \u0442\u044b \u0441\u043c\u043e\u0436\u0435\u0448\u044c \u044d\u0442\u043e \u0441\u0434\u0435\u043b\u0430\u0442\u044c \u2014 \u0442\u044b \u044d\u0442\u043e\u0433\u043e \u0437\u0430\u0441\u043b\u0443\u0436\u0438\u043b\u0430\u00bb.\n\u0420\u0435\u043a\u043b\u0430\u043c\u043e\u0434\u0430\u0442\u0435\u043b\u0438 \u0433\u043e\u0432\u043e\u0440\u044f\u0442 \u043d\u0430\u043c \u0442\u043e \u0436\u0435 \u0441\u0430\u043c\u043e\u0435.\n\u00ab\u0422\u044b \u044d\u0442\u043e\u0433\u043e \u0437\u0430\u0441\u043b\u0443\u0436\u0438\u043b\u2026 \u0414\u0430\u0432\u0430\u0439, \u043a\u0443\u043f\u0438 \u044d\u0442\u043e\u00bb.\n\u041c\u043e\u0436\u0435\u0442 \u0431\u044b\u0442\u044c, \u043a\u0443\u043f\u0438\u0442\u0435 \u0435\u0449\u0451, \u043d\u0438\u0447\u0435\u0433\u043e \u0441\u0442\u0440\u0430\u0448\u043d\u043e\u0433\u043e.\n\u0412\u043e\u0442 \u043f\u043e\u0447\u0435\u043c\u0443 \u043c\u044b \u0432\u0438\u0434\u0438\u043c \u0442\u0430\u043a \u043c\u043d\u043e\u0433\u043e \u043f\u043e\u0434\u043e\u0431\u043d\u043e\u0439 \u0440\u0435\u043a\u043b\u0430\u043c\u044b: \u043d\u0430\u0448\u0430 \u0433\u043e\u0440\u0434\u043e\u0441\u0442\u044c \u0434\u0435\u0439\u0441\u0442\u0432\u0438\u0442\u0435\u043b\u044c\u043d\u043e \u0445\u043e\u0447\u0435\u0442 \u0432\u0435\u0440\u0438\u0442\u044c \u0432 \u044d\u0442\u0438 \u0432\u0435\u0449\u0438.\n\n\u041f\u043e\u0437\u0432\u043e\u043b\u044c\u0442\u0435 \u0437\u0430\u0434\u0430\u0442\u044c \u0432\u0430\u043c \u0432\u043e\u043f\u0440\u043e\u0441, \u0434\u0440\u0443\u0437\u044c\u044f \u043c\u043e\u0438?\n\u0427\u0442\u043e \u0438\u0437 \u044d\u0442\u0438\u0445 \u043f\u044f\u0442\u0438 \u0432\u0430\u043c \u043a\u0430\u0436\u0435\u0442\u0441\u044f \u0437\u043d\u0430\u043a\u043e\u043c\u044b\u043c?\n\u0412\u044b \u0441\u0442\u0440\u0435\u043c\u0438\u0442\u0435\u0441\u044c \u043a \u0433\u043e\u0440\u0434\u043e\u0441\u0442\u0438, \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0443, \u0432\u043b\u0430\u0441\u0442\u0438, \u0443\u0434\u043e\u0432\u043e\u043b\u044c\u0441\u0442\u0432\u0438\u044e \u0438\u043b\u0438 \u043f\u043e\u043f\u0443\u043b\u044f\u0440\u043d\u043e\u0441\u0442\u0438?\n\u0410 \u043c\u043e\u0436\u0435\u0442 \u0431\u044b\u0442\u044c, \u0432\u0430\u0441 \u043e\u0442\u0434\u0430\u043b\u044f\u0435\u0442 \u043e\u0442 \u0411\u043e\u0433\u0430 \u0447\u0442\u043e-\u0442\u043e \u0434\u0440\u0443\u0433\u043e\u0435?\n\u0413\u0434\u0435 \u0441\u0435\u0433\u043e\u0434\u043d\u044f \u0432\u0430\u0448\u0435 \u0441\u0435\u0440\u0434\u0446\u0435, \u0438 \u043a\u0443\u0434\u0430 \u0432\u044b \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u044f\u0435\u0442\u0435\u0441\u044c?\n\u041f\u043e\u043c\u043d\u0438\u0442\u0435, \u0447\u0442\u043e \u0411\u043e\u0433 \u0441\u043f\u0440\u043e\u0441\u0438\u043b \u0443 \u0410\u0434\u0430\u043c\u0430 \u0432 \u0441\u0430\u0434\u0443 \u043f\u043e\u0441\u043b\u0435 \u0442\u043e\u0433\u043e, \u043a\u0430\u043a \u043e\u043d \u0441\u044a\u0435\u043b \u043f\u043b\u043e\u0434?\n\u0410\u0434\u0430\u043c \u0438 \u0415\u0432\u0430 \u043f\u0440\u044f\u0442\u0430\u043b\u0438\u0441\u044c, \u0438 \u0411\u043e\u0433 \u0441\u043f\u0440\u043e\u0441\u0438\u043b: \u00ab\u0413\u0434\u0435 \u0442\u044b, \u0410\u0434\u0430\u043c?\u00bb\n\u0421\u0435\u0433\u043e\u0434\u043d\u044f \u0411\u043e\u0433 \u043f\u0440\u043e\u0441\u0438\u0442 \u043e\u0431 \u043e\u0434\u043d\u043e\u043c \u0438 \u0442\u043e\u043c \u0436\u0435 \u043a\u0430\u0436\u0434\u043e\u0433\u043e \u0447\u0435\u043b\u043e\u0432\u0435\u043a\u0430 \u043d\u0430 \u0437\u0435\u043c\u043b\u0435.\n\u0413\u0434\u0435 \u0442\u044b?\n\u041e\u043d \u043d\u0435 \u0441\u043f\u0440\u0430\u0448\u0438\u0432\u0430\u0435\u0442, \u0433\u0434\u0435 \u0432\u044b \u0444\u0438\u0437\u0438\u0447\u0435\u0441\u043a\u0438 \u043d\u0430\u0445\u043e\u0434\u0438\u0442\u0435\u0441\u044c.\n\u041e\u043d \u0441\u043f\u0440\u0430\u0448\u0438\u0432\u0430\u0435\u0442: \u00ab\u0413\u0434\u0435 \u0442\u0432\u043e\u0451 \u0441\u0435\u0440\u0434\u0446\u0435?\u00bb\n\u041f\u043e\u0442\u043e\u043c\u0443 \u0447\u0442\u043e \u043d\u0430\u0448\u0438 \u0441\u0435\u0440\u0434\u0446\u0430 \u043f\u043e\u0434\u043e\u0431\u043d\u044b \u043a\u043e\u043c\u043f\u0430\u0441\u0443, \u043a\u043e\u0442\u043e\u0440\u044b\u0439 \u0432\u0435\u0434\u0435\u0442 \u043d\u0430\u0441 \u043f\u043e \u043f\u0443\u0442\u0438 \u043a \u0442\u043e\u043c\u0443, \u0447\u0442\u043e \u043c\u044b \u0446\u0435\u043d\u0438\u043c \u0431\u043e\u043b\u044c\u0448\u0435 \u0432\u0441\u0435\u0433\u043e.\n\u041c\u044b \u0437\u0430\u0431\u043b\u0443\u0434\u0438\u043b\u0438\u0441\u044c, \u0434\u0430\u0436\u0435 \u043d\u0435 \u043e\u0441\u043e\u0437\u043d\u0430\u0432\u0430\u044f \u044d\u0442\u043e\u0433\u043e, \u043f\u043e\u0442\u043e\u043c\u0443 \u0447\u0442\u043e \u0433\u0440\u0435\u0445 \u043a\u043e\u0432\u0430\u0440\u0435\u043d.\n\u041d\u0430\u043c \u043d\u0443\u0436\u043d\u0430 \u0411\u043e\u0436\u044c\u044f \u043f\u043e\u043c\u043e\u0449\u044c, \u0447\u0442\u043e\u0431\u044b \u0443\u0432\u0438\u0434\u0435\u0442\u044c, \u0447\u0442\u043e \u043f\u0440\u043e\u0438\u0441\u0445\u043e\u0434\u0438\u0442 \u0432\u043d\u0443\u0442\u0440\u0438 \u043d\u0430\u0441.\n\u0414\u0430\u0432\u0430\u0439\u0442\u0435 \u0432\u043c\u0435\u0441\u0442\u0435 \u043f\u0440\u043e\u0447\u0438\u0442\u0430\u0435\u043c \u041f\u0441\u0430\u043b\u043e\u043c 139:23\u201324 \u043a\u0430\u043a \u043c\u043e\u043b\u0438\u0442\u0432\u0443:\n\u0412\u0421\u0415: 23 \u00ab\u0418\u0441\u0441\u043b\u0435\u0434\u0443\u0439 \u043c\u0435\u043d\u044f, \u0411\u043e\u0436\u0435, \u0438 \u043f\u043e\u0437\u043d\u0430\u0439 \u0441\u0435\u0440\u0434\u0446\u0435 \u043c\u043e\u0435!\u00bb\n\u041f\u0440\u043e\u0432\u0435\u0440\u044c\u0442\u0435 \u043c\u0435\u043d\u044f \u0438 \u0443\u0437\u043d\u0430\u0439\u0442\u0435, \u0447\u0442\u043e \u044f \u0434\u0443\u043c\u0430\u044e!\n24 \u0418 \u043f\u043e\u0441\u043c\u043e\u0442\u0440\u0438, \u043d\u0435\u0442 \u043b\u0438 \u0432\u043e \u043c\u043d\u0435 \u043f\u0443\u0442\u0438 \u0442\u044f\u0436\u043a\u043e\u0433\u043e.\n\u0438 \u0432\u0435\u0434\u0438 \u043c\u0435\u043d\u044f \u043f\u043e \u043f\u0443\u0442\u0438 \u0432\u0435\u0447\u043d\u043e\u043c\u0443!\n\n\u0411\u0435\u0437 \u0411\u043e\u0436\u044c\u0435\u0439 \u043f\u043e\u043c\u043e\u0449\u0438 \u043c\u044b \u043d\u0435 \u0441\u043c\u043e\u0436\u0435\u043c \u0438\u0434\u0442\u0438 \u00ab\u043f\u0443\u0442\u0435\u043c \u0432\u0435\u0447\u043d\u044b\u043c\u00bb.\n\u041c\u044b \u0431\u0443\u0434\u0435\u043c \u0434\u0432\u0438\u0433\u0430\u0442\u044c\u0441\u044f \u0432 \u043d\u0435\u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e\u043c \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u0438\u0438, \u0441\u0442\u0440\u0435\u043c\u044f\u0441\u044c \u043a \u0442\u043e\u043c\u0443, \u0447\u0442\u043e \u0443\u0432\u043e\u0434\u0438\u0442 \u043d\u0430\u0441 \u0434\u0430\u043b\u0435\u043a\u043e \u043e\u0442 \u0441\u0435\u0440\u0434\u0446\u0430 \u0411\u043e\u0436\u044c\u0435\u0433\u043e.\n\u041d\u043e \u0411\u043e\u0433 \u043d\u0430\u0441\u0442\u043e\u043b\u044c\u043a\u043e \u0431\u043b\u0430\u0433, \u0447\u0442\u043e \u043d\u0435 \u043f\u0440\u043e\u0441\u0442\u043e \u043d\u0430\u0431\u043b\u044e\u0434\u0430\u0435\u0442, \u043a\u0430\u043a \u043c\u044b \u0441\u0431\u0438\u0432\u0430\u0435\u043c\u0441\u044f \u0441 \u043f\u0443\u0442\u0438 \u0438 \u0442\u0435\u0440\u044f\u0435\u043c\u0441\u044f.\n\u0412\u043c\u0435\u0441\u0442\u043e \u044d\u0442\u043e\u0433\u043e \u041e\u043d \u0438\u0449\u0435\u0442 \u0421\u0432\u043e\u0438\u0445 \u0437\u0430\u0431\u043b\u0443\u0434\u0448\u0438\u0445 \u043e\u0432\u0435\u0446.\n\u041e\u043d \u043f\u0440\u0438\u0445\u043e\u0434\u0438\u0442 \u043a \u043d\u0430\u043c \u0438 \u043f\u0440\u0435\u0434\u043b\u0430\u0433\u0430\u0435\u0442 \u043f\u0443\u0442\u044c \u043a \u0441\u043f\u0430\u0441\u0435\u043d\u0438\u044e \u0438 \u043e\u0441\u0432\u043e\u0431\u043e\u0436\u0434\u0435\u043d\u0438\u044e.\n\u0412\u0437\u0433\u043b\u044f\u043d\u0438\u0442\u0435 \u0435\u0449\u0435 \u0440\u0430\u0437 \u043d\u0430 2 \u0422\u0438\u043c\u043e\u0444\u0435\u044e 2:25\u0431-26:\n25\u0431 \u00ab\u0412\u043e\u0437\u043c\u043e\u0436\u043d\u043e, \u0411\u043e\u0433 \u0434\u0430\u0440\u0443\u0435\u0442 \u0438\u043c \u043f\u043e\u043a\u0430\u044f\u043d\u0438\u0435, \u0432\u0435\u0434\u0443\u0449\u0435\u0435 \u043a \u043f\u043e\u0437\u043d\u0430\u043d\u0438\u044e \u0438\u0441\u0442\u0438\u043d\u044b\u00bb.\n26 \u0418 \u043e\u043d\u0438 \u043f\u0440\u0438\u0434\u0443\u0442 \u0432 \u0441\u0435\u0431\u044f \u0438 \u0432\u044b\u0440\u0432\u0443\u0442\u0441\u044f \u0438\u0437 \u0441\u0435\u0442\u0438 \u0434\u044c\u044f\u0432\u043e\u043b\u0430, \u043f\u043e\u0441\u043b\u0435 \u0442\u043e\u0433\u043e \u043a\u0430\u043a \u0431\u0443\u0434\u0443\u0442 \u0437\u0430\u0445\u0432\u0430\u0447\u0435\u043d\u044b \u0438\u043c, \u0447\u0442\u043e\u0431\u044b \u0438\u0441\u043f\u043e\u043b\u043d\u044f\u0442\u044c \u0435\u0433\u043e \u0432\u043e\u043b\u044e.\n\n\u0410 \u0432\u044b \u0437\u043d\u0430\u043b\u0438, \u0447\u0442\u043e \u043c\u043e\u0436\u043d\u043e \u043f\u043e\u0447\u0443\u0432\u0441\u0442\u0432\u043e\u0432\u0430\u0442\u044c \u0441\u0435\u0431\u044f \u0441\u043e\u0432\u0435\u0440\u0448\u0435\u043d\u043d\u043e \u0441\u0432\u043e\u0431\u043e\u0434\u043d\u044b\u043c, \u0434\u0430\u0436\u0435 \u043d\u0430\u0445\u043e\u0434\u044f\u0441\u044c \u0432 \u043b\u043e\u0432\u0443\u0448\u043a\u0435 \u0433\u0440\u0435\u0445\u0430 \u0438 \u0434\u044c\u044f\u0432\u043e\u043b\u0430?\n\u0413\u0440\u0435\u0445 \u043a\u0430\u0436\u0435\u0442\u0441\u044f \u0441\u0432\u043e\u0431\u043e\u0434\u043e\u0439, \u043d\u043e \u043d\u0430 \u0441\u0430\u043c\u043e\u043c \u0434\u0435\u043b\u0435 \u0432\u0441\u0451 \u043d\u0430\u043e\u0431\u043e\u0440\u043e\u0442.\n\u0412\u043e\u0442 \u0442\u0430\u043a \u0432\u044b\u0433\u043b\u044f\u0434\u0438\u0442 \u043b\u043e\u0432\u0443\u0448\u043a\u0430.\n\u042d\u0442\u043e \u043b\u043e\u0432\u0443\u0448\u043a\u0430, \u043a\u043e\u0442\u043e\u0440\u0430\u044f \u043b\u043e\u0432\u0438\u0442 \u0436\u0438\u0432\u043e\u0442\u043d\u043e\u0435, \u0441\u0432\u043e\u0431\u043e\u0434\u043d\u043e \u0431\u0435\u0433\u0443\u0449\u0435\u0435 \u043f\u043e \u0442\u0440\u043e\u043f\u0438\u043d\u043a\u0435, \u0438 \u0432\u043d\u0435\u0437\u0430\u043f\u043d\u043e \u043e\u043a\u0430\u0437\u0430\u0432\u0448\u0435\u0435\u0441\u044f \u0432 \u043e\u043f\u0430\u0441\u043d\u043e\u0441\u0442\u0438.\n\u0421\u0430\u0442\u0430\u043d\u0430 \u0440\u0430\u0441\u0441\u0442\u0430\u0432\u043b\u044f\u0435\u0442 \u043b\u043e\u0436\u044c, \u043f\u043e\u0434\u043e\u0431\u043d\u043e \u0443\u043a\u0430\u0437\u0430\u0442\u0435\u043b\u044f\u043c \u043d\u0430 \u043c\u0430\u0440\u0430\u0444\u043e\u043d\u0441\u043a\u043e\u0439 \u0442\u0440\u0430\u0441\u0441\u0435, \u0447\u0442\u043e\u0431\u044b \u043e\u0431\u043c\u0430\u043d\u0443\u0442\u044c \u0438 \u0437\u0430\u043c\u0430\u043d\u0438\u0442\u044c \u043d\u0430\u0441 \u0432 \u043b\u043e\u0432\u0443\u0448\u043a\u0443.\n\u0421\u0430\u0442\u0430\u043d\u0430 \u0445\u043e\u0447\u0435\u0442, \u0447\u0442\u043e\u0431\u044b \u043c\u044b \u0433\u043d\u0430\u043b\u0438\u0441\u044c \u0437\u0430 \u0443\u0434\u043e\u0432\u043e\u043b\u044c\u0441\u0442\u0432\u0438\u044f\u043c\u0438, \u0432\u043b\u0430\u0441\u0442\u044c\u044e, \u043f\u043e\u043f\u0443\u043b\u044f\u0440\u043d\u043e\u0441\u0442\u044c\u044e, \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u043e\u043c \u0438 \u0433\u043e\u0440\u0434\u043e\u0441\u0442\u044c\u044e.\n\u042d\u0442\u0438 \u0438\u0434\u043e\u043b\u044b \u043e\u0431\u0435\u0449\u0430\u044e\u0442 \u043d\u0430\u043c \u0441\u0432\u043e\u0431\u043e\u0434\u0443, \u0430 \u0441\u0432\u043e\u0431\u043e\u0434\u0430 \u2014 \u044d\u0442\u043e \u0442\u043e, \u0447\u0435\u0433\u043e \u043c\u044b \u043e\u0447\u0435\u043d\u044c \u0445\u043e\u0442\u0438\u043c.\n\u041a \u0441\u043e\u0436\u0430\u043b\u0435\u043d\u0438\u044e, \u043c\u044b \u0441\u0447\u0438\u0442\u0430\u0435\u043c, \u0447\u0442\u043e \u043f\u043e\u0434\u043e\u0431\u043d\u044b\u0435 \u0432\u0435\u0449\u0438 \u043c\u043e\u0433\u0443\u0442 \u043f\u043e\u043c\u043e\u0447\u044c \u043d\u0430\u043c \u043f\u043e\u0447\u0443\u0432\u0441\u0442\u0432\u043e\u0432\u0430\u0442\u044c \u0441\u0435\u0431\u044f \u0443\u0434\u043e\u0432\u043b\u0435\u0442\u0432\u043e\u0440\u0435\u043d\u043d\u044b\u043c\u0438, \u0432 \u0431\u0435\u0437\u043e\u043f\u0430\u0441\u043d\u043e\u0441\u0442\u0438 \u0438 \u0441\u0447\u0430\u0441\u0442\u043b\u0438\u0432\u044b\u043c\u0438.\n\u041d\u043e \u044d\u0442\u0438 \u0438\u0434\u043e\u043b\u044b \u2014 \u043b\u043e\u0432\u0443\u0448\u043a\u0438, \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u043e\u0442\u0434\u0430\u043b\u044f\u044e\u0442 \u043d\u0430\u0441 \u043e\u0442 \u0411\u043e\u0433\u0430 \u0438 \u043f\u0443\u0442\u0438 \u0438\u0441\u0442\u0438\u043d\u043d\u043e\u0439 \u0436\u0438\u0437\u043d\u0438.\n\u0421\u0430\u0442\u0430\u043d\u0430 \u0445\u043e\u0447\u0435\u0442 \u0441\u043a\u0440\u044b\u0442\u044c \u043e\u0442 \u043d\u0430\u0441 \u0436\u0438\u0437\u043d\u0435\u043d\u043d\u044b\u0439 \u043f\u0443\u0442\u044c, \u0433\u043e\u0432\u043e\u0440\u044f:\n\u00ab\u0418\u0434\u0438\u0442\u0435 \u044d\u0442\u0438\u043c \u043f\u0443\u0442\u0435\u043c \u043a \u043f\u043e\u0431\u0435\u0434\u0435 \u0438 \u0441\u0447\u0430\u0441\u0442\u044c\u044e!\u00bb\n\u0414\u0430, \u0438\u043c\u0435\u043d\u043d\u043e \u0442\u0430\u043a! \u0421\u043b\u0435\u0434\u0443\u0439\u0442\u0435 \u0437\u0430 \u043c\u043d\u043e\u0439!\u201d\n\n\u0418\u0442\u0430\u043a, \u043a\u0430\u043a \u0436\u0435 \u0436\u0438\u0432\u043e\u0442\u043d\u043e\u043c\u0443 \u0432\u044b\u0431\u0440\u0430\u0442\u044c\u0441\u044f \u0438\u0437 \u0442\u0430\u043a\u043e\u0439 \u043b\u043e\u0432\u0443\u0448\u043a\u0438?\n\u0421\u043c\u043e\u0436\u0435\u0442 \u043b\u0438 \u043e\u043d \u0441\u0434\u0435\u043b\u0430\u0442\u044c \u044d\u0442\u043e \u0441\u0430\u043c\u043e\u0441\u0442\u043e\u044f\u0442\u0435\u043b\u044c\u043d\u043e?\n\u041d\u0435\u0442, \u043a\u0440\u043e\u043b\u0438\u043a \u0431\u0435\u0441\u043f\u043e\u043c\u043e\u0449\u0435\u043d.\n\u0415\u043c\u0443 \u043d\u0443\u0436\u0435\u043d \u043a\u0442\u043e-\u0442\u043e \u0443\u043c\u043d\u0435\u0435 \u0438 \u0441\u0438\u043b\u044c\u043d\u0435\u0435, \u043a\u0442\u043e \u0432\u044b\u0442\u0430\u0449\u0438\u0442 \u0435\u0433\u043e \u0438\u0437 \u043b\u043e\u0432\u0443\u0448\u043a\u0438.\n\u041d\u0430\u043c \u043d\u0443\u0436\u0435\u043d \u043a\u0442\u043e-\u0442\u043e \u0443\u043c\u043d\u0435\u0435 \u0438 \u0441\u0438\u043b\u044c\u043d\u0435\u0435, \u0447\u0442\u043e\u0431\u044b \u0441\u043f\u0430\u0441\u0442\u0438 \u0438 \u043d\u0430\u0441.\n\u042d\u0442\u043e \u0441\u0430\u043c\u044b\u0439 \u0432\u0430\u0436\u043d\u044b\u0439 \u043c\u043e\u043c\u0435\u043d\u0442, \u043d\u0430 \u043a\u043e\u0442\u043e\u0440\u044b\u0439 \u044f \u0445\u043e\u0447\u0443 \u043e\u0431\u0440\u0430\u0442\u0438\u0442\u044c \u0432\u0430\u0448\u0435 \u0432\u043d\u0438\u043c\u0430\u043d\u0438\u0435 \u0432 \u044d\u0442\u043e\u043c \u0441\u0442\u0438\u0445\u0435.\n\u041d\u0430\u043c \u043d\u0443\u0436\u0435\u043d \u0421\u043f\u0430\u0441\u0438\u0442\u0435\u043b\u044c, \u043f\u043e\u0442\u043e\u043c\u0443 \u0447\u0442\u043e \u043c\u044b \u043d\u0435 \u043c\u043e\u0436\u0435\u043c \u0441\u043f\u0430\u0441\u0442\u0438\u0441\u044c \u0441\u0430\u043c\u0438 \u0438\u043b\u0438 \u0434\u0430\u0436\u0435 \u043e\u0431\u0440\u0430\u0442\u0438\u0442\u044c\u0441\u044f \u043a \u0411\u043e\u0433\u0443.\n\u0414\u0443\u0445\u043e\u0432\u043d\u043e \u043c\u0435\u0440\u0442\u0432\u044b\u0435 \u0441\u0435\u0440\u0434\u0446\u0430 \u043d\u0435 \u043c\u043e\u0433\u0443\u0442 \u0432\u044b\u0431\u0440\u0430\u0442\u044c \u0436\u0438\u0437\u043d\u044c.\n\u041f\u043e\u0441\u043c\u043e\u0442\u0440\u0438\u0442\u0435, \u0447\u0442\u043e \u0433\u043e\u0432\u043e\u0440\u0438\u0442\u0441\u044f \u0432 25-\u043c \u0441\u0442\u0438\u0445\u0435:\n\u00ab\u0412\u043e\u0437\u043c\u043e\u0436\u043d\u043e, \u0411\u043e\u0433 \u0434\u0430\u0440\u0443\u0435\u0442 \u0438\u043c \u043f\u043e\u043a\u0430\u044f\u043d\u0438\u0435\u00bb.\n\n\u0413\u0440\u0430\u043d\u0442 \u2014 \u044d\u0442\u043e \u0431\u0435\u0441\u043f\u043b\u0430\u0442\u043d\u044b\u0439 \u043f\u043e\u0434\u0430\u0440\u043e\u043a.\n\u0411\u043e\u0433 \u0434\u0430\u0440\u043e\u0432\u0430\u043b \u043c\u043d\u0435 \u0434\u0430\u0440 \u043f\u043e\u043a\u0430\u044f\u043d\u0438\u044f 30 \u043b\u0435\u0442 \u043d\u0430\u0437\u0430\u0434.\n\u0412 \u0442\u0435\u0447\u0435\u043d\u0438\u0435 10 \u043b\u0435\u0442 \u044f \u0443\u0442\u0432\u0435\u0440\u0436\u0434\u0430\u043b, \u0447\u0442\u043e \u0432\u043e \u0412\u0441\u0435\u043b\u0435\u043d\u043d\u043e\u0439 \u043d\u0435\u0442 \u0411\u043e\u0433\u0430.\n\u041d\u043e \u043f\u043e\u0441\u043a\u043e\u043b\u044c\u043a\u0443 \u0411\u043e\u0433 \u043c\u0438\u043b\u043e\u0441\u0435\u0440\u0434\u0435\u043d, \u043e\u043d \u043f\u043e\u043a\u0430\u0437\u0430\u043b \u043c\u043d\u0435, \u0447\u0442\u043e \u043f\u0438\u0432\u043e, \u0436\u0435\u043d\u0449\u0438\u043d\u044b \u0438 \u0437\u0435\u043c\u043d\u043e\u0439 \u0443\u0441\u043f\u0435\u0445 \u043d\u0438\u043a\u043e\u0433\u0434\u0430 \u043d\u0435 \u0441\u043c\u043e\u0433\u0443\u0442 \u0443\u0434\u043e\u0432\u043b\u0435\u0442\u0432\u043e\u0440\u0438\u0442\u044c \u0436\u0435\u043b\u0430\u043d\u0438\u044f \u043c\u043e\u0435\u0433\u043e \u0441\u0435\u0440\u0434\u0446\u0430.\n\u0412\u043e\u0442 \u0447\u0442\u043e \u043e\u0437\u043d\u0430\u0447\u0430\u0435\u0442 \u0444\u0440\u0430\u0437\u0430 \u00ab\u043e\u0434\u0443\u043c\u0430\u0442\u044c\u0441\u044f\u00bb \u0432 26-\u043c \u0441\u0442\u0438\u0445\u0435.\n\u041a\u043e\u0433\u0434\u0430 \u0432\u0430\u0448\u0435 \u0447\u0443\u0432\u0441\u0442\u0432\u043e \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u0438\u044f \u043d\u0430\u0440\u0443\u0448\u0435\u043d\u043e, \u0432\u044b \u0431\u0435\u0436\u0438\u0442\u0435 \u0432 \u043d\u0435\u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e\u043c \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u0438\u0438.\n\u041f\u0435\u0440\u0432\u044b\u0439 \u0448\u0430\u0433 \u043a \u0442\u043e\u043c\u0443, \u0447\u0442\u043e\u0431\u044b \u043d\u0430\u0439\u0442\u0438 \u0434\u043e\u0440\u043e\u0433\u0443 \u0434\u043e\u043c\u043e\u0439, \u2014 \u044d\u0442\u043e \u043f\u0440\u0438\u0437\u043d\u0430\u0442\u044c, \u0447\u0442\u043e \u0432\u044b \u0437\u0430\u0431\u043b\u0443\u0434\u0438\u043b\u0438\u0441\u044c.\n\u0414\u044d\u043d \u041c\u0430\u043a\u0434\u0430\u0443\u044d\u043b\u043b \u0431\u044b\u043b \u043e\u0434\u043d\u0438\u043c \u0438\u0437 \u0442\u0435\u0445 \u0431\u0435\u0433\u0443\u043d\u043e\u0432, \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u0437\u0430\u0431\u043b\u0443\u0434\u0438\u043b\u0438\u0441\u044c \u0432\u043e \u0432\u0440\u0435\u043c\u044f \u0442\u043e\u0433\u043e \u043c\u0430\u0440\u0430\u0444\u043e\u043d\u0430 \u0432 \u041f\u043e\u0440\u0442\u043b\u0435\u043d\u0434\u0435.\n\u041e\u043d \u0441\u043a\u0430\u0437\u0430\u043b: \u00ab\u042f \u0437\u0430\u0432\u0435\u0440\u043d\u0443\u043b \u0437\u0430 \u0443\u0433\u043e\u043b \u0438 \u0443\u0432\u0438\u0434\u0435\u043b \u0434\u0435\u0441\u044f\u0442\u044c \u0447\u0435\u043b\u043e\u0432\u0435\u043a, \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u043f\u0440\u043e\u0441\u0442\u043e \u0441\u0442\u043e\u044f\u043b\u0438 \u043d\u0435\u043f\u043e\u0434\u0432\u0438\u0436\u043d\u043e\u2026\u00bb\n\u041e\u043d\u0438 \u0441\u043c\u043e\u0442\u0440\u0435\u043b\u0438 \u0434\u0440\u0443\u0433 \u043d\u0430 \u0434\u0440\u0443\u0433\u0430 \u0438 \u0434\u0443\u043c\u0430\u043b\u0438: \u00ab\u042d-\u044d, \u0447\u0442\u043e-\u0442\u043e \u0437\u0434\u0435\u0441\u044c \u043d\u0435 \u0442\u0430\u043a\u00bb.\n\n\u0414\u0440\u0443\u0433\u043e\u0439 \u0431\u0435\u0433\u0443\u043d, \u0417\u0430\u043a \u041a\u0430\u0441\u0442\u0435\u0440, \u0440\u0430\u0441\u0441\u043a\u0430\u0437\u0430\u043b, \u0447\u0442\u043e \u0432\u044a\u0435\u0445\u0430\u043b \u0432 \u0442\u0443\u043d\u043d\u0435\u043b\u044c, \u0433\u0434\u0435 \u043c\u0438\u043c\u043e \u043d\u0435\u0433\u043e \u043f\u0440\u043e\u043d\u043e\u0441\u0438\u043b\u0438\u0441\u044c \u043c\u0430\u0448\u0438\u043d\u044b \u0441\u043e \u0441\u043a\u043e\u0440\u043e\u0441\u0442\u044c\u044e 55 \u043c\u0438\u043b\u044c \u0432 \u0447\u0430\u0441.\n\u0422\u043e\u0433\u0434\u0430 \u043e\u043d \u043f\u043e\u043d\u044f\u043b, \u0447\u0442\u043e \u0441\u0431\u0438\u043b\u0441\u044f \u0441 \u043a\u0443\u0440\u0441\u0430.\n\u0414\u043e \u0442\u043e\u0433\u043e, \u043a\u0430\u043a \u0411\u043e\u0433 \u043f\u0440\u0438\u0432\u0451\u043b \u043c\u0435\u043d\u044f \u0432 \u0447\u0443\u0432\u0441\u0442\u0432\u043e, \u044f \u0434\u0443\u043c\u0430\u043b, \u0447\u0442\u043e \u043e\u0431\u043b\u0430\u0434\u0430\u044e \u00ab\u0437\u043d\u0430\u043d\u0438\u0435\u043c \u0438\u0441\u0442\u0438\u043d\u044b\u00bb.\n\u041c\u043e\u044f \u0433\u043e\u0440\u0434\u043e\u0441\u0442\u044c \u043f\u043e\u0434\u0441\u043a\u0430\u0437\u044b\u0432\u0430\u043b\u0430 \u043c\u043d\u0435, \u0447\u0442\u043e \u044f \u0438\u0434\u0443 \u043f\u043e \u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e\u043c\u0443 \u043f\u0443\u0442\u0438 \u0438 \u043c\u043d\u0435 \u043d\u0435 \u043d\u0443\u0436\u0435\u043d \u0411\u043e\u0433, \u0447\u0442\u043e\u0431\u044b \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u044f\u0442\u044c \u043c\u0435\u043d\u044f, \u043f\u043e\u0442\u043e\u043c\u0443 \u0447\u0442\u043e \u044f \u0431\u044b\u043b \u043e\u0447\u0435\u043d\u044c \u0443\u043c\u0451\u043d.\n\u041f\u043e \u0438\u0440\u043e\u043d\u0438\u0438 \u0441\u0443\u0434\u044c\u0431\u044b, \u044f \u0431\u044b\u043b \u0441\u043b\u0438\u0448\u043a\u043e\u043c \u0433\u043b\u0443\u043f, \u0447\u0442\u043e\u0431\u044b \u0440\u0430\u0437\u0433\u043b\u044f\u0434\u0435\u0442\u044c \u043e\u0431\u043c\u0430\u043d \u0421\u0430\u0442\u0430\u043d\u044b.\n\u042f \u043f\u043e\u043f\u0430\u043b \u0432 \u0435\u0433\u043e \u043b\u043e\u0432\u0443\u0448\u043a\u0443 \u043b\u0436\u0438.\n\u042f \u043f\u043e\u0432\u0435\u0440\u0438\u043b\u0430 \u043e\u0431\u0435\u0449\u0430\u043d\u0438\u044e \u0434\u044c\u044f\u0432\u043e\u043b\u0430, \u0447\u0442\u043e \u043e\u0431\u0440\u0435\u0442\u0443 \u0441\u0447\u0430\u0441\u0442\u044c\u0435, \u0443\u0431\u0435\u0436\u0430\u0432 \u043e\u0442 \u0411\u043e\u0433\u0430.\n\u041d\u043e \u0437\u0430\u0442\u0435\u043c \u0411\u043e\u0433 \u0434\u0430\u0440\u043e\u0432\u0430\u043b \u043c\u043d\u0435 \u0434\u0430\u0440 \u043f\u043e\u043a\u0430\u044f\u043d\u0438\u044f.\n\u0413\u0440\u0435\u0447\u0435\u0441\u043a\u043e\u0435 \u0441\u043b\u043e\u0432\u043e, \u043e\u0431\u043e\u0437\u043d\u0430\u0447\u0430\u044e\u0449\u0435\u0435 \u0437\u0434\u0435\u0441\u044c \u043f\u043e\u043a\u0430\u044f\u043d\u0438\u0435, \u2014 \u043c\u0435\u0442\u0430\u043d\u043e\u0439\u044f.\n\u042d\u0442\u043e \u043e\u0437\u043d\u0430\u0447\u0430\u0435\u0442 \u00ab\u0438\u0437\u043c\u0435\u043d\u0435\u043d\u0438\u0435 \u043c\u044b\u0448\u043b\u0435\u043d\u0438\u044f, \u0438\u0437\u043c\u0435\u043d\u0435\u043d\u0438\u0435 \u043e\u0431\u0440\u0430\u0437\u0430 \u0436\u0438\u0437\u043d\u0438 \u0438 \u0438\u0437\u043c\u0435\u043d\u0435\u043d\u0438\u0435 \u0446\u0435\u043b\u0438\u00bb.\n\u0418\u0438\u0441\u0443\u0441 \u0434\u0430\u043b \u043c\u043d\u0435 \u043d\u043e\u0432\u043e\u0435 \u0441\u0435\u0440\u0434\u0446\u0435, \u0447\u0442\u043e\u0431\u044b \u044f \u043c\u043e\u0433 \u00ab\u043f\u0440\u0438\u0437\u044b\u0432\u0430\u0442\u044c \u0413\u043e\u0441\u043f\u043e\u0434\u0430 \u043e\u0442 \u0447\u0438\u0441\u0442\u043e\u0433\u043e \u0441\u0435\u0440\u0434\u0446\u0430\u00bb, \u043a\u0430\u043a \u0441\u043a\u0430\u0437\u0430\u043d\u043e \u0432 22-\u043c \u0441\u0442\u0438\u0445\u0435.\n\u0427\u0438\u0441\u0442\u043e\u0435 \u0441\u0435\u0440\u0434\u0446\u0435 \u2013 \u044d\u0442\u043e \u0447\u0435\u0441\u0442\u043d\u043e\u0435 \u0441\u0435\u0440\u0434\u0446\u0435.\n\u0421\u0435\u0440\u0434\u0446\u0435, \u0432\u0437\u044b\u0432\u0430\u044e\u0449\u0435\u0435 \u043a \u0411\u043e\u0433\u0443: \u00ab\u042f \u0441\u043e\u0436\u0430\u043b\u0435\u044e \u043e \u0441\u0432\u043e\u0438\u0445 \u0433\u0440\u0435\u0445\u0430\u0445, \u043f\u043e\u0436\u0430\u043b\u0443\u0439\u0441\u0442\u0430, \u043f\u0440\u043e\u0441\u0442\u0438 \u043c\u0435\u043d\u044f\u00bb.\n\u041f\u043e\u043c\u043e\u0433\u0438 \u043c\u043d\u0435 \u0431\u0435\u0436\u0430\u0442\u044c \u043a \u0422\u0435\u0431\u0435, \u0430 \u043d\u0435 \u043e\u0442 \u0422\u0435\u0431\u044f.\n\u0412 \u041f\u043e\u0441\u043b\u0430\u043d\u0438\u0438 \u043a \u0420\u0438\u043c\u043b\u044f\u043d\u0430\u043c 10:9\u201311 \u041f\u0430\u0432\u0435\u043b \u043e\u0447\u0435\u043d\u044c \u044f\u0441\u043d\u043e \u043e\u0431\u044a\u044f\u0441\u043d\u044f\u0435\u0442, \u043a\u0430\u043a \u043c\u043e\u0436\u043d\u043e \u043e\u0431\u0440\u0430\u0442\u0438\u0442\u044c\u0441\u044f \u043a \u0411\u043e\u0433\u0443 \u0438 \u0441\u043f\u0430\u0441\u0442\u0438\u0441\u044c.\n9 \u00ab\u0415\u0441\u043b\u0438 \u0442\u044b \u0443\u0441\u0442\u0430\u043c\u0438 \u0441\u0432\u043e\u0438\u043c\u0438 \u0438\u0441\u043f\u043e\u0432\u0435\u0434\u0443\u0435\u0448\u044c, \u0447\u0442\u043e \u0418\u0438\u0441\u0443\u0441 \u0435\u0441\u0442\u044c \u0413\u043e\u0441\u043f\u043e\u0434\u044c, \u0438 \u0441\u0435\u0440\u0434\u0446\u0435\u043c \u0442\u0432\u043e\u0438\u043c \u0432\u0435\u0440\u0443\u0435\u0448\u044c, \u0447\u0442\u043e \u0411\u043e\u0433 \u0432\u043e\u0441\u043a\u0440\u0435\u0441\u0438\u043b \u0415\u0433\u043e \u0438\u0437 \u043c\u0435\u0440\u0442\u0432\u044b\u0445, \u0442\u043e \u0441\u043f\u0430\u0441\u0435\u0448\u044c\u0441\u044f\u00bb.\n10 \u0418\u0431\u043e \u0441\u0435\u0440\u0434\u0446\u0435\u043c \u0432\u0435\u0440\u0443\u044e\u0442 \u043a \u043f\u0440\u0430\u0432\u0435\u0434\u043d\u043e\u0441\u0442\u0438, \u0430 \u0443\u0441\u0442\u0430\u043c\u0438 \u0438\u0441\u043f\u043e\u0432\u0435\u0434\u0443\u044e\u0442 \u043a \u0441\u043f\u0430\u0441\u0435\u043d\u0438\u044e.\n11 \u041a\u0430\u043a \u0441\u043a\u0430\u0437\u0430\u043d\u043e \u0432 \u041f\u0438\u0441\u0430\u043d\u0438\u0438: \u00ab\u0412\u0441\u044f\u043a\u0438\u0439, \u043a\u0442\u043e \u0432\u0435\u0440\u0443\u0435\u0442 \u0432 \u041d\u0435\u0433\u043e, \u043d\u0435 \u0431\u0443\u0434\u0435\u0442 \u043f\u043e\u0441\u0440\u0430\u043c\u043b\u0451\u043d\u00bb.\n\n\u0418\u0441\u043f\u043e\u0432\u0435\u0434\u0430\u043b\u0438 \u043b\u0438 \u0432\u044b \u0432\u0435\u0440\u0443 \u0443\u0441\u0442\u0430\u043c\u0438 \u0441\u0432\u043e\u0438\u043c\u0438, \u0447\u0442\u043e\u0431\u044b \u0441\u043f\u0430\u0441\u0442\u0438\u0441\u044c?\n\u0415\u0441\u043b\u0438 \u0432\u044b \u044d\u0442\u043e\u0433\u043e \u0435\u0449\u0451 \u043d\u0435 \u0441\u0434\u0435\u043b\u0430\u043b\u0438, \u0440\u0430\u0437\u0432\u0435 \u043d\u0435 \u0441\u0435\u0433\u043e\u0434\u043d\u044f \u0431\u044b\u043b \u0431\u044b \u043e\u0442\u043b\u0438\u0447\u043d\u044b\u0439 \u0434\u0435\u043d\u044c, \u0447\u0442\u043e\u0431\u044b \u044d\u0442\u043e \u0441\u0434\u0435\u043b\u0430\u0442\u044c?\n\u0421\u0432\u044f\u0442\u043e\u0439 \u0414\u0443\u0445 \u043f\u0440\u0435\u0431\u044b\u0432\u0430\u0435\u0442 \u0441\u0440\u0435\u0434\u0438 \u043d\u0430\u0441, \u0438, \u0432\u043e\u0437\u043c\u043e\u0436\u043d\u043e, \u041e\u043d \u0448\u0435\u043f\u0447\u0435\u0442 \u0432\u0430\u043c \u0432 \u0441\u0435\u0440\u0434\u0446\u0435:\n\u00ab\u041e\u0442\u0432\u0435\u0440\u043d\u0438\u0442\u0435\u0441\u044c \u043e\u0442 \u043f\u0443\u0442\u0438 \u0433\u0440\u0435\u0445\u0430 \u0438 \u0441\u043c\u0435\u0440\u0442\u0438!\u00bb\n\u0412\u044b\u0431\u0435\u0440\u0438\u0442\u0435 \u043d\u043e\u0432\u0443\u044e \u0436\u0438\u0437\u043d\u044c \u0438 \u043d\u043e\u0432\u043e\u0435 \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u0438\u0435, \u043f\u0440\u043e\u0432\u043e\u0437\u0433\u043b\u0430\u0441\u0438\u0432: \u00ab\u0418\u0438\u0441\u0443\u0441 \u2014 \u0413\u043e\u0441\u043f\u043e\u0434\u044c!\u00bb\n\n\u041f\u0430\u0432\u0435\u043b \u0443\u0436\u0435 \u043e\u0434\u043d\u0430\u0436\u0434\u044b \u043f\u0438\u0441\u0430\u043b \u043e\u0431 \u044d\u0442\u043e\u043c \u043d\u043e\u0432\u043e\u043c \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u0438\u0438.\n\u042d\u0442\u043e \u0431\u044b\u043b\u043e \u0432 \u043f\u0438\u0441\u044c\u043c\u0435 \u043a \u0442\u043e\u0439 \u0436\u0435 \u0446\u0435\u0440\u043a\u0432\u0438 \u0432 \u042d\u0444\u0435\u0441\u0435, \u0433\u0434\u0435 \u0422\u0438\u043c\u043e\u0444\u0435\u0439 \u0441\u0435\u0439\u0447\u0430\u0441 \u0441\u043b\u0443\u0436\u0438\u0442 \u043f\u0430\u0441\u0442\u043e\u0440\u043e\u043c.\n\u041f\u043e\u0441\u043b\u0443\u0448\u0430\u0439\u0442\u0435, \u0447\u0442\u043e \u041f\u0430\u0432\u0435\u043b \u043d\u0430\u043f\u0438\u0441\u0430\u043b \u0445\u0440\u0438\u0441\u0442\u0438\u0430\u043d\u0441\u043a\u0438\u043c \u0432\u0435\u0440\u0443\u044e\u0449\u0438\u043c \u0432 \u041f\u043e\u0441\u043b\u0430\u043d\u0438\u0438 \u043a \u0415\u0444\u0435\u0441\u044f\u043d\u0430\u043c 2:1-5, \u043e \u0442\u043e\u043c, \u0447\u0442\u043e \u0411\u043e\u0433 \u0441\u0434\u0435\u043b\u0430\u043b, \u0447\u0442\u043e\u0431\u044b \u0434\u0430\u0442\u044c \u0438\u043c \u043d\u043e\u0432\u0443\u044e \u0436\u0438\u0437\u043d\u044c \u0438 \u043d\u043e\u0432\u043e\u0435 \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u0438\u0435:\n1 \u00ab\u0418 \u0432\u044b \u0431\u044b\u043b\u0438 \u043c\u0435\u0440\u0442\u0432\u044b \u0432 \u043f\u0440\u0435\u0441\u0442\u0443\u043f\u043b\u0435\u043d\u0438\u044f\u0445 \u0438 \u0433\u0440\u0435\u0445\u0430\u0445\u2026\u00bb\n2. \u041f\u043e \u043a\u043e\u0442\u043e\u0440\u043e\u043c\u0443 \u0432\u044b \u043d\u0435\u043a\u043e\u0433\u0434\u0430 \u0445\u043e\u0434\u0438\u043b\u0438, \u0441\u043b\u0435\u0434\u0443\u044f \u043f\u043e \u043f\u0443\u0442\u0438 \u044d\u0442\u043e\u0433\u043e \u043c\u0438\u0440\u0430, \u0441\u043b\u0435\u0434\u0443\u044f \u0437\u0430 \u043a\u043d\u044f\u0437\u0435\u043c \u0432\u043b\u0430\u0441\u0442\u0438 \u0432\u043e\u0437\u0434\u0443\u0448\u043d\u043e\u0439, \u0434\u0443\u0445\u043e\u043c, \u043a\u043e\u0442\u043e\u0440\u044b\u0439 \u043d\u044b\u043d\u0435 \u0434\u0435\u0439\u0441\u0442\u0432\u0443\u0435\u0442 \u0432 \u0441\u044b\u043d\u0430\u0445 \u043d\u0435\u043f\u043e\u043a\u043e\u0440\u043d\u043e\u0441\u0442\u0438.\n3 \u0421\u0440\u0435\u0434\u0438 \u043a\u043e\u0442\u043e\u0440\u044b\u0445 \u0438 \u043c\u044b \u0432\u0441\u0435 \u043d\u0435\u043a\u043e\u0433\u0434\u0430 \u0436\u0438\u043b\u0438 \u0432 \u0441\u0442\u0440\u0430\u0441\u0442\u044f\u0445 \u043f\u043b\u043e\u0442\u0438, \u0438\u0441\u043f\u043e\u043b\u043d\u044f\u044f \u0436\u0435\u043b\u0430\u043d\u0438\u044f \u0442\u0435\u043b\u0430 \u0438 \u0443\u043c\u0430, \u0438 \u043f\u043e \u043f\u0440\u0438\u0440\u043e\u0434\u0435 \u0431\u044b\u043b\u0438 \u0434\u0435\u0442\u044c\u043c\u0438 \u0433\u043d\u0435\u0432\u0430, \u043a\u0430\u043a \u0438 \u043e\u0441\u0442\u0430\u043b\u044c\u043d\u044b\u0435 \u043b\u044e\u0434\u0438.\n4 \u041d\u043e \u0411\u043e\u0433, \u0431\u043e\u0433\u0430\u0442\u044b\u0439 \u043c\u0438\u043b\u043e\u0441\u0442\u044c\u044e, \u043f\u043e \u0432\u0435\u043b\u0438\u043a\u043e\u0439 \u043b\u044e\u0431\u0432\u0438, \u043a\u043e\u0442\u043e\u0440\u043e\u0439 \u041e\u043d \u0432\u043e\u0437\u043b\u044e\u0431\u0438\u043b \u043d\u0430\u0441,\n5 \u0414\u0430\u0436\u0435 \u043a\u043e\u0433\u0434\u0430 \u043c\u044b \u0431\u044b\u043b\u0438 \u043c\u0435\u0440\u0442\u0432\u044b \u0432 \u043d\u0430\u0448\u0438\u0445 \u043f\u0440\u0435\u0441\u0442\u0443\u043f\u043b\u0435\u043d\u0438\u044f\u0445, \u0432\u044b \u043e\u0436\u0438\u0432\u0438\u043b\u0438 \u043d\u0430\u0441 \u0432\u043c\u0435\u0441\u0442\u0435 \u0441\u043e \u0425\u0440\u0438\u0441\u0442\u043e\u043c \u2014 \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0442\u044c\u044e \u0432\u044b \u0441\u043f\u0430\u0441\u0435\u043d\u044b!\n\n\u00ab\u041d\u043e \u0411\u043e\u0433\u00bb \u2014 \u044d\u0442\u043e \u0434\u0432\u0430 \u0441\u0430\u043c\u044b\u0445 \u043f\u0440\u0435\u043a\u0440\u0430\u0441\u043d\u044b\u0445 \u0441\u043b\u043e\u0432\u0430, \u043a\u043e\u0433\u0434\u0430-\u043b\u0438\u0431\u043e \u043f\u0440\u043e\u0438\u0437\u043d\u0435\u0441\u0451\u043d\u043d\u044b\u0445.\n\u041f\u0430\u0432\u0435\u043b \u043d\u0430\u043f\u043e\u043c\u0438\u043d\u0430\u0435\u0442 \u0432\u0435\u0440\u0443\u044e\u0449\u0438\u043c \u0432 \u042d\u0444\u0435\u0441\u0435, \u0447\u0442\u043e \u043a\u043e\u0433\u0434\u0430-\u0442\u043e \u043e\u043d\u0438 \u0431\u044b\u043b\u0438 \u0432 \u043b\u043e\u0432\u0443\u0448\u043a\u0435 \u0438 \u0431\u0435\u0441\u043f\u043e\u043c\u043e\u0449\u043d\u044b, \u043f\u043e\u0434\u043e\u0431\u043d\u043e \u043a\u0440\u043e\u043b\u0438\u043a\u0443 \u0432 \u0437\u0430\u043f\u0430\u0434\u043d\u0435.\n\u041d\u043e \u0411\u043e\u0433 \u0432\u043c\u0435\u0448\u0430\u043b\u0441\u044f, \u0447\u0442\u043e\u0431\u044b \u0441\u043f\u0430\u0441\u0442\u0438 \u0438\u0445 \u043e\u0434\u043d\u043e\u0439 \u043b\u0438\u0448\u044c \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0442\u044c\u044e, \u043e\u0434\u043d\u043e\u0439 \u043b\u0438\u0448\u044c \u0432\u0435\u0440\u043e\u0439, \u043e\u0434\u043d\u0438\u043c \u043b\u0438\u0448\u044c \u0425\u0440\u0438\u0441\u0442\u043e\u043c.\n\u0421\u043f\u0430\u0441\u0435\u043d\u0438\u0435 \u043c\u043e\u0436\u0435\u0442 \u043e\u0431\u0440\u0435\u0441\u0442\u0438 \u043a\u0430\u0436\u0434\u044b\u0439, \u0435\u0441\u043b\u0438 \u043e\u043d \u0432\u0435\u0440\u0438\u0442, \u0447\u0442\u043e \u0436\u0435\u0440\u0442\u0432\u0430 \u0425\u0440\u0438\u0441\u0442\u0430 \u043d\u0430 \u043a\u0440\u0435\u0441\u0442\u0435 \u0431\u044b\u043b\u0430 \u043f\u0440\u0438\u043d\u0435\u0441\u0435\u043d\u0430 \u0437\u0430 \u043d\u0435\u0433\u043e, \u0447\u0442\u043e\u0431\u044b \u043e\u0447\u0438\u0441\u0442\u0438\u0442\u044c \u0435\u0433\u043e \u043e\u0442 \u0433\u0440\u0435\u0445\u0430 \u0438 \u0441\u0442\u044b\u0434\u0430.\n\u041a\u043e\u0433\u0434\u0430 \u0432\u044b \u0432 \u044d\u0442\u043e \u0432\u0435\u0440\u0438\u0442\u0435, \u0432\u044b \u043f\u043e\u043b\u0443\u0447\u0430\u0435\u0442\u0435 \u043d\u043e\u0432\u0443\u044e \u0436\u0438\u0437\u043d\u044c, \u0438 \u0418\u0438\u0441\u0443\u0441 \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u044f\u0435\u0442 \u0432\u0430\u0441 \u043d\u0430 \u043d\u043e\u0432\u044b\u0439 \u043f\u0443\u0442\u044c.\n\u041d\u0435\u0441\u043a\u043e\u043b\u044c\u043a\u0438\u043c\u0438 \u0441\u0442\u0438\u0445\u0430\u043c\u0438 \u043f\u043e\u0437\u0436\u0435, \u0432 \u041f\u043e\u0441\u043b\u0430\u043d\u0438\u0438 \u043a \u0415\u0444\u0435\u0441\u044f\u043d\u0430\u043c 2:8, \u041f\u0430\u0432\u0435\u043b \u0433\u043e\u0432\u043e\u0440\u0438\u0442 \u043e\u0431 \u044d\u0442\u043e\u043c \u043d\u043e\u0432\u043e\u043c \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u0438\u0438.\n\u041f\u0440\u043e\u0447\u0438\u0442\u0430\u0439\u0442\u0435 \u044d\u0442\u043e \u0432\u043c\u0435\u0441\u0442\u0435 \u0441\u043e \u043c\u043d\u043e\u0439:\n\u0412\u0421\u0415\u041c: 10 \u00ab\u0418\u0431\u043e \u043c\u044b \u2014 \u0415\u0433\u043e \u0442\u0432\u043e\u0440\u0435\u043d\u0438\u0435, \u0441\u043e\u0437\u0434\u0430\u043d\u044b \u0432\u043e \u0425\u0440\u0438\u0441\u0442\u0435 \u0418\u0438\u0441\u0443\u0441\u0435 \u0434\u043b\u044f \u0434\u043e\u0431\u0440\u044b\u0445 \u0434\u0435\u043b, \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u0411\u043e\u0433 \u043f\u0440\u0438\u0433\u043e\u0442\u043e\u0432\u0438\u043b \u0437\u0430\u0440\u0430\u043d\u0435\u0435, \u0447\u0442\u043e\u0431\u044b \u043c\u044b \u0441\u043e\u0432\u0435\u0440\u0448\u0430\u043b\u0438 \u0438\u0445\u00bb.\n\n\u0412 \u0437\u0430\u0432\u0435\u0440\u0448\u0435\u043d\u0438\u0435 \u044d\u0442\u043e\u0433\u043e \u0441\u043e\u043e\u0431\u0449\u0435\u043d\u0438\u044f \u0434\u0430\u0432\u0430\u0439\u0442\u0435 \u0440\u0430\u0441\u0441\u043c\u043e\u0442\u0440\u0438\u043c, \u0447\u0442\u043e \u0437\u043d\u0430\u0447\u0438\u0442 \u0441\u043e\u0432\u0435\u0440\u0448\u0430\u0442\u044c \u0434\u043e\u0431\u0440\u044b\u0435 \u0434\u0435\u043b\u0430.\n\u041f\u043e\u043c\u043d\u0438\u0442\u0435, \u0447\u0442\u043e \u041f\u0430\u0432\u0435\u043b \u043f\u0438\u0448\u0435\u0442 \u0422\u0438\u043c\u043e\u0444\u0435\u044e, \u0434\u0430\u0432\u0430\u044f \u0435\u043c\u0443 \u0443\u043a\u0430\u0437\u0430\u043d\u0438\u044f \u043e\u0442\u043d\u043e\u0441\u0438\u0442\u0435\u043b\u044c\u043d\u043e \u0442\u043e\u0433\u043e, \u043a\u043e\u0433\u043e \u0441\u043b\u0435\u0434\u0443\u0435\u0442 \u0432\u044b\u0431\u0440\u0430\u0442\u044c \u0438 \u043e\u0431\u0443\u0447\u0438\u0442\u044c \u0432 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435 \u0443\u0447\u0438\u0442\u0435\u043b\u0435\u0439 \u0411\u0438\u0431\u043b\u0438\u0438.\n\u041d\u0430\u0448\u0430 \u043c\u0438\u0441\u0441\u0438\u044f \u043a\u0430\u043a \u0432\u0435\u0440\u0443\u044e\u0449\u0438\u0445 \u2014 \u0434\u0435\u043b\u0438\u0442\u044c\u0441\u044f \u0411\u043b\u0430\u0433\u043e\u0439 \u0412\u0435\u0441\u0442\u044c\u044e \u0415\u0432\u0430\u043d\u0433\u0435\u043b\u0438\u044f \u0441 \u043b\u044e\u0434\u044c\u043c\u0438 \u043a\u0430\u043a \u0432\u0431\u043b\u0438\u0437\u0438, \u0442\u0430\u043a \u0438 \u0432\u0434\u0430\u043b\u0438 \u043e\u0442 \u0434\u043e\u043c\u0430.\n\u041d\u043e \u0447\u0442\u043e\u0431\u044b \u0441\u0434\u0435\u043b\u0430\u0442\u044c \u044d\u0442\u043e \u0434\u043e\u0441\u0442\u043e\u0432\u0435\u0440\u043d\u043e, \u043c\u044b \u0434\u043e\u043b\u0436\u043d\u044b \u043e\u0431\u043b\u0430\u0434\u0430\u0442\u044c \u0442\u0435\u043c \u0445\u0430\u0440\u0430\u043a\u0442\u0435\u0440\u043e\u043c, \u043a\u043e\u0442\u043e\u0440\u044b\u0439 \u041f\u0430\u0432\u0435\u043b \u043e\u043f\u0438\u0441\u044b\u0432\u0430\u0435\u0442 \u0432 \u044d\u0442\u0438\u0445 \u0441\u0442\u0438\u0445\u0430\u0445.\n\u041c\u044b \u043d\u0435 \u043c\u043e\u0436\u0435\u043c \u0438\u0437\u043c\u0435\u043d\u0438\u0442\u044c \u043d\u0438\u0447\u044c\u0435 \u0441\u0435\u0440\u0434\u0446\u0435.\n\u041d\u043e \u043c\u044b \u043c\u043e\u0436\u0435\u043c \u0441\u043a\u0430\u0437\u0430\u0442\u044c \u0438\u043c \u043f\u0440\u0430\u0432\u0434\u0443 \u043c\u044f\u0433\u043a\u043e, \u0434\u043e\u0431\u0440\u043e\u0436\u0435\u043b\u0430\u0442\u0435\u043b\u044c\u043d\u043e \u0438 \u0442\u0435\u0440\u043f\u0435\u043b\u0438\u0432\u043e.\n\u0418 \u043c\u044b \u043c\u043e\u0436\u0435\u043c \u0432\u0435\u0440\u0438\u0442\u044c, \u0447\u0442\u043e \u0411\u043e\u0433 \u0434\u0430\u0440\u0443\u0435\u0442 \u043f\u043e\u043a\u0430\u044f\u043d\u0438\u0435 \u0441\u0432\u043e\u0438\u043c \u0438\u0437\u0431\u0440\u0430\u043d\u043d\u044b\u043c \u0434\u0435\u0442\u044f\u043c \u0432 \u043d\u0430\u0434\u043b\u0435\u0436\u0430\u0449\u0435\u0435 \u0432\u0440\u0435\u043c\u044f.\n\u0412 \u0441\u0442\u0438\u0445\u0430\u0445 24 \u0438 25 \u0441\u0435\u0433\u043e\u0434\u043d\u044f\u0448\u043d\u0435\u0433\u043e \u043e\u0442\u0440\u044b\u0432\u043a\u0430 \u044f \u0432\u0438\u0436\u0443 \u043f\u044f\u0442\u044c \u043a\u0430\u0447\u0435\u0441\u0442\u0432, \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u0411\u043e\u0433 \u0445\u043e\u0447\u0435\u0442 \u0440\u0430\u0437\u0432\u0438\u0442\u044c \u0432 \u0421\u0432\u043e\u0438\u0445 \u0441\u043b\u0443\u0433\u0430\u0445:\n\n\u041a\u0430\u0447\u0435\u0441\u0442\u0432\u043e 1: \u041d\u0435 \u0441\u0432\u0430\u0440\u043b\u0438\u0432\u044b\u0439.\n\u041d\u0435\u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u043b\u044e\u0434\u0438 \u043b\u044e\u0431\u044f\u0442 \u0441\u043f\u043e\u0440\u0438\u0442\u044c.\n\u0412 \u0437\u0434\u043e\u0440\u043e\u0432\u043e\u0439 \u0434\u0438\u0441\u043a\u0443\u0441\u0441\u0438\u0438 \u043d\u0435\u0442 \u043d\u0438\u0447\u0435\u0433\u043e \u043f\u043b\u043e\u0445\u043e\u0433\u043e.\n\u041d\u043e \u043a\u0430\u043a \u043f\u043e\u043d\u044f\u0442\u044c, \u0447\u0442\u043e \u0432\u044b \u0432\u0435\u0434\u0451\u0442\u0435 \u0441\u0435\u0431\u044f \u0433\u0440\u0435\u0445\u043e\u0432\u043d\u043e \u00ab\u0441\u0432\u0430\u0440\u043b\u0438\u0432\u043e\u00bb?\n\u0412\u043e\u0437\u043c\u043e\u0436\u043d\u043e, \u0432\u044b \u043c\u043e\u0436\u0435\u0442\u0435 \u0437\u0430\u0434\u0430\u0442\u044c \u0441\u0435\u0431\u0435 \u0442\u0430\u043a\u043e\u0439 \u0432\u043e\u043f\u0440\u043e\u0441:\n\u00ab\u041a\u043e\u0433\u0434\u0430 \u044f \u0441\u043f\u043e\u0440\u044e \u0441 \u043a\u0435\u043c-\u0442\u043e, \u0447\u0442\u043e \u0434\u043b\u044f \u043c\u0435\u043d\u044f \u0432\u0430\u0436\u043d\u0435\u0435: \u0441\u0430\u043c \u0447\u0435\u043b\u043e\u0432\u0435\u043a \u0438\u043b\u0438 \u043f\u043e\u0431\u0435\u0434\u0430 \u0432 \u0441\u043f\u043e\u0440\u0435?\u00bb\n\u041d\u0435\u0443\u0436\u0435\u043b\u0438 \u043c\u043e\u044f \u0433\u043e\u0440\u0434\u043e\u0441\u0442\u044c \u0437\u0430\u0441\u0442\u0430\u0432\u043b\u044f\u0435\u0442 \u043c\u0435\u043d\u044f \u0441\u043e\u0441\u0440\u0435\u0434\u043e\u0442\u0430\u0447\u0438\u0432\u0430\u0442\u044c\u0441\u044f \u043d\u0430 \u0442\u043e\u043c, \u0447\u0442\u043e\u0431\u044b \u0431\u044b\u0442\u044c \u043f\u0440\u0430\u0432\u044b\u043c, \u0432\u043c\u0435\u0441\u0442\u043e \u0442\u043e\u0433\u043e, \u0447\u0442\u043e\u0431\u044b \u0431\u044b\u0442\u044c \u0434\u043e\u0431\u0440\u044b\u043c?\n\n\u041a\u0430\u0447\u0435\u0441\u0442\u0432\u043e 2: \u0414\u043e\u0431\u0440\u043e\u0442\u0430 \u043a\u043e \u0432\u0441\u0435\u043c.\n\u0421\u043b\u0443\u0433\u0430 \u0413\u043e\u0441\u043f\u043e\u0434\u0430 \u0434\u043e\u043b\u0436\u0435\u043d \u0431\u044b\u0442\u044c \u0434\u043e\u0431\u0440 \u043a\u043e \u0432\u0441\u0435\u043c.\n\u0414\u0430\u0436\u0435 \u0442\u0435\u043c, \u043a\u0442\u043e \u0432\u0430\u0441 \u043d\u0435\u043d\u0430\u0432\u0438\u0434\u0438\u0442 \u0438 \u0445\u043e\u0447\u0435\u0442 \u043f\u0440\u0438\u0447\u0438\u043d\u0438\u0442\u044c \u0432\u0430\u043c \u0431\u043e\u043b\u044c.\n\u042f \u043f\u043e\u043d\u0438\u043c\u0430\u044e, \u044d\u0442\u043e \u0441\u043b\u043e\u0436\u043d\u043e.\n\u041c\u044b \u0441\u0447\u0438\u0442\u0430\u0435\u043c, \u0447\u0442\u043e \u0441\u043f\u043e\u0441\u043e\u0431 \u0437\u0430\u0449\u0438\u0442\u0438\u0442\u044c \u0441\u0435\u0431\u044f \u043e\u0442 \u0434\u0440\u0443\u0433\u0438\u0445 \u043b\u044e\u0434\u0435\u0439 \u2014 \u044d\u0442\u043e \u0431\u044b\u0442\u044c \u0441\u0438\u043b\u044c\u043d\u044b\u043c\u0438, \u0438\u0441\u043f\u043e\u043b\u044c\u0437\u043e\u0432\u0430\u0442\u044c \u0441\u0438\u043b\u0443.\n\u041d\u043e \u043f\u043e\u0441\u043c\u043e\u0442\u0440\u0438\u0442\u0435, \u043e \u0447\u0451\u043c \u043d\u0430\u043f\u043e\u043c\u0438\u043d\u0430\u0435\u0442 \u043d\u0430\u043c \u041f\u0430\u0432\u0435\u043b \u0432 \u041f\u043e\u0441\u043b\u0430\u043d\u0438\u0438 \u043a \u0420\u0438\u043c\u043b\u044f\u043d\u0430\u043c 2:4:\n\u00ab\u0411\u043e\u0436\u044c\u044f \u043c\u0438\u043b\u043e\u0441\u0442\u044c \u043f\u0440\u0438\u0437\u0432\u0430\u043d\u0430 \u043f\u0440\u0438\u0432\u0435\u0441\u0442\u0438 \u0432\u0430\u0441 \u043a \u043f\u043e\u043a\u0430\u044f\u043d\u0438\u044e\u00bb.\n\u041d\u0430\u0441\u043a\u043e\u043b\u044c\u043a\u043e \u0434\u043e\u0431\u0440 \u0431\u044b\u043b \u043a \u0432\u0430\u043c \u0418\u0438\u0441\u0443\u0441, \u043a\u043e\u0433\u0434\u0430 \u0432\u044b \u043f\u0440\u0435\u0431\u044b\u0432\u0430\u043b\u0438 \u0432\u043e \u0433\u0440\u0435\u0445\u0435 \u0438 \u0443\u0431\u0435\u0433\u0430\u043b\u0438 \u043e\u0442 \u041d\u0435\u0433\u043e?\n\u0415\u0433\u043e \u0434\u043e\u0431\u0440\u043e\u0442\u0430 \u043f\u043e\u0431\u0443\u0434\u0438\u043b\u0430 \u0442\u0435\u0431\u044f \u043a \u043f\u043e\u043a\u0430\u044f\u043d\u0438\u044e.\n\u0422\u0435\u043f\u0435\u0440\u044c \u0443 \u0432\u0430\u0441 \u0435\u0441\u0442\u044c \u0432\u043e\u0437\u043c\u043e\u0436\u043d\u043e\u0441\u0442\u044c \u043f\u043e\u0434\u0440\u0430\u0436\u0430\u0442\u044c \u0425\u0440\u0438\u0441\u0442\u0443 \u0438 \u0431\u044b\u0442\u044c \u0434\u043e\u0431\u0440\u044b\u043c\u0438 \u043a\u043e \u0432\u0441\u0435\u043c.\n\n\u041a\u0430\u0447\u0435\u0441\u0442\u0432\u043e 3: \u0422\u0435\u0440\u043f\u0435\u043b\u0438\u0432\u043e\u0435 \u043f\u0435\u0440\u0435\u043d\u0435\u0441\u0435\u043d\u0438\u0435 \u0437\u043b\u0430.\n\u041a\u043e\u0433\u0434\u0430 \u043c\u044b \u0434\u0435\u043b\u0438\u043c\u0441\u044f \u0438\u0441\u0442\u0438\u043d\u043e\u0439 \u0415\u0432\u0430\u043d\u0433\u0435\u043b\u0438\u044f, \u043c\u044b \u0441\u0442\u0430\u043b\u043a\u0438\u0432\u0430\u0435\u043c\u0441\u044f \u0441 \u043f\u0440\u043e\u0442\u0438\u0432\u043e\u0434\u0435\u0439\u0441\u0442\u0432\u0438\u0435\u043c \u0441\u043e \u0441\u0442\u043e\u0440\u043e\u043d\u044b \u043b\u044e\u0434\u0435\u0439, \u043a\u043e\u0442\u043e\u0440\u044b\u043c \u043d\u0435 \u043d\u0440\u0430\u0432\u0438\u0442\u0441\u044f \u0442\u043e, \u0447\u0442\u043e \u043c\u044b \u0433\u043e\u0432\u043e\u0440\u0438\u043c.\n\u0412\u044b \u043f\u043e\u043c\u043d\u0438\u0442\u0435, \u043a\u0430\u043a \u0421\u0442\u0438\u0432\u0435\u043d \u043e\u0442\u0440\u0435\u0430\u0433\u0438\u0440\u043e\u0432\u0430\u043b \u043d\u0430 \u043b\u044e\u0434\u0435\u0439, \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u0435\u0433\u043e \u0443\u0431\u0438\u043b\u0438?\n\u0412 \u0414\u0435\u044f\u043d\u0438\u044f\u0445 7:59\u201360 \u0433\u043e\u0432\u043e\u0440\u0438\u0442\u0441\u044f:\n59 \u041a\u043e\u0433\u0434\u0430 \u0435\u0433\u043e \u0437\u0430\u0431\u0438\u0432\u0430\u043b\u0438 \u043a\u0430\u043c\u043d\u044f\u043c\u0438, \u0421\u0442\u0435\u0444\u0430\u043d \u043c\u043e\u043b\u0438\u043b\u0441\u044f: \u00ab\u0413\u043e\u0441\u043f\u043e\u0434\u0438 \u0418\u0438\u0441\u0443\u0441\u0435, \u043f\u0440\u0438\u043c\u0438 \u0434\u0443\u0445 \u043c\u043e\u0439\u00bb.\n60 \u0422\u043e\u0433\u0434\u0430 \u043e\u043d \u043f\u0430\u043b \u043d\u0430 \u043a\u043e\u043b\u0435\u043d\u0438 \u0438 \u0432\u043e\u0441\u043a\u043b\u0438\u043a\u043d\u0443\u043b: \u00ab\u0413\u043e\u0441\u043f\u043e\u0434\u0438, \u043d\u0435 \u0432\u043c\u0435\u043d\u0438 \u0438\u043c \u044d\u0442\u043e\u0433\u043e \u0433\u0440\u0435\u0445\u0430!\u00bb\n\n\u0422\u043e\u043b\u044c\u043a\u043e \u0411\u043e\u0433 \u043c\u043e\u0436\u0435\u0442 \u043f\u043e\u043c\u043e\u0447\u044c \u043d\u0430\u043c \u0442\u0435\u0440\u043f\u0435\u043b\u0438\u0432\u043e \u043f\u0435\u0440\u0435\u043d\u043e\u0441\u0438\u0442\u044c \u0437\u043b\u043e, \u043a\u0430\u043a \u044d\u0442\u043e \u0434\u0435\u043b\u0430\u043b \u0421\u0442\u0435\u0444\u0430\u043d.\n\u041d\u043e \u041e\u043d \u043f\u043e\u043c\u043e\u0436\u0435\u0442 \u043d\u0430\u043c, \u043a\u043e\u0433\u0434\u0430 \u043c\u044b \u0431\u0443\u0434\u0435\u043c \u0432\u0437\u044b\u0432\u0430\u0442\u044c \u043a \u041d\u0435\u043c\u0443 \u0432 \u0442\u0440\u0443\u0434\u043d\u044b\u0435 \u0432\u0440\u0435\u043c\u0435\u043d\u0430.\n\u041e\u043d \u043f\u043e\u043c\u043e\u0436\u0435\u0442 \u043d\u0430\u043c \u0434\u043e\u0432\u0435\u0440\u044f\u0442\u044c \u0415\u043c\u0443, \u0437\u043d\u0430\u044f, \u0447\u0442\u043e \u043d\u0430\u0448\u0438 \u0434\u0443\u0448\u0438 \u0432 \u0431\u0435\u0437\u043e\u043f\u0430\u0441\u043d\u043e\u0441\u0442\u0438 \u0432 \u0415\u0433\u043e \u0440\u0443\u043a\u0430\u0445, \u0447\u0442\u043e \u0431\u044b \u043d\u0438 \u0441\u043b\u0443\u0447\u0438\u043b\u043e\u0441\u044c \u0441 \u043d\u0430\u0448\u0438\u043c\u0438 \u0442\u0435\u043b\u0430\u043c\u0438.\n\n\u041a\u0430\u0447\u0435\u0441\u0442\u0432\u043e 4: \u041a\u043e\u0440\u0440\u0435\u043a\u0446\u0438\u044f \u0441 \u043e\u0441\u0442\u043e\u0440\u043e\u0436\u043d\u043e\u0441\u0442\u044c\u044e.\n\u041f\u043e\u043f\u0440\u0430\u0432\u043b\u044f\u0442\u044c \u043b\u044e\u0434\u0435\u0439 \u2014 \u044d\u0442\u043e \u0441\u043b\u043e\u0436\u043d\u043e.\n\u041d\u043e \u0435\u0441\u043b\u0438 \u043c\u043e\u0439 \u0441\u044b\u043d \u0434\u0435\u043b\u0430\u0435\u0442 \u0447\u0442\u043e-\u0442\u043e \u043d\u0435 \u0442\u0430\u043a, \u044f \u0433\u043e\u0432\u043e\u0440\u044e \u0435\u043c\u0443 \u043e\u0431 \u044d\u0442\u043e\u043c, \u043f\u043e\u0442\u043e\u043c\u0443 \u0447\u0442\u043e \u043b\u044e\u0431\u043b\u044e \u0435\u0433\u043e.\n\u0412\u043e\u0442 \u0432\u0430\u0436\u043d\u044b\u0439 \u0432\u043e\u043f\u0440\u043e\u0441, \u043d\u0430\u0434 \u043a\u043e\u0442\u043e\u0440\u044b\u043c \u0441\u043b\u0435\u0434\u0443\u0435\u0442 \u0437\u0430\u0434\u0443\u043c\u0430\u0442\u044c\u0441\u044f, \u043a\u043e\u0433\u0434\u0430 \u0432\u0430\u043c \u043d\u0443\u0436\u043d\u043e \u043a\u043e\u0433\u043e-\u0442\u043e \u043f\u043e\u043f\u0440\u0430\u0432\u0438\u0442\u044c:\n\u00ab\u0427\u0443\u0432\u0441\u0442\u0432\u0443\u0435\u0442 \u043b\u0438 \u043c\u043e\u0439 \u0440\u0435\u0431\u0435\u043d\u043e\u043a, \u0434\u0440\u0443\u0433 \u0438\u043b\u0438 \u0441\u0443\u043f\u0440\u0443\u0433 \u043c\u043e\u044e \u043b\u044e\u0431\u043e\u0432\u044c?\u00bb\n\u0418\u043b\u0438 \u043e\u043d\u0438 \u0447\u0443\u0432\u0441\u0442\u0432\u0443\u044e\u0442 \u0442\u043e\u043b\u044c\u043a\u043e \u043c\u043e\u0439 \u0433\u043d\u0435\u0432?\n\n\u041a\u043e\u0433\u0434\u0430 \u043c\u044b \u0438\u0441\u043f\u0440\u0430\u0432\u043b\u044f\u0435\u043c \u0441\u0438\u0442\u0443\u0430\u0446\u0438\u044e \u0441 \u043f\u043e\u043c\u043e\u0449\u044c\u044e \u0433\u043d\u0435\u0432\u0430 \u0438\u043b\u0438 \u0440\u0430\u0437\u043e\u0447\u0430\u0440\u043e\u0432\u0430\u043d\u0438\u044f, \u043c\u044b \u0432\u0435\u0434\u0435\u043c \u0441\u0435\u0431\u044f \u0442\u0430\u043a, \u0431\u0443\u0434\u0442\u043e \u0411\u043e\u0433 \u043d\u0435 \u043c\u043e\u0436\u0435\u0442 \u0438\u0437\u043c\u0435\u043d\u0438\u0442\u044c \u0434\u0440\u0443\u0433\u043e\u0433\u043e \u0447\u0435\u043b\u043e\u0432\u0435\u043a\u0430.\n\u041c\u044b \u0434\u0443\u043c\u0430\u0435\u043c, \u0447\u0442\u043e \u043c\u043e\u0436\u0435\u043c \u0437\u0430\u0441\u0442\u0430\u0432\u0438\u0442\u044c \u0438\u0445 \u0438\u0437\u043c\u0435\u043d\u0438\u0442\u044c\u0441\u044f \u0438\u043b\u0438 \u043a\u0440\u0438\u0447\u0430\u0442\u044c \u0433\u0440\u043e\u043c\u0447\u0435, \u043f\u043e\u043a\u0430 \u043e\u043d\u0438 \u043d\u0435 \u0432\u0441\u0442\u0430\u043d\u0443\u0442 \u043d\u0430 \u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u044b\u0439 \u043f\u0443\u0442\u044c.\n\u041d\u043e \u0443\u0447\u0438\u0442\u0435\u043b\u044c, \u0437\u043d\u0430\u044e\u0449\u0438\u0439, \u0447\u0442\u043e \u0438\u0441\u0442\u0438\u043d\u043d\u0430\u044f \u0441\u0438\u043b\u0430 \u043f\u0440\u0438\u043d\u0430\u0434\u043b\u0435\u0436\u0438\u0442 \u0411\u043e\u0433\u0443, \u0431\u0443\u0434\u0435\u0442 \u043a\u0440\u043e\u0442\u043a\u0438\u043c, \u0442\u0435\u0440\u043f\u0435\u043b\u0438\u0432\u044b\u043c \u0438 \u0434\u043e\u0431\u0440\u044b\u043c.\n\n\u041a\u0430\u0447\u0435\u0441\u0442\u0432\u043e 5: \u0421\u043f\u043e\u0441\u043e\u0431\u043d\u043e\u0441\u0442\u044c \u043e\u0431\u0443\u0447\u0430\u0442\u044c.\n\u0414\u043e\u0441\u0442\u0430\u0442\u043e\u0447\u043d\u043e \u043b\u0438 \u0445\u043e\u0440\u043e\u0448\u043e \u0432\u044b \u043f\u043e\u043d\u0438\u043c\u0430\u0435\u0442\u0435 \u0421\u043b\u043e\u0432\u043e \u0411\u043e\u0436\u044c\u0435, \u0447\u0442\u043e\u0431\u044b \u043e\u0431\u044a\u044f\u0441\u043d\u044f\u0442\u044c \u0435\u0433\u043e \u0434\u0440\u0443\u0433\u0438\u043c?\n\u0412\u044b \u0437\u0430\u0443\u0447\u0438\u0432\u0430\u0435\u0442\u0435 \u043d\u0430\u0438\u0437\u0443\u0441\u0442\u044c \u043e\u0442\u0440\u044b\u0432\u043a\u0438 \u0438\u0437 \u0421\u0432\u044f\u0449\u0435\u043d\u043d\u043e\u0433\u043e \u041f\u0438\u0441\u0430\u043d\u0438\u044f, \u0447\u0442\u043e\u0431\u044b \u043e\u043d\u0438 \u0432\u0441\u0435\u0433\u0434\u0430 \u0431\u044b\u043b\u0438 \u043f\u043e\u0434 \u0440\u0443\u043a\u043e\u0439 \u0438 \u043c\u043e\u0433\u043b\u0438 \u0441\u043b\u0443\u0436\u0438\u0442\u044c \u0432\u0430\u043c \u0440\u0443\u043a\u043e\u0432\u043e\u0434\u0441\u0442\u0432\u043e\u043c \u0432 \u0436\u0438\u0437\u043d\u0438, \u0430 \u0442\u0430\u043a\u0436\u0435 \u0447\u0442\u043e\u0431\u044b \u0432\u044b \u043c\u043e\u0433\u043b\u0438 \u0434\u0435\u043b\u0438\u0442\u044c\u0441\u044f \u0438\u043c\u0438 \u0441 \u0434\u0440\u0443\u0433\u0438\u043c\u0438?\n\u0412 \u044d\u0442\u043e\u043c \u043c\u0435\u0441\u044f\u0446\u0435 \u043c\u044b \u043d\u0430\u0447\u043d\u0451\u043c \u043d\u0435\u0447\u0442\u043e \u043d\u043e\u0432\u043e\u0435.\n\u041c\u044b \u043f\u043e\u043f\u0440\u043e\u0441\u0438\u043c \u0432\u0430\u0441 \u0432\u044b\u0443\u0447\u0438\u0442\u044c \u043d\u0430\u0438\u0437\u0443\u0441\u0442\u044c \u043e\u0434\u0438\u043d \u0441\u0442\u0438\u0445 \u0438\u0437 \u0421\u0432\u044f\u0449\u0435\u043d\u043d\u043e\u0433\u043e \u041f\u0438\u0441\u0430\u043d\u0438\u044f \u043a \u043a\u043e\u043d\u0446\u0443 \u043c\u0430\u0440\u0442\u0430.\n\u0410 \u0435\u0441\u043b\u0438 \u0432\u044b \u0441\u043c\u043e\u0436\u0435\u0442\u0435 \u043f\u0440\u043e\u0447\u0438\u0442\u0430\u0442\u044c \u044d\u0442\u043e \u043e\u0434\u043d\u043e\u043c\u0443 \u0438\u0437 \u043d\u0430\u0448\u0438\u0445 \u043b\u0438\u0434\u0435\u0440\u043e\u0432 \u043d\u0430 \u043b\u044e\u0431\u043e\u043c \u044f\u0437\u044b\u043a\u0435, \u0432\u044b \u043f\u043e\u043b\u0443\u0447\u0438\u0442\u0435 \u043d\u0430\u043a\u043b\u0435\u0439\u043a\u0443.\n\u0412\u044b \u043c\u043e\u0436\u0435\u0442\u0435 \u043f\u0440\u0438\u043a\u0440\u0435\u043f\u0438\u0442\u044c \u0435\u0433\u043e \u043a \u0441\u0432\u043e\u0435\u0439 \u0431\u0443\u0442\u044b\u043b\u043a\u0435 \u0441 \u0432\u043e\u0434\u043e\u0439 \u0438\u043b\u0438 \u0431\u043b\u043e\u043a\u043d\u043e\u0442\u0443.\n\u0412\u0435\u0437\u0434\u0435, \u0433\u0434\u0435 \u0432\u044b \u044d\u0442\u043e \u0443\u0432\u0438\u0434\u0438\u0442\u0435, \u0438 \u043f\u0440\u043e\u0434\u043e\u043b\u0436\u0430\u0439\u0442\u0435 \u043f\u0440\u0430\u043a\u0442\u0438\u043a\u043e\u0432\u0430\u0442\u044c \u044d\u0442\u043e \u0432 \u0442\u0435\u0447\u0435\u043d\u0438\u0435 \u0432\u0441\u0435\u0433\u043e \u0433\u043e\u0434\u0430.\n\u0414\u0430\u0432\u0430\u0439\u0442\u0435 \u0432\u043c\u0435\u0441\u0442\u0435 \u043f\u0440\u043e\u0447\u0438\u0442\u0430\u0435\u043c \u0441\u0442\u0438\u0445 \u043d\u0430 \u043c\u0430\u0440\u0442 \u043c\u0435\u0441\u044f\u0446, 2 \u0422\u0438\u043c\u043e\u0444\u0435\u044e 3:16.\n\u0412\u0421\u0415: \u00ab\u0412\u0441\u0451 \u041f\u0438\u0441\u0430\u043d\u0438\u0435 \u0431\u043e\u0433\u043e\u0434\u0443\u0445\u043d\u043e\u0432\u0435\u043d\u043d\u043e \u0438 \u043f\u043e\u043b\u0435\u0437\u043d\u043e \u0434\u043b\u044f \u043d\u0430\u0443\u0447\u0435\u043d\u0438\u044f, \u043e\u0431\u043b\u0438\u0447\u0435\u043d\u0438\u044f, \u0438\u0441\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u0438\u044f \u0438 \u043d\u0430\u0441\u0442\u0430\u0432\u043b\u0435\u043d\u0438\u044f \u0432 \u043f\u0440\u0430\u0432\u0435\u0434\u043d\u043e\u0441\u0442\u0438\u00bb.\n\n\u041d\u0430\u043c \u0432\u0441\u0435\u043c \u043d\u0443\u0436\u043d\u0430 \u043f\u043e\u043c\u043e\u0449\u044c, \u0447\u0442\u043e\u0431\u044b \u0434\u0432\u0438\u0433\u0430\u0442\u044c\u0441\u044f \u0432 \u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e\u043c \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u0438\u0438.\n\u041d\u0430\u043c \u043d\u0435\u043e\u0431\u0445\u043e\u0434\u0438\u043c\u043e \u0421\u043b\u043e\u0432\u043e \u0411\u043e\u0436\u044c\u0435, \u0447\u0442\u043e\u0431\u044b \u043e\u043d\u043e \u0443\u0447\u0438\u043b\u043e, \u0438\u0441\u043f\u0440\u0430\u0432\u043b\u044f\u043b\u043e \u0438 \u043d\u0430\u0441\u0442\u0430\u0432\u043b\u044f\u043b\u043e \u043d\u0430\u0441 \u043f\u043e\u0441\u0442\u0443\u043f\u0430\u0442\u044c \u0432 \u043f\u0440\u0430\u0432\u0435\u0434\u043d\u043e\u0441\u0442\u0438.\n\u041d\u0430\u043c \u043d\u0443\u0436\u0435\u043d \u0421\u0432\u044f\u0442\u043e\u0439 \u0414\u0443\u0445, \u0447\u0442\u043e\u0431\u044b \u043f\u043e\u043c\u043e\u0447\u044c \u043d\u0430\u043c \u043f\u043e\u043d\u044f\u0442\u044c \u0438 \u043f\u0440\u0438\u043c\u0435\u043d\u0438\u0442\u044c \u0421\u043b\u043e\u0432\u043e, \u043f\u043e\u044d\u0442\u043e\u043c\u0443 \u0434\u0430\u0432\u0430\u0439\u0442\u0435 \u0441\u0435\u0439\u0447\u0430\u0441 \u0432 \u043c\u043e\u043b\u0438\u0442\u0432\u0435 \u043e\u0431\u0440\u0430\u0442\u0438\u043c \u043d\u0430\u0448\u0438 \u0441\u0435\u0440\u0434\u0446\u0430 \u043a \u043d\u0435\u0431\u0435\u0441\u0430\u043c.\n\u0418\u0438\u0441\u0443\u0441, \u043c\u044b \u043c\u043e\u0436\u0435\u043c \u0433\u043e\u0432\u043e\u0440\u0438\u0442\u044c \u0441 \u041e\u0442\u0446\u043e\u043c \u0442\u043e\u043b\u044c\u043a\u043e \u043f\u043e\u0442\u043e\u043c\u0443, \u0447\u0442\u043e \u0422\u044b \u043f\u043e\u0441\u0442\u0440\u043e\u0438\u043b \u043c\u043e\u0441\u0442 \u043c\u0435\u0436\u0434\u0443 \u0437\u0435\u043c\u043b\u0435\u0439 \u0438 \u043d\u0435\u0431\u043e\u043c.\n\u0412\u044b \u0440\u0430\u0437\u0440\u0443\u0448\u0438\u043b\u0438 \u043a\u043e\u0437\u043d\u0438 \u0434\u044c\u044f\u0432\u043e\u043b\u0430 \u0438 \u043e\u0442\u043a\u0440\u044b\u043b\u0438 \u043d\u0430\u043c \u0433\u043b\u0430\u0437\u0430 \u043d\u0430 \u0438\u0441\u0442\u0438\u043d\u0443.\n\u041e\u0442\u0435\u0446, \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u044e \u0422\u0435\u0431\u044f \u0437\u0430 \u0434\u0430\u0440 \u043f\u043e\u043a\u0430\u044f\u043d\u0438\u044f, \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u044f \u043a\u043e\u0442\u043e\u0440\u043e\u043c\u0443 \u043c\u044b \u043c\u043e\u0436\u0435\u043c \u0431\u044b\u0442\u044c \u0447\u0435\u0441\u0442\u043d\u044b \u0441 \u0441\u0430\u043c\u0438\u043c\u0438 \u0441\u043e\u0431\u043e\u0439 \u0438 \u0441 \u0422\u043e\u0431\u043e\u0439 \u0432 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u0438 \u0441\u0432\u043e\u0438\u0445 \u0433\u0440\u0435\u0445\u043e\u0432.\n\u0418 \u0441\u043f\u0430\u0441\u0438\u0431\u043e \u0422\u0435\u0431\u0435, \u0421\u0432\u044f\u0442\u043e\u0439 \u0414\u0443\u0445, \u0437\u0430 \u0442\u043e, \u0447\u0442\u043e \u0422\u044b \u0434\u0430\u0440\u043e\u0432\u0430\u043b \u043d\u0430\u043c \u0432\u0435\u0440\u0443, \u0447\u0442\u043e\u0431\u044b \u043e\u0431\u0440\u0430\u0442\u0438\u0442\u044c\u0441\u044f \u043a \u0418\u0438\u0441\u0443\u0441\u0443 \u0437\u0430 \u043d\u0430\u0448\u0438\u043c \u0441\u043f\u0430\u0441\u0435\u043d\u0438\u0435\u043c.\n\u041e\u0442\u043a\u0440\u043e\u0439\u0442\u0435 \u043d\u0430\u0448\u0438 \u0443\u043c\u044b \u0438 \u0441\u0435\u0440\u0434\u0446\u0430, \u0447\u0442\u043e\u0431\u044b \u043c\u044b \u043c\u043e\u0433\u043b\u0438 \u043f\u043e\u043d\u044f\u0442\u044c \u0438 \u043f\u0440\u0438\u043c\u0435\u043d\u0438\u0442\u044c \u0421\u043b\u043e\u0432\u043e \u0411\u043e\u0436\u044c\u0435 \u0432 \u0441\u0432\u043e\u0435\u0439 \u0436\u0438\u0437\u043d\u0438.\n\u041f\u043e\u043c\u043e\u0433\u0438 \u043d\u0430\u043c \u0443\u0441\u0435\u0440\u0434\u043d\u043e \u0431\u0435\u0436\u0430\u0442\u044c \u043f\u043e \u043f\u0440\u0435\u0434\u0441\u0442\u043e\u044f\u0449\u0435\u0439 \u043d\u0430\u043c \u0434\u0438\u0441\u0442\u0430\u043d\u0446\u0438\u0438, \u043f\u0440\u0438\u0433\u043b\u0430\u0448\u0430\u044f \u0434\u0440\u0443\u0433\u0438\u0445 \u043f\u0440\u0438\u0441\u043e\u0435\u0434\u0438\u043d\u0438\u0442\u044c\u0441\u044f \u043a \u043d\u0430\u043c \u043d\u0430 \u043f\u0443\u0442\u0438 \u043a \u0446\u0435\u043b\u043e\u0441\u0442\u043d\u043e\u0441\u0442\u0438, \u043d\u0430\u0434\u0435\u0436\u0434\u0435 \u0438 \u043d\u0435\u0431\u0435\u0441\u0430\u043c, \u0430\u043c\u0438\u043d\u044c.\n\n\u0412\u043e\u043f\u0440\u043e\u0441\u044b \u0434\u043b\u044f \u0440\u0430\u0437\u043c\u044b\u0448\u043b\u0435\u043d\u0438\u044f \u0438 \u043e\u0431\u0441\u0443\u0436\u0434\u0435\u043d\u0438\u044f\n1.  \u041f\u0440\u043e\u0447\u0438\u0442\u0430\u0439\u0442\u0435 2 \u0422\u0438\u043c\u043e\u0444\u0435\u044e 2:22 \u0438 \u041f\u0441\u0430\u043b\u043e\u043c 119:35-37.\n\u0430) \u041a \u043a\u0430\u043a\u0438\u043c \u0438\u0437 \u00ab\u044e\u043d\u043e\u0448\u0435\u0441\u043a\u0438\u0445 \u0441\u0442\u0440\u0430\u0441\u0442\u0435\u0439\u00bb (\u0443\u0434\u043e\u0432\u043e\u043b\u044c\u0441\u0442\u0432\u0438\u0435, \u0432\u043b\u0430\u0441\u0442\u044c, \u043f\u043e\u043f\u0443\u043b\u044f\u0440\u043d\u043e\u0441\u0442\u044c, \u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u043e, \u0433\u043e\u0440\u0434\u043e\u0441\u0442\u044c) \u0432\u0430\u0448\u0435 \u0441\u0435\u0440\u0434\u0446\u0435 \u0435\u0441\u0442\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u043c \u043e\u0431\u0440\u0430\u0437\u043e\u043c \u0441\u0442\u0440\u0435\u043c\u0438\u0442\u0441\u044f, \u043a\u043e\u0433\u0434\u0430 \u0432\u044b \u0438\u0441\u043f\u044b\u0442\u044b\u0432\u0430\u0435\u0442\u0435 \u0441\u0442\u0440\u0435\u0441\u0441 \u0438\u043b\u0438 \u0438\u0449\u0435\u0442\u0435 \u0443\u0442\u0435\u0448\u0435\u043d\u0438\u044f?\n\n2.  \u041f\u0440\u043e\u0447\u0438\u0442\u0430\u0439\u0442\u0435 \u041f\u043e\u0441\u043b\u0430\u043d\u0438\u0435 \u043a \u0415\u0444\u0435\u0441\u044f\u043d\u0430\u043c 2:1-5 \u0438 \u0418\u0435\u0437\u0435\u043a\u0438\u0438\u043b\u044e 36:26.\n\u0430) \u0427\u0442\u043e \u043d\u0435\u043e\u0431\u0445\u043e\u0434\u0438\u043c\u043e, \u0447\u0442\u043e\u0431\u044b \u043f\u0435\u0440\u0435\u0439\u0442\u0438 \u0438\u0437 \u0441\u043e\u0441\u0442\u043e\u044f\u043d\u0438\u044f \u00ab\u043c\u0435\u0440\u0442\u0432\u043e\u0433\u043e\u00bb \u0432 \u0441\u043e\u0441\u0442\u043e\u044f\u043d\u0438\u0435 \u00ab\u0436\u0438\u0432\u043e\u0433\u043e\u00bb?\n\u0431) \u041f\u043e\u043c\u043e\u0433\u0430\u0435\u0442 \u043b\u0438 \u0432\u0435\u0440\u0430 \u0432 \u0442\u043e, \u0447\u0442\u043e \u043f\u043e\u043a\u0430\u044f\u043d\u0438\u0435 \u2014 \u044d\u0442\u043e \u0434\u0430\u0440 \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0442\u0438, \u0431\u044b\u0442\u044c \u0431\u043e\u043b\u0435\u0435 \u0447\u0435\u0441\u0442\u043d\u044b\u043c \u0441 \u0411\u043e\u0433\u043e\u043c \u0432 \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u0438 \u0441\u0432\u043e\u0438\u0445 \u0433\u0440\u0435\u0445\u043e\u0432?\n\n3.  \u041f\u0440\u043e\u0447\u0438\u0442\u0430\u0439\u0442\u0435 2 \u0422\u0438\u043c\u043e\u0444\u0435\u044e 2:23-25\u0430 \u0438 \u041a\u043e\u043b\u043e\u0441\u0441\u044f\u043d\u0430\u043c 3:12-14.\n\u0430) \u041a\u0430\u043a\u0438\u043c\u0438 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0430\u043c\u0438 \u0434\u043e\u043b\u0436\u0435\u043d \u043e\u0431\u043b\u0430\u0434\u0430\u0442\u044c \u00ab\u0441\u043b\u0443\u0433\u0430 \u0413\u043e\u0441\u043f\u043e\u0434\u0435\u043d\u044c\u00bb \u043f\u0440\u0438 \u043e\u0431\u0441\u0443\u0436\u0434\u0435\u043d\u0438\u0438 \u0438\u043b\u0438 \u0438\u0441\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u0438\u0438 \u0434\u0440\u0443\u0433\u0438\u0445?\n\u0431) \u041f\u043e\u0441\u043a\u043e\u043b\u044c\u043a\u0443 \u0418\u0438\u0441\u0443\u0441 \u0432\u043e\u0437\u043b\u044e\u0431\u0438\u043b \u043d\u0430\u0441 \u0441 \u0432\u0435\u043b\u0438\u043a\u0438\u043c \u0442\u0435\u0440\u043f\u0435\u043d\u0438\u0435\u043c \u0438 \u043a\u0440\u043e\u0442\u043e\u0441\u0442\u044c\u044e, \u043a\u043e\u0433\u043e \u0432 \u0432\u0430\u0448\u0435\u0439 \u0436\u0438\u0437\u043d\u0438 \u0432\u044b \u0431\u0443\u0434\u0435\u0442\u0435 \u043b\u044e\u0431\u0438\u0442\u044c \u0441 \u0442\u043e\u0439 \u0436\u0435 \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0442\u044c\u044e, \u0434\u0430\u0436\u0435 \u0435\u0441\u043b\u0438 \u043e\u043d\u0438 \u043d\u0435 \u0441\u043e\u0433\u043b\u0430\u0441\u043d\u044b \u0441 \u0432\u0430\u043c\u0438 \u0438\u043b\u0438 \u043d\u0435 \u043b\u044e\u0431\u044f\u0442 \u0432\u0430\u0441?\n\n4.  \u041f\u0440\u043e\u0447\u0438\u0442\u0430\u0439\u0442\u0435 \u041f\u043e\u0441\u043b\u0430\u043d\u0438\u0435 \u043a \u0420\u0438\u043c\u043b\u044f\u043d\u0430\u043c 10:9-11 \u0438 \u041f\u043e\u0441\u043b\u0430\u043d\u0438\u0435 \u043a \u0415\u0432\u0440\u0435\u044f\u043c 12:1-2.\n\u0430) \u041a\u0430\u043a \u0441\u043e\u0441\u0440\u0435\u0434\u043e\u0442\u043e\u0447\u0435\u043d\u0438\u0435 \u043d\u0430\u0448\u0435\u0433\u043e \u0432\u0437\u043e\u0440\u0430 \u043d\u0430 \u0418\u0438\u0441\u0443\u0441\u0435 \u043f\u043e\u043c\u043e\u0433\u0430\u0435\u0442 \u043d\u0430\u043c \u043e\u0442\u0432\u0435\u0440\u043d\u0443\u0442\u044c\u0441\u044f \u043e\u0442 \u0433\u0440\u0435\u0445\u0430 \u0438 \u0434\u0432\u0438\u0433\u0430\u0442\u044c\u0441\u044f \u0432 \u043d\u043e\u0432\u043e\u043c \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u0438\u0438?\n\u0431) \u041d\u0435 \u0437\u0430\u0431\u0443\u0434\u044c\u0442\u0435 \u0432\u044b\u0443\u0447\u0438\u0442\u044c \u043d\u0430\u0438\u0437\u0443\u0441\u0442\u044c 2 \u0422\u0438\u043c\u043e\u0444\u0435\u044e 3:16. \u041a\u0430\u043a \u0437\u043d\u0430\u043d\u0438\u0435 \u0421\u043b\u043e\u0432\u0430 \u0411\u043e\u0436\u044c\u0435\u0433\u043e \u043f\u043e\u043c\u043e\u0433\u0430\u0435\u0442 \u043d\u0430\u043c \u043f\u0440\u043e\u0431\u0435\u0436\u0430\u0442\u044c \u043c\u0430\u0440\u0430\u0444\u043e\u043d \u0432\u0435\u0440\u044b?","spanish_content":"\u00bfA d\u00f3nde est\u00e1s corriendo?\n2 Timoteo 2:22-26\nPastor Chris Sicks\n15 de marzo de 2026\n\nEn el Marat\u00f3n de 2019 en Portland, Oreg\u00f3n, algunos de los mejores corredores perdieron la carrera.\nNo porque fueran lentos sino porque tomaron el camino equivocado.\nHab\u00eda un giro en el recorrido que no estaba claramente marcado.\n\u00a1As\u00ed, unos 20 de los corredores m\u00e1s r\u00e1pidos corrieron m\u00e1s de una milla en la direcci\u00f3n equivocada!\nEl error a\u00f1adi\u00f3 minutos preciosos a una carrera que hab\u00edan pasado meses prepar\u00e1ndose para correr.\nAquellos hombres y mujeres corrieron duro y corrieron r\u00e1pido.\nPero perdieron la carrera, porque estaban en el camino equivocado.\nEsta noche continuamos una serie de sermones en el libro de 2 Timoteo.\nEl ap\u00f3stol Pablo le est\u00e1 escribiendo a Timoteo, un joven pastor de la iglesia cristiana en \u00c9feso.\nPablo le est\u00e1 dando a Timoteo, y a nosotros hoy, consejos sobre c\u00f3mo permanecer en el camino correcto.\n2 Timoteo 2:22\u201326\n22 Huye, pues, de las pasiones juveniles y sigue la justicia, la fe, el amor y la paz, con los que invocan al Se\u00f1or con un coraz\u00f3n puro.\n23 No tengan nada que ver con controversias necias e ignorantes, porque saben que engendran contiendas.\n24 Y el siervo del Se\u00f1or no debe ser contencioso, sino amable para con todos, apto para ense\u00f1ar, sufrido,\n25 corrigiendo a sus oponentes con gentileza.\nQuiz\u00e1 Dios les conceda que se arrepientan para conocer la verdad,\n26 y que recobren el sentido y escapen del lazo del diablo, despu\u00e9s de haber estado cautivos de \u00e9l para hacer su voluntad.\n\nleemos juntos Isaias 40:8\n\u201cS\u00e9case la hierba, march\u00edtase la flor, m\u00e1s la palabra del  Dios nuestro permanece para siempre.\u201d\n\nEl vers\u00edculo 22 dice:\n22 Huye, pues, de las pasiones juveniles y sigue la justicia, la fe, el amor y la paz, con los que invocan al Se\u00f1or con un coraz\u00f3n puro.\n\nEste vers\u00edculo es realmente un resumen del serm\u00f3n de hoy.\nVemos esto a menudo en la Palabra de Dios.\nA veces la primera declaraci\u00f3n de un salmo o de un p\u00e1rrafo ser\u00e1 un resumen.\nLuego las palabras que siguen son una explicaci\u00f3n de todo el Salmo o p\u00e1rrafo o cap\u00edtulo.\nUn hombre o una mujer cristiana madura es alguien que se aleja de las cosas que nos tentaron cuando \u00e9ramos m\u00e1s j\u00f3venes.\nEn lugar de \u201cpasiones juveniles\u201d, una persona madura est\u00e1 aprendiendo a perseguir los valores de Dios, incluyendo la justicia, la fe, el amor y la paz.\nCuando Pablo era joven, su nombre era Saulo.\nSaulo estaba lleno de orgullo y confianza en s\u00ed mismo, y usaba el poder para perseguir a los cristianos y ponerlos en la c\u00e1rcel.\nSaulo quer\u00eda ser popular y exitoso y estaba dispuesto a lastimar a otros debido a su propio orgullo.\nPero la carta de 2 Timoteo fue escrita por Pablo, el creyente maduro.\n\u00c9l entiende cu\u00e1nto da\u00f1o le hicieron sus pasiones juveniles y advierte a Timoteo sobre ellas.\nEn el momento en que Pablo escribe esta carta, Timoteo probablemente ten\u00eda alrededor de 40 a\u00f1os.\nPero no hace falta ser joven para correr hacia las \u201cpasiones juveniles\u201d.\nTengo 57 a\u00f1os, pero todav\u00eda estoy aprendiendo a huir constantemente de las pasiones juveniles.\nTengo un amigo de la universidad que tiene la misma edad que yo.\nPero todav\u00eda vive como hace 35 a\u00f1os.\nSu vida est\u00e1 dominada por las pasiones juveniles de nuestros d\u00edas universitarios.\nAqu\u00ed hay algunas pasiones juveniles que muchos de nosotros experimentamos:\n\n*   Placer: El pecado sexual es un ejemplo com\u00fan del pecado del placer, pero no es el \u00fanico.\nOtros placeres pecaminosos pueden incluir el alcohol, la comida y muchos tipos de entretenimiento.\nEstas cosas no son malas si se utilizan correctamente.\nEl sexo, por ejemplo, es un hermoso regalo en el contexto del matrimonio cristiano.\nPero cuando usamos algo de manera incorrecta, le damos poder sobre nuestras vidas.\nCuando usamos cualquiera de los dones de Dios para llenar el vac\u00edo de nuestro coraz\u00f3n, eso se convierte en un dios falso: un \u00eddolo.\n\n*   Poder: Cuando somos j\u00f3venes, a veces nos sentimos impotentes, d\u00e9biles o inadecuados.\nLuch\u00e9 con esos sentimientos cuando era adolescente.\nAlgunas personas buscan el poder para ocultar sus sentimientos de debilidad.\nCreen que actuar con fuerza les ayudar\u00e1 a sentirse seguros.\n\u00bfSab\u00edas que un acosador en realidad no es tan duro como parece?\nUn acosador suele ser alguien que se siente impotente ante algo en su vida, por lo que hiere a otras personas para sentirse poderoso.\n\n*   Popularidad: Esta ha sido otra fuerte tentaci\u00f3n en mi vida.\nA menudo me preocupa si le gusto a la gente.\nMe preocupo demasiado por las opiniones de otras personas.\n\u00bfY t\u00fa?\n\u00bfAlguna vez cambias tu comportamiento o apariencia para agradarle a la gente?\n\u00bfCrees que tienes que actuar o lucir de cierta manera para evitar el rechazo?\n\n*   Posesiones: El amor al dinero y a las posesiones materiales es un problema para la mayor\u00eda de nosotros.\nQueremos la seguridad y comodidad de tener m\u00e1s cosas.\nEsto revela una falta de fe.\nDios quiere que entendamos que \u00c9l es nuestro refugio y fortaleza, \u00c9l es nuestro proveedor.\nLas cosas materiales prometen felicidad, pero nunca pueden cumplir su promesa.\nPorque nuestros corazones siempre anhelar\u00e1n m\u00e1s.\n\n*   Orgullo: Este es realmente el pecado que se esconde detr\u00e1s de todos los dem\u00e1s pecados.\nEl orgullo es la creencia de que realmente merezco posesiones, poder, placer y popularidad.\n\u00bfPor qu\u00e9? Porque soy especial.\nEl orgullo nos susurra mentiras, diciendo:\n\u201cEst\u00e1 bien, puedes hacerlo. Te lo mereces\u201d.\nLos anunciantes nos dicen lo mismo.\n\u201cTe lo mereces... Adelante, c\u00f3mpralo.\nQuiz\u00e1s compre m\u00e1s, est\u00e1 bien\u201d.\nPor eso vemos tantos anuncios como \u00e9ste, porque nuestro orgullo realmente quiere creer estas cosas.\n\n\u00bfPuedo hacerles una pregunta mis amigos?\n\u00bfCu\u00e1l de estas cinco cosas te suena familiar?\n\u00bfEst\u00e1s buscando orgullo, posesiones, poder, placer o popularidad?\n\u00bfO quiz\u00e1s es algo m\u00e1s lo que te aleja de Dios?\n\u00bfD\u00f3nde est\u00e1 tu coraz\u00f3n hoy y hacia d\u00f3nde vas?\n\u00bfRecord\u00e1is lo que Dios le pregunt\u00f3 a Ad\u00e1n en el jard\u00edn, despu\u00e9s de que comi\u00f3 el fruto?\nAd\u00e1n y Eva estaban escondidos, y Dios le dijo: \u201d\u00bfD\u00f3nde est\u00e1s, Ad\u00e1n?\u201d\nDios est\u00e1 pidiendo lo mismo a todos en la tierra hoy.\n\u00bfD\u00f3nde est\u00e1s?\n\u00c9l no est\u00e1 preguntando d\u00f3nde est\u00e1s f\u00edsicamente.\n\u00c9l est\u00e1 preguntando: \u201d\u00bfD\u00f3nde est\u00e1 tu coraz\u00f3n?\u201d\nPorque nuestro coraz\u00f3n es como una br\u00fajula que nos gu\u00eda por el camino hacia aquello que m\u00e1s valoramos.\nNos perdemos y ni siquiera nos damos cuenta porque el pecado es furtivo.\nNecesitamos la ayuda de Dios para ver lo que est\u00e1 pasando dentro de nosotros.\nLeamos juntos el Salmo 139:23-24, como una oraci\u00f3n:\nTODOS: 23 Exam\u00edname, oh Dios, y conoce mi coraz\u00f3n.\n\u00a1Ponme a prueba y conoce mis pensamientos!\n24 Y mirad si hay en m\u00ed camino de perversidad,\n\u00a1Y gu\u00edame en el camino eterno!\u201d\n\nSin la ayuda de Dios, no caminaremos \u201cen el camino eterno\u201d.\nCorreremos en la direcci\u00f3n equivocada, persiguiendo cosas que nos alejan del coraz\u00f3n de Dios.\nPero Dios es tan bueno que no se limita a dejarnos vagar y perdernos.\nM\u00e1s bien, busca a su oveja perdida.\n\u00c9l viene a nosotros y nos ofrece un camino de escape y rescate.\nMire nuevamente 2 Timoteo 2:25b-26:\n25b Quiz\u00e1s Dios les conceda que se arrepientan para conocer la verdad,\n26 y que recuperen la cordura y escapen del lazo del diablo, en que est\u00e1n cautivos para hacer su voluntad.\n\n\u00bfSab\u00edas que es posible sentirse completamente libre, cuando en realidad est\u00e1s atrapado por el pecado y el diablo?\nEl pecado se parece a la libertad, pero es lo opuesto.\nUna trampa se ve as\u00ed.\nEs una trampa que agarra a un animal que estaba corriendo libremente por un camino y de repente se encuentra en peligro.\nSatan\u00e1s coloca mentiras como se\u00f1ales en la carrera de marat\u00f3n, para enga\u00f1arnos y atraparnos.\nSatan\u00e1s quiere que corramos tras el placer, el poder, la popularidad, las posesiones y el orgullo.\nEstos \u00eddolos nos prometen libertad, y la libertad es lo que tanto deseamos.\nDesafortunadamente, creemos que estas cosas pueden ayudarnos a sentirnos satisfechos, seguros y felices.\nPero estos \u00eddolos son trampas que nos alejan de Dios y del camino de la vida verdadera.\nSatan\u00e1s quiere ocultarnos el camino de la vida, diciendo:\n\u201c\u00a1Ve por este camino hacia la victoria y la felicidad!\n\u00a1S\u00ed, ese es el camino! \u00a1S\u00edgueme!\n\nEntonces, \u00bfc\u00f3mo puede un animal escapar de una trampa como \u00e9sta?\n\u00bfEs algo que puede hacer por s\u00ed mismo?\nNo, el conejo est\u00e1 indefenso.\nNecesita que alguien m\u00e1s inteligente y m\u00e1s fuerte venga y lo saque de la trampa.\nTambi\u00e9n necesitamos que alguien m\u00e1s inteligente y m\u00e1s fuerte nos rescate.\n\u00c9se es el punto m\u00e1s importante que quiero que veas acerca de este vers\u00edculo.\nNecesitamos un Salvador porque no podemos salvarnos a nosotros mismos ni siquiera recurrir a Dios.\nLos corazones que est\u00e1n espiritualmente muertos no pueden elegir la vida.\nMira lo que dice el vers\u00edculo 25:\nQuiz\u00e1 Dios les conceda el arrepentimiento.\n\nUna subvenci\u00f3n es un regalo gratuito.\nDios me dio el don del arrepentimiento hace 30 a\u00f1os.\nDurante 10 a\u00f1os dije que no hab\u00eda Dios en el universo.\nPero porque Dios es bondadoso, me mostr\u00f3 que la cerveza, las mujeres y el \u00e9xito terrenal nunca podr\u00edan satisfacer los deseos de mi coraz\u00f3n.\nEso es lo que significa \u201crecuperar el sentido\u201d en el vers\u00edculo 26.\nCuando tu sentido de orientaci\u00f3n est\u00e1 confuso corres en la direcci\u00f3n equivocada.\nEl primer paso para encontrar el camino a casa es reconocer que est\u00e1s perdido.\nDan McDowell fue uno de los corredores perdidos en ese marat\u00f3n en Portland.\nDijo: \u201cDi la vuelta a la esquina y vi a 10 personas paradas sin moverse\u2026\nSe miraban el uno al otro y pensaban: \u201cEsto no se siente bien\u201d.\n\nOtro corredor, Zach Custer, dijo que entr\u00f3 en un t\u00fanel donde los autos pasaban a toda velocidad a 55 millas por hora.\nFue entonces cuando se dio cuenta de que se hab\u00eda desviado del rumbo.\nAntes de que Dios me hiciera entrar en raz\u00f3n, cre\u00eda que ten\u00eda \u201cconocimiento de la verdad\u201d.\nMi orgullo me dec\u00eda que estaba en el camino correcto y que no necesitaba ning\u00fan Dios que me guiara porque era muy inteligente.\nIr\u00f3nicamente, fui demasiado est\u00fapido para ver el enga\u00f1o de Satan\u00e1s.\nFui capturado en su trampa de mentiras.\nCre\u00ed en la promesa del diablo de que encontrar\u00eda la felicidad huyendo de Dios.\nPero luego, Dios me dio el don del arrepentimiento.\nLa palabra griega aqu\u00ed para arrepentimiento es metanoia.\nSignifica \u201cun cambio de mentalidad, un cambio de vida y un cambio de prop\u00f3sito\u201d.\nJes\u00fas me dio un coraz\u00f3n nuevo para poder \u201cinvocar al Se\u00f1or desde un coraz\u00f3n puro\u201d como dice el vers\u00edculo 22.\nUn coraz\u00f3n puro es un coraz\u00f3n honesto.\nUn coraz\u00f3n que clama a Dios: \u201cMe arrepiento de mi pecado, por favor perd\u00f3name\u201d.\nAy\u00fadame a correr hacia ti, no lejos de ti.\u201d\nPablo escribi\u00f3 en Romanos 10:9-11 una explicaci\u00f3n muy clara de c\u00f3mo puedes volverte hacia Dios y ser salvo.\n9 Si confiesas con tu boca que Jes\u00fas es el Se\u00f1or, y crees en tu coraz\u00f3n que Dios lo levant\u00f3 de los muertos, ser\u00e1s salvo.\n10 Porque con el coraz\u00f3n se cree para justicia, pero con la boca se confiesa para salvaci\u00f3n.\n11 Como dice la Escritura: \u00abTodo aquel que cree en \u00e9l, no ser\u00e1 avergonzado jam\u00e1s\u00bb.\n\n\u00bfHas profesado fe con tu boca, para poder ser salvo?\nSi a\u00fan no lo has hecho, \u00bfno crees que hoy ser\u00eda un gran d\u00eda para hacerlo?\nEl Esp\u00edritu Santo est\u00e1 aqu\u00ed entre nosotros, y tal vez est\u00e9 susurrando a tu coraz\u00f3n:\n\u201c\u00a1Ap\u00e1rtate del camino del pecado y de la muerte!\n\u201cElige una nueva vida y un nuevo rumbo, declarando: \u201c\u00a1Jes\u00fas es el Se\u00f1or!\u201d\n\nPablo escribi\u00f3 una vez antes sobre esa nueva direcci\u00f3n.\nFue en una carta a esta misma iglesia en \u00c9feso, donde Timoteo ahora sirve como pastor.\nEscuche lo que Pablo escribi\u00f3 a los creyentes cristianos en Efesios 2:1-5, acerca de lo que Dios hizo para darles nueva vida y una nueva direcci\u00f3n:\n1 Y estabais muertos en vuestros delitos y pecados,\n2 en los cuales anduvisteis en otro tiempo, siguiendo la corriente de este mundo, conforme al pr\u00edncipe de la potestad del aire, el esp\u00edritu que ahora opera en los hijos de desobediencia,\n3 entre los cuales tambi\u00e9n todos nosotros vivimos en otro tiempo en los deseos de nuestra carne, haciendo la voluntad de la carne y de los pensamientos, y \u00e9ramos por naturaleza hijos de ira, lo mismo que los dem\u00e1s.\n4 Pero Dios, que es rico en misericordia, por su gran amor por nosotros,\n5 aun estando nosotros muertos en pecados, nos dio vida juntamente con Cristo (\u00a1por gracia sois salvos!).\n\n\u201cPero Dios\u201d son dos de las palabras m\u00e1s hermosas jam\u00e1s pronunciadas.\nPablo recuerda a los creyentes de \u00c9feso que una vez estuvieron atrapados e indefensos como aquel conejo en la trampa.\nPero Dios intervino para salvarlos s\u00f3lo por gracia, s\u00f3lo por fe, s\u00f3lo en Cristo.\nCualquiera puede ser salvo, si cree que el sacrificio de Cristo en la cruz fue por usted, para lavarle del pecado y la verg\u00fcenza.\nCuando crees eso, recibes vida nueva y Jes\u00fas te pone en un nuevo camino.\nUnos vers\u00edculos m\u00e1s adelante en Efesios 2:8, Pablo habla de esa nueva direcci\u00f3n.\nLean esto junto conmigo:\nTODOS: 10 Porque somos hechura suya, creados en Cristo Jes\u00fas para buenas obras, las cuales Dios prepar\u00f3 de antemano para que anduvi\u00e9semos en ellas.\n\nPara finalizar este mensaje veamos c\u00f3mo es andar en buenas obras.\nRecuerde que Pablo le est\u00e1 escribiendo a Timoteo d\u00e1ndole orientaci\u00f3n sobre a qui\u00e9n seleccionar y capacitar como maestros de la Biblia.\nY nuestra misi\u00f3n como creyentes es compartir las Buenas Nuevas del evangelio con personas cercanas y lejanas.\nPero para hacer eso fielmente, debemos tener el car\u00e1cter que Pablo describe en estos vers\u00edculos.\nNo podemos cambiar el coraz\u00f3n de nadie.\nPero podemos decirles la verdad con gentileza, amabilidad y paciencia.\nY podemos confiar en que Dios conceder\u00e1 el arrepentimiento a sus hijos escogidos en el tiempo adecuado.\nEn los vers\u00edculos 24 y 25 del pasaje de hoy veo cinco cualidades que Dios quiere desarrollar en sus siervos:\n\nCualidad 1: No pendenciero.\nA algunas personas les gusta discutir.\nNo hay nada malo en un debate sano.\nPero \u00bfc\u00f3mo saber cu\u00e1ndo est\u00e1s siendo pecaminosamente \u201cpendenciero\u201d?\nQuiz\u00e1s puedas hacerte esta pregunta:\n\u201cCuando estoy discutiendo con alguien, \u00bfme importa m\u00e1s esa persona o ganar la discusi\u00f3n?\n\u00bfMi orgullo me hace centrarme en tener raz\u00f3n en lugar de ser amable?\n\nCualidad 2: Amable con todos.\nEl siervo del Se\u00f1or debe ser amable con todos.\nIncluso a las personas que te odian y quieren hacerte da\u00f1o.\nEs dif\u00edcil, lo s\u00e9.\nPensamos que la manera de protegernos de otras personas es ser fuertes, usar el poder.\nPero veamos lo que Pablo nos recuerda en Romanos 2:4, que:\n\u201cLa bondad de Dios tiene como objetivo llevarte al arrepentimiento\u201d.\n\u00bfQu\u00e9 tan bondadoso fue Jes\u00fas contigo, cuando estabas en pecado y hu\u00edas de \u00c9l?\nSu bondad te llev\u00f3 a arrepentirte,\nAs\u00ed que ahora tenemos la oportunidad de imitar a Cristo y ser amables con todos.\n\nCualidad 3: Soportar pacientemente el mal.\nCuando compartimos la verdad del evangelio, experimentaremos oposici\u00f3n de personas a quienes no les gusta lo que decimos.\n\u00bfRecuerdas c\u00f3mo respondi\u00f3 Esteban a las personas que lo mataron?\nHechos 7:59\u201360 dice:\n59 Y apedreaban a Esteban, mientras \u00e9l invocaba y dec\u00eda: Se\u00f1or Jes\u00fas, recibe mi esp\u00edritu.\n60 Y puesto de rodillas, clam\u00f3 a gran voz: Se\u00f1or, no les tomes en cuenta este pecado. \n\nS\u00f3lo Dios puede ayudarnos a soportar pacientemente el mal como lo hizo Esteban.\nPero \u00c9l nos ayudar\u00e1 cuando clamemos a \u00c9l en tiempos dif\u00edciles.\n\u00c9l nos ayudar\u00e1 a confiar en \u00c9l, sabiendo que nuestras almas est\u00e1n seguras en sus manos, sin importar lo que les pase a nuestros cuerpos.\n\nCualidad 4: Corregir con delicadeza.\nCorregir a la gente es dif\u00edcil.\nPero si mi hijo hace algo mal se lo digo porque lo amo.\nEsta es la pregunta importante que debemos tener en cuenta cuando tenemos que corregir a alguien:\n\u201c\u00bfMi hijo, mi amigo o mi c\u00f3nyuge siente mi amor?\n\u00bfO s\u00f3lo sienten mi ira?\n\nCuando corregimos con enojo o frustraci\u00f3n, estamos actuando como si Dios no pudiera cambiar a la otra persona.\nCreemos que podemos presionarles para que cambien o gritarles m\u00e1s fuerte hasta que encuentren el camino correcto.\nPero un maestro que sabe que Dios tiene el verdadero poder ser\u00e1 gentil, paciente y amable.\n\nCualidad 5: Capaz de ense\u00f1ar.\n\u00bfEntiendes la Palabra de Dios lo suficientemente bien como para explicarla a otros?\n\u00bfEst\u00e1s memorizando las Escrituras para tenerlas listas para guiarte en la vida y compartirlas con los dem\u00e1s?\nVamos a comenzar algo nuevo este mes.\nLes pediremos que memoricen un vers\u00edculo de las Escrituras antes de fin de mes.\nY si puedes recitarlo a uno de nuestros l\u00edderes, en cualquier idioma, recibir\u00e1s una pegatina.\nPuedes colocarlo en tu botella de agua o en tu cuaderno.\nEn cualquier lugar donde lo veas y contin\u00faes practic\u00e1ndolo todo el a\u00f1o.\nLeamos juntos el vers\u00edculo correspondiente al mes de marzo, 2 Timoteo 3:16.\nTODOS: \u201cToda la Escritura es inspirada por Dios y \u00fatil para ense\u00f1ar, para reprender, para corregir y para instruir en la justicia\u201d\n\nTodos necesitamos ayuda para seguir corriendo en la direcci\u00f3n correcta.\nNecesitamos la Palabra de Dios para ense\u00f1arnos, corregirnos y entrenarnos para caminar en justicia.\nY necesitamos que el Esp\u00edritu Santo nos ayude a entender y aplicar la Palabra, as\u00ed que dirijamos nuestros corazones al cielo ahora en oraci\u00f3n.\nJes\u00fas, s\u00f3lo podemos hablar con el Padre porque T\u00fa construiste un puente entre la tierra y el cielo.\nDestruiste las trampas del diablo y nos abriste los ojos a la verdad.\nPadre, gracias por darnos el don del arrepentimiento, para que podamos ser honestos con nosotros mismos y contigo acerca de nuestro pecado.\nY gracias, Esp\u00edritu Santo, por darnos la fe para recurrir a Jes\u00fas para nuestra salvaci\u00f3n.\nAbre nuestra mente y coraz\u00f3n para entender y aplicar la Palabra a nuestras vidas.\nAy\u00fadanos a correr con ah\u00ednco la carrera que tenemos por delante, invitando a otros a unirse a nosotros en el viaje hacia la plenitud, la esperanza y el cielo. Am\u00e9n.\n\nPreguntas para la meditaci\u00f3n y el debate\n1.  Lea 2 Timoteo 2:22 y Salmo 119:35-37.\na) \u00bfHacia cu\u00e1l de las \u201cpasiones juveniles\u201d (placer, poder, popularidad, posesiones, orgullo) sientes que tu coraz\u00f3n se dirige naturalmente cuando est\u00e1s estresado o buscas consuelo?\n\n2.  Lea Efesios 2:1-5 y Ezequiel 36:26.\na) \u00bfQu\u00e9 es necesario para pasar de estar \u201cmuerto\u201d a estar \u201cvivo\u201d?\nb) \u00bfCreer que el arrepentimiento es un don de la gracia le ayuda a ser m\u00e1s honesto con Dios acerca de su pecado?\n\n3.  Lea 2 Timoteo 2:23-25a y Colosenses 3:12-14.\na) \u00bfCu\u00e1les son las cualidades del \u201csiervo del Se\u00f1or\u201d al debatir o corregir a otros?\nb) Porque Jes\u00fas nos am\u00f3 con gran paciencia y mansedumbre, \u00bfa qui\u00e9n en tu vida amar\u00e1s con esa misma gracia, incluso si no est\u00e1n de acuerdo contigo o no le agradas?\n\n4.  Lea Romanos 10:9-11 y Hebreos 12:1-2.\na) \u00bfC\u00f3mo el fijar nuestros ojos en Jes\u00fas nos ayuda a alejarnos del pecado y correr en una nueva direcci\u00f3n?\nb) Recuerda memorizar 2 Timoteo 3:16. \u00bfC\u00f3mo nos ayuda el conocer la Palabra de Dios a correr la marat\u00f3n de la fe?","turkish_content":"Nereye ko\u015fuyorsunuz?\n2 Timoteos 2:22-26\nRahip Chris Sicks\n15 Mart 2026\n\n2019\u2019da Portland, Oregon\u2019da d\u00fczenlenen maratonda, en iyi ko\u015fuculardan baz\u0131lar\u0131 yar\u0131\u015f\u0131 kaybetti.\nYava\u015f olduklar\u0131 i\u00e7in de\u011fil, yanl\u0131\u015f y\u00f6ne gittikleri i\u00e7in.\nParkurda belirgin bir \u015fekilde i\u015faretlenmemi\u015f bir viraj vard\u0131.\nYani en h\u0131zl\u0131 ko\u015fuculardan yakla\u015f\u0131k 20\u2019si bir milden fazla mesafeyi ters y\u00f6nde ko\u015ftu!\nBu hata, aylarca haz\u0131rland\u0131klar\u0131 yar\u0131\u015fa de\u011ferli dakikalar ekledi.\nO erkekler ve kad\u0131nlar \u00e7ok h\u0131zl\u0131 ve gayretli bir \u015fekilde ko\u015ftular.\nAma yanl\u0131\u015f yolda olduklar\u0131 i\u00e7in yar\u0131\u015f\u0131 kaybettiler.\nBu ak\u015fam 2. Timoteos kitab\u0131ndaki vaaz serisine devam ediyoruz.\nEl\u00e7i Pavlus, Efes\u2019teki Hristiyan kilisesinin gen\u00e7 past\u00f6r\u00fc Timoteos\u2019a yaz\u0131yor.\nPaul, Timoteos\u2019a ve bug\u00fcn bizlere do\u011fru yolda kalman\u0131n yollar\u0131 hakk\u0131nda tavsiyelerde bulunuyor.\n2 Timoteos 2:22-26\n22 \u201c\u00d6yleyse gen\u00e7lik heveslerinden uzak durun ve Rabbe temiz bir y\u00fcrekle dua edenlerle birlikte do\u011fruluk, iman, sevgi ve bar\u0131\u015f\u0131 aray\u0131n.\n23. Ak\u0131ls\u0131zca, bilgisizce tart\u0131\u015fmalara kar\u0131\u015fmay\u0131n; \u00e7\u00fcnk\u00fc biliyorsunuz ki bunlar kavgalara yol a\u00e7ar.\n24 Rabbin hizmetk\u00e2r\u0131 kavgac\u0131 olmamal\u0131, herkese kar\u015f\u0131 nazik olmal\u0131, \u00f6\u011fretme yetene\u011fine sahip olmal\u0131 ve k\u00f6t\u00fcl\u00fc\u011fe sab\u0131rla katlanmal\u0131d\u0131r.\n25. Rakiplerini nazik\u00e7e d\u00fczeltiyor.\nBelki de Tanr\u0131 onlara t\u00f6vbe etme ve ger\u00e7e\u011fi bilme f\u0131rsat\u0131 verecektir.\n26 Ve belki de ak\u0131llar\u0131 ba\u015flar\u0131na gelir ve \u015feytan\u0131n tuza\u011f\u0131ndan kurtulurlar; \u00e7\u00fcnk\u00fc \u015feytan onlar\u0131 kendi iste\u011fini yerine getirmek i\u00e7in esir alm\u0131\u015ft\u0131.\u201d\n\n\u0130\u015faya 40:8\u2019i birlikte okuyal\u0131m:\n\u201d\u00c7im kurur, \u00e7i\u00e7ek solar, ama Tanr\u0131m\u0131z\u0131n s\u00f6z\u00fc sonsuza dek kalacakt\u0131r.\u201d\n\n22. ayet \u015f\u00f6yle diyor:\n22 \u201d\u00d6yleyse gen\u00e7lik heveslerinden uzak durun ve Rabbe temiz bir y\u00fcrekle dua edenlerle birlikte do\u011fruluk, iman, sevgi ve bar\u0131\u015f\u0131 aray\u0131n.\u201d\n\nBu ayet asl\u0131nda bug\u00fcnk\u00fc vaaz\u0131n bir \u00f6zeti niteli\u011finde.\nBunu Tanr\u0131\u2018n\u0131n S\u00f6z\u00fc\u2018nde s\u0131k s\u0131k g\u00f6r\u00fcyoruz.\nBazen bir mezmurun veya bir paragraf\u0131n ilk c\u00fcmlesi bir \u00f6zet niteli\u011finde olur.\nArd\u0131ndan gelen s\u00f6zler, mezmurun tamam\u0131n\u0131n, paragraf\u0131n veya b\u00f6l\u00fcm\u00fcn a\u00e7\u0131klamas\u0131d\u0131r.\nOlgun bir Hristiyan erkek veya kad\u0131n, gen\u00e7ken bizi ayartan \u015feylerden uzakla\u015fan ki\u015fidir.\nOlgun bir insan, \u201cgen\u00e7lik tutkular\u0131\u201d yerine, do\u011fruluk, iman, sevgi ve bar\u0131\u015f gibi Tanr\u0131\u2018n\u0131n de\u011ferlerini takip etmeyi \u00f6\u011frenir.\nPaul gen\u00e7ken ad\u0131 Saul\u2019du.\nSaul, gurur ve \u00f6zg\u00fcven dolu bir adamd\u0131; g\u00fcc\u00fcn\u00fc kullanarak Hristiyanlara zulmetti ve onlar\u0131 hapse att\u0131.\nSaul pop\u00fcler ve ba\u015far\u0131l\u0131 olmak istiyordu ve kendi gururu y\u00fcz\u00fcnden ba\u015fkalar\u0131na zarar vermeye raz\u0131yd\u0131.\nAncak 2 Timoteos mektubu, olgun bir imanl\u0131 olan Pavlus taraf\u0131ndan yaz\u0131lm\u0131\u015ft\u0131r.\nGen\u00e7lik heveslerinin ne kadar zarar verdi\u011finin fark\u0131nda ve Timothy\u2019yi bu konuda uyar\u0131yor.\nPavlus bu mektubu yazd\u0131\u011f\u0131 s\u0131rada Timoteos muhtemelen 40 ya\u015flar\u0131ndayd\u0131.\nAma \u201cgen\u00e7lik tutkular\u0131n\u0131n\u201d pe\u015finden ko\u015fmak i\u00e7in gen\u00e7 olman\u0131za gerek yok.\n57 ya\u015f\u0131nday\u0131m ama gen\u00e7lik tutkular\u0131ndan s\u00fcrekli olarak uzak durmay\u0131 \u00f6\u011frenmeye devam ediyorum.\n\u00dcniversiteden benimle ayn\u0131 ya\u015fta bir arkada\u015f\u0131m var.\nAma o h\u00e2l\u00e2 35 y\u0131l \u00f6nceki gibi ya\u015f\u0131yor.\nHayat\u0131, \u00fcniversite y\u0131llar\u0131m\u0131z\u0131n gen\u00e7lik tutkular\u0131 taraf\u0131ndan \u015fekillendiriliyor.\n\u0130\u015fte bir\u00e7o\u011fumuzun ya\u015fad\u0131\u011f\u0131 gen\u00e7lik tutkular\u0131ndan baz\u0131lar\u0131:\n\n*   Haz: Cinsel g\u00fcnah, haz g\u00fcnah\u0131n\u0131n yayg\u0131n bir \u00f6rne\u011fidir, ancak tek \u00f6rne\u011fi de\u011fildir.\nDi\u011fer g\u00fcnah say\u0131lan zevkler aras\u0131nda alkol, yemek ve bir\u00e7ok e\u011flence t\u00fcr\u00fc say\u0131labilir.\nDo\u011fru kullan\u0131ld\u0131klar\u0131 takdirde bunlar k\u00f6t\u00fc \u015feyler de\u011fildir.\n\u00d6rne\u011fin, Hristiyan evlili\u011fi ba\u011flam\u0131nda seks g\u00fczel bir hediyedir.\nAma herhangi bir \u015feyi yanl\u0131\u015f kulland\u0131\u011f\u0131m\u0131zda, ona hayat\u0131m\u0131z \u00fczerinde g\u00fc\u00e7 vermi\u015f oluruz.\nTanr\u0131\u2018n\u0131n bize verdi\u011fi herhangi bir hediyeyi kalbimizdeki bo\u015flu\u011fu doldurmak i\u00e7in kulland\u0131\u011f\u0131m\u0131zda, o \u015fey sahte bir tanr\u0131ya, bir puta d\u00f6n\u00fc\u015f\u00fcr.\n\n*   G\u00fc\u00e7: Gen\u00e7ken bazen kendimizi g\u00fc\u00e7s\u00fcz, zay\u0131f veya yetersiz hissederiz.\nErgenlik d\u00f6nemimde bu duygularla m\u00fccadele ettim.\nBaz\u0131 insanlar g\u00fc\u00e7s\u00fczl\u00fck duygular\u0131n\u0131 \u00f6rtbas etmek i\u00e7in iktidar\u0131n pe\u015fine d\u00fc\u015ferler.\nG\u00fc\u00e7l\u00fc davranman\u0131n kendilerini g\u00fcvende hissetmelerine yard\u0131mc\u0131 olaca\u011f\u0131n\u0131 d\u00fc\u015f\u00fcn\u00fcyorlar.\nZorbalar\u0131n asl\u0131nda g\u00f6r\u00fcnd\u00fckleri kadar sert olmad\u0131klar\u0131n\u0131 biliyor muydunuz?\nZorba genellikle hayat\u0131nda bir konuda g\u00fc\u00e7s\u00fcz hisseden ve bu y\u00fczden kendini g\u00fc\u00e7l\u00fc hissetmek i\u00e7in ba\u015fkalar\u0131na zarar veren ki\u015fidir.\n\n*   Pop\u00fclerlik: Bu da hayat\u0131mda kar\u015f\u0131la\u015ft\u0131\u011f\u0131m g\u00fc\u00e7l\u00fc bir cazibe unsuru oldu.\n\u0130nsanlar\u0131n beni sevip sevmedi\u011finden s\u0131k s\u0131k endi\u015feleniyorum.\nBa\u015fkalar\u0131n\u0131n g\u00f6r\u00fc\u015flerine \u00e7ok fazla \u00f6nem veriyorum.\nPeki ya sen?\n\u0130nsanlar\u0131n sizi sevmesi i\u00e7in davran\u0131\u015flar\u0131n\u0131z\u0131 veya g\u00f6r\u00fcn\u00fc\u015f\u00fcn\u00fcz\u00fc de\u011fi\u015ftirdi\u011finiz oluyor mu hi\u00e7?\nReddedilmemek i\u00e7in belirli bir \u015fekilde davranman\u0131z veya g\u00f6r\u00fcnmeniz gerekti\u011fini d\u00fc\u015f\u00fcn\u00fcyor musunuz?\n\n*   Maddi Varl\u0131klar: Para ve maddi varl\u0131klara duyulan sevgi \u00e7o\u011fumuz i\u00e7in bir sorundur.\nDaha fazla e\u015fyaya sahip olman\u0131n getirdi\u011fi g\u00fcvenlik ve rahatl\u0131\u011f\u0131 istiyoruz.\nBu, inan\u00e7s\u0131zl\u0131\u011f\u0131 ortaya koyuyor.\nTanr\u0131, O\u2019nun bizim s\u0131\u011f\u0131na\u011f\u0131m\u0131z ve kalemiz oldu\u011funu, O\u2019nun bizim r\u0131z\u0131k vericimiz oldu\u011funu anlamam\u0131z\u0131 istiyor.\nMaddi \u015feyler mutluluk vaat eder, ancak asla bu vaatlerini yerine getiremezler.\n\u00c7\u00fcnk\u00fc kalplerimiz her zaman daha fazlas\u0131n\u0131 isteyecektir.\n\n*   Gurur: Bu, asl\u0131nda her g\u00fcnah\u0131n alt\u0131nda yatan g\u00fcnaht\u0131r.\nGurur, sahip olduklar\u0131ma, g\u00fcce, zevke ve pop\u00fclerli\u011fe ger\u00e7ekten lay\u0131k oldu\u011fuma dair inan\u00e7t\u0131r.\nNeden mi? \u00c7\u00fcnk\u00fc ben \u00f6zelim.\nGurur bize yalanlar f\u0131s\u0131ldar, \u015f\u00f6yle der:\n\u201cSorun yok, bunu yapabilirsin, bunu hak ediyorsun.\u201d\nReklamc\u0131lar da bize ayn\u0131 \u015feyi s\u00f6yl\u00fcyor.\n\u201cBunu hak ediyorsun... Hadi, al.\u201d\nBelki biraz daha al\u0131rs\u0131n, sorun de\u011fil.\u201d\nBu y\u00fczden bu t\u00fcr reklamlar\u0131 \u00e7ok g\u00f6r\u00fcyoruz, \u00e7\u00fcnk\u00fc gururumuz asl\u0131nda bunlara inanmam\u0131z\u0131 istiyor.\n\nArkada\u015flar, size bir soru sormak istiyorum.\nBu be\u015f \u015feyden hangisi size tan\u0131d\u0131k geliyor?\nGurur, mal m\u00fclk, g\u00fc\u00e7, zevk veya pop\u00fclerlik mi pe\u015findesiniz?\nYoksa sizi Tanr\u0131\u2018dan uzakla\u015ft\u0131ran ba\u015fka bir \u015fey mi var?\nBug\u00fcn kalbiniz nerede ve nereye gidiyorsunuz?\nAdem meyveyi yedikten sonra Tanr\u0131\u2018n\u0131n ona bah\u00e7ede ne sordu\u011funu hat\u0131rl\u0131yor musun?\n\u00c2dem ve Havva saklan\u0131yorlard\u0131 ve Tanr\u0131, \u201cNeredesin \u00c2dem?\u201d diye sordu.\nTanr\u0131 bug\u00fcn yery\u00fcz\u00fcndeki herkesten ayn\u0131 \u015feyi istiyor.\nNeredesin?\nO, sizin fiziksel olarak nerede oldu\u011funuzu sormuyor.\n\u201cKalbiniz nerede?\u201d diye soruyor.\n\u00c7\u00fcnk\u00fc kalplerimiz, bizi en \u00e7ok de\u011fer verdi\u011fimiz \u015feye do\u011fru g\u00f6t\u00fcren bir pusula gibidir.\nG\u00fcnah sinsi oldu\u011fu i\u00e7in kendimizi kaybederiz ve bunun fark\u0131na bile varmay\u0131z.\n\u0130\u00e7imizde olup bitenleri g\u00f6rebilmek i\u00e7in Tanr\u0131\u2018n\u0131n yard\u0131m\u0131na ihtiyac\u0131m\u0131z var.\nGelin, Mezmur 139:23-24 ayetlerini birlikte, bir dua gibi okuyal\u0131m:\nT\u00dcM\u00dc: 23 \u201cEy Tanr\u0131m, beni ara\u015ft\u0131r ve kalbimi bil!\u201d\nBeni s\u0131nay\u0131n ve d\u00fc\u015f\u00fcncelerimi \u00f6\u011frenin!\n24 Ve i\u00e7imde k\u00f6t\u00fc bir e\u011filim olup olmad\u0131\u011f\u0131n\u0131 g\u00f6r,\nve beni sonsuzlu\u011fa g\u00f6t\u00fcrecek yola y\u00f6nlendir!\n\nTanr\u0131\u2018n\u0131n yard\u0131m\u0131 olmadan, \u201csonsuzlu\u011fa giden yolda\u201d y\u00fcr\u00fcyemeyiz.\nYanl\u0131\u015f y\u00f6ne do\u011fru ko\u015faca\u011f\u0131z, bizi Tanr\u0131\u2018n\u0131n kalbinden uzakla\u015ft\u0131ran \u015feylerin pe\u015finden gidece\u011fiz.\nAma Tanr\u0131 o kadar iyidir ki, bizim yoldan sap\u0131p kaybolmam\u0131z\u0131 \u00f6ylece izlemez.\nBunun yerine, kay\u0131p koyunlar\u0131n\u0131 aramaya koyulur.\nO bize geliyor ve bir ka\u00e7\u0131\u015f ve kurtulu\u015f yolu sunuyor.\n2 Timoteos 2:25b-26 ayetlerine tekrar bak\u0131n:\n25b \u201cBelki de Tanr\u0131 onlara t\u00f6vbe etme ve ger\u00e7e\u011fi \u00f6\u011frenme f\u0131rsat\u0131 verir,\n26 Ve belki de ak\u0131llar\u0131 ba\u015flar\u0131na gelir ve \u015feytan\u0131n tuza\u011f\u0131ndan kurtulurlar; \u00e7\u00fcnk\u00fc \u015feytan onlar\u0131 kendi iste\u011fini yerine getirmek i\u00e7in esir alm\u0131\u015ft\u0131.\u201d\n\nG\u00fcnah ve \u015feytan\u0131n tuza\u011f\u0131na d\u00fc\u015fm\u00fc\u015fken bile tamamen \u00f6zg\u00fcr hissetmenin m\u00fcmk\u00fcn oldu\u011funu biliyor muydunuz?\nG\u00fcnah, \u00f6zg\u00fcrl\u00fck gibi hissettirir, ama tam tersidir.\nTuzak \u015f\u00f6yle g\u00f6r\u00fcn\u00fcr.\nBu, bir patikada \u00f6zg\u00fcrce ko\u015fan ve aniden tehlikeye d\u00fc\u015fen bir hayvan\u0131 yakalayan bir tuzakt\u0131r.\n\u015eeytan, bizi aldatmak ve tuza\u011fa d\u00fc\u015f\u00fcrmek i\u00e7in yalanlar\u0131 maraton parkuruna i\u015faretler gibi yerle\u015ftirir.\n\u015eeytan, bizleri zevk, g\u00fc\u00e7, pop\u00fclerlik, mal m\u00fclk ve gururun pe\u015finden ko\u015fmaya y\u00f6nlendirmek istiyor.\nBu putlar bize \u00f6zg\u00fcrl\u00fck vaat ediyor ve biz de \u00e7ok \u00f6zg\u00fcrl\u00fck istiyoruz.\nMaalesef, bu t\u00fcr \u015feylerin bize tatmin, g\u00fcvenlik ve mutluluk hissi verebilece\u011fine inan\u0131yoruz.\nAncak bu putlar, bizi Tanr\u0131\u2018dan ve ger\u00e7ek ya\u015fam yolundan uzak tutan tuzaklard\u0131r.\n\u015eeytan, bize hayat yolunu gizlemek istiyor ve \u015f\u00f6yle diyor:\n\u201cZafer ve mutlulu\u011fa giden yol budur!\u201d\nEvet, do\u011fru yol! Beni takip edin!\n\nPeki, bir hayvan b\u00f6yle bir tuzaktan nas\u0131l kurtulabilir?\nBunu kendi ba\u015f\u0131na yapabilir mi?\nHay\u0131r, tav\u015fan \u00e7aresiz.\nOnu bu tuzaktan kurtarmak i\u00e7in daha zeki ve daha g\u00fc\u00e7l\u00fc birine ihtiyac\u0131 var.\nBizi kurtarmak i\u00e7in daha zeki ve daha g\u00fc\u00e7l\u00fc birine de ihtiyac\u0131m\u0131z var.\nBu ayetle ilgili olarak g\u00f6rmenizi istedi\u011fim en \u00f6nemli nokta bu.\nBir Kurtar\u0131c\u0131ya ihtiyac\u0131m\u0131z var \u00e7\u00fcnk\u00fc kendimizi kurtaram\u0131yoruz, hatta Tanr\u0131\u2018ya bile y\u00f6nelemiyoruz.\nManevi olarak \u00f6l\u00fc olan kalpler hayat\u0131 se\u00e7emez.\n25. ayette ne yazd\u0131\u011f\u0131na bak\u0131n:\n\u201cBelki de Tanr\u0131 onlara t\u00f6vbe etme f\u0131rsat\u0131 verir.\u201d\n\nHibe, kar\u015f\u0131l\u0131ks\u0131z bir hediyedir.\nTanr\u0131 bana 30 y\u0131l \u00f6nce t\u00f6vbe etme yetene\u011fini verdi.\n10 y\u0131l boyunca evrende Tanr\u0131 olmad\u0131\u011f\u0131n\u0131 s\u00f6yledim.\nFakat Tanr\u0131 merhametli oldu\u011fu i\u00e7in bana biran\u0131n, kad\u0131nlar\u0131n ve d\u00fcnyevi ba\u015far\u0131lar\u0131n kalbimin arzular\u0131n\u0131 asla tatmin edemeyece\u011fini g\u00f6sterdi.\n26. ayette ge\u00e7en \u201cak\u0131llar\u0131n\u0131 ba\u015flar\u0131na toplamalar\u0131\u201d i\u015fte bunu ifade ediyor.\nY\u00f6n duygunuz kar\u0131\u015f\u0131rsa yanl\u0131\u015f y\u00f6ne ko\u015fars\u0131n\u0131z.\nEve d\u00f6n\u00fc\u015f yolunu bulman\u0131n ilk ad\u0131m\u0131, kayboldu\u011funuzu fark etmektir.\nDan McDowell, Portland\u2019daki o maratonda kaybolan ko\u015fuculardan biriydi.\n\u015e\u00f6yle dedi: \u201cK\u00f6\u015feyi d\u00f6nd\u00fc\u011f\u00fcmde 10 ki\u015finin \u00f6ylece durdu\u011funu g\u00f6rd\u00fcm...\u201d\nBirbirlerine bak\u0131p \u2018Bu hi\u00e7 do\u011fru gelmiyor\u2019 diye d\u00fc\u015f\u00fcn\u00fcyorlard\u0131.\n\nBir di\u011fer ko\u015fucu Zach Custer, arabalar\u0131n saatte 55 mil h\u0131zla yan\u0131ndan ge\u00e7ti\u011fi bir t\u00fcnele girdi\u011fini s\u00f6yledi.\nO zaman rotas\u0131ndan sapt\u0131\u011f\u0131n\u0131 fark etti.\nTanr\u0131 beni akl\u0131m\u0131 ba\u015f\u0131ma getirmeden \u00f6nce \u201chakikat bilgisine\u201d sahip oldu\u011fumu san\u0131yordum.\nGururum bana do\u011fru yolda oldu\u011fumu ve \u00e7ok zeki oldu\u011fum i\u00e7in beni y\u00f6nlendirecek bir Tanr\u0131\u2018ya ihtiyac\u0131m olmad\u0131\u011f\u0131n\u0131 s\u00f6yl\u00fcyordu.\n\u0130ronik bir \u015fekilde, \u015eeytan\u2019\u0131n aldatmacas\u0131n\u0131 g\u00f6remeyecek kadar aptald\u0131m.\nOnun yalan tuza\u011f\u0131na d\u00fc\u015ft\u00fcm.\n\u015eeytan\u0131n, Tanr\u0131\u2018dan ka\u00e7arak mutlulu\u011fu bulaca\u011f\u0131ma dair vaadine inand\u0131m.\nAma sonra Tanr\u0131 bana t\u00f6vbe etme arma\u011fan\u0131n\u0131 verdi.\nBurada t\u00f6vbe i\u00e7in kullan\u0131lan Yunanca kelime metanoia\u2019d\u0131r.\nBu, \u201czihin de\u011fi\u015fikli\u011fi, ya\u015fam de\u011fi\u015fikli\u011fi ve ama\u00e7 de\u011fi\u015fikli\u011fi\u201d anlam\u0131na gelir.\n\u0130sa bana yeni bir kalp verdi, b\u00f6ylece 22. ayette s\u00f6ylendi\u011fi gibi \u201csaf bir y\u00fcrekle Rabbe dua edebileyim\u201d.\nSaf bir kalp, d\u00fcr\u00fcst bir kalptir.\nTanr\u0131\u2018ya \u015f\u00f6yle seslenen bir kalp: \u201cG\u00fcnah\u0131m i\u00e7in \u00f6z\u00fcr dilerim, l\u00fctfen beni ba\u011f\u0131\u015fla.\u201d\n\u201cBana senden uzakla\u015fmak yerine sana do\u011fru ko\u015fmamda yard\u0131mc\u0131 ol.\u201d\nPavlus, Romal\u0131lar 10:9-11\u2019de Tanr\u0131\u2018ya nas\u0131l y\u00f6nelebilece\u011finizi ve kurtulabilece\u011finizi \u00e7ok a\u00e7\u0131k bir \u015fekilde a\u00e7\u0131klam\u0131\u015ft\u0131r.\n9 \u201cA\u011fz\u0131n\u0131zla, \u2018\u0130sa Rabdir\u2019 diye ilan eder ve y\u00fcre\u011finizde Tanr\u0131\u2019n\u0131n onu \u00f6l\u00fcmden diriltti\u011fine inan\u0131rsan\u0131z, kurtulacaks\u0131n\u0131z.\n10 \u00c7\u00fcnk\u00fc iman\u0131n\u0131zla inan\u0131p aklan\u0131rs\u0131n\u0131z, a\u011fz\u0131n\u0131zla da iman\u0131n\u0131z\u0131 ikrar edip kurtulursunuz.\n11 Kutsal Yaz\u0131lar \u015f\u00f6yle der: \u201cOna iman eden hi\u00e7 kimse utand\u0131r\u0131lmayacakt\u0131r.\u201d\n\nKurtulu\u015fa ermek i\u00e7in a\u011fz\u0131nla iman\u0131n\u0131 ikrar ettin mi?\nHen\u00fcz yapmad\u0131ysan\u0131z, bug\u00fcn bunu yapmak i\u00e7in harika bir g\u00fcn olmaz m\u0131yd\u0131?\nKutsal Ruh aram\u0131zda bulunuyor ve belki de kalbinize f\u0131s\u0131ld\u0131yor:\n\u201cG\u00fcnah ve \u00f6l\u00fcm yolundan d\u00f6n\u00fcn!\u201d\n\u201d\u0130sa Rab\u2019dir!\u201d diyerek yeni bir hayat ve yeni bir y\u00f6n se\u00e7in.\n\nPaul daha \u00f6nce de bu yeni y\u00f6nelim hakk\u0131nda yazm\u0131\u015ft\u0131.\nBu, Timoteos\u2019un \u015fu anda papazl\u0131k yapt\u0131\u011f\u0131 Efes\u2019teki ayn\u0131 kiliseye yazd\u0131\u011f\u0131 bir mektupta yer al\u0131yordu.\nPavlus\u2019un Efesliler 2:1-5\u2019te Hristiyan imanl\u0131lara yazd\u0131klar\u0131n\u0131, Tanr\u0131\u2018n\u0131n onlara yeni bir hayat ve yeni bir y\u00f6n vermek i\u00e7in neler yapt\u0131\u011f\u0131n\u0131 dinleyin:\n1 \u201cVe sizler su\u00e7lar\u0131n\u0131z ve g\u00fcnahlar\u0131n\u0131z y\u00fcz\u00fcnden \u00f6l\u00fcyd\u00fcn\u00fcz.\u201d\n2 Bir zamanlar bu d\u00fcnyan\u0131n ak\u0131\u015f\u0131n\u0131 izleyerek, havan\u0131n g\u00fcc\u00fcn\u00fcn prensini, \u015fimdi itaatsizlerin o\u011fullar\u0131nda i\u015f ba\u015f\u0131nda olan ruhu izleyerek y\u00fcr\u00fcd\u00fc\u011f\u00fcn\u00fcz yerdeydiniz--\n3 Bizler de bir zamanlar bedenimizin ve akl\u0131m\u0131z\u0131n arzular\u0131n\u0131 yerine getirerek, nefsimizin tutkular\u0131na kap\u0131lm\u0131\u015f, do\u011fam\u0131z gere\u011fi insanl\u0131\u011f\u0131n geri kalan\u0131 gibi gazab\u0131n \u00e7ocuklar\u0131yd\u0131k.\n4 Fakat Tanr\u0131, merhameti bol oldu\u011fundan ve bizi \u00e7ok sevdi\u011finden,\n5 Biz g\u00fcnahlar\u0131m\u0131z y\u00fcz\u00fcnden \u00f6l\u00fc iken, O bizi Mesih\u2019le birlikte diriltti; l\u00fctuf sayesinde kurtuldunuz!\n\n\u201cAma Tanr\u0131m\u201d s\u00f6zleri, \u015fimdiye kadar s\u00f6ylenmi\u015f en g\u00fczel s\u00f6zlerden ikisidir.\nPavlus, Efes\u2019teki imanl\u0131lara bir zamanlar t\u0131pk\u0131 o kapana k\u0131s\u0131lm\u0131\u015f tav\u015fan gibi \u00e7aresiz ve tuza\u011fa d\u00fc\u015fm\u00fc\u015f olduklar\u0131n\u0131 hat\u0131rlat\u0131r.\nFakat Tanr\u0131, yaln\u0131zca l\u00fctfuyla, yaln\u0131zca iman yoluyla, yaln\u0131zca Mesih arac\u0131l\u0131\u011f\u0131yla onlar\u0131 kurtarmak i\u00e7in devreye girdi.\nE\u011fer Mesih\u2019in \u00e7arm\u0131htaki kurban\u0131n\u0131n sizin i\u00e7in, sizi g\u00fcnah ve utan\u00e7tan ar\u0131nd\u0131rmak i\u00e7in oldu\u011funa inan\u0131yorsan\u0131z, herkes kurtulabilir.\nBuna inand\u0131\u011f\u0131n\u0131zda yeni bir hayat kazan\u0131rs\u0131n\u0131z ve \u0130sa sizi yeni bir yola y\u00f6nlendirir.\nEfesliler 2:8\u2019de, birka\u00e7 ayet sonra Pavlus bu yeni y\u00f6nelimden bahsediyor.\nBunu birlikte okuyal\u0131m:\nHEPS\u0130: 10 \u201c\u00c7\u00fcnk\u00fc biz O\u2019nun eseriyiz, iyi i\u015fler yapmak \u00fczere Mesih \u0130sa\u2019da yarat\u0131ld\u0131k; bu i\u015fleri Tanr\u0131 \u00f6nceden haz\u0131rlad\u0131 ki, biz de onlarda y\u00fcr\u00fcyelim.\u201d\n\nBu mesaj\u0131 sonland\u0131r\u0131rken, iyilik yapman\u0131n ne anlama geldi\u011fine bir bakal\u0131m.\nUnutmay\u0131n ki Pavlus, Timoteos\u2019a kimleri \u0130ncil \u00f6\u011fretmeni olarak se\u00e7ip e\u011fitmesi gerekti\u011fi konusunda rehberlik etmek i\u00e7in yaz\u0131yor.\nBiz inananlar olarak g\u00f6revimiz, hem yak\u0131n\u0131m\u0131zdaki hem de uzaktaki insanlarla \u0130ncil\u2019in m\u00fcjdesini payla\u015fmakt\u0131r.\nAncak bunu sadakatle yapabilmek i\u00e7in, Pavlus\u2019un bu ayetlerde tarif etti\u011fi karaktere sahip olmal\u0131y\u0131z.\nKimsenin kalbini de\u011fi\u015ftiremeyiz.\nAma onlara ger\u00e7e\u011fi nazik\u00e7e, kibarca ve sab\u0131rla anlatabiliriz.\nVe Tanr\u0131\u2018n\u0131n, se\u00e7ilmi\u015f \u00e7ocuklar\u0131na uygun zamanda t\u00f6vbe etme f\u0131rsat\u0131 verece\u011fine g\u00fcvenebiliriz.\nBug\u00fcnk\u00fc ayetlerin 24. ve 25. k\u0131s\u0131mlar\u0131nda Tanr\u0131\u2018n\u0131n kullar\u0131nda geli\u015ftirmek istedi\u011fi be\u015f niteli\u011fi g\u00f6r\u00fcyorum:\n\nNitelik 1: Kavgac\u0131 de\u011fil.\nBaz\u0131 insanlar tart\u0131\u015fmay\u0131 sever.\nSa\u011fl\u0131kl\u0131 tart\u0131\u015fman\u0131n hi\u00e7bir sak\u0131ncas\u0131 yok.\nPeki, ne zaman g\u00fcnahk\u00e2r derecede \u201ckavgac\u0131\u201d davrand\u0131\u011f\u0131n\u0131z\u0131 nas\u0131l anlars\u0131n\u0131z?\nBelki kendinize \u015fu soruyu sorabilirsiniz:\n\u201cBirisiyle tart\u0131\u015f\u0131rken, o ki\u015fiyi mi daha \u00e7ok \u00f6nemsiyorum, yoksa tart\u0131\u015fmay\u0131 kazanmay\u0131 m\u0131?\u201d\n\u201cAcaba gururum, nazik olmak yerine hakl\u0131 olmaya odaklanmama m\u0131 neden oluyor?\u201d\n\nNitelik 2: Herkese kar\u015f\u0131 nazik.\nRabbin hizmetk\u00e2r\u0131 herkese kar\u015f\u0131 nazik olmal\u0131d\u0131r.\nSenden nefret eden ve sana zarar vermek isteyen insanlara bile.\nZor oldu\u011funu biliyorum.\nBizce kendimizi ba\u015fkalar\u0131ndan koruman\u0131n yolu g\u00fc\u00e7l\u00fc olmak, g\u00fc\u00e7 kullanmakt\u0131r.\nFakat Pavlus\u2019un Romal\u0131lar 2:4\u2019te bize hat\u0131rlatt\u0131\u011f\u0131 \u015feye bak\u0131n:\n\u201cTanr\u0131\u2019n\u0131n iyili\u011fi sizi t\u00f6vbeye y\u00f6nlendirmek i\u00e7indir.\u201d\nSiz g\u00fcnah i\u00e7indeyken ve ondan uzakla\u015f\u0131rken, \u0130sa size ne kadar da iyilik g\u00f6sterdi.\nOnun iyili\u011fi sizi t\u00f6vbeye sevk etti.\n\u015eimdi \u0130sa\u2019y\u0131 \u00f6rnek al\u0131p herkese kar\u015f\u0131 nazik olma f\u0131rsat\u0131n\u0131z var.\n\nNitelik 3: K\u00f6t\u00fcl\u00fc\u011fe sab\u0131rla katlanmak.\n\u0130ncilin ger\u00e7e\u011fini payla\u015ft\u0131\u011f\u0131m\u0131zda, s\u00f6ylediklerimizi be\u011fenmeyen insanlardan muhalefetle kar\u015f\u0131la\u015faca\u011f\u0131z.\nStephen\u2019\u0131n kendisini \u00f6ld\u00fcrenlere nas\u0131l cevap verdi\u011fini hat\u0131rl\u0131yor musunuz?\nEl\u00e7ilerin \u0130\u015fleri 7:59-60 \u015f\u00f6yle der:\n59 Onu ta\u015flarlarlarken, Stefanos \u015f\u00f6yle dua etti: \u201cYa Rab \u0130sa, ruhumu kabul et.\u201d\n60 Sonra dizlerinin \u00fczerine \u00e7\u00f6kt\u00fc ve \u015f\u00f6yle hayk\u0131rd\u0131: \u201cYa Rab, bu g\u00fcnah\u0131 onlara y\u00fckleme.\u201d\n\nSadece Tanr\u0131, t\u0131pk\u0131 Stephen gibi k\u00f6t\u00fcl\u00fc\u011fe sab\u0131rla katlanmam\u0131za yard\u0131m edebilir.\nAma s\u0131k\u0131nt\u0131l\u0131 zamanlarda O\u2019na seslendi\u011fimizde bize yard\u0131m edecektir.\nO, bedenlerimize ne olursa olsun ruhlar\u0131m\u0131z\u0131n O\u2019nun ellerinde g\u00fcvende oldu\u011funu bilerek O\u2019na g\u00fcvenmemize yard\u0131mc\u0131 olacakt\u0131r.\n\nKalite 4: Nazik\u00e7e d\u00fczeltme.\n\u0130nsanlar\u0131 d\u00fczeltmek zordur.\nAma o\u011flum yanl\u0131\u015f bir \u015fey yap\u0131yorsa, onu sevdi\u011fim i\u00e7in ona s\u00f6ylerim.\nBirini d\u00fczeltmeniz gerekti\u011finde d\u00fc\u015f\u00fcnmeniz gereken \u00f6nemli soru \u015fudur:\n\u201d\u00c7ocu\u011fum, arkada\u015f\u0131m veya e\u015fim sevgimi hissediyor mu?\u201d\nYoksa sadece \u00f6fkemi mi hissediyorlar?\n\n\u00d6fke veya hayal k\u0131r\u0131kl\u0131\u011f\u0131yla d\u00fczeltme yapmaya \u00e7al\u0131\u015ft\u0131\u011f\u0131m\u0131zda, Tanr\u0131\u2018n\u0131n di\u011fer ki\u015fiyi de\u011fi\u015ftiremeyece\u011fi gibi davran\u0131yoruz.\nOnlar\u0131 de\u011fi\u015fmeye zorlayabilece\u011fimizi veya do\u011fru yola girene kadar daha y\u00fcksek sesle ba\u011f\u0131rabilece\u011fimizi d\u00fc\u015f\u00fcn\u00fcyoruz.\nAncak Tanr\u0131\u2018n\u0131n ger\u00e7ek g\u00fcce sahip oldu\u011funu bilen bir \u00f6\u011fretmen, nazik, sab\u0131rl\u0131 ve iyi kalpli olacakt\u0131r.\n\nNitelik 5: \u00d6\u011fretebilme yetene\u011fi.\nTanr\u0131\u2018n\u0131n S\u00f6z\u00fcn\u00fc ba\u015fkalar\u0131na a\u00e7\u0131klayabilecek kadar iyi anl\u0131yor musunuz?\nHayat\u0131n\u0131zda size rehberlik etmesi ve ba\u015fkalar\u0131yla payla\u015fman\u0131z i\u00e7in kutsal metinleri ezberliyor musunuz?\nBu ay yeni bir \u015feye ba\u015flayaca\u011f\u0131z.\nMart ay\u0131 sonuna kadar sizden bir ayeti ezberlemenizi isteyece\u011fiz.\nVe e\u011fer bunu liderlerimizden birine, herhangi bir dilde, ezberden okuyabilirseniz, bir \u00e7\u0131kartma kazanacaks\u0131n\u0131z.\nSu \u015fi\u015fenize veya defterinize yap\u0131\u015ft\u0131rabilirsiniz.\nOnu g\u00f6rebilece\u011finiz her yerde yap\u0131n ve y\u0131l boyunca uygulamaya devam edin.\nGelin hep birlikte Mart ay\u0131na ait ayeti, 2 Timoteos 3:16\u2019y\u0131 okuyal\u0131m.\nT\u00dcM\u00dc: \u201cKutsal Yaz\u0131lar\u0131n tamam\u0131 Tanr\u0131\u2018n\u0131n ilham\u0131yla yaz\u0131lm\u0131\u015ft\u0131r ve \u00f6\u011fretmek, azarlamak, d\u00fczeltmek ve do\u011frulukta e\u011fitmek i\u00e7in faydal\u0131d\u0131r.\u201d\n\nDo\u011fru y\u00f6nde ilerlemeye devam etmek i\u00e7in hepimizin yard\u0131ma ihtiyac\u0131 var.\nDo\u011fruluk yolunda y\u00fcr\u00fcmemiz i\u00e7in Tanr\u0131\u2018n\u0131n S\u00f6z\u00fc\u2018ne ihtiyac\u0131m\u0131z var; O\u2019nun \u00f6\u011fretileri, d\u00fczeltmeleri ve e\u011fitimleri bize yol g\u00f6sterir.\nVe Kutsal Ruh\u2019un, S\u00f6z\u00fc anlamam\u0131za ve uygulamam\u0131za yard\u0131mc\u0131 olmas\u0131na ihtiyac\u0131m\u0131z var; bu y\u00fczden \u015fimdi kalplerimizi dua ederek g\u00f6\u011fe \u00e7evirelim.\n\u0130sa, ancak sen yery\u00fcz\u00fc ile g\u00f6k aras\u0131nda bir k\u00f6pr\u00fc kurdu\u011fun i\u00e7in Baba ile konu\u015fabiliyoruz.\n\u015eeytan\u0131n tuzaklar\u0131n\u0131 yok ettin ve g\u00f6zlerimizi ger\u00e7e\u011fe a\u00e7t\u0131n.\nBaba, bize t\u00f6vbe arma\u011fan\u0131n\u0131 verdi\u011fin i\u00e7in te\u015fekk\u00fcr ederiz; b\u00f6ylece g\u00fcnahlar\u0131m\u0131z konusunda hem kendimizle hem de seninle d\u00fcr\u00fcst olabiliriz.\nVe bize kurtulu\u015fumuz i\u00e7in \u0130sa\u2019ya y\u00f6nelme inanc\u0131n\u0131 verdi\u011fin i\u00e7in sana \u015f\u00fck\u00fcrler olsun, Kutsal Ruh.\nZihnimizi ve kalbimizi a\u00e7arak S\u00f6z\u00fc anlamay\u0131 ve hayat\u0131m\u0131za uygulamay\u0131 \u00f6\u011frenelim.\n\u00d6n\u00fcm\u00fczde belirlenen yar\u0131\u015f\u0131 azimle ko\u015fmam\u0131za yard\u0131m et, ba\u015fkalar\u0131n\u0131 da b\u00fct\u00fcnl\u00fc\u011fe, umuda ve cennete giden bu yolculu\u011fa kat\u0131lmaya davet et, amin.\n\nMeditasyon ve Tart\u0131\u015fma Sorular\u0131\n1.  2 Timoteos 2:22 ve Mezmur 119:35-37 ayetlerini okuyun.\na) Stresli oldu\u011funuzda veya teselli arad\u0131\u011f\u0131n\u0131zda kalbinizin do\u011fal olarak hangi \u201cgen\u00e7lik tutkusuna\u201d (Haz, G\u00fc\u00e7, Pop\u00fclerlik, Mal m\u00fclk, Gurur) y\u00f6neldi\u011fini hissedersiniz?\n\n2.  Efesliler 2:1-5 ve Hezekiel 36:26 ayetlerini okuyun.\na) \u201d\u00d6l\u00fc\u201d olmaktan \u201ccanl\u0131\u201d olmaya ge\u00e7mek i\u00e7in ne gereklidir?\nb) T\u00f6vbe etmenin bir l\u00fctuf oldu\u011funa inanmak, g\u00fcnahlar\u0131n\u0131z konusunda Tanr\u0131\u2018ya kar\u015f\u0131 daha d\u00fcr\u00fcst olman\u0131za yard\u0131mc\u0131 olur mu?\n\n3.  2 Timoteos 2:23-25a ve Koloseliler 3:12-14 ayetlerini okuyun.\na) Bir \u201cRabbin hizmetkar\u0131\u201cn\u0131n, ba\u015fkalar\u0131yla tart\u0131\u015f\u0131rken veya onlar\u0131 d\u00fczeltirken sahip olmas\u0131 gereken nitelikler nelerdir?\nb) \u0130sa bizi b\u00fcy\u00fck bir sab\u0131r ve \u015fefkatle sevdi\u011fi i\u00e7in, hayat\u0131n\u0131zda kimleri ayn\u0131 l\u00fctufk\u00e2rl\u0131kla seveceksiniz- sizinle ayn\u0131 fikirde olmasalar veya sizi sevmeseler bile?\n\n4.  Romal\u0131lar 10:9-11 ve \u0130braniler 12:1-2 ayetlerini okuyun.\na) G\u00f6zlerimizi \u0130sa\u2019ya dikmek, g\u00fcnahtan d\u00f6nmemize ve yeni bir y\u00f6ne do\u011fru ilerlememize nas\u0131l yard\u0131mc\u0131 olur?\nb) 2 Timoteos 3:16\u2019y\u0131 ezberlemeyi unutmay\u0131n. Tanr\u0131\u2019n\u0131n S\u00f6z\u00fcn\u00fc bilmek, iman maratonunda ko\u015fmam\u0131za nas\u0131l yard\u0131mc\u0131 olur?","ukrainian_content":"\u041a\u0443\u0434\u0438 \u0442\u0438 \u0431\u0456\u0436\u0438\u0448?\n2 \u0422\u0438\u043c\u043e\u0444\u0456\u044f 2:22-26\n\u041f\u0430\u0441\u0442\u043e\u0440 \u041a\u0440\u0456\u0441 \u0421\u0456\u043a\u0441\n15 \u0431\u0435\u0440\u0435\u0437\u043d\u044f 2026 \u0440\u043e\u043a\u0443\n\n\u041d\u0430 \u043c\u0430\u0440\u0430\u0444\u043e\u043d\u0456 2019 \u0440\u043e\u043a\u0443 \u0432 \u041f\u043e\u0440\u0442\u043b\u0435\u043d\u0434\u0456, \u0448\u0442\u0430\u0442 \u041e\u0440\u0435\u0433\u043e\u043d, \u0434\u0435\u044f\u043a\u0456 \u0437 \u043d\u0430\u0439\u043a\u0440\u0430\u0449\u0438\u0445 \u0431\u0456\u0433\u0443\u043d\u0456\u0432 \u0444\u0430\u043a\u0442\u0438\u0447\u043d\u043e \u043f\u0440\u043e\u0433\u0440\u0430\u043b\u0438 \u0433\u043e\u043d\u043a\u0443.\n\u041d\u0435 \u0442\u043e\u043c\u0443, \u0449\u043e \u0432\u043e\u043d\u0438 \u0431\u0443\u043b\u0438 \u043f\u043e\u0432\u0456\u043b\u044c\u043d\u0438\u043c\u0438, \u0430 \u0442\u043e\u043c\u0443, \u0449\u043e \u0432\u043e\u043d\u0438 \u043f\u0456\u0448\u043b\u0438 \u043d\u0435\u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u0438\u043c \u0448\u043b\u044f\u0445\u043e\u043c.\n\u041d\u0430 \u0442\u0440\u0430\u0441\u0456 \u0431\u0443\u0432 \u043f\u043e\u0432\u043e\u0440\u043e\u0442, \u044f\u043a\u0438\u0439 \u043d\u0435 \u0431\u0443\u0432 \u0447\u0456\u0442\u043a\u043e \u043f\u043e\u0437\u043d\u0430\u0447\u0435\u043d\u0438\u0439.\n\u0422\u043e\u0436 \u0431\u043b\u0438\u0437\u044c\u043a\u043e 20 \u043d\u0430\u0439\u0448\u0432\u0438\u0434\u0448\u0438\u0445 \u0431\u0456\u0433\u0443\u043d\u0456\u0432 \u043f\u0440\u043e\u0431\u0456\u0433\u043b\u0438 \u043f\u043e\u043d\u0430\u0434 \u043c\u0438\u043b\u044e \u0432 \u043d\u0435\u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e\u043c\u0443 \u043d\u0430\u043f\u0440\u044f\u043c\u043a\u0443!\n\u0426\u044f \u043f\u043e\u043c\u0438\u043b\u043a\u0430 \u0434\u043e\u0434\u0430\u043b\u0430 \u0434\u043e\u0440\u043e\u0433\u043e\u0446\u0456\u043d\u043d\u0438\u0445 \u0445\u0432\u0438\u043b\u0438\u043d \u0434\u043e \u043f\u0435\u0440\u0435\u0433\u043e\u043d\u0456\u0432, \u0434\u043e \u044f\u043a\u0438\u0445 \u0432\u043e\u043d\u0438 \u0433\u043e\u0442\u0443\u0432\u0430\u043b\u0438\u0441\u044f \u043c\u0456\u0441\u044f\u0446\u044f\u043c\u0438.\n\u0422\u0456 \u0447\u043e\u043b\u043e\u0432\u0456\u043a\u0438 \u0442\u0430 \u0436\u0456\u043d\u043a\u0438 \u0431\u0456\u0433\u043b\u0438 \u0449\u043e\u0441\u0438\u043b\u0438, \u0456 \u0432\u043e\u043d\u0438 \u0431\u0456\u0433\u043b\u0438 \u0448\u0432\u0438\u0434\u043a\u043e.\n\u0410\u043b\u0435 \u0432\u043e\u043d\u0438 \u043f\u0440\u043e\u0433\u0440\u0430\u043b\u0438 \u0433\u043e\u043d\u043a\u0443, \u0431\u043e \u0439\u0448\u043b\u0438 \u0445\u0438\u0431\u043d\u0438\u043c \u0448\u043b\u044f\u0445\u043e\u043c.\n\u0421\u044c\u043e\u0433\u043e\u0434\u043d\u0456 \u0432\u0432\u0435\u0447\u0435\u0440\u0456 \u043c\u0438 \u043f\u0440\u043e\u0434\u043e\u0432\u0436\u0443\u0454\u043c\u043e \u0441\u0435\u0440\u0456\u044e \u043f\u0440\u043e\u043f\u043e\u0432\u0456\u0434\u0435\u0439 \u0437\u0430 \u043a\u043d\u0438\u0433\u043e\u044e 2 \u0422\u0438\u043c\u043e\u0444\u0456\u044f.\n\u0410\u043f\u043e\u0441\u0442\u043e\u043b \u041f\u0430\u0432\u043b\u043e \u043f\u0438\u0448\u0435 \u0434\u043e \u0422\u0438\u043c\u043e\u0444\u0456\u044f, \u043c\u043e\u043b\u043e\u0434\u043e\u0433\u043e \u043f\u0430\u0441\u0442\u043e\u0440\u0430 \u0445\u0440\u0438\u0441\u0442\u0438\u044f\u043d\u0441\u044c\u043a\u043e\u0457 \u0446\u0435\u0440\u043a\u0432\u0438 \u0432 \u0415\u0444\u0435\u0441\u0456.\n\u041f\u0430\u0432\u043b\u043e \u0434\u0430\u0454 \u0422\u0438\u043c\u043e\u0444\u0456\u044e, \u0456 \u043d\u0430\u043c \u0441\u044c\u043e\u0433\u043e\u0434\u043d\u0456, \u043f\u043e\u0440\u0430\u0434\u0438 \u0449\u043e\u0434\u043e \u0442\u043e\u0433\u043e, \u044f\u043a \u0437\u0430\u043b\u0438\u0448\u0430\u0442\u0438\u0441\u044f \u043d\u0430 \u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e\u043c\u0443 \u0448\u043b\u044f\u0445\u0443.\n2 \u0422\u0438\u043c\u043e\u0444\u0456\u044f 2:22\u201326\n22 \u00ab\u0422\u043e\u0436 \u0443\u0442\u0456\u043a\u0430\u0439 \u200b\u200b\u0432\u0456\u0434 \u044e\u043d\u0430\u0446\u044c\u043a\u0438\u0445 \u043f\u043e\u0436\u0430\u0434\u0430\u043d\u044c \u0456 \u0436\u0435\u043d\u0438\u0441\u044f \u043f\u0440\u0430\u0432\u0435\u0434\u043d\u043e\u0441\u0442\u0456, \u0432\u0456\u0440\u0438, \u043b\u044e\u0431\u043e\u0432\u0456 \u0442\u0430 \u043c\u0438\u0440\u0443 \u0440\u0430\u0437\u043e\u043c \u0437 \u0442\u0438\u043c\u0438, \u0445\u0442\u043e \u043a\u043b\u0438\u0447\u0435 \u0413\u043e\u0441\u043f\u043e\u0434\u0430 \u0432\u0456\u0434 \u0447\u0438\u0441\u0442\u043e\u0433\u043e \u0441\u0435\u0440\u0446\u044f.\n23 \u041d\u0435 \u0431\u0435\u0440\u0438 \u0443\u0447\u0430\u0441\u0442\u0456 \u0432 \u0434\u0443\u0440\u043d\u0438\u0445 \u0442\u0430 \u043d\u0435\u0432\u0456\u0433\u043b\u0430\u0441\u043d\u0438\u0445 \u0441\u0443\u043f\u0435\u0440\u0435\u0447\u043a\u0430\u0445, \u0431\u043e \u0437\u043d\u0430\u0454\u0448, \u0449\u043e \u0432\u043e\u043d\u0438 \u043f\u043e\u0440\u043e\u0434\u0436\u0443\u044e\u0442\u044c \u0441\u0432\u0430\u0440\u043a\u0438.\n24 \u0410 \u0441\u043b\u0443\u0433\u0430 \u0413\u043e\u0441\u043f\u043e\u0434\u043d\u0456\u0439 \u043d\u0435 \u043f\u043e\u0432\u0438\u043d\u0435\u043d \u0431\u0443\u0442\u0438 \u0441\u0432\u0430\u0440\u043b\u0438\u0432\u0438\u043c, \u0430\u043b\u0435 \u0434\u043e\u0431\u0440\u0438\u043c \u0434\u043e \u0432\u0441\u0456\u0445, \u0437\u0434\u0430\u0442\u043d\u0438\u043c \u043d\u0430\u0432\u0447\u0430\u0442\u0438, \u0442\u0435\u0440\u043f\u0435\u043b\u0438\u0432\u043e \u0437\u043d\u043e\u0441\u0438\u0442\u0438 \u0437\u043b\u043e,\n25 \u0432\u0438\u043f\u0440\u0430\u0432\u043b\u044f\u044e\u0447\u0438 \u0441\u0432\u043e\u0457\u0445 \u0441\u0443\u043f\u0440\u043e\u0442\u0438\u0432\u043d\u0438\u043a\u0456\u0432 \u0437 \u043b\u0430\u0433\u0456\u0434\u043d\u0456\u0441\u0442\u044e.\n\u041c\u043e\u0436\u043b\u0438\u0432\u043e, \u0411\u043e\u0433 \u0434\u0430\u0440\u0443\u0454 \u0457\u043c \u043f\u043e\u043a\u0430\u044f\u043d\u043d\u044f, \u044f\u043a\u0435 \u043f\u0440\u0438\u0432\u0435\u0434\u0435 \u0434\u043e \u043f\u0456\u0437\u043d\u0430\u043d\u043d\u044f \u0456\u0441\u0442\u0438\u043d\u0438,\n26 \u0449\u043e\u0431 \u0432\u043e\u043d\u0438 \u043c\u043e\u0433\u043b\u0438 \u043e\u0442\u044f\u043c\u0438\u0442\u0438\u0441\u044f \u0442\u0430 \u0432\u0438\u0440\u0432\u0430\u0442\u0438\u0441\u044f \u0437 \u043f\u0430\u0441\u0442\u043a\u0438 \u0434\u0438\u044f\u0432\u043e\u043b\u0430, \u0431\u0443\u0434\u0443\u0447\u0438 \u0441\u0445\u043e\u043f\u043b\u0435\u043d\u0456 \u043d\u0438\u043c, \u0449\u043e\u0431 \u0447\u0438\u043d\u0438\u0442\u0438 \u0439\u043e\u0433\u043e \u0432\u043e\u043b\u044e\u00bb.\n\n\u0420\u0430\u0437\u043e\u043c \u043c\u0438 \u0447\u0438\u0442\u0430\u0454\u043c\u043e \u0406\u0441\u0430\u044e 40:8:\n\u00ab\u0422\u0440\u0430\u0432\u0430 \u0432\u2019\u044f\u043d\u0435, \u043a\u0432\u0456\u0442\u043a\u0430 \u0437\u0456\u0432\u2019\u044f\u043d\u0435, \u0430\u043b\u0435 \u0441\u043b\u043e\u0432\u043e \u043d\u0430\u0448\u043e\u0433\u043e \u0411\u043e\u0433\u0430 \u0441\u0442\u043e\u044f\u0442\u0438\u043c\u0435 \u0432\u0456\u0447\u043d\u043e\u00bb.\n\n\u0423 \u0432\u0456\u0440\u0448\u0456 22 \u0441\u043a\u0430\u0437\u0430\u043d\u043e:\n22 \u00ab\u0422\u043e\u0436 \u0443\u0442\u0456\u043a\u0430\u0439 \u200b\u200b\u0432\u0456\u0434 \u044e\u043d\u0430\u0446\u044c\u043a\u0438\u0445 \u043f\u043e\u0436\u0430\u0434\u0430\u043d\u044c \u0456 \u0436\u0435\u043d\u0438\u0441\u044f \u043f\u0440\u0430\u0432\u0435\u0434\u043d\u043e\u0441\u0442\u0456, \u0432\u0456\u0440\u0438, \u043b\u044e\u0431\u043e\u0432\u0456 \u0442\u0430 \u043c\u0438\u0440\u0443 \u0440\u0430\u0437\u043e\u043c \u0437 \u0442\u0438\u043c\u0438, \u0445\u0442\u043e \u043a\u043b\u0438\u0447\u0435 \u0413\u043e\u0441\u043f\u043e\u0434\u0430 \u0432\u0456\u0434 \u0447\u0438\u0441\u0442\u043e\u0433\u043e \u0441\u0435\u0440\u0446\u044f\u00bb.\n\n\u0426\u0435\u0439 \u0432\u0456\u0440\u0448 \u043d\u0430\u0441\u043f\u0440\u0430\u0432\u0434\u0456 \u0454 \u043a\u043e\u0440\u043e\u0442\u043a\u0438\u043c \u0432\u0438\u043a\u043b\u0430\u0434\u043e\u043c \u0441\u044c\u043e\u0433\u043e\u0434\u043d\u0456\u0448\u043d\u044c\u043e\u0457 \u043f\u0440\u043e\u043f\u043e\u0432\u0456\u0434\u0456.\n\u041c\u0438 \u0447\u0430\u0441\u0442\u043e \u0431\u0430\u0447\u0438\u043c\u043e \u0446\u0435 \u0432 \u0411\u043e\u0436\u043e\u043c\u0443 \u0421\u043b\u043e\u0432\u0456.\n\u0406\u043d\u043e\u0434\u0456 \u043f\u0435\u0440\u0448\u0435 \u0442\u0432\u0435\u0440\u0434\u0436\u0435\u043d\u043d\u044f \u0432 \u041f\u0441\u0430\u043b\u043c\u0456 \u0430\u0431\u043e \u0430\u0431\u0437\u0430\u0446\u0456 \u0431\u0443\u0434\u0435 \u043a\u043e\u0440\u043e\u0442\u043a\u0438\u043c \u0432\u0438\u043a\u043b\u0430\u0434\u043e\u043c.\n\u041f\u043e\u0442\u0456\u043c \u043d\u0430\u0441\u0442\u0443\u043f\u043d\u0456 \u0441\u043b\u043e\u0432\u0430 \u0454 \u043f\u043e\u044f\u0441\u043d\u0435\u043d\u043d\u044f\u043c \u0443\u0441\u044c\u043e\u0433\u043e \u041f\u0441\u0430\u043b\u043c\u0430, \u0430\u0431\u0437\u0430\u0446\u0443 \u0447\u0438 \u0440\u043e\u0437\u0434\u0456\u043b\u0443.\n\u0417\u0440\u0456\u043b\u0438\u0439 \u0445\u0440\u0438\u0441\u0442\u0438\u044f\u043d\u0438\u043d \u2013 \u0446\u0435 \u0442\u043e\u0439, \u0445\u0442\u043e \u0432\u0456\u0434\u0445\u043e\u0434\u0438\u0442\u044c \u0432\u0456\u0434 \u0442\u043e\u0433\u043e, \u0449\u043e \u0441\u043f\u043e\u043a\u0443\u0448\u0430\u043b\u043e \u043d\u0430\u0441 \u0443 \u043c\u043e\u043b\u043e\u0434\u043e\u0441\u0442\u0456.\n\u0417\u0430\u043c\u0456\u0441\u0442\u044c \u00ab\u044e\u043d\u0430\u0446\u044c\u043a\u0438\u0445 \u043f\u0440\u0438\u0441\u0442\u0440\u0430\u0441\u0442\u0435\u0439\u00bb \u0437\u0440\u0456\u043b\u0430 \u043b\u044e\u0434\u0438\u043d\u0430 \u0432\u0447\u0438\u0442\u044c\u0441\u044f \u043f\u0440\u0430\u0433\u043d\u0443\u0442\u0438 \u0411\u043e\u0436\u0438\u0445 \u0446\u0456\u043d\u043d\u043e\u0441\u0442\u0435\u0439, \u0432\u043a\u043b\u044e\u0447\u0430\u044e\u0447\u0438 \u041f\u0440\u0430\u0432\u0435\u0434\u043d\u0456\u0441\u0442\u044c, \u0412\u0456\u0440\u0443, \u041b\u044e\u0431\u043e\u0432, \u041c\u0438\u0440.\n\u041a\u043e\u043b\u0438 \u041f\u0430\u0432\u043b\u043e \u0431\u0443\u0432 \u044e\u043d\u0430\u043a\u043e\u043c, \u0439\u043e\u0433\u043e \u0437\u0432\u0430\u043b\u0438 \u0421\u0430\u0432\u043b\u043e\u043c.\n\u0421\u0430\u0432\u043b \u0431\u0443\u0432 \u0441\u043f\u043e\u0432\u043d\u0435\u043d\u0438\u0439 \u0433\u043e\u0440\u0434\u043e\u0441\u0442\u0456 \u0442\u0430 \u0441\u0430\u043c\u043e\u0432\u043f\u0435\u0432\u043d\u0435\u043d\u043e\u0441\u0442\u0456, \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u043e\u0432\u0443\u044e\u0447\u0438 \u0432\u043b\u0430\u0434\u0443, \u0449\u043e\u0431 \u043f\u0435\u0440\u0435\u0441\u043b\u0456\u0434\u0443\u0432\u0430\u0442\u0438 \u0445\u0440\u0438\u0441\u0442\u0438\u044f\u043d \u0442\u0430 \u0443\u0432\u2018\u044f\u0437\u043d\u044e\u0432\u0430\u0442\u0438 \u0457\u0445.\n\u0421\u0430\u0443\u043b \u0445\u043e\u0442\u0456\u0432 \u0431\u0443\u0442\u0438 \u043f\u043e\u043f\u0443\u043b\u044f\u0440\u043d\u0438\u043c \u0442\u0430 \u0443\u0441\u043f\u0456\u0448\u043d\u0438\u043c \u0456 \u0431\u0443\u0432 \u0433\u043e\u0442\u043e\u0432\u0438\u0439 \u0437\u0430\u0432\u0434\u0430\u0432\u0430\u0442\u0438 \u0431\u043e\u043b\u044e \u0456\u043d\u0448\u0438\u043c \u0447\u0435\u0440\u0435\u0437 \u0432\u043b\u0430\u0441\u043d\u0443 \u0433\u043e\u0440\u0434\u0438\u043d\u044e.\n\u0410\u043b\u0435 \u0414\u0440\u0443\u0433\u0435 \u043f\u043e\u0441\u043b\u0430\u043d\u043d\u044f \u0434\u043e \u0422\u0438\u043c\u043e\u0444\u0456\u044f \u0431\u0443\u043b\u043e \u043d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u041f\u0430\u0432\u043b\u043e\u043c, \u0437\u0440\u0456\u043b\u0438\u043c \u0432\u0456\u0440\u0443\u044e\u0447\u0438\u043c.\n\u0412\u0456\u043d \u0440\u043e\u0437\u0443\u043c\u0456\u0454, \u044f\u043a\u043e\u0457 \u0448\u043a\u043e\u0434\u0438 \u0437\u0430\u0432\u0434\u0430\u043b\u0438 \u0439\u043e\u0433\u043e \u044e\u043d\u0430\u0446\u044c\u043a\u0456 \u043f\u0440\u0438\u0441\u0442\u0440\u0430\u0441\u0442\u0456, \u0456 \u043f\u043e\u043f\u0435\u0440\u0435\u0434\u0436\u0430\u0454 \u043f\u0440\u043e \u043d\u0438\u0445 \u0422\u0456\u043c\u043e\u0442\u0456.\n\u041d\u0430 \u043c\u043e\u043c\u0435\u043d\u0442 \u043d\u0430\u043f\u0438\u0441\u0430\u043d\u043d\u044f \u041f\u0430\u0432\u043b\u043e\u043c \u0446\u044c\u043e\u0433\u043e \u043b\u0438\u0441\u0442\u0430 \u0422\u0438\u043c\u043e\u0444\u0456\u044e, \u0439\u043c\u043e\u0432\u0456\u0440\u043d\u043e, \u0431\u0443\u043b\u043e \u0431\u043b\u0438\u0437\u044c\u043a\u043e 40 \u0440\u043e\u043a\u0456\u0432.\n\u0410\u043b\u0435 \u043d\u0435 \u043e\u0431\u043e\u0432\u2018\u044f\u0437\u043a\u043e\u0432\u043e \u0431\u0443\u0442\u0438 \u043c\u043e\u043b\u043e\u0434\u0438\u043c, \u0449\u043e\u0431 \u0431\u0456\u0433\u0442\u0438 \u043d\u0430\u0437\u0443\u0441\u0442\u0440\u0456\u0447 \u00ab\u044e\u043d\u0430\u0446\u044c\u043a\u0438\u043c \u043f\u0440\u0438\u0441\u0442\u0440\u0430\u0441\u0442\u044f\u043c\u00bb.\n\u041c\u0435\u043d\u0456 57, \u0430\u043b\u0435 \u044f \u0432\u0441\u0435 \u0449\u0435 \u0432\u0447\u0443\u0441\u044f \u043f\u043e\u0441\u043b\u0456\u0434\u043e\u0432\u043d\u043e \u0442\u0456\u043a\u0430\u0442\u0438 \u0432\u0456\u0434 \u044e\u043d\u0430\u0446\u044c\u043a\u0438\u0445 \u043f\u0440\u0438\u0441\u0442\u0440\u0430\u0441\u0442\u0435\u0439.\n\u0423 \u043c\u0435\u043d\u0435 \u0454 \u0434\u0440\u0443\u0433 \u0437 \u043a\u043e\u043b\u0435\u0434\u0436\u0443, \u044f\u043a\u0438\u0439 \u0442\u0430\u043a\u043e\u0433\u043e \u0436 \u0432\u0456\u043a\u0443, \u044f\u043a \u0456 \u044f.\n\u0410\u043b\u0435 \u0432\u0456\u043d \u0434\u043e\u0441\u0456 \u0436\u0438\u0432\u0435 \u0442\u0430\u043a \u0441\u0430\u043c\u043e, \u044f\u043a \u0456 35 \u0440\u043e\u043a\u0456\u0432 \u0442\u043e\u043c\u0443.\n\u0419\u043e\u0433\u043e \u0436\u0438\u0442\u0442\u044f \u043f\u0440\u043e\u043d\u0438\u0437\u0430\u043d\u0435 \u044e\u043d\u0430\u0446\u044c\u043a\u0438\u043c\u0438 \u043f\u0440\u0438\u0441\u0442\u0440\u0430\u0441\u0442\u044f\u043c\u0438 \u043d\u0430\u0448\u0438\u0445 \u0441\u0442\u0443\u0434\u0435\u043d\u0442\u0441\u044c\u043a\u0438\u0445 \u0440\u043e\u043a\u0456\u0432.\n\u041e\u0441\u044c \u0434\u0435\u044f\u043a\u0456 \u044e\u043d\u0430\u0446\u044c\u043a\u0456 \u0437\u0430\u0445\u043e\u043f\u043b\u0435\u043d\u043d\u044f, \u044f\u043a\u0456 \u0432\u0456\u0434\u0447\u0443\u0432\u0430\u044e\u0442\u044c \u0431\u0430\u0433\u0430\u0442\u043e \u0445\u0442\u043e \u0437 \u043d\u0430\u0441:\n\n*   \u0417\u0430\u0434\u043e\u0432\u043e\u043b\u0435\u043d\u043d\u044f: \u0421\u0442\u0430\u0442\u0435\u0432\u0438\u0439 \u0433\u0440\u0456\u0445 \u0454 \u043f\u043e\u0448\u0438\u0440\u0435\u043d\u0438\u043c \u043f\u0440\u0438\u043a\u043b\u0430\u0434\u043e\u043c \u0433\u0440\u0456\u0445\u0430 \u0437\u0430\u0434\u043e\u0432\u043e\u043b\u0435\u043d\u043d\u044f, \u0430\u043b\u0435 \u043d\u0435 \u0454\u0434\u0438\u043d\u0438\u043c.\n\u0406\u043d\u0448\u0456 \u0433\u0440\u0456\u0445\u043e\u0432\u043d\u0456 \u0437\u0430\u0434\u043e\u0432\u043e\u043b\u0435\u043d\u043d\u044f \u043c\u043e\u0436\u0443\u0442\u044c \u0432\u043a\u043b\u044e\u0447\u0430\u0442\u0438 \u0430\u043b\u043a\u043e\u0433\u043e\u043b\u044c, \u0457\u0436\u0443 \u0442\u0430 \u0431\u0430\u0433\u0430\u0442\u043e \u0432\u0438\u0434\u0456\u0432 \u0440\u043e\u0437\u0432\u0430\u0433.\n\u0426\u0456 \u0440\u0435\u0447\u0456 \u043d\u0435 \u0454 \u043f\u043e\u0433\u0430\u043d\u0438\u043c\u0438, \u044f\u043a\u0449\u043e \u0457\u0445 \u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u043e\u0432\u0443\u0432\u0430\u0442\u0438.\n\u041d\u0430\u043f\u0440\u0438\u043a\u043b\u0430\u0434, \u0441\u0435\u043a\u0441 \u2013 \u0446\u0435 \u043f\u0440\u0435\u043a\u0440\u0430\u0441\u043d\u0438\u0439 \u0434\u0430\u0440 \u0443 \u043a\u043e\u043d\u0442\u0435\u043a\u0441\u0442\u0456 \u0445\u0440\u0438\u0441\u0442\u0438\u044f\u043d\u0441\u044c\u043a\u043e\u0433\u043e \u0448\u043b\u044e\u0431\u0443.\n\u0410\u043b\u0435 \u043a\u043e\u043b\u0438 \u043c\u0438 \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u043e\u0432\u0443\u0454\u043c\u043e \u0449\u043e\u0441\u044c \u043d\u0435\u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e, \u043c\u0438 \u043d\u0430\u0434\u0430\u0454\u043c\u043e \u0446\u044c\u043e\u043c\u0443 \u0432\u043b\u0430\u0434\u0443 \u043d\u0430\u0434 \u043d\u0430\u0448\u0438\u043c \u0436\u0438\u0442\u0442\u044f\u043c.\n\u041a\u043e\u043b\u0438 \u043c\u0438 \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u043e\u0432\u0443\u0454\u043c\u043e \u0431\u0443\u0434\u044c-\u044f\u043a\u0438\u0439 \u0411\u043e\u0436\u0438\u0439 \u0434\u0430\u0440, \u0449\u043e\u0431 \u0437\u0430\u043f\u043e\u0432\u043d\u0438\u0442\u0438 \u043f\u043e\u0440\u043e\u0436\u043d\u0435\u0447\u0443 \u0432 \u043d\u0430\u0448\u0438\u0445 \u0441\u0435\u0440\u0446\u044f\u0445, \u0446\u044f \u0440\u0456\u0447 \u0441\u0442\u0430\u0454 \u0444\u0430\u043b\u044c\u0448\u0438\u0432\u0438\u043c \u0431\u043e\u0433\u043e\u043c \u2013 \u0456\u0434\u043e\u043b\u043e\u043c.\n\n*   \u0421\u0438\u043b\u0430: \u041a\u043e\u043b\u0438 \u043c\u0438 \u043c\u043e\u043b\u043e\u0434\u0456, \u043c\u0438 \u0456\u043d\u043e\u0434\u0456 \u043f\u043e\u0447\u0443\u0432\u0430\u0454\u043c\u043e\u0441\u044f \u0431\u0435\u0437\u0441\u0438\u043b\u0438\u043c\u0438, \u0441\u043b\u0430\u0431\u043a\u0438\u043c\u0438 \u0430\u0431\u043e \u043d\u0435\u0430\u0434\u0435\u043a\u0432\u0430\u0442\u043d\u0438\u043c\u0438.\n\u042f \u0431\u043e\u0440\u043e\u0432\u0441\u044f \u0437 \u0446\u0438\u043c\u0438 \u043f\u043e\u0447\u0443\u0442\u0442\u044f\u043c\u0438 \u0432 \u043f\u0456\u0434\u043b\u0456\u0442\u043a\u043e\u0432\u043e\u043c\u0443 \u0432\u0456\u0446\u0456.\n\u0414\u0435\u044f\u043a\u0456 \u043b\u044e\u0434\u0438 \u043f\u0440\u0430\u0433\u043d\u0443\u0442\u044c \u0432\u043b\u0430\u0434\u0438, \u0449\u043e\u0431 \u043f\u0440\u0438\u0445\u043e\u0432\u0430\u0442\u0438 \u043f\u043e\u0447\u0443\u0442\u0442\u044f \u0441\u043b\u0430\u0431\u043a\u043e\u0441\u0442\u0456.\n\u0412\u043e\u043d\u0438 \u0434\u0443\u043c\u0430\u044e\u0442\u044c, \u0449\u043e \u0441\u0438\u043b\u044c\u043d\u0430 \u043f\u043e\u0432\u0435\u0434\u0456\u043d\u043a\u0430 \u0434\u043e\u043f\u043e\u043c\u043e\u0436\u0435 \u0457\u043c \u043f\u043e\u0447\u0443\u0432\u0430\u0442\u0438\u0441\u044f \u0432 \u0431\u0435\u0437\u043f\u0435\u0446\u0456.\n\u0427\u0438 \u0437\u043d\u0430\u0454\u0442\u0435 \u0432\u0438, \u0449\u043e \u0445\u0443\u043b\u0456\u0433\u0430\u043d \u043d\u0430\u0441\u043f\u0440\u0430\u0432\u0434\u0456 \u043d\u0435 \u0442\u0430\u043a\u0438\u0439 \u0436\u043e\u0440\u0441\u0442\u043a\u0438\u0439, \u044f\u043a \u0437\u0434\u0430\u0454\u0442\u044c\u0441\u044f?\n\u0411\u0443\u043b\u0456\u043d\u0433 \u2013 \u0446\u0435 \u0437\u0430\u0437\u0432\u0438\u0447\u0430\u0439 \u0442\u043e\u0439, \u0445\u0442\u043e \u043f\u043e\u0447\u0443\u0432\u0430\u0454\u0442\u044c\u0441\u044f \u0431\u0435\u0437\u0441\u0438\u043b\u0438\u043c \u0443 \u0447\u043e\u043c\u0443\u0441\u044c \u0441\u0432\u043e\u0454\u043c\u0443 \u0436\u0438\u0442\u0442\u0456, \u0442\u043e\u043c\u0443 \u0432\u0456\u043d \u0437\u0430\u0432\u0434\u0430\u0454 \u0431\u043e\u043b\u044e \u0456\u043d\u0448\u0438\u043c \u043b\u044e\u0434\u044f\u043c, \u0449\u043e\u0431 \u0432\u0456\u0434\u0447\u0443\u0442\u0438 \u0441\u0435\u0431\u0435 \u0441\u0438\u043b\u044c\u043d\u0438\u043c.\n\n*   \u041f\u043e\u043f\u0443\u043b\u044f\u0440\u043d\u0456\u0441\u0442\u044c: \u0426\u0435 \u0431\u0443\u043b\u0430 \u0449\u0435 \u043e\u0434\u043d\u0430 \u0441\u0438\u043b\u044c\u043d\u0430 \u0441\u043f\u043e\u043a\u0443\u0441\u0430 \u0432 \u043c\u043e\u0454\u043c\u0443 \u0436\u0438\u0442\u0442\u0456.\n\u042f \u0447\u0430\u0441\u0442\u043e \u0445\u0432\u0438\u043b\u044e\u044e\u0441\u044f, \u0447\u0438 \u043f\u043e\u0434\u043e\u0431\u0430\u044e\u0441\u044f \u044f \u043b\u044e\u0434\u044f\u043c.\n\u041c\u0435\u043d\u0435 \u0437\u0430\u043d\u0430\u0434\u0442\u043e \u0445\u0432\u0438\u043b\u044e\u0454 \u0434\u0443\u043c\u043a\u0430 \u0456\u043d\u0448\u0438\u0445 \u043b\u044e\u0434\u0435\u0439.\n\u0410 \u044f\u043a \u0449\u043e\u0434\u043e \u0442\u0435\u0431\u0435?\n\u0427\u0438 \u0437\u043c\u0456\u043d\u044e\u0454\u0442\u0435 \u0432\u0438 \u043a\u043e\u043b\u0438-\u043d\u0435\u0431\u0443\u0434\u044c \u0441\u0432\u043e\u044e \u043f\u043e\u0432\u0435\u0434\u0456\u043d\u043a\u0443 \u0447\u0438 \u0437\u043e\u0432\u043d\u0456\u0448\u043d\u0456\u0441\u0442\u044c, \u0449\u043e\u0431 \u043f\u043e\u0434\u043e\u0431\u0430\u0442\u0438\u0441\u044f \u043b\u044e\u0434\u044f\u043c?\n\u042f\u043a \u0432\u0438 \u0432\u0432\u0430\u0436\u0430\u0454\u0442\u0435, \u0447\u0438 \u043f\u043e\u0442\u0440\u0456\u0431\u043d\u043e \u043f\u043e\u0432\u043e\u0434\u0438\u0442\u0438\u0441\u044f \u0430\u0431\u043e \u0432\u0438\u0433\u043b\u044f\u0434\u0430\u0442\u0438 \u043f\u0435\u0432\u043d\u0438\u043c \u0447\u0438\u043d\u043e\u043c, \u0449\u043e\u0431 \u0443\u043d\u0438\u043a\u043d\u0443\u0442\u0438 \u0432\u0456\u0434\u043c\u043e\u0432\u0438?\n\n*   \u041c\u0430\u0439\u043d\u043e: \u041b\u044e\u0431\u043e\u0432 \u0434\u043e \u0433\u0440\u043e\u0448\u0435\u0439 \u0442\u0430 \u043c\u0430\u0442\u0435\u0440\u0456\u0430\u043b\u044c\u043d\u0438\u0445 \u0431\u043b\u0430\u0433 \u0454 \u043f\u0440\u043e\u0431\u043b\u0435\u043c\u043e\u044e \u0434\u043b\u044f \u0431\u0456\u043b\u044c\u0448\u043e\u0441\u0442\u0456 \u0437 \u043d\u0430\u0441.\n\u041c\u0438 \u0445\u043e\u0447\u0435\u043c\u043e \u0431\u0435\u0437\u043f\u0435\u043a\u0438 \u0442\u0430 \u043a\u043e\u043c\u0444\u043e\u0440\u0442\u0443 \u0432\u0456\u0434 \u0442\u043e\u0433\u043e, \u0449\u043e \u043c\u0430\u0454\u043c\u043e \u0431\u0456\u043b\u044c\u0448\u0435 \u0440\u0435\u0447\u0435\u0439.\n\u0426\u0435 \u0441\u0432\u0456\u0434\u0447\u0438\u0442\u044c \u043f\u0440\u043e \u0431\u0440\u0430\u043a \u0432\u0456\u0440\u0438.\n\u0411\u043e\u0433 \u0445\u043e\u0447\u0435, \u0449\u043e\u0431 \u043c\u0438 \u0437\u0440\u043e\u0437\u0443\u043c\u0456\u043b\u0438, \u0449\u043e \u0412\u0456\u043d \u2014 \u043d\u0430\u0448 \u043f\u0440\u0438\u0442\u0443\u043b\u043e\u043a \u0456 \u0444\u043e\u0440\u0442\u0435\u0446\u044f, \u0412\u0456\u043d \u2014 \u043d\u0430\u0448 \u043f\u043e\u0441\u0442\u0430\u0447\u0430\u043b\u044c\u043d\u0438\u043a.\n\u041c\u0430\u0442\u0435\u0440\u0456\u0430\u043b\u044c\u043d\u0456 \u0440\u0435\u0447\u0456 \u043e\u0431\u0456\u0446\u044f\u044e\u0442\u044c \u0449\u0430\u0441\u0442\u044f, \u0430\u043b\u0435 \u0432\u043e\u043d\u0438 \u043d\u0456\u043a\u043e\u043b\u0438 \u043d\u0435 \u043c\u043e\u0436\u0443\u0442\u044c \u0432\u0438\u043a\u043e\u043d\u0430\u0442\u0438 \u0441\u0432\u043e\u044e \u043e\u0431\u0456\u0446\u044f\u043d\u043a\u0443.\n\u0411\u043e \u043d\u0430\u0448\u0456 \u0441\u0435\u0440\u0446\u044f \u0437\u0430\u0432\u0436\u0434\u0438 \u043f\u0440\u0430\u0433\u043d\u0443\u0442\u0438\u043c\u0443\u0442\u044c \u0431\u0456\u043b\u044c\u0448\u043e\u0433\u043e.\n\n*   \u0413\u043e\u0440\u0434\u0438\u043d\u044f: \u0426\u0435 \u0441\u043f\u0440\u0430\u0432\u0434\u0456 \u0433\u0440\u0456\u0445, \u0449\u043e \u043b\u0435\u0436\u0438\u0442\u044c \u043f\u0456\u0434 \u0443\u0441\u0456\u043c\u0430 \u0456\u043d\u0448\u0438\u043c\u0438 \u0433\u0440\u0456\u0445\u0430\u043c\u0438.\n\u0413\u043e\u0440\u0434\u0456\u0441\u0442\u044c \u2014 \u0446\u0435 \u043f\u0435\u0440\u0435\u043a\u043e\u043d\u0430\u043d\u043d\u044f, \u0449\u043e \u044f \u043d\u0430\u0441\u043f\u0440\u0430\u0432\u0434\u0456 \u0437\u0430\u0441\u043b\u0443\u0433\u043e\u0432\u0443\u044e \u043d\u0430 \u043c\u0430\u0439\u043d\u043e, \u0432\u043b\u0430\u0434\u0443, \u0437\u0430\u0434\u043e\u0432\u043e\u043b\u0435\u043d\u043d\u044f \u0442\u0430 \u043f\u043e\u043f\u0443\u043b\u044f\u0440\u043d\u0456\u0441\u0442\u044c.\n\u0427\u043e\u043c\u0443? \u0422\u043e\u043c\u0443 \u0449\u043e \u044f \u043e\u0441\u043e\u0431\u043b\u0438\u0432\u0438\u0439\/\u043e\u0441\u043e\u0431\u043b\u0438\u0432\u0430.\n\u0413\u043e\u0440\u0434\u0456\u0441\u0442\u044c \u0448\u0435\u043f\u043e\u0447\u0435 \u043d\u0430\u043c \u0431\u0440\u0435\u0445\u043d\u044e, \u043a\u0430\u0436\u0443\u0447\u0438:\n\u00ab\u0412\u0441\u0435 \u0433\u0430\u0440\u0430\u0437\u0434, \u0442\u0438 \u043c\u043e\u0436\u0435\u0448 \u0446\u0435 \u0437\u0440\u043e\u0431\u0438\u0442\u0438 \u2014 \u0442\u0438 \u0446\u044c\u043e\u0433\u043e \u0437\u0430\u0441\u043b\u0443\u0433\u043e\u0432\u0443\u0454\u0448\u00bb.\n\u0420\u0435\u043a\u043b\u0430\u043c\u043e\u0434\u0430\u0432\u0446\u0456 \u043a\u0430\u0436\u0443\u0442\u044c \u043d\u0430\u043c \u0442\u0435 \u0441\u0430\u043c\u0435.\n\u00ab\u0422\u0438 \u0446\u044c\u043e\u0433\u043e \u0437\u0430\u0441\u043b\u0443\u0433\u043e\u0432\u0443\u0454\u0448\u2026 \u0414\u0430\u0432\u0430\u0439, \u043a\u0443\u043f\u0443\u0439.\u00bb\n\u041c\u043e\u0436\u043b\u0438\u0432\u043e, \u043a\u0443\u043f\u0438 \u0449\u0435 \u0442\u0440\u043e\u0445\u0438, \u043d\u0456\u0447\u043e\u0433\u043e \u0441\u0442\u0440\u0430\u0448\u043d\u043e\u0433\u043e.\n\u041e\u0441\u044c \u0447\u043e\u043c\u0443 \u043c\u0438 \u0431\u0430\u0447\u0438\u043c\u043e \u0442\u0430\u043a \u0431\u0430\u0433\u0430\u0442\u043e \u0442\u0430\u043a\u043e\u0457 \u0440\u0435\u043a\u043b\u0430\u043c\u0438, \u0431\u043e \u043d\u0430\u0448\u0430 \u0433\u043e\u0440\u0434\u0438\u043d\u044f \u043d\u0430\u0441\u043f\u0440\u0430\u0432\u0434\u0456 \u0445\u043e\u0447\u0435 \u0432\u0456\u0440\u0438\u0442\u0438 \u0432 \u0446\u0435.\n\n\u041c\u043e\u0436\u043d\u0430 \u043c\u0435\u043d\u0456 \u043f\u043e\u0441\u0442\u0430\u0432\u0438\u0442\u0438 \u0432\u0430\u043c \u0437\u0430\u043f\u0438\u0442\u0430\u043d\u043d\u044f, \u0434\u0440\u0443\u0437\u0456?\n\u042f\u043a\u0430 \u0437 \u0446\u0438\u0445 \u043f\u2018\u044f\u0442\u0438 \u0440\u0435\u0447\u0435\u0439 \u0437\u0432\u0443\u0447\u0438\u0442\u044c \u0432\u0430\u043c \u0437\u043d\u0430\u0439\u043e\u043c\u043e?\n\u0412\u0438 \u043f\u0440\u0430\u0433\u043d\u0435\u0442\u0435 \u0433\u043e\u0440\u0434\u043e\u0441\u0442\u0456, \u043c\u0430\u0439\u043d\u0430, \u0432\u043b\u0430\u0434\u0438, \u0437\u0430\u0434\u043e\u0432\u043e\u043b\u0435\u043d\u043d\u044f \u0447\u0438 \u043f\u043e\u043f\u0443\u043b\u044f\u0440\u043d\u043e\u0441\u0442\u0456?\n\u0410 \u043c\u043e\u0436\u0435, \u0446\u0435 \u0449\u043e\u0441\u044c \u0456\u043d\u0448\u0435, \u0449\u043e \u0432\u0456\u0434\u0434\u0430\u043b\u044f\u0454 \u0432\u0430\u0441 \u0432\u0456\u0434 \u0411\u043e\u0433\u0430?\n\u0414\u0435 \u0442\u0432\u043e\u0454 \u0441\u0435\u0440\u0446\u0435 \u0441\u044c\u043e\u0433\u043e\u0434\u043d\u0456, \u0456 \u043a\u0443\u0434\u0438 \u0442\u0438 \u0439\u0434\u0435\u0448?\n\u041f\u0430\u043c\u2018\u044f\u0442\u0430\u0454\u0448, \u0449\u043e \u0411\u043e\u0433 \u0441\u043f\u0438\u0442\u0430\u0432 \u0443 \u0410\u0434\u0430\u043c\u0430 \u0432 \u0441\u0430\u0434\u0443, \u043f\u0456\u0441\u043b\u044f \u0442\u043e\u0433\u043e \u044f\u043a \u0442\u043e\u0439 \u0437\u2018\u0457\u0432 \u043f\u043b\u0456\u0434?\n\u0410\u0434\u0430\u043c \u0456 \u0404\u0432\u0430 \u0445\u043e\u0432\u0430\u043b\u0438\u0441\u044f, \u0456 \u0411\u043e\u0433 \u0441\u043a\u0430\u0437\u0430\u0432: \u00ab\u0414\u0435 \u0442\u0438, \u0410\u0434\u0430\u043c\u0435?\u00bb\n\u0411\u043e\u0433 \u043f\u0440\u043e\u0441\u0438\u0442\u044c \u0442\u043e\u0433\u043e \u0436 \u0441\u0430\u043c\u043e\u0433\u043e \u0432\u0456\u0434 \u043a\u043e\u0436\u043d\u043e\u0433\u043e \u043d\u0430 \u0437\u0435\u043c\u043b\u0456 \u0441\u044c\u043e\u0433\u043e\u0434\u043d\u0456.\n\u0414\u0435 \u0442\u0438?\n\u0412\u0456\u043d \u043d\u0435 \u043f\u0438\u0442\u0430\u0454, \u0434\u0435 \u0442\u0438 \u0437\u043d\u0430\u0445\u043e\u0434\u0438\u0448\u0441\u044f \u0444\u0456\u0437\u0438\u0447\u043d\u043e.\n\u0412\u0456\u043d \u043f\u0438\u0442\u0430\u0454: \u00ab\u0414\u0435 \u0442\u0432\u043e\u0454 \u0441\u0435\u0440\u0446\u0435?\u00bb\n\u0411\u043e \u043d\u0430\u0448\u0456 \u0441\u0435\u0440\u0446\u044f \u2014 \u0446\u0435 \u044f\u043a \u043a\u043e\u043c\u043f\u0430\u0441, \u044f\u043a\u0438\u0439 \u0432\u0435\u0434\u0435 \u043d\u0430\u0441 \u0441\u0442\u0435\u0436\u043a\u043e\u044e \u0434\u043e \u0442\u043e\u0433\u043e, \u0449\u043e \u043c\u0438 \u0446\u0456\u043d\u0443\u0454\u043c\u043e \u043d\u0430\u0439\u0431\u0456\u043b\u044c\u0448\u0435.\n\u041c\u0438 \u0433\u0443\u0431\u0438\u043c\u043e\u0441\u044f \u0456 \u043d\u0430\u0432\u0456\u0442\u044c \u043d\u0435 \u0443\u0441\u0432\u0456\u0434\u043e\u043c\u043b\u044e\u0454\u043c\u043e \u0446\u044c\u043e\u0433\u043e, \u0431\u043e \u0433\u0440\u0456\u0445 \u043f\u0456\u0434\u0441\u0442\u0443\u043f\u043d\u0438\u0439.\n\u041d\u0430\u043c \u043f\u043e\u0442\u0440\u0456\u0431\u043d\u0430 \u0411\u043e\u0436\u0430 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0430, \u0449\u043e\u0431 \u043f\u043e\u0431\u0430\u0447\u0438\u0442\u0438, \u0449\u043e \u0432\u0456\u0434\u0431\u0443\u0432\u0430\u0454\u0442\u044c\u0441\u044f \u0432\u0441\u0435\u0440\u0435\u0434\u0438\u043d\u0456 \u043d\u0430\u0441.\n\u0414\u0430\u0432\u0430\u0439\u0442\u0435 \u043f\u0440\u043e\u0447\u0438\u0442\u0430\u0454\u043c\u043e \u0440\u0430\u0437\u043e\u043c \u041f\u0441\u0430\u043b\u043e\u043c 139:23\u201324 \u044f\u043a \u043c\u043e\u043b\u0438\u0442\u0432\u0443:\n\u0412\u0421\u0406: 23 \u00ab\u0414\u043e\u0441\u043b\u0456\u0434\u0438 \u043c\u0435\u043d\u0435, \u0411\u043e\u0436\u0435, \u0456 \u043f\u0456\u0437\u043d\u0430\u0439 \u043c\u043e\u0454 \u0441\u0435\u0440\u0446\u0435!\u00bb\n\u0412\u0438\u043f\u0440\u043e\u0431\u0443\u0439 \u043c\u0435\u043d\u0435 \u0442\u0430 \u0434\u0456\u0437\u043d\u0430\u0439\u0441\u044f \u043c\u043e\u0457 \u0434\u0443\u043c\u043a\u0438!\n24 \u0406 \u043f\u043e\u0434\u0438\u0432\u0438\u0441\u044c, \u0447\u0438 \u0454 \u0432 \u043c\u0435\u043d\u0456 \u044f\u043a\u0438\u0439\u0441\u044c \u043b\u0438\u0445\u0438\u0439 \u0448\u043b\u044f\u0445,\n\u0456 \u0432\u0435\u0434\u0438 \u043c\u0435\u043d\u0435 \u0434\u043e\u0440\u043e\u0433\u043e\u044e \u0432\u0456\u0447\u043d\u043e\u044e!\u00bb\n\n\u0411\u0435\u0437 \u0411\u043e\u0436\u043e\u0457 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0438 \u043c\u0438 \u043d\u0435 \u043f\u0456\u0434\u0435\u043c\u043e \u00ab\u0432\u0456\u0447\u043d\u043e\u044e \u0434\u043e\u0440\u043e\u0433\u043e\u044e\u00bb.\n\u041c\u0438 \u0431\u0443\u0434\u0435\u043c\u043e \u0431\u0456\u0433\u0442\u0438 \u0432 \u0445\u0438\u0431\u043d\u043e\u043c\u0443 \u043d\u0430\u043f\u0440\u044f\u043c\u043a\u0443, \u043f\u0440\u0430\u0433\u043d\u0443\u0447\u0438 \u0442\u043e\u0433\u043e, \u0449\u043e \u0432\u0456\u0434\u0434\u0430\u043b\u044f\u0454 \u043d\u0430\u0441 \u0432\u0456\u0434 \u0411\u043e\u0436\u043e\u0433\u043e \u0441\u0435\u0440\u0446\u044f.\n\u0410\u043b\u0435 \u0411\u043e\u0433 \u0442\u0430\u043a\u0438\u0439 \u0434\u043e\u0431\u0440\u0438\u0439, \u0449\u043e \u043d\u0435 \u043f\u0440\u043e\u0441\u0442\u043e \u0441\u043f\u043e\u0441\u0442\u0435\u0440\u0456\u0433\u0430\u0454, \u044f\u043a \u043c\u0438 \u0431\u043b\u0443\u043a\u0430\u0454\u043c\u043e \u0442\u0430 \u0433\u0443\u0431\u0438\u043c\u043e\u0441\u044f.\n\u041d\u0430\u0442\u043e\u043c\u0456\u0441\u0442\u044c, \u0432\u0456\u043d \u0448\u0443\u043a\u0430\u0454 \u0421\u0432\u043e\u0457\u0445 \u0437\u0430\u0433\u0443\u0431\u043b\u0435\u043d\u0438\u0445 \u043e\u0432\u0435\u0446\u044c.\n\u0412\u0456\u043d \u043f\u0440\u0438\u0445\u043e\u0434\u0438\u0442\u044c \u0434\u043e \u043d\u0430\u0441 \u0456 \u043f\u0440\u043e\u043f\u043e\u043d\u0443\u0454 \u0448\u043b\u044f\u0445 \u0432\u0442\u0435\u0447\u0456 \u0442\u0430 \u043f\u043e\u0440\u044f\u0442\u0443\u043d\u043a\u0443.\n\u0417\u043d\u043e\u0432\u0443 \u043f\u043e\u0434\u0438\u0432\u0456\u0442\u044c\u0441\u044f \u043d\u0430 2 \u0422\u0438\u043c\u043e\u0444\u0456\u044f 2:25\u0431-26:\n25b \u00ab\u041c\u043e\u0436\u043b\u0438\u0432\u043e, \u0411\u043e\u0433 \u0434\u0430\u0440\u0443\u0454 \u0457\u043c \u043f\u043e\u043a\u0430\u044f\u043d\u043d\u044f, \u044f\u043a\u0435 \u0432\u0435\u0434\u0435 \u0434\u043e \u043f\u0456\u0437\u043d\u0430\u043d\u043d\u044f \u0456\u0441\u0442\u0438\u043d\u0438,\n26 \u0449\u043e\u0431 \u0432\u043e\u043d\u0438 \u043c\u043e\u0433\u043b\u0438 \u043e\u0442\u044f\u043c\u0438\u0442\u0438\u0441\u044f \u0442\u0430 \u0432\u0438\u0440\u0432\u0430\u0442\u0438\u0441\u044f \u0437 \u043f\u0430\u0441\u0442\u043a\u0438 \u0434\u0438\u044f\u0432\u043e\u043b\u0430, \u0431\u0443\u0434\u0443\u0447\u0438 \u0441\u0445\u043e\u043f\u043b\u0435\u043d\u0456 \u043d\u0438\u043c, \u0449\u043e\u0431 \u0447\u0438\u043d\u0438\u0442\u0438 \u0439\u043e\u0433\u043e \u0432\u043e\u043b\u044e\u00bb.\n\n\u0427\u0438 \u0437\u043d\u0430\u0454\u0442\u0435 \u0432\u0438, \u0449\u043e \u043c\u043e\u0436\u043d\u0430 \u0432\u0456\u0434\u0447\u0443\u0432\u0430\u0442\u0438 \u0441\u0435\u0431\u0435 \u043f\u043e\u0432\u043d\u0456\u0441\u0442\u044e \u0432\u0456\u043b\u044c\u043d\u0438\u043c, \u043a\u043e\u043b\u0438 \u043d\u0430\u0441\u043f\u0440\u0430\u0432\u0434\u0456 \u0432\u0438 \u0432 \u043f\u0430\u0441\u0442\u0446\u0456 \u0433\u0440\u0456\u0445\u0430 \u0442\u0430 \u0434\u0438\u044f\u0432\u043e\u043b\u0430?\n\u0413\u0440\u0456\u0445 \u0432\u0456\u0434\u0447\u0443\u0432\u0430\u0454\u0442\u044c\u0441\u044f \u044f\u043a \u0441\u0432\u043e\u0431\u043e\u0434\u0430, \u0430\u043b\u0435 \u0432\u0456\u043d \u043d\u0430\u0432\u043f\u0430\u043a\u0438.\n\u041f\u0430\u0441\u0442\u043a\u0430 \u0432\u0438\u0433\u043b\u044f\u0434\u0430\u0454 \u043e\u0441\u044c \u0442\u0430\u043a.\n\u0426\u0435 \u043f\u0430\u0441\u0442\u043a\u0430, \u044f\u043a\u0430 \u043b\u043e\u0432\u0438\u0442\u044c \u0442\u0432\u0430\u0440\u0438\u043d\u0443, \u0449\u043e \u0432\u0456\u043b\u044c\u043d\u043e \u0431\u0456\u0433\u043b\u0430 \u0441\u0442\u0435\u0436\u043a\u043e\u044e, \u0430 \u043f\u043e\u0442\u0456\u043c \u0440\u0430\u043f\u0442\u043e\u0432\u043e \u043e\u043f\u0438\u043d\u0438\u043b\u0430\u0441\u044f \u0432 \u043d\u0435\u0431\u0435\u0437\u043f\u0435\u0446\u0456.\n\u0421\u0430\u0442\u0430\u043d\u0430 \u0440\u043e\u0437\u043c\u0456\u0449\u0443\u0454 \u0431\u0440\u0435\u0445\u043d\u044e, \u043d\u0435\u043c\u043e\u0432 \u0437\u043d\u0430\u043a\u0438, \u043d\u0430 \u043c\u0430\u0440\u0430\u0444\u043e\u043d\u0441\u044c\u043a\u0456\u0439 \u0442\u0440\u0430\u0441\u0456, \u0449\u043e\u0431 \u043e\u0431\u0434\u0443\u0440\u0438\u0442\u0438 \u0442\u0430 \u0437\u0430\u043c\u0430\u043d\u0438\u0442\u0438 \u043d\u0430\u0441 \u0443 \u043f\u0430\u0441\u0442\u043a\u0443.\n\u0421\u0430\u0442\u0430\u043d\u0430 \u0445\u043e\u0447\u0435, \u0449\u043e\u0431 \u043c\u0438 \u0433\u043d\u0430\u043b\u0438\u0441\u044f \u0437\u0430 \u0437\u0430\u0434\u043e\u0432\u043e\u043b\u0435\u043d\u043d\u044f\u043c, \u0432\u043b\u0430\u0434\u043e\u044e, \u043f\u043e\u043f\u0443\u043b\u044f\u0440\u043d\u0456\u0441\u0442\u044e, \u043c\u0430\u0439\u043d\u043e\u043c \u0442\u0430 \u0433\u043e\u0440\u0434\u0456\u0441\u0442\u044e.\n\u0426\u0456 \u0456\u0434\u043e\u043b\u0438 \u043e\u0431\u0456\u0446\u044f\u044e\u0442\u044c \u043d\u0430\u043c \u0441\u0432\u043e\u0431\u043e\u0434\u0443, \u0430 \u0441\u0432\u043e\u0431\u043e\u0434\u0430 \u2014 \u0446\u0435 \u0442\u0435, \u0447\u043e\u0433\u043e \u043c\u0438 \u0434\u0443\u0436\u0435 \u043f\u0440\u0430\u0433\u043d\u0435\u043c\u043e.\n\u041d\u0430 \u0436\u0430\u043b\u044c, \u043c\u0438 \u0432\u0432\u0430\u0436\u0430\u0454\u043c\u043e, \u0449\u043e \u0442\u0430\u043a\u0456 \u0440\u0435\u0447\u0456 \u043c\u043e\u0436\u0443\u0442\u044c \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0442\u0438 \u043d\u0430\u043c \u043f\u043e\u0447\u0443\u0432\u0430\u0442\u0438\u0441\u044f \u0437\u0430\u0434\u043e\u0432\u043e\u043b\u0435\u043d\u0438\u043c\u0438, \u0431\u0435\u0437\u043f\u0435\u0447\u043d\u0438\u043c\u0438, \u0449\u0430\u0441\u043b\u0438\u0432\u0438\u043c\u0438.\n\u0410\u043b\u0435 \u0446\u0456 \u0456\u0434\u043e\u043b\u0438 \u2014 \u043f\u0430\u0441\u0442\u043a\u0438, \u0449\u043e \u0432\u0456\u0434\u0432\u043e\u0434\u044f\u0442\u044c \u043d\u0430\u0441 \u0432\u0456\u0434 \u0411\u043e\u0433\u0430 \u0442\u0430 \u0448\u043b\u044f\u0445\u0443 \u0441\u043f\u0440\u0430\u0432\u0436\u043d\u044c\u043e\u0433\u043e \u0436\u0438\u0442\u0442\u044f.\n\u0421\u0430\u0442\u0430\u043d\u0430 \u0445\u043e\u0447\u0435 \u043f\u0440\u0438\u0445\u043e\u0432\u0430\u0442\u0438 \u0432\u0456\u0434 \u043d\u0430\u0441 \u0448\u043b\u044f\u0445 \u0436\u0438\u0442\u0442\u044f, \u043a\u0430\u0436\u0443\u0447\u0438:\n\u00ab\u0406\u0434\u0438 \u0446\u0438\u043c \u0448\u043b\u044f\u0445\u043e\u043c \u0434\u043e \u043f\u0435\u0440\u0435\u043c\u043e\u0433\u0438 \u0442\u0430 \u0449\u0430\u0441\u0442\u044f!\u00bb\n\u0422\u0430\u043a, \u0446\u0435 \u0442\u043e\u0439 \u0448\u043b\u044f\u0445! \u0406\u0434\u0456\u0442\u044c \u0437\u0430 \u043c\u043d\u043e\u044e!\n\n\u041e\u0442\u0436\u0435, \u044f\u043a \u0442\u0432\u0430\u0440\u0438\u043d\u0430 \u043c\u043e\u0436\u0435 \u0432\u0438\u0431\u0440\u0430\u0442\u0438\u0441\u044f \u0437 \u0442\u0430\u043a\u043e\u0457 \u043f\u0430\u0441\u0442\u043a\u0438?\n\u0427\u0438 \u0446\u0435 \u0449\u043e\u0441\u044c, \u0449\u043e \u0432\u0456\u043d \u043c\u043e\u0436\u0435 \u0437\u0440\u043e\u0431\u0438\u0442\u0438 \u0441\u0430\u043c?\n\u041d\u0456, \u043a\u0440\u043e\u043b\u0438\u043a \u0431\u0435\u0437\u043f\u043e\u0440\u0430\u0434\u043d\u0438\u0439.\n\u0419\u043e\u043c\u0443 \u043f\u043e\u0442\u0440\u0456\u0431\u0435\u043d \u0445\u0442\u043e\u0441\u044c \u0440\u043e\u0437\u0443\u043c\u043d\u0456\u0448\u0438\u0439 \u0456 \u0441\u0438\u043b\u044c\u043d\u0456\u0448\u0438\u0439, \u0449\u043e\u0431 \u043f\u0440\u0438\u0439\u0442\u0438 \u0456 \u0432\u0438\u0442\u044f\u0433\u043d\u0443\u0442\u0438 \u0439\u043e\u0433\u043e \u0437 \u043f\u0430\u0441\u0442\u043a\u0438.\n\u041d\u0430\u043c \u0442\u0430\u043a\u043e\u0436 \u043f\u043e\u0442\u0440\u0456\u0431\u0435\u043d \u0445\u0442\u043e\u0441\u044c \u0440\u043e\u0437\u0443\u043c\u043d\u0456\u0448\u0438\u0439 \u0456 \u0441\u0438\u043b\u044c\u043d\u0456\u0448\u0438\u0439, \u0449\u043e\u0431 \u043d\u0430\u0441 \u0432\u0440\u044f\u0442\u0443\u0432\u0430\u0442\u0438.\n\u0426\u0435 \u043d\u0430\u0439\u0432\u0430\u0436\u043b\u0438\u0432\u0456\u0448\u0438\u0439 \u043c\u043e\u043c\u0435\u043d\u0442, \u043d\u0430 \u044f\u043a\u0438\u0439 \u044f \u0445\u043e\u0447\u0443, \u0449\u043e\u0431 \u0432\u0438 \u0437\u0432\u0435\u0440\u043d\u0443\u043b\u0438 \u0443\u0432\u0430\u0433\u0443 \u0432 \u0446\u044c\u043e\u043c\u0443 \u0432\u0456\u0440\u0448\u0456.\n\u041d\u0430\u043c \u043f\u043e\u0442\u0440\u0456\u0431\u0435\u043d \u0420\u044f\u0442\u0456\u0432\u043d\u0438\u043a, \u0431\u043e \u043c\u0438 \u043d\u0435 \u043c\u043e\u0436\u0435\u043c\u043e \u0432\u0440\u044f\u0442\u0443\u0432\u0430\u0442\u0438 \u0441\u0435\u0431\u0435 \u0441\u0430\u043c\u0456 \u0447\u0438 \u043d\u0430\u0432\u0456\u0442\u044c \u0437\u0432\u0435\u0440\u043d\u0443\u0442\u0438\u0441\u044f \u0434\u043e \u0411\u043e\u0433\u0430.\n\u0414\u0443\u0445\u043e\u0432\u043d\u043e \u043c\u0435\u0440\u0442\u0432\u0456 \u0441\u0435\u0440\u0446\u044f \u043d\u0435 \u043c\u043e\u0436\u0443\u0442\u044c \u043e\u0431\u0440\u0430\u0442\u0438 \u0436\u0438\u0442\u0442\u044f.\n\u041f\u043e\u0434\u0438\u0432\u0456\u0442\u044c\u0441\u044f, \u0449\u043e \u043d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0443 25-\u043c\u0443 \u0432\u0456\u0440\u0448\u0456:\n\u00ab\u041c\u043e\u0436\u043b\u0438\u0432\u043e, \u0411\u043e\u0433 \u0434\u0430\u0440\u0443\u0454 \u0457\u043c \u043f\u043e\u043a\u0430\u044f\u043d\u043d\u044f\u00bb.\n\n\u0413\u0440\u0430\u043d\u0442 \u2013 \u0446\u0435 \u0431\u0435\u0437\u043a\u043e\u0448\u0442\u043e\u0432\u043d\u0438\u0439 \u043f\u043e\u0434\u0430\u0440\u0443\u043d\u043e\u043a.\n\u0411\u043e\u0433 \u0434\u0430\u0432 \u043c\u0435\u043d\u0456 \u0434\u0430\u0440 \u043f\u043e\u043a\u0430\u044f\u043d\u043d\u044f 30 \u0440\u043e\u043a\u0456\u0432 \u0442\u043e\u043c\u0443.\n\u041f\u0440\u043e\u0442\u044f\u0433\u043e\u043c 10 \u0440\u043e\u043a\u0456\u0432 \u044f \u043a\u0430\u0437\u0430\u0432, \u0449\u043e \u0443 \u0432\u0441\u0435\u0441\u0432\u0456\u0442\u0456 \u043d\u0435\u043c\u0430\u0454 \u0411\u043e\u0433\u0430.\n\u0410\u043b\u0435 \u043e\u0441\u043a\u0456\u043b\u044c\u043a\u0438 \u0411\u043e\u0433 \u0434\u043e\u0431\u0440\u0438\u0439, \u0432\u0456\u043d \u043f\u043e\u043a\u0430\u0437\u0430\u0432 \u043c\u0435\u043d\u0456, \u0449\u043e \u043f\u0438\u0432\u043e, \u0436\u0456\u043d\u043a\u0438 \u0442\u0430 \u0437\u0435\u043c\u043d\u0438\u0439 \u0443\u0441\u043f\u0456\u0445 \u043d\u0456\u043a\u043e\u043b\u0438 \u043d\u0435 \u0437\u043c\u043e\u0436\u0443\u0442\u044c \u0437\u0430\u0434\u043e\u0432\u043e\u043b\u044c\u043d\u0438\u0442\u0438 \u0431\u0430\u0436\u0430\u043d\u043d\u044f \u043c\u043e\u0433\u043e \u0441\u0435\u0440\u0446\u044f.\n\u041e\u0441\u044c \u0449\u043e \u043e\u0437\u043d\u0430\u0447\u0430\u0454 \u0444\u0440\u0430\u0437\u0430 \u00ab\u0441\u0445\u0430\u043c\u0435\u043d\u0443\u0442\u0438\u0441\u044f\u00bb \u0443 \u0432\u0456\u0440\u0448\u0456 26.\n\u041a\u043e\u043b\u0438 \u0432\u0430\u0448\u0435 \u0432\u0456\u0434\u0447\u0443\u0442\u0442\u044f \u043d\u0430\u043f\u0440\u044f\u043c\u043a\u0443 \u043f\u043b\u0443\u0442\u0430\u0454\u0442\u044c\u0441\u044f, \u0432\u0438 \u0431\u0456\u0436\u0438\u0442\u0435 \u0432 \u043d\u0435\u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e\u043c\u0443 \u043d\u0430\u043f\u0440\u044f\u043c\u043a\u0443.\n\u041f\u0435\u0440\u0448\u0438\u0439 \u043a\u0440\u043e\u043a \u0434\u043e \u043f\u043e\u0448\u0443\u043a\u0443 \u0434\u043e\u0440\u043e\u0433\u0438 \u0434\u043e\u0434\u043e\u043c\u0443 \u2013 \u0446\u0435 \u0443\u0441\u0432\u0456\u0434\u043e\u043c\u0438\u0442\u0438, \u0449\u043e \u0432\u0438 \u0437\u0430\u0431\u043b\u0443\u043a\u0430\u043b\u0438.\n\u0414\u0435\u043d \u041c\u0430\u043a\u0434\u0430\u0443\u0435\u043b\u043b \u0431\u0443\u0432 \u043e\u0434\u043d\u0438\u043c \u0456\u0437 \u0431\u0456\u0433\u0443\u043d\u0456\u0432, \u044f\u043a\u0456 \u0432\u0442\u0440\u0430\u0442\u0438\u043b\u0438 \u043f\u0435\u0440\u0435\u043c\u043e\u0433\u0443 \u043d\u0430 \u0442\u043e\u043c\u0443 \u043c\u0430\u0440\u0430\u0444\u043e\u043d\u0456 \u0432 \u041f\u043e\u0440\u0442\u043b\u0435\u043d\u0434\u0456.\n\u0412\u0456\u043d \u0441\u043a\u0430\u0437\u0430\u0432: \u00ab\u042f \u0437\u0430\u0439\u0448\u043e\u0432 \u0437\u0430 \u0440\u0456\u0433 \u0456 \u043f\u043e\u0431\u0430\u0447\u0438\u0432 10 \u043b\u044e\u0434\u0435\u0439, \u044f\u043a\u0456 \u043f\u0440\u043e\u0441\u0442\u043e \u0441\u0442\u043e\u044f\u043b\u0438 \u043d\u0435\u0440\u0443\u0445\u043e\u043c\u043e\u2026\u00bb\n\u0412\u043e\u043d\u0438 \u0434\u0438\u0432\u0438\u043b\u0438\u0441\u044f \u043e\u0434\u043d\u0435 \u043d\u0430 \u043e\u0434\u043d\u043e\u0433\u043e \u0456 \u0434\u0443\u043c\u0430\u043b\u0438: \u00ab\u0413\u043c, \u0446\u0435 \u0437\u0434\u0430\u0454\u0442\u044c\u0441\u044f \u043d\u0435\u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u0438\u043c\u00bb.\n\n\u0406\u043d\u0448\u0438\u0439 \u0431\u0456\u0433\u0443\u043d, \u0417\u0430\u043a \u041a\u0430\u0441\u0442\u0435\u0440, \u0440\u043e\u0437\u043f\u043e\u0432\u0456\u0432, \u0449\u043e \u0432\u0456\u043d \u0432\u2018\u0457\u0445\u0430\u0432 \u0443 \u0442\u0443\u043d\u0435\u043b\u044c, \u0434\u0435 \u043f\u043e\u0432\u0437 \u043d\u044c\u043e\u0433\u043e \u043f\u0440\u043e\u043d\u043e\u0441\u0438\u043b\u0438\u0441\u044f \u0430\u0432\u0442\u043e\u043c\u043e\u0431\u0456\u043b\u0456 \u0437\u0456 \u0448\u0432\u0438\u0434\u043a\u0456\u0441\u0442\u044e 55 \u043c\u0438\u043b\u044c \u043d\u0430 \u0433\u043e\u0434\u0438\u043d\u0443.\n\u0421\u0430\u043c\u0435 \u0442\u043e\u0434\u0456 \u0432\u0456\u043d \u0437\u0440\u043e\u0437\u0443\u043c\u0456\u0432, \u0449\u043e \u0437\u0431\u0438\u0432\u0441\u044f \u0437\u0456 \u0448\u043b\u044f\u0445\u0443.\n\u041f\u0435\u0440\u0448 \u043d\u0456\u0436 \u0411\u043e\u0433 \u043f\u0440\u0438\u0432\u0456\u0432 \u043c\u0435\u043d\u0435 \u0434\u043e \u0442\u044f\u043c\u0438, \u044f \u0434\u0443\u043c\u0430\u0432, \u0449\u043e \u043c\u0430\u044e \u00ab\u043f\u0456\u0437\u043d\u0430\u043d\u043d\u044f \u0456\u0441\u0442\u0438\u043d\u0438\u00bb.\n\u041c\u043e\u044f \u0433\u043e\u0440\u0434\u0456\u0441\u0442\u044c \u043f\u0456\u0434\u043a\u0430\u0437\u0443\u0432\u0430\u043b\u0430 \u043c\u0435\u043d\u0456, \u0449\u043e \u044f \u043d\u0430 \u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e\u043c\u0443 \u0448\u043b\u044f\u0445\u0443, \u0456 \u043c\u0435\u043d\u0456 \u043d\u0435 \u043f\u043e\u0442\u0440\u0456\u0431\u0435\u043d \u0431\u0443\u0432 \u044f\u043a\u0438\u0439\u0441\u044c \u0411\u043e\u0433, \u0449\u043e\u0431 \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u044f\u0442\u0438 \u043c\u0435\u043d\u0435, \u0431\u043e \u044f \u0431\u0443\u0432 \u0442\u0430\u043a\u0438\u0439 \u0440\u043e\u0437\u0443\u043c\u043d\u0438\u0439.\n\u0417\u0430 \u0456\u0440\u043e\u043d\u0456\u0454\u044e \u0434\u043e\u043b\u0456, \u044f \u0431\u0443\u0432 \u043d\u0430\u0434\u0442\u043e \u0434\u0443\u0440\u043d\u0438\u0439, \u0449\u043e\u0431 \u043f\u043e\u0431\u0430\u0447\u0438\u0442\u0438 \u043e\u0431\u043c\u0430\u043d \u0421\u0430\u0442\u0430\u043d\u0438.\n\u042f \u043f\u043e\u0442\u0440\u0430\u043f\u0438\u0432 \u0443 \u0439\u043e\u0433\u043e \u043f\u0430\u0441\u0442\u043a\u0443 \u0431\u0440\u0435\u0445\u043d\u0456.\n\u042f \u043f\u043e\u0432\u0456\u0440\u0438\u0432 \u043e\u0431\u0456\u0446\u044f\u043d\u0446\u0456 \u0434\u0438\u044f\u0432\u043e\u043b\u0430, \u0449\u043e \u0437\u043d\u0430\u0439\u0434\u0443 \u0449\u0430\u0441\u0442\u044f, \u0432\u0442\u0456\u043a\u0430\u044e\u0447\u0438 \u0432\u0456\u0434 \u0411\u043e\u0433\u0430.\n\u0410\u043b\u0435 \u043f\u043e\u0442\u0456\u043c \u0411\u043e\u0433 \u0434\u0430\u0432 \u043c\u0435\u043d\u0456 \u0434\u0430\u0440 \u043f\u043e\u043a\u0430\u044f\u043d\u043d\u044f.\n\u0413\u0440\u0435\u0446\u044c\u043a\u0435 \u0441\u043b\u043e\u0432\u043e, \u0449\u043e \u0442\u0443\u0442 \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u043e\u0432\u0443\u0454\u0442\u044c\u0441\u044f \u0434\u043b\u044f \u043f\u043e\u0437\u043d\u0430\u0447\u0435\u043d\u043d\u044f \u043f\u043e\u043a\u0430\u044f\u043d\u043d\u044f, \u2014 \u043c\u0435\u0442\u0430\u043d\u043e\u0439\u044f.\n\u0426\u0435 \u043e\u0437\u043d\u0430\u0447\u0430\u0454 \u00ab\u0437\u043c\u0456\u043d\u0430 \u043c\u0438\u0441\u043b\u0435\u043d\u043d\u044f, \u0437\u043c\u0456\u043d\u0430 \u0436\u0438\u0442\u0442\u044f \u0442\u0430 \u0437\u043c\u0456\u043d\u0430 \u043c\u0435\u0442\u0438\u00bb.\n\u0406\u0441\u0443\u0441 \u0434\u0430\u0432 \u043c\u0435\u043d\u0456 \u043d\u043e\u0432\u0435 \u0441\u0435\u0440\u0446\u0435, \u0449\u043e\u0431 \u044f \u043c\u0456\u0433 \u00ab\u043f\u0440\u0438\u0437\u0438\u0432\u0430\u0442\u0438 \u0434\u043e \u0413\u043e\u0441\u043f\u043e\u0434\u0430 \u0432\u0456\u0434 \u0447\u0438\u0441\u0442\u043e\u0433\u043e \u0441\u0435\u0440\u0446\u044f\u00bb, \u044f\u043a \u0441\u043a\u0430\u0437\u0430\u043d\u043e \u0443 \u0432\u0456\u0440\u0448\u0456 22.\n\u0427\u0438\u0441\u0442\u0435 \u0441\u0435\u0440\u0446\u0435 \u2014 \u0446\u0435 \u0447\u0435\u0441\u043d\u0435 \u0441\u0435\u0440\u0446\u0435.\n\u0421\u0435\u0440\u0446\u0435, \u044f\u043a\u0435 \u043a\u043b\u0438\u0447\u0435 \u0434\u043e \u0411\u043e\u0433\u0430: \u00ab\u041c\u0435\u043d\u0456 \u0448\u043a\u043e\u0434\u0430 \u0437\u0430 \u0441\u0432\u0456\u0439 \u0433\u0440\u0456\u0445, \u0431\u0443\u0434\u044c \u043b\u0430\u0441\u043a\u0430, \u043f\u0440\u043e\u0441\u0442\u0438 \u043c\u0435\u043d\u0435\u00bb.\n\u0414\u043e\u043f\u043e\u043c\u043e\u0436\u0438 \u043c\u0435\u043d\u0456 \u0431\u0456\u0433\u0442\u0438 \u0434\u043e \u0442\u0435\u0431\u0435, \u0430 \u043d\u0435 \u0432\u0456\u0434 \u0442\u0435\u0431\u0435.\n\u041f\u0430\u0432\u043b\u043e \u043d\u0430\u043f\u0438\u0441\u0430\u0432 \u0443 \u041f\u043e\u0441\u043b\u0430\u043d\u043d\u0456 \u0434\u043e \u0420\u0438\u043c\u043b\u044f\u043d 10:9-11 \u0434\u0443\u0436\u0435 \u0447\u0456\u0442\u043a\u0435 \u043f\u043e\u044f\u0441\u043d\u0435\u043d\u043d\u044f \u0442\u043e\u0433\u043e, \u044f\u043a \u0432\u0438 \u043c\u043e\u0436\u0435\u0442\u0435 \u043d\u0430\u0432\u0435\u0440\u043d\u0443\u0442\u0438\u0441\u044f \u0434\u043e \u0411\u043e\u0433\u0430 \u0442\u0430 \u0431\u0443\u0442\u0438 \u0441\u043f\u0430\u0441\u0435\u043d\u043d\u0438\u043c\u0438.\n9 \u00ab\u042f\u043a\u0449\u043e \u0442\u0438 \u0443\u0441\u0442\u0430\u043c\u0438 \u0441\u0432\u043e\u0457\u043c\u0438 \u0432\u0438\u0437\u043d\u0430\u0432\u0430\u0442\u0438\u043c\u0435\u0448: \u201e\u0406\u0441\u0443\u0441 \u2014 \u0413\u043e\u0441\u043f\u043e\u0434\u044c\u201c, \u0456 \u0441\u0435\u0440\u0446\u0435\u043c \u0441\u0432\u043e\u0457\u043c \u0432\u0456\u0440\u0443\u0432\u0430\u0442\u0438\u043c\u0435\u0448, \u0449\u043e \u0411\u043e\u0433 \u0432\u043e\u0441\u043a\u0440\u0435\u0441\u0438\u0432 \u0419\u043e\u0433\u043e \u0437 \u043c\u0435\u0440\u0442\u0432\u0438\u0445, \u0442\u043e \u0431\u0443\u0434\u0435\u0448 \u0441\u043f\u0430\u0441\u0435\u043d\u043d\u0438\u0439\u00bb.\n10 \u0411\u043e \u0441\u0435\u0440\u0446\u0435\u043c \u0432\u0456\u0440\u0438\u0448 \u0456 \u0432\u0438\u043f\u0440\u0430\u0432\u0434\u043e\u0432\u0443\u0454\u0448\u0441\u044f, \u0430 \u0443\u0441\u0442\u0430\u043c\u0438 \u0432\u0438\u0437\u043d\u0430\u0454\u0448 \u0432\u0456\u0440\u0443 \u0456 \u0441\u043f\u0430\u0441\u0430\u0454\u0448\u0441\u044f.\n11 \u042f\u043a \u043a\u0430\u0436\u0435 \u041f\u0438\u0441\u0430\u043d\u043d\u044f: \u00ab\u0425\u0442\u043e \u0432\u0456\u0440\u0443\u0454 \u0432 \u041d\u044c\u043e\u0433\u043e, \u0442\u043e\u0439 \u043d\u0456\u043a\u043e\u043b\u0438 \u043d\u0435 \u0431\u0443\u0434\u0435 \u0437\u0430\u0441\u043e\u0440\u043e\u043c\u043b\u0435\u043d\u0438\u0439\u00bb.\n\n\u0427\u0438 \u0442\u0438 \u0441\u043f\u043e\u0432\u0456\u0434\u0443\u0432\u0430\u0432 \u0432\u0456\u0440\u0443 \u0441\u0432\u043e\u0457\u043c\u0438 \u0443\u0441\u0442\u0430\u043c\u0438, \u0449\u043e\u0431 \u0441\u043f\u0430\u0441\u0442\u0438\u0441\u044f?\n\u042f\u043a\u0449\u043e \u0432\u0438 \u0446\u044c\u043e\u0433\u043e \u043d\u0435 \u0437\u0440\u043e\u0431\u0438\u043b\u0438, \u0447\u0438 \u043d\u0435 \u0434\u0443\u043c\u0430\u0454\u0442\u0435 \u0432\u0438, \u0449\u043e \u0441\u044c\u043e\u0433\u043e\u0434\u043d\u0456 \u0431\u0443\u0432 \u0431\u0438 \u0447\u0443\u0434\u043e\u0432\u0438\u0439 \u0434\u0435\u043d\u044c, \u0449\u043e\u0431 \u0446\u0435 \u0437\u0440\u043e\u0431\u0438\u0442\u0438?\n\u0421\u0432\u044f\u0442\u0438\u0439 \u0414\u0443\u0445 \u0442\u0443\u0442, \u0441\u0435\u0440\u0435\u0434 \u043d\u0430\u0441, \u0456, \u043c\u043e\u0436\u043b\u0438\u0432\u043e, \u0412\u0456\u043d \u0448\u0435\u043f\u043e\u0447\u0435 \u0432\u0430\u0448\u043e\u043c\u0443 \u0441\u0435\u0440\u0446\u044e:\n\u00ab\u0412\u0456\u0434\u0432\u0435\u0440\u043d\u0438\u0441\u044f \u0432\u0456\u0434 \u0448\u043b\u044f\u0445\u0443 \u0433\u0440\u0456\u0445\u0430 \u0439 \u0441\u043c\u0435\u0440\u0442\u0456!\u00bb\n\u041e\u0431\u0435\u0440\u0456\u0442\u044c \u043d\u043e\u0432\u0435 \u0436\u0438\u0442\u0442\u044f \u0442\u0430 \u043d\u043e\u0432\u0438\u0439 \u043d\u0430\u043f\u0440\u044f\u043c\u043e\u043a, \u043f\u0440\u043e\u0433\u043e\u043b\u043e\u0441\u0438\u0432\u0448\u0438, \u0449\u043e \u00ab\u0406\u0441\u0443\u0441 \u2014 \u0413\u043e\u0441\u043f\u043e\u0434\u044c!\u00bb\n\n\u041f\u0430\u0432\u043b\u043e \u0432\u0436\u0435 \u043f\u0438\u0441\u0430\u0432 \u043f\u0440\u043e \u0446\u0435\u0439 \u043d\u043e\u0432\u0438\u0439 \u043d\u0430\u043f\u0440\u044f\u043c\u043e\u043a.\n\u0426\u0435 \u0431\u0443\u043b\u043e \u0432 \u043b\u0438\u0441\u0442\u0456 \u0434\u043e \u0442\u0456\u0454\u0457 \u0436 \u0446\u0435\u0440\u043a\u0432\u0438 \u0432 \u0415\u0444\u0435\u0441\u0456, \u0434\u0435 \u0422\u0438\u043c\u043e\u0444\u0456\u0439 \u0437\u0430\u0440\u0430\u0437 \u0441\u043b\u0443\u0436\u0438\u0442\u044c \u043f\u0430\u0441\u0442\u043e\u0440\u043e\u043c.\n\u041f\u043e\u0441\u043b\u0443\u0445\u0430\u0439\u0442\u0435, \u0449\u043e \u041f\u0430\u0432\u043b\u043e \u043d\u0430\u043f\u0438\u0441\u0430\u0432 \u0445\u0440\u0438\u0441\u0442\u0438\u044f\u043d\u0430\u043c \u0443 \u041f\u043e\u0441\u043b\u0430\u043d\u043d\u0456 \u0434\u043e \u0415\u0444\u0435\u0441\u044f\u043d 2:1-5 \u043f\u0440\u043e \u0442\u0435, \u0449\u043e \u0411\u043e\u0433 \u0437\u0440\u043e\u0431\u0438\u0432, \u0449\u043e\u0431 \u0434\u0430\u0442\u0438 \u0457\u043c \u043d\u043e\u0432\u0435 \u0436\u0438\u0442\u0442\u044f \u0442\u0430 \u043d\u043e\u0432\u0438\u0439 \u043d\u0430\u043f\u0440\u044f\u043c\u043e\u043a:\n1 \u00ab\u0406 \u0432\u0438 \u0431\u0443\u043b\u0438 \u043c\u0435\u0440\u0442\u0432\u0456 \u0447\u0435\u0440\u0435\u0437 \u043f\u0440\u043e\u0432\u0438\u043d\u0438 \u0442\u0430 \u0433\u0440\u0456\u0445\u0438\n2 \u0443 \u044f\u043a\u0438\u0445 \u0432\u0438 \u043a\u043e\u043b\u0438\u0441\u044c \u0445\u043e\u0434\u0438\u043b\u0438, \u0439\u0434\u0443\u0447\u0438 \u0437\u0430 \u0441\u0432\u0456\u0442\u0441\u044c\u043a\u0438\u043c\u0438 \u0448\u043b\u044f\u0445\u0430\u043c\u0438 \u0446\u044c\u043e\u0433\u043e, \u043d\u0430\u0441\u043b\u0456\u0434\u0443\u044e\u0447\u0438 \u043a\u043d\u044f\u0437\u044f, \u0449\u043e \u043f\u0430\u043d\u0443\u0454 \u0432 \u043f\u043e\u0432\u0456\u0442\u0440\u0456, \u0434\u0443\u0445\u0430, \u0449\u043e \u0442\u0435\u043f\u0435\u0440 \u0434\u0456\u0454 \u0432 \u0441\u0438\u043d\u0430\u0445 \u043d\u0435\u043f\u043e\u0441\u043b\u0443\u0445\u0443,\n3 \u043c\u0456\u0436 \u044f\u043a\u0438\u043c\u0438 \u043c\u0438 \u0432\u0441\u0456 \u043a\u043e\u043b\u0438\u0441\u044c \u0436\u0438\u043b\u0438 \u0432 \u043f\u0440\u0438\u0441\u0442\u0440\u0430\u0441\u0442\u044f\u0445 \u043d\u0430\u0448\u043e\u0433\u043e \u0442\u0456\u043b\u0430, \u0432\u0438\u043a\u043e\u043d\u0443\u044e\u0447\u0438 \u043f\u043e\u0436\u0430\u0434\u043b\u0438\u0432\u043e\u0441\u0442\u0456 \u0442\u0456\u043b\u0430 \u0442\u0430 \u0440\u043e\u0437\u0443\u043c\u0443, \u0456 \u0431\u0443\u043b\u0438 \u0437 \u043f\u0440\u0438\u0440\u043e\u0434\u0438 \u0434\u0456\u0442\u044c\u043c\u0438 \u0433\u043d\u0456\u0432\u0443, \u044f\u043a \u0456 \u0440\u0435\u0448\u0442\u0430 \u043b\u044e\u0434\u0435\u0439.\n4 \u0411\u043e\u0433 \u0436\u0435, \u0431\u0430\u0433\u0430\u0442\u0438\u0439 \u043d\u0430 \u043c\u0438\u043b\u043e\u0441\u0435\u0440\u0434\u044f, \u0447\u0435\u0440\u0435\u0437 \u0432\u0435\u043b\u0438\u043a\u0443 \u043b\u044e\u0431\u043e\u0432, \u044f\u043a\u043e\u044e \u0412\u0456\u043d \u043f\u043e\u043b\u044e\u0431\u0438\u0432 \u043d\u0430\u0441,\n5 \u043d\u0430\u0432\u0456\u0442\u044c \u043a\u043e\u043b\u0438 \u043c\u0438 \u0431\u0443\u043b\u0438 \u043c\u0435\u0440\u0442\u0432\u0456 \u0447\u0435\u0440\u0435\u0437 \u043f\u0440\u043e\u0432\u0438\u043d\u0438 \u043d\u0430\u0448\u0456, \u043e\u0436\u0438\u0432\u0438\u0432 \u043d\u0430\u0441 \u0440\u0430\u0437\u043e\u043c \u0456\u0437 \u0425\u0440\u0438\u0441\u0442\u043e\u043c \u2013 \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0442\u0442\u044e \u0432\u0438 \u0441\u043f\u0430\u0441\u0435\u043d\u0456!\n\n\u00ab\u0410\u043b\u0435 \u0411\u043e\u0433\u00bb \u2013 \u0446\u0435 \u0434\u0432\u0430 \u043d\u0430\u0439\u043f\u0440\u0435\u043a\u0440\u0430\u0441\u043d\u0456\u0448\u0456 \u0441\u043b\u043e\u0432\u0430, \u044f\u043a\u0456 \u0431\u0443\u0434\u044c-\u043a\u043e\u043b\u0438 \u0433\u043e\u0432\u043e\u0440\u0438\u043b\u0438.\n\u041f\u0430\u0432\u043b\u043e \u043d\u0430\u0433\u0430\u0434\u0443\u0454 \u0432\u0456\u0440\u0443\u044e\u0447\u0438\u043c \u0432 \u0415\u0444\u0435\u0441\u0456, \u0449\u043e \u043a\u043e\u043b\u0438\u0441\u044c \u0432\u043e\u043d\u0438 \u0431\u0443\u043b\u0438 \u0432 \u043f\u0430\u0441\u0442\u0446\u0456 \u0442\u0430 \u0431\u0435\u0437\u043f\u043e\u0440\u0430\u0434\u043d\u0456, \u044f\u043a \u0442\u043e\u0439 \u043a\u0440\u043e\u043b\u0438\u043a \u0443 \u0441\u0438\u043b\u044c\u0446\u0456.\n\u0410\u043b\u0435 \u0411\u043e\u0433 \u0432\u0442\u0440\u0443\u0442\u0438\u0432\u0441\u044f, \u0449\u043e\u0431 \u0441\u043f\u0430\u0441\u0442\u0438 \u0457\u0445 \u043b\u0438\u0448\u0435 \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0442\u0442\u044e, \u043b\u0438\u0448\u0435 \u0447\u0435\u0440\u0435\u0437 \u0432\u0456\u0440\u0443, \u043b\u0438\u0448\u0435 \u0443 \u0425\u0440\u0438\u0441\u0442\u0456.\n\u0411\u0443\u0434\u044c-\u0445\u0442\u043e \u043c\u043e\u0436\u0435 \u0431\u0443\u0442\u0438 \u0441\u043f\u0430\u0441\u0435\u043d\u043d\u0438\u043c, \u044f\u043a\u0449\u043e \u0432\u0456\u0440\u0438\u0442\u044c, \u0449\u043e \u0436\u0435\u0440\u0442\u0432\u0430 \u0425\u0440\u0438\u0441\u0442\u0430 \u043d\u0430 \u0445\u0440\u0435\u0441\u0442\u0456 \u0431\u0443\u043b\u0430 \u0437\u0430 \u043d\u044c\u043e\u0433\u043e, \u0449\u043e\u0431 \u043e\u0447\u0438\u0441\u0442\u0438\u0442\u0438 \u0439\u043e\u0433\u043e \u0432\u0456\u0434 \u0433\u0440\u0456\u0445\u0430 \u0442\u0430 \u0441\u043e\u0440\u043e\u043c\u0443.\n\u041a\u043e\u043b\u0438 \u0432\u0438 \u0432 \u0446\u0435 \u0432\u0456\u0440\u0438\u0442\u0435, \u0432\u0438 \u043e\u0442\u0440\u0438\u043c\u0443\u0454\u0442\u0435 \u043d\u043e\u0432\u0435 \u0436\u0438\u0442\u0442\u044f, \u0456 \u0406\u0441\u0443\u0441 \u0441\u0442\u0430\u0432\u0438\u0442\u044c \u0432\u0430\u0441 \u043d\u0430 \u043d\u043e\u0432\u0438\u0439 \u0448\u043b\u044f\u0445.\n\u041a\u0456\u043b\u044c\u043a\u0430 \u0432\u0456\u0440\u0448\u0456\u0432 \u0434\u0430\u043b\u0456 \u0432 \u041f\u043e\u0441\u043b\u0430\u043d\u043d\u0456 \u0434\u043e \u0415\u0444\u0435\u0441\u044f\u043d 2:8 \u041f\u0430\u0432\u043b\u043e \u0433\u043e\u0432\u043e\u0440\u0438\u0442\u044c \u043f\u0440\u043e \u0446\u0435\u0439 \u043d\u043e\u0432\u0438\u0439 \u043d\u0430\u043f\u0440\u044f\u043c\u043e\u043a.\n\u041f\u0440\u043e\u0447\u0438\u0442\u0430\u0439\u0442\u0435 \u0446\u0435 \u0440\u0430\u0437\u043e\u043c \u0437\u0456 \u043c\u043d\u043e\u044e:\n\u0412\u0421\u0406: 10 \u00ab\u0411\u043e \u043c\u0438 \u0419\u043e\u0433\u043e \u0442\u0432\u043e\u0440\u0456\u043d\u043d\u044f, \u0441\u0442\u0432\u043e\u0440\u0435\u043d\u0456 \u0432 \u0425\u0440\u0438\u0441\u0442\u0456 \u0406\u0441\u0443\u0441\u0456 \u043d\u0430 \u0434\u043e\u0431\u0440\u0456 \u0434\u0456\u043b\u0430, \u044f\u043a\u0456 \u0411\u043e\u0433 \u043d\u0430\u043f\u0435\u0440\u0435\u0434 \u043f\u0440\u0438\u0433\u043e\u0442\u0443\u0432\u0430\u0432, \u0449\u043e\u0431 \u043c\u0438 \u0432 \u043d\u0438\u0445 \u0447\u0438\u043d\u0438\u043b\u0438\u00bb.\n\n\u041d\u0430 \u0437\u0430\u0432\u0435\u0440\u0448\u0435\u043d\u043d\u044f \u0446\u044c\u043e\u0433\u043e \u043f\u043e\u0441\u043b\u0430\u043d\u043d\u044f \u0434\u0430\u0432\u0430\u0439\u0442\u0435 \u0440\u043e\u0437\u0433\u043b\u044f\u043d\u0435\u043c\u043e, \u044f\u043a \u0446\u0435 \u2014 \u0445\u043e\u0434\u0438\u0442\u0438 \u0443 \u0434\u043e\u0431\u0440\u0438\u0445 \u0434\u0456\u043b\u0430\u0445.\n\u041f\u0430\u043c\u2019\u044f\u0442\u0430\u0439\u0442\u0435, \u0449\u043e \u041f\u0430\u0432\u043b\u043e \u043f\u0438\u0448\u0435 \u0422\u0438\u043c\u043e\u0444\u0456\u044e, \u0434\u0430\u044e\u0447\u0438 \u0439\u043e\u043c\u0443 \u043f\u043e\u0440\u0430\u0434\u0438 \u0449\u043e\u0434\u043e \u0432\u0438\u0431\u043e\u0440\u0443 \u0442\u0430 \u043d\u0430\u0432\u0447\u0430\u043d\u043d\u044f \u0432\u0447\u0438\u0442\u0435\u043b\u0456\u0432 \u0411\u0456\u0431\u043b\u0456\u0457.\n\u0406 \u043d\u0430\u0448\u0430 \u043c\u0456\u0441\u0456\u044f \u044f\u043a \u0432\u0456\u0440\u0443\u044e\u0447\u0438\u0445 \u2014 \u0434\u0456\u043b\u0438\u0442\u0438\u0441\u044f \u0414\u043e\u0431\u0440\u043e\u044e \u041d\u043e\u0432\u0438\u043d\u043e\u044e \u0404\u0432\u0430\u043d\u0433\u0435\u043b\u0456\u044f \u0437 \u043b\u044e\u0434\u044c\u043c\u0438 \u044f\u043a \u0431\u043b\u0438\u0437\u044c\u043a\u0438\u043c\u0438, \u0442\u0430\u043a \u0456 \u0434\u0430\u043b\u0435\u043a\u0438\u043c\u0438.\n\u0410\u043b\u0435 \u0449\u043e\u0431 \u0440\u043e\u0431\u0438\u0442\u0438 \u0446\u0435 \u0432\u0456\u0440\u043d\u043e, \u043c\u0438 \u043f\u043e\u0432\u0438\u043d\u043d\u0456 \u043c\u0430\u0442\u0438 \u0445\u0430\u0440\u0430\u043a\u0442\u0435\u0440, \u044f\u043a\u0438\u0439 \u041f\u0430\u0432\u043b\u043e \u043e\u043f\u0438\u0441\u0443\u0454 \u0443 \u0446\u0438\u0445 \u0432\u0456\u0440\u0448\u0430\u0445.\n\u041c\u0438 \u043d\u0435 \u043c\u043e\u0436\u0435\u043c\u043e \u0437\u043c\u0456\u043d\u0438\u0442\u0438 \u0441\u0435\u0440\u0446\u0435 \u0431\u0443\u0434\u044c-\u043a\u043e\u0433\u043e.\n\u0410\u043b\u0435 \u043c\u0438 \u043c\u043e\u0436\u0435\u043c\u043e \u0441\u043a\u0430\u0437\u0430\u0442\u0438 \u0457\u043c \u043f\u0440\u0430\u0432\u0434\u0443 \u043d\u0456\u0436\u043d\u043e, \u0434\u043e\u0431\u0440\u043e\u0437\u0438\u0447\u043b\u0438\u0432\u043e \u0442\u0430 \u0442\u0435\u0440\u043f\u043b\u044f\u0447\u0435.\n\u0406 \u043c\u0438 \u043c\u043e\u0436\u0435\u043c\u043e \u0431\u0443\u0442\u0438 \u0432\u043f\u0435\u0432\u043d\u0435\u043d\u0456, \u0449\u043e \u0411\u043e\u0433 \u0434\u0430\u0440\u0443\u0454 \u043f\u043e\u043a\u0430\u044f\u043d\u043d\u044f \u0441\u0432\u043e\u0457\u043c \u043e\u0431\u0440\u0430\u043d\u0438\u043c \u0434\u0456\u0442\u044f\u043c \u0443 \u0432\u0456\u0434\u043f\u043e\u0432\u0456\u0434\u043d\u0438\u0439 \u0447\u0430\u0441.\n\u0423 \u0432\u0456\u0440\u0448\u0430\u0445 24 \u0442\u0430 25 \u0441\u044c\u043e\u0433\u043e\u0434\u043d\u0456\u0448\u043d\u044c\u043e\u0433\u043e \u0443\u0440\u0438\u0432\u043a\u0443 \u044f \u0431\u0430\u0447\u0443 \u043f\u2019\u044f\u0442\u044c \u044f\u043a\u043e\u0441\u0442\u0435\u0439, \u044f\u043a\u0456 \u0411\u043e\u0433 \u0445\u043e\u0447\u0435 \u0440\u043e\u0437\u0432\u0438\u043d\u0443\u0442\u0438 \u0443 \u0441\u0432\u043e\u0457\u0445 \u0441\u043b\u0443\u0433\u0430\u0445:\n\n\u042f\u043a\u0456\u0441\u0442\u044c 1: \u041d\u0435 \u0441\u0432\u0430\u0440\u043b\u0438\u0432\u0438\u0439.\n\u0414\u0435\u0445\u0442\u043e \u043b\u044e\u0431\u0438\u0442\u044c \u0441\u043f\u0435\u0440\u0435\u0447\u0430\u0442\u0438\u0441\u044f.\n\u041d\u0435\u043c\u0430\u0454 \u043d\u0456\u0447\u043e\u0433\u043e \u043f\u043e\u0433\u0430\u043d\u043e\u0433\u043e \u0443 \u0437\u0434\u043e\u0440\u043e\u0432\u0438\u0445 \u0434\u0435\u0431\u0430\u0442\u0430\u0445.\n\u0410\u043b\u0435 \u044f\u043a \u0437\u0440\u043e\u0437\u0443\u043c\u0456\u0442\u0438, \u0449\u043e \u0432\u0438 \u0433\u0440\u0456\u0448\u043d\u043e \u00ab\u0441\u0432\u0430\u0440\u0438\u0442\u0435\u0441\u044f\u00bb?\n\u041c\u043e\u0436\u043b\u0438\u0432\u043e, \u0432\u0438 \u043c\u043e\u0436\u0435\u0442\u0435 \u043f\u043e\u0441\u0442\u0430\u0432\u0438\u0442\u0438 \u0441\u043e\u0431\u0456 \u0446\u0435 \u043f\u0438\u0442\u0430\u043d\u043d\u044f:\n\u00ab\u041a\u043e\u043b\u0438 \u044f \u0441\u043f\u0435\u0440\u0435\u0447\u0430\u044e\u0441\u044f \u0437 \u043a\u0438\u043c\u043e\u0441\u044c, \u0447\u0438 \u043c\u0435\u043d\u0456 \u0431\u0456\u043b\u044c\u0448\u0435 \u043f\u043e\u0442\u0440\u0456\u0431\u043d\u0430 \u0446\u044f \u043b\u044e\u0434\u0438\u043d\u0430, \u0447\u0438 \u043f\u0435\u0440\u0435\u043c\u043e\u0433\u0430 \u0432 \u0441\u0443\u043f\u0435\u0440\u0435\u0447\u0446\u0456?\u00bb\n\u0427\u0438 \u043c\u043e\u044f \u0433\u043e\u0440\u0434\u0456\u0441\u0442\u044c \u0437\u043c\u0443\u0448\u0443\u0454 \u043c\u0435\u043d\u0435 \u0437\u043e\u0441\u0435\u0440\u0435\u0434\u0436\u0443\u0432\u0430\u0442\u0438\u0441\u044f \u043d\u0430 \u0442\u043e\u043c\u0443, \u0449\u043e\u0431 \u0431\u0443\u0442\u0438 \u043f\u0440\u0430\u0432\u0438\u043c, \u0437\u0430\u043c\u0456\u0441\u0442\u044c \u0442\u043e\u0433\u043e, \u0449\u043e\u0431 \u0431\u0443\u0442\u0438 \u0434\u043e\u0431\u0440\u0438\u043c?\u00bb\n\n\u042f\u043a\u0456\u0441\u0442\u044c 2: \u0414\u043e\u0431\u0440\u043e\u0437\u0438\u0447\u043b\u0438\u0432\u0438\u0439 \u0434\u043e \u0432\u0441\u0456\u0445.\n\u0421\u043b\u0443\u0433\u0430 \u0413\u043e\u0441\u043f\u043e\u0434\u043d\u0456\u0439 \u043f\u043e\u0432\u0438\u043d\u0435\u043d \u0431\u0443\u0442\u0438 \u0434\u043e\u0431\u0440\u0438\u043c \u0434\u043e \u0432\u0441\u0456\u0445.\n\u041d\u0430\u0432\u0456\u0442\u044c \u043b\u044e\u0434\u044f\u043c, \u044f\u043a\u0456 \u0442\u0435\u0431\u0435 \u043d\u0435\u043d\u0430\u0432\u0438\u0434\u044f\u0442\u044c \u0456 \u0445\u043e\u0447\u0443\u0442\u044c \u0437\u0430\u0432\u0434\u0430\u0442\u0438 \u0442\u043e\u0431\u0456 \u0431\u043e\u043b\u044e.\n\u0426\u0435 \u0432\u0430\u0436\u043a\u043e, \u044f \u0437\u043d\u0430\u044e.\n\u041c\u0438 \u0432\u0432\u0430\u0436\u0430\u0454\u043c\u043e, \u0449\u043e \u0441\u043f\u043e\u0441\u0456\u0431 \u0437\u0430\u0445\u0438\u0441\u0442\u0438\u0442\u0438 \u0441\u0435\u0431\u0435 \u0432\u0456\u0434 \u0456\u043d\u0448\u0438\u0445 \u043b\u044e\u0434\u0435\u0439 \u2014 \u0446\u0435 \u0431\u0443\u0442\u0438 \u0441\u0438\u043b\u044c\u043d\u0438\u043c\u0438, \u0432\u0438\u043a\u043e\u0440\u0438\u0441\u0442\u043e\u0432\u0443\u0432\u0430\u0442\u0438 \u0441\u0438\u043b\u0443.\n\u0410\u043b\u0435 \u043f\u043e\u0433\u043b\u044f\u043d\u044c\u0442\u0435 \u043d\u0430 \u0442\u0435, \u0449\u043e \u041f\u0430\u0432\u043b\u043e \u043d\u0430\u0433\u0430\u0434\u0443\u0454 \u043d\u0430\u043c \u0443 \u041f\u043e\u0441\u043b\u0430\u043d\u043d\u0456 \u0434\u043e \u0420\u0438\u043c\u043b\u044f\u043d 2:4:\n\u00ab\u0411\u043e\u0436\u0430 \u0434\u043e\u0431\u0440\u043e\u0442\u0430 \u043c\u0430\u0454 \u043d\u0430 \u043c\u0435\u0442\u0456 \u043f\u0440\u0438\u0432\u0435\u0441\u0442\u0438 \u0432\u0430\u0441 \u0434\u043e \u043f\u043e\u043a\u0430\u044f\u043d\u043d\u044f\u00bb.\n\u041d\u0430\u0441\u043a\u0456\u043b\u044c\u043a\u0438 \u0434\u043e\u0431\u0440\u0438\u043c \u0431\u0443\u0432 \u0406\u0441\u0443\u0441 \u0434\u043e \u0442\u0435\u0431\u0435, \u043a\u043e\u043b\u0438 \u0442\u0438 \u0433\u0440\u0456\u0448\u0438\u0432 \u0456 \u0442\u0456\u043a\u0430\u0432 \u0432\u0456\u0434 \u041d\u044c\u043e\u0433\u043e?\n\u0419\u043e\u0433\u043e \u0434\u043e\u0431\u0440\u043e\u0442\u0430 \u0441\u043f\u043e\u043d\u0443\u043a\u0430\u043b\u0430 \u0442\u0435\u0431\u0435 \u0434\u043e \u043f\u043e\u043a\u0430\u044f\u043d\u043d\u044f,\n\u0422\u043e\u0436 \u0442\u0435\u043f\u0435\u0440 \u0443 \u0432\u0430\u0441 \u0454 \u043c\u043e\u0436\u043b\u0438\u0432\u0456\u0441\u0442\u044c \u043d\u0430\u0441\u043b\u0456\u0434\u0443\u0432\u0430\u0442\u0438 \u0425\u0440\u0438\u0441\u0442\u0430 \u0442\u0430 \u0431\u0443\u0442\u0438 \u0434\u043e\u0431\u0440\u0438\u043c\u0438 \u0434\u043e \u0432\u0441\u0456\u0445.\n\n\u042f\u043a\u0456\u0441\u0442\u044c 3: \u0422\u0435\u0440\u043f\u043b\u044f\u0447\u0435 \u0437\u043d\u043e\u0441\u0438\u0442\u0438 \u0437\u043b\u043e.\n\u041a\u043e\u043b\u0438 \u043c\u0438 \u0434\u0456\u043b\u0438\u043c\u043e\u0441\u044f \u0456\u0441\u0442\u0438\u043d\u043e\u044e \u0404\u0432\u0430\u043d\u0433\u0435\u043b\u0456\u044f, \u043c\u0438 \u0437\u0456\u0442\u043a\u043d\u0435\u043c\u043e\u0441\u044f \u0437 \u043e\u043f\u043e\u0440\u043e\u043c \u0437 \u0431\u043e\u043a\u0443 \u043b\u044e\u0434\u0435\u0439, \u044f\u043a\u0438\u043c \u043d\u0435 \u043f\u043e\u0434\u043e\u0431\u0430\u0454\u0442\u044c\u0441\u044f \u0442\u0435, \u0449\u043e \u043c\u0438 \u0433\u043e\u0432\u043e\u0440\u0438\u043c\u043e.\n\u041f\u0430\u043c\u2018\u044f\u0442\u0430\u0454\u0448, \u044f\u043a \u0421\u0442\u0456\u0432\u0435\u043d \u0432\u0456\u0434\u0440\u0435\u0430\u0433\u0443\u0432\u0430\u0432 \u043b\u044e\u0434\u044f\u043c, \u044f\u043a\u0456 \u0439\u043e\u0433\u043e \u0432\u0431\u0438\u043b\u0438?\n\u0423 \u0414\u0456\u044f\u043d\u043d\u044f\u0445 7:59\u201360 \u0441\u043a\u0430\u0437\u0430\u043d\u043e:\n59 \u041a\u043e\u043b\u0438 \u0436 \u0439\u043e\u0433\u043e \u043a\u0430\u043c\u0456\u043d\u043d\u044f\u043c \u043f\u043e\u0431\u0438\u0432\u0430\u043b\u0438, \u0421\u0442\u0435\u043f\u0430\u043d \u043c\u043e\u043b\u0438\u0432\u0441\u044f: \u00ab\u0413\u043e\u0441\u043f\u043e\u0434\u0438 \u0406\u0441\u0443\u0441\u0435, \u043f\u0440\u0438\u0439\u043c\u0438 \u0434\u0443\u0445 \u043c\u0456\u0439!\u00bb\n60 \u0422\u043e\u0434\u0456 \u0432\u0456\u043d \u0443\u043f\u0430\u0432 \u043d\u0430 \u043a\u043e\u043b\u0456\u043d\u0430 \u0439 \u0432\u0438\u0433\u0443\u043a\u043d\u0443\u0432: \u00ab\u0413\u043e\u0441\u043f\u043e\u0434\u0438, \u043d\u0435 \u0437\u0430\u0440\u0430\u0445\u0443\u0439 \u0457\u043c \u0446\u044c\u043e\u0433\u043e \u0433\u0440\u0456\u0445\u0430!\u00bb\n\n\u0422\u0456\u043b\u044c\u043a\u0438 \u0411\u043e\u0433 \u043c\u043e\u0436\u0435 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0442\u0438 \u043d\u0430\u043c \u0442\u0435\u0440\u043f\u0435\u043b\u0438\u0432\u043e \u0437\u043d\u043e\u0441\u0438\u0442\u0438 \u0437\u043b\u043e, \u044f\u043a \u0446\u0435 \u0440\u043e\u0431\u0438\u0432 \u0421\u0442\u0435\u043f\u0430\u043d.\n\u0410\u043b\u0435 \u0432\u0456\u043d \u0434\u043e\u043f\u043e\u043c\u043e\u0436\u0435 \u043d\u0430\u043c, \u043a\u043e\u043b\u0438 \u043c\u0438 \u043a\u043b\u0438\u0447\u0435\u043c\u043e \u0434\u043e \u043d\u044c\u043e\u0433\u043e \u0432 \u0447\u0430\u0441\u0438 \u043b\u0438\u0445\u0430.\n\u0412\u0456\u043d \u0434\u043e\u043f\u043e\u043c\u043e\u0436\u0435 \u043d\u0430\u043c \u0434\u043e\u0432\u0456\u0440\u044f\u0442\u0438 \u0419\u043e\u043c\u0443, \u0437\u043d\u0430\u044e\u0447\u0438, \u0449\u043e \u043d\u0430\u0448\u0456 \u0434\u0443\u0448\u0456 \u0432 \u0431\u0435\u0437\u043f\u0435\u0446\u0456 \u0432 \u0419\u043e\u0433\u043e \u0440\u0443\u043a\u0430\u0445, \u0449\u043e \u0431 \u043d\u0435 \u0441\u0442\u0430\u043b\u043e\u0441\u044f \u0437 \u043d\u0430\u0448\u0438\u043c\u0438 \u0442\u0456\u043b\u0430\u043c\u0438.\n\n\u042f\u043a\u0456\u0441\u0442\u044c 4: \u0412\u0438\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u043d\u044f \u0437 \u043b\u0430\u0433\u0456\u0434\u043d\u0456\u0441\u0442\u044e.\n\u0412\u0438\u043f\u0440\u0430\u0432\u043b\u044f\u0442\u0438 \u043b\u044e\u0434\u0435\u0439 \u0432\u0430\u0436\u043a\u043e.\n\u0410\u043b\u0435 \u044f\u043a\u0449\u043e \u043c\u0456\u0439 \u0441\u0438\u043d \u0440\u043e\u0431\u0438\u0442\u044c \u0449\u043e\u0441\u044c \u043d\u0435 \u0442\u0430\u043a, \u044f \u043a\u0430\u0436\u0443 \u0439\u043e\u043c\u0443 \u043f\u0440\u043e \u0446\u0435, \u0431\u043e \u043b\u044e\u0431\u043b\u044e \u0439\u043e\u0433\u043e.\n\u041e\u0441\u044c \u0432\u0430\u0436\u043b\u0438\u0432\u0435 \u043f\u0438\u0442\u0430\u043d\u043d\u044f, \u043d\u0430\u0434 \u044f\u043a\u0438\u043c \u0432\u0430\u0440\u0442\u043e \u043f\u043e\u0434\u0443\u043c\u0430\u0442\u0438, \u043a\u043e\u043b\u0438 \u0432\u0430\u043c \u0434\u043e\u0432\u043e\u0434\u0438\u0442\u044c\u0441\u044f \u043a\u043e\u0433\u043e\u0441\u044c \u0432\u0438\u043f\u0440\u0430\u0432\u043b\u044f\u0442\u0438:\n\u00ab\u0427\u0438 \u0432\u0456\u0434\u0447\u0443\u0432\u0430\u0454 \u043c\u043e\u044f \u0434\u0438\u0442\u0438\u043d\u0430, \u0434\u0440\u0443\u0433 \u0447\u0438 \u0447\u043e\u043b\u043e\u0432\u0456\u043a\/\u0434\u0440\u0443\u0436\u0438\u043d\u0430 \u043c\u043e\u044e \u043b\u044e\u0431\u043e\u0432?\u00bb\n\u0427\u0438 \u0432\u043e\u043d\u0438 \u0432\u0456\u0434\u0447\u0443\u0432\u0430\u044e\u0442\u044c \u043b\u0438\u0448\u0435 \u043c\u0456\u0439 \u0433\u043d\u0456\u0432?\n\n\u041a\u043e\u043b\u0438 \u043c\u0438 \u0432\u0438\u043f\u0440\u0430\u0432\u043b\u044f\u0454\u043c\u043e \u0437 \u0433\u043d\u0456\u0432\u043e\u043c \u0430\u0431\u043e \u0440\u043e\u0437\u0447\u0430\u0440\u0443\u0432\u0430\u043d\u043d\u044f\u043c, \u043c\u0438 \u043f\u043e\u0432\u043e\u0434\u0438\u043c\u043e\u0441\u044f \u0442\u0430\u043a, \u043d\u0456\u0431\u0438 \u0411\u043e\u0433 \u043d\u0435 \u043c\u043e\u0436\u0435 \u0437\u043c\u0456\u043d\u0438\u0442\u0438 \u0456\u043d\u0448\u0443 \u043b\u044e\u0434\u0438\u043d\u0443.\n\u041c\u0438 \u0434\u0443\u043c\u0430\u0454\u043c\u043e, \u0449\u043e \u043c\u043e\u0436\u0435\u043c\u043e \u0442\u0438\u0441\u043d\u0443\u0442\u0438 \u043d\u0430 \u043d\u0438\u0445, \u0449\u043e\u0431 \u0432\u043e\u043d\u0438 \u0437\u043c\u0456\u043d\u0438\u043b\u0438\u0441\u044f, \u0430\u0431\u043e \u043a\u0440\u0438\u0447\u0430\u0442\u0438 \u0433\u043e\u043b\u043e\u0441\u043d\u0456\u0448\u0435, \u043f\u043e\u043a\u0438 \u0432\u043e\u043d\u0438 \u043d\u0435 \u0441\u0442\u0430\u043d\u0443\u0442\u044c \u043d\u0430 \u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u0438\u0439 \u0448\u043b\u044f\u0445.\n\u0410\u043b\u0435 \u0432\u0447\u0438\u0442\u0435\u043b\u044c, \u044f\u043a\u0438\u0439 \u0437\u043d\u0430\u0454, \u0449\u043e \u0441\u043f\u0440\u0430\u0432\u0436\u043d\u044f \u0441\u0438\u043b\u0430 \u043d\u0430\u043b\u0435\u0436\u0438\u0442\u044c \u0411\u043e\u0433\u0443, \u0431\u0443\u0434\u0435 \u043b\u0430\u0433\u0456\u0434\u043d\u0438\u043c, \u0442\u0435\u0440\u043f\u043b\u044f\u0447\u0438\u043c \u0456 \u0434\u043e\u0431\u0440\u0438\u043c.\n\n\u042f\u043a\u0456\u0441\u0442\u044c 5: \u0417\u0434\u0430\u0442\u043d\u0438\u0439 \u043d\u0430\u0432\u0447\u0430\u0442\u0438.\n\u0427\u0438 \u0434\u043e\u0441\u0442\u0430\u0442\u043d\u044c\u043e \u0434\u043e\u0431\u0440\u0435 \u0432\u0438 \u0440\u043e\u0437\u0443\u043c\u0456\u0454\u0442\u0435 \u0421\u043b\u043e\u0432\u043e \u0411\u043e\u0436\u0435, \u0449\u043e\u0431 \u043f\u043e\u044f\u0441\u043d\u0438\u0442\u0438 \u0439\u043e\u0433\u043e \u0456\u043d\u0448\u0438\u043c?\n\u0427\u0438 \u0437\u0430\u043f\u0430\u043c\u2018\u044f\u0442\u043e\u0432\u0443\u0454\u0442\u0435 \u0432\u0438 \u0421\u0432\u044f\u0442\u0435 \u041f\u0438\u0441\u044c\u043c\u043e, \u0449\u043e\u0431 \u0432\u043e\u043d\u043e \u0431\u0443\u043b\u043e \u0443 \u0432\u0430\u0441 \u043f\u0456\u0434 \u0440\u0443\u043a\u043e\u044e, \u0449\u043e\u0431 \u0432\u043e\u043d\u043e \u0431\u0443\u043b\u043e \u0432\u0430\u0448\u0438\u043c \u0434\u043e\u0440\u043e\u0433\u043e\u0432\u043a\u0430\u0437\u043e\u043c \u0443 \u0436\u0438\u0442\u0442\u0456 \u0442\u0430 \u0434\u043b\u044f \u0442\u043e\u0433\u043e, \u0449\u043e\u0431 \u0434\u0456\u043b\u0438\u0442\u0438\u0441\u044f \u043d\u0438\u043c \u0437 \u0456\u043d\u0448\u0438\u043c\u0438?\n\u0426\u044c\u043e\u0433\u043e \u043c\u0456\u0441\u044f\u0446\u044f \u043c\u0438 \u0440\u043e\u0437\u043f\u043e\u0447\u043d\u0435\u043c\u043e \u0449\u043e\u0441\u044c \u043d\u043e\u0432\u0435.\n\u041c\u0438 \u043f\u043e\u043f\u0440\u043e\u0441\u0438\u043c\u043e \u0432\u0430\u0441 \u0432\u0438\u0432\u0447\u0438\u0442\u0438 \u043d\u0430\u043f\u0430\u043c\u2018\u044f\u0442\u044c \u043e\u0434\u0438\u043d \u0432\u0456\u0440\u0448 \u0437 \u041f\u0438\u0441\u0430\u043d\u043d\u044f \u0434\u043e \u043a\u0456\u043d\u0446\u044f \u0431\u0435\u0440\u0435\u0437\u043d\u044f.\n\u0410 \u044f\u043a\u0449\u043e \u0432\u0438 \u0437\u043c\u043e\u0436\u0435\u0442\u0435 \u043f\u0440\u043e\u0434\u0435\u043a\u043b\u0430\u043c\u0443\u0432\u0430\u0442\u0438 \u0446\u0435 \u043e\u0434\u043d\u043e\u043c\u0443 \u0437 \u043d\u0430\u0448\u0438\u0445 \u043b\u0456\u0434\u0435\u0440\u0456\u0432 \u0431\u0443\u0434\u044c-\u044f\u043a\u043e\u044e \u043c\u043e\u0432\u043e\u044e, \u0442\u043e \u043e\u0442\u0440\u0438\u043c\u0430\u0454\u0442\u0435 \u043d\u0430\u043b\u0456\u043f\u043a\u0443.\n\u0412\u0438 \u043c\u043e\u0436\u0435\u0442\u0435 \u043f\u043e\u043a\u043b\u0430\u0441\u0442\u0438 \u0439\u043e\u0433\u043e \u043d\u0430 \u043f\u043b\u044f\u0448\u043a\u0443 \u0437 \u0432\u043e\u0434\u043e\u044e \u0430\u0431\u043e \u0431\u043b\u043e\u043a\u043d\u043e\u0442.\n\u0414\u0435 \u0437\u0430\u0432\u0433\u043e\u0434\u043d\u043e, \u0434\u0435 \u0432\u0438 \u0446\u0435 \u043f\u043e\u0431\u0430\u0447\u0438\u0442\u0435, \u0456 \u043f\u0440\u043e\u0434\u043e\u0432\u0436\u0443\u0439\u0442\u0435 \u043f\u0440\u0430\u043a\u0442\u0438\u043a\u0443\u0432\u0430\u0442\u0438 \u0446\u0435 \u0446\u0456\u043b\u0438\u0439 \u0440\u0456\u043a.\n\u0414\u0430\u0432\u0430\u0439\u0442\u0435 \u0440\u0430\u0437\u043e\u043c \u043f\u0440\u043e\u0447\u0438\u0442\u0430\u0454\u043c\u043e \u0432\u0456\u0440\u0448 \u0437\u0430 \u043c\u0456\u0441\u044f\u0446\u044c \u0431\u0435\u0440\u0435\u0437\u0435\u043d\u044c, 2 \u0422\u0438\u043c\u043e\u0444\u0456\u044f 3:16.\n\u0412\u0421\u0406: \u00ab\u0423\u0441\u0435 \u041f\u0438\u0441\u0430\u043d\u043d\u044f \u043d\u0430\u0442\u0445\u043d\u0435\u043d\u043d\u0435 \u0411\u043e\u0433\u043e\u043c \u0456 \u043a\u043e\u0440\u0438\u0441\u043d\u0435 \u0434\u043b\u044f \u043d\u0430\u0432\u0447\u0430\u043d\u043d\u044f, \u0434\u043b\u044f \u0434\u043e\u043a\u043e\u0440\u0443, \u0434\u043b\u044f \u0432\u0438\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u043d\u044f, \u0434\u043b\u044f \u0432\u0438\u0445\u043e\u0432\u0430\u043d\u043d\u044f \u0432 \u043f\u0440\u0430\u0432\u0435\u0434\u043d\u043e\u0441\u0442\u0456\u00bb\n\n\u041d\u0430\u043c \u0443\u0441\u0456\u043c \u043f\u043e\u0442\u0440\u0456\u0431\u043d\u0430 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0430, \u0449\u043e\u0431 \u043f\u0440\u043e\u0434\u043e\u0432\u0436\u0443\u0432\u0430\u0442\u0438 \u0440\u0443\u0445\u0430\u0442\u0438\u0441\u044f \u0443 \u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u043e\u043c\u0443 \u043d\u0430\u043f\u0440\u044f\u043c\u043a\u0443.\n\u041d\u0430\u043c \u043f\u043e\u0442\u0440\u0456\u0431\u043d\u0435 \u0421\u043b\u043e\u0432\u043e \u0411\u043e\u0436\u0435, \u0449\u043e\u0431 \u043d\u0430\u0432\u0447\u0430\u0442\u0438, \u0432\u0438\u043f\u0440\u0430\u0432\u043b\u044f\u0442\u0438 \u0442\u0430 \u043d\u0430\u0432\u0447\u0430\u0442\u0438 \u043d\u0430\u0441 \u0445\u043e\u0434\u0438\u0442\u0438 \u0432 \u043f\u0440\u0430\u0432\u0435\u0434\u043d\u043e\u0441\u0442\u0456.\n\u0406 \u043d\u0430\u043c \u043f\u043e\u0442\u0440\u0456\u0431\u0435\u043d \u0421\u0432\u044f\u0442\u0438\u0439 \u0414\u0443\u0445, \u0449\u043e\u0431 \u0434\u043e\u043f\u043e\u043c\u043e\u0433\u0442\u0438 \u043d\u0430\u043c \u0437\u0440\u043e\u0437\u0443\u043c\u0456\u0442\u0438 \u0442\u0430 \u0437\u0430\u0441\u0442\u043e\u0441\u0443\u0432\u0430\u0442\u0438 \u0421\u043b\u043e\u0432\u043e, \u0442\u043e\u0436 \u0437\u0432\u0435\u0440\u043d\u0456\u043c\u043e \u0437\u0430\u0440\u0430\u0437 \u043d\u0430\u0448\u0456 \u0441\u0435\u0440\u0446\u044f \u0434\u043e \u043d\u0435\u0431\u0435\u0441 \u0443 \u043c\u043e\u043b\u0438\u0442\u0432\u0456.\n\u0406\u0441\u0443\u0441\u0435, \u043c\u0438 \u043c\u043e\u0436\u0435\u043c\u043e \u0440\u043e\u0437\u043c\u043e\u0432\u043b\u044f\u0442\u0438 \u0437 \u041e\u0442\u0446\u0435\u043c \u043b\u0438\u0448\u0435 \u0442\u043e\u043c\u0443, \u0449\u043e \u0422\u0438 \u0437\u0431\u0443\u0434\u0443\u0432\u0430\u0432 \u043c\u0456\u0441\u0442 \u043c\u0456\u0436 \u0437\u0435\u043c\u043b\u0435\u044e \u0442\u0430 \u043d\u0435\u0431\u043e\u043c.\n\u0422\u0438 \u0437\u0440\u0443\u0439\u043d\u0443\u0432\u0430\u0432 \u043f\u0430\u0441\u0442\u043a\u0438 \u0434\u0438\u044f\u0432\u043e\u043b\u0430 \u0442\u0430 \u0432\u0456\u0434\u043a\u0440\u0438\u0432 \u043d\u0430\u043c \u043e\u0447\u0456 \u043d\u0430 \u0456\u0441\u0442\u0438\u043d\u0443.\n\u041e\u0442\u0447\u0435, \u0434\u044f\u043a\u0443\u0454\u043c\u043e \u0422\u043e\u0431\u0456 \u0437\u0430 \u0434\u0430\u0440 \u043f\u043e\u043a\u0430\u044f\u043d\u043d\u044f, \u0449\u043e\u0431 \u043c\u0438 \u043c\u043e\u0433\u043b\u0438 \u0431\u0443\u0442\u0438 \u0447\u0435\u0441\u043d\u0438\u043c\u0438 \u0437 \u0441\u043e\u0431\u043e\u044e \u0442\u0430 \u0437 \u0422\u043e\u0431\u043e\u044e \u0449\u043e\u0434\u043e \u043d\u0430\u0448\u043e\u0433\u043e \u0433\u0440\u0456\u0445\u0430.\n\u0406 \u0434\u044f\u043a\u0443\u044e \u0422\u043e\u0431\u0456, \u0421\u0432\u044f\u0442\u0438\u0439 \u0414\u0443\u0448\u0435, \u0437\u0430 \u0442\u0435, \u0449\u043e \u0434\u0430\u0432 \u043d\u0430\u043c \u0432\u0456\u0440\u0443 \u0437\u0432\u0435\u0440\u043d\u0443\u0442\u0438\u0441\u044f \u0434\u043e \u0406\u0441\u0443\u0441\u0430 \u0434\u043b\u044f \u043d\u0430\u0448\u043e\u0433\u043e \u0441\u043f\u0430\u0441\u0456\u043d\u043d\u044f.\n\u0412\u0456\u0434\u043a\u0440\u0438\u0439 \u043d\u0430\u0448\u0456 \u0440\u043e\u0437\u0443\u043c\u0438 \u0442\u0430 \u0441\u0435\u0440\u0446\u044f, \u0449\u043e\u0431 \u043c\u0438 \u043c\u043e\u0433\u043b\u0438 \u0437\u0440\u043e\u0437\u0443\u043c\u0456\u0442\u0438 \u0442\u0430 \u0437\u0430\u0441\u0442\u043e\u0441\u043e\u0432\u0443\u0432\u0430\u0442\u0438 \u0421\u043b\u043e\u0432\u043e \u0432 \u043d\u0430\u0448\u043e\u043c\u0443 \u0436\u0438\u0442\u0442\u0456.\n\u0414\u043e\u043f\u043e\u043c\u043e\u0436\u0438 \u043d\u0430\u043c \u043d\u0430\u043f\u043e\u043b\u0435\u0433\u043b\u0438\u0432\u043e \u0431\u0456\u0433\u0442\u0438 \u0432 \u043f\u043e\u043a\u043b\u0430\u0434\u0435\u043d\u0438\u0445 \u043d\u0430 \u043d\u0430\u0441 \u043f\u0435\u0440\u0435\u0433\u043e\u043d\u0430\u0445, \u0437\u0430\u043f\u0440\u043e\u0448\u0443\u044e\u0447\u0438 \u0456\u043d\u0448\u0438\u0445 \u043f\u0440\u0438\u0454\u0434\u043d\u0430\u0442\u0438\u0441\u044f \u0434\u043e \u043d\u0430\u0441 \u0443 \u043f\u043e\u0434\u043e\u0440\u043e\u0436\u0456 \u0434\u043e \u0446\u0456\u043b\u0456\u0441\u043d\u043e\u0441\u0442\u0456, \u043d\u0430\u0434\u0456\u0457 \u0442\u0430 \u043d\u0435\u0431\u0435\u0441, \u0430\u043c\u0456\u043d\u044c.\n\n\u0417\u0430\u043f\u0438\u0442\u0430\u043d\u043d\u044f \u0434\u043b\u044f \u043c\u0435\u0434\u0438\u0442\u0430\u0446\u0456\u0457 \u0442\u0430 \u043e\u0431\u0433\u043e\u0432\u043e\u0440\u0435\u043d\u043d\u044f\n1.  \u041f\u0440\u043e\u0447\u0438\u0442\u0430\u0439\u0442\u0435 2 \u0422\u0438\u043c\u043e\u0444\u0456\u044f 2:22 \u0442\u0430 \u041f\u0441\u0430\u043b\u043e\u043c 119:35-37.\n\u0430) \u0414\u043e \u044f\u043a\u043e\u0457 \u0437 \u00ab\u044e\u043d\u0430\u0446\u044c\u043a\u0438\u0445 \u043f\u0440\u0438\u0441\u0442\u0440\u0430\u0441\u0442\u0435\u0439\u00bb (\u0437\u0430\u0434\u043e\u0432\u043e\u043b\u0435\u043d\u043d\u044f, \u0432\u043b\u0430\u0434\u0430, \u043f\u043e\u043f\u0443\u043b\u044f\u0440\u043d\u0456\u0441\u0442\u044c, \u043c\u0430\u0439\u043d\u043e, \u0433\u043e\u0440\u0434\u0456\u0441\u0442\u044c) \u0432\u0430\u0448\u0435 \u0441\u0435\u0440\u0446\u0435 \u043f\u0440\u0438\u0440\u043e\u0434\u043d\u043e \u043f\u0440\u0430\u0433\u043d\u0435, \u043a\u043e\u043b\u0438 \u0432\u0438 \u043f\u0435\u0440\u0435\u0431\u0443\u0432\u0430\u0454\u0442\u0435 \u0432 \u0441\u0442\u0440\u0435\u0441\u0456 \u0430\u0431\u043e \u0448\u0443\u043a\u0430\u0454\u0442\u0435 \u0440\u043e\u0437\u0440\u0430\u0434\u0438?\n\n2.  \u041f\u0440\u043e\u0447\u0438\u0442\u0430\u0439\u0442\u0435 \u0415\u0444\u0435\u0441\u044f\u043d 2:1-5 \u0442\u0430 \u0404\u0437\u0435\u043a\u0456\u0457\u043b\u044f 36:26.\n\u0430) \u0429\u043e \u043d\u0435\u043e\u0431\u0445\u0456\u0434\u043d\u043e, \u0449\u043e\u0431 \u043f\u0435\u0440\u0435\u0439\u0442\u0438 \u0432\u0456\u0434 \u0441\u0442\u0430\u043d\u0443 \u00ab\u043c\u0435\u0440\u0442\u0432\u043e\u0433\u043e\u00bb \u0434\u043e \u0441\u0442\u0430\u043d\u0443 \u00ab\u0436\u0438\u0432\u043e\u0433\u043e\u00bb?\n\u0431) \u0427\u0438 \u0434\u043e\u043f\u043e\u043c\u0430\u0433\u0430\u0454 \u0432\u0430\u043c \u0432\u0456\u0440\u0430 \u0432 \u0442\u0435, \u0449\u043e \u043f\u043e\u043a\u0430\u044f\u043d\u043d\u044f \u0454 \u0434\u0430\u0440\u043e\u043c \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0442\u0456, \u0431\u0443\u0442\u0438 \u0431\u0456\u043b\u044c\u0448 \u0447\u0435\u0441\u043d\u0438\u043c\u0438 \u0437 \u0411\u043e\u0433\u043e\u043c \u0449\u043e\u0434\u043e \u0432\u0430\u0448\u043e\u0433\u043e \u0433\u0440\u0456\u0445\u0430?\n\n3.  \u041f\u0440\u043e\u0447\u0438\u0442\u0430\u0439\u0442\u0435 2 \u0422\u0438\u043c\u043e\u0444\u0456\u044f 2:23-25\u0430 \u0442\u0430 \u041a\u043e\u043b\u043e\u0441\u044f\u043d 3:12-14.\n\u0430) \u042f\u043a\u0456 \u044f\u043a\u043e\u0441\u0442\u0456 \u043c\u0430\u0454 \u00ab\u0441\u043b\u0443\u0433\u0430 \u0413\u043e\u0441\u043f\u043e\u0434\u043d\u0456\u0439\u00bb, \u043a\u043e\u043b\u0438 \u0432\u0456\u043d \u0434\u0438\u0441\u043a\u0443\u0442\u0443\u0454 \u0437 \u0456\u043d\u0448\u0438\u043c\u0438 \u0430\u0431\u043e \u0432\u0438\u043f\u0440\u0430\u0432\u043b\u044f\u0454 \u0457\u0445?\n\u0431) \u041e\u0441\u043a\u0456\u043b\u044c\u043a\u0438 \u0406\u0441\u0443\u0441 \u043b\u044e\u0431\u0438\u0432 \u043d\u0430\u0441 \u0437 \u0432\u0435\u043b\u0438\u043a\u0438\u043c \u0442\u0435\u0440\u043f\u0456\u043d\u043d\u044f\u043c \u0456 \u043d\u0456\u0436\u043d\u0456\u0441\u0442\u044e, \u043a\u043e\u0433\u043e \u0443 \u0432\u0430\u0448\u043e\u043c\u0443 \u0436\u0438\u0442\u0442\u0456 \u0432\u0438 \u043b\u044e\u0431\u0438\u0442\u0438\u043c\u0435\u0442\u0435 \u0437 \u0442\u0430\u043a\u043e\u044e \u0436 \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0442\u0442\u044e, \u043d\u0430\u0432\u0456\u0442\u044c \u044f\u043a\u0449\u043e \u0432\u043e\u043d\u0438 \u043d\u0435 \u0437\u0433\u043e\u0434\u043d\u0456 \u0437 \u0432\u0430\u043c\u0438 \u0430\u0431\u043e \u043d\u0435 \u043b\u044e\u0431\u043b\u044f\u0442\u044c \u0432\u0430\u0441?\n\n4.  \u041f\u0440\u043e\u0447\u0438\u0442\u0430\u0439\u0442\u0435 \u0420\u0438\u043c\u043b\u044f\u043d 10:9-11 \u0442\u0430 \u0404\u0432\u0440\u0435\u0457\u0432 12:1-2.\n\u0430) \u042f\u043a \u0437\u043e\u0441\u0435\u0440\u0435\u0434\u0436\u0435\u043d\u043d\u044f \u043d\u0430\u0448\u043e\u0433\u043e \u043f\u043e\u0433\u043b\u044f\u0434\u0443 \u043d\u0430 \u0406\u0441\u0443\u0441\u0456 \u0434\u043e\u043f\u043e\u043c\u0430\u0433\u0430\u0454 \u043d\u0430\u043c \u0432\u0456\u0434\u0432\u0435\u0440\u043d\u0443\u0442\u0438\u0441\u044f \u0432\u0456\u0434 \u0433\u0440\u0456\u0445\u0430 \u0442\u0430 \u0431\u0456\u0433\u0442\u0438 \u0432 \u043d\u043e\u0432\u043e\u043c\u0443 \u043d\u0430\u043f\u0440\u044f\u043c\u043a\u0443?\n\u0431) \u041d\u0435 \u0437\u0430\u0431\u0443\u0434\u044c\u0442\u0435 \u0432\u0438\u0432\u0447\u0438\u0442\u0438 \u043d\u0430\u043f\u0430\u043c\u2019\u044f\u0442\u044c 2 \u0422\u0438\u043c\u043e\u0444\u0456\u044f 3:16. \u042f\u043a \u0437\u043d\u0430\u043d\u043d\u044f \u0411\u043e\u0436\u043e\u0433\u043e \u0421\u043b\u043e\u0432\u0430 \u0434\u043e\u043f\u043e\u043c\u0430\u0433\u0430\u0454 \u043d\u0430\u043c \u043f\u0440\u043e\u0431\u0456\u0433\u0442\u0438 \u043c\u0430\u0440\u0430\u0444\u043e\u043d \u0432\u0456\u0440\u0438?","urdu_content":"\u0622\u067e \u06a9\u06c1\u0627\u06ba \u0628\u06be\u0627\u06af \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u061f\n2 \u062a\u06cc\u0645\u062a\u06be\u06cc\u0633 2:22-26\n\u067e\u0627\u062f\u0631\u06cc \u06a9\u0631\u0633 \u0633\u0650\u06a9\u0633\n15 \u0645\u0627\u0631\u0686 2026\n\n\u067e\u0648\u0631\u0679 \u0644\u06cc\u0646\u0688 \u0627\u0648\u0631\u06cc\u06af\u0648\u0646 \u0645\u06cc\u06ba 2019 \u0645\u06cc\u0631\u0627\u062a\u06be\u0646 \u0645\u06cc\u06ba\u060c \u06a9\u0686\u06be \u0628\u06c1\u062a\u0631\u06cc\u0646 \u0631\u0646\u0631\u0632 \u062d\u0642\u06cc\u0642\u062a \u0645\u06cc\u06ba \u0631\u06cc\u0633 \u06c1\u0627\u0631 \u06af\u0626\u06d2\u06d4\n\u0627\u0633 \u0644\u06cc\u06d2 \u0646\u06c1\u06cc\u06ba \u06a9\u06c1 \u0648\u06c1 \u0633\u0633\u062a \u062a\u06be\u06d2\u060c \u0628\u0644\u06a9\u06c1 \u0627\u0633 \u0644\u06cc\u06d2 \u06a9\u06c1 \u0648\u06c1 \u063a\u0644\u0637 \u0631\u0627\u0633\u062a\u06d2 \u067e\u0631 \u0686\u0644\u06d2 \u06af\u0626\u06d2\u06d4\n\u06a9\u0648\u0631\u0633 \u067e\u0631 \u0627\u06cc\u06a9 \u0645\u0648\u0691 \u062a\u06be\u0627 \u062c\u0648 \u0648\u0627\u0636\u062d \u0637\u0648\u0631 \u067e\u0631 \u0646\u0634\u0627\u0646 \u0632\u062f \u0646\u06c1\u06cc\u06ba \u062a\u06be\u0627\u06d4\n\u062a\u0648 \u062a\u0642\u0631\u06cc\u0628\u0627\u064b 20 \u062a\u06cc\u0632 \u062a\u0631\u06cc\u0646 \u062f\u0648\u0691\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u063a\u0644\u0637 \u0633\u0645\u062a \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0645\u06cc\u0644 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u062f\u0648\u0691\u06d2\u06d4\n\u0627\u0633 \u063a\u0644\u0637\u06cc \u0646\u06d2 \u0627\u0633 \u062f\u0648\u0691 \u0645\u06cc\u06ba \u0642\u06cc\u0645\u062a\u06cc \u0645\u0646\u0679\u0648\u06ba \u06a9\u0627 \u0627\u0636\u0627\u0641\u06c1 \u06a9\u06cc\u0627 \u062c\u0633 \u06a9\u06cc \u062a\u06cc\u0627\u0631\u06cc \u0645\u06cc\u06ba \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0645\u06c1\u06cc\u0646\u0648\u06ba \u06af\u0632\u0627\u0631\u06d2 \u062a\u06be\u06d2\u06d4\n\u0648\u06c1 \u0645\u0631\u062f \u0627\u0648\u0631 \u0639\u0648\u0631\u062a\u06cc\u06ba \u0645\u062d\u0646\u062a \u0633\u06d2 \u062f\u0648\u0691\u06d2\u060c \u0627\u0648\u0631 \u0648\u06c1 \u062a\u06cc\u0632\u06cc \u0633\u06d2 \u0628\u06be\u0627\u06af\u06d2\u06d4\n\u0644\u06cc\u06a9\u0646 \u0648\u06c1 \u062f\u0648\u0691 \u06c1\u0627\u0631 \u06af\u0626\u06d2\u060c \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0648\u06c1 \u063a\u0644\u0637 \u0631\u0627\u0633\u062a\u06d2 \u067e\u0631 \u062a\u06be\u06d2\u06d4\n\u0622\u062c \u0631\u0627\u062a \u06c1\u0645 2 \u062a\u06cc\u0645\u062a\u06be\u06cc\u0633 \u06a9\u06cc \u06a9\u062a\u0627\u0628 \u0645\u06cc\u06ba \u0648\u0627\u0639\u0638 \u06a9\u0627 \u0633\u0644\u0633\u0644\u06c1 \u062c\u0627\u0631\u06cc \u0631\u06a9\u06be\u06d2 \u06c1\u0648\u0626\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u067e\u0648\u0644\u0648\u0633 \u0631\u0633\u0648\u0644 \u0627\u0641\u0633\u0633 \u0645\u06cc\u06ba \u0645\u0633\u06cc\u062d\u06cc \u06a9\u0644\u06cc\u0633\u06cc\u0627 \u06a9\u06d2 \u0627\u06cc\u06a9 \u0646\u0648\u062c\u0648\u0627\u0646 \u067e\u0627\u062f\u0631\u06cc \u062a\u06cc\u0645\u062a\u06be\u06cc\u0633 \u06a9\u0648 \u0644\u06a9\u06be \u0631\u06c1\u0627 \u06c1\u06d2\u06d4\n\u067e\u0648\u0644\u064f\u0648\u0633 \u062a\u06cc\u0645\u062a\u06be\u06cc\u0633 \u06a9\u0648\u060c \u0627\u0648\u0631 \u0622\u062c \u06c1\u0645\u06cc\u06ba\u060c \u0627\u0633 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u0645\u0634\u0648\u0631\u06c1 \u062f\u06d2 \u0631\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u06a9\u0633 \u0637\u0631\u062d \u0635\u062d\u06cc\u062d \u0631\u0627\u0633\u062a\u06d2 \u067e\u0631 \u0642\u0627\u0626\u0645 \u0631\u06c1\u0646\u0627 \u06c1\u06d2\u06d4\n2 \u062a\u06cc\u0645\u062a\u06be\u06cc\u0633 2:22-26\n22 \u201d\u062c\u0648\u0627\u0646\u06cc \u06a9\u06cc \u062e\u0648\u0627\u06c1\u0650\u0634\u0648\u06ba \u0633\u06d2 \u0628\u06be\u0627\u06af \u0627\u0648\u0631 \u062c\u0648 \u067e\u0627\u06a9 \u062f\u0650\u0644 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u062e\u064f\u062f\u0627\u0648\u0646\u062f \u0633\u06d2 \u062f\u064f\u0639\u0627 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u064f\u0646 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0631\u0627\u0633\u062a \u0628\u0627\u0632\u06cc \u0627\u0648\u0631 \u0627\u0650\u06cc\u0645\u0627\u0646 \u0627\u0648\u0631 \u0645\u064f\u062d\u0628\u0651\u062a \u0627\u0648\u0631 \u0635\u064f\u0644\u062d \u06a9\u0627 \u0637\u0627\u0644\u0650\u0628 \u06c1\u0648\u06d4\n23 \u0644\u06cc\u06a9\u0646 \u0628\u06cc\u0648\u064f\u0642\u064f\u0648\u0641\u06cc \u0627\u0648\u0631 \u0646\u0627\u062f\u0627\u0646\u06cc \u06a9\u06cc \u062d\u064f\u062c\u062a\u0648\u0651\u06ba \u0633\u06d2 \u06a9\u0646\u0627\u0631\u06c1 \u06a9\u0631 \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u062a\u064f\u0648 \u062c\u0627\u0646\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0627\u064f\u0646 \u0633\u06d2 \u062c\u06be\u06af\u0691\u06d2 \u067e\u064e\u06cc\u062f\u0627 \u06c1\u0648\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n24 \u0627\u0648\u0631 \u0645\u064f\u0646\u0627\u0633\u0650\u0628 \u0646\u06c1\u06cc\u06ba \u06a9\u06c1 \u062e\u064f\u062f\u0627\u0648\u0646\u062f \u06a9\u0627 \u0628\u0646\u062f\u06c1 \u062c\u06be\u06af\u0691\u0627 \u06a9\u0631\u06d2 \u0628\u0644\u06a9\u06c1 \u0633\u0628 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0646\u0631\u0645\u06cc \u06a9\u0631\u06d2 \u0627\u0648\u0631 \u062a\u0639\u0644\u0650\u06cc\u0645 \u062f\u06cc\u0646\u06d2 \u06a9\u06d2 \u0644\u0627\u0626\u0650\u0642 \u0627\u0648\u0631 \u0628\u064f\u0631\u062f\u0628\u0627\u0631 \u06c1\u0648\u06d4\n25 \u0627\u0648\u0631 \u0645\u064f\u062e\u0627\u0644\u0650\u0641\u0648\u06ba \u06a9\u0648 \u062d\u0644\u0650\u06cc\u0645\u06cc \u0633\u06d2 \u062a\u0627\u062f\u0650\u06cc\u0628 \u06a9\u0631\u06d2\u06d4 \n\u0634\u0627\u06cc\u062f \u062e\u064f\u062f\u0627 \u0627\u064f\u0646\u06c1\u06cc\u06ba \u062a\u064e\u0648\u0628\u06c1 \u06a9\u06cc \u062a\u064e\u0648\u0641\u0650\u06cc\u0642 \u0628\u062e\u0634\u06d2 \u062a\u0627\u06a9\u06c1 \u0648\u06c1 \u062d\u0642 \u06a9\u0648 \u067e\u06c1\u0686\u0627\u0646\u06cc\u06ba\u06d4\n26 \u0627\u0648\u0631 \u062e\u064f\u062f\u0627\u0648\u0646\u062f \u06a9\u06d2 \u0628\u0646\u062f\u06c1 \u06a9\u06d2 \u06c1\u0627\u062a\u06be \u0633\u06d2 \u062e\u064f\u062f\u0627 \u06a9\u06cc \u0645\u0631\u0636\u06cc \u06a9\u06d2 \u0627\u0633\u0650\u06cc\u0631\u06c1\u0648 \u06a9\u0631 \u0627\u0650\u0628\u0644\u0650\u06cc\u0633 \u06a9\u06d2 \u067e\u06be\u0646\u062f\u06d2 \u0633\u06d2 \u0686\u064f\u06be\u0648\u0679\u06cc\u06ba\u06d4\n\n\u06c1\u0645 \u0645\u0644 \u06a9\u0631 \u06cc\u0633\u0639\u06cc\u0627\u06c1 40:8 \u067e\u0691\u06be\u06cc\u06ba \u06af\u06d2:\n\u201d\u06af\u06be\u0627\u0633 \u0645\u0631\u062c\u06be\u0627 \u062c\u0627\u062a\u06cc \u06c1\u06d2\u060c \u067e\u06be\u0648\u0644 \u0645\u0631\u062c\u06be\u0627 \u062c\u0627\u062a\u0627 \u06c1\u06d2\u060c \u0644\u06cc\u06a9\u0646 \u06c1\u0645\u0627\u0631\u06d2 \u062e\u062f\u0627 \u06a9\u0627 \u06a9\u0644\u0627\u0645 \u06c1\u0645\u06cc\u0634\u06c1 \u0642\u0627\u0626\u0645 \u0631\u06c1\u06d2 \u06af\u0627\u06d4\u201d\n\n\u0622\u06cc\u062a 22 \u06a9\u06c1\u062a\u06cc \u06c1\u06d2:\n22 \u201d\u062c\u0648\u0627\u0646\u06cc \u06a9\u06cc \u062e\u0648\u0627\u06c1\u0650\u0634\u0648\u06ba \u0633\u06d2 \u0628\u06be\u0627\u06af \u0627\u0648\u0631 \u062c\u0648 \u067e\u0627\u06a9 \u062f\u0650\u0644 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u062e\u064f\u062f\u0627\u0648\u0646\u062f \u0633\u06d2 \u062f\u064f\u0639\u0627 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u064f\u0646 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0631\u0627\u0633\u062a \u0628\u0627\u0632\u06cc \u0627\u0648\u0631 \u0627\u0650\u06cc\u0645\u0627\u0646 \u0627\u0648\u0631 \u0645\u064f\u062d\u0628\u0651\u062a \u0627\u0648\u0631 \u0635\u064f\u0644\u062d \u06a9\u0627 \u0637\u0627\u0644\u0650\u0628 \u06c1\u0648\u06d4\u201d\n\n\u06cc\u06c1 \u0622\u06cc\u062a \u0648\u0627\u0642\u0639\u06cc \u0622\u062c \u06a9\u06d2 \u0648\u0627\u0639\u0638 \u06a9\u0627 \u062e\u0644\u0627\u0635\u06c1 \u06c1\u06d2\u06d4\n\u06c1\u0645 \u06cc\u06c1 \u0627\u06a9\u062b\u0631 \u062e\u062f\u0627 \u06a9\u06d2 \u06a9\u0644\u0627\u0645 \u0645\u06cc\u06ba \u062f\u06cc\u06a9\u06be\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u06a9\u0628\u06be\u06cc \u06a9\u0628\u06be\u06cc \u0632\u0628\u0648\u0631 \u06cc\u0627 \u067e\u06cc\u0631\u0627\u06af\u0631\u0627\u0641 \u0645\u06cc\u06ba \u067e\u06c1\u0644\u0627 \u0628\u06cc\u0627\u0646 \u062e\u0644\u0627\u0635\u06c1 \u06c1\u0648\u06af\u0627\u06d4\n\u0627\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u0622\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0627\u0644\u0641\u0627\u0638 \u067e\u0648\u0631\u06d2 \u0632\u0628\u0648\u0631 \u06cc\u0627 \u067e\u06cc\u0631\u0627\u06af\u0631\u0627\u0641 \u06cc\u0627 \u0628\u0627\u0628 \u06a9\u06cc \u0648\u0636\u0627\u062d\u062a \u06c1\u06cc\u06ba\u06d4\n\u0627\u06cc\u06a9 \u0628\u0627\u0644\u063a \u0645\u0633\u06cc\u062d\u06cc \u0645\u0631\u062f \u06cc\u0627 \u0639\u0648\u0631\u062a \u0648\u06c1 \u06c1\u0648\u062a\u0627 \u06c1\u06d2 \u062c\u0648 \u0627\u064f\u0646 \u0686\u06cc\u0632\u0648\u06ba \u0633\u06d2 \u062f\u0648\u0631 \u06c1\u0648 \u062c\u0627\u062a\u0627 \u06c1\u06d2 \u062c\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06c1\u0645\u06cc\u06ba \u062c\u0648\u0627\u0646\u06cc \u06a9\u06d2 \u0639\u0627\u0644\u0645 \u0645\u06cc\u06ba \u0622\u0632\u0645\u0627\u06cc\u0627 \u062a\u06be\u0627\u06d4\n\u201d\u062c\u0648\u0627\u0646\u06cc \u06a9\u06cc \u062e\u0648\u0627\u06c1\u0634\u0648\u06ba\u201d \u06a9\u06d2 \u0628\u062c\u0627\u0626\u06d2 \u0627\u06cc\u06a9 \u0628\u0627\u0644\u063a \u0634\u062e\u0635 \u062e\u062f\u0627 \u06a9\u06cc \u0627\u0642\u062f\u0627\u0631 \u0628\u0634\u0645\u0648\u0644 \u0631\u0627\u0633\u062a\u0628\u0627\u0632\u06cc\u060c \u0627\u06cc\u0645\u0627\u0646\u060c \u0645\u062d\u0628\u062a\u060c \u0635\u064f\u0644\u062d \u06a9\u0627 \u0637\u0627\u0644\u0628 \u06c1\u0648\u0646\u0627 \u0633\u06cc\u06a9\u06be \u0631\u06c1\u0627 \u06c1\u06d2\u06d4\n\u062c\u0628 \u067e\u0648\u0644\u0633 \u062c\u0648\u0627\u0646 \u062a\u06be\u0627 \u062a\u0648 \u0627\u0633 \u06a9\u0627 \u0646\u0627\u0645 \u0633\u0627\u0624\u0644 \u062a\u06be\u0627\u06d4\n\u0633\u0627\u0624\u0644 \u0641\u062e\u0631 \u0627\u0648\u0631 \u062e\u0648\u062f \u0627\u0639\u062a\u0645\u0627\u062f\u06cc \u0633\u06d2 \u0628\u06be\u0631\u0627 \u06c1\u0648\u0627 \u062a\u06be\u0627\u060c \u0645\u0633\u06cc\u062d\u06cc\u0648\u06ba \u06a9\u0648 \u0627\u0630\u06cc\u062a \u062f\u06cc\u0646\u06d2 \u0627\u0648\u0631 \u0627\u0646\u06c1\u06cc\u06ba \u062c\u06cc\u0644 \u0645\u06cc\u06ba \u0688\u0627\u0644\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0637\u0627\u0642\u062a \u06a9\u0627 \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u06a9\u0631\u062a\u0627 \u062a\u06be\u0627\u06d4\n\u0633\u0627\u0624\u0644 \u0645\u0642\u0628\u0648\u0644 \u0627\u0648\u0631 \u06a9\u0627\u0645\u06cc\u0627\u0628 \u06c1\u0648\u0646\u0627 \u0686\u0627\u06c1\u062a\u0627 \u062a\u06be\u0627 \u0627\u0648\u0631 \u0627\u067e\u0646\u06d2 \u063a\u0631\u0648\u0631 \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u062f\u0648\u0633\u0631\u0648\u06ba \u06a9\u0648 \u062a\u06a9\u0644\u06cc\u0641 \u067e\u06c1\u0646\u0686\u0627\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u062a\u06cc\u0627\u0631 \u062a\u06be\u0627\u06d4\n\u0644\u06cc\u06a9\u0646 2 \u062a\u06cc\u0645\u062a\u06be\u06cc\u0633 \u06a9\u0627 \u062e\u0637 \u0627\u06cc\u06a9 \u0628\u0627\u0644\u063a \u0627\u06cc\u0645\u0627\u0646\u062f\u0627\u0631 \u067e\u0648\u0644\u0633 \u0646\u06d2 \u0644\u06a9\u06be\u0627 \u062a\u06be\u0627\u06d4\n\u0648\u06c1 \u0633\u0645\u062c\u06be\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0627\u0633 \u06a9\u06d2 \u062c\u0648\u0627\u0646\u06cc \u06a9\u06d2 \u062c\u0630\u0628\u0627\u062a \u0646\u06d2 \u06a9\u062a\u0646\u0627 \u0646\u0642\u0635\u0627\u0646 \u067e\u06c1\u0646\u0686\u0627\u06cc\u0627\u060c \u0627\u0648\u0631 \u062a\u06cc\u0645\u062a\u06be\u06cc\u0633 \u06a9\u0648 \u0627\u0646 \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u062e\u0628\u0631\u062f\u0627\u0631 \u06a9\u0631 \u0631\u06c1\u0627 \u06c1\u06d2\u06d4\n\u062c\u0633 \u0648\u0642\u062a \u067e\u0648\u0644\u0633 \u06cc\u06c1 \u062e\u0637 \u0644\u06a9\u06be \u0631\u06c1\u0627 \u06c1\u06d2\u060c \u062a\u06cc\u0645\u062a\u06be\u06cc\u0633 \u06a9\u06cc \u0639\u0645\u0631 \u063a\u0627\u0644\u0628\u0627\u064b 40 \u0633\u0627\u0644 \u06a9\u06d2 \u0642\u0631\u06cc\u0628 \u06c1\u06d2\u06d4\n\u0644\u06cc\u06a9\u0646 \u201d\u062c\u0648\u0627\u0646\u06cc \u06a9\u06cc \u062e\u0648\u0627\u06c1\u0634\u0648\u06ba\u201d \u06a9\u06cc \u0637\u0631\u0641 \u0628\u06be\u0627\u06af\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0622\u067e \u06a9\u0648 \u062c\u0648\u0627\u0646 \u06c1\u0648\u0646\u0627 \u0636\u0631\u0648\u0631\u06cc \u0646\u06c1\u06cc\u06ba \u06c1\u06d2\u06d4\n\u0645\u06cc\u06ba 57 \u0633\u0627\u0644 \u06a9\u0627 \u06c1\u0648\u06ba\u060c \u0644\u06cc\u06a9\u0646 \u0645\u06cc\u06ba \u0627\u0628 \u0628\u06be\u06cc \u062c\u0648\u0627\u0646\u06cc \u06a9\u06d2 \u062c\u0630\u0628\u0648\u06ba \u0633\u06d2 \u0645\u0633\u0644\u0633\u0644 \u0628\u06be\u0627\u06af\u0646\u0627 \u0633\u06cc\u06a9\u06be \u0631\u06c1\u0627 \u06c1\u0648\u06ba\u06d4\n\u0645\u06cc\u0631\u0627 \u0627\u06cc\u06a9 \u06a9\u0627\u0644\u062c \u06a9\u0627 \u062f\u0648\u0633\u062a \u06c1\u06d2 \u062c\u0633 \u06a9\u06cc \u0639\u0645\u0631 \u0645\u06cc\u0631\u06d2 \u062c\u06cc\u0633\u06cc \u06c1\u06d2\u06d4\n\u0644\u06cc\u06a9\u0646 \u0648\u06c1 \u0627\u0628 \u0628\u06be\u06cc 35 \u0633\u0627\u0644 \u067e\u06c1\u0644\u06d2 \u06a9\u06cc \u0637\u0631\u062d \u062c\u06cc\u062a\u0627 \u06c1\u06d2\u06d4\n\u0627\u0646 \u06a9\u06cc \u0632\u0646\u062f\u06af\u06cc \u067e\u0631 \u06c1\u0645\u0627\u0631\u06d2 \u06a9\u0627\u0644\u062c \u06a9\u06d2 \u062f\u0646\u0648\u06ba \u06a9\u06d2 \u0646\u0648\u062c\u0648\u0627\u0646\u0648\u06ba \u06a9\u06d2 \u062c\u0630\u0628\u0627\u062a \u06a9\u0627 \u063a\u0644\u0628\u06c1 \u06c1\u06d2\u06d4\n\u06cc\u06c1\u0627\u06ba \u06a9\u0686\u06be \u062c\u0648\u0627\u0646\u06cc \u06a9\u06cc \u062e\u0648\u0627\u06c1\u0634\u06cc\u06ba \u06c1\u06cc\u06ba \u062c\u0646 \u06a9\u0627 \u06c1\u0645 \u0645\u06cc\u06ba \u0633\u06d2 \u0628\u06c1\u062a \u0633\u06d2 \u0644\u0648\u06af \u062a\u062c\u0631\u0628\u06c1 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba:\n\n*   \u062e\u0648\u0634\u06cc: \u062c\u0646\u0633\u06cc \u06af\u0646\u0627\u06c1 \u062e\u0648\u0634\u06cc \u06a9\u06d2 \u06af\u0646\u0627\u06c1 \u06a9\u06cc \u0627\u06cc\u06a9 \u0639\u0627\u0645 \u0645\u062b\u0627\u0644 \u06c1\u06d2\u060c \u0644\u06cc\u06a9\u0646 \u06cc\u06c1 \u0648\u0627\u062d\u062f \u0646\u06c1\u06cc\u06ba \u06c1\u06d2\u06d4\n\u062f\u0648\u0633\u0631\u06cc \u06af\u0646\u06c1\u06af\u0627\u0631 \u0644\u0630\u062a\u0648\u06ba \u0645\u06cc\u06ba \u0634\u0631\u0627\u0628\u060c \u06a9\u06be\u0627\u0646\u0627 \u0627\u0648\u0631 \u06a9\u0626\u06cc \u0637\u0631\u062d \u06a9\u06cc \u062a\u0641\u0631\u06cc\u062d \u0634\u0627\u0645\u0644 \u06c1\u0648 \u0633\u06a9\u062a\u06cc \u06c1\u06d2\u06d4\n\u06cc\u06c1 \u0686\u06cc\u0632\u06cc\u06ba \u0628\u0631\u06cc \u0646\u06c1\u06cc\u06ba \u06c1\u06cc\u06ba \u0627\u06af\u0631 \u0627\u0646 \u06a9\u0627 \u0635\u062d\u06cc\u062d \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u06a9\u06cc\u0627 \u062c\u0627\u0626\u06d2\u06d4\n\u0645\u062b\u0627\u0644 \u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631\u060c \u0645\u0633\u06cc\u062d\u06cc \u0634\u0627\u062f\u06cc \u06a9\u06d2 \u062a\u0646\u0627\u0638\u0631 \u0645\u06cc\u06ba \u062c\u0633\u0645\u0627\u0646\u06cc \u0645\u0644\u0627\u067e \u0627\u06cc\u06a9 \u062e\u0648\u0628\u0635\u0648\u0631\u062a \u062a\u062d\u0641\u06c1 \u06c1\u06d2\u06d4\n\u0644\u06cc\u06a9\u0646 \u062c\u0628 \u06c1\u0645 \u06a9\u0633\u06cc \u0628\u06be\u06cc \u0686\u06cc\u0632 \u06a9\u0648 \u063a\u0644\u0637 \u0637\u0631\u06cc\u0642\u06d2 \u0633\u06d2 \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u062a\u0648 \u06c1\u0645 \u0627\u0633\u06d2 \u0627\u067e\u0646\u06cc \u0632\u0646\u062f\u06af\u06cc \u067e\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u062f\u06cc\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u062c\u0628 \u06c1\u0645 \u0627\u067e\u0646\u06d2 \u062f\u0644\u0648\u06ba \u0645\u06cc\u06ba \u0645\u0648\u062c\u0648\u062f \u062e\u0627\u0644\u06cc \u067e\u0646 \u06a9\u0648 \u0628\u06be\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u062e\u064f\u062f\u0627 \u06a9\u06d2 \u06a9\u0633\u06cc \u062a\u062d\u0641\u06d2 \u06a9\u0648 \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u062a\u0648 \u0648\u06c1 \u0686\u06cc\u0632 \u0627\u06cc\u06a9 \u062c\u06be\u0648\u0679\u0627 \u062e\u062f\u0627 \u0628\u0646 \u062c\u0627\u062a\u0627 \u06c1\u06d2- \u0627\u06cc\u06a9 \u0628\u062a\u06d4\n\n*   \u0637\u0627\u0642\u062a: \u062c\u0628 \u06c1\u0645 \u062c\u0648\u0627\u0646 \u06c1\u0648\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u062a\u0648 \u06c1\u0645 \u0628\u0639\u0636 \u0627\u0648\u0642\u0627\u062a \u0628\u06d2 \u0627\u062e\u062a\u06cc\u0627\u0631\u060c \u06a9\u0645\u0632\u0648\u0631 \u06cc\u0627 \u0646\u0627\u06a9\u0627\u0641\u06cc \u0645\u062d\u0633\u0648\u0633 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u0645\u06cc\u06ba \u0646\u06d2 \u0627\u06cc\u06a9 \u0646\u0648\u062c\u0648\u0627\u0646 \u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631 \u0627\u0646 \u0627\u062d\u0633\u0627\u0633\u0627\u062a \u06a9\u06d2 \u0633\u0627\u062a\u06be \u062c\u062f\u0648\u062c\u06c1\u062f \u06a9\u06cc.\n\u06a9\u0686\u06be \u0644\u0648\u06af \u0627\u067e\u0646\u06cc \u06a9\u0645\u0632\u0648\u0631\u06cc \u06a9\u06d2 \u0627\u062d\u0633\u0627\u0633 \u06a9\u0648 \u0686\u06be\u067e\u0627\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0637\u0627\u0642\u062a \u06a9\u0627 \u067e\u06cc\u0686\u06be\u0627 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u0648\u06c1 \u0633\u0648\u0686\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u0637\u0627\u0642\u062a\u0648\u0631 \u062f\u0650\u06a9\u06be\u0646\u0627 \u0627\u0646\u06c1\u06cc\u06ba \u0645\u062d\u0641\u0648\u0638 \u0645\u062d\u0633\u0648\u0633 \u06a9\u0631\u0646\u06d2 \u0645\u06cc\u06ba \u0645\u062f\u062f \u062f\u06d2 \u06af\u0627\u06d4\n\u06a9\u06cc\u0627 \u0622\u067e \u062c\u0627\u0646\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u0628\u062f\u0645\u0639\u0627\u0634 \u062f\u0631\u062d\u0642\u06cc\u0642\u062a \u0627\u062a\u0646\u0627 \u0645\u0636\u0628\u0648\u0637 \u0646\u06c1\u06cc\u06ba \u06c1\u0648\u062a\u0627 \u062c\u062a\u0646\u0627 \u0648\u06c1 \u0646\u0638\u0631 \u0622\u062a\u0627 \u06c1\u06d2\u061f\n\u0628\u062f\u0645\u0639\u0627\u0634 \u0639\u0627\u0645 \u0637\u0648\u0631 \u067e\u0631 \u0648\u06c1 \u06c1\u0648\u062a\u0627 \u06c1\u06d2 \u062c\u0648 \u0627\u067e\u0646\u06cc \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u06ba \u06a9\u0633\u06cc \u0686\u06cc\u0632 \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u0628\u06d2 \u0627\u062e\u062a\u06cc\u0627\u0631 \u0645\u062d\u0633\u0648\u0633 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u060c \u0627\u0633 \u0644\u06cc\u06d2 \u0648\u06c1 \u062e\u0648\u062f \u06a9\u0648 \u0637\u0627\u0642\u062a\u0648\u0631 \u0645\u062d\u0633\u0648\u0633 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u062f\u0648\u0633\u0631\u06d2 \u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u062a\u06a9\u0644\u06cc\u0641 \u062f\u06cc\u062a\u0627 \u06c1\u06d2\u06d4\n\n*   \u0645\u0642\u0628\u0648\u0644\u06cc\u062a: \u06cc\u06c1 \u0645\u06cc\u0631\u06cc \u0632\u0646\u062f\u06af\u06cc \u06a9\u0627 \u0627\u06cc\u06a9 \u0627\u0648\u0631 \u0645\u0636\u0628\u0648\u0637 \u0641\u062a\u0646\u06c1 \u0627\u0648\u0631 \u0622\u0632\u0645\u0627\u0626\u0634 \u0631\u06c1\u06cc \u06c1\u06d2\u06d4\n\u0645\u06cc\u06ba \u0627\u06a9\u062b\u0631 \u067e\u0631\u06cc\u0634\u0627\u0646 \u0631\u06c1\u062a\u0627 \u06c1\u0648\u06ba \u06a9\u06c1 \u06a9\u06cc\u0627 \u0644\u0648\u06af \u0645\u062c\u06be\u06d2 \u067e\u0633\u0646\u062f \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u0645\u062c\u06be\u06d2 \u062f\u0648\u0633\u0631\u06d2 \u0644\u0648\u06af\u0648\u06ba \u06a9\u06cc \u0631\u0627\u0626\u06d2 \u06a9\u06cc \u0628\u06c1\u062a \u0632\u06cc\u0627\u062f\u06c1 \u067e\u0631\u0648\u0627\u06c1 \u06c1\u06d2\u06d4\n\u0622\u067e \u0627\u067e\u0646\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u0628\u062a\u0627\u0626\u06cc\u06ba\u061f\n\u06a9\u06cc\u0627 \u0622\u067e \u0627\u067e\u0646\u0627 \u0631\u0648\u06cc\u06c1 \u06cc\u0627 \u0634\u06a9\u0644 \u0627\u0633 \u0644\u06cc\u06d2 \u0628\u062f\u0644\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u0644\u0648\u06af \u0622\u067e \u06a9\u0648 \u067e\u0633\u0646\u062f \u06a9\u0631\u06cc\u06ba\u061f\n\u06a9\u06cc\u0627 \u0622\u067e \u06a9\u0648 \u0644\u06af\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0645\u0633\u062a\u0631\u062f \u06c1\u0648\u0646\u06d2 \u0633\u06d2 \u0628\u0686\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0622\u067e \u06a9\u0648 \u06a9\u0627\u0645 \u06a9\u0631\u0646\u0627 \u06c1\u06d2 \u06cc\u0627 \u06a9\u0648\u0626\u06cc \u062e\u0627\u0635 \u0637\u0631\u06cc\u0642\u06c1 \u062f\u06cc\u06a9\u06be\u0646\u0627 \u06c1\u0648\u06af\u0627\u061f\n\n*   \u0645\u0627\u0644: \u067e\u06cc\u0633\u06d2 \u0627\u0648\u0631 \u0645\u0627\u062f\u06cc \u0627\u0645\u0644\u0627\u06a9 \u06a9\u06cc \u0645\u062d\u0628\u062a \u06c1\u0645 \u0645\u06cc\u06ba \u0633\u06d2 \u0627\u06a9\u062b\u0631 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0627\u06cc\u06a9 \u0645\u0633\u0626\u0644\u06c1 \u06c1\u06d2\u06d4\n\u06c1\u0645 \u0632\u06cc\u0627\u062f\u06c1 \u0686\u06cc\u0632\u06cc\u06ba \u06c1\u0648\u0646\u06d2 \u06a9\u06cc \u0633\u0644\u0627\u0645\u062a\u06cc \u0627\u0648\u0631 \u0631\u0627\u062d\u062a \u0686\u0627\u06c1\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u0627\u0633 \u0633\u06d2 \u0627\u06cc\u0645\u0627\u0646 \u06a9\u06cc \u06a9\u0645\u06cc \u06a9\u0627 \u067e\u062a\u06c1 \u0686\u0644\u062a\u0627 \u06c1\u06d2\u06d4\n\u062e\u062f\u0627 \u0686\u0627\u06c1\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1 \u06c1\u0645 \u06cc\u06c1 \u0633\u0645\u062c\u06be\u06cc\u06ba \u06a9\u06c1 \u0648\u06c1 \u06c1\u0645\u0627\u0631\u06cc \u067e\u0646\u0627\u06c1 \u06af\u0627\u06c1 \u0627\u0648\u0631 \u0642\u0644\u0639\u06c1 \u06c1\u06d2\u060c \u0648\u06c1 \u06c1\u0645\u0627\u0631\u0627 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u0627 \u06c1\u06d2\u06d4\n\u0645\u0627\u062f\u06cc \u0686\u06cc\u0632\u06cc\u06ba \u062e\u0648\u0634\u06cc \u06a9\u0627 \u0648\u0639\u062f\u06c1 \u06a9\u0631\u062a\u06cc \u06c1\u06cc\u06ba\u060c \u0644\u06cc\u06a9\u0646 \u0648\u06c1 \u0627\u067e\u0646\u06d2 \u0648\u0639\u062f\u06d2 \u067e\u0631 \u06a9\u0628\u06be\u06cc \u0639\u0645\u0644 \u0646\u06c1\u06cc\u06ba \u06a9\u0631 \u0633\u06a9\u062a\u06cc\u06ba\u06d4\n\u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u06c1\u0645\u0627\u0631\u06d2 \u062f\u0644 \u06c1\u0645\u06cc\u0634\u06c1 \u0632\u06cc\u0627\u062f\u06c1 \u06a9\u06d2 \u0644\u06cc\u06d2 \u062a\u0631\u0633\u062a\u06d2 \u0631\u06c1\u06cc\u06ba \u06af\u06d2\u06d4\n\n*   \u0641\u062e\u0631: \u06cc\u06c1 \u0648\u0627\u0642\u0639\u06cc \u06c1\u0631 \u062f\u0648\u0633\u0631\u06d2 \u06af\u0646\u0627\u06c1 \u06a9\u06d2 \u0646\u06cc\u0686\u06d2 \u0686\u06be\u067e\u0627 \u06c1\u0648\u0627 \u06af\u0646\u0627\u06c1 \u06c1\u06d2\u06d4\n\u0641\u062e\u0631 \u06cc\u06c1 \u06cc\u0642\u06cc\u0646 \u06c1\u06d2 \u06a9\u06c1 \u0645\u06cc\u06ba \u0627\u0635\u0644 \u0645\u06cc\u06ba \u0645\u0627\u0644\u060c \u0637\u0627\u0642\u062a\u060c \u062e\u0648\u0634\u06cc \u0627\u0648\u0631 \u0645\u0642\u0628\u0648\u0644\u06cc\u062a \u06a9\u0627 \u0645\u0633\u062a\u062d\u0642 \u06c1\u0648\u06ba\u06d4\n\u06a9\u06cc\u0648\u06ba\u061f \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0645\u06cc\u06ba \u062e\u0627\u0635 \u06c1\u0648\u06ba\u06d4\n\u0641\u062e\u0631 \u06c1\u0645 \u0633\u06d2 \u062c\u06be\u0648\u0679 \u0628\u0648\u0644\u062a\u0627 \u06c1\u06d2:\n\u201d\u06cc\u06c1 \u0679\u06be\u06cc\u06a9 \u06c1\u06d2\u060c \u0622\u067e \u06cc\u06c1 \u06a9\u0631 \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba-- \u0622\u067e \u0627\u0633 \u06a9\u06d2 \u0645\u0633\u062a\u062d\u0642 \u06c1\u06cc\u06ba\u06d4\u201d\n\u0645\u0634\u062a\u06c1\u0631\u06cc\u0646 \u0628\u06be\u06cc \u06c1\u0645 \u0633\u06d2 \u06cc\u06c1\u06cc \u06a9\u06c1\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u201d\u0622\u067e \u0627\u0633 \u06a9\u06d2 \u0645\u0633\u062a\u062d\u0642 \u06c1\u06cc\u06ba\u2026 \u0622\u06af\u06d2 \u0628\u0691\u06be\u06cc\u06ba\u060c \u0627\u0633\u06d2 \u062e\u0631\u06cc\u062f\u06cc\u06ba\u06d4\n\u0634\u0627\u06cc\u062f \u06a9\u0686\u06be \u0627\u0648\u0631 \u062e\u0631\u06cc\u062f \u0644\u06cc\u06ba\u060c \u06cc\u06c1 \u0679\u06be\u06cc\u06a9 \u06c1\u06d2\u06d4\u201d\n\u0627\u0633 \u0644\u06cc\u06d2 \u06c1\u0645 \u0627\u0633 \u0637\u0631\u062d \u06a9\u06d2 \u0628\u06c1\u062a \u0633\u06d2 \u0627\u0634\u062a\u06c1\u0627\u0631\u0627\u062a \u062f\u06cc\u06a9\u06be\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u06c1\u0645\u0627\u0631\u0627 \u0641\u062e\u0631 \u062f\u0631\u0627\u0635\u0644 \u0627\u0646 \u0628\u0627\u062a\u0648\u06ba \u067e\u0631 \u06cc\u0642\u06cc\u0646 \u06a9\u0631\u0646\u0627 \u0686\u0627\u06c1\u062a\u0627 \u06c1\u06d2\u06d4\n\n\u06a9\u06cc\u0627 \u0645\u06cc\u06ba \u0622\u067e \u0633\u06d2 \u0627\u06cc\u06a9 \u0633\u0648\u0627\u0644 \u067e\u0648\u0686\u06be \u0633\u06a9\u062a\u0627 \u06c1\u0648\u06ba \u062f\u0648\u0633\u062a\u0648\u06ba\u061f\n\u0627\u0646 \u067e\u0627\u0646\u0686 \u0686\u06cc\u0632\u0648\u06ba \u0645\u06cc\u06ba \u0633\u06d2 \u06a9\u0648\u0646 \u0633\u06cc \u0686\u06cc\u0632 \u0622\u067e \u06a9\u0648 \u0627\u0686\u06be\u06cc \u0644\u06af\u062a\u06cc \u06c1\u06d2\u061f\n\u06a9\u06cc\u0627 \u0622\u067e \u0641\u062e\u0631\u060c \u0645\u0627\u0644\u060c \u0637\u0627\u0642\u062a\u060c \u062e\u0648\u0634\u06cc\u060c \u06cc\u0627 \u0645\u0642\u0628\u0648\u0644\u06cc\u062a \u06a9\u06cc \u062a\u0644\u0627\u0634 \u0645\u06cc\u06ba \u06c1\u06cc\u06ba\u061f\n\u06cc\u0627 \u0634\u0627\u06cc\u062f \u06cc\u06c1 \u06a9\u0648\u0626\u06cc \u0627\u0648\u0631 \u0686\u06cc\u0632 \u06c1\u06d2 \u062c\u0648 \u0622\u067e \u06a9\u0648 \u062e\u062f\u0627 \u0633\u06d2 \u062f\u0648\u0631 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u061f\n\u0622\u062c \u0622\u067e\u06a9\u0627 \u062f\u0644 \u06a9\u06c1\u0627\u06ba \u06c1\u06d2\u060c \u0627\u0648\u0631 \u0622\u067e \u06a9\u06c1\u0627\u06ba \u062c\u0627 \u0631\u06c1\u06d2 \u06c1\u0648\u061f\n\u06a9\u06cc\u0627 \u0622\u067e \u06a9\u0648 \u06cc\u0627\u062f \u06c1\u06d2 \u06a9\u06c1 \u062e\u064f\u062f\u0627 \u0646\u06d2 \u0622\u062f\u0645 \u0633\u06d2 \u0628\u0627\u063a \u0645\u06cc\u06ba \u067e\u06be\u0644 \u06a9\u06be\u0627\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u06a9\u06cc\u0627 \u067e\u0648\u0686\u06be\u0627\u061f\n\u0622\u062f\u0645 \u0627\u0648\u0631 \u062d\u0648\u0627 \u0686\u06be\u067e\u06d2 \u06c1\u0648\u0626\u06d2 \u062a\u06be\u06d2\u060c \u0627\u0648\u0631 \u062e\u062f\u0627 \u0646\u06d2 \u06a9\u06c1\u0627\u060c \u201d\u0627\u06d2 \u0622\u062f\u0645! \u062a\u064f\u0648 \u06a9\u06c1\u0627\u06ba \u06c1\u0648\u061f\u201d\n\u062e\u062f\u0627 \u0622\u062c \u0632\u0645\u06cc\u0646 \u067e\u0631 \u06c1\u0631 \u0627\u06cc\u06a9 \u0633\u06d2 \u06cc\u06c1\u06cc \u067e\u0648\u0686\u06be \u0631\u06c1\u0627 \u06c1\u06d2\u06d4\n\u062a\u0648 \u06a9\u06c1\u0627\u06ba \u06c1\u0648\u061f\n\u0648\u06c1 \u06cc\u06c1 \u0646\u06c1\u06cc\u06ba \u067e\u0648\u0686\u06be \u0631\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u062a\u0648 \u062c\u0633\u0645\u0627\u0646\u06cc \u0637\u0648\u0631 \u067e\u0631 \u06a9\u06c1\u0627\u06ba \u06c1\u06cc\u06ba\u06d4\n\u0648\u06c1 \u067e\u0648\u0686\u06be \u0631\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u062a\u06cc\u0631\u0627 \u062f\u0644 \u06a9\u06c1\u0627\u06ba \u06c1\u06d2\u061f\n\u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u06c1\u0645\u0627\u0631\u06d2 \u062f\u0644 \u0627\u06cc\u06a9 \u06a9\u0645\u067e\u0627\u0633 \u06a9\u06cc \u0637\u0631\u062d \u06c1\u06cc\u06ba \u062c\u0648 \u06c1\u0645\u06cc\u06ba \u0627\u0633 \u0686\u06cc\u0632 \u06a9\u06cc \u0637\u0631\u0641 \u0644\u06d2 \u062c\u0627\u062a\u0627 \u06c1\u06d2 \u062c\u0633 \u06a9\u06cc \u06c1\u0645 \u0633\u0628 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u0642\u062f\u0631 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u06c1\u0645 \u06a9\u06be\u0648 \u06c1\u0648 \u062c\u0627\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u06c1\u0645\u06cc\u06ba \u0627\u0633 \u06a9\u0627 \u0639\u0644\u0645 \u0628\u06be\u06cc \u0646\u06c1\u06cc\u06ba \u06c1\u0648\u062a\u0627 \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u06af\u0646\u0627\u06c1 \u0645\u06a9\u0627\u0631\/\u062f\u06be\u0648\u06a9\u0627 \u06c1\u0648\u062a\u0627 \u06c1\u06d2\u06d4\n\u06c1\u0645\u06cc\u06ba \u06cc\u06c1 \u062f\u06cc\u06a9\u06be\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u062e\u062f\u0627 \u06a9\u06cc \u0645\u062f\u062f \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u06c1\u06d2 \u06a9\u06c1 \u06c1\u0645\u0627\u0631\u06d2 \u0627\u0646\u062f\u0631 \u06a9\u06cc\u0627 \u06c1\u0648 \u0631\u06c1\u0627 \u06c1\u06d2\u06d4\n\u0622\u0626\u06cc\u06d2 \u0627\u06cc\u06a9 \u0633\u0627\u062a\u06be \u062f\u0639\u0627 \u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631 \u0632\u0628\u0648\u0631 139:23-24 \u067e\u0691\u06be\u06cc\u06ba:\n\u062a\u0645\u0627\u0645: 23 \u201d\u0627\u064e\u06d2 \u062e\u064f\u062f\u0627! \u062a\u064f\u0648 \u0645\u064f\u062c\u06be\u06d2 \u062c\u0627\u0646\u0686 \u0627\u0648\u0631 \u0645\u06cc\u0631\u06d2 \u062f\u0650\u0644 \u06a9\u0648 \u067e\u06c1\u0686\u0627\u0646\u06d4\n\u0645\u064f\u062c\u06be\u06d2 \u0622\u0632\u0645\u0627 \u0627\u0648\u0631 \u0645\u06cc\u0631\u06d2 \u062e\u06cc\u0627\u0644\u0648\u06ba \u06a9\u0648 \u062c\u0627\u0646 \u0644\u06d2\n24 \u0627\u0648\u0631 \u062f\u06cc\u06a9\u06be \u06a9\u06c1 \u0645\u064f\u062c\u06be \u0645\u06cc\u06ba \u06a9\u0648\u0626\u06cc \u0628\u064f\u0631\u06cc \u0631\u0648\u0650\u0634 \u062a\u0648 \u0646\u06c1\u06cc\u06ba \n\u0627\u0648\u0631 \u0645\u064f\u062c\u06be \u06a9\u0648 \u0627\u0628\u062f\u06cc \u0631\u0627\u06c1 \u0645\u06cc\u06ba \u0644\u06d2 \u0686\u0644!\u2018\u2018\n\n\u062e\u062f\u0627 \u06a9\u06cc \u0645\u062f\u062f \u06a9\u06d2 \u0628\u063a\u06cc\u0631\u060c \u06c1\u0645 \u201d\u0627\u0628\u062f\u06cc \u0631\u0627\u06c1 \u0645\u06cc\u06ba\u201c \u0646\u06c1\u06cc\u06ba \u0686\u0644 \u067e\u0627\u0626\u06cc\u06ba \u06af\u06d2\u06d4\n\u06c1\u0645 \u063a\u0644\u0637 \u0633\u0645\u062a \u0645\u06cc\u06ba \u0628\u06be\u0627\u06af\u06cc\u06ba \u06af\u06d2\u060c \u0627\u06cc\u0633\u06cc \u0686\u06cc\u0632\u0648\u06ba \u06a9\u0627 \u067e\u06cc\u0686\u06be\u0627 \u06a9\u0631\u06cc\u06ba \u06af\u06d2 \u062c\u0648 \u06c1\u0645\u06cc\u06ba \u062e\u062f\u0627 \u06a9\u06d2 \u062f\u0644 \u0633\u06d2 \u062f\u0648\u0631 \u0644\u06d2 \u062c\u0627\u062a\u06cc \u06c1\u06cc\u06ba\u06d4\n\u0644\u06cc\u06a9\u0646 \u062e\u062f\u0627 \u0627\u062a\u0646\u0627 \u0627\u0686\u06be\u0627 \u06c1\u06d2 \u06a9\u06c1 \u06c1\u0645\u06cc\u06ba \u0635\u0631\u0641 \u0628\u06be\u0679\u06a9\u062a\u06d2 \u0627\u0648\u0631 \u06a9\u06be\u0648\u062a\u06d2 \u06c1\u06cc \u0646\u06c1\u06cc\u06ba \u062f\u06cc\u06a9\u06be\u062a\u0627\u06d4\n\u0627\u0633 \u06a9\u06d2 \u0628\u062c\u0627\u0626\u06d2\u060c \u0648\u06c1 \u0627\u067e\u0646\u06cc \u06a9\u06be\u0648\u0626\u06cc \u06c1\u0648\u0626\u06cc \u0628\u06be\u06cc\u0691\u0648\u06ba \u06a9\u0648 \u0688\u06be\u0648\u0646\u0688\u062a\u0627 \u06c1\u06d2\u06d4\n\u0648\u06c1 \u06c1\u0645\u0627\u0631\u06d2 \u067e\u0627\u0633 \u0622\u062a\u0627 \u06c1\u06d2 \u0627\u0648\u0631 \u0631\u06c1\u0627\u0626\u06cc \u0627\u0648\u0631 \u0646\u062c\u0627\u062a \u06a9\u0627 \u0631\u0627\u0633\u062a\u06c1 \u067e\u06cc\u0634 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4\n2 \u062a\u06cc\u0645\u062a\u06be\u06cc\u0633 2:25b-26 \u06a9\u0648 \u062f\u0648\u0628\u0627\u0631\u06c1 \u062f\u06cc\u06a9\u06be\u06cc\u06ba:\n25b \u201d\u0634\u0627\u06cc\u062f \u062e\u064f\u062f\u0627 \u0627\u064f\u0646\u06c1\u06cc\u06ba \u062a\u064e\u0648\u0628\u06c1 \u06a9\u06cc \u062a\u064e\u0648\u0641\u0650\u06cc\u0642 \u0628\u062e\u0634\u06d2 \u062a\u0627\u06a9\u06c1 \u0648\u06c1 \u062d\u0642 \u06a9\u0648 \u067e\u06c1\u0686\u0627\u0646\u06cc\u06ba\u06d4\n26 \u0627\u0648\u0631 \u062e\u064f\u062f\u0627\u0648\u0646\u062f \u06a9\u06d2 \u0628\u0646\u062f\u06c1 \u06a9\u06d2 \u06c1\u0627\u062a\u06be \u0633\u06d2 \u062e\u064f\u062f\u0627 \u06a9\u06cc \u0645\u0631\u0636\u06cc \u06a9\u06d2 \u0627\u0633\u0650\u06cc\u0631\u06c1\u0648 \u06a9\u0631 \u0627\u0650\u0628\u0644\u0650\u06cc\u0633 \u06a9\u06d2 \u067e\u06be\u0646\u062f\u06d2 \u0633\u06d2 \u0686\u064f\u06be\u0648\u0679\u06cc\u06ba\u06d4\n\n\u06a9\u06cc\u0627 \u0622\u067e \u062c\u0627\u0646\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u0645\u06a9\u0645\u0644 \u0637\u0648\u0631 \u067e\u0631 \u0622\u0632\u0627\u062f \u0645\u062d\u0633\u0648\u0633 \u06a9\u0631\u0646\u0627 \u0645\u0645\u06a9\u0646 \u06c1\u06d2\u060c \u062c\u0628 \u0622\u067e \u0648\u0627\u0642\u0639\u06cc \u06af\u0646\u0627\u06c1 \u0627\u0648\u0631 \u0634\u06cc\u0637\u0627\u0646 \u06a9\u06d2 \u062c\u0627\u0644 \u0645\u06cc\u06ba \u067e\u06be\u0646\u0633 \u062c\u0627\u062a\u06d2 \u06c1\u06cc\u06ba\u061f\n\u06af\u0646\u0627\u06c1 \u0622\u0632\u0627\u062f\u06cc \u06a9\u06cc \u0637\u0631\u062d \u0645\u062d\u0633\u0648\u0633 \u06c1\u0648\u062a\u0627 \u06c1\u06d2\u060c \u0644\u06cc\u06a9\u0646 \u06cc\u06c1 \u0627\u0633 \u06a9\u06d2 \u0628\u0631\u0639\u06a9\u0633 \u06c1\u06d2\u06d4\n\u0627\u06cc\u06a9 \u067e\u06be\u0646\u062f\u0627 \u0627\u06cc\u0633\u0627 \u06c1\u06cc \u0644\u06af\u062a\u0627 \u06c1\u06d2\u06d4\n\u06cc\u06c1 \u0627\u06cc\u06a9 \u0627\u06cc\u0633\u0627 \u062c\u0627\u0644 \u06c1\u06d2 \u062c\u0648 \u0627\u06cc\u06a9 \u0627\u06cc\u0633\u06d2 \u062c\u0627\u0646\u0648\u0631 \u06a9\u0648 \u067e\u06a9\u0691 \u0644\u06cc\u062a\u0627 \u06c1\u06d2 \u062c\u0648 \u0622\u0632\u0627\u062f\u0627\u0646\u06c1 \u0637\u0648\u0631 \u067e\u0631 \u06a9\u0633\u06cc \u0631\u0627\u0633\u062a\u06d2 \u067e\u0631 \u0686\u0644 \u0631\u06c1\u0627 \u062a\u06be\u0627\u060c \u0627\u0648\u0631 \u067e\u06be\u0631 \u0627\u0686\u0627\u0646\u06a9 \u062e\u0637\u0631\u06d2 \u0645\u06cc\u06ba \u067e\u0691 \u06af\u06cc\u0627\u06d4\n\u0634\u06cc\u0637\u0627\u0646 \u06c1\u0645\u06cc\u06ba \u062f\u06be\u0648\u06a9\u06c1 \u062f\u06cc\u0646\u06d2 \u0627\u0648\u0631 \u067e\u06be\u0646\u0633\u0627\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0645\u06cc\u0631\u0627\u062a\u06be\u0646 \u06a9\u0648\u0631\u0633 \u0645\u06cc\u06ba \u0646\u0634\u0627\u0646\u06cc\u0648\u06ba \u06a9\u06cc \u0637\u0631\u062d \u062c\u06be\u0648\u0679 \u0628\u0648\u0644\u062a\u0627 \u06c1\u06d2\u06d4\n\u0634\u06cc\u0637\u0627\u0646 \u0686\u0627\u06c1\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1 \u06c1\u0645 \u062e\u0648\u0634\u06cc\u060c \u0637\u0627\u0642\u062a\u060c \u0645\u0642\u0628\u0648\u0644\u06cc\u062a\u060c \u0645\u0627\u0644 \u0648 \u062f\u0648\u0644\u062a \u0627\u0648\u0631 \u0641\u062e\u0631 \u06a9\u06d2 \u067e\u06cc\u0686\u06be\u06d2 \u0628\u06be\u0627\u06af\u06cc\u06ba\u06d4\n\u06cc\u06c1 \u0628\u062a \u06c1\u0645 \u0633\u06d2 \u0622\u0632\u0627\u062f\u06cc \u06a9\u0627 \u0648\u0639\u062f\u06c1 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u0627\u0648\u0631 \u0622\u0632\u0627\u062f\u06cc \u0648\u06c1 \u06c1\u06d2 \u062c\u0648 \u06c1\u0645 \u0628\u06c1\u062a \u0632\u06cc\u0627\u062f\u06c1 \u0686\u0627\u06c1\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u0628\u062f\u0642\u0633\u0645\u062a\u06cc \u0633\u06d2\u060c \u06c1\u0645\u06cc\u06ba \u06cc\u0642\u06cc\u0646 \u06c1\u06d2 \u06a9\u06c1 \u0627\u06cc\u0633\u06cc \u0686\u06cc\u0632\u06cc\u06ba \u06c1\u0645\u06cc\u06ba \u0645\u0637\u0645\u0626\u0646\u060c \u0645\u062d\u0641\u0648\u0638\u060c \u062e\u0648\u0634 \u0645\u062d\u0633\u0648\u0633 \u06a9\u0631\u0646\u06d2 \u0645\u06cc\u06ba \u0645\u062f\u062f \u06a9\u0631 \u0633\u06a9\u062a\u06cc \u06c1\u06cc\u06ba\u06d4\n\u0644\u06cc\u06a9\u0646 \u06cc\u06c1 \u0628\u062a \u0627\u06cc\u0633\u06d2 \u062c\u0627\u0644 \u06c1\u06cc\u06ba \u062c\u0648 \u06c1\u0645\u06cc\u06ba \u062e\u062f\u0627 \u0627\u0648\u0631 \u062d\u0642\u06cc\u0642\u06cc \u0632\u0646\u062f\u06af\u06cc \u06a9\u06cc \u0631\u0627\u06c1 \u0633\u06d2 \u062f\u0648\u0631 \u0631\u06a9\u06be\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u0634\u06cc\u0637\u0627\u0646 \u06c1\u0645 \u0633\u06d2 \u0632\u0646\u062f\u06af\u06cc \u06a9\u0627 \u0631\u0627\u0633\u062a\u06c1 \u0686\u06be\u067e\u0627\u0646\u0627 \u0686\u0627\u06c1\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1:\n\u201d\u0641\u062a\u062d \u0627\u0648\u0631 \u062e\u0648\u0634\u06cc \u06a9\u06cc \u0637\u0631\u0641 \u0627\u0633 \u0631\u0627\u0633\u062a\u06d2 \u067e\u0631 \u062c\u0627\u0626\u06cc\u06ba!\n\u062c\u06cc \u06c1\u0627\u06ba\u060c \u06cc\u06c1 \u0637\u0631\u06cc\u0642\u06c1 \u06c1\u06d2! \u0645\u06cc\u0631\u06d2 \u067e\u06cc\u0686\u06be\u06d2 \u0686\u0644\u06cc\u06ba!\u201d\n\n\u062a\u0648\u060c \u0627\u06cc\u06a9 \u062c\u0627\u0646\u0648\u0631 \u0627\u0633 \u0637\u0631\u062d \u06a9\u06d2 \u062c\u0627\u0644 \u0633\u06d2 \u06a9\u06cc\u0633\u06d2 \u0628\u0686 \u0633\u06a9\u062a\u0627 \u06c1\u06d2\u061f\n\u06a9\u06cc\u0627 \u06cc\u06c1 \u06a9\u0686\u06be \u0648\u06c1 \u062e\u0648\u062f \u06a9\u0631 \u0633\u06a9\u062a\u0627 \u06c1\u06d2\u061f\n\u0646\u06c1\u06cc\u06ba\u060c \u062e\u0631\u06af\u0648\u0634 \u0628\u06d2 \u0628\u0633 \u06c1\u06d2\u06d4\n\u0627\u0633\u06d2 \u06a9\u0633\u06cc \u0632\u06cc\u0627\u062f\u06c1 \u06c1\u0648\u0634\u06cc\u0627\u0631 \u0627\u0648\u0631 \u0645\u0636\u0628\u0648\u0637 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u06c1\u06d2 \u06a9\u06c1 \u0648\u06c1 \u0622\u0626\u06d2 \u0627\u0648\u0631 \u0627\u0633\u06d2 \u062c\u0627\u0644 \u0633\u06d2 \u0646\u06a9\u0627\u0644\u06d2\u06d4\n\u06c1\u0645\u06cc\u06ba \u0628\u06be\u06cc\u060c \u06c1\u0645\u06cc\u06ba \u0628\u0686\u0627\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06a9\u0633\u06cc \u06c1\u0648\u0634\u06cc\u0627\u0631 \u0627\u0648\u0631 \u0645\u0636\u0628\u0648\u0637 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u06c1\u06d2\u06d4\n\u06cc\u06c1 \u0633\u0628 \u0633\u06d2 \u0627\u06c1\u0645 \u0646\u06a9\u062a\u06c1 \u06c1\u06d2 \u062c\u0648 \u0645\u06cc\u06ba \u0686\u0627\u06c1\u062a\u0627 \u06c1\u0648\u06ba \u06a9\u06c1 \u0622\u067e \u0627\u0633 \u0622\u06cc\u062a \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u062f\u06cc\u06a9\u06be\u06cc\u06ba\u06d4\n\u06c1\u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0646\u062c\u0627\u062a \u062f\u06c1\u0646\u062f\u06c1 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u06c1\u06d2 \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u06c1\u0645 \u062e\u0648\u062f \u06a9\u0648 \u0646\u06c1\u06cc\u06ba \u0628\u0686\u0627 \u0633\u06a9\u062a\u06d2 \u0627\u0648\u0631 \u0646\u06c1 \u06c1\u06cc \u062e\u062f\u0627 \u06a9\u06cc \u0637\u0631\u0641 \u0631\u062c\u0648\u0639 \u06a9\u0631 \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u0648\u06c1 \u062f\u0644 \u062c\u0648 \u0631\u0648\u062d\u0627\u0646\u06cc \u0637\u0648\u0631 \u067e\u0631 \u0645\u0631\u062f\u06c1 \u06c1\u06cc\u06ba \u0632\u0646\u062f\u06af\u06cc \u06a9\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0646\u06c1\u06cc\u06ba \u06a9\u0631 \u0633\u06a9\u062a\u06d2\u06d4\n\u062f\u06cc\u06a9\u06be\u06cc\u06ba \u0622\u06cc\u062a 25 \u06a9\u06cc\u0627 \u06a9\u06c1\u062a\u06cc \u06c1\u06d2:\n\u201d\u0634\u0627\u06cc\u062f \u062e\u064f\u062f\u0627 \u0627\u064f\u0646\u06c1\u06cc\u06ba \u062a\u064e\u0648\u0628\u06c1 \u06a9\u06cc \u062a\u064e\u0648\u0641\u0650\u06cc\u0642 \u0628\u062e\u0634\u06d2\u06d4\u201d\n\n\u062a\u0648\u0641\u06cc\u0642 \u0627\u06cc\u06a9 \u0645\u0641\u062a \u062a\u062d\u0641\u06c1 \u06c1\u06d2\u06d4\n\u062e\u062f\u0627 \u0646\u06d2 \u0645\u062c\u06be\u06d2 30 \u0633\u0627\u0644 \u067e\u06c1\u0644\u06d2 \u062a\u0648\u0628\u06c1 \u06a9\u0627 \u062a\u0648\u0641\u06cc\u0642 \u062f\u06cc \u062a\u06be\u06cc\u06d4\n10 \u0633\u0627\u0644 \u062a\u06a9 \u0645\u06cc\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u06a9\u0627\u0626\u0646\u0627\u062a \u0645\u06cc\u06ba \u06a9\u0648\u0626\u06cc \u062e\u062f\u0627 \u0646\u06c1\u06cc\u06ba \u06c1\u06d2\u06d4\n\u0644\u06cc\u06a9\u0646 \u0686\u0648\u0646\u06a9\u06c1 \u062e\u064f\u062f\u0627 \u0645\u06c1\u0631\u0628\u0627\u0646 \u06c1\u06d2\u060c \u0627\u0650\u0633 \u0644\u06cc\u06d2 \u0627\u064f\u0633 \u0646\u06d2 \u0645\u062c\u06be\u06d2 \u062f\u06a9\u06be\u0627\u06cc\u0627 \u06a9\u06c1 \u0628\u06cc\u0626\u0631\u060c \u0639\u0648\u0631\u062a\u06cc\u06ba \u0627\u0648\u0631 \u062f\u0646\u06cc\u0627\u0648\u06cc \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc \u0645\u06cc\u0631\u06d2 \u062f\u0644 \u06a9\u06cc \u062e\u0648\u0627\u06c1\u0634\u0627\u062a \u06a9\u0648 \u06a9\u0628\u06be\u06cc \u067e\u0648\u0631\u0627 \u0646\u06c1\u06cc\u06ba \u06a9\u0631 \u0633\u06a9\u062a\u06cc\u06d4\n\u0622\u06cc\u062a 26 \u0645\u06cc\u06ba \u201d\u062e\u064f\u062f\u0627 \u06a9\u06d2 \u0628\u0646\u062f\u06c1 \u06a9\u06d2 \u06c1\u0627\u062a\u06be \u0645\u06cc\u06ba\u201d \u06a9\u0627 \u06cc\u06c1\u06cc \u0645\u0637\u0644\u0628 \u06c1\u06d2\u06d4\n\u062c\u0628 \u0622\u067e \u06a9\u06cc \u0633\u0645\u062a \u06a9\u0627 \u0627\u062d\u0633\u0627\u0633 \u0627\u0644\u062c\u06be \u062c\u0627\u062a\u0627 \u06c1\u06d2 \u062a\u0648 \u0622\u067e \u063a\u0644\u0637 \u0633\u0645\u062a \u0645\u06cc\u06ba \u0628\u06be\u0627\u06af\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u0627\u067e\u0646\u06d2 \u06af\u06be\u0631 \u06a9\u0627 \u0631\u0627\u0633\u062a\u06c1 \u062a\u0644\u0627\u0634 \u06a9\u0631\u0646\u06d2 \u06a9\u0627 \u067e\u06c1\u0644\u0627 \u0642\u062f\u0645 \u06cc\u06c1 \u067e\u06c1\u0686\u0627\u0646\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0622\u067e \u06a9\u06be\u0648 \u0686\u06a9\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u067e\u0648\u0631\u0679 \u0644\u06cc\u0646\u0688 \u0645\u06cc\u06ba \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0627\u0633 \u0645\u06cc\u0631\u0627\u062a\u06be\u0646 \u0645\u06cc\u06ba \u0688\u06cc\u0646 \u0645\u06cc\u06a9 \u0688\u0648\u06cc\u0644 \u06a9\u06be\u0648\u0626\u06d2 \u06c1\u0648\u0626\u06d2 \u0631\u0646\u0631\u0632 \u0645\u06cc\u06ba \u0633\u06d2 \u0627\u06cc\u06a9 \u062a\u06be\u06d2\u06d4\n\u0627\u0633 \u0646\u06d2 \u06a9\u06c1\u0627: \u201d\u0645\u06cc\u06ba \u06a9\u0648\u0646\u06d2 \u06a9\u06d2 \u0622\u0633 \u067e\u0627\u0633 \u0622\u06cc\u0627 \u0627\u0648\u0631 \u062f\u06cc\u06a9\u06be\u0627 \u06a9\u06c1 10 \u0644\u0648\u06af \u06a9\u06be\u0691\u06d2 \u06c1\u06cc\u06ba\u2026\n\u0648\u06c1 \u0627\u06cc\u06a9 \u062f\u0648\u0633\u0631\u06d2 \u06a9\u0648 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u0633\u0648\u0686 \u0631\u06c1\u06d2 \u062a\u06be\u06d2 \u06a9\u06c1 \u2018\u0627\u0648\u06c1\u060c \u06cc\u06c1 \u0679\u06be\u06cc\u06a9 \u0646\u06c1\u06cc\u06ba \u0644\u06af\u062a\u0627\u2018\u06d4\n\n\u0627\u06cc\u06a9 \u0627\u0648\u0631 \u0631\u0646\u0631 \u0632\u06cc\u06a9 \u06a9\u0633\u0679\u0631 \u0646\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u0648\u06c1 \u0627\u06cc\u06a9 \u0633\u0631\u0646\u06af \u0645\u06cc\u06ba \u062f\u0627\u062e\u0644 \u06c1\u0648\u0627 \u062c\u06c1\u0627\u06ba \u06a9\u0627\u0631\u06cc\u06ba 55 \u0645\u06cc\u0644 \u0641\u06cc \u06af\u06be\u0646\u0679\u06c1 \u06a9\u06cc \u0631\u0641\u062a\u0627\u0631 \u0633\u06d2 \u0627\u0633 \u06a9\u06d2 \u067e\u0627\u0633 \u0633\u06d2 \u06af\u0632\u0631\u06cc\u06ba\u06d4\n\u062a\u0628 \u0627\u0633\u06d2 \u0627\u062d\u0633\u0627\u0633 \u06c1\u0648\u0627 \u06a9\u06c1 \u0648\u06c1 \u0631\u0627\u0633\u062a\u06d2 \u0633\u06d2 \u06c1\u0679 \u06af\u06cc\u0627 \u06c1\u06d2\u06d4\n\u0627\u0633 \u0633\u06d2 \u067e\u06c1\u0644\u06d2 \u06a9\u06c1 \u062e\u062f\u0627 \u0645\u062c\u06be\u06d2 \u06c1\u0648\u0634 \u0645\u06cc\u06ba \u0644\u0627\u0626\u06d2 \u0645\u06cc\u06ba \u0646\u06d2 \u0633\u0648\u0686\u0627 \u06a9\u06c1 \u0645\u062c\u06be\u06d2 \u201d\u062d\u0642 \u06a9\u0627 \u0639\u0644\u0645\u201d \u06c1\u06d2\u06d4\n\u0645\u06cc\u0631\u06d2 \u063a\u0631\u0648\u0631 \u0646\u06d2 \u0645\u062c\u06be\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u0645\u06cc\u06ba \u0635\u062d\u06cc\u062d \u0631\u0627\u0633\u062a\u06d2 \u067e\u0631 \u06c1\u0648\u06ba\u060c \u0627\u0648\u0631 \u0645\u062c\u06be\u06d2 \u06c1\u062f\u0627\u06cc\u062a \u062f\u06cc\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06a9\u0633\u06cc \u062e\u062f\u0627 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u0646\u06c1\u06cc\u06ba \u062a\u06be\u06cc \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0645\u06cc\u06ba \u0628\u06c1\u062a \u06c1\u0648\u0634\u06cc\u0627\u0631 \u062a\u06be\u0627\u06d4\n\u0633\u062a\u0645 \u0638\u0631\u06cc\u0641\u06cc \u06cc\u06c1 \u06c1\u06d2 \u06a9\u06c1 \u0645\u06cc\u06ba \u0634\u06cc\u0637\u0627\u0646 \u06a9\u06d2 \u0641\u0631\u06cc\u0628 \u06a9\u0648 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u0628\u06c1\u062a \u0628\u06cc\u0648\u0642\u0648\u0641 \u062a\u06be\u0627\u06d4\n\u0645\u06cc\u06ba \u0627\u0633 \u06a9\u06d2 \u062c\u06be\u0648\u0679 \u06a9\u06d2 \u062c\u0627\u0644 \u0645\u06cc\u06ba \u06af\u0631\u0641\u062a\u0627\u0631 \u062a\u06be\u0627\u06d4\n\u0645\u06cc\u06ba \u0646\u06d2 \u0634\u06cc\u0637\u0627\u0646 \u06a9\u06d2 \u0627\u0633 \u0648\u0639\u062f\u06d2 \u067e\u0631 \u06cc\u0642\u06cc\u0646 \u06a9\u06cc\u0627 \u06a9\u06c1 \u0645\u06cc\u06ba \u062e\u062f\u0627 \u0633\u06d2 \u0628\u06be\u0627\u06af\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u062e\u0648\u0634\u06cc \u062d\u0627\u0635\u0644 \u06a9\u0631\u0648\u06ba \u06af\u0627\u06d4\n\u0644\u06cc\u06a9\u0646 \u067e\u06be\u0631\u060c \u062e\u062f\u0627 \u0646\u06d2 \u0645\u062c\u06be\u06d2 \u062a\u0648\u0628\u06c1 \u06a9\u06cc \u062a\u0648\u0641\u06cc\u0642 \u062f\u06cc\u06d4\n\u06cc\u06c1\u0627\u06ba \u062a\u0648\u0628\u06c1 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06cc\u0648\u0646\u0627\u0646\u06cc \u0644\u0641\u0638 metanoia \u06c1\u06d2\u06d4\n\u0627\u0633 \u06a9\u0627 \u0645\u0637\u0644\u0628 \u06c1\u06d2 \u201d\u0630\u06c1\u0646 \u06a9\u06cc \u062a\u0628\u062f\u06cc\u0644\u06cc\u060c \u0632\u0646\u062f\u06af\u06cc \u06a9\u06cc \u062a\u0628\u062f\u06cc\u0644\u06cc\u060c \u0627\u0648\u0631 \u0645\u0642\u0635\u062f \u06a9\u06cc \u062a\u0628\u062f\u06cc\u0644\u06cc\u06d4\u201d\n\u06cc\u0633\u0648\u0639 \u0646\u06d2 \u0645\u062c\u06be\u06d2 \u0627\u06cc\u06a9 \u0646\u06cc\u0627 \u062f\u0644 \u062f\u06cc\u0627 \u062a\u0627\u06a9\u06c1 \u0645\u06cc\u06ba \u201d\u062e\u0627\u0644\u0635 \u062f\u0644 \u0633\u06d2 \u062e\u062f\u0627\u0648\u0646\u062f \u06a9\u0648 \u067e\u06a9\u0627\u0631\u0648\u06ba\u201d \u062c\u06cc\u0633\u0627 \u06a9\u06c1 \u0622\u06cc\u062a 22 \u06a9\u06c1\u062a\u06cc \u06c1\u06d2\u06d4\n\u0627\u06cc\u06a9 \u067e\u0627\u06a9 \u062f\u0644 \u0627\u06cc\u0645\u0627\u0646\u062f\u0627\u0631 \u062f\u0644 \u06c1\u06d2\u06d4\n\u0627\u06cc\u06a9 \u062f\u0644 \u062c\u0648 \u062e\u062f\u0627 \u06a9\u0648 \u067e\u06a9\u0627\u0631\u062a\u0627 \u06c1\u06d2\u060c \u201d\u0645\u06cc\u06ba \u0627\u067e\u0646\u06d2 \u06af\u0646\u0627\u06c1 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0645\u0639\u0630\u0631\u062a \u062e\u0648\u0627\u06c1 \u06c1\u0648\u06ba\u060c \u0645\u062c\u06be\u06d2 \u0645\u0639\u0627\u0641 \u06a9\u0631 \u062f\u06cc\u06ba\u06d4\n\u062a\u06cc\u0631\u06cc \u0637\u0631\u0641 \u0628\u06be\u0627\u06af\u0646\u06d2 \u0645\u06cc\u06ba \u0645\u06cc\u0631\u06cc \u0645\u062f\u062f \u06a9\u0631\u060c \u062a\u062c\u06be \u0633\u06d2 \u062f\u0648\u0631 \u0646\u06c1\u06cc\u06ba\u06d4\u201d\n\u067e\u0648\u0644\u0633 \u0646\u06d2 \u0631\u0648\u0645\u06cc\u0648\u06ba 10:9-11 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0628\u06c1\u062a \u0648\u0627\u0636\u062d \u0648\u0636\u0627\u062d\u062a \u06a9\u06cc \u06a9\u06c1 \u0622\u067e \u06a9\u0633 \u0637\u0631\u062d \u062e\u062f\u0627 \u06a9\u06cc \u0637\u0631\u0641 \u0631\u062c\u0648\u0639 \u06a9\u0631 \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u0646\u062c\u0627\u062a \u067e\u0627 \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n9 \u201d\u06a9\u06c1 \u0627\u06af\u0631 \u062a\u064f\u0648 \u0627\u067e\u0646\u06cc \u0632\u064f\u0628\u0627\u0646 \u0633\u06d2 \u06cc\u0650\u0633\u064f\u0648 \u0639 \u06a9\u06d2 \u062e\u064f\u062f\u0627\u0648\u0646\u062f \u06c1\u0648\u0646\u06d2 \u06a9\u0627 \u0627\u0650\u0642\u0631\u0627\u0631 \u06a9\u0631\u06d2 \u0627\u0648\u0631 \u0627\u067e\u0646\u06d2 \u062f\u0650\u0644 \u0633\u06d2 \u0627\u0650\u06cc\u0645\u0627\u0646 \u0644\u0627\u0626\u06d2 \u06a9\u06c1 \u062e\u064f\u062f\u0627 \u0646\u06d2 \u0627\u064f\u0633\u06d2 \u0645\u064f\u0631\u062f\u0648\u06ba \u0645\u06cc\u06ba \u0633\u06d2 \u062c\u0650\u0644\u0627\u06cc\u0627 \u062a\u0648 \u0646\u062c\u0627\u062a \u067e\u0627\u0626\u06d2 \u06af\u0627\u06d4\n10 \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0631\u0627\u0633\u062a \u0628\u0627\u0632\u06cc \u06a9\u06d2 \u0644\u0650\u0626\u06d2 \u0627\u0650\u06cc\u0645\u0627\u0646 \u0644\u0627\u0646\u0627 \u062f\u0650\u0644 \u0633\u06d2 \u06c1\u0648\u062a\u0627 \u06c1\u06d2 \u0627\u0648\u0631 \u0646\u062c\u0627\u062a \u06a9\u06d2 \u0644\u0650\u0626\u06d2 \u0627\u0650\u0642\u0631\u0627\u0631 \u0645\u064f\u0646\u06c1 \u0633\u06d2 \u06a9\u0650\u06cc\u0627 \u062c\u0627\u062a\u0627 \u06c1\u06d2\u06d4\n11 \u0686\u064f\u0646\u0627\u0646\u0686\u06c1 \u06a9\u0650\u062a\u0627\u0628\u0650 \u0645\u064f\u0642\u062f\u0651\u0633 \u06cc\u06c1 \u06a9\u06c1\u062a\u06cc \u06c1\u06d2 \u06a9\u06c1\u060c\u2019\u2019\u062c\u0648 \u06a9\u0648\u0626\u06cc \u0627\u064f\u0633 \u067e\u0631 \u0627\u0650\u06cc\u0645\u0627\u0646 \u0644\u0627\u0626\u06d2 \u06af\u0627 \u0648\u06c1 \u0634\u0631\u0645\u0650\u0646\u062f\u06c1 \u0646\u06c1 \u06c1\u0648 \u06af\u0627\u06d4\u2018\u2018\n\n\u06a9\u06cc\u0627 \u0622\u067e \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u0645\u0646\u06c1 \u0633\u06d2 \u0627\u06cc\u0645\u0627\u0646 \u06a9\u0627 \u0627\u0642\u0631\u0627\u0631 \u06a9\u06cc\u0627 \u06c1\u06d2\u060c \u062a\u0627\u06a9\u06c1 \u0622\u067e \u0646\u062c\u0627\u062a \u067e\u0627 \u0633\u06a9\u06cc\u06ba\u061f\n\u0627\u06af\u0631 \u0622\u067e \u0646\u06d2 \u0627\u06cc\u0633\u0627 \u0646\u06c1\u06cc\u06ba \u06a9\u06cc\u0627 \u062a\u0648 \u06a9\u06cc\u0627 \u0622\u067e \u06a9\u0648 \u0646\u06c1\u06cc\u06ba \u0644\u06af\u062a\u0627 \u06a9\u06c1 \u0622\u062c \u06a9\u0627 \u062f\u0646 \u0627\u06cc\u0633\u0627 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0627\u06cc\u06a9 \u0628\u06c1\u062a\u0631\u06cc\u0646 \u062f\u0646 \u06c1\u0648\u06af\u0627\u061f\n\u0631\u0648\u062d \u0627\u0644\u0642\u062f\u0633 \u06cc\u06c1\u0627\u06ba \u06c1\u0645\u0627\u0631\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u06c1\u06d2\u060c \u0627\u0648\u0631 \u0634\u0627\u06cc\u062f \u0648\u06c1 \u0622\u067e \u06a9\u06d2 \u062f\u0644 \u0645\u06cc\u06ba \u0633\u0631\u06af\u0648\u0634\u06cc \u06a9\u0631 \u0631\u06c1\u0627 \u06c1\u06d2:\n\u201d\u06af\u0646\u0627\u06c1 \u0627\u0648\u0631 \u0645\u0648\u062a \u06a9\u06d2 \u0631\u0627\u0633\u062a\u06d2 \u0633\u06d2 \u0628\u0627\u0632 \u0622\u0624!\n\u0646\u0626\u06cc \u0632\u0646\u062f\u06af\u06cc \u0627\u0648\u0631 \u0627\u06cc\u06a9 \u0646\u0626\u06cc \u0633\u0645\u062a \u06a9\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0631\u06cc\u06ba\u060c \u06cc\u06c1 \u0627\u0639\u0644\u0627\u0646 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1 \u2018\u06cc\u0633\u0648\u0639 \u062e\u062f\u0627\u0648\u0646\u062f \u06c1\u06d2!\u2019\n\n\u067e\u0648\u0644\u0633 \u0646\u06d2 \u0627\u0633 \u0646\u0626\u06cc \u0633\u0645\u062a \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u067e\u06c1\u0644\u06d2 \u0627\u06cc\u06a9 \u0628\u0627\u0631 \u0644\u06a9\u06be\u0627 \u062a\u06be\u0627\u06d4\n\u06cc\u06c1 \u0627\u0641\u0633\u0633 \u06a9\u06d2 \u0627\u0633\u06cc \u0686\u0631\u0686 \u06a9\u0648 \u0627\u06cc\u06a9 \u062e\u0637 \u0645\u06cc\u06ba \u062a\u06be\u0627\u060c \u062c\u06c1\u0627\u06ba \u062a\u06cc\u0645\u062a\u06be\u06cc\u0633 \u0627\u0628 \u0627\u06cc\u06a9 \u067e\u0627\u062f\u0631\u06cc \u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631 \u062e\u062f\u0645\u0627\u062a \u0627\u0646\u062c\u0627\u0645 \u062f\u06d2 \u0631\u06c1\u0627 \u06c1\u06d2\u06d4\n\u0633\u0646\u06cc\u06ba \u06a9\u06c1 \u067e\u0648\u0644\u0633 \u0646\u06d2 \u0645\u0633\u06cc\u062d\u06cc \u0627\u06cc\u0645\u0627\u0646\u062f\u0627\u0631\u0648\u06ba \u06a9\u0648 \u0627\u0641\u0633\u06cc\u0648\u06ba 2:1-5 \u0645\u06cc\u06ba \u06a9\u06cc\u0627 \u0644\u06a9\u06be\u0627\u060c \u0627\u0633 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u06a9\u06c1 \u062e\u062f\u0627 \u0646\u06d2 \u0627\u0646\u06c1\u06cc\u06ba \u0646\u0626\u06cc \u0632\u0646\u062f\u06af\u06cc \u0627\u0648\u0631 \u0627\u06cc\u06a9 \u0646\u0626\u06cc \u0633\u0645\u062a \u062f\u06cc\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06a9\u06cc\u0627 \u06a9\u06cc\u0627:\n1 \u201d\u0627\u0648\u0631 \u0627\u064f\u0633 \u0646\u06d2 \u062a\u064f\u0645\u06c1\u06cc\u06ba \u0628\u06be\u06cc \u0632\u0650\u0646\u062f\u06c1 \u06a9\u0650\u06cc\u0627 \u062c\u0628 \u0627\u067e\u0646\u06d2 \u0642\u0635\u064f\u0648\u0631\u0648\u06ba \u0627\u0648\u0631 \u06af\u064f\u0646\u0627\u06c1\u0648\u06ba \u06a9\u06d2 \u0633\u0628\u0628 \u0633\u06d2 \u0645\u064f\u0631\u062f\u06c1 \u062a\u06be\u06d2\u06d4\n2 \u062c\u0650\u0646 \u0645\u06cc\u06ba \u062a\u064f\u0645 \u067e\u06cc\u0634\u062a\u0631 \u062f\u064f\u0646\u06cc\u0627 \u06a9\u06cc \u0631\u0648\u0650\u0634 \u067e\u0631 \u0686\u0644\u062a\u06d2 \u062a\u06be\u06d2 \u0627\u0648\u0631 \u06c1\u0648\u0627 \u06a9\u06cc \u0639\u0645\u0644 \u062f\u0627\u0631\u06cc \u06a9\u06d2 \u062d\u0627\u06a9\u0650\u0645 \u06cc\u0639\u0646\u06cc \u0627\u064f\u0633 \u0631\u064f\u0648\u062d \u06a9\u06cc \u067e\u064e\u06cc\u0631\u0648\u06cc \u06a9\u0631\u062a\u06d2 \u062a\u06be\u06d2 \u062c\u0648 \u0627\u064e\u0628 \u0646\u0627\u0641\u0631\u0645\u0627\u0646\u06cc \u06a9\u06d2 \u0641\u0631\u0632\u0646\u062f\u0648\u06ba \u0645\u06cc\u06ba \u062a\u0627\u062b\u0650\u06cc\u0631 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u06d4\n3 \u0627\u0650\u0646 \u0645\u06cc\u06ba \u06c1\u0645 \u0628\u06be\u06cc \u0633\u0628 \u06a9\u06d2 \u0633\u0628 \u067e\u06c1\u0644\u06d2 \u0627\u067e\u0646\u06d2 \u062c\u0650\u0633\u0645 \u06a9\u06cc \u062e\u0648\u0627\u06c1\u0650\u0634\u0648\u06ba \u0645\u06cc\u06ba \u0632\u0650\u0646\u062f\u06af\u06cc \u06af\u064f\u0630\u0627\u0631\u062a\u06d2 \u0627\u0648\u0631 \u062c\u0650\u0633\u0645 \u0627\u0648\u0631 \u0639\u0642\u0644 \u06a9\u06d2 \u0627\u0650\u0631\u0627\u062f\u06d2 \u067e\u064f\u0648\u0631\u06d2 \u06a9\u0631\u062a\u06d2 \u062a\u06be\u06d2 \u0627\u0648\u0631 \u062f\u064f\u0648\u0633\u0631\u0648\u06ba \u06a9\u06cc \u0645\u0627\u0646\u0650\u0646\u062f \u0637\u0628\u0639\u06cc \u0637\u064e\u0648\u0631 \u067e\u0631 \u063a\u0636\u0628 \u06a9\u06d2 \u0641\u0631\u0632\u0646\u062f \u062a\u06be\u06d2\u06d4\n4 \u0645\u06af\u0631 \u062e\u064f\u062f\u0627 \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u0631\u064e\u062d\u0645 \u06a9\u06cc \u062f\u064e\u0648\u0644\u062a \u0633\u06d2 \u0627\u064f\u0633 \u0628\u0691\u06cc \u0645\u064f\u062d\u0628\u0651\u062a \u06a9\u06d2 \u0633\u0628\u0628 \u0633\u06d2 \u062c\u0648 \u0627\u064f\u0633 \u0646\u06d2 \u06c1\u0645 \u0633\u06d2 \u06a9\u06cc\u06d4\n5 \u062c\u0628 \u0642\u0635\u064f\u0648\u0631\u0648\u06ba \u06a9\u06d2 \u0633\u0628\u0628 \u0633\u06d2 \u0645\u064f\u0631\u062f\u06c1 \u06c1\u06cc \u062a\u06be\u06d2 \u062a\u0648 \u06c1\u0645 \u06a9\u0648\u0645\u0633\u0650\u06cc\u062d \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0632\u0650\u0646\u062f\u06c1 \u06a9\u0650\u06cc\u0627 \u06d4 (\u062a\u064f\u0645 \u06a9\u0648 \u0641\u0636\u0644 \u06c1\u06cc \u0633\u06d2 \u0646\u062c\u0627\u062a \u0645\u0650\u0644\u06cc \u06c1\u06d2)\u06d4\u201d\n\n\u201d\u0645\u06af\u0631 \u062e\u062f\u0627\u201d \u0628\u0648\u0644\u06d2 \u062c\u0627\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u062f\u0648 \u0633\u0628 \u0633\u06d2 \u062e\u0648\u0628\u0635\u0648\u0631\u062a \u0627\u0644\u0641\u0627\u0638 \u06c1\u06cc\u06ba\u06d4\n\u067e\u0648\u0644\u0633 \u0627\u0641\u0633\u0633 \u0645\u06cc\u06ba \u0627\u06cc\u0645\u0627\u0646\u062f\u0627\u0631\u0648\u06ba \u06a9\u0648 \u06cc\u0627\u062f \u062f\u0644\u0627\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u06c1 \u0627\u06cc\u06a9 \u0628\u0627\u0631 \u067e\u06be\u0646\u062f\u06d2 \u0645\u06cc\u06ba \u062e\u0631\u06af\u0648\u0634 \u06a9\u06cc \u0637\u0631\u062d \u067e\u06be\u0646\u0633\u06d2 \u06c1\u0648\u0626\u06d2 \u0627\u0648\u0631 \u0628\u06d2 \u0628\u0633 \u062a\u06be\u06d2\u06d4\n\u0644\u06cc\u06a9\u0646 \u062e\u064f\u062f\u0627 \u0646\u06d2 \u0627\u064f\u0646\u06c1\u06cc\u06ba \u0635\u0631\u0641 \u0641\u0636\u0644 \u0633\u06d2\u060c \u0635\u0631\u0641 \u0627\u06cc\u0645\u0627\u0646 \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06d2\u060c \u0627\u06a9\u06cc\u0644\u06d2 \u0645\u0633\u06cc\u062d \u0645\u06cc\u06ba \u0628\u0686\u0627\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0642\u062f\u0645 \u0631\u06a9\u06be\u0627\u06d4\n\u06a9\u0648\u0626\u06cc \u0628\u06be\u06cc \u0628\u0686 \u0633\u06a9\u062a\u0627 \u06c1\u06d2\u060c \u0627\u06af\u0631 \u0622\u067e \u06a9\u0648 \u06cc\u0642\u06cc\u0646 \u06c1\u06d2 \u06a9\u06c1 \u0635\u0644\u06cc\u0628 \u067e\u0631 \u0645\u0633\u06cc\u062d \u06a9\u06cc \u0642\u0631\u0628\u0627\u0646\u06cc \u0622\u067e \u06a9\u06d2 \u0644\u06cc\u06d2 \u062a\u06be\u06cc\u060c \u0622\u067e \u06a9\u0648 \u06af\u0646\u0627\u06c1 \u0627\u0648\u0631 \u0634\u0631\u0645\u0646\u062f\u06af\u06cc \u0633\u06d2 \u062f\u06be\u0648\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2\u06d4\n\u062c\u0628 \u0622\u067e \u0627\u0633 \u067e\u0631 \u06cc\u0642\u06cc\u0646 \u0631\u06a9\u06be\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u0622\u067e \u06a9\u0648 \u0646\u0626\u06cc \u0632\u0646\u062f\u06af\u06cc \u0645\u0644\u062a\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u06cc\u0633\u0648\u0639 \u0622\u067e \u06a9\u0648 \u0627\u06cc\u06a9 \u0646\u0626\u06cc \u0631\u0627\u06c1 \u067e\u0631 \u0688\u0627\u0644 \u062f\u06cc\u062a\u0627 \u06c1\u06d2\u06d4\n\u0627\u0641\u0633\u06cc\u0648\u06ba 2:8 \u0645\u06cc\u06ba \u0686\u0646\u062f \u0622\u06cc\u0627\u062a \u0628\u0639\u062f\u060c \u067e\u0648\u0644\u0633 \u0627\u0633 \u0646\u0626\u06cc \u0633\u0645\u062a \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u0628\u0627\u062a \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4\n\u06cc\u06c1 \u0645\u06cc\u0631\u06d2 \u0633\u0627\u062a\u06be \u0645\u0644 \u06a9\u0631 \u067e\u0691\u06be\u06cc\u06ba:\n\u062a\u0645\u0627\u0645: 10 \u201d\u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u06c1\u0645 \u0627\u064f\u0633\u06cc \u06a9\u06cc \u06a9\u0627\u0631\u0650\u06cc\u06af\u0631\u06cc \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u0645\u0633\u0650\u06cc\u062d \u06cc\u0650\u0633\u064f\u0648 \u0639 \u0645\u06cc\u06ba \u0627\u064f\u0646 \u0646\u06cc\u06a9 \u0627\u064e\u0639\u0645\u0627\u0644 \u06a9\u06d2 \u0648\u0627\u0633\u0637\u06d2 \u0645\u062e\u0644\u064f\u0648\u0642 \u06c1\u064f\u0648\u0626\u06d2 \u062c\u0650\u0646 \u06a9\u0648 \u062e\u064f\u062f\u0627 \u0646\u06d2 \u067e\u06c1\u0644\u06d2 \u0633\u06d2 \u06c1\u0645\u0627\u0631\u06d2 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u0650\u0626\u06d2 \u062a\u06cc\u0651\u0627\u0631 \u06a9\u0650\u06cc\u0627 \u062a\u06be\u0627\u06d4\u201d\n\n\u0627\u0633 \u067e\u06cc\u063a\u0627\u0645 \u06a9\u0648 \u062e\u062a\u0645 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0622\u0626\u06cc\u06d2 \u062f\u06cc\u06a9\u06be\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u0646\u06cc\u06a9 \u06a9\u0627\u0645\u0648\u06ba \u0645\u06cc\u06ba \u0686\u0644\u0646\u0627 \u06a9\u06cc\u0633\u0627 \u0644\u06af\u062a\u0627 \u06c1\u06d2\u06d4\n\u06cc\u0627\u062f \u0631\u06a9\u06be\u06cc\u06ba \u06a9\u06c1 \u067e\u0648\u0644\u0633 \u062a\u06cc\u0645\u062a\u06be\u06cc\u0633 \u06a9\u0648 \u062e\u0637 \u0644\u06a9\u06be \u0631\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0627\u0633\u06d2 \u0628\u0627\u0626\u0628\u0644 \u0627\u0633\u0627\u062a\u0630\u06c1 \u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631 \u06a9\u0633 \u06a9\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0627\u0648\u0631 \u062a\u0631\u0628\u06cc\u062a \u06a9\u0631\u0646\u0627 \u06c1\u06d2\u06d4\n\u0627\u0648\u0631 \u0627\u06cc\u0645\u0627\u0646\u062f\u0627\u0631\u0648\u06ba \u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631 \u06c1\u0645\u0627\u0631\u0627 \u0645\u0634\u0646 \u0642\u0631\u06cc\u0628 \u0627\u0648\u0631 \u062f\u0648\u0631 \u06a9\u06d2 \u0644\u0648\u06af\u0648\u06ba \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0627\u0646\u062c\u06cc\u0644 \u06a9\u06cc \u062e\u0648\u0634\u062e\u0628\u0631\u06cc \u0628\u0627\u0646\u0679\u0646\u0627 \u06c1\u06d2\u06d4\n\u0644\u06cc\u06a9\u0646 \u0627\u06cc\u0645\u0627\u0646\u062f\u0627\u0631\u06cc \u0633\u06d2 \u0627\u06cc\u0633\u0627 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2\u060c \u06c1\u0645\u0627\u0631\u06d2 \u067e\u0627\u0633 \u0648\u06c1 \u06a9\u0631\u062f\u0627\u0631 \u06c1\u0648\u0646\u0627 \u0686\u0627\u06c1\u06cc\u06d2 \u062c\u0648 \u067e\u0648\u0644\u0633 \u0646\u06d2 \u0627\u0646 \u0622\u06cc\u0627\u062a \u0645\u06cc\u06ba \u0628\u06cc\u0627\u0646 \u06a9\u06cc\u0627 \u06c1\u06d2\u06d4\n\u06c1\u0645 \u06a9\u0633\u06cc \u06a9\u0627 \u062f\u0644 \u0646\u06c1\u06cc\u06ba \u0628\u062f\u0644 \u0633\u06a9\u062a\u06d2\u06d4\n\u0644\u06cc\u06a9\u0646 \u06c1\u0645 \u0627\u0646\u06c1\u06cc\u06ba \u0646\u0631\u0645\u06cc\u060c \u0645\u06c1\u0631\u0628\u0627\u0646\u06cc \u0627\u0648\u0631 \u062a\u062d\u0645\u0644 \u0633\u06d2 \u0633\u0686 \u0628\u062a\u0627 \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u0627\u0648\u0631 \u06c1\u0645 \u06cc\u0642\u06cc\u0646 \u06a9\u0631 \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u062e\u064f\u062f\u0627 \u0627\u067e\u0646\u06d2 \u0686\u0646\u06d2 \u06c1\u0648\u0626\u06d2 \u0628\u0686\u0648\u06ba \u06a9\u0648 \u0635\u062d\u06cc\u062d \u0648\u0642\u062a \u067e\u0631 \u062a\u0648\u0628\u06c1 \u06a9\u06cc \u062a\u0648\u0641\u06cc\u0642 \u062f\u06d2 \u06af\u0627\u06d4\n\u0622\u062c \u06a9\u06d2 \u062d\u0648\u0627\u0644\u06d2 \u06a9\u06cc \u0622\u06cc\u0627\u062a 24 \u0627\u0648\u0631 25 \u0645\u06cc\u06ba \u0645\u06cc\u06ba \u067e\u0627\u0646\u0686 \u062e\u0635\u0648\u0635\u06cc\u0627\u062a \u062f\u06cc\u06a9\u06be\u062a\u0627 \u06c1\u0648\u06ba \u062c\u0648 \u062e\u062f\u0627 \u0627\u067e\u0646\u06d2 \u0628\u0646\u062f\u0648\u06ba \u0645\u06cc\u06ba \u067e\u06cc\u062f\u0627 \u06a9\u0631\u0646\u0627 \u0686\u0627\u06c1\u062a\u0627 \u06c1\u06d2:\n\n\u0645\u0639\u06cc\u0627\u0631 1: \u062c\u06be\u06af\u0691\u0627\u0644\u0648 \u0646\u06c1\u06cc\u06ba.\n\u06a9\u0686\u06be \u0644\u0648\u06af \u0628\u062d\u062b \u06a9\u0631\u0646\u0627 \u067e\u0633\u0646\u062f \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u0635\u062d\u062a \u0645\u0646\u062f \u0628\u062d\u062b \u0645\u06cc\u06ba \u06a9\u0648\u0626\u06cc \u062d\u0631\u062c \u0646\u06c1\u06cc\u06ba\u06d4\n\u0644\u06cc\u06a9\u0646 \u0622\u067e \u06a9\u0648 \u06a9\u06cc\u0633\u06d2 \u067e\u062a\u06c1 \u0686\u0644\u06d2 \u06af\u0627 \u06a9\u06c1 \u062c\u0628 \u0622\u067e \u06af\u0646\u0627\u06c1 \u0633\u06d2 \u201d\u062c\u06be\u06af\u0691\u0627\u0644\u0648\u201d \u06c1\u0648 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u061f\n\u0634\u0627\u06cc\u062f \u0622\u067e \u0627\u067e\u0646\u06d2 \u0622\u067e \u0633\u06d2 \u06cc\u06c1 \u0633\u0648\u0627\u0644 \u067e\u0648\u0686\u06be \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba:\n\u201d\u062c\u0628 \u0645\u06cc\u06ba \u06a9\u0633\u06cc \u0633\u06d2 \u0628\u062d\u062b \u06a9\u0631 \u0631\u06c1\u0627 \u06c1\u0648\u06ba\u060c \u06a9\u06cc\u0627 \u0645\u062c\u06be\u06d2 \u0627\u0633 \u0634\u062e\u0635 \u06a9\u06cc \u0632\u06cc\u0627\u062f\u06c1 \u067e\u0631\u0648\u0627\u06c1 \u06c1\u06d2\u060c \u06cc\u0627 \u062f\u0644\u06cc\u0644 \u062c\u06cc\u062a\u0646\u06d2 \u06a9\u06cc\u061f\n\u06a9\u06cc\u0627 \u0645\u06cc\u0631\u0627 \u0641\u062e\u0631 \u0645\u062c\u06be\u06d2 \u0645\u06c1\u0631\u0628\u0627\u0646 \u06c1\u0648\u0646\u06d2 \u06a9\u06d2 \u0628\u062c\u0627\u0626\u06d2 \u0635\u062d\u06cc\u062d \u06c1\u0648\u0646\u06d2 \u067e\u0631 \u062a\u0648\u062c\u06c1 \u062f\u06cc\u0646\u06d2 \u06a9\u0627 \u0628\u0627\u0639\u062b \u0628\u0646\u0627 \u0631\u06c1\u0627 \u06c1\u06d2\u061f\n\n\u06a9\u0648\u0627\u0644\u0679\u06cc 2: \u06c1\u0631 \u0627\u06cc\u06a9 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0645\u06c1\u0631\u0628\u0627\u0646\u06d4\n\u062e\u062f\u0627\u0648\u0646\u062f \u06a9\u06d2 \u0628\u0646\u062f\u06c1 \u06a9\u0648 \u06c1\u0631 \u0627\u06cc\u06a9 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0645\u06c1\u0631\u0628\u0627\u0646 \u06c1\u0648\u0646\u0627 \u0686\u0627\u06c1\u06cc\u06d2\u06d4\n\u06cc\u06c1\u0627\u06ba \u062a\u06a9 \u06a9\u06c1 \u0627\u0646 \u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u0628\u06be\u06cc \u062c\u0648 \u0622\u067e \u0633\u06d2 \u0646\u0641\u0631\u062a \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u0622\u067e \u06a9\u0648 \u062a\u06a9\u0644\u06cc\u0641 \u062f\u06cc\u0646\u0627 \u0686\u0627\u06c1\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u06cc\u06c1 \u0645\u0634\u06a9\u0644 \u06c1\u06d2\u060c \u0645\u06cc\u06ba \u062c\u0627\u0646\u062a\u0627 \u06c1\u0648\u06ba\u06d4\n\u06c1\u0645 \u0633\u0645\u062c\u06be\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u0627\u067e\u0646\u06d2 \u0622\u067e \u06a9\u0648 \u062f\u0648\u0633\u0631\u06d2 \u0644\u0648\u06af\u0648\u06ba \u0633\u06d2 \u0628\u0686\u0627\u0646\u06d2 \u06a9\u0627 \u0637\u0631\u06cc\u0642\u06c1 \u0645\u0636\u0628\u0648\u0637 \u06c1\u0648\u0646\u0627\u060c \u0637\u0627\u0642\u062a \u06a9\u0627 \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u06a9\u0631\u0646\u0627 \u06c1\u06d2\u06d4\n\u0644\u06cc\u06a9\u0646 \u062f\u06cc\u06a9\u06be\u06cc\u06ba \u06a9\u06c1 \u067e\u0648\u0644\u0633 \u06c1\u0645\u06cc\u06ba \u0631\u0648\u0645\u06cc\u0648\u06ba 2:4 \u0645\u06cc\u06ba \u06a9\u06cc\u0627 \u06cc\u0627\u062f \u062f\u0644\u0627\u062a\u0627 \u06c1\u06d2\u060c \u06a9\u06c1:\n\u201d\u062e\u064f\u062f\u0627 \u06a9\u06cc \u0645\u0650\u06c1\u0631\u0628\u0627\u0646\u06cc \u062a\u064f\u062c\u06be \u06a9\u0648 \u062a\u064e\u0648\u0628\u06c1 \u06a9\u06cc \u0637\u0631\u0641 \u0645\u0627\u0626\u0650\u0644 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u06d4\u201d\n\u06cc\u0633\u0648\u0639 \u0622\u067e \u06a9\u06d2 \u0633\u0627\u062a\u06be \u06a9\u062a\u0646\u0627 \u0645\u06c1\u0631\u0628\u0627\u0646 \u062a\u06be\u0627\u060c \u062c\u0628 \u0622\u067e \u06af\u0646\u0627\u06c1 \u0645\u06cc\u06ba \u062a\u06be\u06d2 \u0627\u0648\u0631 \u0627\u0633 \u0633\u06d2 \u062f\u0648\u0631 \u0628\u06be\u0627\u06af \u0631\u06c1\u06d2 \u062a\u06be\u06d2\u061f\n\u0627\u0633 \u06a9\u06cc \u0645\u06c1\u0631\u0628\u0627\u0646\u06cc \u0646\u06d2 \u0622\u067e \u06a9\u0648 \u062a\u0648\u0628\u06c1 \u06a9\u06cc \u0637\u0631\u0641 \u0645\u0627\u0626\u0644 \u06a9\u06cc\u0627\u060c\n\u0644\u06c1\u0630\u0627 \u0627\u0628 \u0622\u067e \u06a9\u06d2 \u067e\u0627\u0633 \u0645\u0648\u0642\u0639 \u06c1\u06d2 \u06a9\u06c1 \u0622\u067e \u0645\u0633\u06cc\u062d \u06a9\u06cc \u0646\u0642\u0644 \u06a9\u0631\u06cc\u06ba\u060c \u0627\u0648\u0631 \u06c1\u0631 \u0627\u06cc\u06a9 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0645\u06c1\u0631\u0628\u0627\u0646\u06cc \u06a9\u0631\u06cc\u06ba\u06d4\n\n\u0645\u0639\u06cc\u0627\u0631 3: \u0628\u0631\u0627\u0626\u06cc \u06a9\u0648 \u0635\u0628\u0631 \u0633\u06d2 \u0628\u0631\u062f\u0627\u0634\u062a \u06a9\u0631\u0646\u0627\u06d4\n\u062c\u0628 \u06c1\u0645 \u062e\u0648\u0634\u062e\u0628\u0631\u06cc \u06a9\u06cc \u0633\u0686\u0627\u0626\u06cc \u06a9\u0627 \u0627\u0634\u062a\u0631\u0627\u06a9 \u06a9\u0631 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u060c \u062a\u0648 \u06c1\u0645\u06cc\u06ba \u0627\u0646 \u0644\u0648\u06af\u0648\u06ba \u06a9\u06cc \u0645\u062e\u0627\u0644\u0641\u062a \u06a9\u0627 \u0633\u0627\u0645\u0646\u0627 \u06a9\u0631\u0646\u0627 \u067e\u0691\u06d2 \u06af\u0627 \u062c\u0648 \u06c1\u0645\u0627\u0631\u06cc \u0628\u0627\u062a\u0648\u06ba \u06a9\u0648 \u067e\u0633\u0646\u062f \u0646\u06c1\u06cc\u06ba \u06a9\u0631\u062a\u06d2\u06d4\n\u06a9\u06cc\u0627 \u0622\u067e \u06a9\u0648 \u06cc\u0627\u062f \u06c1\u06d2 \u06a9\u06c1 \u0627\u0633\u062a\u0641\u0646\u0633 \u0646\u06d2 \u0627\u0646 \u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u06a9\u06cc\u0627 \u062c\u0648\u0627\u0628 \u062f\u06cc\u0627 \u062c\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0627\u0633\u06d2 \u0642\u062a\u0644 \u06a9\u06cc\u0627\u061f\n\u0627\u0639\u0645\u0627\u0644 7:59-60 \u06a9\u06c1\u062a\u0627 \u06c1\u06d2:\n59 \u067e\u064e\u0633 \u06cc\u06c1 \u0633\u062a\u0650\u0641\u064e\u0646\u064f\u0633 \u06a9\u0648 \u0633\u0646\u06af\u0633\u0627\u0631 \u06a9\u0631\u062a\u06d2 \u0631\u06c1\u06d2 \u0627\u0648\u0631 \u0648\u06c1 \u06cc\u06c1 \u06a9\u06c1\u06c1 \u06a9\u0631 \u062f\u064f\u0639\u0627 \u06a9\u0631\u062a\u0627 \u0631\u06c1\u0627 \u06a9\u06c1 \u0627\u064e\u06d2 \u062e\u064f\u062f\u0627\u0648\u0646\u062f \u06cc\u0650\u0633\u064f\u0648\u0639 \u06d4 \u0645\u06cc\u0631\u06cc \u0631\u064f\u0648\u062d \u06a9\u0648 \u0642\u064f\u0628\u064f\u0648\u0644 \u06a9\u0631\u06d4\n60 \u067e\u0650\u06be\u0631 \u0627\u064f\u0633 \u0646\u06d2 \u06af\u06be\u064f\u0679\u0646\u06d2 \u0679\u06cc\u06a9 \u06a9\u0631 \u0628\u0691\u06cc \u0622\u0648\u0627\u0632 \u0633\u06d2 \u067e\u064f\u06a9\u0627\u0631\u0627 \u06a9\u06c1 \u0627\u064e\u06d2 \u062e\u064f\u062f\u0627\u0648\u0646\u062f \u06d4 \u06cc\u06c1 \u06af\u064f\u0646\u0627\u06c1 \u0627\u0650\u0646 \u06a9\u06d2 \u0630\u0650\u0645\u06c1 \u0646\u06c1 \u0644\u06af\u0627\u06d4\u201d\n\n\u0635\u0631\u0641 \u062e\u062f\u0627 \u06c1\u06cc \u06c1\u0645\u06cc\u06ba \u0627\u0633\u062a\u0641\u0646\u0633 \u06a9\u06cc \u0637\u0631\u062d \u0628\u0631\u0627\u0626\u06cc \u06a9\u0648 \u0635\u0628\u0631 \u0633\u06d2 \u0628\u0631\u062f\u0627\u0634\u062a \u06a9\u0631\u0646\u06d2 \u0645\u06cc\u06ba \u0645\u062f\u062f \u06a9\u0631 \u0633\u06a9\u062a\u0627 \u06c1\u06d2\u06d4\n\u0644\u06cc\u06a9\u0646 \u062c\u0628 \u06c1\u0645 \u0645\u0635\u06cc\u0628\u062a \u06a9\u06d2 \u0648\u0642\u062a \u0627\u0633\u06d2 \u067e\u06a9\u0627\u0631\u062a\u06d2 \u06c1\u06cc\u06ba \u062a\u0648 \u0648\u06c1 \u06c1\u0645\u0627\u0631\u06cc \u0645\u062f\u062f \u06a9\u0631\u06d2 \u06af\u0627\u06d4\n\u0648\u06c1 \u06c1\u0645\u06cc\u06ba \u0627\u0633 \u067e\u0631 \u0628\u06be\u0631\u0648\u0633\u06c1 \u06a9\u0631\u0646\u06d2 \u0645\u06cc\u06ba \u0645\u062f\u062f \u06a9\u0631\u06d2 \u06af\u0627\u060c \u06cc\u06c1 \u062c\u0627\u0646\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1 \u06c1\u0645\u0627\u0631\u06cc \u0631\u0648\u062d\u06cc\u06ba \u0627\u0633 \u06a9\u06d2 \u06c1\u0627\u062a\u06be \u0645\u06cc\u06ba \u0645\u062d\u0641\u0648\u0638 \u06c1\u06cc\u06ba\u060c \u0686\u0627\u06c1\u06d2 \u06c1\u0645\u0627\u0631\u06d2 \u062c\u0633\u0645\u0648\u06ba \u06a9\u0648 \u06a9\u0686\u06be \u0628\u06be\u06cc \u06c1\u0648\u06d4\n\n\u0645\u0639\u06cc\u0627\u0631 4: \u0646\u0631\u0645\u06cc \u06a9\u06d2 \u0633\u0627\u062a\u06be \u062f\u0631\u0633\u062a \u06a9\u0631\u0646\u0627\u06d4\n\u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u062f\u0631\u0633\u062a \u06a9\u0631\u0646\u0627 \u0645\u0634\u06a9\u0644 \u06c1\u06d2\u06d4\n\u0644\u06cc\u06a9\u0646 \u0627\u06af\u0631 \u0645\u06cc\u0631\u0627 \u0628\u06cc\u0679\u0627 \u06a9\u0686\u06be \u063a\u0644\u0637 \u06a9\u0631 \u0631\u06c1\u0627 \u06c1\u06d2 \u062a\u0648 \u0645\u06cc\u06ba \u0627\u0633\u06d2 \u0628\u062a\u0627\u062a\u0627 \u06c1\u0648\u06ba \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0645\u06cc\u06ba \u0627\u0633 \u0633\u06d2 \u067e\u06cc\u0627\u0631 \u06a9\u0631\u062a\u0627 \u06c1\u0648\u06ba\u06d4\n\u062c\u0628 \u0622\u067e \u06a9\u0648 \u06a9\u0633\u06cc \u06a9\u0648 \u062f\u0631\u0633\u062a \u06a9\u0631\u0646\u0627 \u06c1\u06d2 \u062a\u0648 \u0627\u0633 \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u0633\u0648\u0686\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06cc\u06c1 \u0627\u06c1\u0645 \u0633\u0648\u0627\u0644 \u06c1\u06d2:\n\u201d\u06a9\u06cc\u0627 \u0645\u06cc\u0631\u0627 \u0628\u0686\u06c1\u060c \u062f\u0648\u0633\u062a\u060c \u06cc\u0627 \u0634\u0631\u06cc\u06a9 \u062d\u06cc\u0627\u062a \u0645\u06cc\u0631\u06cc \u0645\u062d\u0628\u062a \u06a9\u0648 \u0645\u062d\u0633\u0648\u0633 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u061f\n\u06cc\u0627 \u0648\u06c1 \u0635\u0631\u0641 \u0645\u06cc\u0631\u0627 \u063a\u0635\u06c1 \u0645\u062d\u0633\u0648\u0633 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u061f\u201d\n\n\u062c\u0628 \u06c1\u0645 \u063a\u0635\u06d2 \u06cc\u0627 \u0645\u0627\u06cc\u0648\u0633\u06cc \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0627\u0635\u0644\u0627\u062d \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u062a\u0648 \u06c1\u0645 \u0627\u06cc\u0633\u0627 \u06a9\u0627\u0645 \u06a9\u0631 \u0631\u06c1\u06d2 \u06c1\u0648\u062a\u06d2 \u06c1\u06cc\u06ba \u062c\u06cc\u0633\u06d2 \u062e\u062f\u0627 \u062f\u0648\u0633\u0631\u06d2 \u0634\u062e\u0635 \u06a9\u0648 \u062a\u0628\u062f\u06cc\u0644 \u0646\u06c1\u06cc\u06ba \u06a9\u0631 \u0633\u06a9\u062a\u0627\u06d4\n\u06c1\u0645 \u0633\u0648\u0686\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u06c1\u0645 \u0627\u0646 \u067e\u0631 \u062a\u0628\u062f\u06cc\u0644\u06cc \u06a9\u06d2 \u0644\u06cc\u06d2 \u062f\u0628\u0627\u0624 \u0688\u0627\u0644 \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u06cc\u0627 \u0627\u0633 \u0648\u0642\u062a \u062a\u06a9 \u0632\u0648\u0631 \u0633\u06d2 \u0686\u06cc\u062e \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba \u062c\u0628 \u062a\u06a9 \u06a9\u06c1 \u0648\u06c1 \u0635\u062d\u06cc\u062d \u0631\u0627\u0633\u062a\u06d2 \u067e\u0631 \u0646\u06c1 \u0622\u062c\u0627\u0626\u06cc\u06ba\u06d4\n\u0644\u06cc\u06a9\u0646 \u0627\u06cc\u06a9 \u0627\u0633\u062a\u0627\u062f \u062c\u0648 \u062c\u0627\u0646\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1 \u062d\u0642\u06cc\u0642\u06cc \u0637\u0627\u0642\u062a \u062e\u062f\u0627 \u06a9\u06d2 \u067e\u0627\u0633 \u06c1\u06d2 \u0648\u06c1 \u0646\u0631\u0645 \u0645\u0632\u0627\u062c\u060c \u0635\u0627\u0628\u0631 \u0627\u0648\u0631 \u0645\u06c1\u0631\u0628\u0627\u0646 \u06c1\u0648\u06af\u0627\u06d4\n\n\u0645\u0639\u06cc\u0627\u0631 5: \u0633\u06a9\u06be\u0627\u0646\u06d2 \u06a9\u06d2 \u0642\u0627\u0628\u0644\u06d4\n\u06a9\u06cc\u0627 \u0622\u067e \u062e\u062f\u0627 \u06a9\u06d2 \u06a9\u0644\u0627\u0645 \u06a9\u0648 \u062f\u0648\u0633\u0631\u0648\u06ba \u06a9\u0648 \u0633\u0645\u062c\u06be\u0627\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06a9\u0627\u0641\u06cc \u0627\u0686\u06be\u06cc \u0637\u0631\u062d \u0633\u0645\u062c\u06be\u062a\u06d2 \u06c1\u06cc\u06ba\u061f\n\u06a9\u06cc\u0627 \u0622\u067e \u0635\u062d\u06cc\u0641\u06d2 \u06a9\u0648 \u062d\u0641\u0638 \u06a9\u0631 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u060c \u0644\u06c1\u0630\u0627 \u0622\u067e \u06a9\u06d2 \u067e\u0627\u0633 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u06ba \u0622\u067e \u06a9\u06cc \u0631\u06c1\u0646\u0645\u0627\u0626\u06cc \u06a9\u0631\u0646\u06d2 \u0627\u0648\u0631 \u062f\u0648\u0633\u0631\u0648\u06ba \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0627\u0634\u062a\u0631\u0627\u06a9 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u062a\u06cc\u0627\u0631 \u06c1\u06d2\u061f\n\u06c1\u0645 \u0627\u0633 \u0645\u06c1\u06cc\u0646\u06d2 \u06a9\u0686\u06be \u0646\u06cc\u0627 \u0634\u0631\u0648\u0639 \u06a9\u0631\u0646\u06d2 \u062c\u0627 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u06c1\u0645 \u0622\u067e \u0633\u06d2 \u0645\u0627\u0631\u0686 \u06a9\u06d2 \u0622\u062e\u0631 \u062a\u06a9 \u0635\u062d\u06cc\u0641\u06d2 \u06a9\u06cc \u0627\u06cc\u06a9 \u0622\u06cc\u062a \u06a9\u0648 \u062d\u0641\u0638 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06a9\u06c1\u0646\u06d2 \u062c\u0627 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u0627\u0648\u0631 \u0627\u06af\u0631 \u0622\u067e \u0627\u0633\u06d2 \u06c1\u0645\u0627\u0631\u06d2 \u0644\u06cc\u0688\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0633\u06d2 \u06a9\u0633\u06cc \u06a9\u0648\u060c \u06a9\u0633\u06cc \u0628\u06be\u06cc \u0632\u0628\u0627\u0646 \u0645\u06cc\u06ba \u0633\u0646\u0627 \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba\u060c \u062a\u0648 \u0622\u067e \u06a9\u0648 \u0627\u06cc\u06a9 \u0627\u0633\u0679\u06cc\u06a9\u0631 \u0645\u0644\u06d2 \u06af\u0627\u06d4\n\u0622\u067e \u0627\u0633\u06d2 \u0627\u067e\u0646\u06cc \u067e\u0627\u0646\u06cc \u06a9\u06cc \u0628\u0648\u062a\u0644 \u06cc\u0627 \u0646\u0648\u0679 \u0628\u06a9 \u067e\u0631 \u0631\u06a9\u06be \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\n\u06a9\u06c1\u06cc\u06ba \u0628\u06be\u06cc \u0622\u067e \u0627\u0633\u06d2 \u062f\u06cc\u06a9\u06be\u06cc\u06ba \u06af\u06d2 \u0627\u0648\u0631 \u0633\u0627\u0631\u0627 \u0633\u0627\u0644 \u0627\u0633 \u067e\u0631 \u0639\u0645\u0644 \u06a9\u0631\u062a\u06d2 \u0631\u06c1\u06cc\u06ba \u06af\u06d2\u06d4\n\u0622\u0626\u06cc\u06d2 \u0645\u0644 \u06a9\u0631 \u0645\u0627\u0631\u0686 \u06a9\u06d2 \u0645\u06c1\u06cc\u0646\u06d2 \u06a9\u06cc \u0622\u06cc\u062a \u06a9\u0648 \u067e\u0691\u06be\u06cc\u06ba\u060c 2 \u062a\u06cc\u0645\u062a\u06be\u06cc\u0633 3:16\u06d4\n\u062a\u0645\u0627\u0645: \u201d\u06c1\u0631 \u0627\u06cc\u06a9 \u0635\u062d\u0650\u06cc\u0641\u06c1 \u062c\u0648 \u062e\u064f\u062f\u0627 \u06a9\u06d2 \u0627\u0650\u0644\u06c1\u0627\u0645 \u0633\u06d2 \u06c1\u06d2 \u062a\u0639\u0644\u0650\u06cc\u0645 \u0627\u0648\u0631 \u0627\u0650\u0644\u0632\u0627\u0645 \u0627\u0648\u0631 \u0627\u0650\u0635\u0644\u0627\u062d \u0627\u0648\u0631 \u0631\u0627\u0633\u062a \u0628\u0627\u0632\u06cc \u0645\u06cc\u06ba \u062a\u0631\u0628\u0650\u06cc\u0651\u062a \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u0650\u0626\u06d2 \u0641\u0627\u0626\u0650\u062f\u06c1 \u0645\u0646\u062f \u0628\u06be\u06cc \u06c1\u06d2\u06d4\u201d\n\n\u0635\u062d\u06cc\u062d \u0633\u0645\u062a \u0645\u06cc\u06ba \u0686\u0644\u062a\u06d2 \u0631\u06c1\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06c1\u0645 \u0633\u0628 \u06a9\u0648 \u0645\u062f\u062f \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u06c1\u06d2\u06d4\n\u06c1\u0645\u06cc\u06ba \u0631\u0627\u0633\u062a\u0628\u0627\u0632\u06cc \u067e\u0631 \u0686\u0644\u0646\u06d2 \u06a9\u06cc \u062a\u0639\u0644\u06cc\u0645 \u062f\u06cc\u0646\u06d2\u060c \u062f\u0631\u0633\u062a \u06a9\u0631\u0646\u06d2 \u0627\u0648\u0631 \u062a\u0631\u0628\u06cc\u062a \u062f\u06cc\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u062e\u062f\u0627 \u06a9\u06d2 \u06a9\u0644\u0627\u0645 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u06c1\u06d2\u06d4\n\u0627\u0648\u0631 \u06c1\u0645\u06cc\u06ba \u06a9\u0644\u0627\u0645 \u06a9\u0648 \u0633\u0645\u062c\u06be\u0646\u06d2 \u0627\u0648\u0631 \u0644\u0627\u06af\u0648 \u06a9\u0631\u0646\u06d2 \u0645\u06cc\u06ba \u06c1\u0645\u0627\u0631\u06cc \u0645\u062f\u062f \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0631\u0648\u062d \u0627\u0644\u0642\u062f\u0633 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u06c1\u06d2\u060c \u062a\u0648 \u0622\u0626\u06cc\u06d2 \u0627\u0628 \u062f\u0639\u0627 \u0645\u06cc\u06ba \u0627\u067e\u0646\u06d2 \u062f\u0644\u0648\u06ba \u06a9\u0648 \u0622\u0633\u0645\u0627\u0646 \u06a9\u06cc \u0637\u0631\u0641 \u0645\u0648\u0691 \u062f\u06cc\u06ba\u06d4\n\u06cc\u0633\u0648\u0639\u060c \u06c1\u0645 \u0628\u0627\u067e \u0633\u06d2 \u0627\u0633 \u0644\u06cc\u06d2 \u0628\u0627\u062a \u06a9\u0631 \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u062a\u0648 \u0646\u06d2 \u0632\u0645\u06cc\u0646 \u0627\u0648\u0631 \u0622\u0633\u0645\u0627\u0646 \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u0627\u06cc\u06a9 \u067e\u0644 \u0628\u0646\u0627\u06cc\u0627 \u06c1\u06d2\u06d4\n\u062a\u0648 \u0646\u06d2 \u0634\u06cc\u0637\u0627\u0646 \u06a9\u06d2 \u067e\u06be\u0646\u062f\u0648\u06ba \u06a9\u0648 \u062a\u0628\u0627\u06c1 \u06a9\u0631 \u062f\u06cc\u0627 \u0627\u0648\u0631 \u06c1\u0645\u0627\u0631\u06cc \u0622\u0646\u06a9\u06be\u06cc\u06ba \u0633\u0686 \u06a9\u06cc \u0637\u0631\u0641 \u06a9\u06be\u0648\u0644 \u062f\u06cc\u06ba\u06d4\n\u0628\u0627\u067e\u060c \u06c1\u0645\u06cc\u06ba \u062a\u0648\u0628\u06c1 \u06a9\u0627 \u062a\u0648\u0641\u06cc\u0642 \u062f\u06cc\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u062a\u06cc\u0631\u0627 \u0634\u06a9\u0631\u06cc\u06c1\u060c \u062a\u0627\u06a9\u06c1 \u06c1\u0645 \u0627\u067e\u0646\u06d2 \u06af\u0646\u0627\u06c1 \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u0627\u067e\u0646\u06d2 \u0622\u067e \u0627\u0648\u0631 \u062a\u06cc\u0631\u06d2 \u0633\u0627\u062a\u06be \u0627\u06cc\u0645\u0627\u0646\u062f\u0627\u0631 \u06c1\u0648 \u0633\u06a9\u06cc\u06ba\u06d4\n\u0627\u0648\u0631 \u062a\u06cc\u0631\u0627 \u0634\u06a9\u0631\u06cc\u06c1\u060c \u0631\u0648\u062d \u0627\u0644\u0642\u062f\u0633\u060c \u06c1\u0645\u0627\u0631\u06cc \u0646\u062c\u0627\u062a \u06a9\u06d2 \u0644\u06cc\u06d2 \u06cc\u0633\u0648\u0639 \u06a9\u06cc \u0637\u0631\u0641 \u0631\u062c\u0648\u0639 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06c1\u0645\u06cc\u06ba \u0627\u06cc\u0645\u0627\u0646 \u062f\u06cc\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2\u06d4\n\u06a9\u0644\u0627\u0645 \u06a9\u0648 \u0633\u0645\u062c\u06be\u0646\u06d2 \u0627\u0648\u0631 \u0627\u067e\u0646\u06cc \u0632\u0646\u062f\u06af\u06cc\u0648\u06ba \u067e\u0631 \u0644\u0627\u06af\u0648 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06c1\u0645\u0627\u0631\u06d2 \u0630\u06c1\u0646\u0648\u06ba \u0627\u0648\u0631 \u062f\u0644\u0648\u06ba \u06a9\u0648 \u06a9\u06be\u0648\u0644\u06cc\u06ba\u06d4\n\u06c1\u0645\u0627\u0631\u06d2 \u0633\u0627\u0645\u0646\u06d2 \u0631\u06a9\u06be\u06cc \u06c1\u0648\u0626\u06cc \u062f\u0648\u0691 \u06a9\u0648 \u0645\u062d\u0646\u062a \u0633\u06d2 \u062f\u0648\u0691\u0646\u06d2 \u0645\u06cc\u06ba \u06c1\u0645\u0627\u0631\u06cc \u0645\u062f\u062f \u06a9\u0631\u060c \u062f\u0648\u0633\u0631\u0648\u06ba \u06a9\u0648 \u062f\u0639\u0648\u062a \u062f\u06cc\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1 \u0648\u06c1 \u06a9\u0627\u0645\u0644\u06cc\u062a\u060c \u0627\u064f\u0645\u06cc\u062f \u0627\u0648\u0631 \u0622\u0633\u0645\u0627\u0646 \u06a9\u06d2 \u0633\u0641\u0631 \u0645\u06cc\u06ba \u06c1\u0645\u0627\u0631\u06d2 \u0633\u0627\u062a\u06be \u0634\u0627\u0645\u0644 \u06c1\u0648\u06ba\u060c \u0622\u0645\u06cc\u0646\u06d4\n\n\u0633\u0648\u0686 \u0628\u0686\u0627\u0631 \u0627\u0648\u0631 \u0628\u062d\u062b \u06a9\u06d2 \u0644\u06cc\u06d2 \u0633\u0648\u0627\u0644\u0627\u062a\n1.  2 \u062a\u06cc\u0645\u062a\u06be\u06cc\u0633 2:22 \u0627\u0648\u0631 \u0632\u0628\u0648\u0631 119:35-37 \u06a9\u0648 \u067e\u0691\u06be\u06cc\u06ba\u06d4\na) \u062c\u0628 \u0622\u067e \u062a\u0646\u0627\u0624 \u06cc\u0627 \u0633\u06a9\u0648\u0646 \u06a9\u06cc \u062a\u0644\u0627\u0634 \u0645\u06cc\u06ba \u06c1\u0648\u062a\u06d2 \u06c1\u06cc\u06ba \u062a\u0648 \u0622\u067e \u06a9\u0648 \u201d\u062c\u0648\u0627\u0646\u06cc \u06a9\u06cc \u062e\u0648\u0627\u06c1\u0634\u0648\u06ba\u201d \u0645\u06cc\u06ba \u0633\u06d2 \u06a9\u0633 \u0686\u06cc\u0632 (\u062e\u0648\u0634\u06cc\u060c \u0637\u0627\u0642\u062a\u060c \u0645\u0642\u0628\u0648\u0644\u06cc\u062a\u060c \u0645\u0627\u0644\u060c \u0641\u062e\u0631) \u06a9\u06cc \u0637\u0631\u0641 \u0642\u062f\u0631\u062a\u06cc \u0637\u0648\u0631 \u067e\u0631 \u0627\u067e\u0646\u0627 \u062f\u0644 \u062f\u0648\u0691\u062a\u0627 \u0645\u062d\u0633\u0648\u0633 \u06c1\u0648\u062a\u0627 \u06c1\u06d2\u061f\n\n2.  \u0627\u0641\u0633\u06cc\u0648\u06ba 2:1-5 \u0627\u0648\u0631 \u062d\u0632\u0642\u06cc \u0627\u06cc\u0644 36:26 \u06a9\u0648 \u067e\u0691\u06be\u06cc\u06ba\u06d4\na) \u201d\u0645\u0631\u062f\u06c1\u201d \u0633\u06d2 \u201d\u0632\u0646\u062f\u06c1\u201d \u06c1\u0648\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06a9\u06cc\u0627 \u0636\u0631\u0648\u0631\u06cc \u06c1\u06d2\u061f\n\u0628) \u06a9\u06cc\u0627 \u06cc\u06c1 \u0645\u0627\u0646\u0646\u0627 \u06a9\u06c1 \u062a\u0648\u0628\u06c1 \u0641\u0636\u0644 \u06a9\u0627 \u062a\u062d\u0641\u06c1 \u06c1\u06d2 \u0622\u067e \u06a9\u0648 \u0627\u067e\u0646\u06d2 \u06af\u0646\u0627\u06c1 \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u062e\u062f\u0627 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0632\u06cc\u0627\u062f\u06c1 \u0627\u06cc\u0645\u0627\u0646\u062f\u0627\u0631 \u06c1\u0648\u0646\u06d2 \u0645\u06cc\u06ba \u0645\u062f\u062f \u0645\u0644\u062a\u06cc \u06c1\u06d2\u061f\n\n3.  2 \u062a\u06cc\u0645\u062a\u06be\u06cc\u0633 2:23-25a \u0627\u0648\u0631 \u06a9\u0644\u0633\u06cc\u0648\u06ba 3:12-14 \u06a9\u0648 \u067e\u0691\u06be\u06cc\u06ba\u06d4\n\u0627) \u062f\u0648\u0633\u0631\u0648\u06ba \u0633\u06d2 \u0628\u062d\u062b \u06cc\u0627 \u0627\u0635\u0644\u0627\u062d \u06a9\u0631\u062a\u06d2 \u0648\u0642\u062a \u201d\u062e\u062f\u0627\u0648\u0646\u062f \u06a9\u06d2 \u0628\u0646\u062f\u06d2\u201d \u06a9\u06cc \u06a9\u06cc\u0627 \u062e\u0648\u0628\u06cc\u0627\u06ba \u06c1\u06cc\u06ba\u061f\n\u0628) \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u06cc\u0633\u0648\u0639 \u0646\u06d2 \u06c1\u0645 \u0633\u06d2 \u0628\u0691\u06d2 \u062a\u062d\u0645\u0644 \u0627\u0648\u0631 \u0646\u0631\u0645\u06cc \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0645\u062d\u0628\u062a \u06a9\u06cc\u060c \u0622\u067e \u0627\u067e\u0646\u06cc \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u06ba \u06a9\u0633 \u0633\u06d2 \u0627\u0633\u06cc \u0641\u0636\u0644 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0645\u062d\u0628\u062a \u06a9\u0631\u06cc\u06ba \u06af\u06d2- \u062e\u0648\u0627\u06c1 \u0648\u06c1 \u0622\u067e \u0633\u06d2 \u0645\u062a\u0641\u0642 \u06c1\u0648\u06ba \u06cc\u0627 \u0622\u067e \u06a9\u0648 \u067e\u0633\u0646\u062f \u0646\u06c1 \u06a9\u0631\u06cc\u06ba\u061f\n\n4.  \u0631\u0648\u0645\u06cc\u0648\u06ba 10:9-11 \u0627\u0648\u0631 \u0639\u0628\u0631\u0627\u0646\u06cc\u0648\u06ba 12:1-2 \u06a9\u0648 \u067e\u0691\u06be\u06cc\u06ba\u06d4\n\u0627) \u06cc\u0633\u0648\u0639 \u067e\u0631 \u0627\u067e\u0646\u06cc \u0646\u0638\u0631\u06cc\u06ba \u062c\u0645\u0627\u0646\u06d2 \u0633\u06d2 \u06c1\u0645\u06cc\u06ba \u06af\u0646\u0627\u06c1 \u0633\u06d2 \u0628\u0627\u0632 \u0622\u0646\u06d2 \u0627\u0648\u0631 \u0627\u06cc\u06a9 \u0646\u0626\u06cc \u0633\u0645\u062a \u0645\u06cc\u06ba \u0628\u06be\u0627\u06af\u0646\u06d2 \u0645\u06cc\u06ba \u06a9\u06cc\u0633\u06d2 \u0645\u062f\u062f \u0645\u0644\u062a\u06cc \u06c1\u06d2\u061f\n\u0628) 2 \u062a\u06cc\u0645\u062a\u06be\u06cc\u0633 3:16 \u06a9\u0648 \u06cc\u0627\u062f \u06a9\u0631\u0646\u0627 \u06cc\u0627\u062f \u0631\u06a9\u06be\u06cc\u06ba\u06d4 \u062e\u062f\u0627 \u06a9\u06d2 \u06a9\u0644\u0627\u0645 \u06a9\u0648 \u062c\u0627\u0646\u0646\u0627 \u0627\u06cc\u0645\u0627\u0646 \u06a9\u06cc \u0645\u06cc\u0631\u0627\u062a\u06be\u0646 \u0645\u06cc\u06ba \u062f\u0648\u0691\u0646\u06d2 \u0645\u06cc\u06ba \u06c1\u0645\u0627\u0631\u06cc \u0645\u062f\u062f \u06a9\u06cc\u0633\u06d2 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u061f","uyghur_content":"\u0642\u06d5\u064a\u06d5\u0631\u06af\u06d5 \u064a\u06c8\u06af\u06c8\u0631\u06c8\u06cb\u0627\u062a\u0649\u0633\u0649\u0632\u061f\n2 \u062a\u0649\u0645\u0648\u062a\u0649\u064a\u063a\u0627 2:22-26\n\u067e\u0648\u067e \u0643\u0649\u0631\u0649\u0633 \u0633\u0649\u0643\u0649\u0633\n2026-\u064a\u0649\u0644\u0649 15-\u0645\u0627\u0631\u062a\n\n2019-\u064a\u0649\u0644\u0649 \u0626\u0648\u0631\u06d0\u06af\u0648\u0646 \u0634\u0649\u062a\u0627\u062a\u0649\u0646\u0649\u06ad \u067e\u0648\u0631\u062a\u0644\u0627\u0646\u062f \u0634\u06d5\u06be\u0649\u0631\u0649\u062f\u06d5 \u0626\u06c6\u062a\u0643\u06c8\u0632\u06c8\u0644\u06af\u06d5\u0646 \u0645\u0627\u0631\u0627\u0641\u0648\u0646\u0686\u06d5 \u064a\u06c8\u06af\u06c8\u0631\u06c8\u0634 \u0645\u06c7\u0633\u0627\u0628\u0649\u0642\u0649\u0633\u0649\u062f\u06d5\u060c \u0626\u06d5\u06ad \u064a\u0627\u062e\u0634\u0649 \u064a\u06c8\u06af\u06c8\u0631\u06af\u06c8\u0686\u0649\u0644\u06d5\u0631\u0646\u0649\u06ad \u0628\u06d5\u0632\u0649\u0644\u0649\u0631\u0649 \u0645\u06c7\u0633\u0627\u0628\u0649\u0642\u0649\u062f\u06d5 \u0645\u06d5\u063a\u0644\u06c7\u067e \u0628\u0648\u0644\u062f\u0649.\n\u0626\u06c7\u0644\u0627\u0631\u0646\u0649\u06ad \u0626\u0627\u0633\u062a\u0627 \u0628\u0648\u0644\u063a\u0627\u0646\u0644\u0649\u0642\u0649 \u0626\u06c8\u0686\u06c8\u0646 \u0626\u06d5\u0645\u06d5\u0633\u060c \u0628\u06d5\u0644\u0643\u0649 \u062e\u0627\u062a\u0627 \u064a\u0648\u0644\u063a\u0627 \u0643\u0649\u0631\u0649\u067e \u0642\u0627\u0644\u063a\u0627\u0646\u0644\u0649\u0642\u0649 \u0626\u06c8\u0686\u06c8\u0646.\n\u064a\u0648\u0644\u062f\u0627 \u0626\u06d0\u0646\u0649\u0642 \u0628\u06d5\u0644\u06af\u06d5 \u0642\u0648\u064a\u06c7\u0644\u0645\u0649\u063a\u0627\u0646 \u0628\u0649\u0631 \u0628\u06c7\u0631\u06c7\u0644\u06c7\u0634 \u0628\u0627\u0631 \u0626\u0649\u062f\u0649.\n\u0634\u06c7\u06ad\u0627 \u0626\u06d5\u06ad \u062a\u06d0\u0632 \u064a\u06c8\u06af\u06c8\u0631\u06af\u06c8\u0686\u0649\u0644\u06d5\u0631\u0646\u0649\u06ad \u062a\u06d5\u062e\u0645\u0649\u0646\u06d5\u0646 20 \u0633\u0649 \u062e\u0627\u062a\u0627 \u064a\u06c6\u0646\u0649\u0644\u0649\u0634\u062a\u06d5 \u0628\u0649\u0631 \u0645\u0649\u0644\u062f\u0649\u0646 \u0626\u0627\u0631\u062a\u06c7\u0642 \u064a\u06c8\u06af\u06c8\u0631\u062f\u0649!\n\u0628\u06c7 \u062e\u0627\u062a\u0627\u0644\u0649\u0642 \u0626\u06c7\u0644\u0627\u0631\u0646\u0649\u06ad \u0646\u06d5\u0686\u0686\u06d5 \u0626\u0627\u064a \u06cb\u0627\u0642\u0649\u062a \u0633\u06d5\u0631\u067e \u0642\u0649\u0644\u0649\u067e \u0645\u06c7\u0633\u0627\u0628\u0649\u0642\u0649\u06af\u06d5 \u062a\u06d5\u064a\u064a\u0627\u0631\u0644\u0649\u0642 \u0642\u0649\u0644\u063a\u0627\u0646 \u0642\u0649\u0645\u0645\u06d5\u062a\u0644\u0649\u0643 \u0645\u0649\u0646\u06c7\u062a\u0644\u0649\u0631\u0649\u0646\u0649 \u0642\u0648\u0634\u062a\u0649.\n\u0626\u06c7 \u0626\u06d5\u0631-\u0626\u0627\u064a\u0627\u0644\u0644\u0627\u0631 \u0642\u0627\u062a\u062a\u0649\u0642 \u064a\u06c8\u06af\u06c8\u0631\u062f\u0649\u060c \u0626\u06c7\u0644\u0627\u0631 \u062a\u06d0\u0632 \u064a\u06c8\u06af\u06c8\u0631\u062f\u0649.\n\u0644\u06d0\u0643\u0649\u0646 \u0626\u06c7\u0644\u0627\u0631 \u062e\u0627\u062a\u0627 \u064a\u0648\u0644\u062f\u0627 \u0628\u0648\u0644\u063a\u0627\u0686\u0642\u0627\u060c \u0645\u06c7\u0633\u0627\u0628\u0649\u0642\u0649\u062f\u06d5 \u0626\u06c7\u062a\u062a\u06c7\u0631\u06c7\u067e \u0642\u0648\u064a\u062f\u0649.\n\u0628\u06c8\u06af\u06c8\u0646 \u0643\u06d5\u0686\u062a\u06d5 \u0628\u0649\u0632 \u062a\u0649\u0645\u0648\u062a\u0649\u064a\u063a\u0627 \u064a\u06d0\u0632\u0649\u0644\u063a\u0627\u0646 2-\u0628\u0627\u0628 \u0643\u0649\u062a\u0627\u0628\u0649\u062f\u0649\u0643\u0649 \u06cb\u06d5\u0632-\u0646\u06d5\u0633\u0649\u06be\u06d5\u062a\u0644\u06d5\u0631\u0646\u0649 \u062f\u0627\u06cb\u0627\u0645\u0644\u0627\u0634\u062a\u06c7\u0631\u0649\u0645\u0649\u0632.\n\u0626\u06d5\u0644\u0686\u0649 \u067e\u0627\u06cb\u0644\u06c7\u0633 \u0626\u06d5\u0641\u06d5\u0633\u062a\u0649\u0643\u0649 \u062e\u0649\u0631\u0649\u0633\u062a\u0649\u064a\u0627\u0646 \u0686\u06d0\u0631\u0643\u0627\u06cb\u0649\u0646\u0649\u06ad \u064a\u0627\u0634 \u067e\u0648\u067e\u0649 \u062a\u0649\u0645\u0648\u062a\u0649\u064a\u063a\u0627 \u062e\u06d5\u062a \u064a\u0627\u0632\u062f\u0649.\n\u067e\u0627\u06cb\u0644\u06c7\u0633 \u062a\u0649\u0645\u0648\u062a\u0649\u064a\u063a\u0627 \u06cb\u06d5 \u0628\u06c8\u06af\u06c8\u0646 \u0628\u0649\u0632\u06af\u06d5 \u062a\u0648\u063a\u0631\u0627 \u064a\u0648\u0644\u062f\u0627 \u0642\u0627\u0646\u062f\u0627\u0642 \u0645\u06d0\u06ad\u0649\u0634 \u062a\u0648\u063a\u0631\u0649\u0633\u0649\u062f\u0627 \u0645\u06d5\u0633\u0644\u0649\u06be\u06d5\u062a \u0628\u06d0\u0631\u0649\u06cb\u0627\u062a\u0649\u062f\u06c7.\n2 \u062a\u0649\u0645\u0648\u062a\u0649\u064a\u063a\u0627 2:22\u201326\n22 \u0634\u06c7\u06ad\u0627\u060c \u064a\u0627\u0634\u0644\u0649\u0642\u0642\u0627 \u062e\u0627\u0633 \u06be\u06d5\u06cb\u06d5\u0633\u0644\u06d5\u0631\u062f\u0649\u0646 \u0642\u06d0\u0686\u0649\u067e\u060c \u067e\u0627\u0643 \u0642\u06d5\u0644\u0628\u062a\u0649\u0646 \u067e\u06d5\u0631\u06cb\u06d5\u0631\u062f\u0649\u06af\u0627\u0631\u063a\u0627 \u062f\u06c7\u0626\u0627 \u0642\u0649\u0644\u063a\u06c7\u0686\u0649\u0644\u0627\u0631 \u0628\u0649\u0644\u06d5\u0646 \u0628\u0649\u0644\u0644\u06d5 \u06be\u06d5\u0642\u0642\u0627\u0646\u0649\u064a\u06d5\u062a\u060c \u0626\u0649\u0645\u0627\u0646\u060c \u0645\u06c7\u06be\u06d5\u0628\u0628\u06d5\u062a \u06cb\u06d5 \u062a\u0649\u0646\u0686\u0644\u0649\u0642\u0646\u0649\u06ad \u0626\u0649\u0632\u0649\u062f\u0649\u0646 \u0645\u06d0\u06ad\u0649\u06ad.\n23 \u0626\u06d5\u062e\u0645\u06d5\u0642\u0627\u0646\u06d5\u060c \u0646\u0627\u062f\u0627\u0646 \u062a\u0627\u0644\u0627\u0634-\u062a\u0627\u0631\u062a\u0649\u0634\u0644\u0627\u0631\u063a\u0627 \u0626\u0627\u0631\u0649\u0644\u0627\u0634\u0645\u0627\u060c \u0686\u06c8\u0646\u0643\u0649 \u0626\u06c7\u0644\u0627\u0631\u0646\u0649\u06ad \u062c\u06d0\u062f\u06d5\u0644-\u0645\u0627\u062c\u0649\u0631\u0627 \u067e\u06d5\u064a\u062f\u0627 \u0642\u0649\u0644\u0649\u062f\u0649\u063a\u0627\u0646\u0644\u0649\u0642\u0649\u0646\u0649 \u0628\u0649\u0644\u0649\u0633\u0649\u0644\u06d5\u0631.\n24 \u067e\u06d5\u0631\u06cb\u06d5\u0631\u062f\u0649\u06af\u0627\u0631\u0646\u0649\u06ad \u062e\u0649\u0632\u0645\u06d5\u062a\u0643\u0627\u0631\u0649 \u062c\u06d0\u062f\u06d5\u0644\u062e\u0648\u0631 \u0626\u06d5\u0645\u06d5\u0633\u060c \u0628\u06d5\u0644\u0643\u0649 \u06be\u06d5\u0645\u0645\u06d5\u064a\u0644\u06d5\u0646\u06af\u06d5 \u0645\u06d0\u06be\u0631\u0649\u0628\u0627\u0646\u060c \u062a\u06d5\u0644\u0649\u0645 \u0628\u06d0\u0631\u0649\u0634\u0643\u06d5 \u0645\u0627\u06be\u0649\u0631\u060c \u064a\u0627\u0645\u0627\u0646\u0644\u0649\u0642\u0642\u0627 \u0633\u06d5\u06cb\u0631\u0686\u0627\u0646\u0644\u0649\u0642 \u0628\u0649\u0644\u06d5\u0646 \u0686\u0649\u062f\u0627\u064a\u062f\u0649\u063a\u0627\u0646 \u0628\u0648\u0644\u06c7\u0634\u0649 \u0643\u06d0\u0631\u06d5\u0643.\n25 \u0631\u06d5\u0642\u0649\u0628\u0644\u0649\u0631\u0649\u0646\u0649 \u0645\u06c7\u0644\u0627\u064a\u0649\u0645\u0644\u0649\u0642 \u0628\u0649\u0644\u06d5\u0646 \u062a\u06c8\u0632\u0649\u062a\u062a\u0649.\n\u0628\u06d5\u0644\u0643\u0649\u0645 \u062e\u06c7\u062f\u0627 \u0626\u06c7\u0644\u0627\u0631\u063a\u0627 \u06be\u06d5\u0642\u0649\u0642\u06d5\u062a\u0646\u0649 \u0628\u0649\u0644\u0649\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u062a\u06d5\u06cb\u0628\u06d5 \u0642\u0649\u0644\u0649\u0634 \u067e\u06c7\u0631\u0633\u0649\u062a\u0649 \u064a\u0627\u0631\u0649\u062a\u0649\u067e \u0628\u06d0\u0631\u0649\u0634\u0649 \u0645\u06c7\u0645\u0643\u0649\u0646\u060c\n26 \u0626\u06c7\u0644\u0627\u0631 \u0626\u0649\u0628\u0644\u0649\u0633\u0646\u0649\u06ad \u062a\u06c7\u0632\u0649\u0642\u0649\u063a\u0627 \u0686\u06c8\u0634\u06c8\u067e\u060c \u0626\u06c7\u0646\u0649\u06ad \u0626\u0649\u0631\u0627\u062f\u0649\u0633\u0649\u0646\u0649 \u0626\u0627\u062f\u0627 \u0642\u0649\u0644\u0649\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0626\u06c7\u0646\u0649\u06ad \u062a\u06c7\u0632\u0649\u0642\u0649\u062f\u0649\u0646 \u0642\u06c7\u062a\u06c7\u0644\u06c7\u067e\u060c \u0626\u06d5\u0642\u0644\u0649\u0646\u0649 \u064a\u0649\u063a\u0649\u0634\u0649 \u0645\u06c7\u0645\u0643\u0649\u0646.\n\n\u0626\u06c7\u0644-\u0626\u06d0\u062a\u0649\u0642\u0627\u062a\u0686\u0649\u0644\u0627\u0631\n\u00ab\u0626\u0648\u062a-\u0686\u06c6\u067e\u0644\u06d5\u0631 \u0642\u06c7\u0631\u06c7\u067e \u0643\u06d0\u062a\u0649\u062f\u06c7\u060c \u06af\u06c8\u0644\u0644\u06d5\u0631 \u0633\u0648\u0644\u0649\u062f\u06c7\u060c \u0626\u06d5\u0645\u0645\u0627 \u062e\u06c7\u062f\u0627\u064a\u0649\u0645\u0649\u0632\u0646\u0649\u06ad \u0633\u06c6\u0632\u0649 \u0645\u06d5\u06ad\u06af\u06c8 \u062a\u06c7\u0631\u0649\u062f\u06c7\u00bb.\n\n22-\u0626\u0627\u064a\u06d5\u062a\u062a\u06d5 \u0645\u06c7\u0646\u062f\u0627\u0642 \u062f\u06d0\u064a\u0649\u0644\u06af\u06d5\u0646:\n22 \u0634\u06c7\u06ad\u0627\u060c \u064a\u0627\u0634\u0644\u0649\u0642\u0642\u0627 \u062e\u0627\u0633 \u06be\u06d5\u06cb\u06d5\u0633\u0644\u06d5\u0631\u062f\u0649\u0646 \u0642\u06d0\u0686\u0649\u067e\u060c \u067e\u0627\u0643 \u0642\u06d5\u0644\u0628\u062a\u0649\u0646 \u067e\u06d5\u0631\u06cb\u06d5\u0631\u062f\u0649\u06af\u0627\u0631\u063a\u0627 \u062f\u06c7\u0626\u0627 \u0642\u0649\u0644\u063a\u06c7\u0686\u0649\u0644\u0627\u0631 \u0628\u0649\u0644\u06d5\u0646 \u0628\u0649\u0644\u0644\u06d5 \u06be\u06d5\u0642\u0642\u0627\u0646\u0649\u064a\u06d5\u062a\u060c \u0626\u0649\u0645\u0627\u0646\u060c \u0645\u06c7\u06be\u06d5\u0628\u0628\u06d5\u062a \u06cb\u06d5 \u062a\u0649\u0646\u0686\u0644\u0649\u0642\u0646\u0649\u06ad \u0626\u0649\u0632\u0649\u062f\u0649\u0646 \u0645\u06d0\u06ad\u0649\u06ad.\n\n\u0628\u06c7 \u0626\u0627\u064a\u06d5\u062a \u0626\u06d5\u0645\u06d5\u0644\u0649\u064a\u06d5\u062a\u062a\u06d5 \u0628\u06c8\u06af\u06c8\u0646\u0643\u0649 \u062e\u06c7\u062a\u0628\u0649\u0646\u0649\u06ad \u062e\u06c7\u0644\u0627\u0633\u0649\u0633\u0649.\n\u0628\u06c7\u0646\u0649 \u0628\u0649\u0632 \u0626\u0627\u0644\u0644\u0627\u06be\u0646\u0649\u06ad \u0643\u0627\u0644\u0627\u0645\u0649\u062f\u0627 \u0643\u06c6\u067e \u0643\u06c6\u0631\u0649\u0645\u0649\u0632.\n\u0628\u06d5\u0632\u0649\u062f\u06d5 \u0632\u06d5\u0628\u06c7\u0631 \u064a\u0627\u0643\u0649 \u067e\u0627\u0631\u0627\u06af\u0631\u0627\u0641\u062a\u0649\u0643\u0649 \u062a\u06c7\u0646\u062c\u0649 \u062c\u06c8\u0645\u0644\u06d5 \u062e\u06c7\u0644\u0627\u0633\u06d5 \u0628\u0648\u0644\u0649\u062f\u06c7.\n\u0626\u0627\u0646\u062f\u0649\u0646 \u0643\u06d0\u064a\u0649\u0646\u0643\u0649 \u0633\u06c6\u0632\u0644\u06d5\u0631 \u067e\u06c8\u062a\u0643\u06c8\u0644 \u0632\u06d5\u0628\u06c7\u0631\u060c \u067e\u0627\u0631\u0627\u06af\u0631\u0627\u0641 \u064a\u0627\u0643\u0649 \u0628\u0627\u0628\u0646\u0649\u06ad \u0686\u06c8\u0634\u06d5\u0646\u062f\u06c8\u0631\u0645\u0649\u0633\u0649.\n\u067e\u0649\u0634\u0649\u067e \u064a\u06d0\u062a\u0649\u0644\u06af\u06d5\u0646 \u062e\u0649\u0631\u0649\u0633\u062a\u0649\u064a\u0627\u0646 \u0626\u06d5\u0631 \u064a\u0627\u0643\u0649 \u0626\u0627\u064a\u0627\u0644 \u064a\u0627\u0634 \u06cb\u0627\u0642\u062a\u0649\u0645\u0649\u0632\u062f\u0627 \u0628\u0649\u0632\u0646\u0649 \u0626\u0627\u0632\u062f\u06c7\u0631\u063a\u0627\u0646 \u0626\u0649\u0634\u0644\u0627\u0631\u062f\u0649\u0646 \u064a\u0649\u0631\u0627\u0642 \u062a\u06c7\u0631\u0649\u062f\u0649\u063a\u0627\u0646 \u0626\u0627\u062f\u06d5\u0645\u062f\u06c7\u0631.\n\u067e\u0649\u0634\u0649\u067e \u064a\u06d0\u062a\u0649\u0644\u06af\u06d5\u0646 \u0626\u0627\u062f\u06d5\u0645 \u00ab\u064a\u0627\u0634\u0644\u0649\u0642 \u0642\u0649\u0632\u063a\u0649\u0646\u0644\u0649\u0642\u0649\u00bb \u0646\u0649\u06ad \u0626\u0648\u0631\u0646\u0649\u063a\u0627\u060c \u06be\u06d5\u0642\u0642\u0627\u0646\u0649\u064a\u06d5\u062a\u060c \u0626\u0649\u0645\u0627\u0646\u060c \u0645\u06c7\u06be\u06d5\u0628\u0628\u06d5\u062a \u06cb\u06d5 \u062a\u0649\u0646\u0686\u0644\u0649\u0642 \u0642\u0627\u062a\u0627\u0631\u0644\u0649\u0642 \u062e\u06c7\u062f\u0627\u0646\u0649\u06ad \u0642\u0649\u0645\u0645\u06d5\u062a \u0642\u0627\u0631\u0649\u0634\u0649\u063a\u0627 \u0626\u06d5\u06af\u0649\u0634\u0649\u0634\u0646\u0649 \u0626\u06c6\u06af\u0649\u0646\u0649\u06cb\u0627\u062a\u0649\u062f\u06c7.\n\u067e\u0627\u06cb\u0644\u06c7\u0633 \u064a\u0627\u0634 \u06cb\u0627\u0642\u062a\u0649\u062f\u0627\u060c \u0626\u06c7\u0646\u0649\u06ad \u0626\u0649\u0633\u0645\u0649 \u0634\u0627\u0626\u06c7\u0644 \u0626\u0649\u062f\u0649.\n\u0633\u0627\u0626\u06c7\u0644 \u063a\u06c7\u0631\u06c7\u0631 \u06cb\u06d5 \u0626\u06c6\u0632\u0649\u06af\u06d5 \u0626\u0649\u0634\u0649\u0646\u0649\u0634 \u0628\u0649\u0644\u06d5\u0646 \u062a\u0648\u0644\u063a\u0627\u0646 \u0628\u0648\u0644\u06c7\u067e\u060c \u062e\u0649\u0631\u0649\u0633\u062a\u0649\u064a\u0627\u0646\u0644\u0627\u0631\u063a\u0627 \u0632\u0649\u064a\u0627\u0646\u0643\u06d5\u0634\u0644\u0649\u0643 \u0642\u0649\u0644\u0649\u0634 \u06cb\u06d5 \u0626\u06c7\u0644\u0627\u0631\u0646\u0649 \u0632\u0649\u0646\u062f\u0627\u0646\u063a\u0627 \u062a\u0627\u0634\u0644\u0627\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u06be\u0648\u0642\u06c7\u0642\u0649\u062f\u0649\u0646 \u067e\u0627\u064a\u062f\u0649\u0644\u0627\u0646\u063a\u0627\u0646.\n\u0634\u0627\u0626\u06c7\u0644 \u0626\u0627\u0644\u0642\u0649\u0634\u0642\u0627 \u0626\u06d0\u0631\u0649\u0634\u0649\u0634\u0646\u0649 \u06cb\u06d5 \u0645\u06c7\u06cb\u06d5\u067e\u067e\u06d5\u0642\u0649\u064a\u06d5\u062a \u0642\u0627\u0632\u0649\u0646\u0649\u0634\u0646\u0649 \u0626\u0627\u0631\u0632\u06c7 \u0642\u0649\u0644\u0627\u062a\u062a\u0649\u060c \u0634\u06c7\u0646\u062f\u0627\u0642\u0644\u0627 \u0626\u06c6\u0632\u0649\u0646\u0649\u06ad \u063a\u06c7\u0631\u06c7\u0631\u0649 \u0633\u06d5\u06cb\u06d5\u0628\u0649\u062f\u0649\u0646 \u0628\u0627\u0634\u0642\u0649\u0644\u0627\u0631\u063a\u0627 \u0632\u0649\u064a\u0627\u0646 \u064a\u06d5\u062a\u0643\u06c8\u0632\u06c8\u0634\u0643\u06d5 \u062a\u06d5\u064a\u064a\u0627\u0631 \u0626\u0649\u062f\u0649.\n\u0644\u06d0\u0643\u0649\u0646 \u062a\u0649\u0645\u0648\u062a\u0649\u064a\u063a\u0627 \u064a\u06d0\u0632\u0649\u0644\u063a\u0627\u0646 2-\u062e\u06d5\u062a\u0646\u0649 \u067e\u0649\u0634\u0649\u067e \u064a\u06d0\u062a\u0649\u0644\u06af\u06d5\u0646 \u0626\u06d0\u062a\u0649\u0642\u0627\u062f\u0686\u0649\u0644\u0627\u0631 \u067e\u0627\u06cb\u0644\u06c7\u0633 \u064a\u0627\u0632\u063a\u0627\u0646.\n\u0626\u06c7 \u064a\u0627\u0634\u0644\u0649\u0642\u0649\u062f\u0649\u0643\u0649 \u0642\u0649\u0632\u063a\u0649\u0646\u0644\u0649\u0642\u0649\u0646\u0649\u06ad \u0642\u0627\u0646\u0686\u0649\u0644\u0649\u0643 \u0632\u0649\u064a\u0627\u0646 \u064a\u06d5\u062a\u0643\u06c8\u0632\u06af\u06d5\u0646\u0644\u0649\u0643\u0649\u0646\u0649 \u0686\u06c8\u0634\u0649\u0646\u0649\u067e\u060c \u062a\u0649\u0645\u0648\u062a\u0649\u064a\u0646\u0649 \u0628\u06c7 \u06be\u06d5\u0642\u062a\u06d5 \u0626\u0627\u06af\u0627\u06be\u0644\u0627\u0646\u062f\u06c7\u0631\u06c7\u06cb\u0627\u062a\u0649\u062f\u06c7.\n\u067e\u0627\u06cb\u0644\u06c7\u0633 \u0628\u06c7 \u062e\u06d5\u062a\u0646\u0649 \u064a\u0627\u0632\u063a\u0627\u0646\u062f\u0627\u060c \u062a\u0649\u0645\u0648\u062a\u0649\u064a \u062a\u06d5\u062e\u0645\u0649\u0646\u06d5\u0646 40 \u064a\u0627\u0634\u0644\u0627\u0631\u062f\u0627 \u0626\u0649\u062f\u0649.\n\u0644\u06d0\u0643\u0649\u0646 \u00ab\u064a\u0627\u0634\u0644\u0649\u0642 \u0642\u0649\u0632\u063a\u0649\u0646\u0644\u0649\u0642\u0649\u00bb\u063a\u0627 \u0642\u0627\u0631\u0627\u067e \u064a\u06c8\u06af\u06c8\u0631\u06c8\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u064a\u0627\u0634 \u0628\u0648\u0644\u06c7\u0634\u0649\u06ad\u0649\u0632 \u0634\u06d5\u0631\u062a \u0626\u06d5\u0645\u06d5\u0633.\n\u0645\u06d5\u0646 57 \u064a\u0627\u0634\u0642\u0627 \u0643\u0649\u0631\u062f\u0649\u0645\u060c \u0626\u06d5\u0645\u0645\u0627 \u064a\u06d5\u0646\u0649\u0644\u0627 \u064a\u0627\u0634\u0644\u0649\u0642\u0649\u0645\u062f\u0649\u0643\u0649 \u0642\u0649\u0632\u063a\u0649\u0646\u0644\u0649\u0642\u0644\u0627\u0631\u062f\u0649\u0646 \u0626\u06c8\u0632\u0644\u06c8\u0643\u0633\u0649\u0632 \u0642\u06d0\u0686\u0649\u0634\u0646\u0649 \u0626\u06c6\u06af\u0649\u0646\u0649\u06cb\u0627\u062a\u0649\u0645\u06d5\u0646.\n\u0645\u06d0\u0646\u0649\u06ad \u0626\u0627\u0644\u0649\u064a \u0645\u06d5\u0643\u062a\u06d5\u067e\u062a\u0649\u0643\u0649 \u0645\u06d5\u0646 \u0628\u0649\u0644\u06d5\u0646 \u062a\u06d5\u06ad \u064a\u0627\u0634\u0644\u0649\u0642 \u0628\u0649\u0631 \u062f\u0648\u0633\u062a\u06c7\u0645 \u0628\u0627\u0631.\n\u0626\u06d5\u0645\u0645\u0627 \u0626\u06c7 \u06be\u0627\u0632\u0649\u0631\u0645\u06c7 35 \u064a\u0649\u0644 \u0626\u0649\u0644\u06af\u0649\u0631\u0649\u0643\u0649\u062f\u06d5\u0643 \u064a\u0627\u0634\u0627\u06cb\u0627\u062a\u0649\u062f\u06c7.\n\u0626\u06c7\u0646\u0649\u06ad \u06be\u0627\u064a\u0627\u062a\u0649 \u0626\u0627\u0644\u0649\u064a \u0645\u06d5\u0643\u062a\u06d5\u067e \u062f\u06d5\u06cb\u0631\u0649\u062f\u0649\u0643\u0649 \u064a\u0627\u0634\u0644\u0649\u0642 \u0642\u0649\u0632\u063a\u0649\u0646\u0644\u0649\u0642\u0644\u0649\u0631\u0649 \u0628\u0649\u0644\u06d5\u0646 \u062a\u0648\u0644\u063a\u0627\u0646.\n\u0646\u06c7\u0631\u063a\u06c7\u0646\u0649\u0645\u0649\u0632 \u064a\u0627\u0634 \u06cb\u0627\u0642\u062a\u0649\u0645\u0649\u0632\u062f\u0627 \u0628\u0627\u0634\u062a\u0649\u0646 \u0643\u06d5\u0686\u06c8\u0631\u0649\u062f\u0649\u063a\u0627\u0646 \u0628\u06d5\u0632\u0649 \u0642\u0649\u0632\u0649\u0642\u0649\u0634\u0644\u0627\u0631 \u062a\u06c6\u06cb\u06d5\u0646\u062f\u0649\u0643\u0649\u0686\u06d5:\n\n*   \u0644\u06d5\u0632\u0632\u06d5\u062a\u0644\u0649\u0646\u0649\u0634: \u062c\u0649\u0646\u0633\u0649\u064a \u06af\u06c7\u0646\u0627\u06be \u0644\u06d5\u0632\u0632\u06d5\u062a\u0644\u0649\u0646\u0649\u0634 \u06af\u06c7\u0646\u0627\u06be\u0649\u0646\u0649\u06ad \u0643\u06c6\u067e \u0626\u06c7\u0686\u0631\u0627\u064a\u062f\u0649\u063a\u0627\u0646 \u0645\u0649\u0633\u0627\u0644\u0649\u060c \u0626\u06d5\u0645\u0645\u0627 \u0626\u06c7 \u0628\u0649\u0631\u062f\u0649\u0646\u0628\u0649\u0631 \u0626\u06d5\u0645\u06d5\u0633.\n\u0628\u0627\u0634\u0642\u0627 \u06af\u06c7\u0646\u0627\u06be\u0644\u0649\u0642 \u0644\u06d5\u0632\u0632\u06d5\u062a\u0644\u06d5\u0631 \u0626\u0649\u0686\u0649\u0645\u0644\u0649\u0643\u060c \u064a\u06d0\u0645\u06d5\u0643-\u0626\u0649\u0686\u0645\u06d5\u0643 \u06cb\u06d5 \u0646\u06c7\u0631\u063a\u06c7\u0646 \u0643\u06c6\u06ad\u06c8\u0644 \u0626\u06d0\u0686\u0649\u0634 \u062a\u06c8\u0631\u0644\u0649\u0631\u0649\u0646\u0649 \u0626\u06c6\u0632 \u0626\u0649\u0686\u0649\u06af\u06d5 \u0626\u0627\u0644\u0649\u062f\u06c7.\n\u0628\u06c7 \u0646\u06d5\u0631\u0633\u0649\u0644\u06d5\u0631 \u062a\u0648\u063a\u0631\u0627 \u0626\u0649\u0634\u0644\u0649\u062a\u0649\u0644\u0633\u06d5 \u0632\u0649\u064a\u0627\u0646\u0644\u0649\u0642 \u0626\u06d5\u0645\u06d5\u0633.\n\u0645\u06d5\u0633\u0649\u0644\u06d5\u0646\u060c \u062c\u0649\u0646\u0633\u0649\u064a \u0645\u06c7\u0646\u0627\u0633\u0649\u06cb\u06d5\u062a \u062e\u0649\u0631\u0649\u0633\u062a\u0649\u064a\u0627\u0646 \u0646\u0649\u0643\u0627\u06be\u0649 \u0626\u06c8\u0686\u06c8\u0646 \u06af\u06c8\u0632\u06d5\u0644 \u0628\u0649\u0631 \u0633\u0648\u06cb\u063a\u0627\u062a.\n\u0644\u06d0\u0643\u0649\u0646 \u0628\u0649\u0632 \u06be\u06d5\u0631 \u0642\u0627\u0646\u062f\u0627\u0642 \u0646\u06d5\u0631\u0633\u0649\u0646\u0649 \u062e\u0627\u062a\u0627 \u0626\u0649\u0634\u0644\u06d5\u062a\u0633\u06d5\u0643\u060c \u0626\u06c7\u0646\u0649\u06ad\u063a\u0627 \u06be\u0627\u064a\u0627\u062a\u0649\u0645\u0649\u0632\u063a\u0627 \u06be\u06c6\u0643\u06c8\u0645\u0631\u0627\u0646\u0644\u0649\u0642 \u0642\u0649\u0644\u0649\u067e \u0642\u0648\u064a\u0649\u0645\u0649\u0632.\n\u0628\u0649\u0632 \u0642\u06d5\u0644\u0628\u0649\u0645\u0649\u0632\u062f\u0649\u0643\u0649 \u0628\u0648\u0634\u0644\u06c7\u0642\u0646\u0649 \u062a\u0648\u0644\u062f\u06c7\u0631\u06c7\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u062e\u06c7\u062f\u0627\u0646\u0649\u06ad \u06be\u06d5\u0631 \u0642\u0627\u0646\u062f\u0627\u0642 \u0633\u0648\u06cb\u063a\u0649\u0633\u0649\u0646\u0649 \u0626\u0649\u0634\u0644\u06d5\u062a\u0633\u06d5\u0643\u060c \u0626\u06c7 \u0646\u06d5\u0631\u0633\u06d5 \u0633\u0627\u062e\u062a\u0627 \u0626\u0649\u0644\u0627\u06be\u0642\u0627\u060c \u064a\u06d5\u0646\u0649 \u0628\u06c7\u062a\u0642\u0627 \u0626\u0627\u064a\u0644\u0649\u0646\u0649\u062f\u06c7.\n\n*   \u0643\u06c8\u0686: \u064a\u0627\u0634 \u06cb\u0627\u0642\u062a\u0649\u0645\u0649\u0632\u062f\u0627\u060c \u0628\u06d5\u0632\u0649\u062f\u06d5 \u0626\u06c6\u0632\u0649\u0645\u0649\u0632\u0646\u0649 \u0626\u0627\u062c\u0649\u0632\u060c \u0626\u0627\u062c\u0649\u0632 \u064a\u0627\u0643\u0649 \u064a\u06d0\u062a\u06d5\u0631\u0633\u0649\u0632 \u06be\u06d0\u0633 \u0642\u0649\u0644\u0649\u0645\u0649\u0632.\n\u0645\u06d5\u0646 \u0626\u06c6\u0633\u0645\u06c8\u0631\u0644\u06c8\u0643 \u062f\u06d5\u06cb\u0631\u0649\u0645\u062f\u06d5 \u0628\u06c7 \u062e\u0649\u0644 \u06be\u06d0\u0633\u0633\u0649\u064a\u0627\u062a\u0644\u0627\u0631 \u0628\u0649\u0644\u06d5\u0646 \u0643\u06c8\u0631\u06d5\u0634 \u0642\u0649\u0644\u063a\u0627\u0646.\n\u0628\u06d5\u0632\u0649 \u0643\u0649\u0634\u0649\u0644\u06d5\u0631 \u0626\u0627\u062c\u0649\u0632\u0644\u0649\u0642 \u06be\u06d0\u0633\u0633\u0649\u064a\u0627\u062a\u0649\u0646\u0649 \u064a\u0648\u0634\u06c7\u0631\u06c7\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u06be\u0648\u0642\u06c7\u0642\u0642\u0627 \u0626\u0649\u0646\u062a\u0649\u0644\u0649\u062f\u06c7.\n\u0626\u06c7\u0644\u0627\u0631 \u0643\u06c8\u0686\u0644\u06c8\u0643 \u06be\u06d5\u0631\u0649\u0643\u06d5\u062a \u0642\u0649\u0644\u0649\u0634\u0646\u0649\u06ad \u0626\u06c6\u0632\u0644\u0649\u0631\u0649\u06af\u06d5 \u0628\u0649\u062e\u06d5\u062a\u06d5\u0631\u0644\u0649\u0643 \u062a\u06c7\u064a\u063a\u06c7\u0633\u0649\u0646\u0649 \u0628\u06d0\u0631\u0649\u062f\u06c7 \u062f\u06d5\u067e \u0626\u0648\u064a\u0644\u0627\u064a\u062f\u06c7.\n\u0632\u0648\u0631\u0627\u06cb\u0627\u0646\u0646\u0649\u06ad \u0626\u06d5\u0645\u06d5\u0644\u0649\u064a\u06d5\u062a\u062a\u06d5 \u0643\u06c6\u0631\u06c8\u0646\u06af\u0649\u0646\u0649\u062f\u06d5\u0643 \u0642\u0627\u062a\u062a\u0649\u0642 \u0626\u06d5\u0645\u06d5\u0633\u0644\u0649\u0643\u0649\u0646\u0649 \u0628\u0649\u0644\u06d5\u0645\u0633\u0649\u0632\u061f\n\u0632\u0648\u0631\u0627\u06cb\u0627\u0646 \u0626\u0627\u062f\u06d5\u062a\u062a\u06d5 \u06be\u0627\u064a\u0627\u062a\u0649\u062f\u0649\u0643\u0649 \u0628\u0649\u0631\u06d5\u0631 \u0646\u06d5\u0631\u0633\u0649\u06af\u06d5 \u0642\u0627\u0631\u0649\u062a\u0627 \u0626\u06c6\u0632\u0649\u0646\u0649 \u0626\u0627\u062c\u0649\u0632 \u06be\u06d0\u0633 \u0642\u0649\u0644\u0649\u062f\u0649\u063a\u0627\u0646\u060c \u0634\u06c7\u06ad\u0627 \u0626\u06c6\u0632\u0649\u0646\u0649 \u0643\u06c8\u0686\u0644\u06c8\u0643 \u06be\u06d0\u0633 \u0642\u0649\u0644\u062f\u06c7\u0631\u06c7\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0628\u0627\u0634\u0642\u0649\u0644\u0627\u0631\u063a\u0627 \u0626\u0627\u0632\u0627\u0631 \u0628\u06d0\u0631\u0649\u062f\u0649\u063a\u0627\u0646 \u0626\u0627\u062f\u06d5\u0645\u062f\u06c7\u0631.\n\n*   \u0626\u0627\u0644\u0642\u0649\u0634\u0642\u0627 \u0626\u06d0\u0631\u0649\u0634\u0649\u0634: \u0628\u06c7 \u0645\u06d0\u0646\u0649\u06ad \u06be\u0627\u064a\u0627\u062a\u0649\u0645\u062f\u0649\u0643\u0649 \u064a\u06d5\u0646\u06d5 \u0628\u0649\u0631 \u0643\u06c8\u0686\u0644\u06c8\u0643 \u0633\u0649\u0646\u0627\u0642 \u0628\u0648\u0644\u062f\u0649.\n\u0645\u06d5\u0646 \u062f\u0627\u0626\u0649\u0645 \u0628\u0627\u0634\u0642\u0649\u0644\u0627\u0631 \u0645\u06d0\u0646\u0649 \u064a\u0627\u0642\u062a\u06c7\u0631\u06c7\u067e \u0642\u0627\u0644\u0633\u0627 \u062f\u06d5\u067e \u0626\u06d5\u0646\u0633\u0649\u0631\u06d5\u064a\u0645\u06d5\u0646.\n\u0645\u06d5\u0646 \u0628\u0627\u0634\u0642\u0649\u0644\u0627\u0631\u0646\u0649\u06ad \u067e\u0649\u0643\u0649\u0631\u0644\u0649\u0631\u0649\u06af\u06d5 \u0628\u06d5\u0643 \u0626\u06d5\u06be\u0645\u0649\u064a\u06d5\u062a \u0628\u06d0\u0631\u0649\u0645\u06d5\u0646.\n\u0633\u0649\u0632\u0686\u06c7\u061f\n\u0628\u0627\u0634\u0642\u0649\u0644\u0627\u0631\u0646\u0649\u06ad \u0633\u0649\u0632\u0646\u0649 \u064a\u0627\u0642\u062a\u06c7\u0631\u06c7\u0634\u0649 \u0626\u06c8\u0686\u06c8\u0646 \u0642\u0649\u0644\u0649\u0642-\u06be\u06d5\u0631\u0649\u0643\u0649\u062a\u0649\u06ad\u0649\u0632\u0646\u0649 \u064a\u0627\u0643\u0649 \u062a\u0627\u0634\u0642\u0649 \u0642\u0649\u064a\u0627\u067e\u0649\u062a\u0649\u06ad\u0649\u0632\u0646\u0649 \u0626\u06c6\u0632\u06af\u06d5\u0631\u062a\u06d5\u0645\u0633\u0649\u0632\u061f\n\u0631\u06d5\u062a \u0642\u0649\u0644\u0649\u0646\u0649\u0634\u062a\u0649\u0646 \u0633\u0627\u0642\u0644\u0649\u0646\u0649\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0645\u06d5\u0644\u06c7\u0645 \u0628\u0649\u0631 \u0626\u06c7\u0633\u06c7\u0644\u062f\u0627 \u06be\u06d5\u0631\u0649\u0643\u06d5\u062a \u0642\u0649\u0644\u0649\u0634\u0649\u06ad\u0649\u0632 \u064a\u0627\u0643\u0649 \u0643\u06c6\u0631\u06c8\u0646\u06c8\u0634\u0649\u06ad\u0649\u0632 \u0643\u06d0\u0631\u06d5\u0643 \u062f\u06d5\u067e \u0626\u0648\u064a\u0644\u0627\u064a\u0633\u0649\u0632\u0645\u06c7\u061f\n\n*   \u0645\u0627\u0644-\u0645\u06c8\u0644\u06c8\u0643: \u067e\u06c7\u0644 \u06cb\u06d5 \u0645\u0627\u062f\u062f\u0649\u064a \u0646\u06d5\u0631\u0633\u0649\u0644\u06d5\u0631\u06af\u06d5 \u0628\u0648\u0644\u063a\u0627\u0646 \u0645\u06c7\u06be\u06d5\u0628\u0628\u06d5\u062a \u0643\u06c6\u067e\u0686\u0649\u0644\u0649\u0643\u0649\u0645\u0649\u0632 \u0626\u06c8\u0686\u06c8\u0646 \u0628\u0649\u0631 \u0645\u06d5\u0633\u0649\u0644\u06d5.\n\u0628\u0649\u0632 \u062a\u06d0\u062e\u0649\u0645\u06c7 \u0643\u06c6\u067e \u0646\u06d5\u0631\u0633\u0649\u06af\u06d5 \u0626\u0649\u06af\u06d5 \u0628\u0648\u0644\u06c7\u0634\u0646\u0649\u06ad \u0628\u0649\u062e\u06d5\u062a\u06d5\u0631\u0644\u0649\u0643\u0649 \u06cb\u06d5 \u0631\u0627\u06be\u06d5\u062a\u0644\u0649\u0643\u0649\u0646\u0649 \u0626\u06c8\u0645\u0649\u062f \u0642\u0649\u0644\u0649\u0645\u0649\u0632.\n\u0628\u06c7 \u0626\u0649\u0645\u0627\u0646\u0646\u0649\u06ad \u0643\u06d5\u0645\u0686\u0649\u0644\u0644\u0649\u0643\u0649\u0646\u0649 \u0626\u0627\u0634\u0643\u0627\u0631\u0649\u0644\u0627\u064a\u062f\u06c7.\n\u062e\u06c7\u062f\u0627 \u0628\u0649\u0632\u0646\u0649\u06ad \u0626\u06c7\u0646\u0649\u06ad \u0628\u0649\u0632\u0646\u0649\u06ad \u067e\u0627\u0646\u0627\u06be\u06af\u0627\u06be\u0649\u0645\u0649\u0632 \u06cb\u06d5 \u0642\u0648\u0631\u063a\u0627\u0646\u0649\u0645\u0649\u0632\u060c \u0626\u06c7 \u0628\u0649\u0632\u0646\u0649\u06ad \u062a\u06d5\u0645\u0649\u0646\u0644\u0649\u06af\u06c8\u0686\u0649\u0645\u0649\u0632 \u0626\u0649\u0643\u06d5\u0646\u0644\u0649\u0643\u0649\u0646\u0649 \u0686\u06c8\u0634\u0649\u0646\u0649\u0634\u0649\u0645\u0649\u0632\u0646\u0649 \u0626\u06c8\u0645\u0649\u062f \u0642\u0649\u0644\u0649\u062f\u06c7.\n\u0645\u0627\u062f\u062f\u0649\u064a \u0646\u06d5\u0631\u0633\u0649\u0644\u06d5\u0631 \u0628\u06d5\u062e\u062a\u0646\u0649 \u06cb\u06d5\u062f\u06d5 \u0642\u0649\u0644\u0649\u062f\u06c7\u060c \u0626\u06d5\u0645\u0645\u0627 \u0626\u06c7\u0644\u0627\u0631 \u06be\u06d5\u0631\u06af\u0649\u0632 \u06cb\u06d5\u062f\u0649\u0633\u0649\u06af\u06d5 \u0626\u06d5\u0645\u06d5\u0644 \u0642\u0649\u0644\u0627\u0644\u0645\u0627\u064a\u062f\u06c7.\n\u0686\u06c8\u0646\u0643\u0649 \u0642\u06d5\u0644\u0628\u0649\u0645\u0649\u0632 \u06be\u06d5\u0645\u0649\u0634\u06d5 \u062a\u06d0\u062e\u0649\u0645\u06c7 \u0643\u06c6\u067e \u0646\u06d5\u0631\u0633\u0649\u0646\u0649 \u0626\u0649\u0633\u062a\u06d5\u064a\u062f\u06c7.\n\n*   \u063a\u06c7\u0631\u06c7\u0631: \u0628\u06c7 \u0626\u06d5\u0645\u06d5\u0644\u0649\u064a\u06d5\u062a\u062a\u06d5 \u0628\u0627\u0634\u0642\u0627 \u06be\u06d5\u0631 \u0642\u0627\u0646\u062f\u0627\u0642 \u06af\u06c7\u0646\u0627\u06be\u0646\u0649\u06ad \u0626\u0627\u0633\u062a\u0649\u062f\u0649\u0643\u0649 \u06af\u06c7\u0646\u0627\u06be.\n\u063a\u06c7\u0631\u06c7\u0631 \u062f\u06d0\u06af\u06d5\u0646 \u0645\u06d5\u0646 \u06be\u06d5\u0642\u0649\u0642\u06d5\u062a\u06d5\u0646 \u0645\u0627\u0644-\u0645\u06c8\u0644\u06c8\u0643\u060c \u06be\u0648\u0642\u06c7\u0642\u060c \u062e\u06c7\u0634\u0627\u0644\u0644\u0649\u0642 \u06cb\u06d5 \u062f\u0627\u06ad\u0642\u0642\u0627 \u0644\u0627\u064a\u0649\u0642 \u0626\u0649\u0643\u06d5\u0646\u0644\u0649\u0643\u0649\u0645\u06af\u06d5 \u0626\u0649\u0634\u0649\u0646\u0649\u0634\u062a\u06c7\u0631.\n\u0646\u06d0\u0645\u0649\u0634\u0642\u0627\u061f \u0686\u06c8\u0646\u0643\u0649 \u0645\u06d5\u0646 \u0626\u0627\u0644\u0627\u06be\u0649\u062f\u06d5 \u0628\u0649\u0631 \u0626\u0627\u062f\u06d5\u0645.\n\u063a\u06c7\u0631\u06c7\u0631 \u0628\u0649\u0632\u06af\u06d5 \u064a\u0627\u0644\u063a\u0627\u0646 \u0633\u06c6\u0632\u0644\u06d5\u064a\u062f\u06c7\u060c \u062f\u06d5\u064a\u062f\u06c7:\n\u00ab\u06be\u06d0\u0686\u0642\u0649\u0633\u0649 \u064a\u0648\u0642\u060c \u0633\u0649\u0632 \u0628\u06c7\u0646\u0649 \u0642\u0649\u0644\u0627\u0644\u0627\u064a\u0633\u0649\u0632- \u0633\u0649\u0632 \u0628\u06c7\u0646\u0649\u06ad\u063a\u0627 \u0644\u0627\u064a\u0649\u0642.\u00bb\n\u0626\u06d0\u0644\u0627\u0646 \u0628\u06d5\u0631\u06af\u06c8\u0686\u0649\u0644\u06d5\u0631 \u0628\u0649\u0632\u06af\u06d5 \u0626\u0648\u062e\u0634\u0627\u0634 \u06af\u06d5\u067e\u0644\u06d5\u0631\u0646\u0649 \u0642\u0649\u0644\u0649\u062f\u06c7.\n\u00ab\u0633\u0649\u0632 \u0628\u06c7\u0646\u0649\u06ad\u063a\u0627 \u0644\u0627\u064a\u0649\u0642... \u062f\u0627\u06cb\u0627\u0645\u0644\u0627\u0634\u062a\u06c7\u0631\u06c7\u06ad\u060c \u0633\u06d0\u062a\u0649\u06cb\u06d0\u0644\u0649\u06ad.\u00bb\n\u0628\u06d5\u0644\u0643\u0649\u0645 \u064a\u06d5\u0646\u06d5 \u0628\u0649\u0631 \u0626\u0627\u0632 \u0633\u06d0\u062a\u0649\u06cb\u06d0\u0644\u0649\u067e \u0628\u06d0\u0642\u0649\u06ad\u060c \u06be\u06d0\u0686\u0642\u0649\u0633\u0649 \u064a\u0648\u0642.\n\u0634\u06c7\u06ad\u0644\u0627\u0634\u0642\u0627 \u0628\u0649\u0632 \u0628\u06c7\u0646\u062f\u0627\u0642 \u0626\u06d0\u0644\u0627\u0646\u0644\u0627\u0631\u0646\u0649 \u0643\u06c6\u067e \u0643\u06c6\u0631\u0649\u0645\u0649\u0632\u060c \u0686\u06c8\u0646\u0643\u0649 \u0628\u0649\u0632\u0646\u0649\u06ad \u063a\u06c7\u0631\u06c7\u0631\u0649\u0645\u0649\u0632 \u0626\u06d5\u0645\u06d5\u0644\u0649\u064a\u06d5\u062a\u062a\u06d5 \u0628\u06c7 \u0646\u06d5\u0631\u0633\u0649\u0644\u06d5\u0631\u06af\u06d5 \u0626\u0649\u0634\u0649\u0646\u0649\u0634\u0646\u0649 \u062e\u0627\u0644\u0627\u064a\u062f\u06c7.\n\n\u062f\u0648\u0633\u062a\u0644\u0649\u0631\u0649\u0645\u060c \u0633\u0649\u0644\u06d5\u0631\u062f\u0649\u0646 \u0628\u0649\u0631 \u0633\u0648\u0626\u0627\u0644 \u0633\u0648\u0631\u0649\u0633\u0627\u0645 \u0628\u0648\u0644\u0627\u0645\u062f\u06c7\u061f\n\u0628\u06c7 \u0628\u06d5\u0634 \u0646\u06d5\u0631\u0633\u0649\u0646\u0649\u06ad \u0642\u0627\u064a\u0633\u0649\u0633\u0649 \u0633\u0649\u0632\u06af\u06d5 \u062a\u0648\u0646\u06c7\u0634\u0644\u06c7\u0642 \u062a\u06c7\u064a\u06c7\u0644\u0649\u062f\u06c7\u061f\n\u0633\u0649\u0632 \u063a\u06c7\u0631\u06c7\u0631\u060c \u0645\u0627\u0644-\u0645\u06c8\u0644\u06c8\u0643\u060c \u06be\u0648\u0642\u06c7\u0642\u060c \u062e\u06c7\u0634\u0627\u0644\u0644\u0649\u0642 \u064a\u0627\u0643\u0649 \u062f\u0627\u06ad\u0642 \u0642\u0648\u063a\u0644\u0649\u0634\u0649\u06cb\u0627\u062a\u0627\u0645\u0633\u0649\u0632\u061f\n\u064a\u0627\u0643\u0649 \u0628\u06d5\u0644\u0643\u0649\u0645 \u0633\u0649\u0632\u0646\u0649 \u062e\u06c7\u062f\u0627\u062f\u0649\u0646 \u064a\u0649\u0631\u0627\u0642\u0644\u0627\u0634\u062a\u06c7\u0631\u0649\u062f\u0649\u063a\u0627\u0646 \u0628\u0627\u0634\u0642\u0627 \u0628\u0649\u0631 \u0646\u06d5\u0631\u0633\u06d5\u062f\u06c7\u0631\u061f\n\u0628\u06c8\u06af\u06c8\u0646 \u0642\u06d5\u0644\u0628\u0649\u06ad\u0649\u0632 \u0642\u06d5\u064a\u06d5\u0631\u062f\u06d5\u060c \u0642\u06d5\u064a\u06d5\u0631\u06af\u06d5 \u0643\u06d0\u062a\u0649\u06cb\u0627\u062a\u0649\u0633\u0649\u0632\u061f\n\u0628\u0627\u063a\u062f\u0627 \u0626\u0627\u062f\u06d5\u0645 \u0645\u06d0\u06cb\u0649\u0646\u0649 \u064a\u06d0\u06af\u06d5\u0646\u062f\u0649\u0646 \u0643\u06d0\u064a\u0649\u0646\u060c \u062e\u06c7\u062f\u0627 \u0626\u06c7\u0646\u0649\u06ad\u062f\u0649\u0646 \u0646\u06d0\u0645\u06d5 \u062f\u06d0\u06af\u06d5\u0646\u0644\u0649\u0643\u0649\u0646\u0649 \u0626\u06d0\u0633\u0649\u06ad\u0649\u0632\u062f\u0649\u0645\u06c7\u061f\n\u0626\u0627\u062f\u06d5\u0645 \u0628\u0649\u0644\u06d5\u0646 \u06be\u0627\u06cb\u0627 \u064a\u0648\u0634\u06c7\u0631\u06c7\u0646\u06c7\u06cb\u0627\u062a\u0627\u062a\u062a\u0649\u060c \u062e\u06c7\u062f\u0627: \u00ab\u0633\u06d5\u0646 \u0642\u06d5\u064a\u06d5\u0631\u062f\u06d5\u060c \u0626\u0627\u062f\u06d5\u0645\u061f\u00bb \u062f\u06d0\u062f\u0649.\n\u062e\u06c7\u062f\u0627 \u0628\u06c8\u06af\u06c8\u0646 \u064a\u06d5\u0631 \u064a\u06c8\u0632\u0649\u062f\u0649\u0643\u0649 \u0628\u0627\u0631\u0644\u0649\u0642 \u0643\u0649\u0634\u0649\u0644\u06d5\u0631\u062f\u0649\u0646 \u0626\u0648\u062e\u0634\u0627\u0634 \u0646\u06d5\u0631\u0633\u0649\u0646\u0649 \u062a\u06d5\u0644\u06d5\u067e \u0642\u0649\u0644\u0649\u06cb\u0627\u062a\u0649\u062f\u06c7.\n\u0633\u0649\u0632 \u0642\u06d5\u064a\u06d5\u0631\u062f\u06d5\u061f\n\u0626\u06c7 \u0633\u0649\u0632\u0646\u0649\u06ad \u0641\u0649\u0632\u0649\u0643\u0649\u0644\u0649\u0642 \u062c\u06d5\u06be\u06d5\u062a\u062a\u0649\u0646 \u0642\u06d5\u064a\u06d5\u0631\u062f\u06d5 \u0626\u0649\u0643\u06d5\u0646\u0644\u0649\u0643\u0649\u06ad\u0649\u0632\u0646\u0649 \u0633\u0648\u0631\u0649\u0645\u0649\u062f\u0649.\n\u0626\u06c7 \u00ab\u064a\u06c8\u0631\u0649\u0643\u0649\u06ad \u0642\u06d5\u064a\u06d5\u0631\u062f\u06d5\u061f\u00bb \u062f\u06d5\u067e \u0633\u0648\u0631\u0627\u06cb\u0627\u062a\u0649\u062f\u06c7.\n\u0686\u06c8\u0646\u0643\u0649 \u0642\u06d5\u0644\u0628\u0649\u0645\u0649\u0632 \u0628\u0649\u0632\u0646\u0649 \u0626\u06d5\u06ad \u0642\u0649\u0645\u0645\u06d5\u062a\u0644\u0649\u0643 \u0646\u06d5\u0631\u0633\u0649\u06af\u06d5 \u0642\u0627\u0631\u0627\u067e \u064a\u06d0\u062a\u06d5\u0643\u0644\u06d5\u064a\u062f\u0649\u063a\u0627\u0646 \u0643\u0648\u0645\u067e\u0627\u0633\u0642\u0627 \u0626\u0648\u062e\u0634\u0627\u064a\u062f\u06c7.\n\u06af\u06c7\u0646\u0627\u06be \u0626\u0627\u0644\u062f\u0627\u0645\u0686\u0649\u0644\u0649\u0642 \u0628\u0648\u0644\u063a\u0627\u0686\u0642\u0627\u060c \u0628\u0649\u0632 \u064a\u0648\u0644\u0649\u0645\u0649\u0632\u062f\u0649\u0646 \u0626\u0627\u0632\u0649\u067e \u0643\u06d0\u062a\u0649\u0645\u0649\u0632\u060c \u06be\u06d5\u062a\u062a\u0627 \u0628\u06c7\u0646\u0649 \u0628\u0649\u0644\u0645\u06d5\u064a\u0645\u0649\u0632\u0645\u06c7.\n\u0626\u0649\u0686\u0649\u0645\u0649\u0632\u062f\u06d5 \u0646\u06d0\u0645\u06d5 \u0628\u0648\u0644\u06c7\u06cb\u0627\u062a\u0642\u0627\u0646\u0644\u0649\u0642\u0649\u0646\u0649 \u0643\u06c6\u0631\u06c8\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u062e\u06c7\u062f\u0627\u0646\u0649\u06ad \u064a\u0627\u0631\u062f\u0649\u0645\u0649\u06af\u06d5 \u0645\u0648\u06be\u062a\u0627\u062c\u0645\u0649\u0632.\n\u0643\u06d0\u0644\u0649\u06ad\u0644\u0627\u0631\u060c \u0632\u06d5\u0628\u06c7\u0631 139:23\u201324-\u0626\u0627\u064a\u06d5\u062a\u0644\u06d5\u0631\u0646\u0649 \u0628\u0649\u0631\u0644\u0649\u0643\u062a\u06d5 \u062f\u06c7\u0626\u0627 \u0642\u0649\u0644\u0649\u067e \u0626\u0648\u0642\u06c7\u064a\u0644\u0649:\n\u06be\u06d5\u0645\u0645\u0649\u0633\u0649: 23 \u00ab\u0626\u0649 \u062e\u06c7\u062f\u0627\u060c \u0645\u06d0\u0646\u0649 \u062a\u06d5\u0643\u0634\u06c8\u0631\u06c8\u067e\u060c \u0642\u06d5\u0644\u0628\u0649\u0645\u0646\u0649 \u0628\u0649\u0644\u06af\u0649\u0646!\u00bb\n\u0645\u06d0\u0646\u0649 \u0633\u0649\u0646\u0627\u067e \u0628\u06d0\u0642\u0649\u06ad \u06cb\u06d5 \u0626\u0648\u064a-\u067e\u0649\u0643\u0649\u0631\u0644\u0649\u0631\u0649\u0645\u0646\u0649 \u0628\u0649\u0644\u0649\u06ad!\n24 \u0645\u06d0\u0646\u0649\u06ad \u0626\u0649\u0686\u0649\u0645\u062f\u06d5 \u0628\u0649\u0631\u06d5\u0631 \u064a\u0627\u0645\u0627\u0646 \u0626\u0649\u0634 \u0628\u0627\u0631-\u064a\u0648\u0642\u0644\u06c7\u0642\u0649\u0646\u0649 \u0643\u06c6\u0631\u06c8\u067e \u0628\u06d0\u0642\u0649\u06ad\u0644\u0627\u0631.\n\u0645\u06d0\u0646\u0649 \u0645\u06d5\u06ad\u06af\u06c8\u0644\u06c8\u0643 \u064a\u0648\u0644\u063a\u0627 \u0628\u0627\u0634\u0644\u0649\u063a\u0649\u0646!\n\n\u062e\u06c7\u062f\u0627\u0646\u0649\u06ad \u064a\u0627\u0631\u062f\u0649\u0645\u0649 \u0628\u0648\u0644\u0645\u0649\u0633\u0627\u060c \u0628\u0649\u0632 \u00ab\u0645\u06d5\u06ad\u06af\u06c8\u0644\u06c8\u0643 \u064a\u0648\u0644\u062f\u0627\u00bb \u0645\u0627\u06ad\u0627\u0644\u0645\u0627\u064a\u0645\u0649\u0632.\n\u0628\u0649\u0632 \u062e\u0627\u062a\u0627 \u064a\u06c6\u0646\u0649\u0644\u0649\u0634\u0643\u06d5 \u0642\u0627\u0631\u0627\u067e \u064a\u06c8\u06af\u06c8\u0631\u06c8\u067e\u060c \u0628\u0649\u0632\u0646\u0649 \u062e\u06c7\u062f\u0627\u0646\u0649\u06ad \u0642\u06d5\u0644\u0628\u0649\u062f\u0649\u0646 \u064a\u0649\u0631\u0627\u0642\u0644\u0627\u0634\u062a\u06c7\u0631\u0649\u062f\u0649\u063a\u0627\u0646 \u0626\u0649\u0634\u0644\u0627\u0631\u0646\u0649\u06ad \u0643\u06d5\u064a\u0646\u0649\u062f\u0649\u0646 \u0642\u0648\u063a\u0644\u0649\u0634\u0649\u0645\u0649\u0632.\n\u0644\u06d0\u0643\u0649\u0646 \u062e\u06c7\u062f\u0627 \u0634\u06c7\u0646\u062f\u0627\u0642 \u0645\u06d0\u06be\u0631\u0649\u0628\u0627\u0646\u0643\u0649\u060c \u0628\u0649\u0632\u0646\u0649\u06ad \u067e\u06d5\u0642\u06d5\u062a \u0626\u0627\u062f\u0649\u0634\u0649\u067e \u0643\u06d0\u062a\u0649\u067e \u064a\u0648\u0642\u0649\u0644\u0649\u067e \u0643\u06d0\u062a\u0649\u0634\u0649\u0645\u0649\u0632\u0646\u0649 \u0643\u06c6\u0631\u06c8\u067e \u062a\u06c7\u0631\u0645\u0627\u064a\u062f\u06c7.\n\u0626\u06d5\u0643\u0633\u0649\u0686\u06d5\u060c \u0626\u06c7 \u0626\u06c6\u0632\u0649\u0646\u0649\u06ad \u064a\u0648\u0642\u0627\u067e \u0643\u06d5\u062a\u0643\u06d5\u0646 \u0642\u0648\u064a\u0644\u0649\u0631\u0649\u0646\u0649 \u0626\u0649\u0632\u062f\u06d5\u064a\u062f\u06c7.\n\u0626\u06c7 \u0628\u0649\u0632\u0646\u0649\u06ad \u064a\u06d0\u0646\u0649\u0645\u0649\u0632\u063a\u0627 \u0643\u06d0\u0644\u0649\u067e\u060c \u0642\u06d0\u0686\u0649\u0634 \u06cb\u06d5 \u0642\u06c7\u062a\u0642\u06c7\u0632\u06c7\u0634 \u064a\u0648\u0644\u0649\u0646\u0649 \u062a\u06d5\u0645\u0649\u0646\u0644\u06d5\u064a\u062f\u06c7.\n2 \u062a\u0649\u0645\u0648\u062a\u0649\u064a\u063a\u0627 2:25b-26 \u06af\u06d5 \u064a\u06d5\u0646\u06d5 \u0628\u0649\u0631 \u0642\u06d0\u062a\u0649\u0645 \u0642\u0627\u0631\u0627\u06ad:\n25b \u00ab\u0628\u06d5\u0644\u0643\u0649\u0645 \u062e\u06c7\u062f\u0627 \u0626\u06c7\u0644\u0627\u0631\u063a\u0627 \u06be\u06d5\u0642\u0649\u0642\u06d5\u062a\u0646\u0649 \u0628\u0649\u0644\u0649\u0634\u0643\u06d5 \u064a\u0627\u0631\u062f\u06d5\u0645 \u0628\u06d0\u0631\u0649\u067e \u062a\u06d5\u06cb\u0628\u06d5 \u0642\u0649\u0644\u0649\u0634\u0649 \u0645\u06c7\u0645\u0643\u0649\u0646\u060c\n26 \u0626\u06c7\u0644\u0627\u0631 \u0626\u0649\u0628\u0644\u0649\u0633\u0646\u0649\u06ad \u062a\u06c7\u0632\u0649\u0642\u0649\u063a\u0627 \u0686\u06c8\u0634\u06c8\u067e\u060c \u0626\u06c7\u0646\u0649\u06ad \u0626\u0649\u0631\u0627\u062f\u0649\u0633\u0649\u0646\u0649 \u0626\u06d5\u0645\u06d5\u0644\u06af\u06d5 \u0626\u0627\u0634\u06c7\u0631\u06c7\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0626\u06c7\u0646\u0649\u06ad \u062a\u06c7\u0632\u0649\u0642\u0649\u062f\u0649\u0646 \u0642\u06c7\u062a\u06c7\u0644\u06c7\u067e\u060c \u0626\u06d5\u0642\u0644\u0649\u0646\u0649 \u064a\u0649\u063a\u0649\u0634\u0649 \u0645\u06c7\u0645\u0643\u0649\u0646.\n\n\u06af\u06c7\u0646\u0627\u06be \u06cb\u06d5 \u0634\u06d5\u064a\u062a\u0627\u0646\u0646\u0649\u06ad \u0642\u0627\u067e\u0642\u0649\u0646\u0649\u063a\u0627 \u0686\u06c8\u0634\u06c8\u067e \u0642\u0627\u0644\u063a\u0627\u0646\u062f\u0627\u060c \u0626\u06c6\u0632\u0649\u06ad\u0649\u0632\u0646\u0649 \u062a\u0648\u0644\u06c7\u0642 \u0626\u06d5\u0631\u0643\u0649\u0646 \u06be\u06d0\u0633 \u0642\u0649\u0644\u0627\u0644\u0627\u064a\u062f\u0649\u063a\u0627\u0646\u0644\u0649\u0642\u0649\u06ad\u0649\u0632\u0646\u0649 \u0628\u0649\u0644\u06d5\u0645\u0633\u0649\u0632\u061f\n\u06af\u06c7\u0646\u0627\u06be \u0626\u06d5\u0631\u0643\u0649\u0646\u0644\u0649\u0643\u0643\u06d5 \u0626\u0648\u062e\u0634\u0627\u064a\u062f\u06c7\u060c \u0626\u06d5\u0645\u0645\u0627 \u0626\u06c7\u0646\u0649\u06ad \u0626\u06d5\u0643\u0633\u0649\u0686\u06d5.\n\u0628\u0649\u0631 \u062a\u06c7\u0632\u0627\u0642 \u0645\u06c7\u0646\u062f\u0627\u0642 \u0643\u06c6\u0631\u06c8\u0646\u0649\u062f\u06c7.\n\u0628\u06c7\u060c \u064a\u0648\u0644\u062f\u0627 \u0626\u06d5\u0631\u0643\u0649\u0646 \u064a\u06c8\u06af\u06c8\u0631\u06c8\u067e \u0643\u06d0\u062a\u0649\u06cb\u0627\u062a\u0642\u0627\u0646\u060c \u0626\u0627\u0646\u062f\u0649\u0646 \u062a\u06c7\u064a\u06c7\u0642\u0633\u0649\u0632 \u062e\u06d5\u062a\u06d5\u0631\u06af\u06d5 \u062f\u06c7\u0686 \u0643\u06d5\u0644\u06af\u06d5\u0646 \u06be\u0627\u064a\u06cb\u0627\u0646\u0646\u0649 \u062a\u06c7\u062a\u06c7\u06cb\u0627\u0644\u0649\u062f\u0649\u063a\u0627\u0646 \u062a\u06c7\u0632\u0627\u0642.\n\u0634\u06d5\u064a\u062a\u0627\u0646 \u0628\u0649\u0632\u0646\u0649 \u0626\u0627\u0644\u062f\u0627\u067e\u060c \u062a\u06c7\u0632\u0627\u0642\u0642\u0627 \u0686\u06c8\u0634\u06c8\u0631\u06c8\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0645\u0627\u0631\u0627\u0641\u0648\u0646\u0686\u06d5 \u064a\u06c8\u06af\u06c8\u0631\u06c8\u0634 \u064a\u0648\u0644\u0649\u063a\u0627 \u0628\u06d5\u0644\u06af\u0649\u0644\u06d5\u0631\u06af\u06d5 \u0626\u0648\u062e\u0634\u0627\u0634 \u064a\u0627\u0644\u063a\u0627\u0646\u0644\u0627\u0631\u0646\u0649 \u0642\u0648\u064a\u0649\u062f\u06c7.\n\u0634\u06d5\u064a\u062a\u0627\u0646 \u0628\u0649\u0632\u0646\u0649\u06ad \u062e\u06c7\u0634\u0627\u0644\u0644\u0649\u0642\u060c \u06be\u0648\u0642\u06c7\u0642\u060c \u062f\u0627\u06ad\u0642\u060c \u0645\u0627\u0644-\u0645\u06c8\u0644\u06c8\u0643 \u06cb\u06d5 \u063a\u06c7\u0631\u06c7\u0631\u0646\u0649\u06ad \u0626\u0627\u0631\u0642\u0649\u0633\u0649\u062f\u0649\u0646 \u064a\u06c8\u06af\u06c8\u0631\u06c8\u0634\u0649\u0645\u0649\u0632\u0646\u0649 \u0626\u06c8\u0645\u0649\u062f \u0642\u0649\u0644\u0649\u062f\u06c7.\n\u0628\u06c7 \u0628\u06c7\u062a\u0644\u0627\u0631 \u0628\u0649\u0632\u06af\u06d5 \u0626\u06d5\u0631\u0643\u0649\u0646\u0644\u0649\u0643 \u06cb\u06d5\u062f\u06d5 \u0642\u0649\u0644\u0649\u062f\u06c7\u060c \u0626\u06d5\u0631\u0643\u0649\u0646\u0644\u0649\u0643 \u0628\u0649\u0632\u0646\u0649\u06ad \u0626\u06d5\u06ad \u0626\u0627\u0631\u0632\u06c7 \u0642\u0649\u0644\u0649\u062f\u0649\u063a\u0627\u0646 \u0646\u06d5\u0631\u0633\u0649\u0645\u0649\u0632.\n\u0626\u06d5\u067e\u0633\u06c7\u0633\u0643\u0649\u060c \u0628\u0649\u0632 \u0628\u06c7\u0646\u062f\u0627\u0642 \u0646\u06d5\u0631\u0633\u0649\u0644\u06d5\u0631\u0646\u0649\u06ad \u0628\u0649\u0632\u06af\u06d5 \u0631\u0627\u0632\u0649\u0645\u06d5\u0646\u0644\u0649\u0643\u060c \u0628\u0649\u062e\u06d5\u062a\u06d5\u0631\u0644\u0649\u0643 \u06cb\u06d5 \u0628\u06d5\u062e\u062a\u0644\u0649\u0643 \u06be\u06d0\u0633 \u0642\u0649\u0644\u062f\u06c7\u0631\u06c7\u0634\u0642\u0627 \u064a\u0627\u0631\u062f\u06d5\u0645 \u0628\u06d0\u0631\u06d5\u0644\u06d5\u064a\u062f\u0649\u063a\u0627\u0646\u0644\u0649\u0642\u0649\u063a\u0627 \u0626\u0649\u0634\u0649\u0646\u0649\u0645\u0649\u0632.\n\u0644\u06d0\u0643\u0649\u0646 \u0628\u06c7 \u0628\u06c7\u062a\u0644\u0627\u0631 \u0628\u0649\u0632\u0646\u0649 \u0626\u0627\u0644\u0644\u0627\u06be\u062a\u0649\u0646 \u06cb\u06d5 \u06be\u06d5\u0642\u0649\u0642\u0649\u064a \u06be\u0627\u064a\u0627\u062a \u064a\u0648\u0644\u0649\u062f\u0649\u0646 \u062a\u0648\u0633\u0649\u062f\u0649\u063a\u0627\u0646 \u062a\u06c7\u0632\u0627\u0642\u0644\u0627\u0631\u062f\u06c7\u0631.\n\u0634\u06d5\u064a\u062a\u0627\u0646 \u06be\u0627\u064a\u0627\u062a \u064a\u0648\u0644\u0649\u0646\u0649 \u0628\u0649\u0632\u062f\u0649\u0646 \u064a\u0648\u0634\u06c7\u0631\u0645\u0627\u0642\u0686\u0649 \u0628\u0648\u0644\u06c7\u067e \u0645\u06c7\u0646\u062f\u0627\u0642 \u062f\u06d5\u064a\u062f\u06c7:\n\u00ab\u063a\u06d5\u0644\u0649\u0628\u06d5 \u06cb\u06d5 \u0628\u06d5\u062e\u062a\u0643\u06d5 \u0626\u06d0\u0631\u0649\u0634\u0649\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0628\u06c7 \u064a\u0648\u0644\u062f\u0649\u0646 \u0645\u0627\u06ad!\u00bb\n\u06be\u06d5\u0626\u06d5\u060c \u064a\u0648\u0644 \u0634\u06c7! \u0645\u0627\u06ad\u0627 \u0626\u06d5\u06af\u0649\u0634\u0649\u06ad\u0644\u0627\u0631!\n\n\u0626\u06c7\u0646\u062f\u0627\u0642\u062a\u0627\u060c \u06be\u0627\u064a\u06cb\u0627\u0646 \u0628\u06c7\u0646\u062f\u0627\u0642 \u0642\u0627\u067e\u0642\u0627\u0646\u062f\u0649\u0646 \u0642\u0627\u0646\u062f\u0627\u0642 \u0642\u06d0\u0686\u0649\u067e \u0642\u06c7\u062a\u06c7\u0644\u0627\u0644\u0627\u064a\u062f\u06c7\u061f\n\u0628\u06c7 \u0626\u06c7\u0646\u0649\u06ad \u0626\u06c6\u0632\u0649 \u0642\u0649\u0644\u0627\u0644\u0627\u064a\u062f\u0649\u063a\u0627\u0646 \u0626\u0649\u0634\u0645\u06c7\u061f\n\u064a\u0627\u0642\u060c \u0642\u0648\u064a\u0627\u0646\u0646\u0649\u06ad \u0626\u0627\u0645\u0627\u0644\u0649 \u064a\u0648\u0642.\n\u0626\u06c7\u0646\u0649 \u0642\u0627\u067e\u0642\u0627\u0646\u062f\u0649\u0646 \u0642\u06c7\u062a\u06c7\u0644\u062f\u06c7\u0631\u06c7\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0626\u06d5\u0642\u0649\u0644\u0644\u0649\u0642 \u06cb\u06d5 \u0643\u06c8\u0686\u0644\u06c8\u0643 \u0628\u0649\u0631\u0633\u0649\u0646\u0649\u06ad \u0643\u06d0\u0644\u0649\u0634\u0649\u06af\u06d5 \u0645\u0648\u06be\u062a\u0627\u062c.\n\u0628\u0649\u0632\u0646\u0649 \u0642\u06c7\u062a\u0642\u06c7\u0632\u06c7\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0628\u0649\u0632\u06af\u06d5 \u0626\u06d5\u0642\u0649\u0644\u0644\u0649\u0642 \u06cb\u06d5 \u0643\u06c8\u0686\u0644\u06c8\u0643 \u0628\u0649\u0631\u0633\u0649 \u0643\u06d0\u0631\u06d5\u0643.\n\u0628\u06c7 \u0645\u06d5\u0646 \u0628\u06c7 \u0626\u0627\u064a\u06d5\u062a \u06be\u06d5\u0642\u0642\u0649\u062f\u06d5 \u0633\u0649\u0632\u06af\u06d5 \u0643\u06c6\u0631\u0633\u0649\u062a\u0649\u0634\u0649\u06ad\u0649\u0632\u0646\u0649 \u0626\u06c8\u0645\u0649\u062f \u0642\u0649\u0644\u0649\u062f\u0649\u063a\u0627\u0646 \u0626\u06d5\u06ad \u0645\u06c7\u06be\u0649\u0645 \u0646\u06c7\u0642\u062a\u0627.\n\u0628\u0649\u0632 \u0626\u06c6\u0632\u0649\u0645\u0649\u0632\u0646\u0649 \u0642\u06c7\u062a\u0642\u06c7\u0632\u0627\u0644\u0645\u0627\u064a\u0645\u0649\u0632\u060c \u06be\u06d5\u062a\u062a\u0627 \u062e\u06c7\u062f\u0627\u063a\u0627 \u064a\u06c8\u0632\u0644\u0649\u0646\u06d5\u0644\u0645\u06d5\u064a\u0645\u0649\u0632\u060c \u0634\u06c7\u06ad\u0627 \u0628\u0649\u0632\u06af\u06d5 \u0642\u06c7\u062a\u0642\u06c7\u0632\u063a\u06c7\u0686\u0649 \u0643\u06d0\u0631\u06d5\u0643.\n\u0631\u0648\u06be\u0649\u064a \u062c\u06d5\u06be\u06d5\u062a\u062a\u0649\u0646 \u0626\u06c6\u0644\u06c8\u0643 \u0642\u06d5\u0644\u0628\u0644\u06d5\u0631 \u06be\u0627\u064a\u0627\u062a\u0646\u0649 \u062a\u0627\u0644\u0644\u0649\u064a\u0627\u0644\u0645\u0627\u064a\u062f\u06c7.\n25-\u0626\u0627\u064a\u06d5\u062a\u062a\u06d5 \u0646\u06d0\u0645\u06d5 \u062f\u06d0\u064a\u0649\u0644\u06af\u06d5\u0646\u0644\u0649\u0643\u0649\u06af\u06d5 \u0642\u0627\u0631\u0627\u06ad:\n\u00ab\u0628\u06d5\u0644\u0643\u0649\u0645 \u0626\u0627\u0644\u0644\u0627\u06be \u0626\u06c7\u0644\u0627\u0631\u0646\u0649\u06ad \u062a\u06d5\u06cb\u0628\u06d5 \u0642\u0649\u0644\u0649\u0634\u0649\u063a\u0627 \u064a\u0648\u0644 \u0626\u0627\u0686\u0627\u0631\u00bb.\n\n\u064a\u0627\u0631\u062f\u06d5\u0645 \u067e\u06c7\u0644\u0649 \u0628\u0649\u0631 \u062e\u0649\u0644 \u06be\u06d5\u0642\u0633\u0649\u0632 \u0633\u0648\u06cb\u063a\u0627\u062a.\n\u062e\u06c7\u062f\u0627 \u0645\u0627\u06ad\u0627 30 \u064a\u0649\u0644 \u0626\u0649\u0644\u06af\u0649\u0631\u0649 \u062a\u06d5\u06cb\u0628\u06d5 \u0642\u0649\u0644\u0649\u0634 \u0633\u0648\u06cb\u063a\u0649\u0633\u0649\u0646\u0649 \u0628\u06d5\u0631\u06af\u06d5\u0646.\n\u0645\u06d5\u0646 10 \u064a\u0649\u0644 \u0643\u0627\u0626\u0649\u0646\u0627\u062a\u062a\u0627 \u062e\u06c7\u062f\u0627 \u064a\u0648\u0642 \u062f\u06d5\u067e \u0626\u06d0\u064a\u062a\u062a\u0649\u0645.\n\u0644\u06d0\u0643\u0649\u0646 \u062e\u06c7\u062f\u0627 \u0645\u06d0\u06be\u0631\u0649\u0628\u0627\u0646 \u0628\u0648\u0644\u063a\u0627\u0686\u0642\u0627\u060c \u0626\u06c7 \u0645\u0627\u06ad\u0627 \u067e\u0649\u06cb\u0627\u060c \u0626\u0627\u064a\u0627\u0644\u0644\u0627\u0631 \u06cb\u06d5 \u062f\u06c7\u0646\u064a\u0627\u06cb\u0649 \u0645\u06c7\u06cb\u06d5\u067e\u067e\u06d5\u0642\u0649\u064a\u06d5\u062a\u0646\u0649\u06ad \u06be\u06d5\u0631\u06af\u0649\u0632 \u0642\u06d5\u0644\u0628\u0649\u0645\u0646\u0649\u06ad \u0626\u0627\u0631\u0632\u06c7\u0644\u0649\u0631\u0649\u0646\u0649 \u0642\u0627\u0646\u062f\u06c7\u0631\u0627\u0644\u0645\u0627\u064a\u062f\u0649\u063a\u0627\u0646\u0644\u0649\u0642\u0649\u0646\u0649 \u0643\u06c6\u0631\u0633\u06d5\u062a\u062a\u0649.\n26-\u0626\u0627\u064a\u06d5\u062a\u062a\u0649\u0643\u0649 \u00ab\u0626\u06d5\u0642\u0644\u0649\u06af\u06d5 \u0643\u06d0\u0644\u0649\u0634\u00bb \u062f\u06d0\u06af\u06d5\u0646 \u0633\u06c6\u0632\u0646\u0649\u06ad \u0645\u06d5\u0646\u0649\u0633\u0649 \u0645\u06c7\u0634\u06c7.\n\u064a\u06c6\u0646\u0649\u0644\u0649\u0634 \u062a\u06c7\u064a\u063a\u06c7\u06ad\u0649\u0632 \u0642\u0627\u0644\u0627\u064a\u0645\u0649\u0642\u0627\u0646\u0644\u0649\u0634\u0649\u067e \u0643\u06d5\u062a\u0633\u06d5\u060c \u062e\u0627\u062a\u0627 \u064a\u06c6\u0646\u0649\u0644\u0649\u0634\u0643\u06d5 \u0642\u0627\u0631\u0627\u067e \u064a\u06c8\u06af\u06c8\u0631\u0649\u0633\u0649\u0632.\n\u0626\u06c6\u064a\u06af\u06d5 \u0642\u0627\u064a\u062a\u0649\u0634 \u064a\u0648\u0644\u0649\u0646\u0649 \u062a\u06d0\u067e\u0649\u0634\u0646\u0649\u06ad \u062a\u06c7\u0646\u062c\u0649 \u0642\u06d5\u062f\u0649\u0645\u0649 \u0626\u06c6\u0632\u0649\u06ad\u0649\u0632\u0646\u0649\u06ad \u064a\u0648\u0644\u0633\u0649\u0632 \u0642\u0627\u0644\u063a\u0627\u0646\u0644\u0649\u0642\u0649\u06ad\u0649\u0632\u0646\u0649 \u062a\u0648\u0646\u06c7\u0634\u062a\u0649\u0646 \u0626\u0649\u0628\u0627\u0631\u06d5\u062a.\n\u062f\u0627\u0646 \u0645\u0627\u0643\u062f\u0648\u06cb\u06d0\u0644 \u067e\u0648\u0631\u062a\u0644\u0627\u0646\u062f\u062a\u0649\u0643\u0649 \u0645\u0627\u0631\u0627\u0641\u0648\u0646\u0686\u06d5 \u064a\u06c8\u06af\u06c8\u0631\u06c8\u0634 \u0645\u06c7\u0633\u0627\u0628\u0649\u0642\u0649\u0633\u0649\u062f\u06d5 \u064a\u0648\u0642\u0627\u0644\u063a\u0627\u0646 \u064a\u06c8\u06af\u06c8\u0631\u06af\u06c8\u0686\u0649\u0644\u06d5\u0631\u0646\u0649\u06ad \u0628\u0649\u0631\u0649 \u0626\u0649\u062f\u0649.\n\u0626\u06c7 \u0645\u06c7\u0646\u062f\u0627\u0642 \u062f\u06d0\u062f\u0649: \u00ab\u0645\u06d5\u0646 \u0628\u06c7\u0644\u06c7\u06ad\u062f\u0649\u0646 \u0626\u06c6\u062a\u06c8\u067e \u0643\u06d5\u0644\u06af\u06d5\u0646\u062f\u06d5 10 \u0626\u0627\u062f\u06d5\u0645\u0646\u0649\u06ad \u0642\u0649\u0645\u0649\u0631\u0644\u0649\u0645\u0627\u064a \u062a\u06c7\u0631\u063a\u0627\u0646\u0644\u0649\u0642\u0649\u0646\u0649 \u0643\u06c6\u0631\u062f\u06c8\u0645...\u00bb\n\u0626\u06c7\u0644\u0627\u0631 \u0628\u0649\u0631-\u0628\u0649\u0631\u0649\u06af\u06d5 \u0642\u0627\u0631\u0627\u067e: \u00ab\u06cb\u0627\u064a\u060c \u0628\u06c7 \u062a\u0648\u063a\u0631\u0627 \u0626\u06d5\u0645\u06d5\u0633\u062a\u06d5\u0643 \u0642\u0649\u0644\u0649\u062f\u06c7\u00bb \u062f\u06d5\u067e \u0626\u0648\u064a\u0644\u0627\u06cb\u0627\u062a\u0627\u062a\u062a\u0649.\n\n\u064a\u06d5\u0646\u06d5 \u0628\u0649\u0631 \u064a\u06c8\u06af\u06c8\u0631\u06c8\u0634 \u0645\u0627\u06be\u0649\u0631\u0649 \u0632\u0627\u0643 \u0643\u06c7\u0633\u062a\u06d0\u0631\u0646\u0649\u06ad \u0626\u06d0\u064a\u062a\u0649\u0634\u0649\u0686\u06d5\u060c \u0626\u06c7 \u062a\u0648\u0646\u06d0\u0644\u063a\u0627 \u0643\u0649\u0631\u0649\u067e \u0642\u0627\u0644\u063a\u0627\u0646 \u0628\u0648\u0644\u06c7\u067e\u060c \u0645\u0627\u0634\u0649\u0646\u0649\u0644\u0627\u0631 \u0626\u06c7\u0646\u0649\u06ad \u064a\u06d0\u0646\u0649\u062f\u0649\u0646 \u0633\u0627\u0626\u0649\u062a\u0649\u06af\u06d5 55 \u0645\u0649\u0644 \u0633\u06c8\u0631\u0626\u06d5\u062a\u062a\u06d5 \u0626\u06c6\u062a\u06c8\u067e \u0643\u06d5\u062a\u0643\u06d5\u0646.\n\u0634\u06c7 \u0686\u0627\u063a\u062f\u0627 \u0626\u06c7 \u0626\u06c6\u0632\u0649\u0646\u0649\u06ad \u064a\u0648\u0644\u0649\u062f\u0649\u0646 \u0686\u0649\u0642\u0649\u067e \u0643\u06d5\u062a\u0643\u06d5\u0646\u0644\u0649\u0643\u0649\u0646\u0649 \u06be\u06d0\u0633 \u0642\u0649\u0644\u062f\u0649.\n\u062e\u06c7\u062f\u0627 \u0645\u06d0\u0646\u0649 \u0626\u06d5\u0642\u0644\u0649\u0645\u0646\u0649 \u064a\u0649\u063a\u0649\u0634\u062a\u06c7\u0631\u06c7\u0634\u062a\u0649\u0646 \u0628\u06c7\u0631\u06c7\u0646\u060c \u0645\u06d5\u0646 \u00ab\u06be\u06d5\u0642\u0649\u0642\u06d5\u062a\u0646\u0649 \u0628\u0649\u0644\u0649\u0645\u06d5\u0646\u00bb \u062f\u06d5\u067e \u0626\u0648\u064a\u0644\u0649\u063a\u0627\u0646 \u0626\u0649\u062f\u0649\u0645.\n\u0645\u06d0\u0646\u0649\u06ad \u063a\u06c7\u0631\u06c7\u0631\u06c7\u0645 \u0645\u0627\u06ad\u0627 \u062a\u0648\u063a\u0631\u0627 \u064a\u0648\u0644\u062f\u0627 \u0626\u0649\u0643\u06d5\u0646\u0644\u0649\u0643\u0649\u0645\u0646\u0649 \u0626\u06d0\u064a\u062a\u062a\u0649\u060c \u0645\u0627\u06ad\u0627 \u06be\u06d0\u0686\u0642\u0627\u0646\u062f\u0627\u0642 \u0626\u0649\u0644\u0627\u06be\u0646\u0649\u06ad \u064a\u06d0\u062a\u06d5\u0643\u0686\u0649\u0644\u0649\u0643\u0649\u06af\u06d5 \u0645\u0648\u06be\u062a\u0627\u062c \u0626\u06d5\u0645\u06d5\u0633 \u0626\u0649\u062f\u0649\u0645\u060c \u0686\u06c8\u0646\u0643\u0649 \u0645\u06d5\u0646 \u0626\u0649\u0646\u062a\u0627\u064a\u0649\u0646 \u0626\u06d5\u0642\u0649\u0644\u0644\u0649\u0642 \u0626\u0649\u062f\u0649\u0645.\n\u0642\u0649\u0632\u0649\u0642\u0649\u060c \u0645\u06d5\u0646 \u0634\u06d5\u064a\u062a\u0627\u0646\u0646\u0649\u06ad \u0626\u0627\u0644\u062f\u0627\u0645\u0686\u0649\u0644\u0649\u0642\u0649\u0646\u0649 \u0643\u06c6\u0631\u06d5\u0644\u0645\u0649\u06af\u06d5\u0646 \u0626\u06d5\u062e\u0645\u06d5\u0642 \u0626\u0649\u062f\u0649\u0645.\n\u0645\u06d5\u0646 \u0626\u06c7\u0646\u0649\u06ad \u064a\u0627\u0644\u063a\u0627\u0646\u0686\u0649\u0644\u0649\u0642 \u062a\u06c7\u0632\u0649\u0642\u0649\u063a\u0627 \u0626\u06d5\u0633\u0649\u0631 \u0628\u0648\u0644\u06c7\u067e \u0642\u0627\u0644\u062f\u0649\u0645.\n\u0645\u06d5\u0646 \u0634\u06d5\u064a\u062a\u0627\u0646\u0646\u0649\u06ad \u062e\u06c7\u062f\u0627\u062f\u0649\u0646 \u0642\u06d0\u0686\u0649\u067e \u0628\u06d5\u062e\u062a \u062a\u0627\u067e\u0649\u0645\u06d5\u0646 \u062f\u06d0\u06af\u06d5\u0646 \u06cb\u06d5\u062f\u0649\u0633\u0649\u06af\u06d5 \u0626\u0649\u0634\u06d5\u0646\u062f\u0649\u0645.\n\u0626\u06d5\u0645\u0645\u0627 \u0643\u06d0\u064a\u0649\u0646\u060c \u062e\u06c7\u062f\u0627 \u0645\u0627\u06ad\u0627 \u062a\u06d5\u06cb\u0628\u06d5 \u0642\u0649\u0644\u0649\u0634 \u0633\u0648\u06cb\u063a\u0649\u0633\u0649\u0646\u0649 \u0628\u06d5\u0631\u062f\u0649.\n\u0628\u06c7 \u064a\u06d5\u0631\u062f\u0649\u0643\u0649 \u06af\u0631\u06d0\u0643\u0686\u06d5 \u00ab\u0645\u06d0\u062a\u0627\u0646\u0648\u064a\u0627\u00bb \u0633\u06c6\u0632\u0649 \u062a\u06d5\u06cb\u0628\u06d5 \u0642\u0649\u0644\u0649\u0634 \u0645\u06d5\u0646\u0649\u0633\u0649\u0646\u0649 \u0628\u0649\u0644\u062f\u06c8\u0631\u0649\u062f\u06c7.\n\u0628\u06c7\u0646\u0649\u06ad \u0645\u06d5\u0646\u0649\u0633\u0649 \u00ab\u0626\u0648\u064a-\u067e\u0649\u0643\u0649\u0631\u0646\u0649\u06ad \u0626\u06c6\u0632\u06af\u0649\u0631\u0649\u0634\u0649\u060c \u06be\u0627\u064a\u0627\u062a\u0646\u0649\u06ad \u0626\u06c6\u0632\u06af\u0649\u0631\u0649\u0634\u0649 \u06cb\u06d5 \u0645\u06d5\u0642\u0633\u06d5\u062a\u0646\u0649\u06ad \u0626\u06c6\u0632\u06af\u0649\u0631\u0649\u0634\u0649\u00bb \u062f\u06d0\u06af\u06d5\u0646\u0644\u0649\u0643.\n\u0626\u06d5\u064a\u0633\u0627 \u0645\u0627\u06ad\u0627 \u064a\u06d0\u06ad\u0649 \u0628\u0649\u0631 \u0642\u06d5\u0644\u0628 \u0628\u06d5\u0631\u062f\u0649\u060c \u0634\u06c7\u06ad\u0627 \u0645\u06d5\u0646 22-\u0626\u0627\u064a\u06d5\u062a\u062a\u06d5 \u062f\u06d0\u064a\u0649\u0644\u06af\u06d5\u0646\u062f\u06d5\u0643 \u00ab\u067e\u06d5\u0631\u06cb\u06d5\u0631\u062f\u0649\u06af\u0627\u0631\u0646\u0649 \u067e\u0627\u0643 \u0642\u06d5\u0644\u0628\u062a\u0649\u0646 \u062f\u06c7\u0626\u0627 \u0642\u0649\u0644\u0627\u0644\u0627\u064a\u0645\u06d5\u0646\u00bb.\n\u067e\u0627\u0643 \u0642\u06d5\u0644\u0628 \u0631\u0627\u0633\u062a\u0686\u0649\u0644 \u0642\u06d5\u0644\u0628\u062a\u06c7\u0631.\n\u00ab\u06af\u06c7\u0646\u0627\u06be\u0649\u0645 \u0626\u06c8\u0686\u06c8\u0646 \u067e\u06c7\u0634\u0627\u064a\u0645\u0627\u0646 \u0642\u0649\u0644\u062f\u0649\u0645\u060c \u0645\u06d0\u0646\u0649 \u0643\u06d5\u0686\u06c8\u0631\u06af\u0649\u0646\u00bb \u062f\u06d5\u067e \u0626\u0627\u0644\u0644\u0627\u06be\u0642\u0627 \u0646\u0649\u062f\u0627 \u0642\u0649\u0644\u0649\u062f\u0649\u063a\u0627\u0646 \u0642\u06d5\u0644\u0628.\n\u0645\u0627\u06ad\u0627 \u0633\u06d5\u0646\u062f\u0649\u0646 \u064a\u0649\u0631\u0627\u0642\u0644\u0649\u0634\u0649\u0634\u0642\u0627 \u0626\u06d5\u0645\u06d5\u0633\u060c \u0628\u06d5\u0644\u0643\u0649 \u0633\u0627\u06ad\u0627 \u0642\u0627\u0631\u0627\u067e \u064a\u06c8\u06af\u06c8\u0631\u06c8\u0634\u0643\u06d5 \u064a\u0627\u0631\u062f\u06d5\u0645 \u0642\u0649\u0644.\n\u067e\u0627\u06cb\u0644\u06c7\u0633 \u0631\u0649\u0645\u0644\u0649\u0642\u0644\u0627\u0631\u063a\u0627 10:9-11 \u062f\u06d5 \u0642\u0627\u0646\u062f\u0627\u0642 \u0642\u0649\u0644\u0649\u067e \u062e\u06c7\u062f\u0627\u063a\u0627 \u064a\u06c8\u0632\u0644\u0649\u0646\u0649\u067e \u0646\u0649\u062c\u0627\u062a\u0644\u0649\u0642\u0642\u0627 \u0626\u06d0\u0631\u0649\u0634\u0649\u0634 \u062a\u0648\u063a\u0631\u0649\u0633\u0649\u062f\u0627 \u0626\u06d0\u0646\u0649\u0642 \u0686\u06c8\u0634\u06d5\u0646\u062f\u06c8\u0631\u06c8\u0634 \u0628\u06d5\u0631\u06af\u06d5\u0646.\n9 \u0626\u06d5\u06af\u06d5\u0631 \u0626\u0627\u063a\u0632\u0649\u06ad\u0649\u0632 \u0628\u0649\u0644\u06d5\u0646 \u00ab\u0626\u06d5\u064a\u0633\u0627 \u067e\u06d5\u0631\u06cb\u06d5\u0631\u062f\u0649\u06af\u0627\u0631\u062f\u06c7\u0631\u00bb \u062f\u06d5\u067e \u062c\u0627\u0643\u0627\u0631\u0644\u0649\u0633\u0649\u06ad\u0649\u0632 \u06cb\u06d5 \u062e\u06c7\u062f\u0627\u0646\u0649\u06ad \u0626\u06c7\u0646\u0649 \u0626\u06c6\u0644\u06c8\u0645\u062f\u0649\u0646 \u062a\u0649\u0631\u0649\u0644\u062f\u06c8\u0631\u06af\u06d5\u0646\u0644\u0649\u0643\u0649\u06af\u06d5 \u0642\u06d5\u0644\u0628\u0649\u06ad\u0649\u0632 \u0628\u0649\u0644\u06d5\u0646 \u0626\u0649\u0634\u06d5\u0646\u0633\u0649\u06ad\u0649\u0632\u060c \u0642\u06c7\u062a\u0642\u06c7\u0632\u06c7\u0644\u0649\u0633\u0649\u0632.\n10 \u0686\u06c8\u0646\u0643\u0649\u060c \u0633\u06d5\u0646 \u0642\u06d5\u0644\u0628\u0649\u06ad \u0628\u0649\u0644\u06d5\u0646 \u0626\u0649\u0634\u0649\u0646\u0649\u067e\u060c \u06be\u06d5\u0642\u0642\u0627\u0646\u0649\u064a \u0628\u0648\u0644\u0649\u0633\u06d5\u0646\u060c \u0626\u0627\u063a\u0632\u0649\u06ad \u0628\u0649\u0644\u06d5\u0646 \u0626\u0649\u0645\u0627\u0646\u0649\u06ad\u0646\u0649 \u062c\u0627\u0643\u0627\u0631\u0644\u0627\u067e \u0642\u06c7\u062a\u0642\u06c7\u0632\u06c7\u0644\u0649\u0633\u06d5\u0646.\n11 \u0645\u06c7\u0642\u06d5\u062f\u062f\u06d5\u0633 \u064a\u0627\u0632\u0645\u0649\u0644\u0627\u0631\u062f\u0627: \u00ab\u0626\u06c7\u0646\u0649\u06ad\u063a\u0627 \u0626\u0649\u0634\u06d5\u0646\u06af\u06d5\u0646 \u06be\u06d5\u0631 \u0642\u0627\u0646\u062f\u0627\u0642 \u0626\u0627\u062f\u06d5\u0645 \u0646\u0648\u0645\u06c7\u0633\u0642\u0627 \u0642\u0627\u0644\u0645\u0627\u064a\u062f\u06c7\u00bb \u062f\u06d0\u064a\u0649\u0644\u06af\u06d5\u0646.\n\n\u0646\u0649\u062c\u0627\u062a \u062a\u0627\u067e\u0649\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0626\u0627\u063a\u0632\u0649\u06ad \u0628\u0649\u0644\u06d5\u0646 \u0626\u0649\u0645\u0627\u0646 \u0626\u06d0\u064a\u062a\u062a\u0649\u06ad\u0645\u06c7\u061f\n\u0626\u06d5\u06af\u06d5\u0631 \u0633\u0649\u0632 \u0642\u0649\u0644\u0645\u0649\u063a\u0627\u0646 \u0628\u0648\u0644\u0633\u0649\u06ad\u0649\u0632\u060c \u0628\u06c8\u06af\u06c8\u0646 \u0628\u06c7\u0646\u0649 \u0642\u0649\u0644\u0649\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0626\u06d5\u06ad \u064a\u0627\u062e\u0634\u0649 \u0643\u06c8\u0646 \u062f\u06d5\u067e \u0626\u0648\u064a\u0644\u0649\u0645\u0627\u064a\u0633\u0649\u0632\u0645\u06c7\u061f\n\u0645\u06c7\u0642\u06d5\u062f\u062f\u06d5\u0633 \u0631\u0648\u06be \u0626\u0627\u0631\u0649\u0645\u0649\u0632\u062f\u0627\u060c \u0628\u06d5\u0644\u0643\u0649\u0645 \u0626\u06c7 \u0633\u0649\u0632\u0646\u0649\u06ad \u0642\u06d5\u0644\u0628\u0649\u06ad\u0649\u0632\u06af\u06d5 \u067e\u0649\u0686\u0649\u0631\u0644\u0627\u06cb\u0627\u062a\u0642\u0627\u0646 \u0628\u0648\u0644\u06c7\u0634\u0649 \u0645\u06c7\u0645\u0643\u0649\u0646:\n\u00ab\u06af\u06c7\u0646\u0627\u06be \u06cb\u06d5 \u0626\u06c6\u0644\u06c8\u0645 \u064a\u0648\u0644\u0649\u062f\u0649\u0646 \u0642\u0627\u064a\u062a\u0649\u06ad\u0644\u0627\u0631!\n\u00ab\u0626\u06d5\u064a\u0633\u0627 \u067e\u06d5\u0631\u06cb\u06d5\u0631\u062f\u0649\u06af\u0627\u0631!\u00bb \u062f\u06d5\u067e \u062c\u0627\u0643\u0627\u0631\u0644\u0627\u067e\u060c \u064a\u06d0\u06ad\u0649 \u06be\u0627\u064a\u0627\u062a \u06cb\u06d5 \u064a\u06d0\u06ad\u0649 \u064a\u06c6\u0646\u0649\u0644\u0649\u0634\u0646\u0649 \u062a\u0627\u0644\u0644\u0627\u06ad.\n\n\u067e\u0627\u06cb\u0644\u06c7\u0633 \u0626\u0649\u0644\u06af\u0649\u0631\u0649 \u0628\u06c7 \u064a\u06d0\u06ad\u0649 \u064a\u06c6\u0646\u0649\u0644\u0649\u0634 \u062a\u0648\u063a\u0631\u0649\u0633\u0649\u062f\u0627 \u0628\u0649\u0631 \u0642\u06d0\u062a\u0649\u0645 \u064a\u0627\u0632\u063a\u0627\u0646 \u0626\u0649\u062f\u0649.\n\u0628\u06c7\u060c \u062a\u0649\u0645\u0648\u062a\u0649\u064a \u06be\u0627\u0632\u0649\u0631 \u067e\u0648\u067e \u0628\u0648\u0644\u06c7\u067e \u062e\u0649\u0632\u0645\u06d5\u062a \u0642\u0649\u0644\u0649\u06cb\u0627\u062a\u0642\u0627\u0646 \u0626\u06d5\u0641\u06d5\u0633 \u0634\u06d5\u06be\u0649\u0631\u0649\u062f\u0649\u0643\u0649 \u0634\u06c7 \u0686\u06d0\u0631\u0643\u0627\u06cb\u063a\u0627 \u064a\u06d0\u0632\u0649\u0644\u063a\u0627\u0646 \u062e\u06d5\u062a\u062a\u06d5 \u064a\u06d0\u0632\u0649\u0644\u063a\u0627\u0646.\n\u067e\u0627\u06cb\u0644\u06c7\u0633\u0646\u0649\u06ad \u0626\u06d5\u0641\u06d5\u0633\u0644\u0649\u0643\u0644\u06d5\u0631\u06af\u06d5 2:1-5 \u062f\u06d5 \u0645\u06d5\u0633\u0649\u06be\u0649\u064a \u0626\u06d0\u062a\u0649\u0642\u0627\u062f\u0686\u0649\u0644\u0627\u0631\u063a\u0627 \u064a\u0627\u0632\u063a\u0627\u0646\u0644\u0649\u0631\u0649\u063a\u0627 \u0642\u06c7\u0644\u0627\u0642 \u0633\u06d0\u0644\u0649\u06ad\u060c \u0626\u06c7\u0644\u0627\u0631\u062f\u0627 \u062e\u06c7\u062f\u0627\u0646\u0649\u06ad \u0626\u06c7\u0644\u0627\u0631\u063a\u0627 \u064a\u06d0\u06ad\u0649 \u06be\u0627\u064a\u0627\u062a \u06cb\u06d5 \u064a\u06d0\u06ad\u0649 \u064a\u06c6\u0646\u0649\u0644\u0649\u0634 \u0628\u06d0\u0631\u0649\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0642\u0649\u0644\u063a\u0627\u0646 \u0626\u0649\u0634\u0644\u0649\u0631\u0649 \u06be\u06d5\u0642\u0642\u0649\u062f\u06d5 \u0645\u06c7\u0646\u062f\u0627\u0642 \u062f\u06d0\u064a\u0649\u0644\u06af\u06d5\u0646:\n1 \u00ab\u0633\u0649\u0644\u06d5\u0631 \u06af\u06c7\u0646\u0627\u06be \u06cb\u06d5 \u06af\u06c7\u0646\u0627\u06be\u0644\u0627\u0631 \u0626\u0649\u0686\u0649\u062f\u06d5 \u0626\u06c6\u0644\u06c8\u0643 \u0626\u0649\u062f\u0649\u06ad\u0644\u0627\u0631.\n2 \u0633\u0649\u0644\u06d5\u0631 \u0628\u0649\u0631 \u0632\u0627\u0645\u0627\u0646\u0644\u0627\u0631 \u0628\u06c7 \u062f\u06c7\u0646\u064a\u0627\u0646\u0649\u06ad \u064a\u0648\u0644\u0649\u063a\u0627 \u0626\u06d5\u06af\u0649\u0634\u0649\u067e\u060c \u06be\u0627\u06cb\u0627\u0646\u0649\u06ad \u06be\u06c6\u0643\u06c8\u0645\u0631\u0627\u0646\u0644\u0649\u0642 \u0642\u0649\u0644\u063a\u06c7\u0686\u0649\u0633\u0649\u0646\u0649\u06ad\u060c \u064a\u06d5\u0646\u0649 \u06be\u0627\u0632\u0649\u0631 \u0626\u0649\u062a\u0627\u0626\u06d5\u062a\u0633\u0649\u0632 \u0643\u0649\u0634\u0649\u0644\u06d5\u0631\u062f\u06d5 \u06be\u06d5\u0631\u0649\u0643\u06d5\u062a \u0642\u0649\u0644\u0649\u06cb\u0627\u062a\u0642\u0627\u0646 \u0631\u0648\u06be\u0646\u0649\u06ad \u0626\u06d5\u06af\u06d5\u0634\u0643\u06c8\u0686\u0649\u0633\u0649\u06af\u06d5 \u0626\u06d5\u06af\u0649\u0634\u0649\u067e\u060c \u0628\u06c7 \u062f\u06c7\u0646\u064a\u0627\u062f\u0627 \u064a\u0627\u0634\u0649\u062f\u0649\u06ad\u0644\u0627\u0631.\n3 \u0628\u0649\u0632 \u06be\u06d5\u0645\u0645\u0649\u0645\u0649\u0632 \u0628\u0649\u0631 \u0632\u0627\u0645\u0627\u0646\u0644\u0627\u0631 \u0626\u06c7\u0644\u0627\u0631\u0646\u0649\u06ad \u0626\u0627\u0631\u0649\u0633\u0649\u062f\u0627 \u062a\u06d5\u0628\u0649\u0626\u0649\u062a\u0649\u0645\u0649\u0632\u062f\u0649\u0643\u0649 \u0646\u06d5\u067e\u0649\u0633 \u0626\u0627\u0631\u0632\u06c7\u0644\u0627\u0631\u063a\u0627 \u0628\u06d0\u0631\u0649\u0644\u0649\u067e\u060c \u062c\u0649\u0633\u0645\u0649\u0645\u0649\u0632\u0646\u0649\u06ad \u06cb\u06d5 \u0626\u06d5\u0642\u0649\u0644-\u067e\u0627\u0631\u0627\u0633\u0649\u062a\u0649\u0645\u0649\u0632\u0646\u0649\u06ad \u0626\u0627\u0631\u0632\u06c7\u0644\u0649\u0631\u0649\u0646\u0649 \u0642\u0627\u0646\u062f\u06c7\u0631\u0627\u062a\u062a\u06c7\u0642. \u062a\u06d5\u0628\u0649\u0626\u0649\u064a \u06be\u0627\u0644\u062f\u0627 \u0628\u0627\u0634\u0642\u0627 \u0626\u0649\u0646\u0633\u0627\u0646\u0644\u0627\u0631\u063a\u0627 \u0626\u0648\u062e\u0634\u0627\u0634 \u063a\u06d5\u0632\u06d5\u067e\u0643\u06d5 \u0626\u06c7\u0686\u0631\u0649\u063a\u0627\u0646 \u0628\u0627\u0644\u0649\u0644\u0627\u0631 \u0626\u0649\u062f\u06c7\u0642.\n4 \u0644\u06d0\u0643\u0649\u0646\u060c \u0628\u0649\u0632\u06af\u06d5 \u0628\u0648\u0644\u063a\u0627\u0646 \u0645\u06c7\u06be\u06d5\u0628\u0628\u0649\u062a\u0649 \u062a\u06c8\u067e\u06d5\u064a\u0644\u0649\u062f\u0649\u0646\u060c \u0631\u06d5\u06be\u0649\u0645-\u0634\u06d5\u067e\u0642\u06d5\u062a\u0643\u06d5 \u0645\u0648\u0644 \u0628\u0648\u0644\u063a\u0627\u0646 \u062e\u06c7\u062f\u0627\u060c\n5 \u06af\u06c7\u0646\u0627\u06be\u0644\u0649\u0631\u0649\u0645\u0649\u0632 \u062a\u06c8\u067e\u06d5\u064a\u0644\u0649\u062f\u0649\u0646 \u0626\u06c6\u0644\u06af\u06d5\u0646 \u0628\u0648\u0644\u0633\u0627\u0642\u0645\u06c7\u060c \u0628\u0649\u0632\u0646\u0649 \u0645\u06d5\u0633\u0649\u06be \u0628\u0649\u0644\u06d5\u0646 \u0628\u0649\u0644\u0644\u06d5 \u062a\u0649\u0631\u0649\u0644\u062f\u06c8\u0631\u062f\u0649. \u0633\u0649\u0644\u06d5\u0631 \u062e\u06c7\u062f\u0627\u0646\u0649\u06ad \u0645\u06d0\u06be\u0649\u0631-\u0634\u06d5\u067e\u0642\u0649\u062a\u0649 \u0628\u0649\u0644\u06d5\u0646 \u0642\u06c7\u062a\u0642\u06c7\u0632\u06c7\u0644\u062f\u06c7\u06ad\u0644\u0627\u0631!\n\n\u00ab\u0644\u06d0\u0643\u0649\u0646 \u062e\u06c7\u062f\u0627\u00bb \u062f\u06d0\u06af\u06d5\u0646 \u0633\u06c6\u0632\u0644\u06d5\u0631 \u06be\u06d5\u0645\u0645\u06d5 \u0626\u0627\u062f\u06d5\u0645\u0646\u0649\u06ad \u0626\u06d0\u064a\u062a\u0649\u062f\u0649\u063a\u0627\u0646 \u0626\u06d5\u06ad \u06af\u06c8\u0632\u06d5\u0644 \u0626\u0649\u0643\u0643\u0649 \u0633\u06c6\u0632.\n\u067e\u0627\u06cb\u0644\u06c7\u0633 \u0626\u06d5\u0641\u06d5\u0633\u0644\u0649\u0643 \u0626\u06d0\u062a\u0649\u0642\u0627\u062f\u0686\u0649\u0644\u0627\u0631\u063a\u0627 \u0626\u06c7\u0644\u0627\u0631\u0646\u0649\u06ad \u0628\u0649\u0631 \u06cb\u0627\u0642\u0649\u062a\u0644\u0627\u0631\u062f\u0627 \u0642\u0627\u067e\u0642\u0627\u0646\u063a\u0627 \u0686\u06c8\u0634\u0643\u06d5\u0646 \u0642\u0648\u064a\u0627\u0646\u063a\u0627 \u0626\u0648\u062e\u0634\u0627\u0634 \u0642\u0627\u067e\u0642\u0627\u0646\u063a\u0627 \u0686\u06c8\u0634\u06c8\u067e \u0642\u0627\u0644\u063a\u0627\u0646\u0644\u0649\u0642\u0649\u0646\u0649 \u06cb\u06d5 \u064a\u0627\u0631\u062f\u06d5\u0645\u0633\u0649\u0632 \u0642\u0627\u0644\u063a\u0627\u0646\u0644\u0649\u0642\u0649\u0646\u0649 \u0626\u06d5\u0633\u0643\u06d5\u0631\u062a\u0649\u062f\u06c7.\n\u0644\u06d0\u0643\u0649\u0646 \u062e\u06c7\u062f\u0627 \u0626\u06c7\u0644\u0627\u0631\u0646\u0649 \u067e\u06d5\u0642\u06d5\u062a \u0645\u06d0\u06be\u0649\u0631-\u0634\u06d5\u067e\u0642\u06d5\u062a\u060c \u067e\u06d5\u0642\u06d5\u062a \u0626\u0649\u0645\u0627\u0646 \u06cb\u06d5 \u067e\u06d5\u0642\u06d5\u062a \u0645\u06d5\u0633\u0649\u06be\u0643\u06d5 \u0628\u0648\u0644\u063a\u0627\u0646 \u0626\u06d0\u062a\u0649\u0642\u0627\u062f \u0626\u0627\u0631\u0642\u0649\u0644\u0649\u0642 \u0642\u06c7\u062a\u0642\u06c7\u0632\u06c7\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0626\u0627\u0631\u0649\u063a\u0627 \u0643\u0649\u0631\u062f\u0649.\n\u0626\u06d5\u06af\u06d5\u0631 \u0633\u0649\u0632 \u0645\u06d5\u0633\u0649\u06be\u0646\u0649\u06ad \u062e\u0627\u0686\u062a\u0649\u0643\u0649 \u0642\u06c7\u0631\u0628\u0627\u0646\u0644\u0649\u0642\u0649\u0646\u0649\u06ad \u0633\u0649\u0632 \u0626\u06c8\u0686\u06c8\u0646\u060c \u0633\u0649\u0632\u0646\u0649 \u06af\u06c7\u0646\u0627\u06be \u06cb\u06d5 \u0646\u0648\u0645\u06c7\u0633\u062a\u0649\u0646 \u064a\u06c7\u064a\u06c7\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0626\u0649\u0643\u06d5\u0646\u0644\u0649\u0643\u0649\u06af\u06d5 \u0626\u0649\u0634\u06d5\u0646\u0633\u0649\u06ad\u0649\u0632\u060c \u06be\u06d5\u0631 \u0642\u0627\u0646\u062f\u0627\u0642 \u0626\u0627\u062f\u06d5\u0645 \u0642\u06c7\u062a\u0642\u06c7\u0632\u06c7\u0644\u0649\u062f\u06c7.\n\u0628\u06c7\u0646\u0649\u06ad\u063a\u0627 \u0626\u0649\u0634\u06d5\u0646\u0633\u0649\u06ad\u0649\u0632\u060c \u064a\u06d0\u06ad\u0649 \u06be\u0627\u064a\u0627\u062a\u0642\u0627 \u0626\u06d0\u0631\u0649\u0634\u0649\u0633\u0649\u0632 \u06cb\u06d5 \u0626\u06d5\u064a\u0633\u0627 \u0633\u0649\u0632\u0646\u0649 \u064a\u06d0\u06ad\u0649 \u064a\u0648\u0644\u063a\u0627 \u0628\u0627\u0634\u0644\u0627\u064a\u062f\u06c7.\n\u0628\u0649\u0631 \u0642\u0627\u0646\u0686\u06d5 \u0626\u0627\u064a\u06d5\u062a\u062a\u0649\u0646 \u0643\u06d0\u064a\u0649\u0646\u060c \u0626\u06d5\u0641\u06d5\u0633\u0644\u0649\u0643\u0644\u06d5\u0631\u06af\u06d5 \u064a\u06d0\u0632\u0649\u0644\u063a\u0627\u0646 \u062e\u06d5\u062a\u0646\u0649\u06ad 2:8 \u062f\u06d5\u060c \u067e\u0627\u06cb\u0644\u06c7\u0633 \u0628\u06c7 \u064a\u06d0\u06ad\u0649 \u064a\u06c6\u0646\u0649\u0644\u0649\u0634 \u062a\u0648\u063a\u0631\u0649\u0633\u0649\u062f\u0627 \u0633\u06c6\u0632\u0644\u06d5\u064a\u062f\u06c7.\n\u0628\u06c7\u0646\u0649 \u0645\u06d5\u0646 \u0628\u0649\u0644\u06d5\u0646 \u0628\u0649\u0644\u0644\u06d5 \u0626\u0648\u0642\u06c7\u06ad:\n\u06be\u06d5\u0645\u0645\u0649\u0633\u0649: 10 \u00ab\u0686\u06c8\u0646\u0643\u0649 \u0628\u0649\u0632 \u0626\u06c7\u0646\u0649\u06ad \u0626\u0649\u062c\u0627\u062f\u0649\u064a\u0649\u062a\u0649\u0645\u0649\u0632\u060c \u062e\u06c7\u062f\u0627 \u0628\u06c7 \u0626\u0649\u0634\u0644\u0627\u0631\u0646\u0649 \u0626\u0627\u0644\u062f\u0649\u0646 \u062a\u06d5\u064a\u064a\u0627\u0631\u0644\u0627\u067e\u060c \u0628\u0649\u0632\u0646\u0649\u06ad \u0628\u06c7 \u0626\u0649\u0634\u0644\u0627\u0631\u062f\u0627 \u0645\u06d0\u06ad\u0649\u0634\u0649\u0645\u0649\u0632 \u0626\u06c8\u0686\u06c8\u0646 \u0645\u06d5\u0633\u0649\u06be \u0626\u06d5\u064a\u0633\u0627 \u0626\u0627\u0631\u0642\u0649\u0644\u0649\u0642 \u064a\u0627\u0631\u0649\u062a\u0649\u0644\u063a\u0627\u0646\u0645\u0649\u0632\u00bb.\n\n\u0628\u06c7 \u0626\u06c7\u0686\u06c7\u0631\u0646\u0649 \u0626\u0627\u062e\u0649\u0631\u0644\u0627\u0634\u062a\u06c7\u0631\u06c7\u0634 \u0626\u06c8\u0686\u06c8\u0646\u060c \u064a\u0627\u062e\u0634\u0649 \u0626\u0649\u0634\u0644\u0627\u0631\u062f\u0627 \u064a\u06c8\u0631\u06c8\u0634\u0646\u0649\u06ad \u0642\u0627\u0646\u062f\u0627\u0642 \u0628\u0648\u0644\u0649\u062f\u0649\u063a\u0627\u0646\u0644\u0649\u0642\u0649\u063a\u0627 \u0646\u06d5\u0632\u06d5\u0631 \u0633\u0627\u0644\u0627\u064a\u0644\u0649.\n\u067e\u0627\u06cb\u0644\u06c7\u0633\u0646\u0649\u06ad \u062a\u0649\u0645\u0648\u062a\u0649\u064a\u063a\u0627 \u062e\u06d5\u062a \u064a\u06d0\u0632\u0649\u067e\u060c \u0626\u06c7\u0646\u0649\u06ad\u063a\u0627 \u0643\u0649\u0645\u0644\u06d5\u0631\u0646\u0649 \u0626\u0649\u0646\u062c\u0649\u0644 \u0626\u0648\u0642\u06c7\u062a\u0642\u06c7\u0686\u0649\u0633\u0649 \u0642\u0649\u0644\u0649\u067e \u062a\u0627\u0644\u0644\u0627\u0634 \u06cb\u06d5 \u062a\u06d5\u0631\u0628\u0649\u064a\u06d5\u0644\u06d5\u0634 \u062a\u0648\u063a\u0631\u0649\u0633\u0649\u062f\u0627 \u064a\u06d0\u062a\u06d5\u0643\u0686\u0649\u0644\u0649\u0643 \u0628\u06d0\u0631\u0649\u06cb\u0627\u062a\u0642\u0627\u0646\u0644\u0649\u0642\u0649\u0646\u0649 \u0626\u06d0\u0633\u0649\u06ad\u0649\u0632\u062f\u06d5 \u062a\u06c7\u062a\u06c7\u06ad.\n\u0626\u06d0\u062a\u0649\u0642\u0627\u062f\u0686\u0649\u0644\u0627\u0631 \u0633\u06c8\u067e\u0649\u062a\u0649\u062f\u06d5 \u0628\u0649\u0632\u0646\u0649\u06ad \u06cb\u06d5\u0632\u0649\u067e\u0649\u0645\u0649\u0632 \u062e\u06c7\u0634 \u062e\u06d5\u06cb\u06d5\u0631\u0646\u0649 \u064a\u06d0\u0642\u0649\u0646 \u06cb\u06d5 \u064a\u0649\u0631\u0627\u0642\u062a\u0649\u0643\u0649 \u0643\u0649\u0634\u0649\u0644\u06d5\u0631 \u0628\u0649\u0644\u06d5\u0646 \u0626\u0648\u0631\u062a\u0627\u0642\u0644\u0649\u0634\u0649\u0634\u062a\u06c7\u0631.\n\u0644\u06d0\u0643\u0649\u0646 \u0628\u06c7\u0646\u0649 \u0633\u0627\u062f\u0649\u0642\u0644\u0649\u0642 \u0628\u0649\u0644\u06d5\u0646 \u0626\u06d5\u0645\u06d5\u0644\u06af\u06d5 \u0626\u0627\u0634\u06c7\u0631\u06c7\u0634 \u0626\u06c8\u0686\u06c8\u0646\u060c \u0628\u0649\u0632 \u0628\u06c7 \u0626\u0627\u064a\u06d5\u062a\u0644\u06d5\u0631\u062f\u06d5 \u067e\u0627\u06cb\u0644\u06c7\u0633 \u062a\u06d5\u0633\u06cb\u0649\u0631\u0644\u0649\u06af\u06d5\u0646 \u062e\u0627\u0631\u0627\u0643\u062a\u06d0\u0631\u06af\u06d5 \u0626\u0649\u06af\u06d5 \u0628\u0648\u0644\u06c7\u0634\u0649\u0645\u0649\u0632 \u0643\u06d0\u0631\u06d5\u0643.\n\u0628\u0649\u0632 \u06be\u06d0\u0686\u0643\u0649\u0645\u0646\u0649\u06ad \u0642\u06d5\u0644\u0628\u0649\u0646\u0649 \u0626\u06c6\u0632\u06af\u06d5\u0631\u062a\u06d5\u0644\u0645\u06d5\u064a\u0645\u0649\u0632.\n\u0644\u06d0\u0643\u0649\u0646 \u0628\u0649\u0632 \u0626\u06c7\u0644\u0627\u0631\u063a\u0627 \u06be\u06d5\u0642\u0649\u0642\u06d5\u062a\u0646\u0649 \u0645\u06c7\u0644\u0627\u064a\u0649\u0645\u0644\u0649\u0642\u060c \u0645\u06d0\u06be\u0631\u0649\u0628\u0627\u0646\u0644\u0649\u0642 \u06cb\u06d5 \u0633\u06d5\u06cb\u0631\u0686\u0627\u0646\u0644\u0649\u0642 \u0628\u0649\u0644\u06d5\u0646 \u0626\u06d0\u064a\u062a\u0627\u0644\u0627\u064a\u0645\u0649\u0632.\n\u0628\u0649\u0632 \u062e\u06c7\u062f\u0627\u0646\u0649\u06ad \u0626\u06c6\u0632\u0649 \u062a\u0627\u0644\u0644\u0649\u063a\u0627\u0646 \u0628\u0627\u0644\u0649\u0644\u0649\u0631\u0649\u063a\u0627 \u0645\u06c7\u06cb\u0627\u067e\u0649\u0642 \u06cb\u0627\u0642\u0649\u062a\u062a\u0627 \u062a\u06d5\u06cb\u0628\u06d5 \u0642\u0649\u0644\u0649\u0634 \u0626\u0649\u0645\u0643\u0627\u0646\u0649\u064a\u0649\u062a\u0649 \u0628\u06d0\u0631\u0649\u062f\u0649\u063a\u0627\u0646\u0644\u0649\u0642\u0649\u063a\u0627 \u0626\u0649\u0634\u0649\u0646\u0649\u0634\u0649\u0645\u0649\u0632 \u0645\u06c7\u0645\u0643\u0649\u0646.\n\u0628\u06c8\u06af\u06c8\u0646\u0643\u0649 \u067e\u0627\u0631\u0686\u0649\u0646\u0649\u06ad 24- \u06cb\u06d5 25-\u0626\u0627\u064a\u06d5\u062a\u0644\u0649\u0631\u0649\u062f\u06d5 \u0645\u06d5\u0646 \u062e\u06c7\u062f\u0627 \u0626\u06c6\u0632 \u0642\u06c7\u0644\u0644\u0649\u0631\u0649\u062f\u0627 \u064a\u06d0\u062a\u0649\u0644\u062f\u06c8\u0631\u06c8\u0634\u0646\u0649 \u062e\u0627\u0644\u0627\u064a\u062f\u0649\u063a\u0627\u0646 \u0628\u06d5\u0634 \u062e\u0649\u0633\u0644\u06d5\u062a\u0646\u0649 \u0643\u06c6\u0631\u062f\u06c8\u0645:\n\n1-\u0633\u0649\u0641\u0627\u062a: \u062c\u06d0\u062f\u06d5\u0644\u062e\u0648\u0631 \u0626\u06d5\u0645\u06d5\u0633.\n\u0628\u06d5\u0632\u0649 \u0643\u0649\u0634\u0649\u0644\u06d5\u0631 \u062a\u0627\u0644\u0627\u0634-\u062a\u0627\u0631\u062a\u0649\u0634 \u0642\u0649\u0644\u0649\u0634\u0646\u0649 \u064a\u0627\u062e\u0634\u0649 \u0643\u06c6\u0631\u0649\u062f\u06c7.\n\u0633\u0627\u063a\u0644\u0627\u0645 \u0645\u06c7\u0646\u0627\u0632\u0649\u0631\u0649\u062f\u06d5 \u06be\u06d0\u0686\u0642\u0627\u0646\u062f\u0627\u0642 \u062e\u0627\u062a\u0627\u0644\u0649\u0642 \u064a\u0648\u0642.\n\u0644\u06d0\u0643\u0649\u0646\u060c \u0633\u0649\u0632 \u06af\u06c7\u0646\u0627\u06be\u0644\u0649\u0642 \u00ab\u062c\u0649\u062f\u06d5\u0644\u00bb \u0642\u0649\u0644\u0649\u06cb\u0627\u062a\u0642\u0627\u0646\u0644\u0649\u0642\u0649\u06ad\u0649\u0632\u0646\u0649 \u0642\u0627\u0646\u062f\u0627\u0642 \u0628\u0649\u0644\u0649\u0633\u0649\u0632\u061f\n\u0628\u06d5\u0644\u0643\u0649\u0645 \u0633\u0649\u0632 \u0626\u06c6\u0632\u0649\u06ad\u0649\u0632\u062f\u0649\u0646 \u0628\u06c7 \u0633\u0648\u0626\u0627\u0644\u0646\u0649 \u0633\u0648\u0631\u0627\u067e \u0628\u0627\u0642\u0633\u0649\u06ad\u0649\u0632 \u0628\u0648\u0644\u0649\u062f\u06c7:\n\u00ab\u0645\u06d5\u0646 \u0628\u0649\u0631\u06d5\u064a\u0644\u06d5\u0646 \u0628\u0649\u0644\u06d5\u0646 \u062a\u0627\u0644\u0627\u0634-\u062a\u0627\u0631\u062a\u0649\u0634 \u0642\u0649\u0644\u063a\u0627\u0646\u062f\u0627\u060c \u0645\u06d5\u0646 \u0626\u06c7 \u0626\u0627\u062f\u06d5\u0645\u0646\u0649\u06ad \u0626\u06c6\u0632\u0649\u06af\u06d5 \u0643\u06c6\u067e\u0631\u06d5\u0643 \u0643\u06c6\u06ad\u06c8\u0644 \u0628\u06c6\u0644\u0649\u0645\u06d5\u0646\u0645\u06c7 \u064a\u0627\u0643\u0649 \u062a\u0627\u0644\u0627\u0634-\u062a\u0627\u0631\u062a\u0649\u0634\u062a\u0627 \u063a\u06d5\u0644\u0649\u0628\u06d5 \u0642\u0649\u0644\u0649\u0634\u0642\u0627 \u0643\u06c6\u06ad\u06c8\u0644 \u0628\u06c6\u0644\u0649\u0645\u06d5\u0646\u0645\u06c7\u061f\u00bb\n\u0645\u06d0\u0646\u0649\u06ad \u063a\u06c7\u0631\u06c7\u0631\u06c7\u0645 \u0645\u06d0\u0646\u0649 \u0645\u06d0\u06be\u0631\u0649\u0628\u0627\u0646 \u0628\u0648\u0644\u06c7\u0634\u0646\u0649\u06ad \u0626\u0648\u0631\u0646\u0649\u063a\u0627 \u062a\u0648\u063a\u0631\u0627 \u0628\u0648\u0644\u06c7\u0634\u0642\u0627 \u062f\u0649\u0642\u0642\u06d5\u062a \u0642\u0649\u0644\u0649\u0634\u0642\u0627 \u0626\u06c8\u0646\u062f\u0649\u06cb\u0627\u062a\u0627\u0645\u062f\u06c7\u061f\n\n2-\u0633\u0649\u0641\u0627\u062a: \u06be\u06d5\u0645\u0645\u06d5\u064a\u0644\u06d5\u0646\u06af\u06d5 \u0645\u06d0\u06be\u0631\u0649\u0628\u0627\u0646.\n\u067e\u06d5\u0631\u06cb\u06d5\u0631\u062f\u0649\u06af\u0627\u0631\u0646\u0649\u06ad \u062e\u0649\u0632\u0645\u06d5\u062a\u0643\u0627\u0631\u0649 \u06be\u06d5\u0645\u0645\u06d5\u064a\u0644\u06d5\u0646\u06af\u06d5 \u0645\u06d0\u06be\u0631\u0649\u0628\u0627\u0646 \u0628\u0648\u0644\u06c7\u0634\u0649 \u0643\u06d0\u0631\u06d5\u0643.\n\u06be\u06d5\u062a\u062a\u0627 \u0633\u0649\u0632\u0646\u0649 \u064a\u0627\u0645\u0627\u0646 \u0643\u06c6\u0631\u0649\u062f\u0649\u063a\u0627\u0646 \u06cb\u06d5 \u0633\u0649\u0632\u06af\u06d5 \u0632\u0649\u064a\u0627\u0646 \u064a\u06d5\u062a\u0643\u06c8\u0632\u0645\u06d5\u0643\u0686\u0649 \u0628\u0648\u0644\u063a\u0627\u0646 \u0643\u0649\u0634\u0649\u0644\u06d5\u0631\u06af\u0649\u0645\u06c7.\n\u0628\u06c7 \u062a\u06d5\u0633\u060c \u0628\u0649\u0644\u0649\u0645\u06d5\u0646.\n\u0628\u0649\u0632 \u0628\u0627\u0634\u0642\u0649\u0644\u0627\u0631\u062f\u0649\u0646 \u0626\u06c6\u0632\u0649\u0645\u0649\u0632\u0646\u0649 \u0642\u0648\u063a\u062f\u0627\u0634\u0646\u0649\u06ad \u064a\u0648\u0644\u0649 \u0643\u06c8\u0686\u0644\u06c8\u0643 \u0628\u0648\u0644\u06c7\u0634\u060c \u06be\u0648\u0642\u06c7\u0642 \u0626\u0649\u0634\u0644\u0649\u062a\u0649\u0634 \u062f\u06d5\u067e \u0642\u0627\u0631\u0627\u064a\u0645\u0649\u0632.\n\u0644\u06d0\u0643\u0649\u0646 \u067e\u0627\u06cb\u0644\u06c7\u0633\u0646\u0649\u06ad \u0631\u0649\u0645\u0644\u0649\u0642\u0644\u0627\u0631\u063a\u0627 2:4 \u062f\u06d5 \u0628\u0649\u0632\u06af\u06d5 \u0646\u06d0\u0645\u06d5 \u062f\u06d5\u067e \u0626\u06d5\u0633\u0643\u06d5\u0631\u062a\u0643\u06d5\u0646\u0644\u0649\u0643\u0649\u06af\u06d5 \u0642\u0627\u0631\u0627\u067e \u0628\u06d0\u0642\u0649\u06ad:\n\u00ab\u062e\u06c7\u062f\u0627\u0646\u0649\u06ad \u0645\u06d0\u06be\u0631\u0649\u0628\u0627\u0646\u0644\u0649\u0642\u0649 \u0633\u0649\u0632\u0646\u0649 \u062a\u06d5\u06cb\u0628\u06d5 \u0642\u0649\u0644\u0649\u0634\u0642\u0627 \u064a\u06d0\u062a\u06d5\u0643\u0644\u06d5\u0634 \u0626\u06c8\u0686\u06c8\u0646\u062f\u06c7\u0631\u00bb.\n\u06af\u06c7\u0646\u0627\u06be \u0626\u0649\u0686\u0649\u062f\u06d5 \u062a\u06c7\u0631\u06c7\u067e\u060c \u0626\u06c7\u0646\u0649\u06ad\u062f\u0649\u0646 \u064a\u0649\u0631\u0627\u0642\u0644\u0649\u0634\u0649\u06cb\u0627\u062a\u0642\u0627\u0646 \u06cb\u0627\u0642\u062a\u0649\u06ad\u0649\u0632\u062f\u0627\u060c \u0626\u06d5\u064a\u0633\u0627 \u0633\u0649\u0632\u06af\u06d5 \u0642\u0627\u0646\u0686\u0649\u0644\u0649\u0643 \u0645\u06d0\u06be\u0631\u0649\u0628\u0627\u0646 \u0626\u0649\u062f\u0649\u061f\n\u0626\u06c7\u0646\u0649\u06ad \u0645\u06d0\u06be\u0631\u0649\u0628\u0627\u0646\u0644\u0649\u0642\u0649 \u0633\u06d0\u0646\u0649 \u062a\u06d5\u06cb\u0628\u06d5 \u0642\u0649\u0644\u0649\u0634\u0642\u0627 \u064a\u06d0\u062a\u06d5\u0643\u0644\u0649\u062f\u0649\u060c\n\u0634\u06c7\u06ad\u0627\u060c \u0633\u0649\u0644\u06d5\u0631\u062f\u06d5 \u06be\u0627\u0632\u0649\u0631 \u0645\u06d5\u0633\u0649\u06be\u0646\u0649 \u062a\u06d5\u0642\u0644\u0649\u062f \u0642\u0649\u0644\u0649\u0634 \u06cb\u06d5 \u06be\u06d5\u0645\u0645\u06d5\u064a\u0644\u06d5\u0646\u06af\u06d5 \u0645\u06d0\u06be\u0631\u0649\u0628\u0627\u0646 \u0628\u0648\u0644\u06c7\u0634 \u067e\u06c7\u0631\u0633\u0649\u062a\u0649 \u0628\u0627\u0631.\n\n3-\u062e\u0649\u0633\u0644\u06d5\u062a: \u064a\u0627\u0645\u0627\u0646\u0644\u0649\u0642\u0642\u0627 \u0633\u06d5\u06cb\u0631\u0686\u0627\u0646\u0644\u0649\u0642 \u0628\u0649\u0644\u06d5\u0646 \u0686\u0649\u062f\u0627\u067e \u062a\u06c7\u0631\u06c7\u0634.\n\u0628\u0649\u0632 \u062e\u06c7\u0634 \u062e\u06d5\u06cb\u06d5\u0631\u0646\u0649\u06ad \u06be\u06d5\u0642\u0649\u0642\u0649\u062a\u0649\u0646\u0649 \u0626\u0648\u0631\u062a\u0627\u0642\u0644\u0649\u0634\u0649\u06cb\u0627\u062a\u0642\u0627\u0646\u062f\u0627\u060c \u0628\u0649\u0632\u0646\u0649\u06ad \u062f\u06d0\u06af\u0649\u0646\u0649\u0645\u0649\u0632\u0646\u0649 \u064a\u0627\u0642\u062a\u06c7\u0631\u0645\u0627\u064a\u062f\u0649\u063a\u0627\u0646 \u0643\u0649\u0634\u0649\u0644\u06d5\u0631\u0646\u0649\u06ad \u0642\u0627\u0631\u0634\u0649\u0644\u0649\u0642\u0649\u063a\u0627 \u0626\u06c7\u0686\u0631\u0627\u064a\u0645\u0649\u0632.\n\u0633\u062a\u0649\u0641\u06d0\u0646\u0646\u0649\u06ad \u0626\u06c6\u0632\u0649\u0646\u0649 \u0626\u06c6\u0644\u062a\u06c8\u0631\u06af\u06d5\u0646 \u0643\u0649\u0634\u0649\u0644\u06d5\u0631\u06af\u06d5 \u0642\u0627\u0646\u062f\u0627\u0642 \u062c\u0627\u06cb\u0627\u0628 \u0642\u0627\u064a\u062a\u06c7\u0631\u063a\u0627\u0646\u0644\u0649\u0642\u0649\u0646\u0649 \u0626\u06d0\u0633\u0649\u06ad\u0649\u0632\u062f\u0649\u0645\u06c7\u061f\n\u0626\u06d5\u0644\u0686\u0649\u0644\u06d5\u0631\u0646\u0649\u06ad \u0626\u0649\u0634\u0644\u0649\u0631\u0649 7:59-60 \u062f\u06d5 \u0645\u06c7\u0646\u062f\u0627\u0642 \u062f\u06d0\u064a\u0649\u0644\u06af\u06d5\u0646:\n59 \u0626\u06c7\u0644\u0627\u0631 \u0626\u06c7\u0646\u0649 \u062a\u0627\u0634 \u0628\u0649\u0644\u06d5\u0646 \u0626\u06c7\u0631\u063a\u0627\u0646\u062f\u0627\u060c \u0626\u0649\u0633\u062a\u0649\u067e\u0627\u0646: \u00ab\u0626\u0649 \u0631\u06d5\u0628\u0628\u0649\u0645 \u0626\u06d5\u064a\u0633\u0627\u060c \u0631\u0648\u06be\u0649\u0645\u0646\u0649 \u0642\u0648\u0628\u06c7\u0644 \u0642\u0649\u0644\u063a\u0627\u064a\u0633\u06d5\u0646!\u00bb \u062f\u06d5\u067e \u062f\u06c7\u0626\u0627 \u0642\u0649\u0644\u062f\u0649.\n60 \u0626\u0627\u0646\u062f\u0649\u0646 \u0626\u06c7 \u062a\u0649\u0632\u0644\u0649\u0646\u0649\u067e \u062a\u06c7\u0631\u06c7\u067e: \u00ab\u0626\u0649 \u0631\u06d5\u0628\u0628\u0649\u0645\u060c \u0628\u06c7 \u06af\u06c7\u0646\u0627\u06be\u0646\u0649 \u0626\u06c7\u0644\u0627\u0631\u063a\u0627 \u064a\u06c8\u0643\u0644\u0649\u0645\u06d5\u00bb\u060c \u062f\u06d5\u067e \u06cb\u0627\u0631\u0642\u0649\u0631\u0649\u062f\u0649.\n\n\u067e\u06d5\u0642\u06d5\u062a \u062e\u06c7\u062f\u0627\u0644\u0627 \u0628\u0649\u0632\u06af\u06d5 \u0633\u062a\u0649\u0641\u06d0\u0646\u063a\u0627 \u0626\u0648\u062e\u0634\u0627\u0634 \u0633\u06d5\u06cb\u0631\u0686\u0627\u0646\u0644\u0649\u0642 \u0628\u0649\u0644\u06d5\u0646 \u064a\u0627\u0645\u0627\u0646\u0644\u0649\u0642\u0642\u0627 \u0686\u0649\u062f\u0627\u067e \u062a\u06c7\u0631\u06c7\u0634\u0642\u0627 \u064a\u0627\u0631\u062f\u06d5\u0645 \u0628\u06d0\u0631\u06d5\u0644\u06d5\u064a\u062f\u06c7.\n\u0626\u06d5\u0645\u0645\u0627 \u0628\u0649\u0632 \u0642\u0649\u064a\u0649\u0646\u0686\u0649\u0644\u0649\u0642\u0642\u0627 \u064a\u0648\u0644\u06c7\u0642\u0642\u0627\u0646\u062f\u0627 \u0626\u06c7\u0646\u0649\u06ad\u063a\u0627 \u064a\u0627\u0644\u06cb\u06c7\u0631\u063a\u0627\u0646\u062f\u0627\u060c \u0626\u06c7 \u0628\u0649\u0632\u06af\u06d5 \u064a\u0627\u0631\u062f\u06d5\u0645 \u0642\u0649\u0644\u0649\u062f\u06c7.\n\u0626\u06c7 \u0628\u0649\u0632\u0646\u0649\u06ad \u0628\u06d5\u062f\u0649\u0646\u0649\u0645\u0649\u0632\u06af\u06d5 \u0646\u06d0\u0645\u06d5 \u0628\u0648\u0644\u06c7\u0634\u0649\u062f\u0649\u0646 \u0642\u06d5\u062a\u0626\u0649\u064a\u0646\u06d5\u0632\u06d5\u0631\u060c \u0631\u0648\u06be\u0649\u0645\u0649\u0632\u0646\u0649\u06ad \u0626\u06c7\u0646\u0649\u06ad \u0642\u0648\u0644\u0649\u062f\u0627 \u0628\u0649\u062e\u06d5\u062a\u06d5\u0631 \u0626\u0649\u0643\u06d5\u0646\u0644\u0649\u0643\u0649\u0646\u0649 \u0628\u0649\u0644\u0649\u067e\u060c \u0628\u0649\u0632\u06af\u06d5 \u0626\u06c6\u0632\u0649\u06af\u06d5 \u0626\u0649\u0634\u0649\u0646\u0649\u0634\u0649\u0645\u0649\u0632\u06af\u06d5 \u064a\u0627\u0631\u062f\u06d5\u0645 \u0628\u06d0\u0631\u0649\u062f\u06c7.\n\n4-\u0633\u0649\u0641\u0627\u062a: \u0645\u06c7\u0644\u0627\u064a\u0649\u0645\u0644\u0649\u0642 \u0628\u0649\u0644\u06d5\u0646 \u062a\u06c8\u0632\u0649\u062a\u0649\u0634.\n\u0643\u0649\u0634\u0649\u0644\u06d5\u0631\u0646\u0649 \u062a\u06c8\u0632\u0649\u062a\u0649\u0634 \u062a\u06d5\u0633.\n\u0644\u06d0\u0643\u0649\u0646 \u0626\u0648\u063a\u0644\u06c7\u0645 \u0628\u0649\u0631\u06d5\u0631 \u0626\u0649\u0634\u0646\u0649 \u062e\u0627\u062a\u0627 \u0642\u0649\u0644\u0633\u0627\u060c \u0645\u06d5\u0646 \u0626\u06c7\u0646\u0649 \u064a\u0627\u062e\u0634\u0649 \u0643\u06c6\u0631\u0649\u0645\u06d5\u0646\u060c \u0634\u06c7\u06ad\u0627 \u0626\u06c7\u0646\u0649\u06ad\u063a\u0627 \u062f\u06d5\u064a\u0645\u06d5\u0646.\n\u0628\u0649\u0631\u06d5\u064a\u0644\u06d5\u0646\u0646\u0649 \u062a\u06c8\u0632\u0649\u062a\u0649\u0634\u0643\u06d5 \u062a\u0648\u063a\u0631\u0627 \u0643\u06d5\u0644\u06af\u06d5\u0646\u062f\u06d5\u060c \u0626\u0648\u064a\u0644\u0649\u0646\u0649\u0634\u0642\u0627 \u062a\u06d0\u06af\u0649\u0634\u0644\u0649\u0643 \u0645\u06c7\u06be\u0649\u0645 \u0633\u0648\u0626\u0627\u0644 \u062a\u06c6\u06cb\u06d5\u0646\u062f\u0649\u0643\u0649\u0686\u06d5:\n\u00ab\u0628\u0627\u0644\u0627\u0645\u060c \u062f\u0648\u0633\u062a\u06c7\u0645 \u064a\u0627\u0643\u0649 \u0626\u06d0\u0631\u0649\u0645 \u0645\u06d0\u0646\u0649\u06ad \u0645\u06c7\u06be\u06d5\u0628\u0628\u0649\u062a\u0649\u0645\u0646\u0649 \u06be\u06d0\u0633 \u0642\u0649\u0644\u0627\u0645\u062f\u06c7\u061f\u00bb\n\u064a\u0627\u0643\u0649 \u0626\u06c7\u0644\u0627\u0631 \u067e\u06d5\u0642\u06d5\u062a \u0645\u06d0\u0646\u0649\u06ad \u063a\u06d5\u0632\u0649\u067e\u0649\u0645\u0646\u0649\u0644\u0627 \u06be\u06d0\u0633 \u0642\u0649\u0644\u0627\u0645\u062f\u06c7\u061f\n\n\u0628\u0649\u0632 \u063a\u06d5\u0632\u06d5\u067e \u064a\u0627\u0643\u0649 \u0626\u06c8\u0645\u0649\u062f\u0633\u0649\u0632\u0644\u0649\u0643 \u0628\u0649\u0644\u06d5\u0646 \u062e\u0627\u062a\u0627\u0644\u0649\u0642\u0649\u0645\u0649\u0632\u0646\u0649 \u062a\u06c8\u0632\u06d5\u062a\u0643\u06d5\u0646\u062f\u06d5\u060c \u062e\u06c7\u062f\u0627 \u064a\u06d5\u0646\u06d5 \u0628\u0649\u0631 \u0626\u0627\u062f\u06d5\u0645\u0646\u0649 \u0626\u06c6\u0632\u06af\u06d5\u0631\u062a\u06d5\u0644\u0645\u06d5\u064a\u062f\u0649\u063a\u0627\u0646\u062f\u06d5\u0643 \u06be\u06d5\u0631\u0649\u0643\u06d5\u062a \u0642\u0649\u0644\u063a\u0627\u0646 \u0628\u0648\u0644\u0649\u0645\u0649\u0632.\n\u0628\u0649\u0632 \u0626\u06c7\u0644\u0627\u0631\u0646\u0649 \u0626\u06c6\u0632\u06af\u0649\u0631\u0649\u0634\u0643\u06d5 \u0645\u06d5\u062c\u0628\u06c7\u0631\u0644\u0649\u064a\u0627\u0644\u0627\u064a\u0645\u0649\u0632 \u064a\u0627\u0643\u0649 \u0626\u06c7\u0644\u0627\u0631 \u062a\u0648\u063a\u0631\u0627 \u064a\u0648\u0644\u063a\u0627 \u0643\u0649\u0631\u06af\u06c8\u0686\u06d5 \u062a\u06d0\u062e\u0649\u0645\u06c7 \u0642\u0627\u062a\u062a\u0649\u0642 \u06cb\u0627\u0631\u0642\u0649\u0631\u0627\u064a\u0645\u0649\u0632 \u062f\u06d5\u067e \u0626\u0648\u064a\u0644\u0627\u064a\u0645\u0649\u0632.\n\u0644\u06d0\u0643\u0649\u0646\u060c \u062e\u06c7\u062f\u0627\u0646\u0649\u06ad \u06be\u06d5\u0642\u0649\u0642\u0649\u064a \u0642\u06c7\u062f\u0631\u0649\u062a\u0649 \u0628\u0627\u0631\u0644\u0649\u0642\u0649\u0646\u0649 \u0628\u0649\u0644\u0649\u062f\u0649\u063a\u0627\u0646 \u0626\u0648\u0642\u06c7\u062a\u0642\u06c7\u0686\u0649 \u0645\u06c7\u0644\u0627\u064a\u0649\u0645\u060c \u0633\u06d5\u06cb\u0631\u0686\u0627\u0646 \u06cb\u06d5 \u0645\u06d0\u06be\u0631\u0649\u0628\u0627\u0646 \u0628\u0648\u0644\u0649\u062f\u06c7.\n\n5-\u0633\u0649\u0641\u0627\u062a: \u0626\u0648\u0642\u06c7\u062a\u06c7\u0634 \u0626\u0649\u0642\u062a\u0649\u062f\u0627\u0631\u0649\u063a\u0627 \u0626\u0649\u06af\u06d5.\n\u0633\u0649\u0632 \u062e\u06c7\u062f\u0627\u0646\u0649\u06ad \u0633\u06c6\u0632\u0649\u0646\u0649 \u0628\u0627\u0634\u0642\u0649\u0644\u0627\u0631\u063a\u0627 \u0686\u06c8\u0634\u06d5\u0646\u062f\u06c8\u0631\u06c8\u067e \u0628\u06d0\u0631\u06d5\u0644\u06d5\u064a\u062f\u0649\u063a\u0627\u0646 \u062f\u06d5\u0631\u0649\u062c\u0649\u062f\u06d5 \u064a\u0627\u062e\u0634\u0649 \u0686\u06c8\u0634\u0649\u0646\u0649\u067e \u064a\u06d5\u062a\u062a\u0649\u06ad\u0649\u0632\u0645\u06c7\u061f\n\u0633\u0649\u0632 \u06be\u0627\u064a\u0627\u062a\u0649\u06ad\u0649\u0632\u062f\u0627 \u064a\u06d0\u062a\u06d5\u0643\u0686\u0649\u0644\u0649\u0643 \u0642\u0649\u0644\u0649\u0634 \u06cb\u06d5 \u0628\u0627\u0634\u0642\u0649\u0644\u0627\u0631 \u0628\u0649\u0644\u06d5\u0646 \u0626\u0648\u0631\u062a\u0627\u0642\u0644\u0649\u0634\u0649\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u062a\u06d5\u064a\u064a\u0627\u0631 \u062a\u06c7\u0631\u063a\u0627\u0646 \u0645\u06c7\u0642\u06d5\u062f\u062f\u06d5\u0633 \u064a\u0627\u0632\u0645\u0649\u0644\u0627\u0631\u0646\u0649 \u064a\u0627\u062f\u0644\u0627\u06cb\u0627\u062a\u0627\u0645\u0633\u0649\u0632\u061f\n\u0628\u06c7 \u0626\u0627\u064a\u062f\u0627 \u0628\u0649\u0632 \u064a\u06d0\u06ad\u0649 \u0626\u0649\u0634\u0644\u0627\u0631\u0646\u0649 \u0628\u0627\u0634\u0644\u0627\u064a\u0645\u0649\u0632.\n\u0628\u0649\u0632 \u0633\u0649\u0632\u062f\u0649\u0646 \u0645\u0627\u0631\u062a\u0646\u0649\u06ad \u0626\u0627\u062e\u0649\u0631\u0649\u063a\u0649\u0686\u06d5 \u0628\u0649\u0631 \u0626\u0627\u064a\u06d5\u062a\u0646\u0649 \u064a\u0627\u062f\u0644\u0627\u067e \u0642\u0648\u064a\u06c7\u0634\u0649\u06ad\u0649\u0632\u0646\u0649 \u062a\u06d5\u0644\u06d5\u067e \u0642\u0649\u0644\u0649\u0645\u0649\u0632.\n\u0626\u06d5\u06af\u06d5\u0631 \u0633\u0649\u0632 \u0626\u06c7\u0646\u0649 \u0631\u06d5\u06be\u0628\u06d5\u0631\u0644\u0649\u0631\u0649\u0645\u0649\u0632\u0646\u0649\u06ad \u0628\u0649\u0631\u0649\u06af\u06d5\u060c \u06be\u06d5\u0631 \u0642\u0627\u0646\u062f\u0627\u0642 \u062a\u0649\u0644\u062f\u0627 \u0626\u0648\u0642\u06c7\u067e \u0628\u06d0\u0631\u06d5\u0644\u0649\u0633\u0649\u06ad\u0649\u0632\u060c \u0633\u0649\u0632\u06af\u06d5 \u0686\u0627\u067e\u0644\u0627\u0642 \u0628\u06d0\u0631\u0649\u0644\u0649\u062f\u06c7.\n\u0626\u06c7\u0646\u0649 \u0633\u06c7 \u0628\u0648\u062a\u06c7\u0644\u0643\u0649\u0633\u0649\u063a\u0627 \u064a\u0627\u0643\u0649 \u062f\u06d5\u067e\u062a\u06d5\u0631\u06af\u06d5 \u0642\u0648\u064a\u0633\u0649\u06ad\u0649\u0632 \u0628\u0648\u0644\u0649\u062f\u06c7.\n\u0626\u06c7\u0646\u0649 \u0642\u06d5\u064a\u06d5\u0631\u062f\u06d5 \u0643\u06c6\u0631\u0633\u0649\u06ad\u0649\u0632 \u0634\u06c7 \u064a\u06d5\u0631\u062f\u06d5 \u0645\u06d5\u0634\u0649\u0642 \u0642\u0649\u0644\u0649\u0633\u0649\u0632 \u06cb\u06d5 \u064a\u0649\u0644 \u0628\u0648\u064a\u0649 \u0645\u06d5\u0634\u0649\u0642 \u0642\u0649\u0644\u0649\u0634\u0646\u0649 \u062f\u0627\u06cb\u0627\u0645\u0644\u0627\u0634\u062a\u06c7\u0631\u0649\u0633\u0649\u0632.\n\u0643\u06d0\u0644\u0649\u06ad\u0644\u0627\u0631\u060c \u0628\u0649\u0631\u0644\u0649\u0643\u062a\u06d5 \u0645\u0627\u0631\u062a \u0626\u06d0\u064a\u0649\u063a\u0627 \u0626\u0627\u0626\u0649\u062a \u0626\u0627\u064a\u06d5\u062a\u0646\u0649\u060c \u062a\u0649\u0645\u0648\u062a\u0649\u064a\u063a\u0627 2-\u0626\u0627\u064a\u06d5\u062a 3:16-\u0626\u0627\u064a\u06d5\u062a\u0646\u0649 \u0626\u0648\u0642\u06c7\u067e \u0686\u0649\u0642\u0627\u064a\u0644\u0649.\n\u06be\u06d5\u0645\u0645\u0649\u0633\u0649: \u00ab\u0645\u06c7\u0642\u06d5\u062f\u062f\u06d5\u0633 \u064a\u0627\u0632\u0645\u0649\u0644\u0627\u0631\u0646\u0649\u06ad \u06be\u06d5\u0645\u0645\u0649\u0633\u0649 \u062e\u06c7\u062f\u0627 \u062a\u06d5\u0631\u0649\u067e\u0649\u062f\u0649\u0646 \u0626\u0649\u0644\u06be\u0627\u0645\u0644\u0627\u0646\u062f\u06c7\u0631\u06c7\u0644\u063a\u0627\u0646 \u0628\u0648\u0644\u06c7\u067e\u060c \u0626\u06c6\u06af\u0649\u062a\u0649\u0634\u060c \u0626\u06d5\u064a\u0649\u0628\u0644\u06d5\u0634\u060c \u062a\u06c8\u0632\u0649\u062a\u0649\u0634 \u06cb\u06d5 \u06be\u06d5\u0642\u0642\u0627\u0646\u0649\u064a\u06d5\u062a \u064a\u0648\u0644\u0649\u062f\u0627 \u062a\u06d5\u0631\u0628\u0649\u064a\u06d5\u0644\u06d5\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u067e\u0627\u064a\u062f\u0649\u0644\u0649\u0642\u00bb\n\n\u062a\u0648\u063a\u0631\u0627 \u064a\u06c6\u0646\u0649\u0644\u0649\u0634\u062a\u06d5 \u064a\u06c8\u06af\u06c8\u0631\u06c8\u0634\u0646\u0649 \u062f\u0627\u06cb\u0627\u0645\u0644\u0627\u0634\u062a\u06c7\u0631\u06c7\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u06be\u06d5\u0645\u0645\u0649\u0645\u0649\u0632 \u064a\u0627\u0631\u062f\u06d5\u0645\u06af\u06d5 \u0645\u0648\u06be\u062a\u0627\u062c.\n\u0628\u0649\u0632\u06af\u06d5 \u062e\u06c7\u062f\u0627\u0646\u0649\u06ad \u0633\u06c6\u0632\u0649 \u0626\u06c6\u06af\u0649\u062a\u0649\u0634\u060c \u062a\u06c8\u0632\u0649\u062a\u0649\u0634 \u06cb\u06d5 \u06be\u06d5\u0642\u0642\u0627\u0646\u0649\u064a\u06d5\u062a \u064a\u0648\u0644\u0649\u062f\u0627 \u0645\u06d0\u06ad\u0649\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0644\u0627\u0632\u0649\u0645.\n\u0628\u0649\u0632 \u0645\u06c7\u0642\u06d5\u062f\u062f\u06d5\u0633 \u0631\u0648\u06be\u0646\u0649\u06ad \u0628\u0649\u0632\u06af\u06d5 \u0633\u06c6\u0632\u0646\u0649 \u0686\u06c8\u0634\u0649\u0646\u0649\u0634 \u06cb\u06d5 \u0642\u0648\u0644\u0644\u0649\u0646\u0649\u0634\u0642\u0627 \u064a\u0627\u0631\u062f\u06d5\u0645 \u0628\u06d0\u0631\u0649\u0634\u0649\u06af\u06d5 \u0645\u0648\u06be\u062a\u0627\u062c\u060c \u0634\u06c7\u06ad\u0627 \u06be\u0627\u0632\u0649\u0631 \u062f\u06c7\u0626\u0627 \u0642\u0649\u0644\u0649\u067e \u0642\u06d5\u0644\u0628\u0649\u0645\u0649\u0632\u0646\u0649 \u0626\u0627\u0633\u0645\u0627\u0646\u063a\u0627 \u0642\u0627\u0631\u0649\u062a\u0627\u064a\u0644\u0649.\n\u0626\u06d5\u064a\u0633\u0627\u060c \u0628\u0649\u0632 \u067e\u06d5\u0642\u06d5\u062a \u0633\u0649\u0632 \u064a\u06d5\u0631 \u0628\u0649\u0644\u06d5\u0646 \u0626\u0627\u0633\u0645\u0627\u0646 \u0626\u0648\u062a\u062a\u06c7\u0631\u0649\u0633\u0649\u062f\u0627 \u0643\u06c6\u06cb\u0631\u06c8\u0643 \u0642\u06c7\u0631\u063a\u0627\u0646\u0644\u0649\u0642\u0649\u06ad\u0649\u0632 \u0626\u06c8\u0686\u06c8\u0646\u0644\u0627 \u0626\u0627\u062a\u0627 \u0628\u0649\u0644\u06d5\u0646 \u0633\u06c6\u0632\u0644\u06d5\u0634\u06d5\u0644\u06d5\u064a\u0645\u0649\u0632.\n\u0633\u06d5\u0646 \u0634\u06d5\u064a\u062a\u0627\u0646\u0646\u0649\u06ad \u062a\u06c7\u0632\u0627\u0642\u0644\u0649\u0631\u0649\u0646\u0649 \u06cb\u06d5\u064a\u0631\u0627\u0646 \u0642\u0649\u0644\u062f\u0649\u06ad \u06cb\u06d5 \u0643\u06c6\u0632\u0644\u0649\u0631\u0649\u0645\u0649\u0632\u0646\u0649 \u06be\u06d5\u0642\u0649\u0642\u06d5\u062a\u0643\u06d5 \u0626\u0627\u0686\u062a\u0649\u06ad.\n\u0626\u0627\u062a\u0627\u060c \u0628\u0649\u0632\u06af\u06d5 \u062a\u06d5\u06cb\u0628\u06d5 \u0642\u0649\u0644\u0649\u0634 \u0633\u0648\u06cb\u063a\u0649\u0633\u0649\u0646\u0649 \u0628\u06d5\u0631\u06af\u0649\u0646\u0649\u06ad\u0649\u0632\u06af\u06d5 \u0631\u06d5\u06be\u0645\u06d5\u062a\u060c \u0634\u06c7\u0646\u062f\u0627\u0642 \u0642\u0649\u0644\u0633\u0649\u06ad\u0649\u0632 \u06af\u06c7\u0646\u0627\u06be\u0644\u0649\u0631\u0649\u0645\u0649\u0632 \u062a\u0648\u063a\u0631\u0649\u0633\u0649\u062f\u0627 \u0626\u06c6\u0632\u0649\u0645\u0649\u0632\u06af\u06d5 \u06cb\u06d5 \u0633\u0649\u0632\u06af\u06d5 \u0633\u06d5\u0645\u0649\u0645\u0649\u064a \u0628\u0648\u0644\u0627\u0644\u0627\u064a\u0645\u0649\u0632.\n\u0645\u06c7\u0642\u06d5\u062f\u062f\u06d5\u0633 \u0631\u0648\u06be\u060c \u0628\u0649\u0632\u06af\u06d5 \u0646\u0649\u062c\u0627\u062a\u0644\u0649\u0642\u0649\u0645\u0649\u0632 \u0626\u06c8\u0686\u06c8\u0646 \u0626\u06d5\u064a\u0633\u0627\u063a\u0627 \u064a\u06c8\u0632\u0644\u0649\u0646\u0649\u0634\u0649\u0645\u0649\u0632\u06af\u06d5 \u0626\u0649\u0645\u0627\u0646 \u0628\u06d5\u0631\u06af\u0649\u0646\u0649\u06ad \u0626\u06c8\u0686\u06c8\u0646 \u0633\u0627\u06ad\u0627 \u0631\u06d5\u06be\u0645\u06d5\u062a.\n\u062e\u06c7\u062f\u0627\u0646\u0649\u06ad \u0633\u06c6\u0632\u0649\u0646\u0649 \u0686\u06c8\u0634\u0649\u0646\u0649\u0634 \u06cb\u06d5 \u06be\u0627\u064a\u0627\u062a\u0649\u0645\u0649\u0632\u063a\u0627 \u062a\u06d5\u062a\u0628\u0649\u0642\u0644\u0627\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0626\u06d5\u0642\u0644\u0649\u0645\u0649\u0632\u0646\u0649 \u06cb\u06d5 \u0642\u06d5\u0644\u0628\u0649\u0645\u0649\u0632\u0646\u0649 \u0626\u06d0\u0686\u0649\u06ad.\n\u0626\u0627\u0644\u062f\u0649\u0645\u0649\u0632\u062f\u0649\u0643\u0649 \u0645\u06c7\u0633\u0627\u0628\u0649\u0642\u0649\u062f\u06d5 \u062c\u0627\u067e\u0627\u0644\u0649\u0642 \u064a\u06c8\u06af\u06c8\u0631\u06c8\u0634\u0649\u0645\u0649\u0632\u06af\u06d5 \u064a\u0627\u0631\u062f\u06d5\u0645 \u0642\u0649\u0644\u060c \u0628\u0627\u0634\u0642\u0649\u0644\u0627\u0631\u0646\u0649 \u067e\u06c8\u062a\u06c8\u0646\u0644\u06c8\u0643\u060c \u0626\u06c8\u0645\u0649\u062f \u06cb\u06d5 \u062c\u06d5\u0646\u0646\u06d5\u062a \u0633\u06d5\u067e\u0649\u0631\u0649\u06af\u06d5 \u0642\u0627\u062a\u0646\u0649\u0634\u0649\u0634\u0642\u0627 \u062a\u06d5\u0643\u0644\u0649\u067e \u0642\u0649\u0644\u060c \u0626\u0627\u0645\u0649\u0646.\n\n\u0626\u0648\u064a\u0644\u0649\u0646\u0649\u0634 \u06cb\u06d5 \u0645\u06c7\u06be\u0627\u0643\u0649\u0645\u06d5 \u0642\u0649\u0644\u0649\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0633\u0648\u0626\u0627\u0644\u0644\u0627\u0631\n1.  2 \u062a\u0649\u0645\u0648\u062a\u0649\u064a\u063a\u0627 2:22 \u06cb\u06d5 \u0632\u06d5\u0628\u06c7\u0631 119:35-37-\u0626\u0627\u064a\u06d5\u062a\u0644\u06d5\u0631\u0646\u0649 \u0626\u0648\u0642\u06c7\u06ad.\na) \u0628\u06d0\u0633\u0649\u0645\u063a\u0627 \u0626\u06c7\u0686\u0631\u0649\u063a\u0627\u0646\u062f\u0627 \u064a\u0627\u0643\u0649 \u062a\u06d5\u0633\u06d5\u0644\u0644\u0649 \u0626\u0649\u0632\u062f\u0649\u06af\u06d5\u0646\u062f\u06d5\u060c \u0642\u06d5\u0644\u0628\u0649\u06ad\u0649\u0632 \u062a\u06d5\u0628\u0649\u0626\u0649\u064a \u06be\u0627\u0644\u062f\u0627 \u0642\u0627\u064a\u0633\u0649 \u00ab\u064a\u0627\u0634\u0644\u0649\u0642 \u0642\u0649\u0632\u063a\u0649\u0646\u0644\u0649\u0642\u0649\u00bb (\u062e\u06c7\u0634\u0627\u0644\u0644\u0649\u0642\u060c \u06be\u0648\u0642\u06c7\u0642\u060c \u062f\u0627\u06ad\u0642\u060c \u0645\u0627\u0644-\u0645\u06c8\u0644\u06c8\u0643\u060c \u063a\u06c7\u0631\u06c7\u0631) \u063a\u0627 \u0642\u0627\u0631\u0627\u067e \u064a\u06c8\u06af\u06c8\u0631\u0649\u062f\u06c7\u061f\n\n2.  \u0626\u06d5\u0641\u06d5\u0633\u0644\u0649\u0643\u0644\u06d5\u0631\u06af\u06d5 2:1-5 \u06cb\u06d5 \u06be\u06d5\u0632\u0642\u0649\u064a\u0627\u0644 36:26 \u0646\u0649 \u0626\u0648\u0642\u06c7\u06ad.\n\u0626\u0627) \u00ab\u0626\u06c6\u0644\u06c8\u0643\u00bb \u06be\u0627\u0644\u06d5\u062a\u062a\u0649\u0646 \u00ab\u062a\u0649\u0631\u0649\u0643\u00bb \u06be\u0627\u0644\u06d5\u062a\u0643\u06d5 \u0626\u06c6\u062a\u06c8\u0634 \u0626\u06c8\u0686\u06c8\u0646 \u0646\u06d0\u0645\u06d5 \u0642\u0649\u0644\u0649\u0634 \u0643\u06d0\u0631\u06d5\u0643\u061f\n\u0628) \u062a\u06d5\u06cb\u0628\u06d5 \u0642\u0649\u0644\u0649\u0634\u0646\u0649\u06ad \u0631\u06d5\u06be\u0645\u06d5\u062a \u0633\u0648\u06cb\u063a\u0649\u0633\u0649 \u0626\u0649\u0643\u06d5\u0646\u0644\u0649\u0643\u0649\u06af\u06d5 \u0626\u0649\u0634\u0649\u0646\u0649\u0634\u060c \u06af\u06c7\u0646\u0627\u06be\u0649\u06ad\u0649\u0632 \u062a\u0648\u063a\u0631\u0649\u0633\u0649\u062f\u0627 \u062e\u06c7\u062f\u0627\u063a\u0627 \u062a\u06d0\u062e\u0649\u0645\u06c7 \u0633\u06d5\u0645\u0649\u0645\u0649\u064a \u0628\u0648\u0644\u06c7\u0634\u0649\u06ad\u0649\u0632\u063a\u0627 \u064a\u0627\u0631\u062f\u06d5\u0645 \u0628\u06d0\u0631\u06d5\u0645\u062f\u06c7\u061f\n\n3.  2 \u062a\u0649\u0645\u0648\u062a\u0649\u064a\u063a\u0627 2:23-25a \u06cb\u06d5 \u0643\u0648\u0644\u0648\u0633\u0649\u0644\u0649\u0642\u0644\u0627\u0631\u063a\u0627 3:12-14 \u0646\u0649 \u0626\u0648\u0642\u06c7\u06ad.\na) \u0628\u0627\u0634\u0642\u0649\u0644\u0627\u0631 \u0628\u0649\u0644\u06d5\u0646 \u0645\u06c7\u0646\u0627\u0632\u0649\u0631\u0649\u0644\u06d5\u0634\u0643\u06d5\u0646\u062f\u06d5 \u064a\u0627\u0643\u0649 \u0626\u06c7\u0644\u0627\u0631\u0646\u0649 \u062a\u06c8\u0632\u06d5\u062a\u0643\u06d5\u0646\u062f\u06d5 \u00ab\u067e\u06d5\u0631\u06cb\u06d5\u0631\u062f\u0649\u06af\u0627\u0631\u0646\u0649\u06ad \u062e\u0649\u0632\u0645\u06d5\u062a\u0643\u0627\u0631\u0649\u00bb \u0642\u0627\u0646\u062f\u0627\u0642 \u062e\u0649\u0633\u0644\u06d5\u062a\u0644\u06d5\u0631\u06af\u06d5 \u0626\u0649\u06af\u06d5\u061f\n\u0628) \u0626\u06d5\u064a\u0633\u0627 \u0628\u0649\u0632\u0646\u0649 \u0626\u0649\u0646\u062a\u0627\u064a\u0649\u0646 \u0633\u06d5\u06cb\u0631\u0686\u0627\u0646\u0644\u0649\u0642 \u06cb\u06d5 \u0645\u06c7\u0644\u0627\u064a\u0649\u0645\u0644\u0649\u0642 \u0628\u0649\u0644\u06d5\u0646 \u0633\u06c6\u064a\u06af\u06d5\u0646\u0649 \u0626\u06c8\u0686\u06c8\u0646\u060c \u06be\u0627\u064a\u0627\u062a\u0649\u06ad\u0649\u0632\u062f\u0627 \u0643\u0649\u0645\u0646\u0649 \u0634\u06c7\u0646\u062f\u0627\u0642 \u0645\u06d0\u06be\u0631\u0649\u0628\u0627\u0646\u0644\u0649\u0642 \u0628\u0649\u0644\u06d5\u0646 \u0633\u06c6\u064a\u0649\u0633\u0649\u0632-- \u06af\u06d5\u0631\u0686\u06d5 \u0626\u06c7\u0644\u0627\u0631 \u0633\u0649\u0632 \u0628\u0649\u0644\u06d5\u0646 \u067e\u0649\u0643\u0649\u0631 \u0628\u0649\u0631\u0644\u0649\u0643\u0649\u06af\u06d5 \u0643\u06d5\u0644\u0645\u0649\u0633\u0649\u0645\u06c7 \u064a\u0627\u0643\u0649 \u0633\u0649\u0632\u0646\u0649 \u064a\u0627\u0642\u062a\u06c7\u0631\u0645\u0649\u0633\u0649\u0645\u06c7\u061f\n\n4.  \u0631\u0649\u0645\u0644\u0649\u0642\u0644\u0627\u0631\u063a\u0627 10:9-11 \u06cb\u06d5 \u0626\u0649\u0628\u0631\u0627\u0646\u0649\u064a\u0644\u0627\u0631\u063a\u0627 12:1-2 \u0646\u0649 \u0626\u0648\u0642\u06c7\u06ad.\na) \u0643\u06c6\u0632\u06c8\u0645\u0649\u0632\u0646\u0649 \u0626\u06d5\u064a\u0633\u0627\u063a\u0627 \u062a\u0649\u0643\u0649\u0634 \u06af\u06c7\u0646\u0627\u06be\u062a\u0649\u0646 \u064a\u06c8\u0632 \u0626\u06c6\u0631\u06c8\u067e\u060c \u064a\u06d0\u06ad\u0649 \u064a\u06c6\u0646\u0649\u0644\u0649\u0634\u0643\u06d5 \u0642\u0627\u0631\u0627\u067e \u0645\u06d0\u06ad\u0649\u0634\u0649\u0645\u0649\u0632\u063a\u0627 \u0642\u0627\u0646\u062f\u0627\u0642 \u064a\u0627\u0631\u062f\u06d5\u0645 \u0628\u06d0\u0631\u0649\u062f\u06c7\u061f\n\u0628) 2 \u062a\u0649\u0645\u0648\u062a\u0649\u064a 3:16 \u0646\u0649 \u064a\u0627\u062f\u0644\u0627\u067e \u0642\u0648\u064a\u06c7\u0634\u0646\u0649 \u0626\u06c7\u0646\u062a\u06c7\u0645\u0627\u06ad. \u062e\u06c7\u062f\u0627\u0646\u0649\u06ad \u0633\u06c6\u0632\u0649\u0646\u0649 \u0628\u0649\u0644\u0649\u0634 \u0628\u0649\u0632\u0646\u0649\u06ad \u0626\u0649\u0645\u0627\u0646 \u0645\u0627\u0631\u0627\u0641\u0648\u0646\u0649\u062f\u0627 \u064a\u06c8\u06af\u06c8\u0631\u06c8\u0634\u0649\u0645\u0649\u0632\u06af\u06d5 \u0642\u0627\u0646\u062f\u0627\u0642 \u064a\u0627\u0631\u062f\u06d5\u0645 \u0628\u06d0\u0631\u0649\u062f\u06c7\u061f"}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Where are you running? &#187; One Voice Fellowship<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onevoicefellowship.org\/am\/sermons\/where-are-you-running\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Where are you running? &#187; One Voice Fellowship\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onevoicefellowship.org\/am\/sermons\/where-are-you-running\/\" \/>\n<meta property=\"og:site_name\" content=\"One Voice Fellowship\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-17T21:02:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onevoicefellowship.org\/wp-content\/uploads\/2026\/03\/output-onlinejpgtools-2026-03-17T151422.880.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/sermons\\\/where-are-you-running\",\"url\":\"https:\\\/\\\/onevoicefellowship.org\\\/sermons\\\/where-are-you-running\",\"name\":\"Where are you running? &#187; One Voice Fellowship\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/sermons\\\/where-are-you-running#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/sermons\\\/where-are-you-running#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onevoicefellowship.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/output-onlinejpgtools-2026-03-17T151422.880.jpg\",\"datePublished\":\"2026-03-15T04:00:00+00:00\",\"dateModified\":\"2026-03-17T21:02:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/sermons\\\/where-are-you-running#breadcrumb\"},\"inLanguage\":\"am\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onevoicefellowship.org\\\/sermons\\\/where-are-you-running\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"am\",\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/sermons\\\/where-are-you-running#primaryimage\",\"url\":\"https:\\\/\\\/onevoicefellowship.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/output-onlinejpgtools-2026-03-17T151422.880.jpg\",\"contentUrl\":\"https:\\\/\\\/onevoicefellowship.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/output-onlinejpgtools-2026-03-17T151422.880.jpg\",\"width\":2400,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/sermons\\\/where-are-you-running#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onevoicefellowship.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sermons\",\"item\":\"https:\\\/\\\/onevoicefellowship.org\\\/sermonss\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Where are you running?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/#website\",\"url\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/\",\"name\":\"One Voice Fellowship\",\"description\":\"A new multi-lingual church in Northern Virginia\",\"publisher\":{\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"am\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/#organization\",\"name\":\"One Voice Fellowship - Multilingual Church in Northern Virginia\",\"url\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"am\",\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onevoicefellowship.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/onevoice-logo@512x.png\",\"contentUrl\":\"https:\\\/\\\/onevoicefellowship.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/onevoice-logo@512x.png\",\"width\":512,\"height\":320,\"caption\":\"One Voice Fellowship - Multilingual Church in Northern Virginia\"},\"image\":{\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCxxge9PZ7AflMmlwxep89xg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Where are you running? &#187; One Voice Fellowship","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onevoicefellowship.org\/am\/sermons\/where-are-you-running\/","og_locale":"en_US","og_type":"article","og_title":"Where are you running? &#187; One Voice Fellowship","og_url":"https:\/\/onevoicefellowship.org\/am\/sermons\/where-are-you-running\/","og_site_name":"One Voice Fellowship","article_modified_time":"2026-03-17T21:02:51+00:00","og_image":[{"width":2400,"height":1350,"url":"https:\/\/onevoicefellowship.org\/wp-content\/uploads\/2026\/03\/output-onlinejpgtools-2026-03-17T151422.880.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/onevoicefellowship.org\/sermons\/where-are-you-running","url":"https:\/\/onevoicefellowship.org\/sermons\/where-are-you-running","name":"Where are you running? &#187; One Voice Fellowship","isPartOf":{"@id":"https:\/\/onevoicefellowship.org\/tr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onevoicefellowship.org\/sermons\/where-are-you-running#primaryimage"},"image":{"@id":"https:\/\/onevoicefellowship.org\/sermons\/where-are-you-running#primaryimage"},"thumbnailUrl":"https:\/\/onevoicefellowship.org\/wp-content\/uploads\/2026\/03\/output-onlinejpgtools-2026-03-17T151422.880.jpg","datePublished":"2026-03-15T04:00:00+00:00","dateModified":"2026-03-17T21:02:51+00:00","breadcrumb":{"@id":"https:\/\/onevoicefellowship.org\/sermons\/where-are-you-running#breadcrumb"},"inLanguage":"am","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onevoicefellowship.org\/sermons\/where-are-you-running"]}]},{"@type":"ImageObject","inLanguage":"am","@id":"https:\/\/onevoicefellowship.org\/sermons\/where-are-you-running#primaryimage","url":"https:\/\/onevoicefellowship.org\/wp-content\/uploads\/2026\/03\/output-onlinejpgtools-2026-03-17T151422.880.jpg","contentUrl":"https:\/\/onevoicefellowship.org\/wp-content\/uploads\/2026\/03\/output-onlinejpgtools-2026-03-17T151422.880.jpg","width":2400,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/onevoicefellowship.org\/sermons\/where-are-you-running#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onevoicefellowship.org\/"},{"@type":"ListItem","position":2,"name":"Sermons","item":"https:\/\/onevoicefellowship.org\/sermonss"},{"@type":"ListItem","position":3,"name":"Where are you running?"}]},{"@type":"WebSite","@id":"https:\/\/onevoicefellowship.org\/tr\/#website","url":"https:\/\/onevoicefellowship.org\/tr\/","name":"One Voice Fellowship","description":"A new multi-lingual church in Northern Virginia","publisher":{"@id":"https:\/\/onevoicefellowship.org\/tr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onevoicefellowship.org\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"am"},{"@type":"Organization","@id":"https:\/\/onevoicefellowship.org\/tr\/#organization","name":"One Voice Fellowship - Multilingual Church in Northern Virginia","url":"https:\/\/onevoicefellowship.org\/tr\/","logo":{"@type":"ImageObject","inLanguage":"am","@id":"https:\/\/onevoicefellowship.org\/tr\/#\/schema\/logo\/image\/","url":"https:\/\/onevoicefellowship.org\/wp-content\/uploads\/2021\/10\/onevoice-logo@512x.png","contentUrl":"https:\/\/onevoicefellowship.org\/wp-content\/uploads\/2021\/10\/onevoice-logo@512x.png","width":512,"height":320,"caption":"One Voice Fellowship - Multilingual Church in Northern Virginia"},"image":{"@id":"https:\/\/onevoicefellowship.org\/tr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCxxge9PZ7AflMmlwxep89xg"]}]}},"_links":{"self":[{"href":"https:\/\/onevoicefellowship.org\/am\/wp-json\/wp\/v2\/sermonss\/9015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onevoicefellowship.org\/am\/wp-json\/wp\/v2\/sermonss"}],"about":[{"href":"https:\/\/onevoicefellowship.org\/am\/wp-json\/wp\/v2\/types\/sermonss"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onevoicefellowship.org\/am\/wp-json\/wp\/v2\/media\/9016"}],"wp:attachment":[{"href":"https:\/\/onevoicefellowship.org\/am\/wp-json\/wp\/v2\/media?parent=9015"}],"wp:term":[{"taxonomy":"series","embeddable":true,"href":"https:\/\/onevoicefellowship.org\/am\/wp-json\/wp\/v2\/series?post=9015"},{"taxonomy":"topics","embeddable":true,"href":"https:\/\/onevoicefellowship.org\/am\/wp-json\/wp\/v2\/topics?post=9015"},{"taxonomy":"books","embeddable":true,"href":"https:\/\/onevoicefellowship.org\/am\/wp-json\/wp\/v2\/books?post=9015"},{"taxonomy":"speakers","embeddable":true,"href":"https:\/\/onevoicefellowship.org\/am\/wp-json\/wp\/v2\/speakers?post=9015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}