{"id":427,"count":1,"description":"","link":"https:\/\/onevoicefellowship.org\/fr\/themes\/the-lord-of-unsearchable-greatness","name":"The Lord of Unsearchable Greatness","slug":"the-lord-of-unsearchable-greatness","taxonomy":"themes","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Lord of Unsearchable Greatness Archives &#187; One Voice Fellowship<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onevoicefellowship.org\/fr\/themes\/the-lord-of-unsearchable-greatness\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Lord of Unsearchable Greatness Archives &#187; One Voice Fellowship\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onevoicefellowship.org\/fr\/themes\/the-lord-of-unsearchable-greatness\/\" \/>\n<meta property=\"og:site_name\" content=\"One Voice Fellowship\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/themes\\\/the-lord-of-unsearchable-greatness\",\"url\":\"https:\\\/\\\/onevoicefellowship.org\\\/themes\\\/the-lord-of-unsearchable-greatness\",\"name\":\"The Lord of Unsearchable Greatness Archives &#187; One Voice Fellowship\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/themes\\\/the-lord-of-unsearchable-greatness#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/themes\\\/the-lord-of-unsearchable-greatness#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/onevoicefellowship.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Lord of Unsearchable Greatness\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/#website\",\"url\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/\",\"name\":\"One Voice Fellowship\",\"description\":\"A new multi-lingual church in Northern Virginia\",\"publisher\":{\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/#organization\",\"name\":\"One Voice Fellowship - Multilingual Church in Northern Virginia\",\"url\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onevoicefellowship.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/onevoice-logo@512x.png\",\"contentUrl\":\"https:\\\/\\\/onevoicefellowship.org\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/onevoice-logo@512x.png\",\"width\":512,\"height\":320,\"caption\":\"One Voice Fellowship - Multilingual Church in Northern Virginia\"},\"image\":{\"@id\":\"https:\\\/\\\/onevoicefellowship.org\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCxxge9PZ7AflMmlwxep89xg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Lord of Unsearchable Greatness Archives &#187; One Voice Fellowship","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onevoicefellowship.org\/fr\/themes\/the-lord-of-unsearchable-greatness\/","og_locale":"fr_FR","og_type":"article","og_title":"The Lord of Unsearchable Greatness Archives &#187; One Voice Fellowship","og_url":"https:\/\/onevoicefellowship.org\/fr\/themes\/the-lord-of-unsearchable-greatness\/","og_site_name":"One Voice Fellowship","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/onevoicefellowship.org\/themes\/the-lord-of-unsearchable-greatness","url":"https:\/\/onevoicefellowship.org\/themes\/the-lord-of-unsearchable-greatness","name":"The Lord of Unsearchable Greatness Archives &#187; One Voice Fellowship","isPartOf":{"@id":"https:\/\/onevoicefellowship.org\/tr\/#website"},"breadcrumb":{"@id":"https:\/\/onevoicefellowship.org\/themes\/the-lord-of-unsearchable-greatness#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/onevoicefellowship.org\/themes\/the-lord-of-unsearchable-greatness#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onevoicefellowship.org\/"},{"@type":"ListItem","position":2,"name":"The Lord of Unsearchable Greatness"}]},{"@type":"WebSite","@id":"https:\/\/onevoicefellowship.org\/tr\/#website","url":"https:\/\/onevoicefellowship.org\/tr\/","name":"One Voice Fellowship","description":"A new multi-lingual church in Northern Virginia","publisher":{"@id":"https:\/\/onevoicefellowship.org\/tr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onevoicefellowship.org\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/onevoicefellowship.org\/tr\/#organization","name":"One Voice Fellowship - Multilingual Church in Northern Virginia","url":"https:\/\/onevoicefellowship.org\/tr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/onevoicefellowship.org\/tr\/#\/schema\/logo\/image\/","url":"https:\/\/onevoicefellowship.org\/wp-content\/uploads\/2021\/10\/onevoice-logo@512x.png","contentUrl":"https:\/\/onevoicefellowship.org\/wp-content\/uploads\/2021\/10\/onevoice-logo@512x.png","width":512,"height":320,"caption":"One Voice Fellowship - Multilingual Church in Northern Virginia"},"image":{"@id":"https:\/\/onevoicefellowship.org\/tr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCxxge9PZ7AflMmlwxep89xg"]}]}},"_links":{"self":[{"href":"https:\/\/onevoicefellowship.org\/fr\/wp-json\/wp\/v2\/themes\/427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onevoicefellowship.org\/fr\/wp-json\/wp\/v2\/themes"}],"about":[{"href":"https:\/\/onevoicefellowship.org\/fr\/wp-json\/wp\/v2\/taxonomies\/themes"}],"wp:post_type":[{"href":"https:\/\/onevoicefellowship.org\/fr\/wp-json\/wp\/v2\/prayers-readings?themes=427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}